{"id":1515095,"date":"2025-02-10T14:43:00","date_gmt":"2025-02-10T17:43:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1515095"},"modified":"2025-02-10T15:47:25","modified_gmt":"2025-02-10T18:47:25","slug":"estagio-tjsp","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/","title":{"rendered":"Est\u00e1gio do TJSP: como entrar no TJSP como Estagi\u00e1rio?\u00a0"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-confira-neste-artigo-o-que-voce-precisa-para-entrar-no-estagio-do-tjsp\"><strong><em>Confira neste artigo o que voc\u00ea precisa para entrar no Est\u00e1gio do TJSP<\/em><\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27-1024x576.jpeg\" alt=\"Est\u00e1gio do TJSP\n\" class=\"wp-image-1515100\" style=\"width:680px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27-1024x576.jpeg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27-300x169.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27-768x432.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27-1536x864.jpeg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27-150x84.jpeg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Est\u00e1gio do TJSP<\/figcaption><\/figure>\n\n\n\n<p>Ol\u00e1, pessoal! Tudo bem? Hoje falaremos um pouco sobre o <strong>processo seletivo de Est\u00e1gio do TJSP.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Que tal um <strong>2025 cheio de oportunidades? <\/strong>\u00c9 exatamente este o objetivo do <strong>Programa de Est\u00e1gio do <\/strong><a href=\"https:\/\/www.tjsp.jus.br\/\"><strong>Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo (TJSP).<\/strong>&nbsp;<\/a><\/p>\n\n\n\n<p>Em parceria firmada com o <a href=\"https:\/\/pp.ciee.org.br\/home\"><strong>Centro de Integra\u00e7\u00e3o Empresa-Escola (CIEE)<\/strong><\/a> o <a href=\"https:\/\/pp.ciee.org.br\/vitrine\/12865\/detalhe\"><strong>processo seletivo 2025 do TJSP <\/strong>j\u00e1 est\u00e1 com as <strong>inscri\u00e7\u00f5es abertas<\/strong><\/a> e oferecendo vagas em v\u00e1rios munic\u00edpios paulistas, al\u00e9m de <strong>vagas destinadas a<\/strong> <strong>Pessoas com Defici\u00eancia (PcD).<\/strong>&nbsp;<\/p>\n\n\n\n<p>Assim sendo, para que voc\u00ea fique por dentro do assunto, no artigo de hoje analisaremos os <strong>principais pontos do programa<\/strong> e <strong>o que \u00e9 preciso para entrar no TJSP como Estagi\u00e1rio.<\/strong> Acompanhe!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-d329a4a92c87f87cb563b36f25039a45\" id=\"h-principais-pontos-do-programa-de-estagio-do-tjsp-nbsp\">Principais pontos do Programa de Est\u00e1gio do TJSP&nbsp;<\/h2>\n\n\n\n<p>De acordo com as <strong>disposi\u00e7\u00f5es contidas na <\/strong><a href=\"https:\/\/pp.ciee.org.br\/vitrine\/12865\/detalhe\"><strong>p\u00e1gina de acompanhamento do processo seletivo,<\/strong><\/a> as vagas ofertadas destinam-se a candidatos <strong>estudantes do ensino m\u00e9dio regular.<\/strong><\/p>\n\n\n\n<p>Em s\u00edntese,<strong> <\/strong>o candidato interessado em participar do <strong>processo seletivo<\/strong> deve estar atento ao cumprimento de alguns requisitos importantes antes de se inscrever no programa, tais como:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estar regularmente matriculado no 1\u00ba ou no 2\u00ba ano do ensino m\u00e9dio regular;<\/li>\n\n\n\n<li>No ato da inscri\u00e7\u00e3o, possuir idade m\u00ednima de 16 anos completos e estar estudando (restando pelo menos 6&nbsp;meses para terminar o curso);<\/li>\n\n\n\n<li>Se maior de 18 anos, estar em dia com as obriga\u00e7\u00f5es eleitorais e;&nbsp;<\/li>\n\n\n\n<li>Se do sexo masculino e maior de 18 anos, estar em dia com as obriga\u00e7\u00f5es militares;<\/li>\n<\/ul>\n\n\n\n<p>Al\u00e9m disso, o candidato precisa estar ciente de que durante o <strong>per\u00edodo de est\u00e1gio no TJSP<\/strong> n\u00e3o poder\u00e1 estar realizando est\u00e1gio em Escrit\u00f3rios de Advocacia ou em outras entidades afins.<\/p>\n\n\n\n<p>Quanto \u00e0 remunera\u00e7\u00e3o ofertada, trata-se de um valor mensal de <strong>R$600,00,<\/strong> pagos a t\u00edtulo de <strong>bolsa-aux\u00edlio<\/strong> para o exerc\u00edcio de uma jornada de trabalho de 4 horas di\u00e1rias, totalizando <strong>20 horas semanais, <\/strong>com op\u00e7\u00e3o de exerc\u00ea-la de<strong> segunda \u00e0 sexta-feira<\/strong>, das 09h \u00e0s 13h ou das 13h \u00e0s 17h.&nbsp;<\/p>\n\n\n\n<p>Ademais, o <strong>Est\u00e1gio do TJSP<\/strong> tamb\u00e9m oferece um <strong>aux\u00edlio transporte<\/strong> mensal no valor de <strong>R$185,27.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-3ec90e270f158b857ac687b43e9aa8e5\" id=\"h-como-entrar-no-tjsp-como-estagiario\">Como entrar no TJSP como Estagi\u00e1rio?<\/h2>\n\n\n\n<p>Em suma, al\u00e9m do cumprimento dos pr\u00e9-requisitos, para <strong>estagiar no TJSP<\/strong> o candidato interessado precisa ser aprovado na prova aplicada pelo <strong>CIEE.<\/strong>&nbsp;<\/p>\n\n\n\n<p>No entanto, temos uma peculiaridade: aplica-se a prova na <strong>modalidade <\/strong><strong><em>on-line<\/em><\/strong><strong>,<\/strong> dentro do pr\u00f3prio <em>site<\/em> do <strong>CIEE.<\/strong><\/p>\n\n\n\n<p>Desse modo, para realizar a <strong>prova <\/strong><strong><em>online <\/em><\/strong>\u00e9 necess\u00e1rio seguir algumas orienta\u00e7\u00f5es <strong>contidas em pequenos v\u00eddeos disponibilizados na pr\u00f3pria p\u00e1gina de acompanhamento da sele\u00e7\u00e3o.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Assim sendo, depois de estar devidamente inscrito no processo seletivo, o participante precisa, primeiramente, <strong>acessar o seu perfil no CIEE, utilizando seu login e senha.<\/strong><\/p>\n\n\n\n<p>Ap\u00f3s entrar no sistema, o candidato precisa localizar a \u00e1rea do processo seletivo e <strong>selecionar o modo como deseja receber o c\u00f3digo de acesso<\/strong> para realizar a prova, se via SMS ou via e-mail.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, o candidato pode <strong>optar por realizar a prova pelo computador ou pelo celular.<\/strong> Para iniciar a prova \u00e9 necess\u00e1rio tirar uma foto do pr\u00f3prio rosto utilizando a c\u00e2mera do dispositivo escolhido.&nbsp;<\/p>\n\n\n\n<p>Em seguida, cada quest\u00e3o ter\u00e1 um tempo determinado para ser solucionada e s\u00f3 poder\u00e1 ser acessada <strong>uma \u00fanica vez.<\/strong> Mas n\u00e3o v\u00e1 pensando que se trata de uma prova com consulta!&nbsp;<\/p>\n\n\n\n<p>Conforme as orienta\u00e7\u00f5es disponibilizadas, o candidato <strong>n\u00e3o pode abrir outras abas, janelas ou navegadores<\/strong> no momento em que estiver realizando a prova, muito menos tirar fotos ou <em>prints<\/em> da tela e nem receber ajuda de terceiros.<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 proibido sair da frente da c\u00e2mera do dispositivo, usar calculadoras, livros ou celulares enquanto estiver realizando a prova.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-9e3ea3481b340438d67ece9d5a5fa78c\" id=\"h-periodo-de-inscricoes-e-prova-on-line\">Per\u00edodo de inscri\u00e7\u00f5es e prova <em>on-line<\/em><\/h2>\n\n\n\n<p>Em s\u00edntese, a sele\u00e7\u00e3o dos candidatos por meio de <strong>prova <em>on-line<\/em> \u00e9 cont\u00ednua<\/strong> e ficar\u00e1 dispon\u00edvel durante todo o per\u00edodo de inscri\u00e7\u00f5es, que vai de <strong>01\/01\/2025 at\u00e9 31\/12\/2025.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Assim sendo, a prova <em>on-line<\/em> do <strong>Est\u00e1gio do TJSP<\/strong> \u00e9 composta por um total de <strong>30 quest\u00f5es<\/strong> divididas da seguinte maneira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u00edngua portuguesa &#8211; 10 quest\u00f5es;<\/li>\n\n\n\n<li>Matem\u00e1tica &#8211;&nbsp; 10 quest\u00f5es;<\/li>\n\n\n\n<li>Conhecimentos Gerais &#8211; 10 quest\u00f5es.<\/li>\n<\/ul>\n\n\n\n<p>Posteriormente \u00e0 realiza\u00e7\u00e3o da prova, em caso de <strong>aprova\u00e7\u00e3o,<\/strong> o candidato dever\u00e1 entrar em contato com os organizadores da sele\u00e7\u00e3o para enviar a documenta\u00e7\u00e3o necess\u00e1ria. Por outro lado, em caso de reprova\u00e7\u00e3o, o candidato <strong>poder\u00e1 fazer uma nova prova ap\u00f3s 30 dias da reprova\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Nesse sentido, vale salientar que haver\u00e1 <strong>provas todos os meses<\/strong> e ao final de cada m\u00eas as listas com os nomes dos <strong>candidatos aprovados<\/strong> ser\u00e3o publicadas e possuir\u00e3o prazo de validade de 12 meses.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-90ccfad228d5c547a9f9a6bece342736\" id=\"h-trabalhe-no-tjsp\">Trabalhe no TJSP!<\/h2>\n\n\n\n<p>E a\u00ed, voc\u00ea quer trabalhar no <strong>Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo?&nbsp;<\/strong><\/p>\n\n\n\n<p>Pois saiba que al\u00e9m de estagiar no \u00f3rg\u00e3o voc\u00ea tamb\u00e9m pode <strong>garantir uma vaga efetiva<\/strong> para trabalhar com estabilidade.&nbsp;<\/p>\n\n\n\n<p>Nesse sentido, al\u00e9m de lan\u00e7ar editais periodicamente, inclusive para o cargo&nbsp; de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/tj-sp-escrevente-tecnico-judiciario-pacote-completo\/\"><strong>Escrevente T\u00e9cnico Judici\u00e1rio<\/strong>,<\/a> que exige apenas n\u00edvel m\u00e9dio de forma\u00e7\u00e3o escolar, o TJSP tamb\u00e9m oferece <strong>excelentes remunera\u00e7\u00f5es aos seus servidores.<\/strong><\/p>\n\n\n\n<p>Atualmente, por exemplo, est\u00e3o em andamento <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tj-sp\/\">dois novos editais com vagas para <strong>Assistente Social Judici\u00e1rio e Psic\u00f3logo Judici\u00e1rio.&nbsp;<\/strong><\/a><\/p>\n\n\n\n<p>Com organiza\u00e7\u00e3o da<strong> <\/strong><a href=\"https:\/\/www.vunesp.com.br\/\"><strong>Banca Vunesp,<\/strong><\/a> o sal\u00e1rio inicial oferecido para as especialidades \u00e9 de R$ 9.061,53.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, o \u00f3rg\u00e3o oferece aux\u00edlio alimenta\u00e7\u00e3o, aux\u00edlio sa\u00fade e vale transporte, tudo pago em dinheiro aos seus servidores.&nbsp;<\/p>\n\n\n\n<p>N\u00e3o fique de fora! Na <a href=\"https:\/\/www.estrategiaconcursos.com.br\/pesquisa\/?q=tj-sp\"><strong>plataforma do Estrat\u00e9gia Concursos voc\u00ea encontra os cursos e pacotes completos para a sua aprova\u00e7\u00e3o em todas as \u00e1reas do Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo. Clique e confira!<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-f401a9ff97c166dbd2d1c8268775c1dc\" id=\"h-finalizando-nbsp\"><strong>Finalizando&nbsp;<\/strong><\/h2>\n\n\n\n<p>Ent\u00e3o, \u00e9 isso, pessoal! Chegamos ao fim da nossa an\u00e1lise sobre <strong>o Est\u00e1gio do TJSP.<\/strong> Esperamos que tenham gostado.<\/p>\n\n\n\n<p>Confira tamb\u00e9m:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/dia-dia-oficial-justica\/\"><strong>Poder Judici\u00e1rio: como \u00e9 o dia a dia do Oficial de Justi\u00e7a?<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teletrabalho-tjsp\/\"><strong>O que voc\u00ea precisa saber sobre o teletrabalho do TJSP?<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p>Se voc\u00ea quer se preparar para chegar <strong>competitivo <\/strong>em qualquer prova de concurso p\u00fablico, invista nos<a href=\"https:\/\/www.estrategiaconcursos.com.br\/\"><strong> <\/strong><strong>cursos do Estrat\u00e9gia Concursos.<\/strong><\/a> L\u00e1 voc\u00ea encontrar\u00e1 <strong>aulas completas e detalhadas, com os melhores professores do mercado<\/strong>.<\/p>\n\n\n\n<p>Conhe\u00e7a tamb\u00e9m o<a href=\"https:\/\/concursos.estrategia.com\/\"> <strong>Sistema de Quest\u00f5es do Estrat\u00e9gia<\/strong><\/a>. Afinal, a \u00fanica forma de <strong>consolidar o conte\u00fado <\/strong>de maneira satisfat\u00f3ria \u00e9 atrav\u00e9s da <strong>resolu\u00e7\u00e3o de quest\u00f5es.<\/strong><\/p>\n\n\n\n<p>Bons estudos a todos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Cursos e Assinaturas<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-4ee3858d78f8e73e6a059835bfd98e6f\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-1aca1c51fe870dad71059b988ff0425d\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\"><strong>Concursos 2025<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira neste artigo o que voc\u00ea precisa para entrar no Est\u00e1gio do TJSP Ol\u00e1, pessoal! Tudo bem? Hoje falaremos um pouco sobre o processo seletivo de Est\u00e1gio do TJSP.&nbsp; Que tal um 2025 cheio de oportunidades? \u00c9 exatamente este o objetivo do Programa de Est\u00e1gio do Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo (TJSP).&nbsp; [&hellip;]<\/p>\n","protected":false},"author":2974,"featured_media":1515100,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1984,220737,214710],"tags":[],"tax_estado":[219963,219989],"class_list":["post-1515095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-tribunais","category-tribunais-tribunais","category-tribunais-de-contas","tax_estado-concursos-federais","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Est\u00e1gio do TJSP<\/title>\n<meta name=\"description\" content=\"Confira neste artigo o que voc\u00ea precisa para entrar no TJSP como estagi\u00e1rio. Conhe\u00e7a os principais pontos do Programa de Est\u00e1gio do TJSP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est\u00e1gio do TJSP: como entrar no TJSP como Estagi\u00e1rio?\u00a0\" \/>\n<meta property=\"og:description\" content=\"Confira neste artigo o que voc\u00ea precisa para entrar no TJSP como estagi\u00e1rio. Conhe\u00e7a os principais pontos do Programa de Est\u00e1gio do TJSP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-10T17:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T18:47:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edmar Bezerra Araujo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edmar Bezerra Araujo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/\"},\"author\":{\"name\":\"Edmar Bezerra Araujo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da\"},\"headline\":\"Est\u00e1gio do TJSP: como entrar no TJSP como Estagi\u00e1rio?\u00a0\",\"datePublished\":\"2025-02-10T17:43:00+00:00\",\"dateModified\":\"2025-02-10T18:47:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/\"},\"wordCount\":1164,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Tribunais\",\"Tribunais\",\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/\",\"name\":\"Est\u00e1gio do TJSP\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg\",\"datePublished\":\"2025-02-10T17:43:00+00:00\",\"dateModified\":\"2025-02-10T18:47:25+00:00\",\"description\":\"Confira neste artigo o que voc\u00ea precisa para entrar no TJSP como estagi\u00e1rio. Conhe\u00e7a os principais pontos do Programa de Est\u00e1gio do TJSP.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg\",\"width\":1600,\"height\":900,\"caption\":\"Est\u00e1gio do TJSP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Est\u00e1gio do TJSP: como entrar no TJSP como Estagi\u00e1rio?\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da\",\"name\":\"Edmar Bezerra Araujo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"caption\":\"Edmar Bezerra Araujo\"},\"sameAs\":[\"https:\/\/www.instagram.com\/edmarbezerraaraujo\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/edmarbezerraaraujogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Est\u00e1gio do TJSP","description":"Confira neste artigo o que voc\u00ea precisa para entrar no TJSP como estagi\u00e1rio. Conhe\u00e7a os principais pontos do Programa de Est\u00e1gio do TJSP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/","og_locale":"pt_BR","og_type":"article","og_title":"Est\u00e1gio do TJSP: como entrar no TJSP como Estagi\u00e1rio?\u00a0","og_description":"Confira neste artigo o que voc\u00ea precisa para entrar no TJSP como estagi\u00e1rio. Conhe\u00e7a os principais pontos do Programa de Est\u00e1gio do TJSP.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2025-02-10T17:43:00+00:00","article_modified_time":"2025-02-10T18:47:25+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg","type":"image\/jpeg"}],"author":"Edmar Bezerra Araujo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Edmar Bezerra Araujo","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/"},"author":{"name":"Edmar Bezerra Araujo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da"},"headline":"Est\u00e1gio do TJSP: como entrar no TJSP como Estagi\u00e1rio?\u00a0","datePublished":"2025-02-10T17:43:00+00:00","dateModified":"2025-02-10T18:47:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/"},"wordCount":1164,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg","articleSection":["Concursos P\u00fablicos","Tribunais","Tribunais","Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/","name":"Est\u00e1gio do TJSP","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg","datePublished":"2025-02-10T17:43:00+00:00","dateModified":"2025-02-10T18:47:25+00:00","description":"Confira neste artigo o que voc\u00ea precisa para entrar no TJSP como estagi\u00e1rio. Conhe\u00e7a os principais pontos do Programa de Est\u00e1gio do TJSP.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/01\/10102519\/whatsapp-image-2025-01-08-at-12-02-27.jpeg","width":1600,"height":900,"caption":"Est\u00e1gio do TJSP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/estagio-tjsp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Est\u00e1gio do TJSP: como entrar no TJSP como Estagi\u00e1rio?\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da","name":"Edmar Bezerra Araujo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","caption":"Edmar Bezerra Araujo"},"sameAs":["https:\/\/www.instagram.com\/edmarbezerraaraujo\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/edmarbezerraaraujogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1515095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2974"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1515095"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1515095\/revisions"}],"predecessor-version":[{"id":1530436,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1515095\/revisions\/1530436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1515100"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1515095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1515095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1515095"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1515095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}