{"id":1500312,"date":"2024-12-17T14:02:00","date_gmt":"2024-12-17T17:02:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1500312"},"modified":"2024-12-08T20:12:26","modified_gmt":"2024-12-08T23:12:26","slug":"atuacao-extra-autos-juiz-nulidade","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/","title":{"rendered":"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ol\u00e1, tudo bem? Hoje comentaremos se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trata-se de tema importante no estudo do Direito Processual Penal e, para responder ao questionamento, faremos refer\u00eancia \u00e0 Constitui\u00e7\u00e3o Federal, ao C\u00f3digo de Processo Penal e ao entendimento veiculado recentemente pela Quinta Turma do STJ, em processo em segredo de justi\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos ao que interessa!&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2024\/12\/still-life-with-scales-justice-1024x683.jpg\" alt=\"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?\" class=\"wp-image-1500323\" style=\"width:672px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-1024x683.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-768x512.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-1536x1024.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-2048x1365.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-150x100.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h2><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">\u00cdndice<\/mark><\/h2><ul><li><a href=\"#h-atuacao-extra-autos-do-juiz-nulidade-absoluta-ou-relativa\" data-level=\"2\">Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?<\/a><ul><li><a href=\"#h-imparcialidade-do-juiz-e-nulidade\" data-level=\"3\">Imparcialidade do juiz e nulidade<\/a><ul><li><a href=\"#h-constituicao-federal-de-1988-cf-88\" data-level=\"4\">Constitui\u00e7\u00e3o Federal de 1988 (CF\/88)<\/a><\/li><li><a href=\"#h-codigo-de-processo-penal-cpp\" data-level=\"4\">C\u00f3digo de Processo Penal (CPP)<\/a><\/li><\/ul><\/li><li><a href=\"#h-atuacao-extra-autos-nulidade-reconhecida-no-agrg-no-hc-n-924-332-ms\" data-level=\"3\">Atua\u00e7\u00e3o extra autos &#8211; Nulidade reconhecida no AgRg no HC n. 924.332\/MS<\/a><\/li><\/ul><\/li><li><a href=\"#h-conclusao\" data-level=\"2\">Conclus\u00e3o<\/a><\/li><li><a href=\"#h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\" data-level=\"2\">Quer saber tudo sobre concursos previstos? Confira nossos artigos!<\/a><\/li><\/ul><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-8ce78a675c8bacebda8d1f9de9f47712\" id=\"h-atuacao-extra-autos-do-juiz-nulidade-absoluta-ou-relativa\">Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-6b92022f482c01b39160545ae38b08f6\" id=\"h-imparcialidade-do-juiz-e-nulidade\">Imparcialidade do juiz e nulidade<\/h3>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-a465a976292c7ff48aeadc2bc8d37c83\" id=\"h-constituicao-federal-de-1988-cf-88\">Constitui\u00e7\u00e3o Federal de 1988 (CF\/88)<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A Constitui\u00e7\u00e3o Federal de 1988 (CF\/88) prev\u00ea que ningu\u00e9m ser\u00e1 privado da liberdade ou de seus bens sem o devido processo legal (artigo 5\u00ba, LIV), o que inclui o respeito ao contradit\u00f3rio e \u00e0 ampla defesa (artigo 5\u00ba, LV).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, tamb\u00e9m disp\u00f5e que ningu\u00e9m ser\u00e1 processado nem sentenciado sen\u00e3o pela autoridade competente (artigo 5\u00ba, LIII), ao passo que veda a institui\u00e7\u00e3o de tribunais de exce\u00e7\u00e3o (inciso XXXVII).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos esses dispositivos, de um modo geral, asseguram o processo e o julgamento de um acusado por crime da forma mais imparcial, ison\u00f4mica e com respeito \u00e0s garantias fundamentais poss\u00edvel.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-465d162899f72c6d2825de04465f227a\" id=\"h-codigo-de-processo-penal-cpp\">C\u00f3digo de Processo Penal (CPP)<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">O C\u00f3digo de Processo Penal, principalmente ap\u00f3s as altera\u00e7\u00f5es promovidas pelo Pacote Anticrime (Lei n\u00ba 13.964\/2019), preconiza que o processo penal brasileiro possui <strong>estrutura acusat\u00f3ria<\/strong>, <strong>vedadas <\/strong>a iniciativa do juiz na fase de investiga\u00e7\u00e3o e <strong>a substitui\u00e7\u00e3o da atua\u00e7\u00e3o probat\u00f3ria do \u00f3rg\u00e3o de acusa\u00e7\u00e3o<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por conseguinte, temos que o processo penal p\u00e1trio deve funcionar com a devida separa\u00e7\u00e3o entre as fun\u00e7\u00f5es de julgador e de acusador, sem o que estaremos diante de <strong>nulidade absoluta.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, o artigo 564, inciso I, afirma que haver\u00e1 nulidade por incompet\u00eancia, suspei\u00e7\u00e3o ou suborno do juiz;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 claro que <strong>h\u00e1 exce\u00e7\u00f5es <\/strong>e o juiz, por exemplo, em alguns casos, pode constatar a necessidade de determinar, no curso da instru\u00e7\u00e3o, ou antes de proferir senten\u00e7a, a realiza\u00e7\u00e3o de dilig\u00eancias para dirimir d\u00favida sobre ponto relevante, conforme inciso II do artigo 156.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, via de regra, deve haver um <strong>afastamento do magistrado da causa na produ\u00e7\u00e3o probat\u00f3ria<\/strong>, em rela\u00e7\u00e3o \u00e0 qual se deve oportunizar o protagonismo das partes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, \u00e9 importante mencionar alguns dispositivos do C\u00f3digo de Processo Penal:<\/p>\n\n\n\n<div class=\"wp-block-group has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#abb7c233\">\n<p class=\"wp-block-paragraph\">Art. 563.&nbsp; Nenhum ato ser\u00e1 declarado nulo, se da nulidade n\u00e3o resultar preju\u00edzo para a acusa\u00e7\u00e3o ou para a defesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art. 566.&nbsp; N\u00e3o ser\u00e1 declarada a nulidade de ato processual que n\u00e3o houver influ\u00eddo na apura\u00e7\u00e3o da verdade substancial ou na decis\u00e3o da causa.<\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que j\u00e1 falamos sobre as principais diretrizes e citamos os dispositivos acima, vamos entender o que foi decidido pela Quinta Turma do STJ no <a href=\"https:\/\/processo.stj.jus.br\/SCON\/GetInteiroTeorDoAcordao?num_registro=202402298562&amp;dt_publicacao=12\/11\/2024\" target=\"_blank\" rel=\"noreferrer noopener\">AgRg no HC n. 924.332\/MS<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-d9a33d4dcec424b45e6fde9e2645804c\" id=\"h-atuacao-extra-autos-nulidade-reconhecida-no-agrg-no-hc-n-924-332-ms\">Atua\u00e7\u00e3o extra autos &#8211; Nulidade reconhecida no AgRg no HC n. 924.332\/MS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No julgamento do AgRg no HC n. 924.332\/MS, o Superior Tribunal de Justi\u00e7a entendeu que a conduta do magistrado respons\u00e1vel por presidir a audi\u00eancia em que as provas judiciais orais seriam colhidas sob contradit\u00f3rio, configurou <strong>nulidade ABSOLUTA<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso porque, antes da audi\u00eancia, <strong>atuou de maneira direta e fora da solenidade, &#8220;no corredor&#8221; das depend\u00eancias do f\u00f3rum<\/strong>, tendo mencionado tal fato a pretexto de influenciar no depoimento da parte j\u00e1 durante a audi\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A atua\u00e7\u00e3o extra autos do magistrado, que teria influenciado no depoimento do adolescente infrator, configurou, conforme o STJ, <strong>flagrante descumprimento<\/strong> dos deveres de <strong>prud\u00eancia<\/strong>, <strong>imparcialidade <\/strong>e <strong>transpar\u00eancia<\/strong>, o que conduz \u00e0 nulidade do ato.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdsicvng6jXT6pPCIDt-K4_jDax1GyMnRZFJgsUANQWAP-zIJyfe5wrPNY6d996V8809SfQKnRnSXOJRDqcsI8iX6JBRsWJBTqiAWXnEkb7__BWP9GTOS_NxpuCv0oXXLvrZF6-?key=g5_uEU6SnwVa3Imo4YRUwGhd\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O Superior Tribunal de Justi\u00e7a ainda considerou<strong> n\u00e3o ser sequer poss\u00edvel cogitar da validade do ato, nem sequer a pretexto de aus\u00eancia de preju\u00edzo<\/strong>, uma vez que o entendimento pac\u00edfico do STJ \u00e9 no sentido de que <strong>a quebra de imparcialidade do magistrado \u00e9 fator gerador de nulidade ABSOLUTA.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, \u00e9 interessante destacar que, no voto condutor do ac\u00f3rd\u00e3o, foram citados outros precedentes, que tamb\u00e9m podemos utilizar para fins de estudo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, citou-se o caso do <a href=\"https:\/\/processo.stj.jus.br\/SCON\/GetInteiroTeorDoAcordao?num_registro=202103733919&amp;dt_publicacao=26\/04\/2023\" target=\"_blank\" rel=\"noreferrer noopener\">Habeas Corpus n\u00ba 708.007\/RS<\/a>, em que se reconheceu a nulidade absoluta do processo cuja senten\u00e7a foi lastreada justamente no depoimento das testemunhas ouvidas em audi\u00eancia de instru\u00e7\u00e3o sem a presen\u00e7a do Parquet &#8211; inquiri\u00e7\u00e3o que foi conduzida, de forma protagonista, pela Magistrada da causa, em substitui\u00e7\u00e3o \u00e0 atividade t\u00edpica das Partes (HC n. 708.007\/RS, relatora Ministra Laurita Vaz, Sexta Turma, julgado em 18\/4\/2023, DJe de 26\/4\/2023.).<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-e7b20fe698c6c29a007e244ab912bd2c\" id=\"h-conclusao\">Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, pessoal, esse foi nosso resumo sobre a atua\u00e7\u00e3o extra autos do juiz (se ela provoca nulidade absoluta ou relativa no processo penal), conforme a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como vimos, <strong>o STJ entende que a quebra de imparcialidade do magistrado \u00e9 fator gerador de nulidade absoluta.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o deixe de revisar o assunto em seu material de estudo e praticar com diversas quest\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"506\" height=\"1024\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2020\/09\/Coruja_Concursos@4x-506x1024.png\" alt=\"Concursos 2024 Estrat\u00e9gia Concursos\" class=\"wp-image-574355\" style=\"aspect-ratio:0.5;width:30px;height:auto\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\">Concursos 2024<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrat-corj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\" style=\"text-align: left;\">Concursos 2025<\/h3>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Explore os cursos preparat\u00f3rios completos! \u2728<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/cursos\/concurso\/\" role=\"button\" rel=\"noopener noreferrer\">CLIQUE AQUI<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem? Hoje comentaremos se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ). Trata-se de tema importante no estudo do Direito Processual Penal e, para responder ao questionamento, faremos refer\u00eancia \u00e0 Constitui\u00e7\u00e3o Federal, ao C\u00f3digo de Processo Penal e [&hellip;]<\/p>\n","protected":false},"author":2567,"featured_media":1500323,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1500312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?<\/title>\n<meta name=\"description\" content=\"Confira nossa an\u00e1lise se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme o STJ.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?\" \/>\n<meta property=\"og:description\" content=\"Confira nossa an\u00e1lise se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme o STJ.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-17T17:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/\"},\"author\":{\"name\":\"Frederico Tadeu Borlot Peixoto\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/48a7e085e45aee7c3d4596399af50ebb\"},\"headline\":\"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?\",\"datePublished\":\"2024-12-17T17:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/\"},\"wordCount\":958,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2024\\\/12\\\/05111844\\\/still-life-with-scales-justice-scaled.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/\",\"name\":\"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2024\\\/12\\\/05111844\\\/still-life-with-scales-justice-scaled.jpg\",\"datePublished\":\"2024-12-17T17:02:00+00:00\",\"description\":\"Confira nossa an\u00e1lise se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme o STJ.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2024\\\/12\\\/05111844\\\/still-life-with-scales-justice-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2024\\\/12\\\/05111844\\\/still-life-with-scales-justice-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/atuacao-extra-autos-juiz-nulidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/48a7e085e45aee7c3d4596399af50ebb\",\"name\":\"Frederico Tadeu Borlot Peixoto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"caption\":\"Frederico Tadeu Borlot Peixoto\"},\"description\":\"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\\\/\\\/www.instagram.com\\\/proffrederico\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/proffrederico\\\/\"],\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/xfredericohotmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?","description":"Confira nossa an\u00e1lise se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme o STJ.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?","og_description":"Confira nossa an\u00e1lise se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme o STJ.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-12-17T17:02:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-scaled.jpg","type":"image\/jpeg"}],"author":"Frederico Tadeu Borlot Peixoto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Frederico Tadeu Borlot Peixoto","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/"},"author":{"name":"Frederico Tadeu Borlot Peixoto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb"},"headline":"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?","datePublished":"2024-12-17T17:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/"},"wordCount":958,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-scaled.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"accessibilityFeature":["tableOfContents"]},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/","name":"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-scaled.jpg","datePublished":"2024-12-17T17:02:00+00:00","description":"Confira nossa an\u00e1lise se a atua\u00e7\u00e3o extra autos do juiz provoca nulidade absoluta ou relativa no processo penal, conforme o STJ.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/12\/05111844\/still-life-with-scales-justice-scaled.jpg","width":2560,"height":1707,"caption":"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/atuacao-extra-autos-juiz-nulidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Atua\u00e7\u00e3o extra autos do juiz: Nulidade absoluta ou relativa?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb","name":"Frederico Tadeu Borlot Peixoto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","caption":"Frederico Tadeu Borlot Peixoto"},"description":"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/","sameAs":["https:\/\/www.instagram.com\/proffrederico\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1500312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2567"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1500312"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1500312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1500323"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1500312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1500312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1500312"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1500312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}