{"id":1498730,"date":"2024-12-16T08:02:00","date_gmt":"2024-12-16T11:02:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1498730"},"modified":"2024-12-08T20:00:59","modified_gmt":"2024-12-08T23:00:59","slug":"psicanalise-trt-24","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/","title":{"rendered":"Psican\u00e1lise: resumo para o TRT-24"},"content":{"rendered":"\n<p>Neste artigo voc\u00ea ter\u00e1 um resumo de <strong>Psican\u00e1lise<\/strong>, o qual auxiliar\u00e1 voc\u00ea na prepara\u00e7\u00e3o para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema.<\/p>\n\n\n\n<p>Ol\u00e1, concurseiro! Tudo bem com voc\u00ea? Estudando muito para o concurso do TRT-24? Certamente sim! Afinal, o dia da prova est\u00e1 chegando e, para auxiliar voc\u00ea nessa prepara\u00e7\u00e3o, elaboramos um resumo bastante did\u00e1tico acerca do tema <strong>Psican\u00e1lise<\/strong>, pertencente ao t\u00f3pico <strong>Teorias e T\u00e9cnicas Psicoter\u00e1picas<\/strong>.<\/p>\n\n\n\n<p>Veja o edital do TRT-24 <a href=\"https:\/\/conhecimento.fgv.br\/sites\/default\/files\/concursos\/edital-trt-24-em-31.10.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-iniciais\">Considera\u00e7\u00f5es Iniciais<\/h2>\n\n\n\n<p>Primeiramente, antes de adentrarmos ao assunto de <strong>Terapia Psicanal\u00edtica<\/strong> propriamente dito, conv\u00e9m falarmos um pouco acerca do conceito de <strong>Psicoterapia<\/strong>, de acordo com o que preceitua Cordioli (2009).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-psicoterapia\">Psicoterapia<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"239\" height=\"180\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/26175642\/fique-atento-2.png\" alt=\"psican\u00e1lise\" class=\"wp-image-1482475\" style=\"width:216px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/26175642\/fique-atento-2.png 239w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/26175642\/fique-atento-2-150x113.png 150w\" sizes=\"auto, (max-width: 239px) 100vw, 239px\" \/><\/figure>\n\n\n\n<p>Conforme o autor, a <strong>psicoterapia<\/strong> \u00e9 um <strong>m\u00e9todo de tratamento<\/strong> mediante o qual um <strong>profissional treinado<\/strong>, fazendo-se valer de <strong>meios psicol\u00f3gicos<\/strong>, especialmente da <strong>comunica\u00e7\u00e3o verbal<\/strong> e <strong>da rela\u00e7\u00e3o terap\u00eautica<\/strong>, realiza, de modo deliberado, uma variedade de <strong>interven\u00e7\u00f5es<\/strong>, com o <strong>objetivo de influenciar um cliente ou paciente, auxiliando-o a modificar problemas de natureza emocional, cognitiva e comportamental<\/strong>, tendo em vista que ele (cliente\/paciente) o procurou com essa finalidade.<\/p>\n\n\n\n<p>Um <strong>m\u00e9todo de tratamento<\/strong> significa que se trata de um <strong>processo sistematizado<\/strong>, com o <strong>objetivo de aliviar sintomas<\/strong> que prejudicam o cliente\/paciente.<\/p>\n\n\n\n<p>Al\u00e9m disso, nesse processo, est\u00e1 presente um <strong>profissional treinado<\/strong>, com conhecimentos necess\u00e1rios que o possibilitam identificar as demandas trazidas por quem o procura em busca de tratamento.<\/p>\n\n\n\n<p>Outrossim, a <strong>comunica\u00e7\u00e3o verbal<\/strong> baseia-se numa <strong>troca de informa\u00e7\u00f5es<\/strong> pela linguagem falada, a qual ocorre devido \u00e0 <strong>rela\u00e7\u00e3o terap\u00eautica<\/strong>, marcada pelo estabelecimento da confian\u00e7a (<strong><em>rapport<\/em><\/strong>), com o objetivo de modificar problemas.<\/p>\n\n\n\n<p>Ademais, \u00e9 importante destacar neste resumo, o conceito de <strong><em>rapport<\/em><\/strong>, tendo em vista que \u00e9 um ponto que pode ser cobrado em sua prova de concurso. De acordo com Anastasi e Urbina, \u00e9 poss\u00edvel definir <strong><em>rapport <\/em><\/strong>como o <strong>estabelecimento do v\u00ednculo com o indiv\u00edduo a quem o profissional se dirige<\/strong>. Trata-se de uma <strong>rela\u00e7\u00e3o especial<\/strong> que tem como alicerce aspectos emocionais e de apresenta\u00e7\u00e3o f\u00edsica, tais como aten\u00e7\u00e3o especial ao tom de voz, dire\u00e7\u00e3o do olhar, gestualidade, entre outros). Desse modo, \u00e9 necess\u00e1rio o estabelecimento do <em>rapport<\/em> para que se possa assegurar a <strong>consolida\u00e7\u00e3o de um v\u00ednculo de confian\u00e7a entre cliente\/paciente e terapeuta<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-caracteristicas-comuns-a-todas-as-abordagens-de-psicoterapia\">Caracter\u00edsticas comuns a todas as abordagens de psicoterapia<\/h3>\n\n\n\n<p>Conforme Cordioli, as <strong>psicoterapias<\/strong> s\u00e3o <strong>diferentes<\/strong> quanto a seus <strong>objetivos<\/strong> e pressupostos te\u00f3ricos, \u00e0 frequ\u00eancia das sess\u00f5es, quanto ao tempo que duram. Entretanto, existem <strong>caracter\u00edsticas comuns a todas as abordagens<\/strong>. S\u00e3o elas, de acordo com o entendimento do autor:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tratamento conduzido por um <strong>profissional treinado<\/strong> que tem como <strong>objetivo aliviar ou acabar com um problema<\/strong> de um <strong>paciente<\/strong> que voluntariamente, n\u00e3o, <strong>procura ajuda<\/strong>.<\/li>\n\n\n\n<li>O terapeuta utiliza <strong>ferramentas psicol\u00f3gicas para conduzir um processo<\/strong>.<\/li>\n\n\n\n<li>A <strong>rela\u00e7\u00e3o terap\u00eautica<\/strong> ocorre em um contexto interpessoal.<\/li>\n\n\n\n<li>Ocorre por meio da <strong>comunica\u00e7\u00e3o verbal<\/strong>.<\/li>\n\n\n\n<li>Ocorre uma <strong>colabora\u00e7\u00e3o entre paciente e terapeuta<\/strong>.<\/li>\n\n\n\n<li>Existe <strong>confian\u00e7a<\/strong> e <strong>apoio<\/strong>, e o paciente acredita que o terapeuta ir\u00e1 ajud\u00e1-lo e seu problema ser\u00e1 resolvido.<\/li>\n\n\n\n<li>O terapeuta utiliza <strong>ferramentas de um modelo<\/strong> que explica a origem e a continuidade dos sintomas, oferecendo um caminho para ajudar a solucionar.<\/li>\n\n\n\n<li>A terapia deve ajudar o paciente a se <strong>conhecer e a buscar solu\u00e7\u00f5es para a forma como est\u00e1 agindo, pensando e sentindo<\/strong>, pois n\u00e3o est\u00e1 funcionando.<\/li>\n\n\n\n<li>O paciente precisa <strong>sentir que \u00e9 necess\u00e1ria a mudan\u00e7a<\/strong> e que precisa <strong>se esfor\u00e7ar<\/strong> para isso.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-terapia-psicanalitica\">Terapia Psicanal\u00edtica<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"207\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/11\/30081219\/indo-mais-fundo.png\" alt=\"\" class=\"wp-image-1497693\" style=\"width:477px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/11\/30081219\/indo-mais-fundo.png 766w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/11\/30081219\/indo-mais-fundo-300x81.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/11\/30081219\/indo-mais-fundo-150x41.png 150w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/figure>\n\n\n\n<p>Em primeiro lugar, \u00e9 importante destacar que essa <strong>modalidade psicoter\u00e1pica busca a cura por meio do autoconhecimento <\/strong>e tem como seu fundador <strong>Sigmund Freud<\/strong>. A escola freudiana \u00e9 a base da psican\u00e1lise<\/p>\n\n\n\n<p>Outrossim, a palavra <strong>psican\u00e1lise <\/strong>\u00e9 utilizada para designar tanto uma <strong>teoria do funcionamento mental<\/strong>, quanto um <strong>m\u00e9todo de investiga\u00e7\u00e3o dos processos mentais inconscientes<\/strong> ou ainda um <strong>m\u00e9todo de tratamento para transtornos emocionais<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-principais-conceitos-da-psicanalise\">Principais conceitos da Psican\u00e1lise<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"279\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/19205623\/esclarecendo.png\" alt=\"\" class=\"wp-image-1479131\" style=\"width:218px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/19205623\/esclarecendo.png 294w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/19205623\/esclarecendo-150x142.png 150w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><\/figure>\n\n\n\n<p>Agora traremos alguns dos conceitos da <strong>Psican\u00e1lise <\/strong>que mais caem em provas de concurso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-determinismo-psiquico\">Determinismo Ps\u00edquico<\/h3>\n\n\n\n<p>Em primeiro lugar, conv\u00e9m destacar que o conceito de <strong>determinismo ps\u00edquico<\/strong> \u00e9 um dos conceitos centrais da teoria psicanal\u00edtica e que cai com bastante frequ\u00eancia em provas de concurso.<\/p>\n\n\n\n<p>De acordo com esse conceito, <strong>todos os acontecimentos da vida mental s\u00e3o determinados, produzidos ou, ao menos, influenciado por eventos anteriores do desenvolvimento, tanto os que ocorreram imediatamente antes quanto aqueles que foram vividos no in\u00edcio do desenvolvimento.<\/strong><\/p>\n\n\n\n<p>Portanto, de acordo com a teoria psicanal\u00edtica, <strong>nada ocorre ao acaso<\/strong>, sobretudo os processos mentais. Conforme preceitua Freud, h\u00e1 uma causa para cada pensamento, para cada mem\u00f3ria revivida, sentimento ou a\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-consciente\">Consciente<\/h3>\n\n\n\n<p>Conforme a teoria psicanal\u00edtica, o sistema <strong>consciente tem a fun\u00e7\u00e3o de receber informa\u00e7\u00f5es advindas das excita\u00e7\u00f5es oriundas do exterior e do interior.<\/strong><\/p>\n\n\n\n<p>Revela-se, portanto, como uma <strong>parte da nossa mente que nos conecta \u00e0 realidade<\/strong>.\u00a0 A maior parte das fun\u00e7\u00f5es perceptivo-cognitivas-motoras do ego s\u00e3o processadas no sistema consciente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-pre-consciente\">Pr\u00e9-consciente<\/h3>\n\n\n\n<p>O sistema <strong>pr\u00e9-consciente<\/strong> foi concebido como articulado ao inconsciente. Ele surge como uma \u201cbarreira de contato\u201d, <strong>funciona como uma esp\u00e9cie de peneira que seleciona aquilo que pode ou n\u00e3o passar para o consciente.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inconsciente\">Inconsciente<\/h3>\n\n\n\n<p>Outrossim, \u00e9 importante trazer destaque a esse conceito, pois ele \u00e9 a base da teoria psicanal\u00edtica.<\/p>\n\n\n\n<p>Conforme a teoria em an\u00e1lise, o sistema<strong> inconsciente designa a parte mais arcaica do aparelho ps\u00edquico. <\/strong>De acordo com Freud, n\u00e3o \u00e9 poss\u00edvel abordar diretamente o inconsciente, sendo este conhecido somente por suas forma\u00e7\u00f5es: atos falhos, sonhos, chistes e sintomas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-id\">Id<\/h3>\n\n\n\n<p>De acordo com Freud, o<strong> id \u00e9 a parte instintiva de nossa natureza<\/strong>. Ele representa os <strong>processos primitivos do pensamento e constitui o reservat\u00f3rio das puls\u00f5es.<\/strong> Desse modo, toda a energia que envolve a atividade humana vem do Id.<\/p>\n\n\n\n<p>Ademais, vale lembrar que o <strong>id \u00e9 regido pelo princ\u00edpio do prazer<\/strong>. Dessa forma, para o Id, n\u00e3o h\u00e1 regra a  seguir: tudo que lhe interessa \u00e9 a vaz\u00e3o do desejo, a a\u00e7\u00e3o, a express\u00e3o, a satisfa\u00e7\u00e3o.<\/p>\n\n\n\n<p>O <strong>id fica localizado no n\u00edvel inconsciente<\/strong> e n\u00e3o reconhece os elementos sociais. Portanto, para ele, n\u00e3o h\u00e1 certo ou errado. N\u00e3o h\u00e1 tempo ou espa\u00e7o. O id \u00e9 o ambiente dos impulsos sexuais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ego\">Ego<\/h3>\n\n\n\n<p>De acordo com Freud, o<strong> ego \u00e9 a inst\u00e2ncia ps\u00edquica que evolui a partir do Id<\/strong>. Em decorr\u00eancia disso, <strong>possui elementos do inconsciente<\/strong>. Apesar disso,<strong> funciona principalmente em n\u00edvel consciente. Outrossim, \u00e9 o princ\u00edpio da realidade que rege o superego. <\/strong>Uma de suas fun\u00e7\u00f5es \u00e9 <strong>limitar o id<\/strong> quando considerar seus desejos inadequados para determinado momento ou ocasi\u00e3o.<\/p>\n\n\n\n<p><strong>O ego representa a media\u00e7\u00e3o entre as exig\u00eancias do Id e as ordens do Superego.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-superego\">Superego<\/h3>\n\n\n\n<p>O <strong>superego<\/strong>, por sua vez, \u00e9 a <strong>parte que contra age ao id<\/strong>.<strong> Representa os pensamentos morais e \u00e9ticos da sociedade que s\u00e3o internalizados pelo indiv\u00edduo.<\/strong><\/p>\n\n\n\n<p>Outrossim, \u00e9 importante ressaltar que ele \u00e9 o<strong> aspecto social<\/strong>. Resulta, em grande parte, das imposi\u00e7\u00f5es e castigos sofridos na inf\u00e2ncia. Ele se encontra e participa desses dois n\u00edveis mentais. O superego \u00e9 a <strong>censura<\/strong>, a <strong>culpa <\/strong>e o <strong>medo da puni\u00e7\u00e3o<\/strong>. O superego \u00e9 uma inst\u00e2ncia reguladora. \u00c9 considerado o <strong>herdeiro do Complexo de \u00c9dipo.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-para-finalizar\">Para finalizar<\/h2>\n\n\n\n<p>Por fim, saiba que o objetivo deste artigo foi trazer para voc\u00ea, psic\u00f3logo concurseiro, pontos importantes acerca do tema <strong>Terapia Psicanal\u00edtica<\/strong> para o concurso do TRT 24. No entanto, para al\u00e9m desse certame, esse tema \u00e9 extremamente relevante para provas de concurso na \u00e1rea de psicologia em geral.<\/p>\n\n\n\n<p>Outrossim, este resumo n\u00e3o abrange toda a complexidade do tema <strong>Psican\u00e1lise<\/strong>, mas, certamente, nele voc\u00ea encontrar\u00e1 aspectos importantes que ajudar\u00e3o voc\u00ea a gabaritar quest\u00f5es sobre esse assunto.<\/p>\n\n\n\n<p>Al\u00e9m disso, para a sua prepara\u00e7\u00e3o, n\u00e3o deixe de responder muitas quest\u00f5es. Para auxiliar voc\u00ea nessa miss\u00e3o, o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/?srsltid=AfmBOopuIKg18aAnqg5fR5p7dRDBGc5fjnEdFvQXIG-F5BrVj9ZKXK1G\" target=\"_blank\" rel=\"noreferrer noopener\">Estrat\u00e9gia Concursos<\/a> oferece um <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/sistema-de-questoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">sistema de quest\u00f5es<\/a> bastante completo que certamente ajudar\u00e1 voc\u00ea na conquista da t\u00e3o sonhada vaga no servi\u00e7o p\u00fablico.<\/p>\n\n\n\n<p>Finalmente, n\u00e3o deixe de acompanhar e ficar por dentro do que acontece no mundo dos concursos.<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 202<\/a><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">4<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste artigo voc\u00ea ter\u00e1 um resumo de Psican\u00e1lise, o qual auxiliar\u00e1 voc\u00ea na prepara\u00e7\u00e3o para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema. Ol\u00e1, concurseiro! Tudo bem com voc\u00ea? Estudando muito para o concurso do TRT-24? Certamente sim! Afinal, o dia da prova est\u00e1 chegando e, para auxiliar [&hellip;]<\/p>\n","protected":false},"author":2982,"featured_media":1319564,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1498730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Psican\u00e1lise: resumo para o TRT-24<\/title>\n<meta name=\"description\" content=\"Neste artigo voc\u00ea ter\u00e1 um resumo de Psican\u00e1lise para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Psican\u00e1lise: resumo para o TRT-24\" \/>\n<meta property=\"og:description\" content=\"Neste artigo voc\u00ea ter\u00e1 um resumo de Psican\u00e1lise para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T11:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caroline Martins da Costa Leite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Caroline Martins da Costa Leite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/\"},\"author\":{\"name\":\"Caroline Martins da Costa Leite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a\"},\"headline\":\"Psican\u00e1lise: resumo para o TRT-24\",\"datePublished\":\"2024-12-16T11:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/\"},\"wordCount\":1393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/\",\"name\":\"Psican\u00e1lise: resumo para o TRT-24\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg\",\"datePublished\":\"2024-12-16T11:02:00+00:00\",\"description\":\"Neste artigo voc\u00ea ter\u00e1 um resumo de Psican\u00e1lise para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg\",\"width\":768,\"height\":432,\"caption\":\"concurso trt ms retomado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Psican\u00e1lise: resumo para o TRT-24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a\",\"name\":\"Caroline Martins da Costa Leite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g\",\"caption\":\"Caroline Martins da Costa Leite\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carol_leite1706hotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Psican\u00e1lise: resumo para o TRT-24","description":"Neste artigo voc\u00ea ter\u00e1 um resumo de Psican\u00e1lise para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/","og_locale":"pt_BR","og_type":"article","og_title":"Psican\u00e1lise: resumo para o TRT-24","og_description":"Neste artigo voc\u00ea ter\u00e1 um resumo de Psican\u00e1lise para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-12-16T11:02:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg","type":"image\/jpeg"}],"author":"Caroline Martins da Costa Leite","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Caroline Martins da Costa Leite","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/"},"author":{"name":"Caroline Martins da Costa Leite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a"},"headline":"Psican\u00e1lise: resumo para o TRT-24","datePublished":"2024-12-16T11:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/"},"wordCount":1393,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/","name":"Psican\u00e1lise: resumo para o TRT-24","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg","datePublished":"2024-12-16T11:02:00+00:00","description":"Neste artigo voc\u00ea ter\u00e1 um resumo de Psican\u00e1lise para o concurso do TRT da 24\u00aa Regi\u00e3o e em outros certames que cobrem esse tema.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/11162718\/trt-24.jpg","width":768,"height":432,"caption":"concurso trt ms retomado"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/psicanalise-trt-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Psican\u00e1lise: resumo para o TRT-24"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1c7ac186f04b04e87eeba66c2467cf6a","name":"Caroline Martins da Costa Leite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/061997e69e4fd91b5e3d45dff736c5f05b3c02a4283b46708faf52b75701224e?s=96&d=mm&r=g","caption":"Caroline Martins da Costa Leite"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carol_leite1706hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1498730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2982"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1498730"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1498730\/revisions"}],"predecessor-version":[{"id":1498751,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1498730\/revisions\/1498751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1319564"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1498730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1498730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1498730"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1498730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}