{"id":1483828,"date":"2024-11-11T08:02:00","date_gmt":"2024-11-11T11:02:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1483828"},"modified":"2024-11-02T17:34:49","modified_gmt":"2024-11-02T20:34:49","slug":"resumo-malware-concursos","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/","title":{"rendered":"Resumo de malware para concursos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg\" alt=\"Resumo de malware para concursos p\u00fablicos\" class=\"wp-image-1013626\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg 700w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972-610x407.jpg 610w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p>O presente artigo procura trazer um resumo de <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware<\/strong><\/mark> para concursos p\u00fablicos.<\/p>\n\n\n\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>Malware <\/strong><\/mark>\u00e9 um tipo de software, s\u00f3 que malicioso. Enquanto o software \u00e9 um programa de computador \u00fatil como ferramenta, no uso de tecnologia da informa\u00e7\u00e3o, o <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\"><strong>malware <\/strong><\/mark>\u00e9 um software utilizado para ataques hacker, roubos de senha, envio de correio eletr\u00f4nico indesejado, espionagem ou propaga\u00e7\u00e3o de v\u00edrus.<\/p>\n\n\n\n<p>Em concursos p\u00fablicos, bancas como a <a href=\"https:\/\/www.vunesp.com.br\/\">Funda\u00e7\u00e3o Vunesp<\/a> e a <a href=\"https:\/\/www.concursosfcc.com.br\/\">Funda\u00e7\u00e3o Carlos Chagas<\/a>, na disciplina de conhecimentos em inform\u00e1tica ou tecnologia da informa\u00e7\u00e3o, especificamente seguran\u00e7a da informa\u00e7\u00e3o, cobram <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware<\/strong><\/mark>.<\/p>\n\n\n\n<p>E essa cobran\u00e7a, geralmente, busca fazer com que o candidato associe uma defini\u00e7\u00e3o do modus operandi com o nome de um <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware <\/strong><\/mark>espec\u00edfico.<\/p>\n\n\n\n<p>Assim, o artigo procura trazer o resumo da defini\u00e7\u00e3o de alguns dos principais <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\"><strong>malware <\/strong><\/mark>cobrados em provas de concurso p\u00fablico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-de-malwares-para-concursos-spyware-keyloger-e-screenloger\">Resumo de malwares para concursos &#8211; Spyware, Keyloger e Screenloger<\/h2>\n\n\n\n<p>Existem tr\u00eas tipos de <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\"><strong>malware <\/strong><\/mark>que fazem basicamente alguma coisa, mas de maneiras e com focos diferentes.\u00a0 A fun\u00e7\u00e3o deles \u00e9, quando instalado em uma m\u00e1quina, monitorar a atividade realizada pelo usu\u00e1rio.<\/p>\n\n\n\n<p>O spyware monitora a navega\u00e7\u00e3o online do usu\u00e1rio J\u00e1 o keylogger registra todo o movimento do teclado que o usu\u00e1rio realiza. E o screenlog faz o registro das telas visualizadas pelo usu\u00e1rio.<\/p>\n\n\n\n<p>Nesse caso, o usu\u00e1rio \u00e9 a v\u00edtima, que n\u00e3o sabe sobre a exist\u00eancia do <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware<\/strong><\/mark>. O resultado do monitoramento vai para um terceiro, que pode usar os dados para roubar senhas, realizar chantagem ou extors\u00e3o, ou at\u00e9 mesmo tra\u00e7ar perfil do usu\u00e1rio sem autoriza\u00e7\u00e3o, para usar em marketing e propaganda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-golpe-do-phishing\">O golpe do Phishing<\/h2>\n\n\n\n<p>Continuando com o resumo de <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware <\/strong><\/mark>para concursos, o phishing \u00e9 um conceito moderno, perigoso, e um dos mais cobrados nas provas.<\/p>\n\n\n\n<p>A palavra phishing vem de fishing, que significa pescar, em ingl\u00eas.<\/p>\n\n\n\n<p>Primeiramente, o usu\u00e1rio v\u00edtima recebe um SMS ou e-mail, com o remetente identificado como alguma organiza\u00e7\u00e3o importante, banco, loja ou empresa, que geralmente todas as pessoas possuem conta.<\/p>\n\n\n\n<p>Ao clicar em um link da mensagem, vai para um site id\u00eantico ao site oficial da empresa\/banco\/loja, por\u00e9m n\u00e3o \u00e9 o site oficial, \u00e9 um site falso. Em seguida, o site solicita dados do usu\u00e1rio ou senha de acesso. Caso inserida, o golpista captura toda essa informa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Com finalidade de evitar o phishing, deve-se ficar atento se a mensagem enviada \u00e9 realmente de um remetente confi\u00e1vel. Al\u00e9m disso, a barra de endere\u00e7o e o URL do site falso geralmente n\u00e3o \u00e9 igual ao site da organiza\u00e7\u00e3o oficial. Portanto, \u00e9 bom se atentar ao endere\u00e7o do site antes de fornecer as informa\u00e7\u00f5es solicitadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-de-malwares-para-concursos-spam\">Resumo de malwares para concursos \u2013 Spam<\/h2>\n\n\n\n<p>Em continua\u00e7\u00e3o ao resumo de <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware <\/strong><\/mark>para concursos p\u00fablicos, spam s\u00e3o e-mails que chegam de forma muito r\u00e1pida e indesejada nas caixas de e-mail pessoais. Devido \u00e0 tamanha rapidez e quantidade, muitas vezes os e-mail de spam s\u00e3o disparados por rob\u00f4s, utilizando listas gigantescas de e-mail pessoais.<\/p>\n\n\n\n<p>Geralmente, s\u00e3o de lojas e sites que o usu\u00e1rio nunca acessou. Tamb\u00e9m podem ser frutos de troca de dados ilegal entre empresas.<\/p>\n\n\n\n<p>Assim, acabam lotando a caixa de e-mail r\u00e1pido. Ent\u00e3o, aconselha-se identificar o endere\u00e7o de envio como spam, para n\u00e3o receber mais e-mails daquele endere\u00e7o automaticamente. Ademais, \u00e9 aconselh\u00e1vel  reportar o spam, para diminuir essa pr\u00e1tica indesejada da internet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cavalo-de-troia-e-worm\">Cavalo de Tr\u00f3ia e Worm<\/h2>\n\n\n\n<p>Seguindo o resumo de <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware <\/strong><\/mark>para concursos, restam o calavo de Tr\u00f3ia e worm como malwares.<\/p>\n\n\n\n<p>Na hist\u00f3ria, o cavalo de Tr\u00f3ia foi uma estrat\u00e9gia dos gregos para ganhar uma guerra. Os gregos encheram um cavalo de madeira gigante com soldados, e enviaram como presente para o rei inimigo. Ao adentrar a cidade, o presente se abriu, cheio de soldados, que ganharam a batalha devido ao fato surpresa.<\/p>\n\n\n\n<p>O <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware <\/strong><\/mark>usa um racioc\u00ednio semelhante. No caso, o usu\u00e1rio baixa ou recebe um arquivo por vontade pr\u00f3pria, com nome certo, e abre para utilizar. Por\u00e9m, o arquivo \u00e9 um v\u00edrus execut\u00e1vel, que imediatamente age no computador.<\/p>\n\n\n\n<p>Muitas vezes, um arquivo que deveria ter extens\u00e3o doc ou mp3, respectivamente, um texto ou uma m\u00fasica, quando aparecer com extens\u00e3o exe, de execut\u00e1vel, \u00e9 suspeito de ser um cavalo de tr\u00f3ia. Assim, uma boa dica e ficar atento \u00e0 extens\u00e3o do arquivo.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao worm, larva, em ingl\u00eas, \u00e9 um arquivo que tem como objetivo se espalhar o m\u00e1ximo que conseguir. Primeiro se espalha dentro do computador do pr\u00f3prio usu\u00e1rio, e, quando o usu\u00e1rio transmite arquivos, se espalha para outros computadores. Pode conter outro <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware<\/strong><\/mark>, e \u00e9 programado para se propagar de maneira r\u00e1pida e dif\u00edcil de conter.<\/p>\n\n\n\n<p>Chegamos ao fim do resumo de <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>malware <\/strong><\/mark>para concursos. Tome cuidado ao navegar na internet, e ao responder quest\u00f5es sobre o tema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\">Cursos e Assinaturas<\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos Abertos<\/mark><\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos 2024<\/mark><\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos 2025<\/mark><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presente artigo procura trazer um resumo de malware para concursos p\u00fablicos. Malware \u00e9 um tipo de software, s\u00f3 que malicioso. Enquanto o software \u00e9 um programa de computador \u00fatil como ferramenta, no uso de tecnologia da informa\u00e7\u00e3o, o malware \u00e9 um software utilizado para ataques hacker, roubos de senha, envio de correio eletr\u00f4nico indesejado, [&hellip;]<\/p>\n","protected":false},"author":2978,"featured_media":1013626,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1483828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo de malware para concursos<\/title>\n<meta name=\"description\" content=\"Resumo de malware para concursos Spam keylogger screenlogger spyware phishing cavalo de troia worm seguran\u00e7a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo de malware para concursos\" \/>\n<meta property=\"og:description\" content=\"Resumo de malware para concursos Spam keylogger screenlogger spyware phishing cavalo de troia worm seguran\u00e7a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-11T11:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlos Augusto Canada Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Augusto Canada Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/\"},\"author\":{\"name\":\"Carlos Augusto Canada Silva\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321\"},\"headline\":\"Resumo de malware para concursos\",\"datePublished\":\"2024-11-11T11:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/\"},\"wordCount\":874,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/\",\"name\":\"Resumo de malware para concursos\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg\",\"datePublished\":\"2024-11-11T11:02:00+00:00\",\"description\":\"Resumo de malware para concursos Spam keylogger screenlogger spyware phishing cavalo de troia worm seguran\u00e7a\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg\",\"width\":700,\"height\":467,\"caption\":\"Resumo de malware para concursos p\u00fablicos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo de malware para concursos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321\",\"name\":\"Carlos Augusto Canada Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"caption\":\"Carlos Augusto Canada Silva\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carlosaugusto-c-silvagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo de malware para concursos","description":"Resumo de malware para concursos Spam keylogger screenlogger spyware phishing cavalo de troia worm seguran\u00e7a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo de malware para concursos","og_description":"Resumo de malware para concursos Spam keylogger screenlogger spyware phishing cavalo de troia worm seguran\u00e7a","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-11-11T11:02:00+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg","type":"image\/jpeg"}],"author":"Carlos Augusto Canada Silva","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Carlos Augusto Canada Silva","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/"},"author":{"name":"Carlos Augusto Canada Silva","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321"},"headline":"Resumo de malware para concursos","datePublished":"2024-11-11T11:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/"},"wordCount":874,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/","name":"Resumo de malware para concursos","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg","datePublished":"2024-11-11T11:02:00+00:00","description":"Resumo de malware para concursos Spam keylogger screenlogger spyware phishing cavalo de troia worm seguran\u00e7a","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/04\/22142305\/mao-digitando-no-teclado-do-computador-na-linha-de-negocios-e-ideias-de-negocios-700-147121972.jpg","width":700,"height":467,"caption":"Resumo de malware para concursos p\u00fablicos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-malware-concursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo de malware para concursos"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321","name":"Carlos Augusto Canada Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","caption":"Carlos Augusto Canada Silva"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carlosaugusto-c-silvagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1483828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2978"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1483828"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1483828\/revisions"}],"predecessor-version":[{"id":1483847,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1483828\/revisions\/1483847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1013626"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1483828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1483828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1483828"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1483828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}