{"id":1483362,"date":"2024-11-10T14:13:00","date_gmt":"2024-11-10T17:13:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1483362"},"modified":"2024-11-29T11:27:01","modified_gmt":"2024-11-29T14:27:01","slug":"agente-policia-legislativa-ales","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/","title":{"rendered":"Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-confira-neste-artigo-os-principais-pontos-referentes-ao-cargo-de-agente-de-policia-legislativa-da-ales\"><strong><em>Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES<\/em><\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"568\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49-1024x568.jpeg\" alt=\"Agente de Pol\u00edcia Legislativa da ALES \n\" class=\"wp-image-1483366\" style=\"width:709px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49-1024x568.jpeg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49-300x166.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49-768x426.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49-1536x852.jpeg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49-150x83.jpeg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Agente de Pol\u00edcia Legislativa da ALES&nbsp;<\/figcaption><\/figure>\n\n\n\n<p>Ol\u00e1, pessoal! Tudo bem? Hoje falaremos sobre o<strong> cargo de Agente de Pol\u00edcia Legislativa da ALES.<\/strong> Voc\u00ea se interessa?&nbsp;<\/p>\n\n\n\n<p>Pois ent\u00e3o saiba que este artigo est\u00e1 na <strong>medida certa<\/strong> para voc\u00ea! Trata-se de mais uma <strong>oportunidade<\/strong> para trabalhar na \u00e1rea da <strong>Pol\u00edcia Legislativa<\/strong> que voc\u00ea poder\u00e1&nbsp; deixar no seu radar e aproveitar a sua bagagem de estudos.<\/p>\n\n\n\n<p>O edital do pr\u00f3ximo <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-assembleia-legislativa-es\/#cursos\"><strong>Concurso da ALES (Assembleia Legislativa do Esp\u00edrito Santo) segue com previs\u00e3o de lan\u00e7amento ainda em 2024.<\/strong><\/a> Assim sendo, espera-se que o certame ofere\u00e7a oportunidades para os cargos de Consultor Legislativo, Analista Legislativo e <strong>Agente de Pol\u00edcia Legislativa<\/strong>.<\/p>\n\n\n\n<p>Ent\u00e3o, pensando pelo lado da fun\u00e7\u00e3o de <strong>Agente de Pol\u00edcia Legislativa<\/strong>, preparamos este conte\u00fado para que voc\u00ea n\u00e3o s\u00f3 fique por dentro do assunto, mas, tamb\u00e9m, tire suas d\u00favidas e entenda os<strong> principais pontos referentes ao cargo <\/strong>em quest\u00e3o. Acompanhe!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-914d8001e9678a4e5fad355967e3a0d1\" id=\"h-agente-de-policia-legislativa-da-ales-precedentes\">Agente de Pol\u00edcia Legislativa da ALES: precedentes<\/h2>\n\n\n\n<p>Atrav\u00e9s do <a href=\"https:\/\/www3.al.es.gov.br\/processo.aspx?id=408632\"><strong>Projeto de Lei 77\/2024,<\/strong><\/a> a <strong>ALES<\/strong> criou a estrutura da <strong>Pol\u00edcia Legislativa<\/strong> no \u00e2mbito de seu quadro funcional. Desse modo, converteu-se o antigo cargo de T\u00e9cnico Legislativo J\u00fanior em um novo cargo, denominado <strong>Agente de Pol\u00edcia Legislativa.<\/strong><\/p>\n\n\n\n<p>E o que isso significa? Na pr\u00e1tica, a partir da convers\u00e3o do Projeto mencionado em Lei, todos os servidores ocupantes do cargo de T\u00e9cnico Legislativo J\u00fanior foram automaticamente transferidos para a <strong>carreira de Agente de Pol\u00edcia Legislativa,<\/strong> mantendo-se as mesmas prerrogativas j\u00e1 existentes.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, atrav\u00e9s da altera\u00e7\u00e3o do cargo tamb\u00e9m se instituiu a <strong>FGESL (Fun\u00e7\u00e3o Gratificada Especial de Seguran\u00e7a Legislativa),<\/strong> de&nbsp; exclusividade dos titulares da carreira de Agente de Pol\u00edcia Legislativa.<\/p>\n\n\n\n<p>Desse modo, tal&nbsp; gratifica\u00e7\u00e3o estabelece um <strong>acr\u00e9scimo de 20%<\/strong> ao vencimento do servidor. Entretanto, determinou-se que o quantitativo m\u00e1ximo de gratifica\u00e7\u00f5es dessa natureza a serem concedidas \u00e9 de trinta e oito.&nbsp;<\/p>\n\n\n\n<p>Quanto \u00e0 carga hor\u00e1ria da profiss\u00e3o, vale destacar que mesmo ap\u00f3s a convers\u00e3o do cargo anterior para o novo cargo, manteve-se a mesma <strong>jornada de trabalho semanal, de 30 horas,<\/strong> tal qual a carga hor\u00e1ria de trabalho de todas as demais carreiras da ALES.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-41024dcaf5fbe6bd742d3208287410b6\" id=\"h-principais-atribuicoes-do-cargo\">Principais atribui\u00e7\u00f5es do cargo<\/h2>\n\n\n\n<p>O candidato que for nomeado para trabalhar como<strong> Agente de Pol\u00edcia Legislativa da ALES<\/strong> ficar\u00e1 respons\u00e1vel por cumprir algumas tarefas importantes no dia a dia da profiss\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Dentre as atribui\u00e7\u00f5es, cumpre ao profissional a execu\u00e7\u00e3o de <strong>atividades de policiamento<\/strong> relacionadas \u00e0 orienta\u00e7\u00e3o e manuten\u00e7\u00e3o da ordem no \u00e2mbito da ALES.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 da compet\u00eancia do servidor <strong>garantir a integridade <\/strong>dos deputados, dos demais servidores e tamb\u00e9m das autoridades presentes nas depend\u00eancias do \u00f3rg\u00e3o.<\/p>\n\n\n\n<p>Ademais, tamb\u00e9m \u00e9&nbsp; da al\u00e7ada do membro da <strong>Pol\u00edcia Legislativa da ALES,<\/strong> identificar pessoas, retendo armas ou outros instrumentos de agress\u00e3o e inspecionando a entrada e a sa\u00edda de ve\u00edculos e objetos no \u00e2mbito do \u00f3rg\u00e3o.<\/p>\n\n\n\n<p>Tamb\u00e9m est\u00e1 entre as atividades rotineiras da fun\u00e7\u00e3o a <strong>realiza\u00e7\u00e3o de revistas.<\/strong> Nesse sentido, tal procedimento abrange a revista de pessoas, de banheiros, dos vesti\u00e1rios e tamb\u00e9m dos espa\u00e7os de uso exclusivo.<\/p>\n\n\n\n<p>Por \u00faltimo, tamb\u00e9m <strong>cabe ao Agente de Pol\u00edcia Legislativa fiscalizar os ambientes,<\/strong> comunicar as ocorr\u00eancias identificadas \u00e0 chefia e escoltar os presos e os depoentes que estejam sob a responsabilidade da ALES.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-very-light-gray-to-cyan-bluish-gray-gradient-background has-text-color has-background has-link-color wp-elements-35abd518cc5cd5f49b75c0ef900c0d23\" id=\"h-o-que-podemos-esperar-do-concurso-de-agente-de-policia-legislativa-da-ales\">O que podemos esperar do concurso de Agente de Pol\u00edcia Legislativa da ALES?<\/h2>\n\n\n\n<p>Primeiramente, de acordo com a atual <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/15192540\/estrutura_organizacional_remuneratoria-efetivos.pdf\"><strong>estrutura remunerat\u00f3ria do quadro de servidores efetivos da ALES<\/strong>,<\/a> a <strong>remunera\u00e7\u00e3o base inicial para o cargo de Agente de Pol\u00edcia Legislativa \u00e9 de R$3.007,32, podendo chegar a R$6.255,89 na sigla final de progress\u00e3o funcional.&nbsp;<\/strong><\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 preciso atentar para a poss\u00edvel <strong>quantidade de cargos desocupados para a especialidade no momento.<\/strong> Esse dado est\u00e1 dispon\u00edvel acessando o <a href=\"https:\/\/www.al.es.gov.br\/Transparencia\"><strong>Portal da Transpar\u00eancia da ALES.<\/strong><\/a> Dessa maneira, se voc\u00ea filtrar uma busca pela nomenclatura da fun\u00e7\u00e3o, ir\u00e1 constatar que <strong>apenas 43 profissionais<\/strong> se encontram ativos atualmente.&nbsp;<\/p>\n\n\n\n<p>Desse modo, conclui-se que h\u00e1 um d\u00e9ficit consider\u00e1vel de servidores para a carreira em quest\u00e3o nos dias atuais. A <a href=\"https:\/\/www3.al.es.gov.br\/arquivo\/documents\/legislacao\/html\/RES34992013.html#a47\"><strong>Resolu\u00e7\u00e3o n\u00ba 3.499, de 25 de outubro de 2013,<\/strong><\/a> a qual regulamenta a <strong>estrutura funcional da ALES,<\/strong> lista a quantidade de cargos dispon\u00edveis para cada especialidade do \u00f3rg\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Portanto, seguindo as disposi\u00e7\u00f5es da resolu\u00e7\u00e3o, o antigo cargo de T\u00e9cnico Legislativo J\u00fanior possui <strong>110 cargos dispon\u00edveis para nomea\u00e7\u00e3o.<\/strong> Ou seja, usando um pouco de matem\u00e1tica \u00e9 f\u00e1cil chegar ao seguinte resultado: 110 &#8211; 43 = 67.&nbsp;<\/p>\n\n\n\n<p>Desse modo, temos um <strong>d\u00e9ficit atual de pelo menos 67 servidores da especialidade<\/strong> na estrutura do \u00f3rg\u00e3o. Somado a isso, dos 43 servidores que est\u00e3o ativos na carreira, as \u00faltimas nomea\u00e7\u00f5es realizadas ocorreram no ano de 2002.<\/p>\n\n\n\n<p>Por isso, se voc\u00ea est\u00e1 considerando se preparar para mais uma oportunidade da \u00e1rea, fique atento, pois de acordo com o panorama levantado, a necessidade de m\u00e3o de obra para a fun\u00e7\u00e3o e a<strong> poss\u00edvel<\/strong> <strong>oferta de vagas para o cargo se mostram promissoras.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-b1b81023c7d99605d4f67996ac462964\" id=\"h-consideracoes-finais-nbsp\"><strong>Considera\u00e7\u00f5es finais&nbsp;<\/strong><\/h2>\n\n\n\n<p>Ent\u00e3o, \u00e9 isso, pessoal! Chegamos ao fim da nossa an\u00e1lise sobre <strong>o cargo de Agente de Pol\u00edcia Legislativa da ALES.<\/strong> Esperamos que tenham gostado.\u00a0<\/p>\n\n\n\n<p><strong>Voc\u00ea se interessa pela \u00e1rea?<\/strong><\/p>\n\n\n\n<p>Pois saiba que voc\u00ea tamb\u00e9m pode colocar outros certames no seu radar! Est\u00e1 em imin\u00eancia um <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/novo-concurso-camara-deputados\/\"><strong>novo concurso da C\u00e2mara dos Deputados,<\/strong><\/a> com <strong>oportunidades<\/strong> para o cargo de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/camara-dos-deputados-agente-de-policia-legislativa-pacote\/\"><strong>Policial Legislativo Federal<\/strong><\/a>, com iniciais de&nbsp; <strong>at\u00e9 R$17,4 mil.<\/strong><\/p>\n\n\n\n<p>Al\u00e9m disso, vale a pena dar uma lida em nossos artigos referentes \u00e0 tem\u00e1tica. Clique e confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-institucional-mpu\/\"><strong>Vale a pena estudar para o concurso da Pol\u00edcia Institucional do MPU?<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policial-camara-deputados\/\"><strong>Concurso Policial da C\u00e2mara dos Deputados: saiba como foi o \u00faltimo certame para o cargo de Agente de Pol\u00edcia Legislativa<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p>Se voc\u00ea quer se preparar para chegar <strong>competitivo <\/strong>em qualquer prova da \u00e1rea, invista nos cursos da<a href=\"https:\/\/www.estrategiaconcursos.com.br\/pesquisa\/?q=policial\"> <strong>\u00e1rea Policial<\/strong><\/a> do<a href=\"https:\/\/www.estrategiaconcursos.com.br\/\"> <strong>Estrat\u00e9gia Concursos<\/strong><\/a>. L\u00e1 voc\u00ea encontrar\u00e1 <strong>aulas completas e detalhadas, com os melhores professores do mercado<\/strong>.<\/p>\n\n\n\n<p>Conhe\u00e7a tamb\u00e9m o<a href=\"https:\/\/concursos.estrategia.com\/\"> <strong>Sistema de Quest\u00f5es do Estrat\u00e9gia<\/strong><\/a>. Afinal, a \u00fanica forma de <strong>consolidar o conte\u00fado <\/strong>de maneira satisfat\u00f3ria \u00e9 atrav\u00e9s da <strong>resolu\u00e7\u00e3o de quest\u00f5es.<\/strong><\/p>\n\n\n\n<p>Bons estudos a todos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Cursos e Assinaturas<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-4ee3858d78f8e73e6a059835bfd98e6f\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-7265033e1f6ded266c715abc872649b3\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\"><strong>Concursos 2024<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-1aca1c51fe870dad71059b988ff0425d\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\"><strong>Concursos 2025<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES Ol\u00e1, pessoal! Tudo bem? Hoje falaremos sobre o cargo de Agente de Pol\u00edcia Legislativa da ALES. Voc\u00ea se interessa?&nbsp; Pois ent\u00e3o saiba que este artigo est\u00e1 na medida certa para voc\u00ea! Trata-se de mais uma oportunidade para trabalhar na [&hellip;]<\/p>\n","protected":false},"author":2974,"featured_media":1483366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,2017,220188,1988,220189,220190,220186,220187],"tags":[],"tax_estado":[219963,219971],"class_list":["post-1483362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-concursos-legislativos","category-policial-agente-penitenciario","category-policia","category-policial-guarda-civis","category-policial-peritos","category-policial-oficial","category-policial-pracas","tax_estado-concursos-federais","tax_estado-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agente de Pol\u00edcia Legislativa da ALES<\/title>\n<meta name=\"description\" content=\"Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES. O que esperar do concurso?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES\" \/>\n<meta property=\"og:description\" content=\"Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES. O que esperar do concurso?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-10T17:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-29T14:27:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edmar Bezerra Araujo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edmar Bezerra Araujo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\"},\"author\":{\"name\":\"Edmar Bezerra Araujo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da\"},\"headline\":\"Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES\",\"datePublished\":\"2024-11-10T17:13:00+00:00\",\"dateModified\":\"2024-11-29T14:27:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\"},\"wordCount\":1128,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Legislativo\",\"Policial (Agente Penitenci\u00e1rio)\",\"Policial (Agente, Escriv\u00e3o e Investigador)\",\"Policial (Guardas Civis)\",\"Policial (Peritos, Papiloscopistas)\",\"Policial (PM\/BM - Oficial)\",\"Policial (PM\/BM - Pra\u00e7as)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\",\"name\":\"Agente de Pol\u00edcia Legislativa da ALES\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg\",\"datePublished\":\"2024-11-10T17:13:00+00:00\",\"dateModified\":\"2024-11-29T14:27:01+00:00\",\"description\":\"Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES. O que esperar do concurso?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg\",\"width\":1600,\"height\":887,\"caption\":\"Agente de Pol\u00edcia Legislativa da ALES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da\",\"name\":\"Edmar Bezerra Araujo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g\",\"caption\":\"Edmar Bezerra Araujo\"},\"sameAs\":[\"https:\/\/www.instagram.com\/edmarbezerraaraujo\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/edmarbezerraaraujogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agente de Pol\u00edcia Legislativa da ALES","description":"Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES. O que esperar do concurso?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES","og_description":"Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES. O que esperar do concurso?","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-11-10T17:13:00+00:00","article_modified_time":"2024-11-29T14:27:01+00:00","og_image":[{"width":1600,"height":887,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg","type":"image\/jpeg"}],"author":"Edmar Bezerra Araujo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Edmar Bezerra Araujo","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/"},"author":{"name":"Edmar Bezerra Araujo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da"},"headline":"Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES","datePublished":"2024-11-10T17:13:00+00:00","dateModified":"2024-11-29T14:27:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/"},"wordCount":1128,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg","articleSection":["Concursos P\u00fablicos","Legislativo","Policial (Agente Penitenci\u00e1rio)","Policial (Agente, Escriv\u00e3o e Investigador)","Policial (Guardas Civis)","Policial (Peritos, Papiloscopistas)","Policial (PM\/BM - Oficial)","Policial (PM\/BM - Pra\u00e7as)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/","name":"Agente de Pol\u00edcia Legislativa da ALES","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg","datePublished":"2024-11-10T17:13:00+00:00","dateModified":"2024-11-29T14:27:01+00:00","description":"Confira neste artigo os principais pontos referentes ao cargo de Agente de Pol\u00edcia Legislativa da ALES. O que esperar do concurso?","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/10\/29141309\/whatsapp-image-2024-10-29-at-11-57-49.jpeg","width":1600,"height":887,"caption":"Agente de Pol\u00edcia Legislativa da ALES"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/agente-policia-legislativa-ales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso Policial: Agente de Pol\u00edcia Legislativa da ALES"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/5516090bbe46c1c8aab9a7c5bf8595da","name":"Edmar Bezerra Araujo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ec0a15819de7eef1b7fcba85aadb329188a10da1e37eb279bb6e0f264e6b9c7?s=96&d=mm&r=g","caption":"Edmar Bezerra Araujo"},"sameAs":["https:\/\/www.instagram.com\/edmarbezerraaraujo\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/edmarbezerraaraujogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1483362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2974"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1483362"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1483362\/revisions"}],"predecessor-version":[{"id":1497245,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1483362\/revisions\/1497245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1483366"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1483362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1483362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1483362"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1483362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}