{"id":1465965,"date":"2024-10-14T08:58:00","date_gmt":"2024-10-14T11:58:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1465965"},"modified":"2024-10-07T13:29:45","modified_gmt":"2024-10-07T16:29:45","slug":"uso-ranking-pos-provas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/","title":{"rendered":"Uso de ranking p\u00f3s-provas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"928\" height=\"630\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png\" alt=\"uso de ranking p\u00f3s-provas\" class=\"wp-image-1128632\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png 928w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao-300x204.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao-768x521.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao-610x414.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao-150x102.png 150w\" sizes=\"auto, (max-width: 928px) 100vw, 928px\" \/><\/figure>\n\n\n\n<p>        Este artigo procura analisar e dar dicas sobre o uso de ranking p\u00f3s-provas de concursos p\u00fablicos.<\/p>\n\n\n\n<p>         Primeiramente, os rankings p\u00f3s-prova s\u00e3o sites nos quais os candidatos registram formul\u00e1rios com o gabarito que preencheram na prova que prestaram.\u00a0 Tais sites armazenam os gabaritos dos candidatos, e os comparam, ordenando as supostas notas.<\/p>\n\n\n\n<p>           Desse modo, o ranking faz isso antes do resultado da prova, de maneira n\u00e3o oficial. Usa estat\u00edsticas com m\u00e9todos que n\u00e3o cobrem a nota de todos os candidatos. Utiliza estat\u00edstica e proje\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vantagens-do-uso-de-rankings-pos-prova\">Vantagens do uso de rankings p\u00f3s-prova<\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ainda que o n\u00famero de candidatos do ranking seja menor que o n\u00famero de candidatos do concurso em si, geralmente, a nota de corte do ranking se aproxima da nota de corte real do concurso.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Esse fato pode diminuir a ansiedade do candidato, ao ter uma ideia do que esperar quando sair o resultado.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Quanto \u00e0s quest\u00f5es, as estat\u00edsticas do ranking podem guiar melhor o candidato ao elaborar recursos e pedir anula\u00e7\u00e3o, e acompanhar de perto quest\u00f5es importantes. A divis\u00e3o n\u00edtida por disciplina e quest\u00e3o ajuda nesse tipo de direcionamento p\u00f3s-prova.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Bancas como o <a href=\"https:\/\/www.cebraspe.org.br\/concursos\/\">Centro Brasileiro de Pesquisa em Avalia\u00e7\u00e3o e Sele\u00e7\u00e3o e de Promo\u00e7\u00e3o de Eventos (CEBRASPE)<\/a> e a <a href=\"https:\/\/conhecimento.fgv.br\/concursos\">Funda\u00e7\u00e3o Get\u00falio Vargas (FGV)<\/a>, em concursos com v\u00e1rias etapas e publica\u00e7\u00f5es de notas, costumam colocar as notas em ordem alfab\u00e9tica do nome dos candidatos, de forma n\u00e3o ordenada.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;O ranking faz essa ordena\u00e7\u00e3o, apesar de ter menos candidatos, e melhora a no\u00e7\u00e3o da pr\u00f3xima etapa do resultado.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;A longo prazo, as estat\u00edsticas do ranking podem servir de guia de estudos para as pr\u00f3ximas provas do candidato. Dar <em>feedback<\/em> do que pode ser aprimorado, e de quais disciplinas devem ser estudadas melhor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-confiabilidade-e-atualizacao-dos-rankings\">Confiabilidade e atualiza\u00e7\u00e3o dos rankings<\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00c9 aconselh\u00e1vel utilizar um ranking confi\u00e1vel.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ao confirmar o n\u00famero de inscri\u00e7\u00e3o do candidato, o ranking evita que sejam registrados gabaritos inexistentes ou alterados, tornando maior a proximidade com a realidade das notas dos candidatos.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;As estat\u00edsticas do ranking tamb\u00e9m devem eliminar notas e gabaritos <em>outliers<\/em>, que s\u00e3o evidentemente irreais, para evitar distor\u00e7\u00f5es.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;O ranking deve acompanhar as fases das provas reais dos concursos.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Geralmente, algum candidato do certame cria o ranking, antes da sa\u00edda do gabarito preliminar da prova. E ainda pode n\u00e3o ser conhecido cada tipo de gabarito, de forma a poder n\u00e3o haver a classifica\u00e7\u00e3o necess\u00e1ria no ranking por tipo de prova.<\/p>\n\n\n\n<p>            Quando o gabarito preliminar sair, a estat\u00edstica deve ser ajustada, colocando cada gabarito em seu tipo de prova, e corrigindo os gabaritos com o gabarito preliminar.<\/p>\n\n\n\n<p>            Da mesma forma, quando sa\u00edrem altera\u00e7\u00f5es, sejam em fases intermedi\u00e1rias, ou na fase final, quando sai o gabarito final oficial, o ranking deve ser ajustado. Al\u00e9m disso, a atualiza\u00e7\u00e3o ideal deve ocorrer a cada novidade oficial no concurso.<\/p>\n\n\n\n<p>            Um bom ranking, tamb\u00e9m, na sa\u00edda do resultado final do certame, compara a si mesmo com o resultado final, para medir sua acur\u00e1cia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cuidados-com-o-uso-de-rankings-pos-prova\">Cuidados com o uso de rankings p\u00f3s-prova<\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00c9 aconselh\u00e1vel nunca esquecer que o ranking cobre apenas uma fatia das notas dos candidatos, e funciona por proje\u00e7\u00e3o e estat\u00edstica. Apesar de se aproximar muitas vezes e em muitos aspectos do resultado real, existem muitas distor\u00e7\u00f5es.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Ademais, existe o risco de notas fict\u00edcias, de proje\u00e7\u00f5es que n\u00e3o condizem com o real.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;O uso do ranking \u00e9 para diminuir a ansiedade, e trabalhar com pr\u00f3ximos planejamentos com mais calma, e n\u00e3o o contr\u00e1rio.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Se o uso do ranking est\u00e1 aumentando a ansiedade de forma n\u00e3o saud\u00e1vel, \u00e9 melhor esperar o resultado oficial, pois a ansiedade pode atrapalhar a fase de elabora\u00e7\u00e3o de recursos ou a continuidade dos estudos.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Em resumo, o ranking deve ser uma ferramenta de facilita\u00e7\u00e3o e aumento do conforto na vida dos concursos p\u00fablicos, e n\u00e3o o contr\u00e1rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ranking-pos-prova-proprios\">Ranking p\u00f3s-prova pr\u00f3prios<\/h2>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Com a finalidade do uso de ranking p\u00f3s prova, n\u00e3o \u00e9 necess\u00e1rio utilizar um ranking pronto de um site.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Ademais, o Excel \u00e9 uma excelente ferramenta para elabora\u00e7\u00e3o de rankings. Ent\u00e3o, ao construir sozinho, pode ser que seja necess\u00e1rio esperar os primeiros resultados preliminares da banca, e ent\u00e3o seguir no Excel, ou outro editor de planilhas, simulando e ranqueando notas e gabaritos.<\/p>\n\n\n\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Para antecipar esse movimento, \u00e9 poss\u00edvel formar um grupo ou comunidade online de candidatos ao cargo, para colher os gabaritos. Al\u00e9m disso, o Google Forms, ou outro aplicativo de formul\u00e1rios, \u00e9 bom para colher os gabaritos.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Geralmente esses grupos se consolidam e acabam formando comiss\u00f5es para acompanhar as nomea\u00e7\u00f5es e acompanhamento do aproveitamento do cadastro reserva, se houver, no certame.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;O Estrat\u00e9gia Concursos, al\u00e9m de seus cursos e assinaturas, possui rankings de provas e simulados. Deixe sua nota.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\">Cursos e Assinaturas<\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos Abertos<\/mark><\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos 2024<\/mark><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este artigo procura analisar e dar dicas sobre o uso de ranking p\u00f3s-provas de concursos p\u00fablicos. Primeiramente, os rankings p\u00f3s-prova s\u00e3o sites nos quais os candidatos registram formul\u00e1rios com o gabarito que preencheram na prova que prestaram.\u00a0 Tais sites armazenam os gabaritos dos candidatos, e os comparam, ordenando as supostas notas. Desse modo, o ranking [&hellip;]<\/p>\n","protected":false},"author":2978,"featured_media":1128632,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219963],"class_list":["post-1465965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Uso de ranking p\u00f3s-provas<\/title>\n<meta name=\"description\" content=\"Uso de ranking p\u00f3s-provas concurso p\u00fablico nota estat\u00edstica banca quest\u00e3o CEBRASPE FGV resultado confiabilidade atualiza\u00e7\u00e3o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uso de ranking p\u00f3s-provas\" \/>\n<meta property=\"og:description\" content=\"Uso de ranking p\u00f3s-provas concurso p\u00fablico nota estat\u00edstica banca quest\u00e3o CEBRASPE FGV resultado confiabilidade atualiza\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T11:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png\" \/>\n\t<meta property=\"og:image:width\" content=\"928\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carlos Augusto Canada Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Augusto Canada Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/\"},\"author\":{\"name\":\"Carlos Augusto Canada Silva\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321\"},\"headline\":\"Uso de ranking p\u00f3s-provas\",\"datePublished\":\"2024-10-14T11:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/\"},\"wordCount\":1053,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/\",\"name\":\"Uso de ranking p\u00f3s-provas\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png\",\"datePublished\":\"2024-10-14T11:58:00+00:00\",\"description\":\"Uso de ranking p\u00f3s-provas concurso p\u00fablico nota estat\u00edstica banca quest\u00e3o CEBRASPE FGV resultado confiabilidade atualiza\u00e7\u00e3o\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png\",\"width\":928,\"height\":630,\"caption\":\"uso de ranking p\u00f3s-provas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uso de ranking p\u00f3s-provas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321\",\"name\":\"Carlos Augusto Canada Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g\",\"caption\":\"Carlos Augusto Canada Silva\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carlosaugusto-c-silvagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Uso de ranking p\u00f3s-provas","description":"Uso de ranking p\u00f3s-provas concurso p\u00fablico nota estat\u00edstica banca quest\u00e3o CEBRASPE FGV resultado confiabilidade atualiza\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/","og_locale":"pt_BR","og_type":"article","og_title":"Uso de ranking p\u00f3s-provas","og_description":"Uso de ranking p\u00f3s-provas concurso p\u00fablico nota estat\u00edstica banca quest\u00e3o CEBRASPE FGV resultado confiabilidade atualiza\u00e7\u00e3o","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-10-14T11:58:00+00:00","og_image":[{"width":928,"height":630,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png","type":"image\/png"}],"author":"Carlos Augusto Canada Silva","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Carlos Augusto Canada Silva","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/"},"author":{"name":"Carlos Augusto Canada Silva","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321"},"headline":"Uso de ranking p\u00f3s-provas","datePublished":"2024-10-14T11:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/"},"wordCount":1053,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/","name":"Uso de ranking p\u00f3s-provas","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png","datePublished":"2024-10-14T11:58:00+00:00","description":"Uso de ranking p\u00f3s-provas concurso p\u00fablico nota estat\u00edstica banca quest\u00e3o CEBRASPE FGV resultado confiabilidade atualiza\u00e7\u00e3o","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/11\/23172314\/concursos-publicos-e-nota-do-enem-relacao.png","width":928,"height":630,"caption":"uso de ranking p\u00f3s-provas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/uso-ranking-pos-provas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Uso de ranking p\u00f3s-provas"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/ba5353c5ae7c03146aa160997380a321","name":"Carlos Augusto Canada Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3678a0de9b78f31cae66e58ba52f2e5ba85775337ae7925bf91eb689694b7e7?s=96&d=mm&r=g","caption":"Carlos Augusto Canada Silva"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carlosaugusto-c-silvagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1465965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2978"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1465965"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1465965\/revisions"}],"predecessor-version":[{"id":1468556,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1465965\/revisions\/1468556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1128632"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1465965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1465965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1465965"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1465965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}