{"id":145440,"date":"2018-10-03T13:26:08","date_gmt":"2018-10-03T16:26:08","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=145440"},"modified":"2018-10-03T13:26:08","modified_gmt":"2018-10-03T16:26:08","slug":"icms-go-sugestao-de-recurso-contabilidade","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/","title":{"rendered":"ICMS GO &#8211; sugest\u00e3o de recurso &#8211; contabilidade"},"content":{"rendered":"<p>ICMS GO \u2013 Sugest\u00e3o de recurso \u2013 Contabilidade<\/p>\n<p>Abaixo, uma sugest\u00e3o de recurso para contabilidade &#8211; ICMS GO.<\/p>\n<p>74 \u2013 Uma empresa realizou, em 31\/12\/2016, um contrato de arrendamento mercantil de um equipamento industrial. O Contrato tem prazo de 8 anos, a empresa pagar\u00e1 8 parcelas anuais de R$ 837.338,81, vencendo-se a primeira parcela em 31\/12\/2017, e a taxa impl\u00edcita de juros no contrato \u00e9 de 7% ao ano. O valor presente das parcelas do contrato, na dato do in\u00edcio do arrendamento, era R$ 5.000.000,00 (igual ao valor justo do equipamento) e a empresa pretende ficar com o equipamento ap\u00f3s o t\u00e9rmino do contrato. A vida \u00fatil estimada para o equipamento \u00e9 10 anos e o valor residual esperado \u00e9 de R$ 800.000,00. Com base nestas informa\u00e7\u00f5es, a despesa total reconhecida na Demonstra\u00e7\u00e3o do Resultado de 2017, decorrente da opera\u00e7\u00e3o de arrendamento mercantil realizada foi, em reais<br \/>\nA) 750.000,00<br \/>\nB) 837.338,81<br \/>\nC) 420.000,00<br \/>\nD) 770.000,00<br \/>\nE) 350.000,00<br \/>\nO gabarito preliminar foi a letra D \u2013 770.000<br \/>\nDe acordo com o Pronunciamento T\u00e9cnico CPC 08 (R1) \u2013 Opera\u00e7\u00f5es de Arrendamento Mercantil, vigente at\u00e9 31\/12\/218:<br \/>\n27. Um arrendamento mercantil financeiro d\u00e1 origem a uma despesa de deprecia\u00e7\u00e3o (amortiza\u00e7\u00e3o) relativa a ativos depreci\u00e1veis (amortiz\u00e1veis), assim como uma despesa financeira para cada per\u00edodo cont\u00e1bil. A pol\u00edtica de deprecia\u00e7\u00e3o (amortiza\u00e7\u00e3o) para os ativos arrendados depreci\u00e1veis (amortiz\u00e1veis) deve ser consistente com a pol\u00edtica dos demais ativos depreci\u00e1veis (amortiz\u00e1veis) sobre os quais se detenha a propriedade e a deprecia\u00e7\u00e3o reconhecida deve ser calculada de acordo com o Pronunciamento T\u00e9cnico CPC 27 \u2013 Ativo Imobilizado, ou para o caso de amortiza\u00e7\u00e3o, de acordo com o Pronunciamento T\u00e9cnico CPC 10 CPC_06 (R1) 04 \u2013 Ativo Intang\u00edvel. (CPC 08)<\/p>\n<p>Efetuando os c\u00e1lculos, encontramos o valor de deprecia\u00e7\u00e3o anual de $ 420.000 e o valor de juros de $ 350.000, totalizando $ 770.000.<br \/>\nOcorre que a quest\u00e3o menciona que se trata do arrendamento mercantil de um equipamento industrial.<br \/>\nA deprecia\u00e7\u00e3o de um equipamento industrial \u00e9 inclu\u00edda, inicialmente, no custo do produto. Ap\u00f3s a venda, o custo do produto (incluindo a deprecia\u00e7\u00e3o) entra na Demonstra\u00e7\u00e3o do Resultado como \u201cCusto dos produtos vendidos\u201d, que tecnicamente \u00e9 uma despesa, mas possui outra denomina\u00e7\u00e3o.<br \/>\nQuando a quest\u00e3o cobra \u201ca despesa total reconhecida na Demonstra\u00e7\u00e3o do Resultado de 2017, decorrente da opera\u00e7\u00e3o de arrendamento mercantil realizada\u201d, n\u00e3o fica claro em qual momento devemos considerar a deprecia\u00e7\u00e3o.<br \/>\nSe for no momento inicial, em que ocorre a deprecia\u00e7\u00e3o, n\u00e3o h\u00e1 despesa, eis que a deprecia\u00e7\u00e3o \u00e9 inclu\u00edda no custo do produto. Nessa interpreta\u00e7\u00e3o, a despesa decorrente do arrendamento inclui apenas o valor dos juros de $350.000, e assim o gabarito seria a letra E.<br \/>\nSe considerarmos o efeito ap\u00f3s a venda dos produtos (e considerando tamb\u00e9m que toda a produ\u00e7\u00e3o do ano foi vendida, n\u00e3o restando nada em estoque), ent\u00e3o o efeito na demonstra\u00e7\u00e3o do resultado inclui a deprecia\u00e7\u00e3o. Nesse caso, o gabarito seria a letra D &#8211; $ 770.000.<br \/>\nN\u00e3o haveria problema se a quest\u00e3o mencionasse, por exemplo, que trata-se do arrendamento de um computador para controlar a administra\u00e7\u00e3o da empresa. Nesse caso, a deprecia\u00e7\u00e3o entra como despesa na Demonstra\u00e7\u00e3o do Resultado.<br \/>\nComo a quest\u00e3o menciona um equipamento industrial e portanto h\u00e1 dois entendimentos razo\u00e1veis e com respostas diferentes, solicitamos a ANULA\u00c7\u00c2O da quest\u00e3o.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;xxx&#8212;&#8212;&#8212;<br \/>\nPrezados, mudem, as bancas n\u00e3o gostam de copia e cola.<\/p>\n<p>Boa sorte a todos.<\/p>\n<p>Luciano Rosa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ICMS GO \u2013 Sugest\u00e3o de recurso \u2013 Contabilidade Abaixo, uma sugest\u00e3o de recurso para contabilidade &#8211; ICMS GO. 74 \u2013 Uma empresa realizou, em 31\/12\/2016, um contrato de arrendamento mercantil de um equipamento industrial. O Contrato tem prazo de 8 anos, a empresa pagar\u00e1 8 parcelas anuais de R$ 837.338,81, vencendo-se a primeira parcela em [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-145440","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ICMS GO - sugest\u00e3o de recurso - contabilidade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ICMS GO - sugest\u00e3o de recurso - contabilidade\" \/>\n<meta property=\"og:description\" content=\"ICMS GO \u2013 Sugest\u00e3o de recurso \u2013 Contabilidade Abaixo, uma sugest\u00e3o de recurso para contabilidade &#8211; ICMS GO. 74 \u2013 Uma empresa realizou, em 31\/12\/2016, um contrato de arrendamento mercantil de um equipamento industrial. O Contrato tem prazo de 8 anos, a empresa pagar\u00e1 8 parcelas anuais de R$ 837.338,81, vencendo-se a primeira parcela em [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-03T16:26:08+00:00\" \/>\n<meta name=\"author\" content=\"Luciano Rosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luciano Rosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/\"},\"author\":{\"name\":\"Luciano Rosa\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/523996854b82477bef38e2ab59b10b96\"},\"headline\":\"ICMS GO &#8211; sugest\u00e3o de recurso &#8211; contabilidade\",\"datePublished\":\"2018-10-03T16:26:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/\"},\"wordCount\":582,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/\",\"name\":\"ICMS GO - sugest\u00e3o de recurso - contabilidade\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2018-10-03T16:26:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ICMS GO &#8211; sugest\u00e3o de recurso &#8211; contabilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/523996854b82477bef38e2ab59b10b96\",\"name\":\"Luciano Rosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/83a121de5c60d4c6fd842714d97bf0c8077c4e40935f2d96950c4a5859cf82c4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83a121de5c60d4c6fd842714d97bf0c8077c4e40935f2d96950c4a5859cf82c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/83a121de5c60d4c6fd842714d97bf0c8077c4e40935f2d96950c4a5859cf82c4?s=96&d=mm&r=g\",\"caption\":\"Luciano Rosa\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/lucianorosaestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ICMS GO - sugest\u00e3o de recurso - contabilidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"ICMS GO - sugest\u00e3o de recurso - contabilidade","og_description":"ICMS GO \u2013 Sugest\u00e3o de recurso \u2013 Contabilidade Abaixo, uma sugest\u00e3o de recurso para contabilidade &#8211; ICMS GO. 74 \u2013 Uma empresa realizou, em 31\/12\/2016, um contrato de arrendamento mercantil de um equipamento industrial. O Contrato tem prazo de 8 anos, a empresa pagar\u00e1 8 parcelas anuais de R$ 837.338,81, vencendo-se a primeira parcela em [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2018-10-03T16:26:08+00:00","author":"Luciano Rosa","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Luciano Rosa","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/"},"author":{"name":"Luciano Rosa","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/523996854b82477bef38e2ab59b10b96"},"headline":"ICMS GO &#8211; sugest\u00e3o de recurso &#8211; contabilidade","datePublished":"2018-10-03T16:26:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/"},"wordCount":582,"commentCount":1,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/","name":"ICMS GO - sugest\u00e3o de recurso - contabilidade","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-10-03T16:26:08+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/icms-go-sugestao-de-recurso-contabilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"ICMS GO &#8211; sugest\u00e3o de recurso &#8211; contabilidade"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/523996854b82477bef38e2ab59b10b96","name":"Luciano Rosa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/83a121de5c60d4c6fd842714d97bf0c8077c4e40935f2d96950c4a5859cf82c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/83a121de5c60d4c6fd842714d97bf0c8077c4e40935f2d96950c4a5859cf82c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83a121de5c60d4c6fd842714d97bf0c8077c4e40935f2d96950c4a5859cf82c4?s=96&d=mm&r=g","caption":"Luciano Rosa"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/lucianorosaestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/145440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=145440"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/145440\/revisions"}],"predecessor-version":[{"id":145444,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/145440\/revisions\/145444"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=145440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=145440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=145440"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=145440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}