{"id":1449280,"date":"2024-09-10T08:22:00","date_gmt":"2024-09-10T11:22:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1449280"},"modified":"2024-09-01T19:20:42","modified_gmt":"2024-09-01T22:20:42","slug":"qual-diferenca-entre-transacao-parcelamento","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/","title":{"rendered":"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"430\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/22200556\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1.png\" alt=\"parcelamento e transa\u00e7\u00e3o\" class=\"wp-image-1450029\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/22200556\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1.png 750w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/22200556\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-300x172.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/22200556\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-610x350.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/22200556\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-150x86.png 150w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>Ol\u00e1, pessoal! O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento, no direito tribut\u00e1rio.<\/p>\n\n\n\n<p>Vamos passar basicamente pelos seguintes t\u00f3picos:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aspectos gerais sobre a transa\u00e7\u00e3o no C\u00f3digo Tribut\u00e1rio Nacional;<\/li>\n\n\n\n<li>Aspectos gerais sobre o parcelamento no C\u00f3digo Tribut\u00e1rio Nacional;<\/li>\n\n\n\n<li>Diferen\u00e7as entre os institutos;&nbsp;e<\/li>\n\n\n\n<li>Cobran\u00e7a em provas.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-aspectos-gerais-sobre-a-transacao\">Aspectos gerais sobre a transa\u00e7\u00e3o<\/h2>\n\n\n\n<p>A transa\u00e7\u00e3o \u00e9 um neg\u00f3cio jur\u00eddico em que as partes, mediante concess\u00f5es m\u00fatuas, extinguem obriga\u00e7\u00f5es, resolvendo lit\u00edgios. Em direito tribut\u00e1rio, a lei autoriza a transa\u00e7\u00e3o.<\/p>\n\n\n\n<p>A lei que autoriza a transa\u00e7\u00e3o imp\u00f5e os limites da negocia\u00e7\u00e3o, obedecendo ao princ\u00edpio da indisponibilidade do patrim\u00f4nio p\u00fablico. Logo, o particular pode negociar com a Administra\u00e7\u00e3o Tribut\u00e1ria, por\u00e9m sem ampla liberdade, observando os limites legais impostos.<\/p>\n\n\n\n<p>A transa\u00e7\u00e3o \u00e9 modalidade de extin\u00e7\u00e3o do cr\u00e9dito tribut\u00e1rio e somente se exaure ap\u00f3s cumpridos os requisitos acordados. O instituto tem previs\u00e3o expressa no C\u00f3digo Tribut\u00e1rio Nacional.<\/p>\n\n\n\n<div class=\"wp-block-group has-vivid-green-cyan-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\"><strong>Veja a Lei!<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-style-default has-vivid-red-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-elements-67c03d28791b107681ebc93750b7dae0 is-layout-flow wp-block-quote-is-layout-flow\" style=\"font-style:normal;font-weight:700\">\n<p>C\u00f3digo Tribut\u00e1rio Nacional<\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">Art. 171. A lei pode facultar, nas condi\u00e7\u00f5es que estabele\u00e7a, aos sujeitos ativo e passivo da obriga\u00e7\u00e3o tribut\u00e1ria celebrar transa\u00e7\u00e3o que, mediante concess\u00f5es m\u00fatuas, importe em determina\u00e7\u00e3o de lit\u00edgio e consequente extin\u00e7\u00e3o de cr\u00e9dito tribut\u00e1rio.<\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">Par\u00e1grafo \u00fanico. A lei indicar\u00e1 a autoridade competente para autorizar a transa\u00e7\u00e3o em cada caso.<\/p>\n<\/blockquote>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-aspectos-gerais-sobre-o-parcelamento\">Aspectos gerais sobre o parcelamento<\/h2>\n\n\n\n<p>O parcelamento consiste em medida de recupera\u00e7\u00e3o de cr\u00e9ditos tribut\u00e1rios inadimplidos, pela Administra\u00e7\u00e3o Tribut\u00e1ria. Nesse sentido, a Administra\u00e7\u00e3o Tribut\u00e1ria, por meio de lei espec\u00edfica, estabelecer\u00e1 regras e condi\u00e7\u00f5es para concess\u00e3o de parcelamentos com vistas a trazer de volta a regularidade fiscal, contribuintes inadimplentes.<\/p>\n\n\n\n<p>A lei espec\u00edfica do parcelamento, via de regra, n\u00e3o exclui a incid\u00eancia de multa e juros, podendo, no entanto, dispor em sentido contr\u00e1rio. Frequentemente, no \u00e2mbito da administra\u00e7\u00e3o tribut\u00e1ria federal, chama-se este tipo de parcelamento que concede redu\u00e7\u00f5es de \u201cparcelamento especial\u201d.<\/p>\n\n\n\n<p>As regras gerais de parcelamento est\u00e3o previstas no C\u00f3digo Tribut\u00e1rio Nacional e est\u00e3o enquadradas no rol de causas suspensivas da exigibilidade do cr\u00e9dito tribut\u00e1rio.<\/p>\n\n\n\n<div class=\"wp-block-group has-vivid-green-cyan-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\">Veja a Lei!<\/a><\/div>\n<\/div>\n\n\n\n<blockquote class=\"wp-block-quote has-vivid-red-color has-vivid-green-cyan-background-color has-text-color has-background has-link-color wp-elements-12ae4dc71aba80dae6902ae23d7a3311 is-layout-flow wp-block-quote-is-layout-flow\">\n<p style=\"font-style:normal;font-weight:700\">C\u00f3digo Tribut\u00e1rio Nacional<\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">Art. 155-A. O parcelamento ser\u00e1 concedido na forma e condi\u00e7\u00e3o estabelecidas em lei espec\u00edfica.&nbsp;(Inclu\u00eddo pela Lcp n\u00ba 104, de 2001<\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">\u00a7 1<sup><u>o<\/u><\/sup>&nbsp;Salvo disposi\u00e7\u00e3o de lei em contr\u00e1rio, o parcelamento do cr\u00e9dito tribut\u00e1rio n\u00e3o exclui a incid\u00eancia de juros e multas.&nbsp;<\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:400\">\u00a7 2<sup><u>o<\/u><\/sup>&nbsp;Aplicam-se, subsidiariamente, ao parcelamento as disposi\u00e7\u00f5es desta Lei, relativas \u00e0 morat\u00f3ria.&nbsp;<\/p>\n<\/blockquote>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-parcelamento-de-recuperacao-judicial\"><strong>Parcelamento de Recupera\u00e7\u00e3o Judicial<\/strong><\/h2>\n\n\n\n<p>A Lei Complementar n\u00ba 118, de 2005, alterou o C\u00f3digo Tribut\u00e1rio Nacional, incluindo condi\u00e7\u00f5es especiais para parcelamento de cr\u00e9ditos tribut\u00e1rios do devedor em recupera\u00e7\u00e3o judicial.<\/p>\n\n\n\n<p>Nesse sentido. entendeu o legislador que deve existir uma segunda lei espec\u00edfica (lembrem que cada ente dever\u00e1 editar \u201c<em>lei geral de parcelamento\u201d)<\/em> com condi\u00e7\u00f5es mais vantajosas aos devedores em recupera\u00e7\u00e3o judicial. O CTN n\u00e3o estabeleceu quais seriam as vantagens, deixando a cargo da lei espec\u00edfica de cada ente.<\/p>\n\n\n\n<p><strong>Aten\u00e7\u00e3o, concurseiro!<\/strong> Sempre que a lei espec\u00edfica de parcelamento do devedor em recupera\u00e7\u00e3o judicial n\u00e3o for editada pelo ente, o devedor tem o direito de utilizar a lei geral de parcelamento do ente. Contudo, o prazo do parcelamento n\u00e3o poder\u00e1 ser inferior a <strong>lei especifica federal <\/strong>de parcelamento relativos a devedores em recupera\u00e7\u00e3o judicial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-regras-de-moratoria\"><strong>Regras de Morat\u00f3ria<\/strong><\/h2>\n\n\n\n<p>O CTN prev\u00ea ainda que as regras de morat\u00f3ria se aplicam subsidiariamente ao parcelamento. A FGV j\u00e1 cobrou isto em prova recente para Auditor-Fiscal da Receita Federal do Brasil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-sigilo-fiscal\"><strong>Sigilo Fiscal<\/strong><\/h2>\n\n\n\n<p>Por fim, outro ponto cobrado em prova \u00e9 sobre o sigilo fiscal. Em regra, as informa\u00e7\u00f5es tribut\u00e1rias est\u00e3o sujeitas ao sigilo. J\u00e1 as informa\u00e7\u00f5es referentes ao parcelamento s\u00e3o exce\u00e7\u00e3o a regra e devem ser divulgadas.<\/p>\n\n\n\n<p>No \u00e2mbito da Administra\u00e7\u00e3o Tribut\u00e1ria Federal, a Lei n\u00ba 10.522, de 2002, estabelece que Receita Federal e Procuradoria da Fazenda Nacional devem informar em seus s\u00edtios eletr\u00f4nicos, mensalmente, informa\u00e7\u00f5es sobre os parcelamentos por elas administrados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-diferencas-entre-os-institutos-da-transacao-e-do-parcelamento\">Diferen\u00e7as entre os institutos da transa\u00e7\u00e3o e do parcelamento<\/h2>\n\n\n\n<p>O concurseiro deve entender que a principal diferen\u00e7a entre a transa\u00e7\u00e3o e o parcelamento, no direito tribut\u00e1rio, \u00e9 que aquele instituto \u00e9 causa de <strong>extin\u00e7\u00e3o do cr\u00e9dito tribut\u00e1rio<\/strong> e este \u00e9 causa de <strong>suspens\u00e3o da exigiblidade do cr\u00e9dito tribut\u00e1rio<\/strong>. As bancas ir\u00e3o buscar confundir o candidato.<\/p>\n\n\n\n<p>Existem outras diferen\u00e7as:<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-condicoes\"><strong>Condi\u00e7\u00f5es<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O parcelamento deve ser concedido ao contribuinte em caso de cumprimento das condi\u00e7\u00f5es previstas em lei especifica.<\/li>\n\n\n\n<li>Em contrapartida, a transa\u00e7\u00e3o \u00e9 uma negocia\u00e7\u00e3o, em que ocorrem concess\u00f5es m\u00fatuas dentro de par\u00e2metros estabelecidos pela lei.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Recupera\u00e7\u00e3o Judicial<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os entes devem editar lei espec\u00edfica para parcelamentos relativos \u00e0 contribuintes em recupera\u00e7\u00e3o judicial.<\/li>\n\n\n\n<li>Por outro lado, na transa\u00e7\u00e3o, s\u00f3 h\u00e1 exig\u00eancia para edi\u00e7\u00e3o de lei especifica autorizativa. Logo, n\u00e3o existem regras para devedores em recupera\u00e7\u00e3o judicial.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Objetivos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A transa\u00e7\u00e3o busca <strong>resolver lit\u00edgios<\/strong>, sejam administrativos ou judicias. Por meio de concess\u00f5es m\u00fatuas, contribuinte e Administra\u00e7\u00e3o tribut\u00e1ria resolver\u00e3o um conflito.<\/li>\n\n\n\n<li>J\u00e1 o parcelamento \u00e9 um medida de politica fiscal que busca criar condi\u00e7\u00f5es para que contribuintes inadimplentes<strong> retornem a regularidade fiscal.<\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cobranca-em-provas\">Cobran\u00e7a em provas<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote has-black-color has-pale-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-252499eca2cd9c3720785dafc66f1104 is-layout-flow wp-block-quote-is-layout-flow\">\n<p style=\"font-style:normal;font-weight:700\"><em>FGV&nbsp;&#8211;&nbsp;2023 &#8211; Auditor Fiscal da Receita Federal do Brasil\/Geral<\/em><\/p>\n\n\n\n<p><em>Acerca do instituto do parcelamento tribut\u00e1rio, \u00e0 luz do C\u00f3digo Tribut\u00e1rio Nacional (CTN), assinale a afirmativa correta.<\/em><\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:800\">A) <em>Lei espec\u00edfica pode excluir a incid\u00eancia de juros em caso de parcelamento do cr\u00e9dito tribut\u00e1rio.<\/em><\/p>\n\n\n\n<p><em>B) Ao parcelamento n\u00e3o se aplicam, subsidiariamente, as disposi\u00e7\u00f5es do C\u00f3digo Tribut\u00e1rio Nacional (CTN) relativas \u00e0 morat\u00f3ria.<\/em><\/p>\n\n\n\n<p><em>C) A inexist\u00eancia de lei espec\u00edfica local dispondo sobre as condi\u00e7\u00f5es de parcelamento dos cr\u00e9ditos tribut\u00e1rios do devedor em recupera\u00e7\u00e3o judicial importa aplica\u00e7\u00e3o da lei geral federal de parcelamento.<\/em><\/p>\n\n\n\n<p><em>D) O parcelamento \u00e9 modalidade de exclus\u00e3o do cr\u00e9dito tribut\u00e1rio.<\/em><\/p>\n\n\n\n<p><em>E) O parcelamento \u00e9 modalidade de extin\u00e7\u00e3o do cr\u00e9dito tribut\u00e1rio.<\/em><\/p>\n\n\n\n<p><\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group has-black-color has-pale-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-a2bb9327fc26668225c00f4c0076afdf has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p style=\"font-style:normal;font-weight:700\"><em>FGV &#8211; 2021 &#8211; SEFAZ-ES &#8211; Auditor Fiscal da Receita Estadual &#8211; Manh\u00e3<\/em><\/p>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-fe9cc265 wp-block-group-is-layout-flex\">\n<p><em>Lei ordin\u00e1ria do Estado X, visando a uma maior transpar\u00eancia na Administra\u00e7\u00e3o Tribut\u00e1ria, determinou que fossem divulgadas, publicamente, no s\u00edtio eletr\u00f4nico da Secretaria Estadual de Fazenda, as seguintes informa\u00e7\u00f5es referentes aos contribuintes:<\/em><\/p>\n\n\n\n<p>I. <em>representa\u00e7\u00f5es fiscais para fins penais;<\/em><\/p>\n\n\n\n<p>II. <em>inscri\u00e7\u00f5es na D\u00edvida Ativa da Fazenda P\u00fablica;<\/em><\/p>\n\n\n\n<p>III. <em>parcelamento ou morat\u00f3ria.<\/em><\/p>\n\n\n\n<p><em>Diante desse cen\u00e1rio e \u00e0 luz do C\u00f3digo Tribut\u00e1rio Nacional, assinale a afirmativa correta.<\/em><\/p>\n<\/div>\n\n\n\n<p><em>A)&nbsp;A divulga\u00e7\u00e3o de representa\u00e7\u00f5es fiscais para fins penais viola o sigilo fiscal.<\/em><\/p>\n<\/div>\n\n\n\n<p><em>B)&nbsp;A divulga\u00e7\u00e3o de inscri\u00e7\u00f5es na D\u00edvida Ativa da Fazenda P\u00fablica viola o sigilo fiscal.<\/em><\/p>\n\n\n\n<p><em>C)&nbsp;A divulga\u00e7\u00e3o de parcelamento ou morat\u00f3ria viola o sigilo fiscal.<\/em><\/p>\n\n\n\n<p><em>D)&nbsp;A divulga\u00e7\u00e3o de representa\u00e7\u00f5es fiscais para fins penais e de parcelamento ou morat\u00f3ria viola o sigilo fiscal.<\/em><\/p>\n\n\n\n<p style=\"font-style:normal;font-weight:800\"><em>E)&nbsp;As informa\u00e7\u00f5es divulgadas n\u00e3o violam o sigilo fiscal.<\/em><\/p>\n<\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\" style=\"font-style:normal;font-weight:400\">\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es Finais<\/h2>\n<cite>Chegamos ao final do nosso breve artigo sobre as diferen\u00e7as entre transa\u00e7\u00e3o e parcelamento, e esperamos que seja muito \u00fatil para a sua prepara\u00e7\u00e3o e aprova\u00e7\u00e3o.&nbsp;<br \/><br \/>\u00c9 importante que o concurseiro fa\u00e7a a leitura dos PDF\u2019s e a revis\u00e3o frequente dos conte\u00fados, para que assim os seus estudos fiquem cada vez mais avan\u00e7ados.&nbsp;&nbsp;Uma boa dica para consolidar os estudos \u00e9 acessar o <a href=\"https:\/\/concursos.estrategia.com\/\">Sistema de Quest\u00f5es<\/a> e treinar.<br \/><br \/>Um grande abra\u00e7o e at\u00e9 mais!&nbsp;<br \/><br \/>Igor Arrais de S\u00e1<br \/><br \/><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong>&nbsp;<br \/><br \/><strong>Confira nossos artigos!<\/strong>&nbsp;<br \/><br \/><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\">Concursos abertos<\/a><br \/><br \/><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\">Concursos 2024<\/a><\/cite><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p> O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento, no direito tribut\u00e1rio.<\/p>\n","protected":false},"author":2960,"featured_media":1453718,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1983,220182,220183],"tags":[40,861,484],"tax_estado":[219963],"class_list":["post-1449280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-estadual","category-fiscal-federal","category-fiscal-municipal","tag-concurso","tag-dicas-de-estudo","tag-receita-federal","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?<\/title>\n<meta name=\"description\" content=\"O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?\" \/>\n<meta property=\"og:description\" content=\"O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T11:22:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Igor Arrais de Sa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Igor Arrais de Sa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/\"},\"author\":{\"name\":\"Igor Arrais de Sa\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d484208510b0a8a5f2e0f5f872112dbd\"},\"headline\":\"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?\",\"datePublished\":\"2024-09-10T11:22:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/\"},\"wordCount\":1371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png\",\"keywords\":[\"Concurso\",\"dicas de estudo\",\"Receita Federal\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Estadual (ICMS)\",\"Fiscal - Federal (RFB e AFT)\",\"Fiscal - Municipal (ISS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/\",\"name\":\"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png\",\"datePublished\":\"2024-09-10T11:22:00+00:00\",\"description\":\"O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento..\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png\",\"width\":750,\"height\":430,\"caption\":\"Parcelamento e transa\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d484208510b0a8a5f2e0f5f872112dbd\",\"name\":\"Igor Arrais de Sa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/01cbf140e4eda4918f27c914be5c09855dd63798cd9a1990e819ed58e0401649?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/01cbf140e4eda4918f27c914be5c09855dd63798cd9a1990e819ed58e0401649?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/01cbf140e4eda4918f27c914be5c09855dd63798cd9a1990e819ed58e0401649?s=96&d=mm&r=g\",\"caption\":\"Igor Arrais de Sa\"},\"sameAs\":[\"https:\/\/www.instagram.com\/igor.arrais.sa\/\",\"https:\/\/www.linkedin.com\/in\/igor-arrais-sa\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/igordesahotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?","description":"O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?","og_description":"O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento..","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-09-10T11:22:00+00:00","og_image":[{"width":750,"height":430,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png","type":"image\/png"}],"author":"Igor Arrais de Sa","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Igor Arrais de Sa","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/"},"author":{"name":"Igor Arrais de Sa","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d484208510b0a8a5f2e0f5f872112dbd"},"headline":"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?","datePublished":"2024-09-10T11:22:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/"},"wordCount":1371,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png","keywords":["Concurso","dicas de estudo","Receita Federal"],"articleSection":["Concursos P\u00fablicos","Fiscal - Estadual (ICMS)","Fiscal - Federal (RFB e AFT)","Fiscal - Municipal (ISS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/","name":"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png","datePublished":"2024-09-10T11:22:00+00:00","description":"O presente artigo aborda um assunto que tem tudo para cair em concursos da \u00e1rea fiscal: qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento..","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/09\/30131707\/mudanca-na-transacao-tributaria-beneficia-contribuintes-01-1-750x430-1-1.png","width":750,"height":430,"caption":"Parcelamento e transa\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/qual-diferenca-entre-transacao-parcelamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Qual a diferen\u00e7a entre transa\u00e7\u00e3o e parcelamento?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/d484208510b0a8a5f2e0f5f872112dbd","name":"Igor Arrais de Sa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/01cbf140e4eda4918f27c914be5c09855dd63798cd9a1990e819ed58e0401649?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01cbf140e4eda4918f27c914be5c09855dd63798cd9a1990e819ed58e0401649?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01cbf140e4eda4918f27c914be5c09855dd63798cd9a1990e819ed58e0401649?s=96&d=mm&r=g","caption":"Igor Arrais de Sa"},"sameAs":["https:\/\/www.instagram.com\/igor.arrais.sa\/","https:\/\/www.linkedin.com\/in\/igor-arrais-sa\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/igordesahotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1449280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2960"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1449280"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1449280\/revisions"}],"predecessor-version":[{"id":1453719,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1449280\/revisions\/1453719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1453718"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1449280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1449280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1449280"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1449280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}