{"id":144624,"date":"2018-09-30T17:56:14","date_gmt":"2018-09-30T20:56:14","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=144624"},"modified":"2022-10-26T15:02:42","modified_gmt":"2022-10-26T18:02:42","slug":"gabarito-extraoficial-sefaz-go-direito-tributario","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/","title":{"rendered":"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio"},"content":{"rendered":"<p style=\"text-align: justify;\">Ol\u00e1, meus amigos, tudo bem?<\/p>\n<p style=\"text-align: justify;\">Meu nome \u00e9 F\u00e1bio Dutra, sou professor de Direito Tribut\u00e1rio do Estrat\u00e9gia Concursos e Auditor-Fiscal da RFB.<\/p>\n<p style=\"text-align: justify;\">Estou aqui com voc\u00eas, pois neste final de semana, foi aplicada a prova do concurso SEFAZ-GO (Auditor-Fiscal), realizada pela banca Funda\u00e7\u00e3o Carlos Chagas (FCC), e, como de costume, j\u00e1 providenciamos o coment\u00e1rio da prova e os gabaritos extraoficiais.<\/p>\n<p style=\"text-align: justify;\">Antes de iniciarmos a resolu\u00e7\u00e3o, convido voc\u00ea a me seguir l\u00e1 no Instagram, para acompanhar os pr\u00f3ximos concursos da \u00e1rea fiscal bem como os projetos gratuitos de quest\u00f5es comentadas: <a href=\"http:\/\/www.instagram.com\/proffabiodutra\" target=\"_blank\" rel=\"noopener\"><strong>@proffabiodutra<\/strong><\/a><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 107 \u2013 J.J. Silva, Auditor-Fiscal da Receita Estadual, autoridade competente para a pr\u00e1tica de todos os atos de fiscaliza\u00e7\u00e3o de tributos estaduais nas empresas do Estado de Goi\u00e1s, no curso de procedimento fiscal que est\u00e1 realizando na empresa \u201cCachoeira dos Anjos e Arcanjos Ltda.\u201d (empresa hipot\u00e9tica), localizada em Itumbiara\/GO, depois de examinar documentos e livros fiscais e cont\u00e1beis do estabelecimento, chegou \u00e0 conclus\u00e3o, fundamentadamente, de que seria indispens\u00e1vel o exame de informa\u00e7\u00f5es banc\u00e1rias e financeiras da referida empresa. Com base nas informa\u00e7\u00f5es acima e no disposto na Lei Complementar 105\/01, o referido Auditor-Fiscal:<\/p>\n<p style=\"text-align: justify;\">a) n\u00e3o poder\u00e1 examinar documentos, livros e registros de institui\u00e7\u00f5es financeiras, inclusive os referentes a contas de dep\u00f3sitos ou aplica\u00e7\u00f5es financeiras, sem que haja decis\u00e3o judicial autorizando a quebra do sigilo fiscal do contribuinte.<\/p>\n<p style=\"text-align: justify;\">B) nada poder\u00e1 fazer, se n\u00e3o comprovar a ocorr\u00eancia de crime contra a Administra\u00e7\u00e3o p\u00fablica, contra a ordem tribut\u00e1ria e contra a previd\u00eancia social, ou ainda, de lavagem de dinheiro ou de oculta\u00e7\u00e3o de bens, direitos e valores.<\/p>\n<p style=\"text-align: justify;\">c) dever\u00e1 solicitar a instaura\u00e7\u00e3o de processo administrativo espec\u00edfico para, com base nele, solicitar o exame dos livros e registros das institui\u00e7\u00f5es financeiras, vedado o exame \u00e0s contas de dep\u00f3sitos e \u00e0s aplica\u00e7\u00f5es financeiras do contribuinte.<\/p>\n<p style=\"text-align: justify;\">d) poder\u00e1 examinar documentos, livros e registros de institui\u00e7\u00f5es financeiras, inclusive os referentes a contas de dep\u00f3sitos e aplica\u00e7\u00f5es financeiras, porque h\u00e1 procedimento fiscal em curso na empresa.<\/p>\n<p style=\"text-align: justify;\">e) dever\u00e1 solicitar \u00e0 Delegacia da Receita Federal a instaura\u00e7\u00e3o de processo administrativo especifico para obten\u00e7\u00e3o de informa\u00e7\u00f5es de que necessita, e o posterior repasse dessas informa\u00e7\u00f5es ao fisco estadual goiano, mediante assinatura de conv\u00eanio de que trata o art. 199 do CTN.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio: De acordo com o art. 6\u00ba, da LC 105\/01, as autoridades e os agentes fiscais tribut\u00e1rios da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios somente poder\u00e3o examinar documentos, livros e registros de institui\u00e7\u00f5es financeiras, inclusive os referentes a contas de dep\u00f3sitos e aplica\u00e7\u00f5es financeiras, quando houver processo administrativo instaurado ou procedimento fiscal em curso e tais exames sejam considerados indispens\u00e1veis pela autoridade administrativa competente. O STF j\u00e1 considerou tal dispositivo constitucional, por haver transfer\u00eancia do sigilo banc\u00e1rio para o sigilo fiscal.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra D<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 108 \u2013 M.M. Alves, Auditor-Fiscal da Receita Estadual, autoridade competente para a pr\u00e1tica de todos os atos de fiscaliza\u00e7\u00e3o de tributos estaduais nas empresas do Estado de Goi\u00e1s, estava legalmente na posse de informa\u00e7\u00f5es sigilosas, protegidas pela Lei Complementarn\u00b0105\/01, e relacionadas com contribuinte goiano que estava sendo fiscalizado por ele. Contrariamente ao que determina a referida lei, M.M. Alves utilizou e viabilizou a outras pessoas a utiliza\u00e7\u00e3o indevida dessas informa\u00e7\u00f5es. Em raz\u00e3o disso,<\/p>\n<p style=\"text-align: justify;\">a) Esse Auditor-Fiscal n\u00e3o responder\u00e1 pelos danos decorrentes de seus atos, se ficar comprovado que ele agiu de acordo com orienta\u00e7\u00e3o oficial.<\/p>\n<p style=\"text-align: justify;\">b) a entidade p\u00fablica n\u00e3o ser\u00e1 responsabilizada por danos causados, ainda que o servidor tenha agido de acordo com orienta\u00e7\u00e3o oficial sua, se ficar comprovado que o referido Auditor-Fiscal, tendo conhecimento da ilicitude de seu comportamente, mesmo assim agiu com dolo, fraude ou simula\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">c) esse Auditor-Fiscal n\u00e3o responder\u00e1 pelos danos decorrentes de seus atos, se n\u00e3o ficar comprovado que ele agiu com dolo, fraude ou simula\u00e7\u00e3o, mas a entidade p\u00fablica ser\u00e1 responsabilizada objetivamente.<\/p>\n<p style=\"text-align: justify;\">d) esse Auditor-Fiscal responder\u00e1 subsidiariamente pelos danos decorrentes de seus atos qdesde que n\u00e3o seja poss\u00edvel responsabilizar, em primeiro lugar, objetivamente, a entidade p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">e) esse Auditor-Fiscal responder\u00e1 pessoal e diretamente pelos danos decorrentes, sem preju\u00edzo da responsabilidade objetiva da entidade p\u00fablica, quando comprovado que o servidor agiu de acordo com orienta\u00e7\u00e3o oficial.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio: O art. 11, da LC 105\/01 estabelece que o servidor p\u00fablico que utilizar ou viabilizar a utiliza\u00e7\u00e3o de qualquer informa\u00e7\u00e3o obtida em decorr\u00eancia da quebra de sigilo de que trata esta Lei Complementar responde pessoal e diretamente pelos danos decorrentes, sem preju\u00edzo da responsabilidade objetiva da entidade p\u00fablica, quando comprovado que o servidor agiu de acordo com orienta\u00e7\u00e3o oficial. Assim sendo, a resposta \u00e9 muito clara: Letra E.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra E<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 109 \u2013 O supermercado \u201cSol Brasil\u201d (empresa fict\u00edcia) adquiriu as seguintes mercadorias: 100 latas de goiabada, 100 kg de farinha de tributo, 1.000 barras de sab\u00e3o, 1.000 tubos de pasta de dente, 100 exemplares da revisa semanal \u201cFutebol\u201d e 1 forno industrial para assar p\u00e3o. O contribuinte em quest\u00e3o pretende creditar-se da integralidade do ICMS relacionado a todas essas aquisi\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Com base nas normas da Lei Complementar n\u00b0 87\/96 e nas informa\u00e7\u00f5es acima, bem como tendo em vista que todas essas mercadorias\/bens n\u00e3o est\u00e3o sujeitas ao regime de substitui\u00e7\u00e3o tribut\u00e1ria e que o contribuinte n\u00e3o se enquadra nas regras do Simples Nacional, o referido supermercado<\/p>\n<p style=\"text-align: justify;\">a) s\u00f3 poder\u00e1 creditar-se do valor equivalente \u00e0 entrada de 50 revistas \u201cFutebol\u201d, porque metade deltas extraviou-se antes de sua entrada no supermercado.<\/p>\n<p style=\"text-align: justify;\">b) dever\u00e1 estornar o cr\u00e9dito referente 100 barras de sab\u00e3o, em raz\u00e3o de essas 100 barras terem sido utilizadas, tr\u00eas semanas ap\u00f3s a sua aquisi\u00e7\u00e3o, na limpeza do pr\u00f3prio estabelecimento, n\u00e3o tendo sido objeto de revenda \u00e0 clientela do supermercado, como era a inten\u00e7\u00e3o no momento de sua aquisi\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">c) poder\u00e1 creditar-se do ICMS destacado nos documentos de aquisi\u00e7\u00e3o de 100 latas de goiabada e de 1.000 tubos de pasta de dente, ainda que essas mercadorias tenham sido adquiridas em opera\u00e7\u00e3o isenta, pois o supermercado n\u00e3o sabe, de antem\u00e3o, se a sa\u00edda subsequente ser\u00e1 ou n\u00e3o onerada pelo imposto.<\/p>\n<p style=\"text-align: justify;\">d) dever\u00e1 estornar 20% do cr\u00e9dito referente \u00e0 aquisi\u00e7\u00e3o dos 100 Kg de farinha de trigo, pois foram utilizados 80 Kg daquela farinha na elabora\u00e7\u00e3o dos p\u00e3ezinhos vendidos na festa de Nossa Senhora de Sant\u2019Ana, venda essa beneficiada pela isen\u00e7\u00e3o do ICMS.<\/p>\n<p style=\"text-align: justify;\">e) poder\u00e1 creditar-se, de uma s\u00f3 vez, do valor integral do ICMS incidente na opera\u00e7\u00e3o referente \u00e0 aquisi\u00e7\u00e3o do forno industrial.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Alternativa A: A revista \u00e9 considerada um peri\u00f3dico, estando, portanto, imune ao ICMS. N\u00e3o cabe, portanto, escritura\u00e7\u00e3o de cr\u00e9dito. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa B: Conforme art. 33, I, da LC 87\/96, somente dar\u00e3o direito de cr\u00e9dito as mercadorias destinadas ao uso ou consumo do estabelecimento nele entradas a partir de 1\u00ba de janeiro de 2020. Logo, deve haver o estorno do cr\u00e9dito de ICMS escriturado. Alternativa correta.<\/p>\n<p style=\"text-align: justify;\">Alternativa C: Nos termos do art. 20, \u00a7 1\u00ba, da LC 87\/96, n\u00e3o d\u00e3o direito a cr\u00e9dito as entradas de mercadorias ou utiliza\u00e7\u00e3o de servi\u00e7os resultantes de opera\u00e7\u00f5es ou presta\u00e7\u00f5es isentas ou n\u00e3o tributadas, ou que se refiram a mercadorias ou servi\u00e7os alheios \u00e0 atividade do estabelecimento. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa D: Na verdade, o estorno corresponde ao percentual utilizado na industrializa\u00e7\u00e3o dos produtos isentos, isto \u00e9, 80%. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa E: Admite-se o cr\u00e9dito de ICMS na aquisi\u00e7\u00e3o de bens do ativo permanente, por\u00e9m n\u00e3o pode ser feito de uma s\u00f3 vez, havendo que se respeitar a apropria\u00e7\u00e3o \u00e0 raz\u00e3o de 1\/48 por m\u00eas. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra B<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 110. A Constitui\u00e7\u00e3o Federal estabelece, na al\u00edena \u201cg\u201d do inciso XII do \u00a7 2\u00ba do seu art. 155, que cabe \u00e0 lei complementar federal regulara\u00a0 forma como, mediante delibera\u00e7\u00e3o dos Estados e do Distrito Federal, isen\u00e7\u00f5es, incentivos e benef\u00edcios fiscais ser\u00e3o concedidos e revogados. A Lei Complementar n\u00b0 24\/75 faz a regulamenta\u00e7\u00e3o determinada no texto constitucional. De acordo com esta Lei Complementar, se um Estado brasileiro desejar conceder isen\u00e7\u00e3o no \u00e2mbito do ICMS, \u00e9 preciso que ele obtenha autoriza\u00e7\u00e3o para tanto, em reuni\u00f5es do CONFAZ, para as quais tenham sido convocados representantes:<\/p>\n<p style=\"text-align: justify;\">a) de todos os Estados e do Distrito Federal, sob a presid\u00eancia de representantes do governo federal, que a maioria das Unidades da Federa\u00e7\u00e3o esteja presente a elas, e que a decis\u00e3o pela concess\u00e3o do benef\u00edcio seja tomada por unanimidade dos Estados representados.<\/p>\n<p style=\"text-align: justify;\">b) de todos os Estados e do Distrito Federal, sob a presid\u00eancia rotativa do representante de um dos Estados, que quatro quintos das Unidades da Federa\u00e7\u00e3o esteja presente a elas, e que a decis\u00e3o pela concess\u00e3o do benef\u00edcio seja tomada por, pelo menos, tr\u00eas quartos dos Estados representados.<\/p>\n<p style=\"text-align: justify;\">c) de todos os Estados e do Distrito Federal, sob a presid\u00eancia rotativa do representante de um dos Estados, que a totalidade das Unidades da Federa\u00e7\u00e3o convidadas esteja presente a elas, e que a decis\u00e3o do benef\u00edcio seja tomada por, pelo menos, quatro quintos dos Estados representados.<\/p>\n<p style=\"text-align: justify;\">d) da maioria dos Estados e do Distrito Federal, sob a presid\u00eancia de representantes do governo federal, que quatro quintos das Unidades da Federa\u00e7\u00e3o convidadas esteja presente a elas, e que a decis\u00e3o pela concess\u00e3o do benef\u00edcio seja tomada por unanimidade dos Estados representados.<\/p>\n<p style=\"text-align: justify;\">e) de todos os Estados e do Distrito Federal, sob a presid\u00eancia de representantes do governo federal, que quatro quintos das Unidades da Federa\u00e7\u00e3o convidadas esteja presente a elas, e que a decis\u00e3o pela concess\u00e3o do benef\u00edcio seja tomada por unanimidade dos Estados representados.<\/p>\n<p style=\"text-align: justify;\">e) de todos os Estados e do Distrito Federal, sob a presid\u00eancia rotativa do representante de um dos Estados, que a maioria das Unidades da Federa\u00e7\u00e3o convidadas esteja presente a elas, e que a decis\u00e3o do benef\u00edcio seja tomada por, pelo menos, quatro quintos dos Estados representados.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio: De acordo com o art. 2\u00ba, da LC 24\/75, os Estados podem conceder isen\u00e7\u00f5es, incentivos e benef\u00edcios fiscais ap\u00f3s terem autoriza\u00e7\u00e3o em reuni\u00f5es do CONFAZ, \u00a0para as quais tenham sido convocados representantes de todos os Estados e do Distrito Federal, sob a presid\u00eancia de representantes do Governo federal. Tais reuni\u00f5es se realizar\u00e3o com a presen\u00e7a de representantes da maioria das Unidades da Federa\u00e7\u00e3o. A concess\u00e3o de benef\u00edcios depender\u00e1 sempre de decis\u00e3o un\u00e2nime dos Estados representados.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra A<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 111. A Constitui\u00e7\u00e3o Federal, na al\u00ednea \u201cc\u201d do inciso XII do \u00a7 2\u00ba do seu art. 155 estabelece que cabe \u00e0 lei complementar federal disciplinar o regime de compensa\u00e7\u00e3o do imposto. Atendendo a este comando da norma constitucional acerca do regime de compensa\u00e7\u00e3o do ICMS, a lei complementar n\u00b0 87\/96 estipula que<\/p>\n<p style=\"text-align: justify;\">a) as obriga\u00e7\u00f5es consideram-se vencidas, salvo disposi\u00e7\u00e3o de lei estadual em contr\u00e1rio, no quinto dia \u00fatil posterior ao do termo do per\u00edodo de apura\u00e7\u00e3o do imposto.<\/p>\n<p style=\"text-align: justify;\">b) a lei estadual, em substitui\u00e7\u00e3o a outras formas de apura\u00e7\u00e3o do imposto, poder\u00e1 estabelecer que o cotejo entre cr\u00e9ditos e d\u00e9bitos se fa\u00e7a por mercadoria ou servi\u00e7o, em cada opera\u00e7\u00e3o, vedado este cotejo dentro de determinado per\u00edodo.<\/p>\n<p style=\"text-align: justify;\">c) \u00c9 vedado, sem pr\u00e9via autoriza\u00e7\u00e3o fiscal, o transporte de saldo credor do imposto para o per\u00edodo seguinte de apura\u00e7\u00e3o quando o montante dos cr\u00e9ditos de um estabelecimento superar os d\u00e9bitos deste mesmo estabelecimento.<\/p>\n<p style=\"text-align: justify;\">d) A legisla\u00e7\u00e3o tribut\u00e1ria estadual dispor\u00e1 sobre o per\u00edodo de apura\u00e7\u00e3o do imposto.<\/p>\n<p style=\"text-align: justify;\">e) Estabelece que a lei estadual em substitui\u00e7\u00e3o a outras formas de apura\u00e7\u00e3o do imposto, poder\u00e1 estabelecer que o cotejo entre cr\u00e9ditos e d\u00e9bitos se fa\u00e7a por mercadoria ou servi\u00e7o dentro de determinado per\u00edodo, vedado o cotejo opera\u00e7\u00e3o por opera\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Alternativa A: De acordo com o art. 24, da LC 87\/96, a legisla\u00e7\u00e3o tribut\u00e1ria estadual dispor\u00e1 sobre o per\u00edodo de apura\u00e7\u00e3o do imposto. As obriga\u00e7\u00f5es consideram-se vencidas na data em que termina o per\u00edodo de apura\u00e7\u00e3o. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa B: O art. 26, I e II, da LC 87\/96, autoriza o cotejo entre cr\u00e9ditos e d\u00e9bitos se fa\u00e7a por mercadoria ou servi\u00e7o, em cada opera\u00e7\u00e3o, permitindo ainda este cotejo dentro de determinado per\u00edodo. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa C: O art. 24, III, da LC 87\/96, n\u00e3o exige pr\u00e9via autoriza\u00e7\u00e3o fiscal para o transporte do saldo credor do ICMS para o per\u00edodo seguinte. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa D: De acordo com o art. 24, da LC 87\/96, a legisla\u00e7\u00e3o tribut\u00e1ria estadual dispor\u00e1 sobre o per\u00edodo de apura\u00e7\u00e3o do imposto. Alternativa correta.<\/p>\n<p style=\"text-align: justify;\">Alternativa E: O art. 26, I e II, da LC 87\/96, autoriza o cotejo entre cr\u00e9ditos e d\u00e9bitos se fa\u00e7a por mercadoria ou servi\u00e7o, em cada opera\u00e7\u00e3o, permitindo ainda este cotejo dentro de determinado per\u00edodo. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra D<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 112.\u00a0 A Constitui\u00e7\u00e3o Federal contempla v\u00e1rias regras que t\u00eam por finalidade limitar o poder de tributar das pessoas jur\u00eddicas de direito p\u00fablico interno. De\u00a0 acordo com essas regras, \u00e9 vedado aos Estados<\/p>\n<p style=\"text-align: justify;\">a) Estabelecer limita\u00e7\u00f5es ao tr\u00e1fego de pessoas ou bens por meio de tributos interestaduais ou intermunicipais, ressalvada a cobran\u00e7a de ped\u00e1gio pela utiliza\u00e7\u00e3o de vias conservadas pelo Poder P\u00fablico.<\/p>\n<p style=\"text-align: justify;\">b) Instituir impostos sobre videofonogramas musicais produzidos no Mercosul, contendo obras musicas ou literomusicais de autores brasileiros, e obras em geral interpretadas por artistas brasileiros ou por artistas cidad\u00e3os de pa\u00edses integrantes do Mercosul, bem como sobre os suportes materiais ou arquivos digitais que contenham, inclusive na etapa de replica\u00e7\u00e3o industrial de m\u00eddias \u00f3pticas de leitura a laser.<\/p>\n<p style=\"text-align: justify;\">c) Instituir tratamento desigual entre contribuintes que se encontrem em situa\u00e7\u00e3o equivalente, facultada, para fins de desonera\u00e7\u00e3o tribut\u00e1ria total ou parcial, a distin\u00e7\u00e3o em raz\u00e3o de origem \u00e9tnica de n\u00edvel de escolaridade, de ocupa\u00e7\u00e3o profissional e de fun\u00e7\u00e3o por eles exercida.<\/p>\n<p style=\"text-align: justify;\">d) Cobrar tributos em rela\u00e7\u00e3o a fatos geradores ocorridos antes do in\u00edcio da regulamenta\u00e7\u00e3o de lei que os houver institu\u00eddo, aumentado ou reduzido.<\/p>\n<p style=\"text-align: justify;\">e) Cobrar tributos antes de decorridos noventa dias da data em que haja sido regulamentada a lei que os instituiu ou aumentou, podendo o referido prazo ser reduzido, nos casos em que seu t\u00e9rmino ocorrer no exerc\u00edcio subsequente, hip\u00f3tese em que o tributo poder\u00e1 ser cobrado desde o primeiro dia do novo exerc\u00edcio.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Alternativa A: \u00c9 o que estabelece o art. 150, V, da CF\/88. Alternativa correta.<\/p>\n<p style=\"text-align: justify;\">Alternativa B: Para estarem ao abrigo da imunidade os videofonogramas musicais devem ser produzidos no Pa\u00eds, devem ser de autoria de brasileiros ou devem ser interpretados por artistas brasileiros. Ademais, a imunidade em comento exclui a etapa de replica\u00e7\u00e3o industrial de m\u00eddias \u00f3pticas de leitura a laser. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa C: O que o princ\u00edpio da isonomia, previsto no art. 150, II, da CF\/88 veda \u00e9 a instituir tratamento desigual entre contribuintes que se encontrem em situa\u00e7\u00e3o equivalente, vedando, ainda, a distin\u00e7\u00e3o em raz\u00e3o da ocupa\u00e7\u00e3o profissional e de fun\u00e7\u00e3o por eles exercida. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa D: O art. 150, III, \u201ca\u201d veda a cobran\u00e7a de tributos em rela\u00e7\u00e3o a fatos geradores ocorridos antes do in\u00edcio da vig\u00eancia da lei que os tenha institu\u00eddo ou majorado. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa E: O princ\u00edpio da anterioridade nonagesimal impede a cobran\u00e7a de tributos antes de decorridos noventa dias da data em que haja sido publicada a lei que os instituiu ou aumentou, n\u00e3o podendo tal prazo ser reduzido. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra A<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 113 \u2013 \u00c9 fundamental, para o exerc\u00edcio do cargo de Auditor-Fiscal da Receita Estadual, conhecer as regras do C\u00f3digo Tribut\u00e1rio Nacional a respeito do lan\u00e7amento tribut\u00e1rio, pois uma de suas atividades funcionais poder\u00e1 ser a de\u00a0 promover a constitui\u00e7\u00e3o do cr\u00e9dito por meio daquele procedimento administrativo. De acordo com o referido c\u00f3digo<\/p>\n<p style=\"text-align: justify;\">A) a legisla\u00e7\u00e3o tribut\u00e1ria de cada tributo poder\u00e1 fixar prazo para homologa\u00e7\u00e3o da atividade desenvolvida pelo sujeito passivo, que ser\u00e1 de cinco anos, a contar do primeiro dia do exerc\u00edcio seguinte \u00e0quele em que o lan\u00e7amento poderia ter sido efetuado, e de 8 anos, no caso de se comprovar que o sujeito passivo agiu com dolo, fraude ou simula\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">B) quando se comprove que o sujeito passivo, ou terceiro em benef\u00edcio daquele, agiu com dolo, fraude ou simula\u00e7\u00e3o, a autoridade administrativa dever\u00e1 desenvolver a atividade de lan\u00e7amento por homologa\u00e7\u00e3o do tributo e da penalidade pecuni\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">C) quando o sujeito passivo ou terceiro presta \u00e0 autoridade administrativa, na forma da legisla\u00e7\u00e3o tribut\u00e1ria, informa\u00e7\u00f5es sobre mat\u00e9ria de fato indispens\u00e1veis \u00e0 constitui\u00e7\u00e3o do cr\u00e9dito tribut\u00e1rio, est\u00e1-se distante do denominado \u201clan\u00e7amento de of\u00edcio\u201d.<\/p>\n<p style=\"text-align: justify;\">D) O lan\u00e7amento que ocorre quanto aos tributos cuja legisla\u00e7\u00e3o atribua ao sujeito passivo, ou a terceiro a obriga\u00e7\u00e3o de prestar \u00e0 autoridade administrativa, na forma da legisla\u00e7\u00e3o tribut\u00e1ria, informa\u00e7\u00f5es sobre mat\u00e9ria de fato, as quais dever\u00e3o ser homologadas no prazo decadencial de cinco anos, denomina-se \u201clan\u00e7amento por homologa\u00e7\u00e3o\u201d.<\/p>\n<p style=\"text-align: justify;\">E) quando se comprova a\u00e7\u00e3o ou omiss\u00e3o do sujeito passivo, ou de terceiro legalmente obrigado, que d\u00ea lugar a aplica\u00e7\u00e3o da penalidade pecuni\u00e1ria, o lan\u00e7amento ser\u00e1 efetuado de of\u00edcio aplicando-se ao infrator a penalidade pecuni\u00e1ria correspondente.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Alternativa A: Nos casos de dolo, fraude ou simula\u00e7\u00e3o, o prazo para homologa\u00e7\u00e3o da atividade desenvolvida pelo sujeito passivo ser\u00e1 tamb\u00e9m de cinco anos, sendo iniciada sua contagem a partir do primeiro dia do ano seguinte \u00e0quele em que o lan\u00e7amento poderia ter sido efetuado. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa B: Nos termos do art. 149, VII, em tal caso cabe o lan\u00e7amento de of\u00edcio. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa C: Trata-se do disposto no art. 147, do CTN, que prev\u00ea o lan\u00e7amento \u201cpor declara\u00e7\u00e3o\u201d. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa D: N\u00e3o se trata de homologa\u00e7\u00e3o, mas sim de lan\u00e7amento \u201cpor declara\u00e7\u00e3o\u201d, nos termos do art. 147, do CTN. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa E: O art. 149, VI, determina o lan\u00e7amento de of\u00edcio quando se comprovar a\u00e7\u00e3o ou omiss\u00e3o do sujeito passivo, ou de terceiro legalmente obrigado, que d\u00ea lugar a aplica\u00e7\u00e3o da penalidade pecuni\u00e1ria, aplicando-se ao infrator a penalidade pecuni\u00e1ria correspondente. Alternativa correta.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra E<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 114 \u2013 De acordo com a Constitui\u00e7\u00e3o Federal, o Estado de Goi\u00e1s ser\u00e1 sujeito ativo da obriga\u00e7\u00e3o tribut\u00e1ria principal relativamente ao ITCMD, na<\/p>\n<p style=\"text-align: justify;\">a) transmiss\u00e3o onerosa de um apartamento localizado no Munic\u00edpio de An\u00e1polis\/GO, sendo que o alienante tem domic\u00edlio, resid\u00eancia em Catal\u00e3o\/GO, e o adquirente tem domic\u00edlio e resid\u00eancia no Distrito Federal.<\/p>\n<p style=\"text-align: justify;\">b) transmiss\u00e3o, por doa\u00e7\u00e3o, da propriedade de rebanho localizado em fazenda do Munic\u00edpio de Novas Crix\u00e1s\/GO, sendo que o doador e donat\u00e1rio t\u00eam domic\u00edlio e resid\u00eancia no Distrito Federal.<\/p>\n<p style=\"text-align: justify;\">c) transmiss\u00e3o causa mortis de bem im\u00f3vel localizado no Distrito Federal, quando o invent\u00e1rio seja processado no Munic\u00edpio de Rio Verde\/GO.<\/p>\n<p style=\"text-align: justify;\">d) transmiss\u00e3o, por doa\u00e7\u00e3o, de um terreno localizado em Senador Canedo\/GO, sendo que o doador tem domic\u00edlio e resid\u00eancia em Manaus\/AM e o donat\u00e1rio tem domic\u00edlio e resid\u00eancia no Distrito Federal.<\/p>\n<p style=\"text-align: justify;\">e) transmiss\u00e3o causa mortis de ve\u00edculo automotor localizado no Distrito Federal, quando o invent\u00e1rio seja processado no Distrito Federal, mas o legat\u00e1rio deste bem seja domiciliado em Morrinhos\/GO.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Alternativa A: O ITCMD n\u00e3o incide sobre transmiss\u00e3o onerosa, mas apenas sobre transmiss\u00f5es a t\u00edtulo gratuito e transmiss\u00f5es causa mortis. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa B: Em se tratando de bens m\u00f3veis, o ITCMD \u00e9 devido ao Estado (ou DF) onde o doador tiver resid\u00eancia. Logo, o Estado de Goi\u00e1s n\u00e3o ser\u00e1 sujeito ativo nesta situa\u00e7\u00e3o. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa C: Em se tratando de bem im\u00f3vel, o ITCMD compete ao Estado da situa\u00e7\u00e3o do bem, ou ao Distrito Federal. Logo, neste caso, o imposto ser\u00e1 devido ao Distrito Federal. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa D: Em se tratando de bem im\u00f3vel, o ITCMD compete ao Estado da situa\u00e7\u00e3o do bem, ou ao Distrito Federal. Portanto, neste caso, o ITCMD ser\u00e1 devido ao Estado de Goi\u00e1s. Alternativa correta.<\/p>\n<p style=\"text-align: justify;\">Alternativa E: Em se tratando de bens m\u00f3veis, o ITCMD \u00e9 devido ao Estado (ou DF) onde se processar o invent\u00e1rio ou arrolamento. Logo, neste caso, o imposto ser\u00e1 devido ao Distrito Federal. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra D<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 115 \u2013 Dr. Diogo, titular de escrit\u00f3rio de consultoria em mat\u00e9ria tribut\u00e1ria, foi indagado por quatro clientes seus, a respeito da tributa\u00e7\u00e3o do ISSQN e do ICMS, pois queriam saber como deveriam tributar corretamente as atividades que pretendiam desenvolver. Dr Diogo respondeu para<\/p>\n<p style=\"text-align: justify;\">I) Al\u00edcia, dentista, que os servi\u00e7os odontol\u00f3gicos prestados ser\u00e3o tributados pelo ISSQN enquanto que o material aplicado ser\u00e1 tributado ICMS, desde que esse material representasse mais de 50% do valor cobrado do paciente.<\/p>\n<p style=\"text-align: justify;\">II) Renato, propriet\u00e1rio de hotel, que o valor da alimenta\u00e7\u00e3o fornecida, se inclu\u00edda no valor da di\u00e1ria, estar\u00e1 sujeita ao ISSQN, mas se exclu\u00edda do valor da di\u00e1ria, estar\u00e1 sujeita ao ICMS.<\/p>\n<p style=\"text-align: justify;\">III) Carlos, propriet\u00e1rio de um estabelecimento que tem por atividade a reprografia de documentos, que, no caso de elabora\u00e7\u00e3o de fotoc\u00f3pias, o ISSQN incidir\u00e1 somente sobre 2\/3 do valor cobrado do cliente, enquanto que o ICMS incidir\u00e1 apenas sobre 1\/3 do valor cobrado.<\/p>\n<p>IV) Andrea, propriet\u00e1ria de um laborat\u00f3rio de pr\u00f3teses dent\u00e1rias confeccionadas sob encomenda, que, se a pr\u00f3tese tiver finalidade meramente est\u00e9tica e n\u00e3o pl\u00e1stica reparadora, tanto os servi\u00e7os prestados como os materiais utilizados na sua confec\u00e7\u00e3o ser\u00e3o tributados pelo ICMS.<\/p>\n<p style=\"text-align: justify;\">Est\u00e1 correto o que Dr. Diogo respondeu APENAS em<\/p>\n<p style=\"text-align: justify;\">A) II e IV;<\/p>\n<p style=\"text-align: justify;\">B) III;<\/p>\n<p style=\"text-align: justify;\">C) I e III;<\/p>\n<p style=\"text-align: justify;\">D) I e IV;<\/p>\n<p style=\"text-align: justify;\">E) II.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Item I: No caso de servi\u00e7o de compet\u00eancia dos Munic\u00edpios, e n\u00e3o havendo ressalva na LC 116\/03 para incid\u00eancia do ICMS em rela\u00e7\u00e3o \u00e0 mercadoria fornecida na presta\u00e7\u00e3o do servi\u00e7o, caber\u00e1 a incid\u00eancia do ISS sobre o valor total da opera\u00e7\u00e3o, como ocorre no servi\u00e7o odontol\u00f3gico. Item errado.<\/p>\n<p style=\"text-align: justify;\">Item II: No caso dos servi\u00e7os de hospedagem, item 9.01 da lista anexa \u00e0 LC 116\/03, o ISS incidir\u00e1 sobre o servi\u00e7o e tamb\u00e9m sobre o valor da alimenta\u00e7\u00e3o fornecida, desde que esta esteja inclu\u00edda no valor da di\u00e1ria. Caso esteja exclu\u00edda, haver\u00e1 incid\u00eancia do ICMS, como apontou a banca examinadora. Item correto.<\/p>\n<p style=\"text-align: justify;\">Item III: No caso de servi\u00e7o de compet\u00eancia dos Munic\u00edpios, e n\u00e3o havendo ressalva na LC 116\/03 para incid\u00eancia do ICMS em rela\u00e7\u00e3o \u00e0 mercadoria fornecida na presta\u00e7\u00e3o do servi\u00e7o, caber\u00e1 a incid\u00eancia do ISS sobre o valor total da opera\u00e7\u00e3o, como ocorre no servi\u00e7o de reprografia de documentos. Item errado.<\/p>\n<p style=\"text-align: justify;\">Item IV: O mesmo racioc\u00ednio do item I e III \u00e9 aplic\u00e1vel neste item, considerando o servi\u00e7o previsto no item 4.14, da lista anexa \u00e0 LC 116\/03. Item errado.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra E<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 116 \u2013 O C\u00f3digo Tribut\u00e1rio Nacional estabelece que a morat\u00f3ria suspende a exigibilidade do cr\u00e9dito tribut\u00e1rio. De acordo com o referido c\u00f3digo<\/p>\n<p style=\"text-align: justify;\">A) ela pode ser concedida em car\u00e1ter individual, por despacho da autoridade administrativa, desde que autorizada por decreto, seu prazo concedido for de at\u00e9 de seis meses, e, por lei, se o prazo concedido for superior a 6 meses.<\/p>\n<p style=\"text-align: justify;\">B) a morat\u00f3ria pode ser concedida em car\u00e1ter geral pelos Estados, quanto a tributos de compet\u00eancia da Uni\u00e3o, dos pr\u00f3prios Estados e do Distrito Federal, ou ainda dos Munic\u00edpios, quando essa concess\u00e3o tiver sido autorizada, de forma geral ou espec\u00edfica, por resolu\u00e7\u00e3o do Senado Federal.<\/p>\n<p style=\"text-align: justify;\">C) A lei concessiva de morat\u00f3ria pode circunscrever expressamente a sua aplicabilidade a determinada regi\u00e3o do territ\u00f3rio da pessoa jur\u00eddica de direito p\u00fablica que a expedir, vedada essa concess\u00e3o a determinada classe ou categoria de sujeitos passivos.<\/p>\n<p style=\"text-align: justify;\">D) A morat\u00f3ria, exceto quando se tratar de reincid\u00eancia em um prazo quinquenal, pode ser concedida aos casos de simula\u00e7\u00e3o do sujeito passivo, ou do terceiro em benef\u00edcio daquele.<\/p>\n<p style=\"text-align: justify;\">E) Salvo disposi\u00e7\u00e3o de lei em contr\u00e1rio, a morat\u00f3ria somente abrange os cr\u00e9ditos definitivamente constitu\u00eddos \u00e0 data da lei ou do despacho que a conceder, ou cujo lan\u00e7amento j\u00e1 tenha sido iniciado \u00e0quela data por ato regularmente notificado ao sujeito passivo.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Alternativa A: A morat\u00f3ria sempre deve ser concedida ou autorizada por meio de lei, conforme art. 153, do CTN. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa B: A \u00fanica previs\u00e3o de morat\u00f3ria heter\u00f4noma diz respeito \u00e0 sua concess\u00e3o pela Uni\u00e3o, no art. 152, I, \u201cb\u201d, do CTN. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa C: O par. \u00fanico, do art. 152, do CTN, prev\u00ea que a lei concessiva de morat\u00f3ria pode circunscrever expressamente a sua aplicabilidade \u00e0 determinada regi\u00e3o do territ\u00f3rio da pessoa jur\u00eddica de direito p\u00fablico que a expedir, ou a determinada classe ou categoria de sujeitos passivos. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa D: O art. 154, par. \u00fanico, do CTN, prev\u00ea que a morat\u00f3ria n\u00e3o aproveita aos casos de dolo, fraude ou simula\u00e7\u00e3o do sujeito passivo ou do terceiro em benef\u00edcio daquele. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa E: \u00c9 o que estabelece o caput do art. 154, do CTN: salvo disposi\u00e7\u00e3o de lei em contr\u00e1rio, a morat\u00f3ria somente abrange os cr\u00e9ditos definitivamente constitu\u00eddos \u00e0 data da lei ou do despacho que a conceder, ou cujo lan\u00e7amento j\u00e1 tenha sido iniciado \u00e0quela data por ato regularmente notificado ao sujeito passivo. Alternativa correta.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra E<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 117 \u2013 Relativamente ao domic\u00edlio tribut\u00e1rio do sujeito passivo, o CTN<\/p>\n<p style=\"text-align: justify;\">A) Disp\u00f5e que, na falta de elei\u00e7\u00e3o, o domic\u00edlio tribut\u00e1rio das pessoas naturais ser\u00e1 o local de resid\u00eancia do parente mais pr\u00f3ximo do sujeito passivo.<\/p>\n<p style=\"text-align: justify;\">B) Estabelece que o domic\u00edlio da pessoa natural \u00e9 a sua resid\u00eancia habitual, ficando facultado \u00e0 autoridade administrativa eleg\u00ea-lo apenas nos casos em que essa resid\u00eancia habitual for incerta ou desconhecida.<\/p>\n<p style=\"text-align: justify;\">C) Estabelece que o domic\u00edlio da pessoa jur\u00eddica de direito privado, em rela\u00e7\u00e3o aos atos ou fatos que derem origem \u00e0 obriga\u00e7\u00e3o, \u00e9 o lugar de cada estabelecimento seu, desde que outro n\u00e3o seja por ela eleito.<\/p>\n<p style=\"text-align: justify;\">D) Permite, como regra, que o contribuinte o escolha livremente, vedada esta possibilidade ao respons\u00e1vel.<\/p>\n<p style=\"text-align: justify;\">E) Estabelece que \u00e9 aquele previsto na lei que instituir cada tributo, ou, no caso de ser permitida sua elei\u00e7\u00e3o pelo contribuinte, \u00e9 vedada sua altera\u00e7\u00e3o dentro de um mesmo exerc\u00edcio.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio:<\/p>\n<p style=\"text-align: justify;\">Alternativa A: Na falta de elei\u00e7\u00e3o, o domic\u00edlio tribut\u00e1rio das pessoas naturais ser\u00e1 a sua resid\u00eancia habitual, ou, sendo esta incerta ou desconhecida, o centro habitual de sua atividade. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa B: O domic\u00edlio da pessoa natural \u00e9 eleito pelo pr\u00f3prio sujeito passivo. Na falta de elei\u00e7\u00e3o, o domic\u00edlio tribut\u00e1rio das pessoas naturais ser\u00e1 a sua resid\u00eancia habitual, ou, sendo esta incerta ou desconhecida, o centro habitual de sua atividade. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa C: De fato, o art. 127, II, do CTN, prev\u00ea que, na falta de elei\u00e7\u00e3o, o domic\u00edlio tribut\u00e1rio das pessoas jur\u00eddicas de direito privado, em rela\u00e7\u00e3o aos atos ou fatos que derem origem \u00e0 obriga\u00e7\u00e3o, ser\u00e1 o de cada estabelecimento. Alternativa correta.<\/p>\n<p style=\"text-align: justify;\">Alternativa D: O caput do art. 127, do CTN, prev\u00ea que a elei\u00e7\u00e3o \u00e9 realizada pelo contribuinte ou respons\u00e1vel. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\">Alternativa E: N\u00e3o \u00e9 essa a reda\u00e7\u00e3o do art. 127, do CTN, conforme j\u00e1 comentado nas demais alternativas. Alternativa errada.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra C<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 118 \u2013 &#8221;H. Silva&amp; Silva\u2019\u2019 (empresa fict\u00edcia), com\u00e9rcio atacadista de produtos aliment\u00edcios, \u00e9 contribuinte do ICMS e, nas vendas de mercadorias que efetua a sua clientela, ele mesmo se encarrega de remeter, transportar e entreg\u00e1-las, por meio de ve\u00edculos pr\u00f3prios. Certa vez, quando seu ve\u00edculo estava em tr\u00e2nsito, transportando mercadorias para serem entregues a seus clientes, foi abordado por autoridades fiscais, que solicitaram ao motorista a exibi\u00e7\u00e3o dos documentos fiscais que deveriam estar acompanhando a remessa, o transporte e a entrega das mercadorias aos seus respectivos destinat\u00e1rios. O motorista, por\u00e9m, afirmou que n\u00e3o tinha documento fiscal algum consigo.<\/p>\n<p style=\"text-align: justify;\">A penalidade que a legisla\u00e7\u00e3o do ICMS comina para o contribuinte que n\u00e3o emite o documento fiscal \u00e9 de 50% do valor da opera\u00e7\u00e3o. Por outro lado, a mesma lei comina penalidade de 30% para o contribuinte que emite o referido documento, mas deixa de lev\u00e1-lo consigo na remessa, transporte e entrega das mercadorias aos seus destinat\u00e1rios. A mesma lei, ainda, estabelece que a apena\u00e7\u00e3o do sujeito passivo por uma das infra\u00e7\u00f5es, impede a apena\u00e7\u00e3o dele pela outra.<\/p>\n<p style=\"text-align: justify;\">Tendo em conta a disciplina do C\u00f3digo Tribut\u00e1rio Nacional acerca desta mat\u00e9ria, considerando a situa\u00e7\u00e3o descrita, bem como a d\u00favida insuper\u00e1vel existente quanto ao fato infracional efetivamente ocorrido, as referidas autoridades fiscais<\/p>\n<p style=\"text-align: justify;\">A) dever\u00e3o interpretar a norma que define infra\u00e7\u00f5es e a que lhe comina penalidades, de maneira mais favor\u00e1vel ao sujeito passivo infrator, caso n\u00e3o consigam eliminar a d\u00favida quanto \u00e0 natureza ou \u00e0s circunst\u00e2ncias materiais do fato infracional por praticado pelo sujeito passivo.<\/p>\n<p style=\"text-align: justify;\">B) dever\u00e3o efetuar um lan\u00e7amento reclamando a penalidade referente \u00e0 falta de emiss\u00e3o de documento fiscal, e outro reclamando a penalidade por remessa, transporte e entrega de mercadoria, desacompanhada de documento fiscal, com a finalidade de evitar a decad\u00eancia, conforme determina expressamente o pr\u00f3prio CTN, deixando para a autoridade judicante, administrativa ou judicial, a tarefa de identificar qual san\u00e7\u00e3o dever\u00e1 ser efetivamente aplicada.<\/p>\n<p style=\"text-align: justify;\">C) dever\u00e3o efetuar um lan\u00e7amento \u00fanico, reclamando tanto a penalidade referente \u00e0 falta de emiss\u00e3o de documento fiscal, como a penalidade por remessa, transporte e entrega de mercadoria, desacompanhada de documento fiscal, deixando para a autoridade judicante, administrativa ou judicial, a tarefa de identificar qual san\u00e7\u00e3o dever\u00e1 ser efetivamente aplicada.<\/p>\n<p style=\"text-align: justify;\">D) dever\u00e3o efetuar o lan\u00e7amento de penalidade por falta de emiss\u00e3o de documento fiscal, pelo simples fato de esta infra\u00e7\u00e3o implicar san\u00e7\u00e3o menos branda do que a cominada para a falta de emiss\u00e3o de documento fiscal, uma vez que o fisco n\u00e3o tem compet\u00eancia para abrir m\u00e3o da receita de natureza punitiva.<\/p>\n<p style=\"text-align: justify;\">E) n\u00e3o poder\u00e3o efetuar o lan\u00e7amento da penalidade, enquanto n\u00e3o tiverem absoluta certeza quanto \u00e0 infra\u00e7\u00e3o cometida.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio: Nos termos do art. 112, do CTN, a lei tribut\u00e1ria que define infra\u00e7\u00f5es, ou lhe comina penalidades, interpreta-se da maneira mais favor\u00e1vel ao acusado, em caso de d\u00favida quanto \u00e0 natureza ou \u00e0s circunst\u00e2ncias materiais do fato, ou \u00e0 natureza ou extens\u00e3o dos seus efeitos.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra A<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 119 &#8211; A contribui\u00e7\u00e3o de melhoria \u00e9 uma esp\u00e9cie de tributo expressamente mencionada na Constitui\u00e7\u00e3o Federal e no C\u00f3digo Tribut\u00e1rio Nacional. De acordo com as normas do CTN, esta contribui\u00e7\u00e3o pode ser cobrada pelo Estado, para fazer face<\/p>\n<p style=\"text-align: justify;\">A) ao custo dos reparos promovidos em uma pista elevada para bicicletas, que, embora tenha ocasionado a deprecia\u00e7\u00e3o dos im\u00f3veis circunvizinhos a ela, solucionou os problemas de tr\u00e1fego da regi\u00e3o.<\/p>\n<p style=\"text-align: justify;\">B) ao custo extraordin\u00e1rio incorrido pelo poder p\u00fablico, referente \u00e0 contrata\u00e7\u00e3o de professores estrangeiros, contratados para lecionar na faculdade estadual local, tornando-a uma faculdade de ponta no Brasil.<\/p>\n<p style=\"text-align: justify;\">C) a despesas referentes \u00e0 limpeza de um campo de futebol de propriedade do clube da regi\u00e3o, que conseguiu, com isso, melhorar a qualidade de vida das crian\u00e7as que residiam nas suas redondezas.<\/p>\n<p style=\"text-align: justify;\">D) ao custo de obras p\u00fablicas referentes \u00e0 edifica\u00e7\u00e3o, pelo poder p\u00fablico estadual, de uma escola e de um parque p\u00fablicos, os quais acabaram valorizando a regi\u00e3o como um todo, inclusive os im\u00f3veis circunvizinhos.<\/p>\n<p style=\"text-align: justify;\">E) ao custo extraordin\u00e1rio incorrido pelo poder p\u00fablico, referente \u00e0 altera\u00e7\u00e3o de destina\u00e7\u00e3o dos pr\u00e9dios hist\u00f3ricos da regi\u00e3o, ocasionando a valoriza\u00e7\u00e3o do acervo hist\u00f3rico mobili\u00e1rio que neles se encontra.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio: A contribui\u00e7\u00e3o de melhoria somente pode ser cobrada em raz\u00e3o da realiza\u00e7\u00e3o de obra p\u00fablica da qual decorra valoriza\u00e7\u00e3o imobili\u00e1ria. A \u00fanica alternativa que aponta esta situa\u00e7\u00e3o \u00e9 a Letra D.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra D<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Quest\u00e3o 120 &#8211; Relativamente \u00e0 fiscaliza\u00e7\u00e3o tribut\u00e1ria, notadamente no que diz respeito aos impostos de compet\u00eancia das diversas pessoas jur\u00eddicas de direito p\u00fablico interno, o C\u00f3digo Tribut\u00e1rio Nacional estabelece que \u00e0s Fazendas P\u00fablicas \u00e9 permitida a presta\u00e7\u00e3o de assist\u00eancia m\u00fatua<\/p>\n<p style=\"text-align: justify;\">A) para permuta de informa\u00e7\u00f5es de car\u00e1ter tribut\u00e1rio, mas vedada para fiscaliza\u00e7\u00e3o dos tributos respectivos, pois a fiscaliza\u00e7\u00e3o \u00e9 atividade indeleg\u00e1vel.<\/p>\n<p style=\"text-align: justify;\">B) apenas para a fiscaliza\u00e7\u00e3o de tributos respectivos, desde que restrita ao \u00e2mbito dos Estados e do Distrito Federal, relativamente aos impostos de sua compet\u00eancia comum, e ao \u00e2mbito dos Munic\u00edpios, relativamente aos impostos de compet\u00eancia comum destes.<\/p>\n<p style=\"text-align: justify;\">C) entre todas elas, para a fiscaliza\u00e7\u00e3o dos tributos respectivos e para a permuta de informa\u00e7\u00f5es, na forma estabelecida por lei ou conv\u00eanio, em car\u00e1ter geral ou espec\u00edfico.<\/p>\n<p style=\"text-align: justify;\">D) apenas para permuta de informa\u00e7\u00f5es, desde que restrita ao \u00e2mbito dos Estados e do Distrito Federal, relativamente aos impostos de sua compet\u00eancia comum, e ao \u00e2mbito dos Munic\u00edpios e do Distrito Federal, relativamente aos impostos de compet\u00eancia comum destes.<\/p>\n<p style=\"text-align: justify;\">E) entre todas elas, para a permuta de informa\u00e7\u00f5es e para a fiscaliza\u00e7\u00e3o de tributos, na forma estabelecida, por lei ou conv\u00eanio, vedada a presta\u00e7\u00e3o de informa\u00e7\u00f5es pela fazenda P\u00fablica da Uni\u00e3o, que, no entanto, poder\u00e1 receb\u00ea-las das Fazendas P\u00fablicas estaduais e municipais.<\/p>\n<p style=\"text-align: justify;\">Coment\u00e1rio: O art. 199, do CTN, estabelece que a Fazenda P\u00fablica da Uni\u00e3o e as dos Estados, do Distrito Federal e dos Munic\u00edpios prestar-se-\u00e3o mutuamente assist\u00eancia para a fiscaliza\u00e7\u00e3o dos tributos respectivos e permuta de informa\u00e7\u00f5es, na forma estabelecida, em car\u00e1ter geral ou espec\u00edfico, por lei ou conv\u00eanio.<\/p>\n<p style=\"text-align: justify;\"><strong>Gabarito Extraoficial: Letra C<\/strong><\/p>\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-sefaz-go\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"font-size: 18pt;\"><em><strong>Preencha seu Gabarito e entre no Ranking!<\/strong><\/em><\/span><\/span><\/a><\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, meus amigos, tudo bem? Meu nome \u00e9 F\u00e1bio Dutra, sou professor de Direito Tribut\u00e1rio do Estrat\u00e9gia Concursos e Auditor-Fiscal da RFB. Estou aqui com voc\u00eas, pois neste final de semana, foi aplicada a prova do concurso SEFAZ-GO (Auditor-Fiscal), realizada pela banca Funda\u00e7\u00e3o Carlos Chagas (FCC), e, como de costume, j\u00e1 providenciamos o coment\u00e1rio da [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-144624","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1, meus amigos, tudo bem? Meu nome \u00e9 F\u00e1bio Dutra, sou professor de Direito Tribut\u00e1rio do Estrat\u00e9gia Concursos e Auditor-Fiscal da RFB. Estou aqui com voc\u00eas, pois neste final de semana, foi aplicada a prova do concurso SEFAZ-GO (Auditor-Fiscal), realizada pela banca Funda\u00e7\u00e3o Carlos Chagas (FCC), e, como de costume, j\u00e1 providenciamos o coment\u00e1rio da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-30T20:56:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T18:02:42+00:00\" \/>\n<meta name=\"author\" content=\"F\u00e1bio Dutra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"F\u00e1bio Dutra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/\"},\"author\":{\"name\":\"F\u00e1bio Dutra\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63\"},\"headline\":\"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio\",\"datePublished\":\"2018-09-30T20:56:14+00:00\",\"dateModified\":\"2022-10-26T18:02:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/\"},\"wordCount\":5911,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/\",\"name\":\"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2018-09-30T20:56:14+00:00\",\"dateModified\":\"2022-10-26T18:02:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63\",\"name\":\"F\u00e1bio Dutra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g\",\"caption\":\"F\u00e1bio Dutra\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabiodutraestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/","og_locale":"pt_BR","og_type":"article","og_title":"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio","og_description":"Ol\u00e1, meus amigos, tudo bem? Meu nome \u00e9 F\u00e1bio Dutra, sou professor de Direito Tribut\u00e1rio do Estrat\u00e9gia Concursos e Auditor-Fiscal da RFB. Estou aqui com voc\u00eas, pois neste final de semana, foi aplicada a prova do concurso SEFAZ-GO (Auditor-Fiscal), realizada pela banca Funda\u00e7\u00e3o Carlos Chagas (FCC), e, como de costume, j\u00e1 providenciamos o coment\u00e1rio da [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2018-09-30T20:56:14+00:00","article_modified_time":"2022-10-26T18:02:42+00:00","author":"F\u00e1bio Dutra","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"F\u00e1bio Dutra","Est. tempo de leitura":"30 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/"},"author":{"name":"F\u00e1bio Dutra","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63"},"headline":"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio","datePublished":"2018-09-30T20:56:14+00:00","dateModified":"2022-10-26T18:02:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/"},"wordCount":5911,"commentCount":3,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/","name":"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-09-30T20:56:14+00:00","dateModified":"2022-10-26T18:02:42+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-sefaz-go-direito-tributario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gabarito Extraoficial SEFAZ-GO: Direito Tribut\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/c6615b1e72eae70edca73ea5362ead63","name":"F\u00e1bio Dutra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fb4b2715a33320653086a45a7174528e6836e078753b587b59cb70f7b453819?s=96&d=mm&r=g","caption":"F\u00e1bio Dutra"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fabiodutraestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/144624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=144624"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/144624\/revisions"}],"predecessor-version":[{"id":1116004,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/144624\/revisions\/1116004"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=144624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=144624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=144624"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=144624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}