{"id":1439676,"date":"2024-08-06T16:27:38","date_gmt":"2024-08-06T19:27:38","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1439676"},"modified":"2024-08-08T00:44:46","modified_gmt":"2024-08-08T03:44:46","slug":"concurso-tce-pa-recursos-auditor-direito-e-auxiliar","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/","title":{"rendered":"Concurso TCE PA: poss\u00edveis recursos de Auditor &#8211; Direito e Auxiliar"},"content":{"rendered":"\n<p>No \u00faltimo domingo, 04, foram aplicadas as provas do <strong>concurso TCE PA (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/tce-pa-tribunal-de-contas-do-estado-do-para\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tribunal de Contas do Estado do Par\u00e1<\/a>)<\/strong> para <strong>Auditor de Controle Externo &#8211; \u00c1rea Fiscaliza\u00e7\u00e3o &#8211; Direito<\/strong> <strong>e Auxiliar T\u00e9cnico de Controle Externo.<\/strong><\/p>\n\n\n\n<p>O Estrat\u00e9gia Concursos esteve presente durante toda sua prepara\u00e7\u00e3o (assim como nas corre\u00e7\u00f5es extraoficiais de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-tce-pa-auditor-de-controle-externo-direito\/\" target=\"_blank\" rel=\"noreferrer noopener\">Auditor<\/a> e <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-tce-pa-cargo-auxiliar-tecnico\" target=\"_blank\" rel=\"noreferrer noopener\">Auxiliar<\/a>) e, mesmo ap\u00f3s aplica\u00e7\u00e3o das avalia\u00e7\u00f5es, n\u00e3o deixar\u00e1 de te acompanhar!<\/p>\n\n\n\n<p>Com isso, reunimos nosso time de professores para apontar quais quest\u00f5es s\u00e3o pass\u00edveis de recursos, cujo <strong>prazo para interposi\u00e7\u00e3o ficar\u00e1 aberto at\u00e9 o dia 08 de agosto,<\/strong> no site da banca <a href=\"https:\/\/conhecimento.fgv.br\/concursos\/tcepa24\" target=\"_blank\" rel=\"noreferrer noopener\">FGV<\/a>.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background:linear-gradient(135deg,rgb(238,238,238) 0%,rgb(179,175,175) 37%,rgb(169,184,195) 100%);font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><strong>Concurso TCE PA: poss\u00edveis recursos de <\/strong><strong>Auditor de Controle Externo &#8211; \u00c1rea Fiscaliza\u00e7\u00e3o &#8211; Direito<\/strong><\/p>\n\n\n\n<p><strong><span style=\"text-decoration: underline;\">PROVA TIPO 01 &#8211; BRANCA<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-background has-medium-font-size\" style=\"background-color:#d9dbde\"><strong>Disciplina:<\/strong> <strong>\u00c1rea Administrativa &#8211; Gest\u00e3o Governamental<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><span style=\"text-decoration: underline;\">Quest\u00e3o 42<\/span><\/strong><\/p>\n\n\n\n<p>Na popula\u00e7\u00e3o de determinado munic\u00edpio sobressa\u00edram discuss\u00f5es quanto \u00e0 necessidade de se incrementar a economia local, mais propriamente aquela referente aos microempreendedores. Ap\u00f3s an\u00e1lises, verificou-se a dificuldade de obten\u00e7\u00e3o de cr\u00e9dito por parte desse setor que, por sua vez, \u00e9 o maior respons\u00e1vel pelas contrata\u00e7\u00f5es diretas de m\u00e3o de obra no setor privado. O Poder Executivo local elencou ent\u00e3o alternativas poss\u00edveis, entre elas a concess\u00e3o de microcr\u00e9dito mediante ag\u00eancia p\u00fablica de fomento a ser criada. Outra alternativa poss\u00edvel seria a concess\u00e3o de benef\u00edcios exclusivos nas contrata\u00e7\u00f5es p\u00fablicas, mas parte do parlamento local discorda das propostas apresentadas. Assim, o tema foi conduzido \u00e0 audi\u00eancia p\u00fablica na C\u00e2mara de Vereadores. A situa\u00e7\u00e3o apresentada se refere \u00e0 seguinte etapa do ciclo das pol\u00edticas p\u00fablicas:<br \/>(A) Pr\u00e9-defini\u00e7\u00e3o do problema p\u00fablico.<br \/>(B) Forma\u00e7\u00e3o da agenda p\u00fablica.<br \/>(C) Elabora\u00e7\u00e3o da pol\u00edtica p\u00fablica.<br \/>(D) Formula\u00e7\u00e3o da pol\u00edtica p\u00fablica.<br \/>(E) Implementa\u00e7\u00e3o da pol\u00edtica p\u00fablica.<\/p>\n\n\n\n<p>O gabarito preliminar da banca examinadora foi alternativa \u201cC\u201d. No entanto, esta quest\u00e3o precisa ser anulada, pois apresenta duas respostas corretas \u2013 alternativa C e D.<\/p>\n\n\n\n<p>No entendimento de Leonardo Secchi (2020, p.61), no que se refere ao ciclo de pol\u00edtica p\u00fablicas, a fase na qual os atores elencam alternativas poss\u00edveis de solu\u00e7\u00e3o de problemas \u00e9 denominada \u201cFormula\u00e7\u00e3o de Alternativas\u201d, ou seja, o Autor n\u00e3o denomina a fase de \u201celabora\u00e7\u00e3o\u201d. De acordo com o supracitado mestre,<\/p>\n\n\n\n<p>A formula\u00e7\u00e3o de alternativas de solu\u00e7\u00e3o se desenvolve por meio de estruturas formais ou informais das consequ\u00eancias do problema, e dos potenciais custos e benef\u00edcios de cada alternativa dispon\u00edvel.<\/p>\n\n\n\n<p>Capella (2018), na mesma linha, trata da formula\u00e7\u00e3o de pol\u00edticas p\u00fablicas como uma fase na qual as alternativas s\u00e3o analisadas, conforme trecho transcrito a seguir<\/p>\n\n\n\n<p>A defini\u00e7\u00e3o de alternativas, tema central do presente cap\u00edtulo, refere-se \u00e0 formula\u00e7\u00e3o propriamente dita, momento em que diferentes cursos de a\u00e7\u00e3o (alternativas, propostas, solu\u00e7\u00f5es,<br \/>a\u00e7\u00f5es) s\u00e3o avaliados para que seja definida uma forma de lidar com uma quest\u00e3o. Na defini\u00e7\u00e3o de Howlett e Mukherjee (2017):<\/p>\n\n\n\n<p>[\u2026] formula\u00e7\u00e3o \u00e9 o est\u00e1gio da produ\u00e7\u00e3o de pol\u00edticas em que uma variedade de op\u00e7\u00f5es dispon\u00edveis \u00e9 considerada e, em seguida, reduzida a um conjunto sobre o qual atores relevantes, especialmente o governo, podem concordar que sejam \u00fateis para lidar com uma quest\u00e3o de pol\u00edtica p\u00fablica (Howlett; Mukherjee, 2017, p. 06, tradu\u00e7\u00e3o nossa).<\/p>\n\n\n\n<p>Em outro trecho do livro, no mesmo cap\u00edtulo que se refere a fase de formula\u00e7\u00e3o de pol\u00edticas p\u00fablicas, a autora cita que quando uma proposta se mostra vi\u00e1vel, os empreendedores realizam debates e audi\u00eancias, conforme explicitado na quest\u00e3o da Banca. Segue a transcri\u00e7\u00e3o do trecho do livro:<\/p>\n\n\n\n<p>Os empreendedores atuam na estrutura\u00e7\u00e3o do debate interno das comunidades a respeito de poss\u00edveis mudan\u00e7as a serem introduzidas numa pol\u00edtica, defendendo rela\u00e7\u00f5es causais entre problemas e solu\u00e7\u00f5es, destacando aspectos de propostas que sejam adequados aos seus membros. Al\u00e9m disso, o empreendedor atua nas conex\u00f5es entre uma comunidade e outros grupos, por meio do estabelecimento de contato com diferentes audi\u00eancias, da difus\u00e3o e experimenta\u00e7\u00e3o de ideias<\/p>\n\n\n\n<p>(Capella, 2018, P. 106). Cabe considerar, tamb\u00e9m, que no dicion\u00e1rio, o sin\u00f4nimo de \u201celabora\u00e7\u00e3o\u201d pode ser<br \/>\u201cformula\u00e7\u00e3o\u201d.<br \/>(https:\/\/www.sinonimos.com.br\/elaboracao#:~:text=Cria%C3%A7%C3%A3o%20de%20ideias%2C%20teorias%2C%20obras,%2C%20delinea%C3%A7%C3%A3o%2C%20planejamento%2C%20planeamento.)<\/p>\n\n\n\n<p>Cria\u00e7\u00e3o de ideias, teorias, obras, projetos:<\/p>\n\n\n\n<p>2 cria\u00e7\u00e3o, concep\u00e7\u00e3o, formula\u00e7\u00e3o, idealiza\u00e7\u00e3o, idea\u00e7\u00e3o, imagina\u00e7\u00e3o, inven\u00e7\u00e3o, engendramento, delineamento, delinea\u00e7\u00e3o, planejamento, planeamento.<\/p>\n\n\n\n<p>Isso posto, n\u00e3o h\u00e1 como prosperar o gabarito apresentado pela banca, pois alguns autores denominam a fase de levantamento de alternativas tanto como \u201celabora\u00e7\u00e3o\u201d como \u201cformula\u00e7\u00e3o\u201d, demonstrando que a quest\u00e3o apresenta duas respostas corretas.<\/p>\n\n\n\n<p>Necess\u00e1rio se faz a devida anula\u00e7\u00e3o, atendendo ao princ\u00edpio da justi\u00e7a.<br \/>Capella, Ana Cl\u00e1udia Niedhardt. Formula\u00e7\u00e3o de Pol\u00edticas \/ Ana Cl\u00e1udia Niedhardt Capella.&#8211;Bras\u00edlia: Enap, 2018.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><span style=\"text-decoration: underline;\">Quest\u00e3o 45:<\/span><\/strong><\/p>\n\n\n\n<p>Uma Secretaria Municipal de Sa\u00fade levantou, durante a elabora\u00e7\u00e3o de seu planejamento estrat\u00e9gico, os seguintes fatores:<br \/>I. Profissionais competentes e engajados.<br \/>II. Dimensionamento inadequado das equipes.<br \/>III. Equipe aderente \u00e0 melhoria do processo.<br \/>IV. Equipamentos modernos.<br \/>V. Novas exig\u00eancias pelo Minist\u00e9rio da Sa\u00fade como requisito para transfer\u00eancia de recursos de procedimentos n\u00e3o previstos.<br \/>VI. Falta de estrutura f\u00edsica para expans\u00e3o.<br \/>VII. Dificuldade na integra\u00e7\u00e3o entre sistemas de informa\u00e7\u00e3o.<br \/>VIII. Inova\u00e7\u00f5es tecnologias em sa\u00fade.<br \/>IX. Contingenciamento or\u00e7ament\u00e1rio.<br \/>X. Transfer\u00eancias da Uni\u00e3o por emenda parlamentar.<br \/>Considerando a an\u00e1lise SWOT, assinale a afirmativa correta:<br \/>(A) Os fatores III, VIII e X s\u00e3o oportunidades.<br \/>(B) Os fatores II, V e IX s\u00e3o amea\u00e7as.<br \/>(C) Os fatores I, IV e VIII s\u00e3o for\u00e7as.<br \/>(D) Os fatores II, VI e IX s\u00e3o fraquezas.<br \/>(E) Os fatores V, VI e X s\u00e3o amea\u00e7as.<\/p>\n\n\n\n<p>O gabarito preliminar da banca examinadora foi a alternativa \u201cA\u201d, que aponta como oportunidades os fatores III, VIII e X., No entanto, analisando detalhadamente os itens verifica-se que o fator III &#8211; Equipe aderente \u00e0 melhoria do processo \u2013 n\u00e3o pode ser considerado uma oportunidade, pois a equipe \u00e9 elemento interno do Minist\u00e9rio e, no caso de ela estar aderente \u00e0 melhoria, \u00e9 considerado uma for\u00e7a, assim como o item I &#8211; Profissionais competentes e engajados; e o item IV &#8211; Equipamentos modernos.<\/p>\n\n\n\n<p>Por outro lado, na alternativa \u201cD\u201d, os fatores II, VI e IX s\u00e3o fraquezas. Analisando cada um dos itens da alternativa D, temos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>II. Dimensionamento inadequado das equipes \u2013 equipe \u00e9 elemento interno, e por estar mal dimensionada \u00e9 uma fraqueza do Minist\u00e9rio.<\/li>\n\n\n\n<li>VI. Falta de estrutura f\u00edsica para expans\u00e3o \u2013 estrutura \u00e9 fator interno e a falta \u00e9 uma fraqueza do Minist\u00e9rio.<\/li>\n\n\n\n<li>IX. Contingenciamento or\u00e7ament\u00e1rio \u2013 o or\u00e7amento \u00e9 do \u00f3rg\u00e3o, fator interno e o contingenciamento refere-se ao retardamento na execu\u00e7\u00e3o da programa\u00e7\u00e3o da despesa prevista por insufici\u00eancia de receita, ou seja, \u00e9 um fator que enfraquece internamente o minist\u00e9rio.<\/li>\n<\/ul>\n\n\n\n<p>Isto posto, solicita-se a mudan\u00e7a do gabarito para a alternativa D, conforme argumentos acima, pois indubitavelmente houve um equ\u00edvoco da banca examinadora.<\/p>\n\n\n\n<p><strong><span style=\"text-decoration: underline;\">PROVA TIPO 02 &#8211; VERDE<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-background has-medium-font-size\" style=\"background-color:#d9dbde\"><strong>Disciplina:<\/strong> <strong>Controle Externo<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><span style=\"text-decoration: underline;\">Quest\u00e3o 58<\/span><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"302\" height=\"306\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06162614\/image-128.png\" alt=\"\" class=\"wp-image-1440851\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06162614\/image-128.png 302w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06162614\/image-128-296x300.png 296w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06162614\/image-128-96x96.png 96w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06162614\/image-128-150x152.png 150w\" sizes=\"auto, (max-width: 302px) 100vw, 302px\" \/><\/figure>\n\n\n\n<p>Coment\u00e1rio:<\/p>\n\n\n\n<p>Segundo a quest\u00e3o, o Secret\u00e1rio de Sa\u00fade praticou ato potencialmente danoso ao er\u00e1rio. Ato seguinte, houve a instaura\u00e7\u00e3o de tomada de contas especial, que apurou d\u00e9bito e imputou a responsabilidade. Na sequ\u00eancia, o Tribunal de Contas, antes de pronunciar-se quanto ao m\u00e9rito das contas, concedeu o direito de defesa ao respons\u00e1vel.<\/p>\n\n\n\n<p>Nesse caso, seria indicada a alternativa correta sobre o \u201cjulgamento\u201d do Tribunal.<\/p>\n\n\n\n<p>A banca indicou como resposta correta a letra C, que disp\u00f5e que ser\u00e1 realizada a cita\u00e7\u00e3o dos respons\u00e1veis, para apresenta\u00e7\u00e3o de defesa.<\/p>\n\n\n\n<p>Contudo, a op\u00e7\u00e3o B tamb\u00e9m est\u00e1 de acordo com o Regimento Interno e a Lei Org\u00e2nica do TCE.<\/p>\n\n\n\n<p>Nesse sentido, a Lei Org\u00e2nica do Tribunal estabelece que:<\/p>\n\n\n\n<p>Art. 53. A Decis\u00e3o em Processo de Presta\u00e7\u00e3o ou Tomada de Contas pode ser preliminar, definitiva ou terminativa.<\/p>\n\n\n\n<p>\u00a7 1\u00ba Preliminar \u00e9 a decis\u00e3o pela qual o Relator ou o Tribunal, antes de se pronunciar quanto ao m\u00e9rito, resolve sobrestar o feito, ordenar a audi\u00eancia ou a CITA\u00c7\u00c3O dos respons\u00e1veis ou determinar outras dilig\u00eancias necess\u00e1rias ao saneamento do processo.<\/p>\n\n\n\n<p>Assim, a decis\u00e3o que ordena a cita\u00e7\u00e3o \u00e9 tamb\u00e9m uma decis\u00e3o preliminar. Justamente por isso, a op\u00e7\u00e3o B est\u00e1 correta, pois, antes de pronunciar-se quanto ao m\u00e9rito, o Tribunal dever\u00e1 realizar a cita\u00e7\u00e3o dos respons\u00e1veis para apresenta\u00e7\u00e3o de defesa, adotando, assim, uma decis\u00e3o preliminar. Essa, inclusive, \u00e9 a previs\u00e3o expressa da Lei Org\u00e2nica (art. 53, \u00a7 3\u00ba) e do Regimento Interno (art. 155, \u00a7 1\u00ba, I).<\/p>\n\n\n\n<p><strong>Por isso, prop\u00f5e-se a anula\u00e7\u00e3o da quest\u00e3o.<\/strong><\/p>\n\n\n\n<p class=\"has-background has-medium-font-size\" style=\"background-color:#d9dbde\"><strong>Disciplina:<\/strong> <strong>L\u00edngua Portuguesa<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><span style=\"text-decoration: underline;\">Quest\u00e3o 06<\/span><\/strong><\/p>\n\n\n\n<p>Pessoal, na quest\u00e3o 6, entendo que a banca considerou como correto um conceito errado de &#8220;trama&#8221;.<\/p>\n\n\n\n<p>Na alternativa C, dada como correta, a banca afirma que a discuss\u00e3o interior do personagem corresponde \u00e0 trama narrativa.<\/p>\n\n\n\n<p>A discuss\u00e3o interior do personagem \u00e9 o &#8220;conflito&#8221;, n\u00e3o \u00e9 a trama.<\/p>\n\n\n\n<p>Vejamos o conceito de TRAMA, segundo o consagrado especialista em teoria liter\u00e1ria Jo\u00e3o Batista Cardoso:<\/p>\n\n\n\n<p><strong><em>Ao conjunto de acontecimentos que se sucedem de modo ordenado numa est\u00f3ria, dos quais participam as personagens, \u00e9 dado o nome de a\u00e7\u00e3o, trama, intriga ou enredo.<\/em><\/strong><\/p>\n\n\n\n<p>Conforme veremos adiante, \u00e9 poss\u00edvel encontrar na teoria liter\u00e1ria, como sin\u00f4nimo de \u201cacontecimentos\u201d, os termos fatos, eventos ou acontecimentos marginais (como se refere CARDOSO, tratando por acontecimento, em sua obra, o enredo propriamente dito, sendo os acontecimentos marginais \u2018subconjuntos\u2019 do acontecimento principal do qual trata a narrativa).<\/p>\n\n\n\n<p>Segundo Gancho, a organiza\u00e7\u00e3o das partes de um enredo, bem como dos acontecimentos que o comp\u00f5em, \u00e9 determinada pelo conflito, o componente da est\u00f3ria gerador da tens\u00e3o que faz o enredo evolver e prende a aten\u00e7\u00e3o do apreciador \u00e0 mat\u00e9ria narrada. \u201cSeja entre dois personagens, seja entre o personagem e o ambiente, o conflito possibilita ao leitor-ouvinte criar expectativas frente aos fatos do enredo\u201d (GANCHO, 2004:10).<\/p>\n\n\n\n<p>Al\u00e9m disso, a alternativa E, dada como incorreta e, portanto, como gabarito, est\u00e1 certa. Realmente, arrepender-se&nbsp; voltar para a loja \u00e9 o desfecho da hist\u00f3ria, at\u00e9 o ponto em que est\u00e1 escrita na prova, \u00e9 o fim do conflito. Se havia outras etapas nessa narrativa, n\u00e3o foram apresentadas e n\u00e3o seria poss\u00edvel julgar que a \u00faltima etapa n\u00e3o era realmente a \u00faltima etapa.<\/p>\n\n\n\n<p>Segundo li\u00e7\u00e3o de C\u00e2ndida Vilares Gancho:<\/p>\n\n\n\n<p><strong><em>A conclus\u00e3o \u00e9 a parte do enredo que apresenta a solu\u00e7\u00e3o do conflito, revelando por completo, ao final, a ess\u00eancia da obra, sua mensagem, moral ou subtexto. Fazem parte da conclus\u00e3o o cl\u00edmax (momento culminante da est\u00f3ria) e o desfecho. Costuma apresentar o final da est\u00f3ria.<\/em><\/strong><\/p>\n\n\n\n<p><strong>BIBLIOGRAFIA:<\/strong><\/p>\n\n\n\n<p><strong>GANCHO, C\u00e2ndida Vilares. Como Analisar Narrativas. S\u00e3o Paulo: \u00c1tica, 1991<\/strong><\/p>\n\n\n\n<p>Portanto, solicita-se anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><span style=\"text-decoration: underline;\">Quest\u00e3o 0<\/span>7<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"436\" height=\"228\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180258\/image-139.png\" alt=\"\" class=\"wp-image-1440965\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180258\/image-139.png 436w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180258\/image-139-300x157.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180258\/image-139-150x78.png 150w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/><\/figure>\n\n\n\n<p>Ora, &#8220;muito&#8221; e &#8220;pouco&#8221; s\u00e3o ant\u00f4nimos perfeitos, dicionarizados. N\u00e3o h\u00e1 como negar que h\u00e1 real oposi\u00e7\u00e3o entre eles. Vejamos no pr\u00f3prio dicion\u00e1rio &#8220;Houaiss&#8221;, especificamente na aba ant\u00f4nimos:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"357\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180317\/image-140.png\" alt=\"\" class=\"wp-image-1440967\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180317\/image-140.png 567w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180317\/image-140-300x189.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180317\/image-140-150x94.png 150w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/figure>\n\n\n\n<p>Al\u00e9m disso, n\u00e3o podemos afirmar que &#8220;aprender&#8221; e &#8220;ensinar&#8221; s\u00e3o ant\u00f4nimos, muito menos &#8220;sempre&#8221; e &#8220;de repente&#8221;.<\/p>\n\n\n\n<p>A pr\u00f3pria banca, em quest\u00e3o anterior, estabeleceu como &#8220;oposi\u00e7\u00e3o&#8221; como sin\u00f4nimo de ant\u00f4nimo e deu como resposta a oposi\u00e7\u00e3o &#8220;todos\/ningu\u00e9m&#8221; e n\u00e3o considerou opostos &#8220;todos e poucos&#8221;, justamente porque a real oposi\u00e7\u00e3o de &#8220;poucos&#8221; \u00e9 &#8220;muitos&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"207\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180333\/image-141.png\" alt=\"\" class=\"wp-image-1440968\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180333\/image-141.png 567w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180333\/image-141-300x110.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180333\/image-141-150x55.png 150w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/figure>\n\n\n\n<p>Assim, ocorre contradi\u00e7\u00e3o entre gabaritos da pr\u00f3pria banca, bem como frontal conflito com informa\u00e7\u00f5es verific\u00e1veis em dicion\u00e1rios.<\/p>\n\n\n\n<p>Por isso, solicita-se anula\u00e7\u00e3o da quest\u00e3o.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background:linear-gradient(135deg,rgb(238,238,238) 0%,rgb(179,175,175) 37%,rgb(169,184,195) 100%);font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><strong>Concurso TCE PA: poss\u00edveis recursos de Auxiliar T\u00e9cnico de Controle Externo<\/strong><\/p>\n\n\n\n<p><strong><span style=\"text-decoration: underline;\">PROVA TIPO 01 &#8211; BRANCA<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-background has-medium-font-size\" style=\"background-color:#d9dbde\"><strong>Disciplina:<\/strong> <strong>No\u00e7\u00f5es de Administra\u00e7\u00e3o P\u00fablica<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><span style=\"text-decoration: underline;\">Quest\u00e3o 60<\/span><\/strong><\/p>\n\n\n\n<p>A corrup\u00e7\u00e3o \u00e9 um grande obst\u00e1culo para a efic\u00e1cia das pol\u00edticas p\u00fablicas, afetando a confian\u00e7a da popula\u00e7\u00e3o e a qualidade dos servi\u00e7os. Para combat\u00ea-la, \u00e9 fundamental implementar pol\u00edticas que promovam transpar\u00eancia, presta\u00e7\u00e3o de contas e participa\u00e7\u00e3o cidad\u00e3, al\u00e9m de fortalecer mecanismos de controle. Uma salvaguarda contra o desenvolvimento de estruturas regulat\u00f3rias corruptas pode ser conseguida por meio da<br \/>(A) Avalia\u00e7\u00e3o de Impacto Normativo.<br \/>(B) An\u00e1lise de Impacto Regulat\u00f3rio.<br \/>(C) An\u00e1lise de Impacto Normativo.<br \/>(D) Avalia\u00e7\u00e3o de Impacto Regulat\u00f3rio.<br \/>(E) Desvirtua\u00e7\u00e3o Regulat\u00f3ria.<\/p>\n\n\n\n<p>O gabarito preliminar da banca examinadora foi alternativa \u201cB\u201d. No entanto, esta quest\u00e3o precisa ser anulada, pois apresenta duas respostas corretas \u2013 alternativa D e B.<\/p>\n\n\n\n<p>A \u00fanica diferen\u00e7a entre as duas alternativas \u00e9 que na \u201cB\u201d trata de An\u00e1lise e na \u201cD\u201d trata de Avalia\u00e7\u00e3o. Ou seja, a quest\u00e3o n\u00e3o pede conhecimento t\u00e9cnico do tema, mas apenas a distin\u00e7\u00e3o sutil e sin\u00f4nima entre an\u00e1lise e avalia\u00e7\u00e3o, que na pr\u00e1tica e levando-se em considera\u00e7\u00e3o qualquer ciclo de implementa\u00e7\u00e3o, a an\u00e1lise e a avalia\u00e7\u00e3o fazem parte de uma mesma fase (um mesmo constructo), pois para que se proceda a avalia\u00e7\u00e3o, deve-se fazer a devida an\u00e1lise.<\/p>\n\n\n\n<p>Neste sentido, existem diversas publica\u00e7\u00f5es que afirmam que as duas palavras possuem pontos de contato e colaboram uma com a outra, com equil\u00edbrio entre ambas e eventual predom\u00ednio de uma ou de outra, conforme extrato a seguir:<\/p>\n\n\n\n<p>Pesquisa qualitativa e quantitativa, epidemiologia descritiva e anal\u00edtica, individual e coletivo s\u00e3o exemplos de paradigmas distintos que surgiram e se mantiveram polarizados mas que, cada vez mais, tem os pontos de contato reconhecidos, sem desmerecer suas diferen\u00e7as. Nesse sentido, avalia\u00e7\u00e3o e an\u00e1lise se distinguem pela maior vincula\u00e7\u00e3o com a pr\u00e1tica e atributos pr\u00e9vios da primeira e pela inten\u00e7\u00e3o em se distanciar e abstrair do objeto considerado por via de teorias pr\u00e9-estabelecidas, pela segunda. H\u00e1 colabora\u00e7\u00f5es poss\u00edveis entre as duas sob diversas combina\u00e7\u00f5es poss\u00edveis: de equil\u00edbrio entre ambas a eventual predom\u00ednio de uma ou outra, de acordo com o interesse dos pesquisadores, objeto e objetivo da investiga\u00e7\u00e3o.<\/p>\n\n\n\n<p>A nosso ver, a diferencia\u00e7\u00e3o constitui entrave quando presta servi\u00e7o ao estigma, mascara disputas ou reproduz posi\u00e7\u00f5es a serem superadas, como o desapre\u00e7o de parte do campo acad\u00eamico por quest\u00f5es pr\u00e1ticas. E a distin\u00e7\u00e3o pode ser oportuna quando permite delinear melhor espa\u00e7os diferentes e, no caso da avalia\u00e7\u00e3o, colabora para compreender melhor as potencialidades e limita\u00e7\u00f5es da mesma, sobretudo quando vivemos a utiliza\u00e7\u00e3o indiscriminada das avalia\u00e7\u00f5es desde o plano institucional at\u00e9 o cotidiano dos indiv\u00edduos, por meio de aplicativos presentes nos aparelhos de telefones celulares. (grifos nossos) Juarez Pereira Furtado; Max Felipe Vianna Gasparini. H\u00e1 diferen\u00e7as entre avaliar e analisar? OPINI\u00c3O \u2022 Ci\u00eanc. sa\u00fade coletiva 24(8). Ago 2019. https:\/\/doi.org\/10.1590\/1413-81232018248.25302017<\/p>\n\n\n\n<p>Nessa mesma linha, extra\u00edmos publica\u00e7\u00e3o do site https:\/\/faq-iso9001.portaliso.com\/o-que-e-analisar\/ referente aos termos utilizados pela ISO 9001 e o que se depreende \u00e9 que os termos an\u00e1lise e avalia\u00e7\u00e3o est\u00e3o associados \u00e0 verifica\u00e7\u00e3o, ou seja conceitos interdependentes, realizados muitas vezes numa mesma fase. Vejamos:<\/p>\n\n\n\n<p>A ISO 9001 utiliza diversas vezes esse termo, em sua maioria acompanhados, an\u00e1lise cr\u00edtica ou an\u00e1lise e avalia\u00e7\u00e3o.<\/p>\n\n\n\n<p>Analisar \u00e9 identificar quais fatores contribu\u00edram para o desempenho alcan\u00e7ado. \u00c9 conseguir distinguir e separar as partes, para entender e compreender melhor o todo. Por isso, a an\u00e1lise cr\u00edtica \u00e9 citada usualmente associada ao planejamento e a an\u00e1lise e avalia\u00e7\u00e3o \u00e9 citada associada \u00e0 verifica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Acrescenta-se que a \u201csalvaguarda contra o desenvolvimento de estruturas regulat\u00f3rias corruptas\u201d deve ser realizada mediante uma an\u00e1lise detalhada de todos os fatos e da avalia\u00e7\u00e3o do processo, para verificar se os atos regulat\u00f3rios promoveram ou permitiram a corrup\u00e7\u00e3o, pois somente a an\u00e1lise dos fatos n\u00e3o permite tal conclus\u00e3o e ju\u00edzo de valor.<\/p>\n\n\n\n<p>Isto posto, diante da dubiedade e ambiguidade de interpreta\u00e7\u00e3o que os conceitos de \u201can\u00e1lise\u201d e \u201cavalia\u00e7\u00e3o\u201d apresentam, solicita-se a anula\u00e7\u00e3o da quest\u00e3o, visando atender ao princ\u00edpio da justi\u00e7a a todos os candidatos.<\/p>\n\n\n\n<p><strong><span style=\"text-decoration: underline;\">PROVA TIPO 04 &#8211; AZUL<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-background has-medium-font-size\" style=\"background-color:#d9dbde\"><strong>Disciplina:<\/strong> <strong>L\u00edngua Portuguesa<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><span style=\"text-decoration: underline;\">Quest\u00e3o 08<\/span><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"426\" height=\"430\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180113\/image-138.png\" alt=\"\" class=\"wp-image-1440960\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180113\/image-138.png 426w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180113\/image-138-297x300.png 297w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180113\/image-138-150x151.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/08\/06180113\/image-138-96x96.png 96w\" sizes=\"auto, (max-width: 426px) 100vw, 426px\" \/><\/figure>\n\n\n\n<p>A banca considerou &#8220;por baixo do solo de Paris&#8221; um caso de uso &#8220;inadequado&#8221; de &#8220;baixo&#8221;.<\/p>\n\n\n\n<p>Esse gabarito contraria a li\u00e7\u00e3o b\u00e1sica de diversas gram\u00e1ticas consagradas, entre as quais cito a de Evanildo Bechara. A locu\u00e7\u00e3o prepositiva &#8220;por baixo de&#8221; existe e \u00e9 adequada, tendo em vista que o referente est\u00e1 &#8220;sob&#8221; o solo de Paris, debaixo do solo de Paris.<\/p>\n\n\n\n<p>BIBLIOGRAFIA:<\/p>\n\n\n\n<p><strong>bechara evanildo (2009). moderna gram\u00e1tica portuguesa. 37a ed. rio de janeiro editora nova fronteira (VERS\u00c3O DIGITAL, P\u00c1GINA 79)<\/strong><\/p>\n\n\n\n<p>Quer saber todos os detalhes do concurso TCE PA, cujos poss\u00edveis recursos das provas voc\u00ea conferiu AQUI, basta acessar o link abaixo:<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#f4f4f4;font-size:clamp(15.197px, 0.95rem + ((1vw - 3.2px) * 0.765), 23px);\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa\/\" target=\"_blank\" rel=\"noreferrer noopener\">TCE PA<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\"><em>Cursos para o concurso TCE PA<\/em><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-tcg\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Carreiras Controladorias<\/h3>\n        <p class=\"subtitulo-assinatura\">Estude conosco<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/tce-pa-tribunal-de-contas-do-estado-do-para\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a os cursos<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-controle-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Controle<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo domingo, 04, foram aplicadas as provas do concurso TCE PA (Tribunal de Contas do Estado do Par\u00e1) para Auditor de Controle Externo &#8211; \u00c1rea Fiscaliza\u00e7\u00e3o &#8211; Direito e Auxiliar T\u00e9cnico de Controle Externo. O Estrat\u00e9gia Concursos esteve presente durante toda sua prepara\u00e7\u00e3o (assim como nas corre\u00e7\u00f5es extraoficiais de Auditor e Auxiliar) e, mesmo [&hellip;]<\/p>\n","protected":false},"author":2134,"featured_media":1056979,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214710,220219],"tags":[],"tax_estado":[219977],"class_list":["post-1439676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais-de-contas","category-noticias","tax_estado-pa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso TCE PA: poss\u00edveis recursos de Auditor - Direito e Auxiliar<\/title>\n<meta name=\"description\" content=\"Concurso TCE PA: veja os poss\u00edveis recursos das provas de Auditor de Controle Externo - Direito e Auxiliar T\u00e9cnico de Controle Externo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso TCE PA: poss\u00edveis recursos de Auditor - Direito e Auxiliar\" \/>\n<meta property=\"og:description\" content=\"Concurso TCE PA: veja os poss\u00edveis recursos das provas de Auditor de Controle Externo - Direito e Auxiliar T\u00e9cnico de Controle Externo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-06T19:27:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T03:44:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela Teixeira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Teixeira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/\"},\"author\":{\"name\":\"Rafaela Teixeira\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1\"},\"headline\":\"Concurso TCE PA: poss\u00edveis recursos de Auditor &#8211; Direito e Auxiliar\",\"datePublished\":\"2024-08-06T19:27:38+00:00\",\"dateModified\":\"2024-08-08T03:44:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/\"},\"wordCount\":2932,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg\",\"articleSection\":[\"Tribunais de Contas (TCU, TCE, TCM)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/\",\"name\":\"Concurso TCE PA: poss\u00edveis recursos de Auditor - Direito e Auxiliar\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg\",\"datePublished\":\"2024-08-06T19:27:38+00:00\",\"dateModified\":\"2024-08-08T03:44:46+00:00\",\"description\":\"Concurso TCE PA: veja os poss\u00edveis recursos das provas de Auditor de Controle Externo - Direito e Auxiliar T\u00e9cnico de Controle Externo!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg\",\"width\":768,\"height\":432,\"caption\":\"Concurso TCE PA MPC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso TCE PA: poss\u00edveis recursos de Auditor &#8211; Direito e Auxiliar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1\",\"name\":\"Rafaela Teixeira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"caption\":\"Rafaela Teixeira\"},\"description\":\"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso TCE PA: poss\u00edveis recursos de Auditor - Direito e Auxiliar","description":"Concurso TCE PA: veja os poss\u00edveis recursos das provas de Auditor de Controle Externo - Direito e Auxiliar T\u00e9cnico de Controle Externo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso TCE PA: poss\u00edveis recursos de Auditor - Direito e Auxiliar","og_description":"Concurso TCE PA: veja os poss\u00edveis recursos das provas de Auditor de Controle Externo - Direito e Auxiliar T\u00e9cnico de Controle Externo!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-08-06T19:27:38+00:00","article_modified_time":"2024-08-08T03:44:46+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg","type":"image\/jpeg"}],"author":"Rafaela Teixeira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafaela Teixeira","Est. tempo de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/"},"author":{"name":"Rafaela Teixeira","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1"},"headline":"Concurso TCE PA: poss\u00edveis recursos de Auditor &#8211; Direito e Auxiliar","datePublished":"2024-08-06T19:27:38+00:00","dateModified":"2024-08-08T03:44:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/"},"wordCount":2932,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg","articleSection":["Tribunais de Contas (TCU, TCE, TCM)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/","name":"Concurso TCE PA: poss\u00edveis recursos de Auditor - Direito e Auxiliar","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg","datePublished":"2024-08-06T19:27:38+00:00","dateModified":"2024-08-08T03:44:46+00:00","description":"Concurso TCE PA: veja os poss\u00edveis recursos das provas de Auditor de Controle Externo - Direito e Auxiliar T\u00e9cnico de Controle Externo!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/07121320\/tce_pa.jpg","width":768,"height":432,"caption":"Concurso TCE PA MPC"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tce-pa-recursos-auditor-direito-e-auxiliar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso TCE PA: poss\u00edveis recursos de Auditor &#8211; Direito e Auxiliar"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1","name":"Rafaela Teixeira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","caption":"Rafaela Teixeira"},"description":"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no TRE-SP. Possui mais de 7 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica cont\u00ednua, an\u00e1lise de editais e obten\u00e7\u00e3o de informa\u00e7\u00f5es diretamente junto a \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior, respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de concursos p\u00fablicos, garantindo a continuidade, fluidez e confiabilidade das publica\u00e7\u00f5es e dos bastidores dos certames.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1439676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1439676"}],"version-history":[{"count":13,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1439676\/revisions"}],"predecessor-version":[{"id":1441761,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1439676\/revisions\/1441761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1056979"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1439676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1439676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1439676"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1439676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}