{"id":1436979,"date":"2024-07-30T08:21:10","date_gmt":"2024-07-30T11:21:10","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1436979"},"modified":"2024-07-30T08:21:12","modified_gmt":"2024-07-30T11:21:12","slug":"informativo-stj-818-comentado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/","title":{"rendered":"Informativo STJ 818 Comentado"},"content":{"rendered":"\n<p><\/p><p><span data-darkreader-inline-color=\"\" style=\"font-size: revert;color: initial;, sans-serif;--darkreader-inline-color: initial\">Mais um passo em nossa caminhada&#8230; Informativos n\u00ba 818 do STJ\u00a0<\/span><strong style=\"font-size: revert;color: initial;, sans-serif;--darkreader-inline-color: initial\" data-darkreader-inline-color=\"\">COMENTADO<\/strong><span data-darkreader-inline-color=\"\" style=\"font-size: revert;color: initial;, sans-serif;--darkreader-inline-color: initial\"> entra na parada. Simbora!<\/span><\/p><p class=\"has-text-align-center\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/30082057\/stj-informativo-818.pdf\" rel=\"sponsored nofollow\">DOWNLOAD do PDF AQUI!<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_UmDpMTpN5Xg\"><div id=\"lyte_UmDpMTpN5Xg\" data-src=\"\/\/i.ytimg.com\/vi\/UmDpMTpN5Xg\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/UmDpMTpN5Xg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/UmDpMTpN5Xg\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div>\n<\/div><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-administrativo\"><a>DIREITO ADMINISTRATIVO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-nbsp-nbsp-nbsp-nbsp-forma-de-calculo-da-tarifa-progressiva-dos-servicos-de-fornecimento-de-agua-e-de-esgoto-sanitario-em-unidades-compostas-por-varias-economias-e-hidrometro-unico\"><a>1.&nbsp;&nbsp;&nbsp;&nbsp; Forma de c\u00e1lculo da tarifa progressiva dos servi\u00e7os de fornecimento de \u00e1gua e de esgoto sanit\u00e1rio em unidades compostas por v\u00e1rias economias e hidr\u00f4metro \u00fanico<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>1. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 l\u00edcita a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento por meio da exig\u00eancia de uma parcela fixa (&#8220;tarifa m\u00ednima&#8221;), concebida sob a forma de franquia de consumo devida por cada uma das unidades consumidoras (economias); bem como por meio de uma segunda parcela, vari\u00e1vel e eventual, exigida apenas se o consumo real aferido pelo medidor \u00fanico do condom\u00ednio exceder a franquia de consumo de todas as unidades conjuntamente consideradas.<\/p>\n\n\n\n<p>2. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 ilegal a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento que, utilizando-se apenas do consumo real global, considere o condom\u00ednio como uma \u00fanica unidade de consumo (uma \u00fanica economia).<\/p>\n\n\n\n<p>3. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 ilegal a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento que, a partir de um hibridismo de regras e conceitos, dispense cada unidade de consumo do condom\u00ednio da tarifa m\u00ednima exigida a t\u00edtulo de franquia de consumo.<\/p>\n\n\n\n<p>REsp 1.937.887-RJ, Rel. Ministro Paulo S\u00e9rgio Domingues, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 20\/6\/2024, DJe 25\/6\/2024. (Tema 414). (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-1-nbsp-situacao-fatica\"><a>1.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Sabe aquelas casas compostas por v\u00e1rias economias e hidr\u00f4metro \u00fanico, ap\u00f3s a aferi\u00e7\u00e3o do consumo? Pois bem, questiona-se a forma de c\u00e1lculo da tarifa progressiva dos servi\u00e7os de fornecimento de \u00e1gua e de esgoto sanit\u00e1rio nessas unidades (Tema 414\/STJ).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-2-nbsp-analise-estrategica\"><a>1.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>1.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 11.445\/2007:<\/p>\n\n\n\n<p>Art. 29. Os servi\u00e7os p\u00fablicos de saneamento b\u00e1sico ter\u00e3o a sustentabilidade econ\u00f4mico-financeira assegurada por meio de remunera\u00e7\u00e3o pela cobran\u00e7a dos servi\u00e7os, e, quando necess\u00e1rio, por outras formas adicionais, como subs\u00eddios ou subven\u00e7\u00f5es, vedada a cobran\u00e7a em duplicidade de custos administrativos ou gerenciais a serem pagos pelo usu\u00e1rio, nos seguintes servi\u00e7os:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>I &#8211; de abastecimento de \u00e1gua e esgotamento sanit\u00e1rio, na forma de taxas, tarifas e outros pre\u00e7os p\u00fablicos, que poder\u00e3o ser estabelecidos para cada um dos servi\u00e7os ou para ambos, conjuntamente;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>II &#8211; de limpeza urbana e manejo de res\u00edduos s\u00f3lidos, na forma de taxas, tarifas e outros pre\u00e7os p\u00fablicos, conforme o regime de presta\u00e7\u00e3o do servi\u00e7o ou das suas atividades; e&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>III &#8211; de drenagem e manejo de \u00e1guas pluviais urbanas, na forma de tributos, inclusive taxas, ou tarifas e outros pre\u00e7os p\u00fablicos, em conformidade com o regime de presta\u00e7\u00e3o do servi\u00e7o ou das suas atividades.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7 1<sup>o<\/sup>&nbsp; Observado o disposto nos incisos I a III do caput deste artigo, a institui\u00e7\u00e3o das tarifas, pre\u00e7os p\u00fablicos e taxas para os servi\u00e7os de saneamento b\u00e1sico observar\u00e1 as seguintes diretrizes:<\/p>\n\n\n\n<p>I &#8211; prioridade para atendimento das fun\u00e7\u00f5es essenciais relacionadas \u00e0 sa\u00fade p\u00fablica;<\/p>\n\n\n\n<p>II &#8211; amplia\u00e7\u00e3o do acesso dos cidad\u00e3os e localidades de baixa renda aos servi\u00e7os;<\/p>\n\n\n\n<p>III &#8211; gera\u00e7\u00e3o dos recursos necess\u00e1rios para realiza\u00e7\u00e3o dos investimentos, objetivando o cumprimento das metas e objetivos do servi\u00e7o;<\/p>\n\n\n\n<p>IV &#8211; inibi\u00e7\u00e3o do consumo sup\u00e9rfluo e do desperd\u00edcio de recursos;<\/p>\n\n\n\n<p>V &#8211; recupera\u00e7\u00e3o dos custos incorridos na presta\u00e7\u00e3o do servi\u00e7o, em regime de efici\u00eancia;<\/p>\n\n\n\n<p>VI &#8211; remunera\u00e7\u00e3o adequada do capital investido pelos prestadores dos servi\u00e7os;<\/p>\n\n\n\n<p>VII &#8211; est\u00edmulo ao uso de tecnologias modernas e eficientes, compat\u00edveis com os n\u00edveis exigidos de qualidade, continuidade e seguran\u00e7a na presta\u00e7\u00e3o dos servi\u00e7os;<\/p>\n\n\n\n<p>VIII &#8211; incentivo \u00e0 efici\u00eancia dos prestadores dos servi\u00e7os.<\/p>\n\n\n\n<p>\u00a7 2\u00ba Poder\u00e3o ser adotados subs\u00eddios tarif\u00e1rios e n\u00e3o tarif\u00e1rios para os usu\u00e1rios que n\u00e3o tenham capacidade de pagamento suficiente para cobrir o custo integral dos servi\u00e7os.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7 3\u00ba As novas edifica\u00e7\u00f5es condominiais adotar\u00e3o padr\u00f5es de sustentabilidade ambiental que incluam, entre outros procedimentos, a medi\u00e7\u00e3o individualizada do consumo h\u00eddrico por unidade imobili\u00e1ria.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7 4\u00ba Na hip\u00f3tese de presta\u00e7\u00e3o dos servi\u00e7os sob regime de concess\u00e3o, as tarifas e pre\u00e7os p\u00fablicos ser\u00e3o arrecadados pelo prestador diretamente do usu\u00e1rio, e essa arrecada\u00e7\u00e3o ser\u00e1 facultativa em caso de taxas.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7 5\u00ba Os pr\u00e9dios, edif\u00edcios e condom\u00ednios que foram constru\u00eddos sem a individualiza\u00e7\u00e3o da medi\u00e7\u00e3o at\u00e9 a entrada em vigor da&nbsp;Lei n\u00ba 13.312, de 12 de julho de 2016, ou em que a individualiza\u00e7\u00e3o for invi\u00e1vel, pela onerosidade ou por raz\u00e3o t\u00e9cnica, poder\u00e3o instrumentalizar contratos especiais com os prestadores de servi\u00e7os, nos quais ser\u00e3o estabelecidos as responsabilidades, os crit\u00e9rios de rateio e a forma de cobran\u00e7a.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Art. 30. Observado o disposto no art. 29 desta Lei, a estrutura de remunera\u00e7\u00e3o e de cobran\u00e7a dos servi\u00e7os p\u00fablicos de saneamento b\u00e1sico considerar\u00e1 os seguintes fatores:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>I &#8211; categorias de usu\u00e1rios, distribu\u00eddas por faixas ou quantidades crescentes de utiliza\u00e7\u00e3o ou de consumo;<\/p>\n\n\n\n<p>II &#8211; padr\u00f5es de uso ou de qualidade requeridos;<\/p>\n\n\n\n<p>III &#8211; quantidade m\u00ednima de consumo ou de utiliza\u00e7\u00e3o do servi\u00e7o, visando \u00e0 garantia de objetivos sociais, como a preserva\u00e7\u00e3o da sa\u00fade p\u00fablica, o adequado atendimento dos usu\u00e1rios de menor renda e a prote\u00e7\u00e3o do meio ambiente;<\/p>\n\n\n\n<p>IV &#8211; custo m\u00ednimo necess\u00e1rio para disponibilidade do servi\u00e7o em quantidade e qualidade adequadas;<\/p>\n\n\n\n<p>V &#8211; ciclos significativos de aumento da demanda dos servi\u00e7os, em per\u00edodos distintos; e<\/p>\n\n\n\n<p>VI &#8211; capacidade de pagamento dos consumidores.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-2-nbsp-nbsp-nbsp-licita-a-exigencia-de-tarifa-minima\"><a>1.2.2.&nbsp;&nbsp;&nbsp; L\u00edcita a exig\u00eancia de tarifa m\u00ednima?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeap!!!!<\/strong><\/p>\n\n\n\n<p><strong>As diretrizes para institui\u00e7\u00e3o da tarifa de \u00e1gua e esgoto, previstas no art. 29 da Lei n. 11.445\/2007<\/strong>, assim como os fatores a serem considerados na estrutura de remunera\u00e7\u00e3o e cobran\u00e7a pelos servi\u00e7os de saneamento, expostos no art. 30 do mesmo diploma legal, <strong>n\u00e3o s\u00e3o regras jur\u00eddicas inseridas aleatoriamente pelo legislador no marco regulat\u00f3rio do saneamento b\u00e1sico adotado no Brasil<\/strong>. Muito ao contr\u00e1rio: decorrem do modelo econ\u00f4mico alinhavado para o desenvolvimento do mercado de presta\u00e7\u00e3o dos servi\u00e7os p\u00fablicos de \u00e1gua e esgoto, modelo esse estruturado em um regime de monop\u00f3lio natural.<\/p>\n\n\n\n<p>A previsibilidade quanto \u00e0s receitas futuras decorrentes da execu\u00e7\u00e3o dos servi\u00e7os de saneamento \u00e9 obtida por meio da estrutura\u00e7\u00e3o em duas etapas da contrapresta\u00e7\u00e3o (tarifa) devida pelos servi\u00e7os prestados: a primeira, por meio da outorga de uma franquia de consumo ao usu\u00e1rio (parcela fixa da tarifa cobrada); e a segunda, por meio da cobran\u00e7a pelo consumo eventualmente excedente \u00e0quele franqueado, aferido por meio do medidor correspondente (parcela vari\u00e1vel da tarifa).<\/p>\n\n\n\n<p>A parcela fixa, ou franquia de consumo, tem uma finalidade essencial: assegurar \u00e0 prestadora do servi\u00e7o de saneamento receitas recorrentes, necess\u00e1rias para fazer frente aos custos fixos elevados do neg\u00f3cio tal como estruturado, no qual n\u00e3o se obedece \u00e0 l\u00f3gica do livre mercado, pois a interven\u00e7\u00e3o estatal imp\u00f5e a realiza\u00e7\u00e3o de investimentos irrecuper\u00e1veis em nome do interesse p\u00fablico, al\u00e9m de subs\u00eddios tarif\u00e1rios \u00e0s camadas mais vulner\u00e1veis da popula\u00e7\u00e3o. A parcela vari\u00e1vel, por sua vez, embora seja fonte relevante de receita, destina-se primordialmente ao atendimento do interesse p\u00fablico de inibir o consumo irrespons\u00e1vel de um bem cada vez mais escasso (\u00e1gua), obedecendo \u00e0 ideia-for\u00e7a de que paga mais quem consome mais.<\/p>\n\n\n\n<p>A parcela fixa \u00e9 um componente necess\u00e1rio da tarifa, pois remunera a prestadora por um servi\u00e7o essencial colocado \u00e0 disposi\u00e7\u00e3o do consumidor, e, por consequ\u00eancia, \u00e9 cobrada independentemente de qual seja o consumo real de \u00e1gua aferido pelo medidor, desde que esse consumo esteja situado entre o m\u00ednimo (zero metros c\u00fabicos) e o teto (tantos metros c\u00fabicos quantos previstos nas normais locais) da franquia de consumo outorgada ao usu\u00e1rio. A parcela vari\u00e1vel, a seu turno, \u00e9 um componente eventual da tarifa, podendo ou n\u00e3o ser cobrada a depender, sempre, do consumo real de \u00e1gua aferido pelo medidor, considerado, para tanto, o consumo que tenha excedido o teto da franquia, que j\u00e1 fora paga por meio da cobran\u00e7a da componente fixa da tarifa.<\/p>\n\n\n\n<p>A an\u00e1lise cr\u00edtica e comparativa das metodologias de c\u00e1lculo da tarifa de \u00e1gua e esgoto de condom\u00ednios dotados de um \u00fanico hidr\u00f4metro permite afirmar que os m\u00e9todos do consumo real global e do consumo real fracionado (mais conhecido como &#8220;modelo h\u00edbrido&#8221;) n\u00e3o atendem aos fatores e diretrizes de estrutura\u00e7\u00e3o da tarifa previstos nos arts. 29 e 30 da Lei n. 11.445\/2007, criando assimetrias no modelo legal de regula\u00e7\u00e3o da presta\u00e7\u00e3o dos servi\u00e7os da \u00e1rea do saneamento b\u00e1sico que ora colocam o condom\u00ednio dotado de um \u00fanico hidr\u00f4metro em uma posi\u00e7\u00e3o de injustific\u00e1vel vantagem jur\u00eddica e econ\u00f4mica (modelo h\u00edbrido), ora o colocam em uma posi\u00e7\u00e3o de intoler\u00e1vel desvantagem, elevando \u00e0s alturas as tarifas a partir de uma fic\u00e7\u00e3o despropositada, que toma o condom\u00ednio como se fora um \u00fanico usu\u00e1rio dos servi\u00e7os, os quais, na realidade, s\u00e3o usufru\u00eddos de maneira independente por cada unidade condominial.<\/p>\n\n\n\n<p>Descartadas que sejam, ent\u00e3o, essas duas formas de c\u00e1lculo das tarifas para os condom\u00ednios dotados de um \u00fanico hidr\u00f4metro, coloca-se diante do Tribunal um estado de coisas desafiador, dado que a metodologia remanescente (consumo individual presumido ou franqueado), que permitiria ao prestador dos servi\u00e7os de saneamento b\u00e1sico exigir de cada unidade de consumo (economia) do condom\u00ednio uma &#8220;tarifa m\u00ednima&#8221; a t\u00edtulo de franquia de consumo, vem a ser justamente aquela considerada il\u00edcita nos termos do julgamento que edificou o&nbsp;Tema 414\/STJ&nbsp;(REsp n. 1.166.561\/RJ). N\u00e3o se verifica, entretanto, raz\u00e3o jur\u00eddica ou econ\u00f4mica que justifique manter o entendimento jurisprudencial consolidado quando do julgamento, em 2010, do REsp n. 1.166.561\/RJ, perpetuando-se um tratamento anti-ison\u00f4mico entre unidades de consumo de \u00e1gua e esgoto baseado exclusivamente na exist\u00eancia ou inexist\u00eancia de medidor individualizado, tratamento esse que n\u00e3o atende aos fatores e diretrizes de estrutura\u00e7\u00e3o tarif\u00e1ria estabelecidos nos arts. 29 e 30 da Lei n. 11.445\/2007.<\/p>\n\n\n\n<p>\u00c9 preciso, enfim, rever esse entendimento a fim de super\u00e1-lo, evitando-se, assim, que alguns consumidores usufruam de posi\u00e7\u00e3o injustificadamente privilegiada, j\u00e1 que desobrigados de arcar com a franquia de consumo &#8211; parcela fixa da tarifa de saneamento b\u00e1sico &#8211; que de todos \u00e9 exigida, e cuja&nbsp;<em>ratio essendi<\/em>&nbsp;\u00e9 a amortiza\u00e7\u00e3o dos custos fixos incorridos pelas prestadoras dos servi\u00e7os para torn\u00e1-los universais, eficientes e perenemente dispon\u00edveis, e para que sejam oferecidos a popula\u00e7\u00f5es economicamente vulner\u00e1veis de forma subsidiada.<\/p>\n\n\n\n<p>Dessa forma, s\u00e3o fixadas as seguintes teses jur\u00eddicas de efic\u00e1cia vinculante, sintetizadoras da<em>&nbsp;ratio decidendi<\/em>&nbsp;deste julgado paradigm\u00e1tico de supera\u00e7\u00e3o do REsp n. 1.166.561\/RJ e de revis\u00e3o do&nbsp;Tema 414\/STJ: &#8220;1. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 l\u00edcita a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento por meio da exig\u00eancia de uma parcela fixa (&#8220;tarifa m\u00ednima&#8221;), concebida sob a forma de franquia de consumo devida por cada uma das unidades consumidoras (economias); bem como por meio de uma segunda parcela, vari\u00e1vel e eventual, exigida apenas se o consumo real aferido pelo medidor \u00fanico do condom\u00ednio exceder a franquia de consumo de todas as unidades conjuntamente consideradas. 2. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 ilegal a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento que, utilizando-se apenas do consumo real global, considere o condom\u00ednio como uma \u00fanica unidade de consumo (uma \u00fanica economia). 3. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 ilegal a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento que, a partir de um hibridismo de regras e conceitos, dispense cada unidade de consumo do condom\u00ednio da tarifa m\u00ednima exigida a t\u00edtulo de franquia de consumo.&#8221;<\/p>\n\n\n\n<p>Trata-se, ademais, <strong>de evolu\u00e7\u00e3o substancial da jurisprud\u00eancia que bem se amolda \u00e0 previs\u00e3o do art. 927, \u00a7 3\u00ba, do CPC, de modo a autorizar a parcial modula\u00e7\u00e3o de efeitos do julgamento, a fim de que \u00e0s prestadoras dos servi\u00e7os de saneamento b\u00e1sico seja declarado l\u00edcito modificar o m\u00e9todo de c\u00e1lculo da tarifa de \u00e1gua e esgoto nos casos em que, por conta de a\u00e7\u00e3o revisional de tarifa ajuizada por condom\u00ednio, esteja sendo adotado o &#8220;modelo h\u00edbrido<\/strong>&#8220;. Entretanto, fica vedado, para fins de modula\u00e7\u00e3o e em nome da seguran\u00e7a jur\u00eddica e do interesse social, que sejam cobrados dos condom\u00ednios quaisquer valores pret\u00e9ritos por eventuais pagamentos a menor decorrentes da ado\u00e7\u00e3o do chamado &#8220;modelo h\u00edbrido&#8221;.<\/p>\n\n\n\n<p>Nos casos em que a prestadora dos servi\u00e7os de saneamento b\u00e1sico tenha calculado a tarifa devida pelos condom\u00ednios dotados de medidor \u00fanico tomando-os como um \u00fanico usu\u00e1rio dos servi\u00e7os (uma economia apenas), mant\u00e9m-se o dever de modificar o m\u00e9todo de c\u00e1lculo da tarifa, sem embargo, entretanto, do direito do condom\u00ednio de ser ressarcido pelos valores pagos a maior e autorizando-se que a restitui\u00e7\u00e3o do ind\u00e9bito seja feita pelas prestadoras por meio de compensa\u00e7\u00e3o entre o montante restitu\u00edvel com parcelas vincendas da pr\u00f3pria tarifa de saneamento devida pelo condom\u00ednio, at\u00e9 integral extin\u00e7\u00e3o da obriga\u00e7\u00e3o, respeitado o prazo prescricional. Na restitui\u00e7\u00e3o do ind\u00e9bito, modulam-se os efeitos do julgamento de modo a afastar a dobra do art. 42, par\u00e1grafo \u00fanico, do CDC, \u00e0 compreens\u00e3o de que a din\u00e2mica da evolu\u00e7\u00e3o jurisprudencial relativa ao tema conferiu certa escusabilidade \u00e0 conduta da prestadora dos servi\u00e7os.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>1.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>1. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 l\u00edcita a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento por meio da exig\u00eancia de uma parcela fixa (&#8220;tarifa m\u00ednima&#8221;), concebida sob a forma de franquia de consumo devida por cada uma das unidades consumidoras (economias); bem como por meio de uma segunda parcela, vari\u00e1vel e eventual, exigida apenas se o consumo real aferido pelo medidor \u00fanico do condom\u00ednio exceder a franquia de consumo de todas as unidades conjuntamente consideradas.<\/p>\n\n\n\n<p>2. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 ilegal a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento que, utilizando-se apenas do consumo real global, considere o condom\u00ednio como uma \u00fanica unidade de consumo (uma \u00fanica economia).<\/p>\n\n\n\n<p>3. Nos condom\u00ednios formados por m\u00faltiplas unidades de consumo (economias) e um \u00fanico hidr\u00f4metro \u00e9 ilegal a ado\u00e7\u00e3o de metodologia de c\u00e1lculo da tarifa devida pela presta\u00e7\u00e3o dos servi\u00e7os de saneamento que, a partir de um hibridismo de regras e conceitos, dispense cada unidade de consumo do condom\u00ednio da tarifa m\u00ednima exigida a t\u00edtulo de franquia de consumo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-nbsp-nbsp-nbsp-nbsp-dever-de-reparacao-ambiental-do-expropriado\"><a>2.&nbsp;&nbsp;&nbsp;&nbsp; Dever de repara\u00e7\u00e3o ambiental do expropriado<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO EM RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>O expropriado n\u00e3o tem o dever de pagar pela <a>repara\u00e7\u00e3o do dano ambiental no bem desapropriado<\/a>, podendo responder, no entanto, por eventual dano moral coletivo.<\/p>\n\n\n\n<p>AREsp 1.886.951-RJ, Rel. Ministro Gurgel de Faria, Primeira Turma, por maioria, julgado em 11\/6\/2024, DJe 20\/6\/2024. (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-1-nbsp-situacao-fatica\"><a>2.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O MP ajuizou A\u00e7\u00e3o Civil P\u00fablica pretendendo condenar Tadeu \u00e0 repara\u00e7\u00e3o de dano ambiental alegadamente causado em im\u00f3vel de propriedade deste. Ocorre que, durante o andamento de tal processo, o Munic\u00edpio iniciou procedimento de desapropria\u00e7\u00e3o do im\u00f3vel. Mesmo ap\u00f3s a desapropria\u00e7\u00e3o, o MP insiste na condena\u00e7\u00e3o do rapaz ao pagamento de dano moral coletivo, bem como \u00e0 repara\u00e7\u00e3o do dano ambiental.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-2-nbsp-analise-estrategica\"><a>2.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>2.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>S\u00famula n. 623 do STJ: As obriga\u00e7\u00f5es ambientais possuem natureza propter rem, sendo admiss\u00edvel cobr\u00e1-las do propriet\u00e1rio ou possuidor atual e\/ou dos anteriores, \u00e0 escolha do credor.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-2-nbsp-nbsp-nbsp-deve-reparar-o-dano-ambiental\"><a>2.2.2.&nbsp;&nbsp;&nbsp; Deve reparar o dano ambiental?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Em parte!!!!<\/strong><\/p>\n\n\n\n<p>Inicialmente, ressalte-se que nos termos da S\u00famula n. 623 do STJ, &#8220;as obriga\u00e7\u00f5es ambientais possuem natureza&nbsp;<em>propter rem<\/em>, sendo admiss\u00edvel cobr\u00e1-las do propriet\u00e1rio ou possuidor atual e\/ou dos anteriores, \u00e0 escolha do credor&#8221;; e do Tema repetitivo n. 1204, cuja tese jur\u00eddica detalha que &#8220;as obriga\u00e7\u00f5es ambientais possuem natureza&nbsp;<em>propter rem<\/em>, sendo poss\u00edvel exigi-las, \u00e0 escolha do credor, do propriet\u00e1rio ou possuidor atual, de qualquer dos anteriores, ou de ambos, ficando isento de responsabilidade o alienante cujo direito real tenha cessado antes da causa\u00e7\u00e3o do dano, desde que para ele n\u00e3o tenha concorrido, direta ou indiretamente&#8221;.<\/p>\n\n\n\n<p>Todavia, o caso em an\u00e1lise se distingue da supracitada orienta\u00e7\u00e3o quanto \u00e0 possibilidade de cobrar a repara\u00e7\u00e3o do dano tanto do propriet\u00e1rio atual quanto do anterior, visto que no representativo da controv\u00e9rsia se trata de aquisi\u00e7\u00e3o derivada da propriedade (transfer\u00eancia volunt\u00e1ria), ao passo que aqui se est\u00e1 diante de aquisi\u00e7\u00e3o origin\u00e1ria por desapropria\u00e7\u00e3o, que tem contornos pr\u00f3prios e distintos.<\/p>\n\n\n\n<p>Nesse contexto, o art. 31 do Decreto-Lei n. 3.365\/1941 disciplina que &#8220;ficam sub-rogados no pre\u00e7o quaisquer \u00f4nus ou direitos que recaiam sobre o bem expropriado&#8221;.<\/p>\n\n\n\n<p>Isso implica dizer que <strong>o \u00f4nus de repara\u00e7\u00e3o que reca\u00eda sobre o bem (de natureza hist\u00f3rico-cultural) expropriado j\u00e1 foi considerado no pre\u00e7o (justa indeniza\u00e7\u00e3o) que foi desembolsado pelo Munic\u00edpio para a aquisi\u00e7\u00e3o do im\u00f3vel, isto \u00e9, a Fazenda municipal j\u00e1 descontou o passivo ambiental do valor pago<\/strong>.<\/p>\n\n\n\n<p>Diante desse quadro superveniente, a condena\u00e7\u00e3o da parte expropriada no dever de pagar pela repara\u00e7\u00e3o do im\u00f3vel desapropriado implicaria viola\u00e7\u00e3o do postulado do&nbsp;<em>non bis in idem<\/em>, uma vez que o particular amargaria duplo preju\u00edzo pelo mesmo fato: perceberia indeniza\u00e7\u00e3o j\u00e1 descontada em raz\u00e3o do passivo ambiental e ainda teria que pag\u00e1-lo (o passivo) novamente na a\u00e7\u00e3o civil p\u00fablica.<\/p>\n\n\n\n<p>Desse modo, embora a obriga\u00e7\u00e3o de repara\u00e7\u00e3o ambiental permane\u00e7a de natureza&nbsp;<em>propter rem<\/em>, competir\u00e1 ao ente expropriante atend\u00ea-la (a obriga\u00e7\u00e3o), pois o valor relativo ao passivo ambiental j\u00e1 deve ter sido exclu\u00eddo da indeniza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por outro lado, <strong>\u00e9 poss\u00edvel reconhecer a legitimidade passiva do particular em rela\u00e7\u00e3o ao dever, em tese, de reparar o suposto dano moral coletivo, pois, nesse caso, a obriga\u00e7\u00e3o ou o \u00f4nus n\u00e3o est\u00e3o relacionados ao pr\u00f3prio bem, inexistindo sub-roga\u00e7\u00e3o no pre\u00e7o<\/strong>. O dano moral, nessa modalidade, \u00e9 experimentado pela coletividade em car\u00e1ter difuso, de modo que o dever de indenizar \u00e9 completamente independente do destino do im\u00f3vel expropriado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>2.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>O expropriado n\u00e3o tem o dever de pagar pela repara\u00e7\u00e3o do dano ambiental no bem desapropriado, podendo responder, no entanto, por eventual dano moral coletivo.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-civil\"><a>DIREITO PROCESSUAL CIVIL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-nbsp-nbsp-nbsp-nbsp-fixacao-de-honorarios-em-cumprimento-de-sentenca-que-resulta-em-expedicao-de-rpv\"><a>3.&nbsp;&nbsp;&nbsp;&nbsp; Fixa\u00e7\u00e3o de honor\u00e1rios em cumprimento de senten\u00e7a que resulta em expedi\u00e7\u00e3o de RPV<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>Na aus\u00eancia de impugna\u00e7\u00e3o \u00e0 pretens\u00e3o execut\u00f3ria, n\u00e3o s\u00e3o devidos honor\u00e1rios advocat\u00edcios sucumbenciais em cumprimento de senten\u00e7a contra a Fazenda P\u00fablica, ainda que o cr\u00e9dito esteja submetido a pagamento por meio de Requisi\u00e7\u00e3o de Pequeno Valor &#8211; RPV.<\/p>\n\n\n\n<p>REsp 2.029.636-SP, Rel. Ministro Herman Benjamin, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 20\/6\/2024. (Tema 1190). (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-1-nbsp-situacao-fatica\"><a>3.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Em um cumprimento de senten\u00e7a n\u00e3o impugnado pela Fazenda P\u00fablica que resultaria no pagamento por meio de RPV, n\u00e3o foram fixados honor\u00e1rios advocat\u00edcios sucumbenciais, uma vez considerado que n\u00e3o houve resist\u00eancia da parte contr\u00e1ria.<\/p>\n\n\n\n<p>Por\u00e9m, os advogados exequentes defendem que a previs\u00e3o do art. 85, \u00a7 7\u00ba, do CPC, tem aplicabilidade limitada aos casos que ensejem a expedi\u00e7\u00e3o de precat\u00f3rios, n\u00e3o afastando os honor\u00e1rios na hip\u00f3tese de pagamento via RPV.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-2-nbsp-analise-estrategica\"><a>3.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>3.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei 9.494\/97:<\/p>\n\n\n\n<p>Art. 1o-D.&nbsp; N\u00e3o ser\u00e3o devidos honor\u00e1rios advocat\u00edcios pela Fazenda P\u00fablica nas execu\u00e7\u00f5es n\u00e3o embargadas.<\/p>\n\n\n\n<p>CPC:<\/p>\n\n\n\n<p>Art. 523. No caso de condena\u00e7\u00e3o em quantia certa, ou j\u00e1 fixada em liquida\u00e7\u00e3o, e no caso de decis\u00e3o sobre parcela incontroversa, o cumprimento definitivo da senten\u00e7a far-se-\u00e1 a requerimento do exequente, sendo o executado intimado para pagar o d\u00e9bito, no prazo de 15 (quinze) dias, acrescido de custas, se houver.<\/p>\n\n\n\n<p><a><\/a>\u00a7 1\u00ba N\u00e3o ocorrendo pagamento volunt\u00e1rio no prazo do&nbsp;caput&nbsp;, o d\u00e9bito ser\u00e1 acrescido de multa de dez por cento e, tamb\u00e9m, de honor\u00e1rios de advogado de dez por cento.<\/p>\n\n\n\n<p>Art. 535. A Fazenda P\u00fablica ser\u00e1 intimada na pessoa de seu representante judicial, por carga, remessa ou meio eletr\u00f4nico, para, querendo, no prazo de 30 (trinta) dias e nos pr\u00f3prios autos, impugnar a execu\u00e7\u00e3o, podendo arguir:<\/p>\n\n\n\n<p>\u00a7 3\u00ba N\u00e3o impugnada a execu\u00e7\u00e3o ou rejeitadas as argui\u00e7\u00f5es da executada:<\/p>\n\n\n\n<p><a><\/a><a><\/a>II &#8211; por ordem do juiz, dirigida \u00e0 autoridade na pessoa de quem o ente p\u00fablico foi citado para o processo, o pagamento de obriga\u00e7\u00e3o de pequeno valor ser\u00e1 realizado no prazo de 2 (dois) meses contado da entrega da requisi\u00e7\u00e3o, mediante dep\u00f3sito na ag\u00eancia de banco oficial mais pr\u00f3xima da resid\u00eancia do exequente.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-2-nbsp-nbsp-nbsp-devidos-os-honorarios-sucumbenciais\"><a>3.2.2.&nbsp;&nbsp;&nbsp; Devidos os honor\u00e1rios sucumbenciais?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Negativo!!!<\/strong><\/p>\n\n\n\n<p>O Superior Tribunal de Justi\u00e7a tem decidido que, quando o cr\u00e9dito est\u00e1 sujeito ao regime da Requisi\u00e7\u00e3o de Pequeno Valor &#8211; RPV, \u00e9 cab\u00edvel a fixa\u00e7\u00e3o dos honor\u00e1rios advocat\u00edcios em cumprimento de senten\u00e7a contra a Fazenda P\u00fablica, independentemente da exist\u00eancia de impugna\u00e7\u00e3o \u00e0 pretens\u00e3o execut\u00f3ria.<\/p>\n\n\n\n<p>A quest\u00e3o remonta ao decidido pela Corte Especial no julgamento dos EREsp n. 217883\/RS, em 2003. Na ocasi\u00e3o, firmou-se o entendimento de que, na execu\u00e7\u00e3o de t\u00edtulo judicial, ainda que n\u00e3o embargada, os honor\u00e1rios sucumbenciais seriam devidos, mesmo que o pagamento estivesse submetido ao precat\u00f3rio.<\/p>\n\n\n\n<p>Contudo, a vig\u00eancia da MP 2.180-35, de 24.8.2001, que acrescentou \u00e0 Lei n. 9.494\/1997 o art. 1\u00ba-D, alterou o quadro normativo a respeito da mat\u00e9ria e disp\u00f4s que n\u00e3o seriam devidos honor\u00e1rios advocat\u00edcios pela Fazenda P\u00fablica nas execu\u00e7\u00f5es n\u00e3o embargadas.<\/p>\n\n\n\n<p>O Supremo Tribunal Federal, ao julgar o Recurso Extraordin\u00e1rio n. 420.816\/PR, confirmou a constitucionalidade do art. 1\u00ba-D da Lei 9.494\/97. A raz\u00e3o para tal consiste na impossibilidade de o ente p\u00fablico adimplir espontaneamente a obriga\u00e7\u00e3o de pagar quantia certa sujeita ao regime dos precat\u00f3rios. Entretanto, conferiu-lhe a interpreta\u00e7\u00e3o de que a norma n\u00e3o se aplica \u00e0s execu\u00e7\u00f5es de obriga\u00e7\u00f5es legalmente definidas como de pequeno valor, visto que, em tal situa\u00e7\u00e3o, o processo executivo se acha excepcionalmente exclu\u00eddo do regime a que alude o art. 100,&nbsp;<em>caput<\/em>, da Constitui\u00e7\u00e3o Federal de1988.<\/p>\n\n\n\n<p>Na mesma linha do precedente do STF, a Primeira Se\u00e7\u00e3o do STJ, no julgamento dos EREsp n. 676.719\/SC, Rel. Ministro Jos\u00e9 Delgado, passou a afirmar que n\u00e3o mais seriam cab\u00edveis honor\u00e1rios sucumbenciais em execu\u00e7\u00e3o de obriga\u00e7\u00e3o submetida a pagamento por precat\u00f3rio, desde que n\u00e3o embargada. Quanto \u00e0s obriga\u00e7\u00f5es de pequeno valor, fixou-se o entendimento de que os honor\u00e1rios sucumbenciais s\u00e3o devidos, independentemente de impugna\u00e7\u00e3o.<\/p>\n\n\n\n<p>A partir de ent\u00e3o, a jurisprud\u00eancia do STJ consolidou-se no sentido de que &#8220;os honor\u00e1rios advocat\u00edcios de sucumb\u00eancia s\u00e3o devidos nas execu\u00e7\u00f5es contra a Fazenda sujeitas ao regime de requisi\u00e7\u00e3o de pequeno valor &#8211; RPV, ainda que n\u00e3o seja apresentada impugna\u00e7\u00e3o.&#8221; (AgInt no REsp n. 2.021.231\/SC, Rel. Ministro Paulo S\u00e9rgio Domingues, Primeira Turma, DJe 10\/3\/2023).<\/p>\n\n\n\n<p>Ocorre que, o C\u00f3digo de Processo Civil de 2015 trouxe novo regramento a respeito da mat\u00e9ria, a qual voltou a ser debatida e merece passar por um novo olhar. Segundo disp\u00f5e, em seu art. 85, \u00a7\u00a7 1\u00ba e 7\u00ba: &#8220;Art. 85. A senten\u00e7a condenar\u00e1 o vencido a pagar honor\u00e1rios ao advogado do vencedor. \u00a7 1\u00ba S\u00e3o devidos honor\u00e1rios advocat\u00edcios na reconven\u00e7\u00e3o, no cumprimento de senten\u00e7a, provis\u00f3rio ou definitivo, na execu\u00e7\u00e3o, resistida ou n\u00e3o, e nos recursos interpostos, cumulativamente. (&#8230;) \u00a7 7\u00ba N\u00e3o ser\u00e3o devidos honor\u00e1rios no cumprimento de senten\u00e7a contra a Fazenda P\u00fablica que enseje expedi\u00e7\u00e3o de precat\u00f3rio, desde que n\u00e3o tenha sido impugnada.&#8221;<\/p>\n\n\n\n<p>Observa-se que <strong>a regra \u00e9 o pagamento de honor\u00e1rios sucumbenciais no cumprimento de senten\u00e7a e na execu\u00e7\u00e3o, resistida ou n\u00e3o<\/strong>. Por\u00e9m, uma EXCE\u00c7\u00c3O ocorre quando o cumprimento de senten\u00e7a ensejar a expedi\u00e7\u00e3o de precat\u00f3rio, desde que n\u00e3o tenha sido impugnado. \u00c0 luz do princ\u00edpio da causalidade, o Poder P\u00fablico n\u00e3o d\u00e1 causa \u00e0 instaura\u00e7\u00e3o do rito executivo, uma vez que se revela impositiva a observ\u00e2ncia do art. 535, \u00a7 3\u00ba, II, do CPC.<\/p>\n\n\n\n<p>No cumprimento de senten\u00e7a que imp\u00f5e a obriga\u00e7\u00e3o de pagar quantia certa, os entes p\u00fablicos n\u00e3o t\u00eam a op\u00e7\u00e3o de adimplir voluntariamente. Ainda que n\u00e3o haja impugna\u00e7\u00e3o, o C\u00f3digo de Processo Civil vigente imp\u00f5e rito pr\u00f3prio que dever\u00e1 ser observado pelas partes, qual seja, o requerimento do exequente, que dever\u00e1 apresentar demonstrativo discriminado do cr\u00e9dito (art. 534 do CPC), seguido da ordem do juiz para pagamento da quantia, que &#8220;ser\u00e1 realizado no prazo de 2 (dois) meses contado da entrega da requisi\u00e7\u00e3o, mediante dep\u00f3sito na ag\u00eancia de banco oficial mais pr\u00f3xima da resid\u00eancia do exequente.&#8221;<\/p>\n\n\n\n<p>Dessa forma, a \u00fanica conduta que o Estado pode adotar em favor do imediato cumprimento do t\u00edtulo executivo judicial \u00e9 a de n\u00e3o impugnar a execu\u00e7\u00e3o e depositar a quantia requisitada pelo juiz no prazo legal. N\u00e3o \u00e9 razo\u00e1vel que o particular que pague voluntariamente a obriga\u00e7\u00e3o fique isento do pagamento de honor\u00e1rios sucumbenciais (art. 523, \u00a7 1\u00ba, do CPC), mas o Poder P\u00fablico, reconhecendo a d\u00edvida (ao deixar de impugn\u00e1-la) e pagando-a tamb\u00e9m no prazo legal, tenha de suportar esse \u00f4nus.<\/p>\n\n\n\n<p>Por oportuno, recorda-se que, se a Fazenda P\u00fablica optar por impugnar parcialmente os c\u00e1lculos apresentados pelo credor, os honor\u00e1rios ter\u00e3o como base apenas a parcela controvertida, nos termos da jurisprud\u00eancia desta Corte. A prop\u00f3sito: AgInt nos EDcl nos EDcl no REsp n. 2.031.385\/RS, Rel. Ministro Herman Benjamin, Segunda Turma, DJe de 21.9.2023; AgInt no AREsp n. 2.272.059\/SP, Rel. Ministro S\u00e9rgio Kukina, Primeira Turma, DJe de 24.8.2023; AgInt no REsp n. 2.045.035\/SP, Rel. Ministro Mauro Campbell Marques, Segunda Turma, DJe de 23.8.2023; e AgInt nos EDcl no REsp n. 1.885.625\/RS, Rel. Ministro Og Fernandes, Segunda Turma, DJe de 1.6.2021.<\/p>\n\n\n\n<p>Nesse sentido, seria financeiramente mais favor\u00e1vel \u00e0 Administra\u00e7\u00e3o P\u00fablica a impugna\u00e7\u00e3o parcial da execu\u00e7\u00e3o, ainda que com argumentos fr\u00e1geis, do que reconhecer a d\u00edvida. Por essa raz\u00e3o, manter o entendimento favor\u00e1vel ao cabimento de honor\u00e1rios advocat\u00edcios ainda que n\u00e3o impugnada a execu\u00e7\u00e3o premia o conflito, e n\u00e3o a solu\u00e7\u00e3o c\u00e9lere e consensual da lide.<\/p>\n\n\n\n<p>Por tudo isso, a mudan\u00e7a da jurisprud\u00eancia do STJ \u00e9 necess\u00e1ria. Esse entendimento n\u00e3o contraria aquele firmado pelo Supremo Tribunal Federal no RE 420.816\/PR ao reconhecer a constitucionalidade do 1\u00ba-D da Lei n. 9.494\/1997, justamente porque o Poder P\u00fablico est\u00e1 impossibilitado de adimplir espontaneamente a obriga\u00e7\u00e3o de pagar quantia certa sujeita ao regime dos precat\u00f3rios. \u00c0 luz do novo C\u00f3digo de Processo Civil, a mesma&nbsp;<em>ratio<\/em>&nbsp;deve ser estendida ao cumprimento de senten\u00e7a que determine o pagamento de quantia submetida a RPV.<\/p>\n\n\n\n<p>Os pressupostos para a modula\u00e7\u00e3o est\u00e3o presentes, uma vez que a jurisprud\u00eancia do STJ havia se firmado no sentido de que, nas hip\u00f3teses em que o pagamento da obriga\u00e7\u00e3o \u00e9 feito mediante Requisi\u00e7\u00e3o de Pequeno Valor, seria cab\u00edvel a fixa\u00e7\u00e3o de honor\u00e1rios advocat\u00edcios nos cumprimentos de senten\u00e7a contra o Estado, ainda que n\u00e3o impugnados.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>3.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Na aus\u00eancia de impugna\u00e7\u00e3o \u00e0 pretens\u00e3o execut\u00f3ria, n\u00e3o s\u00e3o devidos honor\u00e1rios advocat\u00edcios sucumbenciais em cumprimento de senten\u00e7a contra a Fazenda P\u00fablica, ainda que o cr\u00e9dito esteja submetido a pagamento por meio de Requisi\u00e7\u00e3o de Pequeno Valor &#8211; RPV.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-nbsp-nbsp-nbsp-nbsp-nulidade-da-citacao-por-edital-quando-incerto-o-endereco-do-reu-no-pais-estrangeiro\"><a>4.&nbsp;&nbsp;&nbsp;&nbsp; Nulidade da cita\u00e7\u00e3o por edital quando incerto o endere\u00e7o do r\u00e9u no pa\u00eds estrangeiro<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>Incerto o endere\u00e7o do r\u00e9u no pa\u00eds estrangeiro, admite-se a cita\u00e7\u00e3o por edital, dispensada a carta rogat\u00f3ria. O valor da causa na a\u00e7\u00e3o de querela nullitatis deve corresponder ao valor da causa origin\u00e1ria ou do proveito econ\u00f4mico obtido, a depender do teor da decis\u00e3o que se pretende declarar inexistente.<\/p>\n\n\n\n<p>REsp 2.145.294-SC, Rel. Ministra Nancy Andrighi, Terceira Turma, por unanimidade, julgado em 18\/6\/2024, DJe 21\/6\/2024. (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-1-nbsp-situacao-fatica\"><a>4.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Ap\u00f3s o tr\u00e2nsito em julgado de a\u00e7\u00e3o condenat\u00f3ria, Gertrude ajuizou a\u00e7\u00e3o de nulidade sob o argumento de que houve ilegalidade na cita\u00e7\u00e3o por edital realizada. Alega que havendo ci\u00eancia de que a parte r\u00e9 residia em pa\u00eds estrangeiro, deveria ter sido enviada solicita\u00e7\u00e3o de informa\u00e7\u00e3o \u00e0 Alf\u00e2ndega dos Estados Unidos da Am\u00e9rica, por meio da coopera\u00e7\u00e3o jur\u00eddica internacional, para que fosse descoberto o seu endere\u00e7o. Somente com eventual resposta negativa por parte da Alf\u00e2ndega ou, em caso de resposta positiva, ap\u00f3s o cumprimento da carta rogat\u00f3ria no endere\u00e7o, \u00e9 que teriam sido esgotados todos os meios de localiza\u00e7\u00e3o pessoal, o que autorizaria a cita\u00e7\u00e3o edital\u00edcia.<\/p>\n\n\n\n<p>Informou ainda valor da causa simb\u00f3lico, por entender que n\u00e3o haveria proveito econ\u00f4mico na a\u00e7\u00e3o de \u201cquerela nullitatis\u201d, pois o reconhecimento da nulidade da cita\u00e7\u00e3o n\u00e3o implicaria nulidade do neg\u00f3cio jur\u00eddico da a\u00e7\u00e3o principal, mas apenas reabertura do prazo para apresenta\u00e7\u00e3o de contesta\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-2-nbsp-analise-estrategica\"><a>4.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>4.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil:<\/p>\n\n\n\n<p>Art. 256. A cita\u00e7\u00e3o por edital ser\u00e1 feita:<\/p>\n\n\n\n<p><a><\/a><a><\/a>II &#8211; quando ignorado, incerto ou inacess\u00edvel o lugar em que se encontrar o citando;<\/p>\n\n\n\n<p><a><\/a><a><\/a>\u00a7 1\u00ba Considera-se inacess\u00edvel, para efeito de cita\u00e7\u00e3o por edital, o pa\u00eds que recusar o cumprimento de carta rogat\u00f3ria.<\/p>\n\n\n\n<p>Art. 292. O valor da causa constar\u00e1 da peti\u00e7\u00e3o inicial ou da reconven\u00e7\u00e3o e ser\u00e1:<\/p>\n\n\n\n<p><a><\/a><a><\/a>II &#8211; na a\u00e7\u00e3o que tiver por objeto a exist\u00eancia, a validade, o cumprimento, a modifica\u00e7\u00e3o, a resolu\u00e7\u00e3o, a resili\u00e7\u00e3o ou a rescis\u00e3o de ato jur\u00eddico, o valor do ato ou o de sua parte controvertida;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-2-nbsp-nbsp-nbsp-correta-a-citacao-por-edital\"><a>4.2.2.&nbsp;&nbsp;&nbsp; Correta a cita\u00e7\u00e3o por edital?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Obviamente!!!<\/strong><\/p>\n\n\n\n<p>Cinge-se a controv\u00e9rsia a definir se a informa\u00e7\u00e3o de que o r\u00e9u reside no exterior \u00e9 motivo suficiente para promover cita\u00e7\u00e3o por edital.<\/p>\n\n\n\n<p><strong>Entre os mecanismos de coopera\u00e7\u00e3o jur\u00eddica internacional est\u00e1 a carta rogat\u00f3ria, que pode ser meio de cita\u00e7\u00e3o quando o citando residir no exterior, em endere\u00e7o certo e conhecido<\/strong>.<\/p>\n\n\n\n<p>Nada obstante, <strong>o art. 256, II, do C\u00f3digo de Processo Civil estabelece que a cita\u00e7\u00e3o por edital ser\u00e1 feita quando ignorado, incerto ou inacess\u00edvel o lugar em que se encontrar o citando.<\/strong> Assim, sendo incerto o endere\u00e7o do r\u00e9u, no Brasil ou no exterior, admite-se a cita\u00e7\u00e3o por edital, nos termos do referido artigo do CPC.<\/p>\n\n\n\n<p>Portanto, embora o art. 256, \u00a7 1\u00ba, do CPC, preveja que se considera inacess\u00edvel, para efeito de cita\u00e7\u00e3o por edital, o pa\u00eds que recusar o cumprimento de carta rogat\u00f3ria; isso n\u00e3o significa que a negativa da carta rogat\u00f3ria seja pr\u00e9-requisito para o deferimento de cita\u00e7\u00e3o por edital, pois a ocorr\u00eancia de quaisquer das outras hip\u00f3teses elencadas no art. 256 do CPC j\u00e1 autoriza essa modalidade citat\u00f3ria.<\/p>\n\n\n\n<p>O simples fato de o r\u00e9u residir no exterior n\u00e3o \u00e9 suficiente para autorizar a cita\u00e7\u00e3o por edital. Contudo, se for incerto o seu endere\u00e7o no pa\u00eds estrangeiro, a previs\u00e3o do art. 256, II, do CPC admite a cita\u00e7\u00e3o edital\u00edcia, sendo dispensada a carta rogat\u00f3ria.<\/p>\n\n\n\n<p><strong>E quanto ao valor da causa da a\u00e7\u00e3o declarat\u00f3ria de nulidade???<\/strong><\/p>\n\n\n\n<p><strong>Deve corresponder ao valor da causa ORIGIN\u00c1RIA!!!!<\/strong><\/p>\n\n\n\n<p>Embora comumente denominada a\u00e7\u00e3o declarat\u00f3ria de nulidade, a&nbsp;<em>querela nullitati<\/em>s opera-se no plano da exist\u00eancia da senten\u00e7a, pois o defeito ou a inexist\u00eancia da cita\u00e7\u00e3o \u00e9 v\u00edcio transrescis\u00f3rio de tamanha gravidade que macula exist\u00eancia do ato jur\u00eddico.<\/p>\n\n\n\n<p>No que tange ao estabelecimento do valor da causa, a l\u00f3gica adotada para a a\u00e7\u00e3o rescis\u00f3ria pode ser utilizada para a&nbsp;<em>querela nullitatis<\/em>, observadas as particularidades de cada uma das a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Assim, rememora-se que o entendimento do STJ define que o valor da causa nas a\u00e7\u00f5es rescis\u00f3rias deve corresponder ao da causa origin\u00e1ria, devidamente atualizado, salvo se o proveito econ\u00f4mico pretendido com a rescis\u00e3o do julgado for discrepante daquele valor, ocasi\u00e3o em que este \u00faltimo prevalecer\u00e1.<\/p>\n\n\n\n<p>Portanto, nem sempre o valor da causa da a\u00e7\u00e3o rescis\u00f3ria corresponder\u00e1 ao da a\u00e7\u00e3o origin\u00e1ria. \u00c9 o que ocorre, por exemplo, quando se pleiteia apenas a rescis\u00e3o parcial da senten\u00e7a ou ac\u00f3rd\u00e3o ou quando se pretende rescindir decis\u00e3o de parcial proced\u00eancia do pedido. Nestas hip\u00f3teses, o valor da causa da a\u00e7\u00e3o rescis\u00f3ria n\u00e3o guardar\u00e1 correspond\u00eancia com aquele da a\u00e7\u00e3o origin\u00e1ria, mas sim com o conte\u00fado econ\u00f4mico imediatamente pretendido pela parte com a rescis\u00e3o do julgado.<\/p>\n\n\n\n<p>Nessa mesma linha, sendo o objetivo da&nbsp;<em>querela nullitatis<\/em>&nbsp;declarar a inexist\u00eancia de senten\u00e7a em raz\u00e3o da aus\u00eancia de cita\u00e7\u00e3o, essa decis\u00e3o ser\u00e1 desconsiderada por inteiro, motivo pelo qual o valor a ser atribu\u00eddo \u00e0 a\u00e7\u00e3o declarat\u00f3ria corresponder\u00e1 ao do&nbsp;<em>decisum<\/em>&nbsp;que se pretende declarar inexistente. Assim, se a decis\u00e3o alegadamente inexistente tiver decidido pela total proced\u00eancia do pedido da a\u00e7\u00e3o origin\u00e1ria, o valor a ser atribu\u00eddo \u00e0 a\u00e7\u00e3o de declarat\u00f3ria corresponder\u00e1 ao da a\u00e7\u00e3o origin\u00e1ria, pois este ser\u00e1 o proveito econ\u00f4mico pretendido pelo autor da&nbsp;<em>querela nullitatis<\/em>.<\/p>\n\n\n\n<p>\u00c9 precisamente isto que o art. 292, II do CPC estabelece ao determinar que na a\u00e7\u00e3o que tiver por objeto a exist\u00eancia, a validade, o cumprimento, a modifica\u00e7\u00e3o, a resolu\u00e7\u00e3o, a resili\u00e7\u00e3o ou a rescis\u00e3o de ato jur\u00eddico, o valor da causa ser\u00e1 do ato ou o de sua parte controvertida.<\/p>\n\n\n\n<p>Reitera este entendimento a jurisprud\u00eancia firmada na Terceira Turma do STJ no sentido de que o valor da causa deve equivaler, em princ\u00edpio, ao conte\u00fado econ\u00f4mico a ser obtido na demanda, embora o provimento jurisdicional buscado tenha conte\u00fado meramente declarat\u00f3rio. (REsp n. 2.096.465\/SP, Terceira Turma, DJe de 16\/5\/2024).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>4.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Incerto o endere\u00e7o do r\u00e9u no pa\u00eds estrangeiro, admite-se a cita\u00e7\u00e3o por edital, dispensada a carta rogat\u00f3ria. O valor da causa na a\u00e7\u00e3o de querela nullitatis deve corresponder ao valor da causa origin\u00e1ria ou do proveito econ\u00f4mico obtido, a depender do teor da decis\u00e3o que se pretende declarar inexistente.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-tributario\"><a>DIREITO TRIBUT\u00c1RIO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-nbsp-nbsp-nbsp-nbsp-base-de-calculo-do-pis-pasep-e-cofins-e-os-valores-de-juros-calculados-pela-taxa-selic-ou-outros-indices-recebidos-em-face-de-repeticao-de-indebito-tributario-na-devolucao-de-depositos-judiciais-ou-nos-pagamentos-efetuados-decorrentes-de-obrigacoes-contratuais-em-atraso\"><a>5.&nbsp;&nbsp;&nbsp;&nbsp; Base de c\u00e1lculo do PIS\/PASEP e COFINS e os valores de juros, calculados pela taxa SELIC ou outros \u00edndices, recebidos em face de repeti\u00e7\u00e3o de ind\u00e9bito tribut\u00e1rio, na devolu\u00e7\u00e3o de dep\u00f3sitos judiciais ou nos pagamentos efetuados decorrentes de obriga\u00e7\u00f5es contratuais em atraso<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>Os valores de juros, calculados pela taxa SELIC ou outros \u00edndices, recebidos em face de repeti\u00e7\u00e3o de ind\u00e9bito tribut\u00e1rio, na devolu\u00e7\u00e3o de dep\u00f3sitos judiciais ou nos pagamentos efetuados decorrentes de obriga\u00e7\u00f5es contratuais em atraso, por se caracterizarem como Receita Bruta Operacional, est\u00e3o na base de c\u00e1lculo das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS cumulativas e, por integrarem o conceito amplo de Receita Bruta, na base de c\u00e1lculo das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS n\u00e3o cumulativas.<\/p>\n\n\n\n<p>REsp 2.065.817-RJ, Rel. Ministro Mauro Campbell Marques, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 20\/6\/2024, DJe 25\/6\/2024. (Tema 1237). (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-1-nbsp-situacao-fatica\"><a>5.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Trata-se de julgamento de recurso repetitivo para o STJ decidir se incidem PIS e Cofins sobre juros Selic recebidos via repeti\u00e7\u00e3o de ind\u00e9bito tribut\u00e1rio \u2014 a\u00e7\u00e3o para pedir a restitui\u00e7\u00e3o de tributo pago indevidamente ou a maior \u2014 e na devolu\u00e7\u00e3o de dep\u00f3sitos judiciais ou de pagamentos efetuados por clientes em atraso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-2-nbsp-analise-estrategica\"><a>5.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>5.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>CTN:<\/p>\n\n\n\n<p>Art. 109. Os princ\u00edpios gerais de direito privado utilizam-se para pesquisa da defini\u00e7\u00e3o, do conte\u00fado e do alcance de seus institutos, conceitos e formas, mas n\u00e3o para defini\u00e7\u00e3o dos respectivos efeitos tribut\u00e1rios.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-2-nbsp-nbsp-nbsp-tais-valores-compoem-a-bc-do-pis-cofins\"><a>5.2.2.&nbsp;&nbsp;&nbsp; Tais valores comp\u00f5em a BC do PIS\/COFINS?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeap!!!!<\/strong><\/p>\n\n\n\n<p>Conforme a autonomia do Direito Tribut\u00e1rio positivada no art. 109, do CTN, <strong>a defini\u00e7\u00e3o dos efeitos tribut\u00e1rios dos institutos de direito civil se submete \u00e0 norma tribut\u00e1ria. Assim, quando se est\u00e1 a falar da percep\u00e7\u00e3o da verba por pessoas jur\u00eddicas, os juros, sejam morat\u00f3rios (danos emergentes na repeti\u00e7\u00e3o de ind\u00e9bito tribut\u00e1rio ou lucros cessantes nas demais hip\u00f3teses como pagamentos de clientes em atraso), sejam remunerat\u00f3rios (produto do capital investido ou devolu\u00e7\u00e3o de dep\u00f3sitos judiciais), recebem classifica\u00e7\u00e3o cont\u00e1bil tribut\u00e1ria consoante a legisla\u00e7\u00e3o em vigor<\/strong>.<\/p>\n\n\n\n<p>Os juros remunerat\u00f3rios &#8211; categoria que abrange os juros SELIC incidentes na devolu\u00e7\u00e3o dos dep\u00f3sitos judiciais &#8211; s\u00e3o Receitas Financeiras (remunera\u00e7\u00e3o do capital) integrantes do Lucro Operacional, consoante o disposto no art. 17, do Decreto-Lei n. 1.598\/1977 e o art. 9\u00ba, da Lei n. 9.718\/1998, portanto integrantes do conceito maior de Receita Bruta Operacional.<\/p>\n\n\n\n<p>J\u00e1 os juros morat\u00f3rios, se recebidos em face de repeti\u00e7\u00e3o de ind\u00e9bito tribut\u00e1rio &#8211; categoria que abrange os juros SELIC incidentes na repeti\u00e7\u00e3o de ind\u00e9bito tribut\u00e1rio &#8211; s\u00e3o, excepcionalmente, recupera\u00e7\u00f5es ou devolu\u00e7\u00f5es de custos (indeniza\u00e7\u00f5es a t\u00edtulo de danos emergentes) integrantes da Receita Bruta Operacional, consoante o disposto no art. 44, III, da Lei n. 4.506\/1964.<\/p>\n\n\n\n<p><strong>Caso auferidos nas demais hip\u00f3teses de inadimplemento &#8211; categoria que abrange os juros incidentes sobre os pagamentos efetuados por clientes em atraso &#8211; s\u00e3o Receitas Financeiras (indeniza\u00e7\u00f5es a t\u00edtulo de lucros cessantes) integrantes do Lucro Operacional<\/strong>, consoante o disposto no art. 17, do Decreto-Lei n. 1.598\/1977 e o art. 9\u00ba, da Lei n. 9.718\/1998, portanto integrantes do conceito maior de Receita Bruta Operacional.<\/p>\n\n\n\n<p>Ainda que se entendesse inaplic\u00e1vel o disposto no art. 44, III, da Lei n. 4.506\/1964, aos juros morat\u00f3rios, subsistiria a aplica\u00e7\u00e3o do art. 17, do Decreto-Lei n. 1.598\/1977 e do art. 9\u00ba, da Lei n. 9.718\/1998, que os classificaria como Receitas Financeiras, sendo que todas as Receitas Financeiras tamb\u00e9m integram o conceito maior de Receita Bruta Operacional.<\/p>\n\n\n\n<p>Desta forma, a lei tribut\u00e1ria estabelece expressamente que o aumento do valor do cr\u00e9dito das pessoas jur\u00eddicas contribuintes em raz\u00e3o da aplica\u00e7\u00e3o de determinada taxa de juros, seja ela qual for, por for\u00e7a de lei ou contrato, atrelada ou n\u00e3o a corre\u00e7\u00e3o monet\u00e1ria (como o \u00e9 a taxa SELIC), proveniente de ato l\u00edcito (remunera\u00e7\u00e3o) ou il\u00edcito (mora) possui a natureza de Receita Bruta Operacional, assim ingressando na contabilidade das empresas para efeitos tribut\u00e1rios. Precedente repetitivo: REsp. n. 1.138.695-SC, Primeira Se\u00e7\u00e3o, Rel. Ministro Mauro Campbell Marques, julgado em 22\/5\/2013 e ju\u00edzo de retrata\u00e7\u00e3o julgado em em 26\/4\/2023.<\/p>\n\n\n\n<p><strong>Essa natureza jur\u00eddico-tribut\u00e1ria dos juros (de mora ou remunerat\u00f3rios) como Receita Bruta Operacional os coloca dentro da base de c\u00e1lculo das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS sob os regimes cumulativo<\/strong> (base de c\u00e1lculo Receita Bruta Operacional ou faturamento) e n\u00e3o cumulativo (base de c\u00e1lculo Receita Bruta em sentido amplo ou total).<\/p>\n\n\n\n<p>A condi\u00e7\u00e3o dos juros de mora na repeti\u00e7\u00e3o do ind\u00e9bito tribut\u00e1rio como verba indenizat\u00f3ria a t\u00edtulo de dano emergente &#8211; Temas ns. 808 e 962 da Repercuss\u00e3o Geral do STF, RE n. 855.091 e RE n. 1.063.187 e&nbsp;Tema 505\/STJ, Ju\u00edzo de Retrata\u00e7\u00e3o no REsp. n. 1.138.695-SC &#8211; pode lhes retirar a natureza jur\u00eddica de renda ou lucro, relevante para o IRPJ e para a CSLL, mas n\u00e3o lhes retira a natureza de Receita Bruta a qual \u00e9 determinante para o deslinde da causa para as contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>5.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Os valores de juros, calculados pela taxa SELIC ou outros \u00edndices, recebidos em face de repeti\u00e7\u00e3o de ind\u00e9bito tribut\u00e1rio, na devolu\u00e7\u00e3o de dep\u00f3sitos judiciais ou nos pagamentos efetuados decorrentes de obriga\u00e7\u00f5es contratuais em atraso, por se caracterizarem como Receita Bruta Operacional, est\u00e3o na base de c\u00e1lculo das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS cumulativas e, por integrarem o conceito amplo de Receita Bruta, na base de c\u00e1lculo das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS n\u00e3o cumulativas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-nbsp-nbsp-nbsp-nbsp-i-legalidade-do-teto-para-parcelamento-fiscal-estabelecido-por-meio-de-ato-infralegal\"><a>6.&nbsp;&nbsp;&nbsp;&nbsp; (I)Legalidade do teto para parcelamento fiscal estabelecido por meio de ato infralegal.<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>O estabelecimento de teto para ades\u00e3o ao parcelamento simplificado, por constituir medida de gest\u00e3o e efici\u00eancia na arrecada\u00e7\u00e3o e recupera\u00e7\u00e3o do cr\u00e9dito p\u00fablico, pode ser feito por ato infralegal, nos termos do art. 96 do CTN. Excetua-se a hip\u00f3tese em que a lei em sentido restrito definir diretamente o valor m\u00e1ximo e a autoridade administrativa, na regulamenta\u00e7\u00e3o da norma, fixar quantia inferior \u00e0 estabelecida na lei, em preju\u00edzo do contribuinte.<\/p>\n\n\n\n<p>REsp 1.679.536-RN, Rel. Ministro Herman Benjamin, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 20\/6\/2024, DJe 1\u00ba\/7\/2024. (Tema 997). (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-1-nbsp-situacao-fatica\"><a>6.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A Receita Federal, por meio de Portaria, estabeleceu requisitos para ades\u00e3o ao parcelamento simplificado. Dentre os requisitos, constava um teto ao valor poss\u00edvel de parcelamento.<\/p>\n\n\n\n<p>Inconformada, a empresa Longa Esperan\u00e7a contesta a legalidade do teto limitador, por entender que tal crit\u00e9rio deveria ter sido estabelecido por meio de lei.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-2-nbsp-analise-estrategica\"><a>6.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>6.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>CTN:<\/p>\n\n\n\n<p>Art. 96. A express\u00e3o &#8220;legisla\u00e7\u00e3o tribut\u00e1ria&#8221; compreende as leis, os tratados e as conven\u00e7\u00f5es internacionais, os decretos e as normas complementares que versem, no todo ou em parte, s\u00f4bre tributos e rela\u00e7\u00f5es jur\u00eddicas a eles pertinentes.<\/p>\n\n\n\n<p>Art. 155-A. O parcelamento ser\u00e1 concedido na forma e condi\u00e7\u00e3o estabelecidas em lei espec\u00edfica.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-2-nbsp-nbsp-nbsp-ato-infralegal-pode-estabelecer-teto-de-parcelamento\"><a>6.2.2.&nbsp;&nbsp;&nbsp; Ato infralegal pode estabelecer teto de parcelamento?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong><strong>Como regra, SIM!!!<\/strong><\/p>\n\n\n\n<p>Cinge-se a controv\u00e9rsia em saber se o estabelecimento de valor m\u00e1ximo (&#8220;teto&#8221;) para formaliza\u00e7\u00e3o e ades\u00e3o ao parcelamento simplificado por atos normativos infralegais, seja da Receita Federal ou da Procuradoria-Geral da Fazenda Nacional, ofende o princ\u00edpio da legalidade.<\/p>\n\n\n\n<p>Segundo o art. 155-A do CTN, o<strong> parcelamento ser\u00e1 concedido na forma e condi\u00e7\u00e3o estabelecidas em lei espec\u00edfica.<\/strong> Por se tratar (o parcelamento) de liberalidade submetida \u00e0 conveni\u00eancia do Fisco, cabe \u00e0 lei em sentido estrito definir, essencialmente, o respectivo prazo de dura\u00e7\u00e3o, os tributos aos quais ela se aplica, bem como o n\u00famero de presta\u00e7\u00f5es e periodicidade de seu vencimento.<\/p>\n\n\n\n<p>A Lei n. 10.522\/2002, por sua vez, versa sobre o denominado &#8220;parcelamento ordin\u00e1rio&#8221; (ou comum) de d\u00e9bitos com o Fisco, abrangendo generalizadamente os contribuintes que possuam pend\u00eancias com a Administra\u00e7\u00e3o Tribut\u00e1ria Federal. No mesmo diploma normativo, consta a cria\u00e7\u00e3o, em car\u00e1ter igualmente geral, do &#8220;parcelamento simplificado&#8221; de d\u00e9bitos.<\/p>\n\n\n\n<p>A origem do parcelamento simplificado, na forma estipulada na Lei n. 10.522\/2002, consiste na Medida Provis\u00f3ria n. 1621-30, de 12.12.1997, que dispunha em seu art. 11, \u00a7 6\u00ba (reda\u00e7\u00e3o id\u00eantica ao do mesmo dispositivo da Lei n. 10.522\/2002), que: &#8220;Atendendo ao princ\u00edpio da economicidade, observados os termos, os limites e as condi\u00e7\u00f5es estabelecidos em ato do Ministro de Estado da Fazenda, poder\u00e1 ser concedido, de of\u00edcio, parcelamento simplificado, importando o pagamento da primeira parcela confiss\u00e3o irretrat\u00e1vel da d\u00edvida e ades\u00e3o ao sistema de parcelamentos de que trata esta Medida Provis\u00f3ria&#8221;. Tal dispositivo, como se infere, limitou-se a instituir o parcelamento simplificado, delegando ao Ministro de Estado da Fazenda ampla atribui\u00e7\u00e3o normativa, ao prever que a ele competia estabelecer os respectivos termos, limites e as condi\u00e7\u00f5es.<\/p>\n\n\n\n<p><strong>A premissa que se depreende da norma acima \u00e9 de que o &#8220;parcelamento simplificado&#8221; n\u00e3o representa, na ess\u00eancia, modalidade substancialmente distinta do parcelamento ordin\u00e1rio<\/strong>. N\u00e3o se trata do estabelecimento de um programa espec\u00edfico, com natureza ou caracter\u00edsticas diversas, em rela\u00e7\u00e3o ao parcelamento comum, mas exatamente o mesmo parcelamento, cuja instrumentaliza\u00e7\u00e3o\/operacionaliza\u00e7\u00e3o \u00e9 feita de modo menos trabalhoso, ou, para usar a terminologia empregada na sua denomina\u00e7\u00e3o literal, de modo mais &#8220;simples&#8221; (diretamente pelo contribuinte, on-line, sem a apresenta\u00e7\u00e3o de garantias).<\/p>\n\n\n\n<p>A nota distintiva, portanto, entre os dois tipos de parcelamento reside exclusivamente na circunst\u00e2ncia de que o simplificado, para ser formalizado, dispensa a pr\u00e9via apresenta\u00e7\u00e3o de garantia. Representa, assim, mera t\u00e9cnica que, em observ\u00e2ncia ao princ\u00edpio da efici\u00eancia, introduz mecanismo destinado a garantir maior qualidade na gest\u00e3o e arrecada\u00e7\u00e3o do cr\u00e9dito p\u00fablico.<\/p>\n\n\n\n<p>Nos termos acima, merece destaque a constata\u00e7\u00e3o de que o estabelecimento dos limites e condi\u00e7\u00f5es para o parcelamento simplificado jamais constituiu mat\u00e9ria reservada \u00e0 disciplina por lei em sentido estrito. Pelo contr\u00e1rio, <strong>a Lei n. 10.522\/2002 expressamente fixava compet\u00eancia para o Ministro da Fazenda, por ato infralegal, definir crit\u00e9rios para diferenciar se o d\u00e9bito poderia ser parcelado no regime simplificado ou no comum<\/strong>.<\/p>\n\n\n\n<p>A judicializa\u00e7\u00e3o do tema ocorreu porque o art. 11, \u00a7 6\u00ba, da citada Lei foi revogada pelo art. 35 da Lei n. 11.941\/2009, de modo que o parcelamento simplificado passou a ser disciplinado no art. 14-C (Lei n. 10.522\/2002), nos seguintes termos: &#8220;Art. 14-C. Poder\u00e1 ser concedido, de of\u00edcio ou a pedido, parcelamento simplificado, importando o pagamento da primeira presta\u00e7\u00e3o em confiss\u00e3o de d\u00edvida e instrumento h\u00e1bil e suficiente para a exig\u00eancia do cr\u00e9dito tribut\u00e1rio&#8221;. Observa-se, assim, que foi preservada a exist\u00eancia do parcelamento simplificado, consistindo a \u00fanica novidade na supress\u00e3o da refer\u00eancia expressa de que ato infralegal do Ministro de Estado da Fazenda estabeleceria os termos, limites e condi\u00e7\u00f5es para a concess\u00e3o do parcelamento simplificado.<\/p>\n\n\n\n<p>Nesse sentido, a utiliza\u00e7\u00e3o adequada dos m\u00e9todos de hermen\u00eautica conduz ao entendimento de que a supress\u00e3o da norma que previa incumbir ao Ministro de Estado da Fazenda estabelecer, por ato infralegal, os limites de valor para ades\u00e3o ao parcelamento simplificado, n\u00e3o \u00e9 suficiente para justificar a conclus\u00e3o de que o legislador ordin\u00e1rio tomou para si tal atribui\u00e7\u00e3o. Isso porque se revela indispens\u00e1vel aplicar corretamente o princ\u00edpio da legalidade no \u00e2mbito do Direito Tribut\u00e1rio.<\/p>\n\n\n\n<p>De acordo com o art. 96 do CTN, a &#8220;express\u00e3o &#8216;legisla\u00e7\u00e3o tribut\u00e1ria&#8217; compreende as leis, os tratados e as conven\u00e7\u00f5es internacionais, os decretos e as normas complementares que versem, no todo ou em parte, sobre tributos e rela\u00e7\u00f5es jur\u00eddicas a eles pertinentes&#8221;. Dito de outro modo, os tributos e rela\u00e7\u00f5es jur\u00eddicas a eles pertinentes s\u00e3o disciplinados por uma vasta gama de diplomas normativos, tais como: a) as leis; b) os tratos e as conven\u00e7\u00f5es internacionais; c) os decretos e d) as normas complementares. Tem-se, assim, a &#8220;legisla\u00e7\u00e3o tribut\u00e1ria&#8221; como g\u00eanero, composta pelas respectivas esp\u00e9cies normativas, de modo que, nem tudo que verse sobre tributos &#8211; e, notadamente, sobre rela\u00e7\u00f5es jur\u00eddicas atinentes aos tributos &#8211; deve ser disciplinado exclusivamente por lei em sentido estrito.<\/p>\n\n\n\n<p>Consoante observado, j\u00e1 no regime anterior (reda\u00e7\u00e3o original da Lei n. 10.252\/2002), a mat\u00e9ria nunca foi disciplinada por lei em sentido estrito, sendo incab\u00edvel, portanto, concluir que o tema est\u00e1 sujeito ao princ\u00edpio da reserva legal. Com efeito, se a lei prev\u00ea a exist\u00eancia do parcelamento comum e do simplificado, n\u00e3o se justifica a exegese cujo resultado, ao retirar do administrador a compet\u00eancia para especificar os d\u00e9bitos cujo parcelamento pode ser formalizado de modo singelo, implica a inexist\u00eancia de parcelamentos diferenciados, pois haveria apenas o parcelamento simplificado, excluindo-se a hip\u00f3tese para a concess\u00e3o do parcelamento ordin\u00e1rio. Dessa forma, tal exegese impediria a Administra\u00e7\u00e3o Tribut\u00e1ria de exigir a apresenta\u00e7\u00e3o de garantia real ou fidejuss\u00f3ria &#8211; expressamente autorizada por lei (art. 11, \u00a7 1\u00ba, da Lei n. 10.522\/2002) para os d\u00e9bitos inscritos na d\u00edvida ativa da Uni\u00e3o -, comprometendo grave e injustificadamente a aplica\u00e7\u00e3o do princ\u00edpio da efici\u00eancia na institui\u00e7\u00e3o de medidas assecurat\u00f3rias da melhor qualidade na recupera\u00e7\u00e3o do cr\u00e9dito p\u00fablico.<\/p>\n\n\n\n<p>Dessarte<em>,<\/em>&nbsp;inexiste viola\u00e7\u00e3o ao princ\u00edpio da legalidade, pois o estabelecimento do valor m\u00e1ximo (teto) para identifica\u00e7\u00e3o do regime de parcelamento (simplificado ou ordin\u00e1rio) n\u00e3o foi feito com a inten\u00e7\u00e3o de restringir direitos uma vez que, os referidos parcelamentos s\u00e3o id\u00eanticos entre si, de modo que a impossibilidade de ades\u00e3o ao parcelamento simplificado em nada interfere com o acesso ao mesmo parcelamento na outra modalidade ordin\u00e1ria. A \u00fanica diferencia\u00e7\u00e3o entre ambos consiste na simplifica\u00e7\u00e3o do meio de ades\u00e3o, mat\u00e9ria que diz respeito \u00e0 administra\u00e7\u00e3o e gest\u00e3o do cr\u00e9dito tribut\u00e1rio, plenamente pass\u00edvel de disciplina por normas complementares de Direito Tribut\u00e1rio, sendo a autoridade que administra o cr\u00e9dito quem possui, naturalmente, contato direto com a realidade cotidiana que envolve o estabelecimento dos crit\u00e9rios e meios de obter, com maior efic\u00e1cia, a recupera\u00e7\u00e3o do cr\u00e9dito p\u00fablico.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>6.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>O estabelecimento de teto para ades\u00e3o ao parcelamento simplificado, por constituir medida de gest\u00e3o e efici\u00eancia na arrecada\u00e7\u00e3o e recupera\u00e7\u00e3o do cr\u00e9dito p\u00fablico, pode ser feito por ato infralegal, nos termos do art. 96 do CTN. Excetua-se a hip\u00f3tese em que a lei em sentido restrito definir diretamente o valor m\u00e1ximo e a autoridade administrativa, na regulamenta\u00e7\u00e3o da norma, fixar quantia inferior \u00e0 estabelecida na lei, em preju\u00edzo do contribuinte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-nbsp-nbsp-nbsp-nbsp-tributos-recolhidos-em-substituicao-tributaria-como-custo-de-aquisicao\"><a>7.&nbsp;&nbsp;&nbsp;&nbsp; Tributos recolhidos em substitui\u00e7\u00e3o tribut\u00e1ria como custo de aquisi\u00e7\u00e3o<\/a><\/h2>\n\n\n\n<p><strong>EMBARGOS DE DIVERG\u00caNCIA EM RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>I. Os tributos recolhidos em substitui\u00e7\u00e3o tribut\u00e1ria n\u00e3o integram o conceito de custo de aquisi\u00e7\u00e3o previsto no art. 13, do Decreto-Lei n. 1.598\/1977; e II. Os valores pagos pelo contribuinte substituto a t\u00edtulo de ICMS-ST n\u00e3o geram, no regime n\u00e3o cumulativo, cr\u00e9ditos para fins de incid\u00eancia das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS devidas pelo contribuinte substitu\u00eddo.<\/p>\n\n\n\n<p>EREsp 1.959.571-RS, Rel. Ministro Mauro Campbell Marques, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 20\/6\/2024, DJe 25\/6\/2024. (Tema 1231). (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-1-nbsp-situacao-fatica\"><a>7.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A empresa Rudiger ajuizou a\u00e7\u00e3o por meio da qual requereu o reconhecimento ao direito de apurar cr\u00e9ditos de PIS\/COFINS sobre as mercadorias adquiridas para revenda sempre que comprovado que o ICMS-ST tenha sido destacado na nota fiscal de entrada das mercadorias no seu estabelecimento e integrado o pre\u00e7o pago.<\/p>\n\n\n\n<p>Inconformada, a Fazenda Nacional sustenta diverg\u00eancia entre as Turmas do STJ e que n\u00e3o tem direito o contribuinte ao creditamento, no \u00e2mbito do regime n\u00e3o- cumulativo do PIS e COFINS, dos valores que, na condi\u00e7\u00e3o de substitu\u00eddo tribut\u00e1rio, paga ao contribuinte substituto a t\u00edtulo de reembolso pelo recolhimento do ICMS-substitui\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-2-nbsp-analise-estrategica\"><a>7.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-1-nbsp-nbsp-nbsp-os-tributos-recolhidos-integram-o-conceito-de-custo-de-aquisicao\"><a>7.2.1.&nbsp;&nbsp;&nbsp; Os tributos recolhidos integram o conceito de custo de aquisi\u00e7\u00e3o?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Negativo!!!!<\/strong><\/p>\n\n\n\n<p>Cinge-se a controv\u00e9rsia sobre a possibilidade de creditamento, no \u00e2mbito do regime n\u00e3o-cumulativo das contribui\u00e7\u00f5es ao PIS e COFINS, dos valores que o contribuinte, na condi\u00e7\u00e3o de substitu\u00eddo tribut\u00e1rio, paga ao contribuinte substituto a t\u00edtulo de reembolso pelo recolhimento do ICMS-substitui\u00e7\u00e3o (ICMS-ST).<\/p>\n\n\n\n<p>Quando o ICMS-ST \u00e9 cobrado pelo vendedor dos bens ou prestador dos servi\u00e7os na condi\u00e7\u00e3o de substituto tribut\u00e1rio este \u00e9 mero deposit\u00e1rio do valor financeiro correspondente ao tributo que ser\u00e1 posteriormente entregue ao Fisco, em outras palavras, o substituto tribut\u00e1rio \u00e9 mero deposit\u00e1rio de valor correspondente a tributo de outrem.<\/p>\n\n\n\n<p><strong>N\u00e3o sendo receita bruta do substituto tribut\u00e1rio, o ICMS-ST n\u00e3o est\u00e1 na base de c\u00e1lculo das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS n\u00e3o cumulativas por si<\/strong> (pelo substituto) devidas e definida nos arts. 1\u00ba e \u00a7 2\u00ba, das Leis ns. 10.637\/2002 e 10.833\/2003.<\/p>\n\n\n\n<p>Como o princ\u00edpio da n\u00e3o cumulatividade preconiza que o valor do tributo incidente sobre o bem na sa\u00edda do vendedor \u00e9 que ir\u00e1 gerar o valor do cr\u00e9dito na entrada do bem para o adquirente, se n\u00e3o houver tributa\u00e7\u00e3o na sa\u00edda do vendedor (substituto), n\u00e3o haver\u00e1 creditamento na entrada para o adquirente (substitu\u00eddo) e qualquer cr\u00e9dito concedido nessa situa\u00e7\u00e3o ou para al\u00e9m do valor do tributo pago na etapa anterior \u00e9 cr\u00e9dito presumido ou fict\u00edcio, carecedor de lei espec\u00edfica, na forma do art. 150, \u00a76\u00ba, da CF\/1988. Precedentes: S\u00famula Vinculante n. 58\/STF; Repercuss\u00e3o Geral Tema n. 844\/STF; recurso repetitivo REsp. n. 1.894.741\/RS, Primeira Se\u00e7\u00e3o, Rel. Min. Mauro Campbell Marques, julgado em 27.04.2022. Assim, se as contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS n\u00e3o incidirem sobre o ICMS-ST na etapa anterior (substituto), na aus\u00eancia de lei expressa criadora do cr\u00e9dito presumido, n\u00e3o podem gerar cr\u00e9dito para ser utilizado na etapa posterior (substitu\u00eddo).<\/p>\n\n\n\n<p>Com o julgamento do&nbsp;Tema 1125\/STJ&nbsp;(&#8220;O ICMS-ST n\u00e3o comp\u00f5e a base de c\u00e1lculo da Contribui\u00e7\u00e3o ao PIS e da COFINS devidas pelo contribuinte substitu\u00eddo no regime de substitui\u00e7\u00e3o tribut\u00e1ria progressiva&#8221;), o Superior Tribunal de Justi\u00e7a equiparou a situa\u00e7\u00e3o econ\u00f4mica dos contribuintes de direito do ICMS normal \u00e0quela dos contribuintes de fato do ICMS-ST, em raz\u00e3o do princ\u00edpio da isonomia, tornando a escolha do Estado em tributar determinada mercadoria via ICMS ou ICMS-ST economicamente neutra para as contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS e, por consequ\u00eancia, para as empresas.<\/p>\n\n\n\n<p>Caso hoje fosse concedido o creditamento, a distor\u00e7\u00e3o existente entre o contribuinte de fato do ICMS-ST e o contribuinte de direito do ICMS normal voltaria a ocorrer, desta vez em preju\u00edzo deste \u00faltimo. Isso porque o primeiro, al\u00e9m de excluir o ICMS-ST da base de c\u00e1lculo das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS por si devidas, tamb\u00e9m ganharia o direito ao cr\u00e9dito dos valores correspondentes ao ICMS-ST, caracterizando odioso duplo benef\u00edcio (ganharia de volta o cr\u00e9dito sem ter o d\u00e9bito correspondente), sendo que o segundo nenhum benef\u00edcio mais tem depois do advento dos os artigos 6\u00ba e 7\u00ba, da Lei n. 14.592\/2023 (n\u00e3o tem cr\u00e9dito e n\u00e3o tem d\u00e9bito).<\/p>\n\n\n\n<p>Os tributos recolhidos em substitui\u00e7\u00e3o tribut\u00e1ria n\u00e3o integram o conceito de custo de aquisi\u00e7\u00e3o previsto no art. 13, do Decreto-Lei n. 1.598\/1977, isto porque i) a lei foi publicada em per\u00edodo onde n\u00e3o havia substitui\u00e7\u00e3o tribut\u00e1ria progressiva (substitui\u00e7\u00e3o tribut\u00e1ria &#8220;para frente&#8221;) no Brasil, n\u00e3o podendo dar efeitos a algo que n\u00e3o existia, desta forma, sequer \u00e9 poss\u00edvel instru\u00e7\u00e3o normativa que assim trate a mat\u00e9ria, sob pena de extrapolar a lei de reg\u00eancia; ii) Os tributos recolhidos em substitui\u00e7\u00e3o tribut\u00e1ria &#8220;para frente&#8221; s\u00e3o mera antecipa\u00e7\u00e3o de um tributo que incidiria na venda (n\u00e3o na aquisi\u00e7\u00e3o) a ser feita pelo substitu\u00eddo, ou seja, n\u00e3o s\u00e3o juridicamente uma onera\u00e7\u00e3o na aquisi\u00e7\u00e3o, mas uma onera\u00e7\u00e3o antecipada da venda a ser futuramente feita; e iii) a classifica\u00e7\u00e3o de &#8220;tributo recuper\u00e1vel&#8221; e &#8220;tributo n\u00e3o recuper\u00e1vel&#8221; n\u00e3o \u00e9 aplic\u00e1vel aos casos de substitui\u00e7\u00e3o tribut\u00e1ria, porque monof\u00e1sicos.<\/p>\n\n\n\n<p>Ainda que o ICMS-ST integrasse o conceito de custo de aquisi\u00e7\u00e3o, o STJ tem posicionamento pacificado no sentido de que nem todo o custo de aquisi\u00e7\u00e3o gera direito ao creditamento na sistem\u00e1tica n\u00e3o cumulativa das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS. Precedentes em recursos repetitivos: REsp. n. 1.221.170\/PR, Primeira Se\u00e7\u00e3o, Rel. Ministro Napole\u00e3o Nunes Maia Filho, julgado em 22.02.2018 e REsp. n. 1.894.741\/RS, Primeira Se\u00e7\u00e3o, Rel. Ministro Mauro Campbell Marques, julgado em 27.04.2022.<\/p>\n\n\n\n<p>Dessa forma, <strong>seja em raz\u00e3o dos limites impostos pelo princ\u00edpio da n\u00e3o cumulatividade, seja em raz\u00e3o da impossibilidade de tratamento anti-ison\u00f4mico entre os contribuintes, seja porque n\u00e3o configuram custo de aquisi\u00e7\u00e3o e seja porque nem todo o custo de aquisi\u00e7\u00e3o gera direito ao creditamento na sistem\u00e1tica n\u00e3o cumulativa das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS<\/strong>, os valores despendidos pelo contribuinte substitu\u00eddo, a t\u00edtulo de reembolso ao contribuinte substituto pelo recolhimento do ICMS-ST, n\u00e3o geram cr\u00e9ditos das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS n\u00e3o cumulativas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-2-nbsp-nbsp-nbsp-resultado-final\"><a>7.2.2.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>I. Os tributos recolhidos em substitui\u00e7\u00e3o tribut\u00e1ria n\u00e3o integram o conceito de custo de aquisi\u00e7\u00e3o previsto no art. 13, do Decreto-Lei n. 1.598\/1977; e II. Os valores pagos pelo contribuinte substituto a t\u00edtulo de ICMS-ST n\u00e3o geram, no regime n\u00e3o cumulativo, cr\u00e9ditos para fins de incid\u00eancia das contribui\u00e7\u00f5es ao PIS\/PASEP e COFINS devidas pelo contribuinte substitu\u00eddo.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-previdenciario\"><a>DIREITO PREVIDENCI\u00c1RIO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-nbsp-nbsp-nbsp-nbsp-criterio-para-compensacao-de-prestacoes-previdenciarias-concomitantes\"><a>8.&nbsp;&nbsp;&nbsp;&nbsp; Crit\u00e9rio para compensa\u00e7\u00e3o de presta\u00e7\u00f5es previdenci\u00e1rias concomitantes.<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>A compensa\u00e7\u00e3o de presta\u00e7\u00f5es previdenci\u00e1rias, recebidas na via administrativa, quando da elabora\u00e7\u00e3o de c\u00e1lculos em cumprimento de senten\u00e7a concessiva de outro benef\u00edcio, com elas n\u00e3o acumul\u00e1vel, deve ser feita m\u00eas a m\u00eas, no limite, para cada compet\u00eancia, do valor correspondente ao t\u00edtulo judicial, n\u00e3o devendo ser apurado valor mensal ou final negativo ao benefici\u00e1rio, de modo a evitar a execu\u00e7\u00e3o invertida ou a restitui\u00e7\u00e3o indevida.<\/p>\n\n\n\n<p>REsp 2.039.614-PR, Rel. Ministro Gurgel de Faria, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 20\/6\/2024, DJe 28\/6\/2024. (Tema 1207). (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-1-nbsp-situacao-fatica\"><a>8.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Geremia teve benef\u00edcio previdenci\u00e1rio negado administrativamente pelo INSS, o que resultou no ajuizamento de a\u00e7\u00e3o previdenci\u00e1ria na qual foi reconhecido o direito ao benef\u00edcio em quest\u00e3o. Ocorre que, quando do cumprimento da senten\u00e7a, o INSS insistiu em abater os valores recebidos no per\u00edodo em raz\u00e3o de outro benef\u00edcio, listado entre os n\u00e3o acumul\u00e1veis.<\/p>\n\n\n\n<p>Sustenta a autarquia que a fim de evitar cumula\u00e7\u00e3o il\u00edcita de benef\u00edcios previdenci\u00e1rios, deve-se n\u00e3o apenas zerar as compet\u00eancias em que houve gozo de benef\u00edcio pago na via administrativa, mas tamb\u00e9m deduzir e\/ou compensar valores a maior pagos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-2-nbsp-analise-estrategica\"><a>8.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>8.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 8.213\/1991:<\/p>\n\n\n\n<p>Art.&nbsp;124.&nbsp;Salvo no caso de direito adquirido, n\u00e3o \u00e9 permitido o recebimento conjunto dos seguintes benef\u00edcios da Previd\u00eancia Social:<\/p>\n\n\n\n<p>I &#8211; aposentadoria e aux\u00edlio-doen\u00e7a;<\/p>\n\n\n\n<p>II &#8211; mais de uma aposentadoria;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>III &#8211; aposentadoria e abono de perman\u00eancia em servi\u00e7o;<\/p>\n\n\n\n<p>IV &#8211; sal\u00e1rio-maternidade e aux\u00edlio-doen\u00e7a;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>V &#8211; mais de um aux\u00edlio-acidente;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>VI &#8211; mais de uma pens\u00e3o deixada por c\u00f4njuge ou companheiro, ressalvado o direito de op\u00e7\u00e3o pela mais vantajosa.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Par\u00e1grafo \u00fanico. \u00c9 vedado o recebimento conjunto do seguro-desemprego com qualquer benef\u00edcio de presta\u00e7\u00e3o continuada da Previd\u00eancia Social, exceto pens\u00e3o por morte ou aux\u00edlio-acidente.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-2-nbsp-nbsp-nbsp-a-compensacao-limita-se-ao-valor-do-titulo-judicial\"><a>8.2.2.&nbsp;&nbsp;&nbsp; A compensa\u00e7\u00e3o limita-se ao valor do t\u00edtulo judicial?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Exatamente!!!!<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia circunscreve-se \u00e0 defini\u00e7\u00e3o sobre qual a forma de compensa\u00e7\u00e3o das presta\u00e7\u00f5es previdenci\u00e1rias, recebidas na via administrativa, no momento da elabora\u00e7\u00e3o dos c\u00e1lculos de cumprimento de senten\u00e7a concessiva de outro benef\u00edcio, com elas n\u00e3o acumul\u00e1vel, \u00e0 luz do art. 124 da Lei n. 8.213\/1991 (Lei de Benef\u00edcios).<\/p>\n\n\n\n<p>O exame da mat\u00e9ria parte das seguintes premissas: (a) ambos os benef\u00edcios foram concedidos com atendimento aos seus requisitos e (b) s\u00e3o concomitantes em certo per\u00edodo.<\/p>\n\n\n\n<p>Assim, o objetivo \u00e9 decidir se, nos meses em que houver o percebimento (na via administrativa) de import\u00e2ncia maior que a estabelecida na via judicial, a dedu\u00e7\u00e3o (i) dever\u00e1 abranger todo o quantum recebido pelo benefici\u00e1rio naquela compet\u00eancia ou (ii) ter\u00e1 como teto o valor referente \u00e0 parcela fruto da coisa julgada.<\/p>\n\n\n\n<p>A mesma quest\u00e3o foi objeto de Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas &#8211; IRDR n. 5023872-14.2017.4.04.000 perante o Tribunal Regional Federal da 4\u00aa Regi\u00e3o (Tema 14), o qual definiu: &#8220;O procedimento no desconto de valores recebidos a t\u00edtulo de benef\u00edcios inacumul\u00e1veis quando o direito \u00e0 percep\u00e7\u00e3o de um deles transita em julgado ap\u00f3s o auferimento do outro, gerando cr\u00e9dito de proventos em atraso, deve ser realizado por compet\u00eancia e no limite do valor da mensalidade resultante da aplica\u00e7\u00e3o do julgado, evitando-se, desta forma, a execu\u00e7\u00e3o invertida ou a restitui\u00e7\u00e3o indevida de valores, haja vista o car\u00e1ter alimentar do benef\u00edcio previdenci\u00e1rio e a boa-f\u00e9 do segurado, n\u00e3o se ferindo a coisa julgada, sem exist\u00eancia de &#8220;<em>refomatio in pejus<\/em>&#8220;, eis que h\u00e1 expressa determina\u00e7\u00e3o legal para tanto.&#8221;<\/p>\n\n\n\n<p>De fato, <strong>o art. 124 da Lei n. 8.213\/1991 veda o recebimento conjunto de benef\u00edcios substitutivos de renda, bem como de mais de um aux\u00edlio-acidente<\/strong>. E, na hip\u00f3tese, n\u00e3o houve percep\u00e7\u00e3o conjunta de benef\u00edcios. Contudo, na apura\u00e7\u00e3o do valor em cumprimento de senten\u00e7a, observou-se que as parcelas atrasadas alcan\u00e7avam um per\u00edodo em que o segurado havia usufru\u00eddo outro benef\u00edcio na via administrativa, o que acarreta a necessidade de compensa\u00e7\u00e3o entre tais verbas.<\/p>\n\n\n\n<p>Ocorre que o encontro de compet\u00eancias e, por conseguinte, a imposi\u00e7\u00e3o legal de compensar as parcelas inacumul\u00e1veis n\u00e3o transformam o recebimento de benef\u00edcio concedido mediante o preenchimento dos requisitos legais, no \u00e2mbito administrativo, em pagamento al\u00e9m do devido, de modo a se exigir sua restitui\u00e7\u00e3o aos cofres da autarquia, pois n\u00e3o se trata de pagamento por erro da Administra\u00e7\u00e3o ou por m\u00e1-f\u00e9.<\/p>\n\n\n\n<p><strong>\u00c9 poss\u00edvel que uma presta\u00e7\u00e3o previdenci\u00e1ria concedida na via administrativa seja superior \u00e0quela devida por for\u00e7a do t\u00edtulo judicial transitado em julgado, pois o seu valor depende da esp\u00e9cie de benef\u00edcio e do percentual estabelecido por lei a incidir na sua base de c\u00e1lculo<\/strong>. Isso ocorre porque \u00e9 a legisla\u00e7\u00e3o que determina os crit\u00e9rios para fixa\u00e7\u00e3o da Renda Mensal Inicial &#8211; RMI de cada presta\u00e7\u00e3o previdenci\u00e1ria. A RMI, por sua vez, \u00e9 apurada com base no Sal\u00e1rio de Benef\u00edcio (SB), que \u00e9 a m\u00e9dia dos sal\u00e1rios de contribui\u00e7\u00e3o do segurado. Ainda, cada esp\u00e9cie de benef\u00edcio previdenci\u00e1rio possui um percentual espec\u00edfico que incidir\u00e1 sobre o sal\u00e1rio de benef\u00edcio.<\/p>\n\n\n\n<p>Assim, a depender do percentual do sal\u00e1rio de benef\u00edcio estipulado na norma, haver\u00e1 diferen\u00e7a de valores. Al\u00e9m desse aspecto, a incid\u00eancia, ou n\u00e3o, de fator previdenci\u00e1rio, de igual modo, implica altera\u00e7\u00e3o na RMI, e tudo isso pode elevar a renda mensal de uma aposentadoria em rela\u00e7\u00e3o a outra, ainda que relativa ao mesmo segurado.<\/p>\n\n\n\n<p>Portanto, eventuais diferen\u00e7as a maior decorrentes, frise-se, de crit\u00e9rios legais n\u00e3o podem ser decotadas, pois, al\u00e9m de serem verbas de natureza alimentar recebidas de boa-f\u00e9, s\u00e3o inerentes ao pr\u00f3prio c\u00e1lculo do benef\u00edcio deferido na forma da lei, ao qual a parte exequente fez jus.<\/p>\n\n\n\n<p>Ademais, o cumprimento de senten\u00e7a deve observar o t\u00edtulo judicial, sendo incab\u00edvel falar em excesso de execu\u00e7\u00e3o por falta de abatimento total das parcelas pagas administrativamente. Entendimento contr\u00e1rio levaria a uma execu\u00e7\u00e3o invertida, pois tornaria o segurado-exequente em devedor, em certas compet\u00eancias, o que n\u00e3o se pode admitir, sobretudo quando o indeferimento indevido de benef\u00edcios tem ocasionado demasiada judicializa\u00e7\u00e3o de demandas previdenci\u00e1rias.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>8.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>E-Hub Tecnologia Ltda impetrou mandado de seguran\u00e7a por meio do qual intenta ter declarado direito \u00e0 n\u00e3o incid\u00eancia da contribui\u00e7\u00e3o patronal sobre o adicional de insalubridade. A Fazenda Nacional n\u00e3o concorda com a tese e sustenta que, por se tratar de verba de natureza remunerat\u00f3ria, n\u00e3o haveria que se falar em n\u00e3o incid\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-9-nbsp-nbsp-nbsp-nbsp-incidencia-da-contribuicao-previdenciaria-patronal-sobre-adicional-de-insalubridade\"><a>9.&nbsp;&nbsp;&nbsp;&nbsp; Incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria patronal sobre adicional de insalubridade<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>Incide a contribui\u00e7\u00e3o previdenci\u00e1ria patronal sobre o adicional de insalubridade, em raz\u00e3o da sua natureza remunerat\u00f3ria.<\/p>\n\n\n\n<p>REsp 2.050.498-SP, Rel. Ministro Herman Benjamin, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 20\/6\/2024, DJe de 2\/7\/2024. (Tema 1252). (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-1-nbsp-situacao-fatica\"><a>9.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>E-Hub Tecnologia Ltda impetrou mandado de seguran\u00e7a por meio do qual intenta ter declarado direito a n\u00e3o incid\u00eancia da contribui\u00e7\u00e3o patronal sobre o adicional de insalubridade.<\/p>\n\n\n\n<p>A Fazenda Nacional n\u00e3o concorda com a tese e sustenta que, por se tratar de verba de natureza remunerat\u00f3ria, n\u00e3o haveria que se falar em n\u00e3o incid\u00eancia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-2-nbsp-analise-estrategica\"><a>9.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>9.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 8.212\/1991:<\/p>\n\n\n\n<p>Art. 22. A contribui\u00e7\u00e3o a cargo da empresa, destinada \u00e0 Seguridade Social, al\u00e9m do disposto no art. 23, \u00e9 de:&nbsp;<\/p>\n\n\n\n<p>I &#8211; vinte por cento sobre o total das remunera\u00e7\u00f5es pagas, devidas ou creditadas a qualquer t\u00edtulo, durante o m\u00eas, aos segurados empregados e trabalhadores avulsos que lhe prestem servi\u00e7os, destinadas a retribuir o trabalho, qualquer que seja a sua forma, inclusive as gorjetas, os ganhos habituais sob a forma de utilidades e os adiantamentos decorrentes de reajuste salarial, quer pelos servi\u00e7os efetivamente prestados, quer pelo tempo \u00e0 disposi\u00e7\u00e3o do empregador ou tomador de servi\u00e7os, nos termos da lei ou do contrato ou, ainda, de conven\u00e7\u00e3o ou acordo coletivo de trabalho ou senten\u00e7a normativa.<\/p>\n\n\n\n<p>Art. 28. Entende-se por sal\u00e1rio-de-contribui\u00e7\u00e3o:<\/p>\n\n\n\n<p>I &#8211; para o empregado e trabalhador avulso: a remunera\u00e7\u00e3o auferida em uma ou mais empresas, assim entendida a totalidade dos rendimentos pagos, devidos ou creditados a qualquer t\u00edtulo, durante o m\u00eas, destinados a retribuir o trabalho, qualquer que seja a sua forma, inclusive as gorjetas, os ganhos habituais sob a forma de utilidades e os adiantamentos decorrentes de reajuste salarial, quer pelos servi\u00e7os efetivamente prestados, quer pelo tempo \u00e0 disposi\u00e7\u00e3o do empregador ou tomador de servi\u00e7os nos termos da lei ou do contrato ou, ainda, de conven\u00e7\u00e3o ou acordo coletivo de trabalho ou senten\u00e7a normativa;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-2-nbsp-nbsp-nbsp-incide-a-contribuicao-patronal\"><a>9.2.2.&nbsp;&nbsp;&nbsp; Incide a contribui\u00e7\u00e3o patronal?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Com certeza!!!!<\/strong><\/p>\n\n\n\n<p>A contribui\u00e7\u00e3o previdenci\u00e1ria devida pela empresa encontra-se prevista na Constitui\u00e7\u00e3o Federal nos seguintes termos: &#8220;Art. 195. A seguridade social ser\u00e1 financiada por toda a sociedade, de forma direta e indireta, nos termos da lei, mediante recursos provenientes dos or\u00e7amentos da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios, e das seguintes contribui\u00e7\u00f5es sociais: I &#8211; do empregador, da empresa e da entidade a ela equiparada na forma da lei, incidentes sobre: a) a folha de sal\u00e1rios e demais rendimentos do trabalho pagos ou creditados, a qualquer t\u00edtulo, \u00e0 pessoa f\u00edsica que lhe preste servi\u00e7o, mesmo sem v\u00ednculo empregat\u00edcio.&#8221;.<\/p>\n\n\n\n<p><strong>A Constitui\u00e7\u00e3o Federal tamb\u00e9m estabelece que &#8220;os ganhos habituais do empregado, a qualquer t\u00edtulo, ser\u00e3o incorporados ao sal\u00e1rio para efeito de contribui\u00e7\u00e3o previdenci\u00e1ria e consequente repercuss\u00e3o em benef\u00edcios<\/strong>, nos casos e na forma da lei&#8221; (art. 201, \u00a711, da CF).<\/p>\n\n\n\n<p>No \u00e2mbito infraconstitucional, a Lei n. 8.212\/1991, em seu art. 22, I, determina que a contribui\u00e7\u00e3o previdenci\u00e1ria a cargo da empresa \u00e9 de &#8220;vinte por cento sobre o total das remunera\u00e7\u00f5es pagas, devidas ou creditadas a qualquer t\u00edtulo, durante o m\u00eas, aos segurados empregados e trabalhadores avulsos que lhe prestem servi\u00e7os, destinadas a retribuir o trabalho, qualquer que seja a sua forma, inclusive as gorjetas, os ganhos habituais sob a forma de utilidades e os adiantamentos decorrentes de reajuste salarial, quer pelos servi\u00e7os efetivamente prestados, quer pelo tempo \u00e0 disposi\u00e7\u00e3o do empregador ou tomador de servi\u00e7os, nos termos da lei ou do contrato ou, ainda, de conven\u00e7\u00e3o ou acordo coletivo de trabalho ou senten\u00e7a normativa&#8221;.<\/p>\n\n\n\n<p>O art. 28, I, da Lei n. 8.212\/1991, por seu turno, traz o conceito de sal\u00e1rio de contribui\u00e7\u00e3o para o empregado e trabalhador avulso como sendo &#8220;a remunera\u00e7\u00e3o auferida em uma ou mais empresas, assim entendida a totalidade dos rendimentos pagos, devidos ou creditados a qualquer t\u00edtulo, durante o m\u00eas, destinados a retribuir o trabalho, qualquer que seja a sua forma, inclusive as gorjetas, os ganhos habituais sob a forma de utilidades e os adiantamentos decorrentes de reajuste salarial, quer pelos servi\u00e7os efetivamente prestados, quer pelo tempo \u00e0 disposi\u00e7\u00e3o do empregador ou tomador de servi\u00e7os nos termos da lei ou do contrato ou, ainda, de conven\u00e7\u00e3o ou acordo coletivo de trabalho ou senten\u00e7a normativa;&#8221;.<\/p>\n\n\n\n<p>Diante disso, <strong>o STJ consolidou firme jurisprud\u00eancia no sentido de que n\u00e3o sofrem a incid\u00eancia de contribui\u00e7\u00e3o previdenci\u00e1ria &#8220;as import\u00e2ncias pagas a t\u00edtulo de indeniza\u00e7\u00e3o, que n\u00e3o correspondam a servi\u00e7os prestados nem a tempo \u00e0 disposi\u00e7\u00e3o do empregador<\/strong>&#8221; (REsp n. 1.230.957\/RS, Rel. Ministro Mauro Campbell Marques, Primeira Se\u00e7\u00e3o, DJe 18\/3\/2014, submetido ao art. 543-C do CPC). Por outro lado, <strong>se a verba trabalhista possuir natureza remunerat\u00f3ria, destinando-se a retribuir o trabalho, qualquer que seja a sua forma, ela deve integrar a base de c\u00e1lculo da contribui\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>No caso, verifica-se que o adicional de insalubridade est\u00e1 previsto na CLT com a seguinte reda\u00e7\u00e3o: &#8220;Art. 189 &#8211; Ser\u00e3o consideradas atividades ou opera\u00e7\u00f5es insalubres aquelas que, por sua natureza, condi\u00e7\u00f5es ou m\u00e9todos de trabalho, exponham os empregados a agentes nocivos \u00e0 sa\u00fade, acima dos limites de toler\u00e2ncia fixados em raz\u00e3o da natureza e da intensidade do agente e do tempo de exposi\u00e7\u00e3o aos seus efeitos.&#8221;.<\/p>\n\n\n\n<p>A orienta\u00e7\u00e3o pac\u00edfica das duas Turmas que comp\u00f5em a Primeira Se\u00e7\u00e3o do STJ \u00e9 no sentido de que o adicional de insalubridade possui natureza remunerat\u00f3ria, sujeitando-se \u00e0 incid\u00eancia da contribui\u00e7\u00e3o previdenci\u00e1ria patronal.<\/p>\n\n\n\n<p>Ademais, <strong>o adicional de insalubridade n\u00e3o consta no rol das verbas que n\u00e3o integram o conceito de sal\u00e1rio de contribui\u00e7\u00e3o, listadas no \u00a7 9\u00b0 do art. 28 da Lei n. 8.212\/1991, uma vez que n\u00e3o \u00e9 import\u00e2ncia recebida a t\u00edtulo de ganhos eventuais, mas, sim, de forma habitual<\/strong>. Desse modo, em se tratando de verba de natureza SALARIAL, \u00e9 leg\u00edtima a incid\u00eancia de contribui\u00e7\u00e3o previdenci\u00e1ria a cargo da empresa sobre o adicional de insalubridade.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-3-nbsp-nbsp-nbsp-resultado-final\"><a><\/a><a><\/a><a><\/a><a><\/a><a>9.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Incide a contribui\u00e7\u00e3o previdenci\u00e1ria patronal sobre o adicional de insalubridade, em raz\u00e3o da sua natureza remunerat\u00f3ria.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-empresarial\"><a>DIREITO EMPRESARIAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-10-nbsp-im-possibilidade-da-arguicao-de-nulidade-como-materia-de-defesa-em-acao-de-infracao-de-desenho-industrial\"><a>10.&nbsp; (Im)Possibilidade da argui\u00e7\u00e3o de nulidade como mat\u00e9ria de defesa em a\u00e7\u00e3o de infra\u00e7\u00e3o de desenho industrial.<\/a><\/h2>\n\n\n\n<p><strong>EMBARGOS DE DIVERG\u00caNCIA EM RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>\u00c9 poss\u00edvel a argui\u00e7\u00e3o de nulidade como mat\u00e9ria de defesa em a\u00e7\u00e3o de infra\u00e7\u00e3o de desenho industrial.<\/p>\n\n\n\n<p>EREsp 1.332.417-RS, Rel. Ministra Nancy Andrighi, Segunda Se\u00e7\u00e3o, por unanimidade, julgado em 12\/6\/2024, DJe 18\/6\/2024. (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-situacao-fatica\"><a>10.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Pardal Ltda ajuizou a\u00e7\u00e3o de obriga\u00e7\u00e3o de n\u00e3o fazer cumulada com perdas e danos em face de Mancha S.A., na qual alega a infra\u00e7\u00e3o a registro de desenho industrial.<\/p>\n\n\n\n<p>O tribunal local julgou o pedido procedente, mas Mancha interp\u00f4s recurso no qual defende a possibilidade de argui\u00e7\u00e3o de nulidade de patente e de desenho industrial como mat\u00e9ria de defesa em a\u00e7\u00f5es de infra\u00e7\u00e3o, ao contr\u00e1rio do que foi decidido em ac\u00f3rd\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a>10.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-1-questao-juridica\"><a>10.2.1. Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Constitui\u00e7\u00e3o da Rep\u00fablica:<\/p>\n\n\n\n<p>Art. 5\u00ba Todos s\u00e3o iguais perante a lei, sem distin\u00e7\u00e3o de qualquer natureza, garantindo-se aos brasileiros e aos estrangeiros residentes no Pa\u00eds a inviolabilidade do direito \u00e0 vida, \u00e0 liberdade, \u00e0 igualdade, \u00e0 seguran\u00e7a e \u00e0 propriedade, nos termos seguintes:<\/p>\n\n\n\n<p>LV &#8211; aos litigantes, em processo judicial ou administrativo, e aos acusados em geral s\u00e3o assegurados o contradit\u00f3rio e ampla defesa, com os meios e recursos a ela inerentes;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-2-possivel-a-arguicao-de-nulidade-como-materia-de-defesa\"><a>10.2.2. Poss\u00edvel a argui\u00e7\u00e3o de nulidade como mat\u00e9ria de defesa?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeap!!!!<\/strong><\/p>\n\n\n\n<p>A Lei n. 9.279\/1996 &#8211; Lei de Propriedade Industrial &#8211; exige, como regra, a participa\u00e7\u00e3o do Instituto Nacional de Propriedade Industrial &#8211; INPI, autarquia federal, nas a\u00e7\u00f5es que objetivam a declara\u00e7\u00e3o de nulidade de direitos da propriedade industrial (marca, patente e desenho industrial), de modo que \u00e9 da Justi\u00e7a Federal a compet\u00eancia para processar e julgar tais demandas.<\/p>\n\n\n\n<p>Esse mesmo diploma legal, no entanto, cont\u00e9m ressalva expressa no que diz respeito, especificamente, \u00e0s patentes e aos desenhos industriais, autorizando a argui\u00e7\u00e3o de nulidade pelo r\u00e9u, em a\u00e7\u00e3o de infra\u00e7\u00e3o, como mat\u00e9ria de defesa. Nessas hip\u00f3teses, como a rela\u00e7\u00e3o jur\u00eddica processual n\u00e3o \u00e9 integrada pelo INPI, n\u00e3o h\u00e1 falar em usurpa\u00e7\u00e3o de compet\u00eancia da Justi\u00e7a Federal.<\/p>\n\n\n\n<p>O reconhecimento da nulidade de patentes e de desenhos industriais pela Justi\u00e7a estadual, por ocorrer em car\u00e1ter incidental, somente opera efeitos i<em>nter partes<\/em>, podendo servir, exclusivamente, como fundamento condutor do julgamento de improced\u00eancia dos pedidos deduzidos na correlata a\u00e7\u00e3o de infra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ademais, havendo autoriza\u00e7\u00e3o expressa na Lei n. 9.279\/1996 acerca da possibilidade de argui\u00e7\u00e3o de nulidade de patentes e de desenhos industriais como mat\u00e9ria de defesa, obstar os efeitos da norma em quest\u00e3o resultaria em indevida restri\u00e7\u00e3o do direito fundamental \u00e0 ampla defesa, em clara viola\u00e7\u00e3o ao disposto no art. 5\u00ba, LV, da Constitui\u00e7\u00e3o da Rep\u00fablica.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-3-resultado-final\"><a>10.2.3. Resultado final.<\/a><\/h4>\n\n\n\n<p>\u00c9 poss\u00edvel a argui\u00e7\u00e3o de nulidade como mat\u00e9ria de defesa em a\u00e7\u00e3o de infra\u00e7\u00e3o de desenho industrial.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-penal\"><a>DIREITO PROCESSUAL PENAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-11-nbsp-fuga-ao-avistar-viatura-e-fundada-suspeita-para-realizacao-de-busca-pessoal\"><a>11.&nbsp; Fuga ao avistar viatura e fundada suspeita para realiza\u00e7\u00e3o de busca pessoal<\/a><\/h2>\n\n\n\n<p><strong>HABEAS CORPUS<\/strong><\/p>\n\n\n\n<p>Fugir correndo repentinamente ao avistar uma guarni\u00e7\u00e3o policial configura fundada suspeita a autorizar busca pessoal em via p\u00fablica, mas a prova desse motivo, cujo \u00f4nus \u00e9 do Estado, por ser usualmente amparada apenas na palavra dos policiais, deve ser submetida a especial escrut\u00ednio, o que implica recha\u00e7ar narrativas inveross\u00edmeis, incoerentes ou infirmadas por outros elementos dos autos.<\/p>\n\n\n\n<p>HC 877.943-MS, Rel. Ministro Rogerio Schietti Cruz, Terceira Se\u00e7\u00e3o, por unanimidade, julgado em 18\/4\/2024, DJe 15\/5\/2024. (Info 818 STJ)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-situacao-fatica\"><a>11.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creitinho avistou e foi avistado por viatura policial. Por quase que reflexo, o rapaz saiu correndo, mas foi alcan\u00e7ado e abordado pelos policiais. Realizada busca pessoal, foram encontradas drogas na posse do rapaz.<\/p>\n\n\n\n<p>Ap\u00f3s a condena\u00e7\u00e3o por tr\u00e1fico, a defesa de Creitinho impetrou Habeas Corpus no qual alega a nulidade da busca e apreens\u00e3o em raz\u00e3o da aus\u00eancia de fundada suspeita.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a>11.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-1-questao-juridica\"><a>11.2.1. Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo de Processo Penal:<\/p>\n\n\n\n<p>Art. 244.&nbsp; A busca pessoal independer\u00e1 de mandado, no caso de pris\u00e3o ou quando houver fundada suspeita de que a pessoa esteja na posse de arma proibida ou de objetos ou pap\u00e9is que constituam corpo de delito, ou quando a medida for determinada no curso de busca domiciliar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-2-fundada-suspeita\"><a>11.2.2. Fundada suspeita???<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong><strong> SIM sinh\u00f4!!!<\/strong><\/p>\n\n\n\n<p>No julgamento do RHC n. 158.580\/BA, a Sexta Turma do STJ prop\u00f4s criteriosa an\u00e1lise sobre a realiza\u00e7\u00e3o de buscas pessoais e apresentou como conclus\u00f5es, no que interessa: a) &#8220;Exige-se, em termos de&nbsp;<em>standard<\/em>&nbsp;probat\u00f3rio para busca pessoal ou veicular sem mandado judicial, a exist\u00eancia de fundada suspeita (justa causa) &#8211; baseada em um ju\u00edzo de probabilidade, descrita com a maior precis\u00e3o poss\u00edvel, aferida de modo objetivo e devidamente justificada pelos ind\u00edcios e circunst\u00e2ncias do caso concreto &#8211; de que o indiv\u00edduo esteja na posse de drogas, armas ou de outros objetos ou pap\u00e9is que constituam corpo de delito, evidenciando-se a urg\u00eancia de se executar a dilig\u00eancia&#8230;&#8221; b) &#8220;N\u00e3o satisfazem a exig\u00eancia legal, por si s\u00f3s, meras informa\u00e7\u00f5es de fonte n\u00e3o identificada (e.g. den\u00fancias an\u00f4nimas) ou intui\u00e7\u00f5es\/impress\u00f5es subjetivas, intang\u00edveis e n\u00e3o demonstr\u00e1veis de maneira clara e concreta, baseadas, por exemplo, exclusivamente, no tiroc\u00ednio policial&#8221;.<\/p>\n\n\n\n<p>No mesmo sentido, o Plen\u00e1rio do Supremo Tribunal Federal encampou essa compreens\u00e3o quanto \u00e0 necessidade de elementos objetivos para a busca, ao firmar a tese, no HC n. 208.240\/SP, de que &#8220;<strong>a busca pessoal, independente de mandado judicial, deve estar fundada em elementos indici\u00e1rios objetivos de que a pessoa esteja na posse de arma proibida, ou de objetos ou papeis que constituam corpo de delito, n\u00e3o sendo l\u00edcita a realiza\u00e7\u00e3o da medida com base na ra\u00e7a, sexo, orienta\u00e7\u00e3o sexual, cor da pele, ou apar\u00eancia f\u00edsica<\/strong>&#8220;.<\/p>\n\n\n\n<p>N\u00e3o se ignora que o STJ vem recha\u00e7ando a validade de buscas domiciliares realizadas com base apenas no fato de o suspeito haver corrido para dentro de casa ao avistar uma guarni\u00e7\u00e3o policial. Tamb\u00e9m n\u00e3o se desconhece a recente decis\u00e3o proferida sobre o tema pelo Plen\u00e1rio do Supremo Tribunal Federal no julgamento do HC n. 169.788\/SP. \u00c9 importante notar, por\u00e9m, que, ao contr\u00e1rio do que noticiaram alguns ve\u00edculos de informa\u00e7\u00e3o, embora a ordem de&nbsp;<em>habeas corpus<\/em>&nbsp;n\u00e3o haja sido concedida pela Suprema Corte, n\u00e3o houve maioria no colegiado para estabelecer a tese de que a fuga do suspeito para o interior da resid\u00eancia ao avistar a pol\u00edcia justifica, por si s\u00f3, o ingresso domiciliar. <strong>Assim, por imperativo de coer\u00eancia, \u00e9 necess\u00e1rio esclarecer o motivo pelo qual essa atitude, embora n\u00e3o justifique uma busca domiciliar sem mandado, pode justificar uma busca pessoal em via p\u00fablica. Para isso, \u00e9 preciso invocar a no\u00e7\u00e3o de&nbsp;<em>standards<\/em>&nbsp;probat\u00f3rios, os quais devem seguir uma tend\u00eancia progressiva, de acordo com a gravidade da medida a ser adotada<\/strong>.<\/p>\n\n\n\n<p>Enquanto a prote\u00e7\u00e3o contra buscas pessoais arbitr\u00e1rias est\u00e1 no C\u00f3digo de Processo Penal (art. 244) e decorre apenas indiretamente das prote\u00e7\u00f5es constitucionais \u00e0 privacidade, \u00e0 intimidade e \u00e0 liberdade, a inviolabilidade do domic\u00edlio est\u00e1 prevista expressamente em diversos diplomas internacionais de prote\u00e7\u00e3o aos direitos humanos e na Constitui\u00e7\u00e3o Federal, em inciso pr\u00f3prio do art. 5\u00ba, como cl\u00e1usula p\u00e9trea, al\u00e9m de a afronta a essa garantia ser criminalizada nos arts. 22 da Lei n. 13.869\/2019 e 150 do C\u00f3digo Penal. \u00c9 bem verdade que as buscas pessoais s\u00e3o invasivas e algumas delas eventualmente podem ser quase t\u00e3o constrangedoras quanto buscas domiciliares. No entanto, n\u00e3o h\u00e1 como negar a diferen\u00e7a jur\u00eddica de tratamento entre as medidas. Nesse sentido, o art. 5\u00ba, XI, da Constitui\u00e7\u00e3o Federal exige, para o ingresso domiciliar sem mandado judicial &#8211; ressalvadas as hip\u00f3teses de &#8220;prestar socorro&#8221; ou &#8220;desastre&#8221; -, a exist\u00eancia de flagrante delito.<\/p>\n\n\n\n<p>Ainda quanto ao assunto, o Supremo Tribunal Federal, no julgamento do Tema de Repercuss\u00e3o Geral n. 280, reputou necess\u00e1rio haver &#8220;fundadas raz\u00f5es&#8221; pr\u00e9vias quanto \u00e0 exist\u00eancia de situa\u00e7\u00e3o flagrancial no interior do im\u00f3vel. Assim, embora o STF n\u00e3o haja imposto um&nbsp;<em>standard<\/em>&nbsp;probat\u00f3rio de plena certeza, trata-se de uma exig\u00eancia elevada quanto \u00e0 prov\u00e1vel exist\u00eancia de flagrante delito, diante da ressaltada dimens\u00e3o que a prote\u00e7\u00e3o domiciliar ocupa e da interpreta\u00e7\u00e3o restritiva que se deve atribuir \u00e0s exce\u00e7\u00f5es a essa garantia fundamental. E, ao contr\u00e1rio do que se d\u00e1 na busca pessoal, o direito \u00e0 inviolabilidade do domic\u00edlio n\u00e3o protege apenas o alvo de uma atua\u00e7\u00e3o policial, mas todo o grupo de pessoas que residem ou se encontram no local da dilig\u00eancia.<\/p>\n\n\n\n<p>No que concerne \u00e0s buscas pessoais, apesar de evidentemente n\u00e3o poderem ser realizadas sem crit\u00e9rio leg\u00edtimo, o que a lei exige \u00e9 a presen\u00e7a de fundada suspeita da posse de objeto que constitua corpo de delito, isto \u00e9, uma suspei\u00e7\u00e3o razoavelmente amparada em algo s\u00f3lido, concreto e objetivo, que se diferencie da mera suspeita intuitiva e subjetiva.<\/p>\n\n\n\n<p>\u00c9 poss\u00edvel cogitar quatro motivos principais para que algu\u00e9m empreenda fuga ao avistar uma guarni\u00e7\u00e3o policial: a) estar praticando crime naquele exato momento (flagrante delito); b) estar na posse de objeto que constitua corpo de delito (o que nem sempre representa uma situa\u00e7\u00e3o flagrancial); c) estar em situa\u00e7\u00e3o de descumprimento de alguma medida judicial (por exemplo, medida cautelar de recolhimento noturno, pris\u00e3o domiciliar, mandado de pris\u00e3o em aberto etc.) ou cometendo irregularidade administrativa (v. g. dirigir sem habilita\u00e7\u00e3o); d) ter medo de sofrer pessoalmente algum abuso por parte da pol\u00edcia ou receio de ficar pr\u00f3ximo a eventual tiroteio e ser atingido por bala perdida, sobretudo nas comunidades perif\u00e9ricas habitadas por grupos vulner\u00e1veis e marginalizados, em que a viol\u00eancia policial e as intensas trocas de tiros entre policiais e criminosos s\u00e3o dados presentes da realidade.<\/p>\n\n\n\n<p><strong>Com base nessas premissas, diante da consider\u00e1vel variabilidade de poss\u00edveis explica\u00e7\u00f5es para essa atitude, entende-se que fugir correndo repentinamente ao avistar uma guarni\u00e7\u00e3o policial n\u00e3o configura, por si s\u00f3, flagrante delito, nem algo pr\u00f3ximo disso para justificar que se excepcione a garantia constitucional da inviolabilidade domiciliar. Trata-se, todavia, de conduta intensa e marcante que consiste em fato objetivo &#8211; n\u00e3o meramente subjetivo ou intuitivo -, vis\u00edvel, control\u00e1vel pelo judici\u00e1rio e que, embora possa ter outras explica\u00e7\u00f5es, no m\u00ednimo gera suspeita razo\u00e1vel<\/strong>, amparada em ju\u00edzo de probabilidade, sobre a posse de objeto que constitua corpo de delito (conceito mais amplo do que situa\u00e7\u00e3o de flagrante delito).<\/p>\n\n\n\n<p>Ademais, tamb\u00e9m n\u00e3o se trata de mera &#8220;suspeita baseada no estado emocional ou na idoneidade ou n\u00e3o da rea\u00e7\u00e3o ou forma de vestir&#8221; ou classifica\u00e7\u00e3o subjetiva de &#8220;certa rea\u00e7\u00e3o ou express\u00e3o corporal como nervosa&#8221;, o que \u00e9 insuficiente para uma busca pessoal, segundo decis\u00e3o proferida pela Corte Interamericana de Direitos Humanos no caso Fernandez Prieto e Tumbeiro v. Argentina. Fugir correndo \u00e9 mais do que uma mera rea\u00e7\u00e3o sutil, como seria o caso, por exemplo, de: a) um simples olhar (ou desvio de olhar), b) levantar-se (ou sentar-se), c) andar (ou parar de andar), d) mudar a dire\u00e7\u00e3o ou o passo, enfim, comportamentos naturais de qualquer pessoa que podem ser explicados por uma infinidade de raz\u00f5es, insuficientes, a depender do contexto, para classificar a pessoa que assim se comporta como suspeita. Essas rea\u00e7\u00f5es corporais, isoladamente, s\u00e3o assaz fr\u00e1geis para embasar de maneira s\u00f3lida uma suspei\u00e7\u00e3o; a fuga, por\u00e9m, se distingue por representar atitude intensa, n\u00edtida e ostensiva, dificilmente confund\u00edvel com uma mera rea\u00e7\u00e3o corporal natural.<\/p>\n\n\n\n<p>N\u00e3o se deve ignorar, entretanto, a possibilidade de que se criem discursos ou narrativas dos fatos para legitimar a dilig\u00eancia policial. Da\u00ed, por conseguinte, a necessidade de ser exercido um &#8220;especial escrut\u00ednio&#8221; sobre o depoimento policial, na linha do que prop\u00f4s o Ministro Gilmar Mendes por ocasi\u00e3o do julgamento do RE n. 603.616\/RO (Tema de Repercuss\u00e3o Geral n. 280): &#8220;O policial pode invocar o pr\u00f3prio testemunho para justificar a medida. Claro que o ingresso for\u00e7ado baseado em fatos presenciados pelo pr\u00f3prio policial que realiza a busca coloca o agente p\u00fablico em uma posi\u00e7\u00e3o de grande poder e, por isso mesmo, deve merecer especial escrut\u00ednio&#8221;.<\/p>\n\n\n\n<p>Trata-se, portanto, de abandonar a c\u00f4moda e antiga pr\u00e1tica de atribuir car\u00e1ter quase que inquestion\u00e1vel a depoimentos prestados por testemunhas policiais, como se fossem absolutamente imunes \u00e0 possibilidade de desviar-se da verdade; do contr\u00e1rio, deve-se submet\u00ea-los a cuidadosa an\u00e1lise de coer\u00eancia &#8211; interna e externa -, verossimilhan\u00e7a e conson\u00e2ncia com as demais provas dos autos.<\/p>\n\n\n\n<p>Assim, \u00e0 luz de todas essas pondera\u00e7\u00f5es, conclui-se que fugir correndo repentinamente ao avistar uma guarni\u00e7\u00e3o policial configura motivo id\u00f4neo para autorizar uma busca pessoal em via p\u00fablica. Por\u00e9m, a prova desse motivo, cujo \u00f4nus \u00e9 do Estado, por ser usualmente amparada apenas na palavra dos policiais, deve ser submetida a especial escrut\u00ednio, o que implica recha\u00e7ar narrativas inveross\u00edmeis, incoerentes ou infirmadas por outros elementos dos autos.<\/p>\n\n\n\n<p>No caso, o r\u00e9u, ao avistar uma viatura policial que fazia patrulhamento de rotina na regi\u00e3o dos fatos, correu, em fuga, para um terreno baldio, o que motivou a revista pessoal, na qual foram encontradas drogas. Assim, diante das premissas estabelecidas e da aus\u00eancia de elementos suficientes para infirmar ou desacreditar a vers\u00e3o policial, mostra-se configurada a fundada suspeita de posse de corpo de delito a autorizar a busca pessoal, nos termos do art. 244 do CPP.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-3-resultado-final\"><a>11.2.3. Resultado final.<\/a><\/h4>\n\n\n\n<p>Fugir correndo repentinamente ao avistar uma guarni\u00e7\u00e3o policial configura fundada suspeita a autorizar busca pessoal em via p\u00fablica, mas a prova desse motivo, cujo \u00f4nus \u00e9 do Estado, por ser usualmente amparada apenas na palavra dos policiais, deve ser submetida a especial escrut\u00ednio, o que implica recha\u00e7ar narrativas inveross\u00edmeis, incoerentes ou infirmadas por outros elementos dos autos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-12-nbsp-realizacao-de-julgamento-virtual-com-oposicao-das-partes-e-nulidade\"><a>12.&nbsp; Realiza\u00e7\u00e3o de julgamento virtual com oposi\u00e7\u00e3o das partes e nulidade<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO REGIMENTAL NO HABEAS CORPUS<\/strong><\/p>\n\n\n\n<p>A realiza\u00e7\u00e3o do julgamento de forma virtual, mesmo com a oposi\u00e7\u00e3o expressa da parte, n\u00e3o \u00e9, por si s\u00f3, causa de nulidade ou de cerceamento de defesa.<\/p>\n\n\n\n<p>AgRg no HC 832.679-BA, Rel. Ministro Ribeiro Dantas, Quinta Turma, por unanimidade, julgado em 15\/4\/2024, DJe 18\/4\/2024. <a>(Info 818 STJ)<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-12-1-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-situacao-fatica\"><a>12.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Em um processo criminal, foi realizado julgamento de forma virtual, mesmo com oposi\u00e7\u00e3o expressa da parte r\u00e9. Ap\u00f3s a condena\u00e7\u00e3o, a defesa impetrou Habeas Corpus no qual sustenta que tal pr\u00e1tica implicaria em nulidade e cerceamento de defesa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-12-2-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-nbsp-analise-estrategica\"><a>12.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-12-2-1-causa-de-nulidade\"><a>12.2.1. Causa de nulidade?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>N\u00e3o \u00e9 para tanto!!!<\/strong><\/p>\n\n\n\n<p>A jurisprud\u00eancia do STJ firmou-se no sentido que <strong>n\u00e3o h\u00e1, no ordenamento jur\u00eddico vigente, o direito de exigir que o julgamento ocorra por meio de sess\u00e3o presencial<\/strong>. Portanto, o fato de o julgamento ter sido realizado de forma virtual, mesmo com a oposi\u00e7\u00e3o expressa e tempestiva da parte, n\u00e3o \u00e9, por si s\u00f3, causa de nulidade ou cerceamento de defesa.<\/p>\n\n\n\n<p>Ademais, <strong>mesmo nas hip\u00f3teses em que cabe sustenta\u00e7\u00e3o oral, se o seu exerc\u00edcio for garantido e viabilizado na modalidade de julgamento virtual, n\u00e3o haver\u00e1 qualquer preju\u00edzo ou nulidade, ainda que a parte se oponha a essa forma de julgamento, porquanto o direito de sustentar oralmente as suas raz\u00f5es n\u00e3o significa o de, necessariamente, o fazer de forma presencial<\/strong>.<\/p>\n\n\n\n<p>Outrossim, n\u00e3o se demonstrou a necessidade de exclus\u00e3o do feito da pauta virtual, n\u00e3o sendo suficiente para tanto a mera alega\u00e7\u00e3o de que deve ser dada a oportunidade de acompanhamento do julgamento do recurso interposto e a indica\u00e7\u00e3o abstrata de relev\u00e2ncia da mat\u00e9ria.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-12-2-2-resultado-final\"><a>12.2.2. Resultado final.<\/a><\/h4>\n\n\n\n<p>A realiza\u00e7\u00e3o do julgamento de forma virtual, mesmo com a oposi\u00e7\u00e3o expressa da parte, n\u00e3o \u00e9, por si s\u00f3, causa de nulidade ou de cerceamento de defesa.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"Incorporar PDF\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-4aa9bcc6-29fb-4ac7-9e9a-6bb711f9c208\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/30082057\/stj-informativo-818.pdf\">stj-informativo-818<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/30082057\/stj-informativo-818.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-4aa9bcc6-29fb-4ac7-9e9a-6bb711f9c208\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mais um passo em nossa caminhada&#8230; Informativos n\u00ba 818 do STJ\u00a0COMENTADO entra na parada. Simbora! DOWNLOAD do PDF AQUI! DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp; Forma de c\u00e1lculo da tarifa progressiva dos servi\u00e7os de fornecimento de \u00e1gua e de esgoto sanit\u00e1rio em unidades compostas por v\u00e1rias economias e hidr\u00f4metro \u00fanico RECURSO ESPECIAL 1. Nos condom\u00ednios formados por m\u00faltiplas [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1436979","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STJ 818 Comentado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STJ 818 Comentado\" \/>\n<meta property=\"og:description\" content=\"Mais um passo em nossa caminhada&#8230; Informativos n\u00ba 818 do STJ\u00a0COMENTADO entra na parada. Simbora! DOWNLOAD do PDF AQUI! DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp; Forma de c\u00e1lculo da tarifa progressiva dos servi\u00e7os de fornecimento de \u00e1gua e de esgoto sanit\u00e1rio em unidades compostas por v\u00e1rias economias e hidr\u00f4metro \u00fanico RECURSO ESPECIAL 1. Nos condom\u00ednios formados por m\u00faltiplas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-30T11:21:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T11:21:12+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"76 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STJ 818 Comentado\",\"datePublished\":\"2024-07-30T11:21:10+00:00\",\"dateModified\":\"2024-07-30T11:21:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/\"},\"wordCount\":15137,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/\",\"name\":\"Informativo STJ 818 Comentado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2024-07-30T11:21:10+00:00\",\"dateModified\":\"2024-07-30T11:21:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STJ 818 Comentado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STJ 818 Comentado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STJ 818 Comentado","og_description":"Mais um passo em nossa caminhada&#8230; Informativos n\u00ba 818 do STJ\u00a0COMENTADO entra na parada. Simbora! DOWNLOAD do PDF AQUI! DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp; Forma de c\u00e1lculo da tarifa progressiva dos servi\u00e7os de fornecimento de \u00e1gua e de esgoto sanit\u00e1rio em unidades compostas por v\u00e1rias economias e hidr\u00f4metro \u00fanico RECURSO ESPECIAL 1. Nos condom\u00ednios formados por m\u00faltiplas [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-07-30T11:21:10+00:00","article_modified_time":"2024-07-30T11:21:12+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"76 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STJ 818 Comentado","datePublished":"2024-07-30T11:21:10+00:00","dateModified":"2024-07-30T11:21:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/"},"wordCount":15137,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/","name":"Informativo STJ 818 Comentado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2024-07-30T11:21:10+00:00","dateModified":"2024-07-30T11:21:12+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-818-comentado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STJ 818 Comentado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1436979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1436979"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1436979\/revisions"}],"predecessor-version":[{"id":1436983,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1436979\/revisions\/1436983"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1436979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1436979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1436979"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1436979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}