{"id":1430666,"date":"2024-07-19T11:00:00","date_gmt":"2024-07-19T14:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1430666"},"modified":"2024-07-17T17:34:12","modified_gmt":"2024-07-17T20:34:12","slug":"lei-organica-sao-paulo-planoplurianual","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/","title":{"rendered":"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual"},"content":{"rendered":"\n<p>Aprenda neste artigo tudo sobre o Plano Plurianual na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo e atropele a concorr\u00eancia!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/www.capital.sp.gov.br\/\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"268\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032446\/cidade-de-sao-paulo.png\" alt=\"logo da cidade de S\u00e3o Paulo. LOM-SP\" class=\"wp-image-1430667\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032446\/cidade-de-sao-paulo.png 762w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032446\/cidade-de-sao-paulo-300x106.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032446\/cidade-de-sao-paulo-610x215.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032446\/cidade-de-sao-paulo-150x53.png 150w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><\/a><\/figure>\n\n\n\n<p>Ol\u00e1 Estrategistas! Esperamos que estejam estudando o m\u00e1ximo poss\u00edvel!<\/p>\n\n\n\n<p>No artigo de hoje trataremos do <strong>Plano Plurianual<\/strong> <strong>na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo <\/strong>. Concurseiros que far\u00e3o as provas do IPREM\/SP (<strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iprem-sp\/\">com edital j\u00e1 publicado<\/a><\/strong>) e da<strong> <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cgm-sp\/\">Controladoria Geral do Munic\u00edpio de S\u00e3o Paulo (CGM-SP)<\/a><\/strong> podem se servir desse precioso material.<\/p>\n\n\n\n<p>Est\u00e1 prevista a cobran\u00e7a de LOM-SP no seu edital? <strong>Serve para voc\u00ea tamb\u00e9m<\/strong>!<\/p>\n\n\n\n<p>O objetivo desse artigo \u00e9 <strong>trazer de forma organizada e objetiva<\/strong> os dispositivos da Lei Org\u00e2nica de S\u00e3o Paulo que tratam especificamente do Plano Plurianual, nos moldes de <strong>perguntas e respostas.<\/strong><\/p>\n\n\n\n<p>Caso queira ler a LOM-SP na \u00edntegra <a href=\"https:\/\/www.saopaulo.sp.leg.br\/atividade-legislativa\/lei-organica-do-municipio\/\">CLIQUE AQUI.<\/a><\/p>\n\n\n\n<p>Neste artigo trataremos responderemos \u00e0s seguintes perguntas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Qual a import\u00e2ncia do PPA no mun\u00edcipio de S\u00e3o Paulo?<\/li>\n\n\n\n<li>Mas o que \u00e9 o Plano Plurianual afinal?<\/li>\n\n\n\n<li>De quem \u00e9 a iniciativa do Plano Plurianual no munic\u00edpio de S\u00e3o Paulo?<\/li>\n\n\n\n<li>Quais os prazos relativos ao Plano Plurianual na LOM-SP?<\/li>\n\n\n\n<li>No Poder Legislativo da cidade de S\u00e3o Paulo quem examina o Plano Plurianual?<\/li>\n\n\n\n<li>O Plano Plurianual serve de par\u00e2metro para outros instrumentos de planejamento?<\/li>\n\n\n\n<li>O que cont\u00e9m na lei que institui o Plano Plurianual?<\/li>\n\n\n\n<li>Qual o qu\u00f3rum de aprova\u00e7\u00e3o da lei que institui o Plano Plurianual?<\/li>\n\n\n\n<li>Existe participa\u00e7\u00e3o popular na Elabora\u00e7\u00e3o do Plano Plurianual de S\u00e3o Paulo?<\/li>\n\n\n\n<li>Quem deve avaliar o cumprimento do PPA municipal?<\/li>\n\n\n\n<li>Existem outros artigos na LOM-SP sobre o PPA que eu devo dar aten\u00e7\u00e3o?<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-85cab2a5e747f5ee9d58bd993fb30af0\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/depoimento\/entrevista-carlos-henrique-von-muhlen-de-sales-aprovado-em-27-lugar-no-concurso-ipea-para-o-cargo-de-gestao-e-logistica\/\">Entrevista com 27\u00ba lugar no IPEA para o cargo Gest\u00e3o e Log\u00edstica<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-qual-a-importancia-do-ppa-no-municipio-de-sao-paulo\">Qual a import\u00e2ncia do PPA no mun\u00edcipio de S\u00e3o Paulo?<\/h2>\n\n\n\n<p>Segundo a Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo (LOM-SP) o Plano Plurianual integra o planejamento municipal. O planejamento \u00e9 importante para definir as estrat\u00e9gias de a\u00e7\u00e3o do poder p\u00fablico municipal durante determinado per\u00edodo de tempo. Lembre-se: Sem planejamento, n\u00e3o h\u00e1 como efetuar uma bom controle.<\/p>\n\n\n\n<p class=\"has-text-align-left\">\u201c<em>Art. 144:<\/em> <em>Integram o processo de planejamento os seguintes planos: &#8230; II &#8211; o plano plurianual;<\/em>\u201d<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mas-o-que-e-o-plano-plurianual-afinal\">Mas o que \u00e9 o Plano Plurianual afinal?<\/h2>\n\n\n\n<p>O PPA \u00e9 o instrumento de planejamento <strong>de m\u00e9dio prazo<\/strong>, formulado para o per\u00edodo de 4 anos, <strong>n\u00e3o coincidente<\/strong> com o mandato do chefe do Poder Executivo Municipal. Isso significa que o PPA em S\u00e3o Paulo <strong>\u00e9 v\u00e1lido a partir do 2\u00ba ano do mandato do chefe do Poder Executivo<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-de-quem-e-a-iniciativa-do-plano-plurianual-no-municipio-de-sao-paulo\">De quem \u00e9 a iniciativa do Plano Plurianual no munic\u00edpio de S\u00e3o Paulo?<\/h2>\n\n\n\n<p>Basicamente, cabe ao Chefe do Poder Executivo, na figura do <strong>Prefeito<\/strong>, propor o projeto de lei relativo ao PPA municipal. Essa compet\u00eancia \u00e9 <strong>privativa<\/strong> nos termos da LOM-SP.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Art. 137 &#8211; <strong>Leis de iniciativa do Poder Executivo Municipal<\/strong> estabelecer\u00e3o: I &#8211; o plano plurianual<\/em>\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 69 <strong>&#8211; Compete privativamente ao Prefeito<\/strong>, al\u00e9m de outras atribui\u00e7\u00f5es previstas nesta Lei<\/em>:<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>X <strong>&#8211; propor<\/strong> \u00e0 C\u00e2mara Municipal <strong>projetos de leis relativos ao plano plurianual<\/strong>, diretrizes or\u00e7ament\u00e1rias, or\u00e7amento anual, d\u00edvida p\u00fablica e opera\u00e7\u00f5es de cr\u00e9dito.\u201d<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-os-prazos-relativos-ao-plano-plurianual-na-lom-sp\">Quais os prazos relativos ao Plano Plurianual na LOM-SP?<\/h2>\n\n\n\n<p>O PPA municipal deve ser enviado pelo Prefeito \u00e0 C\u00e2mara Municipal at\u00e9 o dia <strong>30 de setembro (30\/09)<\/strong> do <strong>primeiro ano<\/strong> do mandato e ser\u00e1 votado e devolvido \u00e0 san\u00e7\u00e3o at\u00e9 o dia <strong>31 de dezembro (31\/12)<\/strong>. Veja que os prazos s\u00e3o diferentes daqueles previstos no PPA do governo federal. Fique atento!!<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 138, \u00a7 6\u00ba &#8211; \u201cOs projetos de lei do plano plurianual, das diretrizes or\u00e7ament\u00e1rias e do or\u00e7amento anual ser\u00e3o enviadas pelo Prefeito \u00e0 C\u00e2mara Municipal, nos termos da lei, e nos seguintes prazos:&#8230; II &#8211; <strong>plano plurianual<\/strong> e or\u00e7amento anual<strong>: 30 de setembro<\/strong>.\u201d<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u00a7 10 &#8211; O projeto de lei do plano plurianual encaminhado \u00e0 C\u00e2mara Municipal no prazo previsto no inciso II do \u00a7 6\u00ba deste artigo ser\u00e1 votado e <strong>remetido \u00e0 san\u00e7\u00e3o at\u00e9 31 de dezembro<\/strong>. (Acrescentados pela Emenda 24\/01)\u201d<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-no-poder-legislativo-da-cidade-de-sao-paulo-quem-examina-o-plano-plurianual\">No Poder Legislativo da cidade de S\u00e3o Paulo quem examina o Plano Plurianual?<\/h2>\n\n\n\n<p>A C\u00e2mara Municipal de S\u00e3o Paulo apreciar\u00e1 o PPA municipal <strong>atrav\u00e9s da Comiss\u00e3o de Finan\u00e7as e Or\u00e7amentos<\/strong> que <strong>examinar\u00e1 e emitir\u00e1 parecer<\/strong> sobre o projeto de lei enviado pelo Prefeito.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 138 &#8211; <strong>Os projetos de lei<\/strong> relativos ao <strong>plano plurianual<\/strong>, \u00e0s diretrizes or\u00e7ament\u00e1rias, ao or\u00e7amento anual e aos cr\u00e9ditos adicionais ser\u00e3o apreciados pela C\u00e2mara Municipal, na forma do Regimento Interno.<\/em><em>\u00a7 1\u00ba &#8211; <strong>Caber\u00e1 \u00e0 Comiss\u00e3o de Finan\u00e7as e Or\u00e7amento<\/strong>: I &#8211; examinar e emitir parecer sobre os projetos referidos neste artigo e sobre as contas apresentadas anualmente pelo Prefeito<\/em>\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-plano-plurianual-serve-de-parametro-para-outros-instrumentos-de-planejamento\">O Plano Plurianual serve de par\u00e2metro para outros instrumentos de planejamento?<\/h2>\n\n\n\n<p>N\u00e3o tenha d\u00favidas, amigo concurseiro! Aquilo que foi previsto no PPA municipal deve ser respeitado n\u00e3o s\u00f3 pela Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) e pela Lei Or\u00e7ament\u00e1ria Anual (LOA) mas tamb\u00e9m pelos planos e programas municipais, regionais e setoriais previstos na Lei Org\u00e2nica.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 138, \u00a7 3\u00ba &#8211; As <strong>emendas ao projeto de lei do or\u00e7amento anual<\/strong> ou aos projetos que o modifiquem somente podem ser aprovadas caso: I &#8211; <strong>sejam compat\u00edveis com o plano plurianual<\/strong> e com a lei de diretrizes or\u00e7ament\u00e1rias;<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u00a7 4\u00ba &#8211; As <strong>emendas ao projeto de lei de diretrizes or\u00e7ament\u00e1rias<\/strong> n\u00e3o poder\u00e3o ser aprovadas <strong>quando incompat\u00edveis com o plano plurianual<\/strong>.\u201d<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 137, \u00a7 4\u00ba &#8211; <strong>Os planos e programas municipais, regionais e setoriais previstos na Lei Org\u00e2nica<\/strong> ser\u00e3o <strong>elaborados em conson\u00e2ncia com o plano plurianual <\/strong>e apreciados pela C\u00e2mara Municipal\u201d.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-06c2a91f711034fa6d205f9df37743a9\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\">ESTUDE COM QUEM MAIS APROVA NO MERCADO!<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-contem-na-lei-que-institui-o-plano-plurianual\"><em>O que cont\u00e9m na lei que institui o Plano Plurianual?<\/em><\/h2>\n\n\n\n<p>O mnem\u00f4nico aqui \u00e9 <strong>DOM<\/strong>: <strong>Diretrizes, Objetivos e Metas<\/strong> da administra\u00e7\u00e3o p\u00fablica municipal. Segue a literalidade da LOM-SP:<\/p>\n\n\n\n<p class=\"has-text-align-left\">Art. 137, \u00a7 1\u00ba &#8211; \u201c<em>A lei que instituir o plano plurianual estabelecer\u00e1, <strong>de forma regionalizada<\/strong>, as <strong>diretrizes, objetivos e metas<\/strong> da administra\u00e7\u00e3o p\u00fablica municipal para as despesas de capital, e outras delas decorrentes, e para as relativas aos programas de dura\u00e7\u00e3o continuada.\u201d<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-qual-o-quorum-de-aprovacao-da-lei-que-institui-o-plano-plurianual\">Qual o qu\u00f3rum de aprova\u00e7\u00e3o da lei que institui o Plano Plurianual?<\/h2>\n\n\n\n<p>Nos estritos termos da LOM-SP, em seu art. 13, \u00a7 3\u00ba, o qu\u00f3rum de aprova\u00e7\u00e3o da lei do PPA \u00e9 de <strong>maioria absoluta<\/strong>! Leve a literalidade da Lei Org\u00e2nica e acerte a quest\u00e3o na sua prova!<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 13 &#8211; Cabe \u00e0 C\u00e2mara, com san\u00e7\u00e3o do Prefeito &#8230; dispor sobre as mat\u00e9rias de compet\u00eancia do Munic\u00edpio, especialmente: &#8230;IV &#8211; <strong>votar o plano plurianual<\/strong>, as diretrizes or\u00e7ament\u00e1rias e o or\u00e7amento anual, bem como autorizar a abertura de cr\u00e9ditos suplementares e especiais<\/em>.&#8221;<\/p>\n\n\n\n<p class=\"has-text-align-left\">&#8220;<em>\u00a7 3\u00ba &#8211; Depender\u00e3o do voto favor\u00e1vel <strong>da maioria absoluta<\/strong> dos membros da C\u00e2mara a aprova\u00e7\u00e3o e as altera\u00e7\u00f5es das seguintes mat\u00e9rias:<\/em> <em>IX &#8211; lei de diretrizes or\u00e7ament\u00e1rias, <strong>plano plurianual<\/strong> e lei or\u00e7ament\u00e1ria anual\u201d.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-existe-participacao-popular-na-elaboracao-do-plano-plurianual-de-sao-paulo\">Existe participa\u00e7\u00e3o popular na Elabora\u00e7\u00e3o do Plano Plurianual de S\u00e3o Paulo?<\/h2>\n\n\n\n<p>Sim! A LOM-SP prev\u00ea que uma lei vai dispor sobre o modo de participa\u00e7\u00e3o dos Conselhos, bem como das associa\u00e7\u00f5es representativas, no processo de planejamento municipal. Lembre-se: <strong>o PPA faz parte do processo de planejamento municipal<\/strong>. Al\u00e9m disso, ser\u00e3o realizadas, <strong>no m\u00ednimo<\/strong>, <strong>2 (duas) audi\u00eancia p\u00fablicas<\/strong> durante a tramita\u00e7\u00e3o do PPA municipal.<\/p>\n\n\n\n<p class=\"has-text-align-left\">\u201c<em>Art. 41 &#8211; A C\u00e2mara Municipal, atrav\u00e9s de suas Comiss\u00f5es Permanentes, na forma regimental e <strong>mediante pr\u00e9via e ampla publicidade<\/strong>, convocar\u00e1 obrigatoriamente <strong>pelo menos 2 (duas) audi\u00eancias p\u00fablicas<\/strong> durante a tramita\u00e7\u00e3o de projetos de leis que versem sobre: &#8230; <strong>II &#8211; plano plurianual<\/strong><\/em>.&#8221;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quem-deve-avaliar-o-cumprimento-do-ppa-municipal\">Quem deve avaliar o cumprimento do PPA municipal?<\/h2>\n\n\n\n<p>Segundo a LOM-SP, caber\u00e1 <strong>ao sistema de controle interno municipal<\/strong> a avalia\u00e7\u00e3o do cumprimento das metas do PPA.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 53 &#8211; Os Poderes Executivo e Legislativo manter\u00e3o, de forma integrada, sistema de controle interno, com a finalidade de: I &#8211; avaliar o adequado cumprimento das metas previstas no plano plurianual, a execu\u00e7\u00e3o dos programas de governo e dos or\u00e7amentos do Munic\u00edpio.\u201d<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-existem-outros-artigos-na-lom-sp-sobre-o-ppa-que-eu-devo-dar-atencao\">Existem outros artigos na LOM-SP sobre o PPA que eu devo dar aten\u00e7\u00e3o?<\/h2>\n\n\n\n<p>Como o \u201cseguro morreu de velho\u201d n\u00e3o custa nada apresentar outros artigos que tem o Plano Plurianual como tema principal. <strong>Leia-os com aten\u00e7\u00e3o!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 137, \u00a7 10<strong>. As diretrizes do Programa de Metas ser\u00e3o incorporadas<\/strong> ao projeto de lei que visar \u00e0 institui\u00e7\u00e3o do <strong>plano plurianual<\/strong> dentro do prazo legal definido para a sua apresenta\u00e7\u00e3o \u00e0 C\u00e2mara Municipal.\u201d<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>\u201cArt. 168 &#8230; O <strong>plano plurianual do Munic\u00edpio<\/strong>, as diretrizes or\u00e7ament\u00e1rias e o or\u00e7amento anual <strong>dar\u00e3o prioridade ao atendimento das necessidades sociais<\/strong> na distribui\u00e7\u00e3o dos recursos p\u00fablicos, destinando verbas especiais para programas de habita\u00e7\u00e3o para a popula\u00e7\u00e3o de baixa renda segundo avalia\u00e7\u00e3o s\u00f3cio-econ\u00f4mica realizada por \u00f3rg\u00e3o do Munic\u00edpio.\u201d<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao\">Conclus\u00e3o.<\/h2>\n\n\n\n<p>Chegamos ao final do artigo sobre a Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual.  Desejamos que este artigo tenha sido \u00fatil na sua prepara\u00e7\u00e3o.<\/p>\n\n\n\n<p>N\u00e3o tivemos a pretens\u00e3o de esgotar todos os aspectos relativos ao tema exposto. Para o necess\u00e1rio aprofundamento <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/concursos-tribunais-de-contas-nivel-superior-afo-orcamento-publico-e-lrf-curso-regular\/\"><strong>utilize nossos materiais em PDF e nossas aulas em V\u00eddeo<\/strong>.<\/a><\/p>\n\n\n\n<p>Os cursos do Estrat\u00e9gia Concursos <strong>s\u00e3o os mais completos do mercado<\/strong>. N\u00e3o \u00e9 \u00e0 toa que o Estrat\u00e9gia aprova mais do que qualquer outro curso preparat\u00f3rio. <strong>Confie nos nossos materiais!<\/strong><\/p>\n\n\n\n<p>Siga nossas redes sociais <strong>: <\/strong><strong><a href=\"https:\/\/www.youtube.com\/@EstrategiaConcursosBrasil\">youtube<\/a><\/strong><strong>, <a href=\"http:\/\/instagram.com\/estrategiaconcursos\/?hl=pt-br\">instagram<\/a><\/strong><strong>, <a href=\"http:\/\/facebook.com\/EstrategiaConcursos\">facebook<\/a><\/strong><\/p>\n\n\n\n<p>Ficamos por aqui! Bons estudos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p>Carlos Sales<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/pesquisa\/?q=IPREM\">Cursos e Assinaturas<\/a><\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-9f9c9963fb36cb6b51f3ca94751881cd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\"><strong>Concursos Abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background has-link-color wp-elements-e3c3f83efe17daeff0846d92047fd69d\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\"><strong>Concursos 2024<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>logotipo da Cidade de S\u00e3o Paulo<\/p>\n","protected":false},"author":2975,"featured_media":1430668,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220180,3766,214992,220183,2017,214710],"tags":[125,963,33862,221814,221816,221815],"tax_estado":[219963,219989],"class_list":["post-1430666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-controle-gestao","category-educacional","category-concursos-administrativos","category-fiscal-municipal","category-concursos-legislativos","category-tribunais-de-contas","tag-as-diretrizes-orcamentarias-e-o-plano-plurianual-sao-disciplinados-por-leis-cuja-iniciativa-e-do-poder-executivo-comentarios-cobra-se-a-literalidade-do-art-165-da-constituicao-federal-art-165-le","tag-cgm-sp","tag-concurso-prefeitura-de-sao-paulo","tag-iprem","tag-lei-organica-de-sao-paulo","tag-lom-sp","tax_estado-concursos-federais","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual<\/title>\n<meta name=\"description\" content=\"Aprenda neste artigo tudo sobre o Plano Plurianual na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo e atropele a concorr\u00eancia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual\" \/>\n<meta property=\"og:description\" content=\"Aprenda neste artigo tudo sobre o Plano Plurianual na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo e atropele a concorr\u00eancia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-19T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"257\" \/>\n\t<meta property=\"og:image:height\" content=\"311\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carlos Henrique Von Muhlen De Sales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Henrique Von Muhlen De Sales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/\"},\"author\":{\"name\":\"Carlos Henrique Von Muhlen De Sales\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6cc8afba454d81556360302a4bf29426\"},\"headline\":\"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual\",\"datePublished\":\"2024-07-19T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/\"},\"wordCount\":1645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png\",\"keywords\":[\"as diretrizes or\u00e7ament\u00e1rias e o plano plurianual s\u00e3o disciplinados por leis cuja iniciativa \u00e9 do Poder Executivo. Coment\u00e1rios: Cobra-se a literalidade do art. 165 da Constitui\u00e7\u00e3o Federal: Art. 165. Le\",\"cgm-sp\",\"Concurso Prefeitura de S\u00e3o Paulo\",\"IPREM\",\"Lei Org\u00e2nica de S\u00e3o Paulo\",\"LOM-SP\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)\",\"Educa\u00e7\u00e3o\",\"Executivo (Administrativa)\",\"Fiscal - Municipal (ISS)\",\"Legislativo\",\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/\",\"name\":\"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png\",\"datePublished\":\"2024-07-19T14:00:00+00:00\",\"description\":\"Aprenda neste artigo tudo sobre o Plano Plurianual na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo e atropele a concorr\u00eancia!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png\",\"width\":257,\"height\":311},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6cc8afba454d81556360302a4bf29426\",\"name\":\"Carlos Henrique Von Muhlen De Sales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/79a47320e5fedb7d4577321e45e23d8e1759973a4285dfb61043da7735c8d8b1?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/79a47320e5fedb7d4577321e45e23d8e1759973a4285dfb61043da7735c8d8b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/79a47320e5fedb7d4577321e45e23d8e1759973a4285dfb61043da7735c8d8b1?s=96&d=mm&r=g\",\"caption\":\"Carlos Henrique Von Muhlen De Sales\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carloshvms20gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual","description":"Aprenda neste artigo tudo sobre o Plano Plurianual na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo e atropele a concorr\u00eancia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/","og_locale":"pt_BR","og_type":"article","og_title":"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual","og_description":"Aprenda neste artigo tudo sobre o Plano Plurianual na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo e atropele a concorr\u00eancia!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-07-19T14:00:00+00:00","og_image":[{"width":257,"height":311,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png","type":"image\/png"}],"author":"Carlos Henrique Von Muhlen De Sales","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Carlos Henrique Von Muhlen De Sales","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/"},"author":{"name":"Carlos Henrique Von Muhlen De Sales","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6cc8afba454d81556360302a4bf29426"},"headline":"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual","datePublished":"2024-07-19T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/"},"wordCount":1645,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png","keywords":["as diretrizes or\u00e7ament\u00e1rias e o plano plurianual s\u00e3o disciplinados por leis cuja iniciativa \u00e9 do Poder Executivo. Coment\u00e1rios: Cobra-se a literalidade do art. 165 da Constitui\u00e7\u00e3o Federal: Art. 165. Le","cgm-sp","Concurso Prefeitura de S\u00e3o Paulo","IPREM","Lei Org\u00e2nica de S\u00e3o Paulo","LOM-SP"],"articleSection":["Concursos P\u00fablicos","Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)","Educa\u00e7\u00e3o","Executivo (Administrativa)","Fiscal - Municipal (ISS)","Legislativo","Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/","name":"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png","datePublished":"2024-07-19T14:00:00+00:00","description":"Aprenda neste artigo tudo sobre o Plano Plurianual na Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo e atropele a concorr\u00eancia!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/07\/16032816\/logo-cidade-de-sao-paulo.png","width":257,"height":311},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lei-organica-sao-paulo-planoplurianual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Lei Org\u00e2nica do Munic\u00edpio de S\u00e3o Paulo: Plano Plurianual"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6cc8afba454d81556360302a4bf29426","name":"Carlos Henrique Von Muhlen De Sales","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/79a47320e5fedb7d4577321e45e23d8e1759973a4285dfb61043da7735c8d8b1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79a47320e5fedb7d4577321e45e23d8e1759973a4285dfb61043da7735c8d8b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79a47320e5fedb7d4577321e45e23d8e1759973a4285dfb61043da7735c8d8b1?s=96&d=mm&r=g","caption":"Carlos Henrique Von Muhlen De Sales"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carloshvms20gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1430666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2975"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1430666"}],"version-history":[{"count":7,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1430666\/revisions"}],"predecessor-version":[{"id":1431311,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1430666\/revisions\/1431311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1430668"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1430666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1430666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1430666"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1430666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}