{"id":1429542,"date":"2024-07-17T11:00:00","date_gmt":"2024-07-17T14:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1429542"},"modified":"2024-07-17T17:30:00","modified_gmt":"2024-07-17T20:30:00","slug":"policia-penal-go-plano","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/","title":{"rendered":"Pol\u00edcia Penal GO: Plano de carreira promissor"},"content":{"rendered":"\n<p>Ol\u00e1, tudo bem com voc\u00ea? hoje vamos falar sobre <em>&#8220;Pol\u00edcia Penal GO: Plano de carreira promissor!&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" data-id=\"928257\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13144218\/goias.jpeg\" alt=\"Pol\u00edcia Penal GO: Plano de carreira promissor\" class=\"wp-image-928257\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13144218\/goias.jpeg 1020w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13144218\/goias-300x200.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13144218\/goias-768x512.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/13144218\/goias-610x407.jpeg 610w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-policia-penal-go-plano-de-carreira-promissor\">Pol\u00edcia Penal GO: Plano de carreira promissor<\/h2>\n\n\n\n<p>Como voc\u00ea j\u00e1 pode ter visto, foi publicado o edital do\u00a0<strong>concurso Pol\u00edcia Penal GO<\/strong>. De acordo com o documento, est\u00e3o sendo oferecidas\u00a0<strong>1.600 vagas imediatas de n\u00edvel superior<\/strong>.<\/p>\n\n\n\n<p>Inclusive, as oportunidades s\u00e3o destinadas \u00e0 carreira de\u00a0<strong>Policial Penal<\/strong>, distribu\u00eddas entre os sexos feminino e masculino, ampla concorr\u00eancia e pessoas com defici\u00eancia. <\/p>\n\n\n\n<p>Al\u00e9m disso, o sal\u00e1rio inicial \u00e9 de<strong>\u00a0R$ 5.971,42<\/strong>\u00a0para jornada de 40 horas semanais.<\/p>\n\n\n\n<p>Assim, a Pol\u00edcia Penal de Goi\u00e1s (GO) tem se destacado como um exemplo promissor de desenvolvimento de carreira no Brasil. <\/p>\n\n\n\n<p>Pensando nisso, esse artigo explora os detalhes e as perspectivas desse plano de carreira, ressaltando suas implica\u00e7\u00f5es para os profissionais da \u00e1rea e para a seguran\u00e7a p\u00fablica no estado.<\/p>\n\n\n\n<p>Al\u00e9m do alto n\u00famero de vagas ofertadas, neste concurso tamb\u00e9m chama a aten\u00e7\u00e3o pelos<strong>\u00a0sal\u00e1rios e benef\u00edcios<\/strong>, que ser\u00e3o oferecidos aos aprovados.<\/p>\n\n\n\n<p>Inclusive, seguindo consta no edital do concurso da Pol\u00edcia Penal GO, a remunera\u00e7\u00e3o inicial do aprovado ser\u00e1 de\u00a0<strong>R$5.971,41<\/strong>. Por sua vez, ao final da carreira, o valor poder\u00e1 chegar a<strong>\u00a0R$14.679,35<\/strong>.<\/p>\n\n\n\n<p>Al\u00e9m desse valor elencado no edital, o servidor ainda receber\u00e1 diversos incentivos, que incrementar\u00e3o a remunera\u00e7\u00e3o.<\/p>\n\n\n\n<p>Um dos principais incentivos \u00e9 a possibilidade de realizar o\u00a0<strong>Servi\u00e7o Extraordin\u00e1rio (AC4)<\/strong>. De acordo com a Portaria n\u00ba 0550\/2024, os valores variam segundo os dias da semana e o hor\u00e1rio em que \u00e9 realizado. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-policia-penal-go-plano\">Pol\u00edcia Penal GO: Plano<\/h3>\n\n\n\n<p><strong>Escala azul<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Per\u00edodo diurno (que vai das 5h1 \u00e0s 21h59): sendo o valor de segunda-feira a quinta-feira de\u00a0<strong>R$26,47<\/strong>; e<\/li>\n\n\n\n<li>Per\u00edodo noturno (que vai das 22h \u00e0s 5h): sendo o valor de segunda-feira a quinta-feira de\u00a0<strong>R$29,80<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p><strong>Escala vermelha<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Per\u00edodo diurno (que vai das 5h1 \u00e0s 21h59): sendo o valor de sexta-feira a domingo de\u00a0<strong>R$36,41<\/strong>; e<\/li>\n\n\n\n<li>Per\u00edodo noturno (que vai das 22h \u00e0s 5h):  sendo o valor de sexta-feira a domingo de\u00a0<strong>R$41,38<\/strong>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-distribuicao-das-vagas\">Distribui\u00e7\u00e3o das Vagas<\/h2>\n\n\n\n<p>Como falamos, s\u00e3o 1.600 oportunidades de garantir a vaga na Pol\u00edcia Penal de Goi\u00e1s. Essas vagas foram distribu\u00eddas por nove regionais prisionais, incluindo as cidades de Goi\u00e2nia, S\u00e3o Lu\u00eds de Montes Belos, Rio Verde, Aparecida de Goi\u00e2nia, Itabera\u00ed, Luzi\u00e2nia, Caldas Novas, Goian\u00e9sia e Formosa.<\/p>\n\n\n\n<p><strong>Sendo a distribui\u00e7\u00e3o das vagas da seguinte maneira:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1\u00aa-9\u00aa Regional Prisional &#8211; Goi\u00e2nia e Aparecida de Goi\u00e2nia: 390 vagas<\/li>\n\n\n\n<li>2\u00aa Regional &#8211; Itabera\u00ed: 90 vagas<\/li>\n\n\n\n<li>3\u00aa\/9\u00aa Regional &#8211; Luzi\u00e2nia: 280 vagas<\/li>\n\n\n\n<li>4\u00aa Regional &#8211; Caldas Novas: 140 vagas<\/li>\n\n\n\n<li>5\u00aa Regional &#8211; S\u00e3o Lu\u00eds de Montes Belos: 100 vagas<\/li>\n\n\n\n<li>6\u00aa Regional &#8211; Rio Verde: 259 vagas<\/li>\n\n\n\n<li>7\u00aa Regional &#8211; Goian\u00e9sia: 120 vagas<\/li>\n\n\n\n<li>8\u00aa\/9\u00aa Regional &#8211; Formosa: 221 vagas.<\/li>\n<\/ul>\n\n\n\n<p>Al\u00e9m disso, h\u00e1 reserva de 5% das vagas para Pessoas com Defici\u00eancia (PcD&#8217;s).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estrutura-da-prova-policia-penal-go-plano\">Estrutura da Prova &#8211; Pol\u00edcia Penal GO: Plano<\/h2>\n\n\n\n<p>Os candidatos do concurso Pol\u00edcia Penal de Goi\u00e1s ser\u00e3o avaliados por meio das seguintes etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Prova objetiva<\/strong>: com car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li><strong>Prova discursiva<\/strong>: com car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li><strong>Avalia\u00e7\u00e3o por equipe multiprofissional dos candidatos inscritos para as vagas PcD<\/strong>: com car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Avalia\u00e7\u00e3o m\u00e9dica<\/strong>: com car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Avalia\u00e7\u00e3o de aptid\u00e3o f\u00edsica<\/strong>: com car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Psicol\u00f3gica<\/strong>: com car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Avalia\u00e7\u00e3o de vida pregressa e investiga\u00e7\u00e3o social<\/strong>:\u00a0com car\u00e1ter eliminat\u00f3rio; e<\/li>\n\n\n\n<li><strong>Avalia\u00e7\u00e3o de t\u00edtulos<\/strong>: com car\u00e1ter classificat\u00f3rio.<\/li>\n<\/ul>\n\n\n\n<p>Assim, os candidatos ser\u00e3o avaliados por v\u00e1rias etapas, incluindo as fases objetivas e discursivas.<\/p>\n\n\n\n<p>Inclusive, as provas v\u00e3o ser aplicadas no\u00a0<strong>dia 15 de setembro<\/strong>, nas cidades de Goi\u00e2nia, Aparecida de Goi\u00e2nia, Itabera\u00ed, Luzi\u00e2nia, Caldas Novas, Formosa, Goian\u00e9sia, Rio Verde e S\u00e3o Lu\u00eds dos Montes Belos, no Estado de Goi\u00e1s.<\/p>\n\n\n\n<p>Nesse sentido, para as provas objetivas, o concurso Pol\u00edcia Penal de Goi\u00e1s cobrar\u00e1 as seguintes disciplinas:<\/p>\n\n\n\n<p><strong>Conhecimentos Gerais: Totalizando 30 quest\u00f5es<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa &#8211; 10 quest\u00f5es<\/li>\n\n\n\n<li>Realidade \u00c9tnica, Social, Hist\u00f3rica, Geogr\u00e1fica, Cultural, Pol\u00edtica e Econ\u00f4mica do Estado de Goi\u00e1s &#8211; 5 quest\u00f5es<\/li>\n\n\n\n<li>Racioc\u00ednio L\u00f3gico &#8211; 5 quest\u00f5es<\/li>\n\n\n\n<li>\u00c9tica no Servi\u00e7o P\u00fablico &#8211; 5 quest\u00f5es<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Inform\u00e1tica &#8211; 5 quest\u00f5es<\/li>\n<\/ul>\n\n\n\n<p><strong>Conhecimentos Espec\u00edficos: Totalizando 50 quest\u00f5es<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito Constitucional;<\/li>\n\n\n\n<li>Direito Administrativo;<\/li>\n\n\n\n<li>Direito Penal;<\/li>\n\n\n\n<li>Direito Processual Penal;<\/li>\n\n\n\n<li>Direitos Humanos;<\/li>\n\n\n\n<li>Lei de Execu\u00e7\u00e3o Penal;<\/li>\n\n\n\n<li>Lei Estadual n\u00ba 12.786\/1995; e<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Penal Extravagante.<\/li>\n<\/ul>\n\n\n\n<p>Portanto, ser\u00e1 aprovado o candidato que obtiver:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>no m\u00ednimo, 6 pontos na prova de Conhecimentos Gerais.<\/li>\n\n\n\n<li>no m\u00ednimo, 37,5 pontos na prova de Conhecimentos Espec\u00edficos.<\/li>\n\n\n\n<li>no m\u00ednimo, pontos do total da prova objetiva\u200b\u200b.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-conclusao-policia-penal-go-plano\">Conclus\u00e3o &#8211; Pol\u00edcia Penal GO: Plano<\/h3>\n\n\n\n<p>O plano de carreira da Pol\u00edcia Penal de Goi\u00e1s representa um avan\u00e7o significativo na valoriza\u00e7\u00e3o e profissionaliza\u00e7\u00e3o dos servidores penitenci\u00e1rios. Afinal, a Pol\u00edcia Penal de Goi\u00e1s apresenta uma estrutura bem definida, benef\u00edcios atraentes e oportunidades de crescimento.<\/p>\n\n\n\n<p>Essa oportunidade conta com 1.600 vagas imediatas de n\u00edvel superior, distribu\u00eddas entre diversas regionais do estado.<\/p>\n\n\n\n<p>Al\u00e9m disso, os sal\u00e1rios iniciais de R$ 5.971,42 para uma jornada de 40 horas semanais, com possibilidade de chegar a R$ 14.679,35 ao final da carreira, juntamente com os incentivos adicionais, tornam a carreira ainda mais atrativa. <\/p>\n\n\n\n<p>O plano de carreira estruturado proporciona um desenvolvimento profissional claro e progressivo, incentivando a qualifica\u00e7\u00e3o cont\u00ednua dos servidores.<\/p>\n\n\n\n<p>Portanto, o plano de carreira da Pol\u00edcia Penal de Goi\u00e1s \u00e9 promissor n\u00e3o apenas por oferecer boas condi\u00e7\u00f5es de trabalho e remunera\u00e7\u00e3o, mas tamb\u00e9m por contribuir significativamente para a seguran\u00e7a p\u00fablica do estado, ao promover a qualifica\u00e7\u00e3o e o desenvolvimento cont\u00ednuo de seus servidores.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-espero-que-voce-tenha-gostado-do-nosso-artigo-de-hoje\">Espero que voc\u00ea tenha gostado do nosso artigo de hoje!<\/h4>\n\n\n\n<p>Bom Estudo!<\/p>\n\n\n\n<p>Elizabeth Menezes <\/p>\n\n\n\n<p>@prof.elizabethmenezes<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_1KKFxYFXauE\"><div id=\"lyte_1KKFxYFXauE\" data-src=\"\/\/i.ytimg.com\/vi\/1KKFxYFXauE\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/1KKFxYFXauE\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/1KKFxYFXauE\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><a href=\"https:\/\/www.youtube.com\/watch?v=1KKFxYFXauE\">https:\/\/www.youtube.com\/watch?v=1KKFxYFXauE<\/a><\/figcaption><\/figure>\n\n\n<p><a href=\"https:\/\/www.policiapenal.go.gov.br\">https:\/\/www.policiapenal.go.gov.br<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-cyan-bluish-gray-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-cyan-bluish-gray-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\">Concursos 2024<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, tudo bem com voc\u00ea? hoje vamos falar sobre &#8220;Pol\u00edcia Penal GO: Plano de carreira promissor!&#8221; Pol\u00edcia Penal GO: Plano de carreira promissor Como voc\u00ea j\u00e1 pode ter visto, foi publicado o edital do\u00a0concurso Pol\u00edcia Penal GO. De acordo com o documento, est\u00e3o sendo oferecidas\u00a01.600 vagas imediatas de n\u00edvel superior. Inclusive, as oportunidades s\u00e3o destinadas [&hellip;]<\/p>\n","protected":false},"author":2277,"featured_media":983739,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220188],"tags":[],"tax_estado":[219963,219972],"class_list":["post-1429542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-agente-penitenciario","tax_estado-concursos-federais","tax_estado-go"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pol\u00edcia Penal GO: Plano de carreira promissor<\/title>\n<meta name=\"description\" content=\"Pol\u00edcia Penal GO: Plano de carreira promissor! Saiba tudo sobre o plano de carreira da Pol\u00edcia Penal de Goi\u00e1s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edcia Penal GO: Plano de carreira promissor\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edcia Penal GO: Plano de carreira promissor! Saiba tudo sobre o plano de carreira da Pol\u00edcia Penal de Goi\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-17T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T20:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elizabeth Menezes de Pinho Alves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elizabeth Menezes de Pinho Alves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/\"},\"author\":{\"name\":\"Elizabeth Menezes de Pinho Alves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562\"},\"headline\":\"Pol\u00edcia Penal GO: Plano de carreira promissor\",\"datePublished\":\"2024-07-17T14:00:00+00:00\",\"dateModified\":\"2024-07-17T20:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/\"},\"wordCount\":1045,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg\",\"articleSection\":[\"Policial (Agente Penitenci\u00e1rio)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/\",\"name\":\"Pol\u00edcia Penal GO: Plano de carreira promissor\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg\",\"datePublished\":\"2024-07-17T14:00:00+00:00\",\"dateModified\":\"2024-07-17T20:30:00+00:00\",\"description\":\"Pol\u00edcia Penal GO: Plano de carreira promissor! Saiba tudo sobre o plano de carreira da Pol\u00edcia Penal de Goi\u00e1s\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg\",\"width\":1024,\"height\":768,\"caption\":\"Pol\u00edcia Penal GO: Plano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edcia Penal GO: Plano de carreira promissor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562\",\"name\":\"Elizabeth Menezes de Pinho Alves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g\",\"caption\":\"Elizabeth Menezes de Pinho Alves\"},\"description\":\"Bacharel em Administra\u00e7\u00e3o pela UFPE, bacharelanda em Direito, p\u00f3s-graduada em Direito Administrativo e Constitucional. Come\u00e7ou em 2014 os estudos para concursos apenas para a \u00e1rea fiscal, por influ\u00eancia de amigos e familiares que trabalhavam na \u00e1rea. Ent\u00e3o, em 2017, com a abertura do concurso do Tribunal de Contas de Pernambuco, decidiu mudar o foco e aproveitar as oportunidades da \u00e1rea de controle, o que se mostrou uma excelente e acertada decis\u00e3o. Atualmente exerce o cargo de Auditor de Controle Externo no Tribunal de Contas do Estado de S\u00e3o Paulo, tendo tamb\u00e9m sido aprovada em: 5\u00b0 lugar para Auditor Fiscal de Garanhus - PE (2015), Auditor Fiscal de Goi\u00e2nia - GO (2016), Auditor Fiscal do Maranh\u00e3o (2016), Analista de Gest\u00e3o do TCE-PE (2017) e Auditor de Contas P\u00fablicas do TCE-PB (2018). Al\u00e9m disso, foi aprovada e nomeada em concursos de Auditor Fiscal Estadual, Municipal e da \u00e1rea de Controle.\",\"sameAs\":[\"https:\/\/www.instagram.com\/prof.elizabethmenezes\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/elizabethpinhoagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edcia Penal GO: Plano de carreira promissor","description":"Pol\u00edcia Penal GO: Plano de carreira promissor! Saiba tudo sobre o plano de carreira da Pol\u00edcia Penal de Goi\u00e1s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/","og_locale":"pt_BR","og_type":"article","og_title":"Pol\u00edcia Penal GO: Plano de carreira promissor","og_description":"Pol\u00edcia Penal GO: Plano de carreira promissor! Saiba tudo sobre o plano de carreira da Pol\u00edcia Penal de Goi\u00e1s","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-07-17T14:00:00+00:00","article_modified_time":"2024-07-17T20:30:00+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg","type":"image\/jpeg"}],"author":"Elizabeth Menezes de Pinho Alves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Elizabeth Menezes de Pinho Alves","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/"},"author":{"name":"Elizabeth Menezes de Pinho Alves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562"},"headline":"Pol\u00edcia Penal GO: Plano de carreira promissor","datePublished":"2024-07-17T14:00:00+00:00","dateModified":"2024-07-17T20:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/"},"wordCount":1045,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg","articleSection":["Policial (Agente Penitenci\u00e1rio)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/","name":"Pol\u00edcia Penal GO: Plano de carreira promissor","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg","datePublished":"2024-07-17T14:00:00+00:00","dateModified":"2024-07-17T20:30:00+00:00","description":"Pol\u00edcia Penal GO: Plano de carreira promissor! Saiba tudo sobre o plano de carreira da Pol\u00edcia Penal de Goi\u00e1s","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/09120906\/goias.jpeg","width":1024,"height":768,"caption":"Pol\u00edcia Penal GO: Plano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-go-plano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edcia Penal GO: Plano de carreira promissor"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562","name":"Elizabeth Menezes de Pinho Alves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g","caption":"Elizabeth Menezes de Pinho Alves"},"description":"Bacharel em Administra\u00e7\u00e3o pela UFPE, bacharelanda em Direito, p\u00f3s-graduada em Direito Administrativo e Constitucional. Come\u00e7ou em 2014 os estudos para concursos apenas para a \u00e1rea fiscal, por influ\u00eancia de amigos e familiares que trabalhavam na \u00e1rea. Ent\u00e3o, em 2017, com a abertura do concurso do Tribunal de Contas de Pernambuco, decidiu mudar o foco e aproveitar as oportunidades da \u00e1rea de controle, o que se mostrou uma excelente e acertada decis\u00e3o. Atualmente exerce o cargo de Auditor de Controle Externo no Tribunal de Contas do Estado de S\u00e3o Paulo, tendo tamb\u00e9m sido aprovada em: 5\u00b0 lugar para Auditor Fiscal de Garanhus - PE (2015), Auditor Fiscal de Goi\u00e2nia - GO (2016), Auditor Fiscal do Maranh\u00e3o (2016), Analista de Gest\u00e3o do TCE-PE (2017) e Auditor de Contas P\u00fablicas do TCE-PB (2018). Al\u00e9m disso, foi aprovada e nomeada em concursos de Auditor Fiscal Estadual, Municipal e da \u00e1rea de Controle.","sameAs":["https:\/\/www.instagram.com\/prof.elizabethmenezes\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/elizabethpinhoagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1429542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2277"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1429542"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1429542\/revisions"}],"predecessor-version":[{"id":1429600,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1429542\/revisions\/1429600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/983739"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1429542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1429542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1429542"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1429542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}