{"id":1415835,"date":"2024-06-24T08:00:00","date_gmt":"2024-06-24T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1415835"},"modified":"2024-06-18T18:14:55","modified_gmt":"2024-06-18T21:14:55","slug":"seguranca-informacao-iso-27005-2023","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/","title":{"rendered":"Universo Seguran\u00e7a da Informa\u00e7\u00e3o: NBR ISO\/IEC 27005:2023."},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-8e2a4af07f3003a8533125137aaf75dd\" id=\"h-introducao\">Introdu\u00e7\u00e3o<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Vamos retomar a nossa s\u00e9rie especial de temas sobre Seguran\u00e7a da Informa\u00e7\u00e3o.\u00a0 Neste artigo, voc\u00ea ver\u00e1 um resumo direto &#8220;e reto&#8221; sobre a NBR ISO\/IEC 27005:2023. Prepare-se!<\/p>\n\n\n\n<p>A norma brasileira (adaptada da internacional) sofreu uma atualiza\u00e7\u00e3o em 2023. Vamos apresentar alguns pontos importantes da norma, traduzidos da vers\u00e3o em ingl\u00eas, a fim de deix\u00e1-lo preparado para as provas. Veja o nosso roteiro ent\u00e3o:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Escopo da NBR ISO\/IEC 27005:2023 <\/strong><\/li>\n\n\n\n<li><strong>Gerenciamento de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Estabelecimento do Contexto<\/strong> <strong>na<\/strong> <strong>NBR ISO\/IEC 27005:2023 <\/strong><\/li>\n\n\n\n<li><strong>Processo de Avalia\u00e7\u00e3o de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Processo de Tratamento de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o<\/strong><\/li>\n\n\n\n<li><strong>Etapas Perif\u00e9ricas<\/strong> <strong>da NBR ISO\/IEC 27005:2023 <\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Preparamos um artigo objetivo, para que voc\u00ea consiga ter acesso ao conte\u00fado em poucos minutos. N\u00e3o deixe de ler caso esteja estudando para concursos da \u00e1rea de Tecnologia da Informa\u00e7\u00e3o (TI) ou outros que cobrem a disciplina de Seguran\u00e7a da Informa\u00e7\u00e3o. Tenha uma \u00f3tima leitura e vamos come\u00e7ar.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Tempo de leitura aproximada: 5 a 10 minutos<\/mark><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-e1b60f5d89a9452e3a617357414cd917\" id=\"h-escopo-da-nbr-iso-iec-27005-2023\">Escopo da NBR ISO\/IEC 27005:2023<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>A NBR ISO\/IEC 27005:2023 visa tra\u00e7ar a\u00e7\u00f5es para lidar com os riscos de Seguran\u00e7a da Informa\u00e7\u00e3o, al\u00e9m de realizar atividades de gerenciamento na \u00e1rea, especificamente avalia\u00e7\u00e3o e tratamento de riscos. Ela pode se aplicar a todas as organiza\u00e7\u00f5es, independente de tipo, tamanho ou setor. &nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-light-green-cyan-background-color has-background\"><strong>Momento Curiosidade:<\/strong> As siglas ISO e IEC s\u00e3o internacionais, indicando que a norma \u00e9 um padr\u00e3o mundial. ISO significa <em>International Organization for Standardization<\/em>, enquanto IEC significa <em>International Electrotechnical Commission<\/em>.<\/p>\n\n\n\n<p class=\"has-light-green-cyan-background-color has-background\"><strong>Mais Curiosidade:<\/strong> NBR \u00e9 abrevia\u00e7\u00e3o de norma brasileira. Ou seja, a NBR ISO\/IEC 27005:2023 \u00e9 a norma internacional ISO\/IEC 27005:2022 adaptada para o Brasil.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-45c63fa3c6e31f97ea135cf9d33a66e4\" id=\"h-gerenciamento-de-riscos-de-seguranca-da-informacao\">Gerenciamento de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Primeiramente, o processo de gerenciamento de riscos de Seguran\u00e7a da Informa\u00e7\u00e3o funciona de maneira iterativa. Guarde a figura abaixo, pois ela \u00e9 cl\u00e1ssica. Al\u00e9m disso, ela \u00e9 um resumo do que veremos no artigo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"900\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14202521\/processogerenciamentoriscos.png\" alt=\"Figura 1 \u2013 Processo de Gerenciamento de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o da NBR ISO\/IEC 27005:2023.\" class=\"wp-image-1415836\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14202521\/processogerenciamentoriscos.png 664w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14202521\/processogerenciamentoriscos-221x300.png 221w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14202521\/processogerenciamentoriscos-610x827.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14202521\/processogerenciamentoriscos-150x203.png 150w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><figcaption class=\"wp-element-caption\">Figura 1 \u2013 Processo de Gerenciamento de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o da NBR ISO\/IEC 27005:2023.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Primeiramente, estabelecemos um contexto interno e externo para o gerenciamento de riscos. Posteriormente, os riscos passam por uma macro etapa de avalia\u00e7\u00e3o, que consiste em sua identifica\u00e7\u00e3o, an\u00e1lise e avalia\u00e7\u00e3o propriamente dita.<\/p>\n\n\n\n<p>O risco pode seguir para o tratamento, dependendo se a avalia\u00e7\u00e3o foi satisfat\u00f3ria ou n\u00e3o (se n\u00e3o for, o fluxo vai se repetir). Ao t\u00e9rmino do tratamento, se for aceito, ele passa a ser monitorado e revisto. Caso n\u00e3o seja, o fluxo retorna.<\/p>\n\n\n\n<p>Veja que a comunica\u00e7\u00e3o e consulta, al\u00e9m de informa\u00e7\u00f5es documentadas, &nbsp;est\u00e3o presentes em v\u00e1rios momentos do fluxo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-c26858d85d99854b728d20dc4a6dbcf5\" id=\"h-estabelecimento-do-contexto-na-nbr-iso-iec-27005-2023\">Estabelecimento do Contexto na NBR ISO\/IEC 27005:2023<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>O contexto do gerenciamento de riscos envolve algumas quest\u00f5es, incluindo o ambiente em que a organiza\u00e7\u00e3o est\u00e1 inserida. Antes de mais nada, a organiza\u00e7\u00e3o precisa conhecer o seu apetite ao risco.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><strong>Voc\u00ea Sabia?<\/strong> Apetite ao risco \u00e9 a quantidade de risco que uma organiza\u00e7\u00e3o est\u00e1 disposta a assumir ou aceitar. O alto escal\u00e3o deve defini-lo e rev\u00ea-lo regularmente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Al\u00e9m disso, documentos de refer\u00eancia que definem regras e controles de seguran\u00e7a e que se aplicam no \u00e2mbito da avalia\u00e7\u00e3o de riscos de Seguran\u00e7a da Informa\u00e7\u00e3o precisam de identifica\u00e7\u00e3o. <\/p>\n\n\n\n<p>A organiza\u00e7\u00e3o tamb\u00e9m precisa estabelecer e manter crit\u00e9rios de riscos de Seguran\u00e7a da Informa\u00e7\u00e3o. Para isso, ela deve considerar a natureza e o tipo de incertezas que afetam os resultados e objetivos, previs\u00e3o e medi\u00e7\u00e3o de consequ\u00eancias e probabilidades, fatores temporais, n\u00edvel de risco etc.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-c006e73a315c98abc2d754d1724d2a31\" id=\"h-processo-de-avaliacao-de-riscos-de-seguranca-da-informacao\">Processo de Avalia\u00e7\u00e3o de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>A avalia\u00e7\u00e3o de riscos da NBR ISO\/IEC 27005:2023 permite que os propriet\u00e1rios priorizem os riscos alinhados com a perspectiva do tratamento, com base nas suas consequ\u00eancias e probabilidade ou outros crit\u00e9rios.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><strong>Voc\u00ea Sabia?<\/strong> O propriet\u00e1rio do risco possui autoridade e responsabilidade para gerir os riscos atribu\u00eddos a ele. Em organiza\u00e7\u00f5es s\u00e9rias, um propriet\u00e1rio costuma fazer a gest\u00e3o de mais de um risco, mas nunca todos. Normalmente, esse papel se divide entre pessoas diferentes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-luminous-vivid-orange-color has-text-color has-link-color wp-elements-d17198887b9f991e65569a0e5c7fc48a\" id=\"h-etapas-da-avaliacao\">Etapas da Avalia\u00e7\u00e3o<\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>O contexto da avalia\u00e7\u00e3o de riscos deve ser determinado, incluindo uma descri\u00e7\u00e3o do escopo e da finalidade, bem como das quest\u00f5es internas e externas que afetam a avalia\u00e7\u00e3o de riscos. O macroprocesso consiste nas seguintes atividades:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Identifica\u00e7\u00e3o de Riscos:<\/mark><\/strong> processo de encontrar, reconhecer e descrever riscos. A sa\u00edda deste processo \u00e9 uma <span style=\"text-decoration: underline;\">Lista de Riscos Identificados<\/span>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">An\u00e1lise de Riscos:<\/mark><\/strong> processo de compreender os tipos de risco elencados na lista e determinar seus n\u00edveis, mediante alguns crit\u00e9rios.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\"><strong>Voc\u00ea Sabia?<\/strong> As t\u00e9cnicas de an\u00e1lise de riscos podem ser qualitativas (adotam escala de atributos de qualifica\u00e7\u00e3o, tais como baixo, alto etc.), quantitativas (adotam escala com valores num\u00e9ricos (custo, probabilidade) ou semiquantitativas (adotam escala qualitativa com valores definidos).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"531\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14203203\/image-3-2.png\" alt=\"Figura 2 \u2013 Exemplo de Matriz para An\u00e1lise de Risco Qualitativa.\" class=\"wp-image-1415838\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14203203\/image-3-2.png 820w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14203203\/image-3-2-300x194.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14203203\/image-3-2-768x497.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14203203\/image-3-2-610x395.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14203203\/image-3-2-150x97.png 150w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><figcaption class=\"wp-element-caption\">Figura 2 \u2013 Exemplo de Matriz para An\u00e1lise de Risco Qualitativa (Fonte: RSData. Dispon\u00edvel em: <a href=\"https:\/\/www.rsdata.com.br\/matriz-de-risco-o-impasse\/\">https:\/\/www.rsdata.com.br\/matriz-de-risco-o-impasse\/<\/a>. Acesso em: 13 jun. 2024).<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Avalia\u00e7\u00e3o de Riscos:<\/mark><\/strong> processo de comparar os resultados da an\u00e1lise com crit\u00e9rios para determinar se o risco e\/ou sua import\u00e2ncia \u00e9 aceit\u00e1vel, al\u00e9m de prioriz\u00e1-lo \u200b\u200bpara tratamento.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background\" style=\"background-color:#9b51e06e\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">N\u00edvel do Risco<\/th><th class=\"has-text-align-center\" data-align=\"center\">Avalia\u00e7\u00e3o do Risco<\/th><th class=\"has-text-align-center\" data-align=\"center\">Descri\u00e7\u00e3o<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Baixo<\/strong><strong><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Aceit\u00e1vel<\/td><td class=\"has-text-align-center\" data-align=\"center\">O risco pode ser aceito sem nenhuma a\u00e7\u00e3o adicional.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Moderado<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Toler\u00e1vel sob controle<\/td><td class=\"has-text-align-center\" data-align=\"center\">Dever\u00e1 ser realizado um acompanhamento em termos de gest\u00e3o de riscos e definidas a\u00e7\u00f5es no \u00e2mbito da melhoria cont\u00ednua a m\u00e9dio e longo prazo.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Alto<\/strong><strong><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Inaceit\u00e1vel<\/td><td class=\"has-text-align-center\" data-align=\"center\">As medidas para reduzir o risco devem ser tomadas a curto prazo. Caso contr\u00e1rio, toda ou parte da atividade dever\u00e1 ser recusada.<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Tabela 1 \u2013 Exemplo de Escala para Avalia\u00e7\u00e3o do Risco de Seguran\u00e7a da Informa\u00e7\u00e3o.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-88a1624a227d4fd3e7e8a4426baf51cd\" id=\"h-processo-de-tratamento-de-riscos-de-seguranca-da-informacao\">Processo de Tratamento de Riscos de Seguran\u00e7a da Informa\u00e7\u00e3o<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>O tratamento dos riscos de seguran\u00e7a da informa\u00e7\u00e3o baseia-se nos resultados do processo de avalia\u00e7\u00e3o de riscos, conforme vimos anteriormente. Esses resultados apresentam um conjunto priorizado de riscos para tratamento.<\/p>\n\n\n\n<p>O conjunto de riscos ser\u00e1 tratado no <span style=\"text-decoration: underline;\">Plano de Tratamento de Riscos<\/span>. Parece f\u00e1cil de t\u00e3o intuitivo, mas \u00e9 isso mesmo. A ideia do plano \u00e9 decidir qual a\u00e7\u00e3o tomar sobre cada risco, de tal forma que atenda aos crit\u00e9rios desejados pela organiza\u00e7\u00e3o.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"556\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14204519\/trt13riscosplanodetratamentodosriscos-1-1024x556.png\" alt=\"Figura 3 \u2013 Exemplo de Plano de Tratamento de Riscos.\" class=\"wp-image-1415841\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14204519\/trt13riscosplanodetratamentodosriscos-1-1024x556.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14204519\/trt13riscosplanodetratamentodosriscos-1-300x163.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14204519\/trt13riscosplanodetratamentodosriscos-1-768x417.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14204519\/trt13riscosplanodetratamentodosriscos-1-610x331.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14204519\/trt13riscosplanodetratamentodosriscos-1-150x82.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14204519\/trt13riscosplanodetratamentodosriscos-1.png 1130w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Figura 3 \u2013 Exemplo de Plano de Tratamento de Riscos (Fonte: TRT-13\u00aa. Regi\u00e3o. Dispon\u00edvel em: <a href=\"https:\/\/www.trt13.jus.br\/age\/gestao-de-risco\">https:\/\/www.trt13.jus.br\/age\/gestao-de-risco<\/a>. Acesso em: 13 jun. 2024).<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>As a\u00e7\u00f5es para tratamento de risco denominam-se <span style=\"text-decoration: underline;\">Respostas ao Risco<\/span>. A NBR ISO\/IEC 27005:2023 destaca as seguintes op\u00e7\u00f5es abaixo. Procure decorar essa tabela tamb\u00e9m, pois isso despenca em prova:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background\" style=\"background-color:#9b51e06e\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Resposta ao Risco<\/th><th class=\"has-text-align-center\" data-align=\"center\">Descri\u00e7\u00e3o<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-vivid-red-color\">M<\/mark>itigar \/ Modificar<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Consiste em alterar a probabilidade de ocorr\u00eancia de um evento ou alterar a gravidade da consequ\u00eancia. O risco fica mais dif\u00edcil de ocorrer ou menos impactante. &nbsp;<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-vivid-red-color\">A<\/mark>ceitar \/ Reter<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Consiste em reconhecer o risco e n\u00e3o tomar nenhuma a\u00e7\u00e3o. \u00c9 uma estrat\u00e9gia muito adotada quando o custo para atuar sobre o risco ultrapassa a consequ\u00eancia que ele traria.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-vivid-red-color\">T<\/mark>ransferir \/ Compartilhar<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Consiste em dividir responsabilidades com outras partes, interna ou externamente. O exemplo cl\u00e1ssico \u00e9 contratar um seguro.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-vivid-red-color\">E<\/mark>vitar<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Consiste em decidir n\u00e3o iniciar ou continuar com a atividade que d\u00e1 origem ao risco.<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Tabela 2 \u2013 Respostas ao Risco da NBR ISO\/IEC 27005:2023.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Mnem\u00f4nico: <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-vivid-red-color\">MATE<\/mark> O RISCO!!<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Os riscos residuais s\u00e3o aqueles que permanecem mesmo ap\u00f3s o tratamento. Os propriet\u00e1rios dos riscos devem decidir sobre sua aceita\u00e7\u00e3o ou n\u00e3o, de acordo com crit\u00e9rios definidos. Caso n\u00e3o aceitem, novas a\u00e7\u00f5es podem ser aplicadas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-29a8b0f284a37ac21f8de5d8ae2fde1f\" id=\"h-etapas-perifericas-da-nbr-iso-iec-27005-2023\">Etapas Perif\u00e9ricas da NBR ISO\/IEC 27005:2023<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Uma vez tratado, n\u00e3o \u00e9 prudente que o risco seja esquecido. A organiza\u00e7\u00e3o deve revisit\u00e1-lo constantemente, por meio do Monitoramento e Revis\u00e3o, a fim de garantir que houve efetividade nas a\u00e7\u00f5es e evitar que outros riscos decorrentes surjam.<\/p>\n\n\n\n<p>As informa\u00e7\u00f5es sobre os riscos, suas causas, consequ\u00eancias, sua probabilidade e os controles realizados para trat\u00e1-los devem ser comunicadas ou obtidas das partes interessadas externas e internas. Essa \u00e9 a base da Comunica\u00e7\u00e3o e Consulta.<\/p>\n\n\n\n<p>Por fim, toda a gest\u00e3o dos riscos sustenta-se por meio da documenta\u00e7\u00e3o. Volte na Figura 1 e veja que a fase de Informa\u00e7\u00f5es Documentadas permeia todo o processo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-red-color has-text-color has-link-color wp-elements-afb9d8d5f80c728b1dd72a12fec5312d\" id=\"h-conclusao\">Conclus\u00e3o<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Hoje falamos sobre a nova vers\u00e3o da NBR ISO\/IEC 27005:2023, de uma maneira objetiva. Fique atento, porque as provas de TI que exigem a disciplina de Seguran\u00e7a da Informa\u00e7\u00e3o cobram muito essa norma.<\/p>\n\n\n\n<p>Sugerimos tamb\u00e9m que voc\u00ea aprofunde o conte\u00fado de Seguran\u00e7a da Informa\u00e7\u00e3o por meio dos materiais da plataforma. O Estrat\u00e9gia oferece diversos cursos em pdf, videoaulas e \u00e1udios para voc\u00ea ouvir onde quiser. Descubra tudo no <em>link<\/em> <a href=\"http:\/\/www.estrategiaconcursos.com.br\/cursos\/\">http:\/\/www.estrategiaconcursos.com.br\/cursos\/<\/a>.<\/p>\n\n\n\n<p>Por fim, \u00e9 importante que voc\u00ea fa\u00e7a muitas quest\u00f5es. Alunos aprovados realizam centenas ou at\u00e9 milhares de exerc\u00edcios para atingir seu objetivo. O acesso ao Sistema de Quest\u00f5es do Estrat\u00e9gia \u00e9 feito pelo <em>link<\/em>: <a href=\"https:\/\/concursos.estrategia.com\/\">https:\/\/concursos.estrategia.com\/<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Bons estudos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Cristiane Selem Ferreira Neves \u00e9 Bacharel em Ci\u00eancia da Computa\u00e7\u00e3o e Mestre em Sistemas de Informa\u00e7\u00e3o pela Universidade Federal do Rio de Janeiro (UFRJ), al\u00e9m de possuir a certifica\u00e7\u00e3o Project Management Professional pelo Project Management Institute (PMI). J\u00e1 foi aprovada nos seguintes concursos: ITERJ (2012), DATAPREV (2012), VALEC (2012), Rioprevid\u00eancia (2012\/2013), TJ-RJ (2022), TCE-RJ (2022) e CGE-SC (2022\/2023). Atualmente exerce o cargo efetivo de Auditora de Controle Externo \u2013 Tecnologia da Informa\u00e7\u00e3o e integra o corpo docente da Escola de Contas de Gest\u00e3o do TCE-RJ, al\u00e9m de ser produtora de conte\u00fado dos Blogs do Estrat\u00e9gia Concursos, OAB e Carreiras Jur\u00eddicas.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-de-concursos-previstos\"><strong>Quer Saber Tudo de Concursos Previstos?<\/strong><\/h4>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"h-confira-nossos-artigos\"><strong>Confira Nossos Artigos<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a a nova vers\u00e3o da norma brasileira ISO\/IEC 27005, atualizada em 2023, e fique bem preparado para as provas de Seguran\u00e7a da Informa\u00e7\u00e3o!<\/p>\n","protected":false},"author":2462,"featured_media":1415876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220215,220216,2313,1,220180,220184,220181,1983,220182,220183,220190,220191,1984,220737,214710],"tags":[40,221798,221198,25,1365],"tax_estado":[219964,219965,219966,219967,219968,219969,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1415835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-reguladora","category-agencia-reguladora-agencia-reguladora","category-carreiras-bancarias","category-cursos-e-concursos","category-controle-gestao","category-engenharias-e-ti","category-area-financeira","category-fiscal-estadual","category-fiscal-federal","category-fiscal-municipal","category-policial-peritos","category-previdenciaria","category-tribunais","category-tribunais-tribunais","category-tribunais-de-contas","tag-concurso","tag-iso-27005","tag-seguranca-da-informacao","tag-tecnologia-da-informacao","tag-ti-para-tribunais","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ISO 27005:2023: Universo Seguran\u00e7a da Informa\u00e7\u00e3o.<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a a nova vers\u00e3o da norma brasileira ISO\/IEC 27005, atualizada em 2023, e fique bem preparado para as provas de Seguran\u00e7a da Informa\u00e7\u00e3o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universo Seguran\u00e7a da Informa\u00e7\u00e3o: NBR ISO\/IEC 27005:2023.\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a a nova vers\u00e3o da norma brasileira ISO\/IEC 27005, atualizada em 2023, e fique bem preparado para as provas de Seguran\u00e7a da Informa\u00e7\u00e3o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-24T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristiane Selem Ferreira Neves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiane Selem Ferreira Neves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/\"},\"author\":{\"name\":\"Cristiane Selem Ferreira Neves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4afd42dbb493f6ef0c87baf438fd3904\"},\"headline\":\"Universo Seguran\u00e7a da Informa\u00e7\u00e3o: NBR ISO\/IEC 27005:2023.\",\"datePublished\":\"2024-06-24T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/\"},\"wordCount\":1686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg\",\"keywords\":[\"Concurso\",\"iso 27005\",\"Seguran\u00e7a da Informa\u00e7\u00e3o\",\"Tecnologia da Informa\u00e7\u00e3o\",\"TI para Tribunais\"],\"articleSection\":[\"Ag\u00eancia Reguladora\",\"Ag\u00eancia Reguladora\",\"Banc\u00e1ria (BB, CEF e Bancos Estaduais)\",\"Concursos P\u00fablicos\",\"Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)\",\"Engenharias e TI\",\"Financeira (BACEN, CVM, SUSEP e BNDES)\",\"Fiscal - Estadual (ICMS)\",\"Fiscal - Federal (RFB e AFT)\",\"Fiscal - Municipal (ISS)\",\"Policial (Peritos, Papiloscopistas)\",\"Previdenci\u00e1ria (INSS, PREVIC)\",\"Tribunais\",\"Tribunais\",\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/\",\"name\":\"ISO 27005:2023: Universo Seguran\u00e7a da Informa\u00e7\u00e3o.\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg\",\"datePublished\":\"2024-06-24T11:00:00+00:00\",\"description\":\"Conhe\u00e7a a nova vers\u00e3o da norma brasileira ISO\/IEC 27005, atualizada em 2023, e fique bem preparado para as provas de Seguran\u00e7a da Informa\u00e7\u00e3o!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universo Seguran\u00e7a da Informa\u00e7\u00e3o: NBR ISO\/IEC 27005:2023.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4afd42dbb493f6ef0c87baf438fd3904\",\"name\":\"Cristiane Selem Ferreira Neves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/75398471ed0bdb2b96874c4f62eccff4b792181d3ee38d22ddd2bcb33c82e45a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/75398471ed0bdb2b96874c4f62eccff4b792181d3ee38d22ddd2bcb33c82e45a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/75398471ed0bdb2b96874c4f62eccff4b792181d3ee38d22ddd2bcb33c82e45a?s=96&d=mm&r=g\",\"caption\":\"Cristiane Selem Ferreira Neves\"},\"description\":\"Cristiane Selem Ferreira Neves \u00e9 Bacharel em Ci\u00eancia da Computa\u00e7\u00e3o e Mestre em Sistemas de Informa\u00e7\u00e3o pela Universidade Federal do Rio de Janeiro (UFRJ), al\u00e9m de possuir a certifica\u00e7\u00e3o Project Management Professional pelo Project Management Institute (PMI). J\u00e1 foi aprovada nos seguintes concursos: ITERJ (2012), DATAPREV (2012), VALEC (2012), Rioprevid\u00eancia (2012\/2013), TJ-RJ (2022), TCE-RJ (2022) e CGE-SC (2022\/2023). Atualmente exerce o cargo efetivo de Auditora de Controle Externo \u2013 Tecnologia da Informa\u00e7\u00e3o e integra o corpo docente da Escola de Contas de Gest\u00e3o do TCE-RJ, al\u00e9m de ser produtora de conte\u00fado dos Blogs do Estrat\u00e9gia Concursos, OAB e Carreiras Jur\u00eddicas.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/cristianeselemgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ISO 27005:2023: Universo Seguran\u00e7a da Informa\u00e7\u00e3o.","description":"Conhe\u00e7a a nova vers\u00e3o da norma brasileira ISO\/IEC 27005, atualizada em 2023, e fique bem preparado para as provas de Seguran\u00e7a da Informa\u00e7\u00e3o!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/","og_locale":"pt_BR","og_type":"article","og_title":"Universo Seguran\u00e7a da Informa\u00e7\u00e3o: NBR ISO\/IEC 27005:2023.","og_description":"Conhe\u00e7a a nova vers\u00e3o da norma brasileira ISO\/IEC 27005, atualizada em 2023, e fique bem preparado para as provas de Seguran\u00e7a da Informa\u00e7\u00e3o!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-06-24T11:00:00+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg","type":"image\/jpeg"}],"author":"Cristiane Selem Ferreira Neves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Cristiane Selem Ferreira Neves","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/"},"author":{"name":"Cristiane Selem Ferreira Neves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4afd42dbb493f6ef0c87baf438fd3904"},"headline":"Universo Seguran\u00e7a da Informa\u00e7\u00e3o: NBR ISO\/IEC 27005:2023.","datePublished":"2024-06-24T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/"},"wordCount":1686,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg","keywords":["Concurso","iso 27005","Seguran\u00e7a da Informa\u00e7\u00e3o","Tecnologia da Informa\u00e7\u00e3o","TI para Tribunais"],"articleSection":["Ag\u00eancia Reguladora","Ag\u00eancia Reguladora","Banc\u00e1ria (BB, CEF e Bancos Estaduais)","Concursos P\u00fablicos","Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)","Engenharias e TI","Financeira (BACEN, CVM, SUSEP e BNDES)","Fiscal - Estadual (ICMS)","Fiscal - Federal (RFB e AFT)","Fiscal - Municipal (ISS)","Policial (Peritos, Papiloscopistas)","Previdenci\u00e1ria (INSS, PREVIC)","Tribunais","Tribunais","Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/","name":"ISO 27005:2023: Universo Seguran\u00e7a da Informa\u00e7\u00e3o.","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg","datePublished":"2024-06-24T11:00:00+00:00","description":"Conhe\u00e7a a nova vers\u00e3o da norma brasileira ISO\/IEC 27005, atualizada em 2023, e fique bem preparado para as provas de Seguran\u00e7a da Informa\u00e7\u00e3o!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/06\/14214402\/imagemdestaque.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/seguranca-informacao-iso-27005-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Universo Seguran\u00e7a da Informa\u00e7\u00e3o: NBR ISO\/IEC 27005:2023."}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4afd42dbb493f6ef0c87baf438fd3904","name":"Cristiane Selem Ferreira Neves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/75398471ed0bdb2b96874c4f62eccff4b792181d3ee38d22ddd2bcb33c82e45a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/75398471ed0bdb2b96874c4f62eccff4b792181d3ee38d22ddd2bcb33c82e45a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/75398471ed0bdb2b96874c4f62eccff4b792181d3ee38d22ddd2bcb33c82e45a?s=96&d=mm&r=g","caption":"Cristiane Selem Ferreira Neves"},"description":"Cristiane Selem Ferreira Neves \u00e9 Bacharel em Ci\u00eancia da Computa\u00e7\u00e3o e Mestre em Sistemas de Informa\u00e7\u00e3o pela Universidade Federal do Rio de Janeiro (UFRJ), al\u00e9m de possuir a certifica\u00e7\u00e3o Project Management Professional pelo Project Management Institute (PMI). J\u00e1 foi aprovada nos seguintes concursos: ITERJ (2012), DATAPREV (2012), VALEC (2012), Rioprevid\u00eancia (2012\/2013), TJ-RJ (2022), TCE-RJ (2022) e CGE-SC (2022\/2023). Atualmente exerce o cargo efetivo de Auditora de Controle Externo \u2013 Tecnologia da Informa\u00e7\u00e3o e integra o corpo docente da Escola de Contas de Gest\u00e3o do TCE-RJ, al\u00e9m de ser produtora de conte\u00fado dos Blogs do Estrat\u00e9gia Concursos, OAB e Carreiras Jur\u00eddicas.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/cristianeselemgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1415835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2462"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1415835"}],"version-history":[{"count":38,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1415835\/revisions"}],"predecessor-version":[{"id":1415890,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1415835\/revisions\/1415890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1415876"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1415835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1415835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1415835"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1415835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}