{"id":141076,"date":"2018-09-17T12:02:57","date_gmt":"2018-09-17T15:02:57","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=141076"},"modified":"2018-09-17T16:27:42","modified_gmt":"2018-09-17T19:27:42","slug":"gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/","title":{"rendered":"GABARITO PF 2018 &#8211; Direito Penal e Processual Penal (extraoficial) &#8211; Agente e Escriv\u00e3o"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><b>GABARITO PF 2018 &#8211; DIREITO PENAL E DIREITO PROCESSUAL PENAL (AGENTE E ESCRIV\u00c3O)<\/b><\/span><\/p>\n<p style=\"text-align: justify;\">Ol\u00e1, pessoal<\/p>\n<p style=\"text-align: justify;\">Para quem n\u00e3o me conhece ainda, meu nome \u00e9 <strong>Renan Araujo<\/strong> e sou professor aqui no Estrat\u00e9gia Concursos, lecionando as mat\u00e9rias de Direito Penal e Processual Penal.<\/p>\n<p style=\"text-align: justify;\">Antes de prosseguir, <span style=\"color: #ff0000;\"><strong>convido voc\u00ea a me seguir no INSTAGRAM<\/strong><\/span>:<strong>\u00a0<a href=\"http:\/\/www.instagram.com\/profrenanaraujo\/?hl=pt-br\">Instagram do Prof. Renan Araujo<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Neste artigo vamos comentar as quest\u00f5es de Direito Penal e Processual Penal que foram cobradas pelo CESPE, no<strong>\u00a0concurso da PF 2018 neste domingo, 16.09.2018.<\/strong><\/p>\n<p>Mas antes de conferir a corre\u00e7\u00e3o, n\u00e3o deixe de participar do\u00a0<strong><em>Ranking Pol\u00edcia Federal\u00a0<\/em><\/strong>para conferir seu desempenho na prova. Clique na imagem abaixo para cadastrar seu gabarito:<\/p>\n<p><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfrtcIsm3eLZ7-aVjgxz7o6NEgy2VTZ6cjwdT6ECWt5C9r9cg\/viewform\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-141175\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg\" alt=\"\" width=\"1184\" height=\"183\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg 1184w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg 610w\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Todas as quest\u00f5es foram exaustivamente abordadas em nosso curso, e tenho certeza de que nossos alunos se sa\u00edram bem. <span style=\"color: #0000ff;\"><strong>Inclusive, v\u00e1rias quest\u00f5es foram abordadas em nossa revis\u00e3o de v\u00e9spera, s\u00e1bado!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Vamos aos coment\u00e1rios:<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>ESCRIV\u00c3O \u2028<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; ESCRIV\u00c3O)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 33<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item errado, pois neste caso a pena ser\u00e1 aplicada em DOBRO, e n\u00e3o aumentada de metade, conforme art. 334-A do CP:<\/p>\n<p style=\"text-align: justify;\">Contrabando<\/p>\n<p style=\"text-align: justify;\">Art. 334-A. Importar ou exportar mercadoria proibida:\u00a0\u00a0(Inclu\u00eddo pela Lei n\u00ba 13.008, de 26.6.2014)<\/p>\n<p style=\"text-align: justify;\">Pena &#8211; reclus\u00e3o, de 2 (dois) a 5 ( cinco) anos.\u00a0\u00a0(Inclu\u00eddo pela Lei n\u00ba 13.008, de 26.6.2014)<\/p>\n<p style=\"text-align: justify;\">(&#8230;)<\/p>\n<p style=\"text-align: justify;\">\u00a7 3o\u00a0A pena aplica-se em dobro se o crime de contrabando \u00e9 praticado em transporte a\u00e9reo, mar\u00edtimo ou fluvial.\u00a0(Inclu\u00eddo pela Lei n\u00ba 13.008, de 26.6.2014)<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Errada<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; ESCRIV\u00c3O)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 34<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item errado, pois o prazo para conclus\u00e3o do IP, neste caso, ser\u00e1 de 15 dias, e n\u00e3o de 10 dias, na forma do art. 66 da Lei 5.010\/66:<\/p>\n<p style=\"text-align: justify;\">Art. 66. O prazo para conclus\u00e3o do inqu\u00e9rito policial ser\u00e1 de quinze dias, quando o indiciado estiver pr\u00easo, podendo ser prorrogado por mais quinze dias, a pedido, devidamente fundamentado, da autoridade policial e deferido pelo Juiz a que competir o conhecimento do processo.<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Errada<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; ESCRIV\u00c3O)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 35<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item errado, pois n\u00e3o basta apenas a indica\u00e7\u00e3o do local preciso em que ser\u00e1 realizada a dilig\u00eancia e a assinatura da autoridade, sendo necess\u00e1rias as demais informa\u00e7\u00f5es elencadas no art. 243 do CPP (como os fins da dilig\u00eancia, por exemplo):<\/p>\n<p style=\"text-align: justify;\">Art. 243.\u00a0 O mandado de busca dever\u00e1:<\/p>\n<p style=\"text-align: justify;\">I &#8211; indicar, o mais precisamente poss\u00edvel, a casa em que ser\u00e1 realizada a dilig\u00eancia e o nome do respectivo propriet\u00e1rio ou morador; ou, no caso de busca pessoal, o nome da pessoa que ter\u00e1 de sofr\u00ea-la ou os sinais que a identifiquem;<\/p>\n<p style=\"text-align: justify;\">II &#8211; mencionar o motivo e os fins da dilig\u00eancia;<\/p>\n<p style=\"text-align: justify;\">III &#8211; ser subscrito pelo escriv\u00e3o e assinado pela autoridade que o fizer expedir.<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Errada<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; ESCRIV\u00c3O)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 36<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item correto, pois esta \u00e9 a exata previs\u00e3o do art. 305 do CPP:<\/p>\n<p style=\"text-align: justify;\">Art. 305.\u00a0 Na falta ou no impedimento do escriv\u00e3o, qualquer pessoa designada pela autoridade lavrar\u00e1 o auto, depois de prestado o compromisso legal.<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Correta<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; ESCRIV\u00c3O)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 37<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item correto, pois, de fato, a conduta relativa ao contrabando foi retirada do art. 334, mas n\u00e3o houve descriminaliza\u00e7\u00e3o, tendo havido transposi\u00e7\u00e3o desta conduta para o art. 334-A do CP, que hoje tipifica a conduta, tendo havido, portanto, o fen\u00f4meno da continuidade t\u00edpico-normativa.<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Correta<\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>AGENTE<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; AGENTE)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 33<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item correto, pois, de fato, o IP \u00e9 um procedimento administrativo (n\u00e3o \u00e9 judicial), pr\u00e9-processual, cuja finalidade \u00e9 obter os elementos de informa\u00e7\u00e3o necess\u00e1rios ao ajuizamento v\u00e1lido da a\u00e7\u00e3o penal, que s\u00e3o a prova da materialidade e ind\u00edcios suficientes de autoria (justa causa).<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Correta<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; AGENTE)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 34<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item errado, pois a acarea\u00e7\u00e3o n\u00e3o \u00e9 admitida apenas na fase de investiga\u00e7\u00e3o, sendo admitida tamb\u00e9m durante o processo, na forma do art. 229 do CPP.<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Errada<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; AGENTE)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 35<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item errado, pois n\u00e3o h\u00e1 qualquer ju\u00edzo de discricionariedade, j\u00e1 que os agentes DEVEM prender Jos\u00e9, que se encontra em situa\u00e7\u00e3o de flagrante delito, na forma do art. 301 do CPP, pois s\u00e3o sujeitos ativos OBRIGAT\u00d3RIOS da pris\u00e3o em flagrante.<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Errada<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; AGENTE)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 36<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item correto, pois quando Jos\u00e9 adquire o armamento, j\u00e1 est\u00e1 consumado o crime de recepta\u00e7\u00e3o, eis que esta \u00e9 uma das condutas tipificadas no art. 180 do CP:<\/p>\n<p style=\"text-align: justify;\">Recepta\u00e7\u00e3o<\/p>\n<p style=\"text-align: justify;\">Art. 180 &#8211; Adquirir, receber, transportar, conduzir ou ocultar, em proveito pr\u00f3prio ou alheio, coisa que sabe ser produto de crime, ou influir para que terceiro, de boa-f\u00e9, a adquira, receba ou oculte:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (Reda\u00e7\u00e3o dada pela Lei n\u00ba 9.426, de 1996)<\/p>\n<p style=\"text-align: justify;\">Pena &#8211; reclus\u00e3o, de um a quatro anos, e multa.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 (Reda\u00e7\u00e3o dada pela Lei n\u00ba 9.426, de 1996)<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Correta<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(CESPE &#8211; GABARITO PF 2018 &#8211; AGENTE)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Q. 37<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COMENT\u00c1RIOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Item errado, pois Jos\u00e9 ser\u00e1 beneficiado pela nova lei, j\u00e1 que ser\u00e1 uma lei nova mais ben\u00e9fica, e a lei penal nova mais ben\u00e9fica \u00e9 dotada de efic\u00e1cia RETROATIVA (aplica-se aos fatos anteriores), na forma do art. 2\u00ba, \u00a7 \u00fanico do CP.<\/p>\n<p style=\"text-align: justify;\"><strong>GABARITO: Errada<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0__________________<\/p>\n<p style=\"text-align: justify;\">Se voc\u00ea quer conhecer mais do meu trabalho aqui no Estrat\u00e9gia Concursos, <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorProfessor\/renan-araujo-3209\/\">clique aqui<\/a> e baixe, gratuitamente, as aulas demonstrativas dos meus cursos.<\/p>\n<p style=\"text-align: justify;\"><strong>Bons estudos!<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Prof. Renan Araujo<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>E-mail:\u00a0<\/strong><a href=\"mailto:profrenanaraujo@gmail.com\"><strong>prof<\/strong><\/a><strong>renanaraujo@gmail.com<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Facebook:\u00a0<\/strong><a href=\"http:\/\/www.facebook.com\/profrenanaraujoestrategia\"><strong>www.facebook.com\/profrenanaraujoestrategia<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Instagram:\u00a0<\/strong><a href=\"http:\/\/www.instagram.com\/profrenanaraujo\/?hl=pt-br\"><strong>www.instagram.com\/profrenanaraujo\/?hl=pt-br<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Youtube:\u00a0<\/strong><a href=\"http:\/\/www.youtube.com\/channel\/UClIFS2cyREWT35OELN8wcFQ\"><strong>www.youtube.com\/channel\/UClIFS2cyREWT35OELN8wcFQ<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GABARITO PF 2018 &#8211; DIREITO PENAL E DIREITO PROCESSUAL PENAL (AGENTE E ESCRIV\u00c3O) Ol\u00e1, pessoal Para quem n\u00e3o me conhece ainda, meu nome \u00e9 Renan Araujo e sou professor aqui no Estrat\u00e9gia Concursos, lecionando as mat\u00e9rias de Direito Penal e Processual Penal. Antes de prosseguir, convido voc\u00ea a me seguir no INSTAGRAM:\u00a0Instagram do Prof. Renan [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-141076","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GABARITO PF 2018 - Direito Penal e Processual Penal (extraoficial) - Agente e Escriv\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GABARITO PF 2018 - Direito Penal e Processual Penal (extraoficial) - Agente e Escriv\u00e3o\" \/>\n<meta property=\"og:description\" content=\"GABARITO PF 2018 &#8211; DIREITO PENAL E DIREITO PROCESSUAL PENAL (AGENTE E ESCRIV\u00c3O) Ol\u00e1, pessoal Para quem n\u00e3o me conhece ainda, meu nome \u00e9 Renan Araujo e sou professor aqui no Estrat\u00e9gia Concursos, lecionando as mat\u00e9rias de Direito Penal e Processual Penal. Antes de prosseguir, convido voc\u00ea a me seguir no INSTAGRAM:\u00a0Instagram do Prof. Renan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-17T15:02:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-17T19:27:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/09\/RANKING-PF2.jpg\" \/>\n<meta name=\"author\" content=\"Renan Araujo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Renan Araujo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/\"},\"author\":{\"name\":\"Renan Araujo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b\"},\"headline\":\"GABARITO PF 2018 &#8211; Direito Penal e Processual Penal (extraoficial) &#8211; Agente e Escriv\u00e3o\",\"datePublished\":\"2018-09-17T15:02:57+00:00\",\"dateModified\":\"2018-09-17T19:27:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/\"},\"wordCount\":946,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/09\/RANKING-PF2.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/\",\"name\":\"GABARITO PF 2018 - Direito Penal e Processual Penal (extraoficial) - Agente e Escriv\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/09\/RANKING-PF2.jpg\",\"datePublished\":\"2018-09-17T15:02:57+00:00\",\"dateModified\":\"2018-09-17T19:27:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg\",\"width\":1184,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GABARITO PF 2018 &#8211; Direito Penal e Processual Penal (extraoficial) &#8211; Agente e Escriv\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b\",\"name\":\"Renan Araujo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g\",\"caption\":\"Renan Araujo\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/renanaraujoestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GABARITO PF 2018 - Direito Penal e Processual Penal (extraoficial) - Agente e Escriv\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/","og_locale":"pt_BR","og_type":"article","og_title":"GABARITO PF 2018 - Direito Penal e Processual Penal (extraoficial) - Agente e Escriv\u00e3o","og_description":"GABARITO PF 2018 &#8211; DIREITO PENAL E DIREITO PROCESSUAL PENAL (AGENTE E ESCRIV\u00c3O) Ol\u00e1, pessoal Para quem n\u00e3o me conhece ainda, meu nome \u00e9 Renan Araujo e sou professor aqui no Estrat\u00e9gia Concursos, lecionando as mat\u00e9rias de Direito Penal e Processual Penal. Antes de prosseguir, convido voc\u00ea a me seguir no INSTAGRAM:\u00a0Instagram do Prof. Renan [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2018-09-17T15:02:57+00:00","article_modified_time":"2018-09-17T19:27:42+00:00","og_image":[{"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/09\/RANKING-PF2.jpg","type":"","width":"","height":""}],"author":"Renan Araujo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Renan Araujo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/"},"author":{"name":"Renan Araujo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b"},"headline":"GABARITO PF 2018 &#8211; Direito Penal e Processual Penal (extraoficial) &#8211; Agente e Escriv\u00e3o","datePublished":"2018-09-17T15:02:57+00:00","dateModified":"2018-09-17T19:27:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/"},"wordCount":946,"commentCount":7,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/09\/RANKING-PF2.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/","name":"GABARITO PF 2018 - Direito Penal e Processual Penal (extraoficial) - Agente e Escriv\u00e3o","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/09\/RANKING-PF2.jpg","datePublished":"2018-09-17T15:02:57+00:00","dateModified":"2018-09-17T19:27:42+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/17162625\/RANKING-PF2.jpg","width":1184,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-pf-2018-direito-penal-e-processual-penal-extraoficial-agente-e-escrivao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"GABARITO PF 2018 &#8211; Direito Penal e Processual Penal (extraoficial) &#8211; Agente e Escriv\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/1a7a7af72da82939a6308b2ee292162b","name":"Renan Araujo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca6cb9ba5a547fbe93c05c63d6103dff6c2566555a601f1efb8590a69fb9ed76?s=96&d=mm&r=g","caption":"Renan Araujo"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/renanaraujoestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/141076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=141076"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/141076\/revisions"}],"predecessor-version":[{"id":141177,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/141076\/revisions\/141177"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=141076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=141076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=141076"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=141076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}