{"id":1407466,"date":"2024-06-16T14:00:00","date_gmt":"2024-06-16T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1407466"},"modified":"2024-06-01T11:39:21","modified_gmt":"2024-06-01T14:39:21","slug":"policia-penal-governanca-accountability","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/","title":{"rendered":"Pol\u00edcia Penal: Governan\u00e7a e Accountability"},"content":{"rendered":"\n<p>No artigo de hoje, Pol\u00edcia Penal: Governan\u00e7a e accountability, tema do concurso da <a href=\"https:\/\/www.sap.ce.gov.br\/\">Secretaria de Seguran\u00e7a<\/a> do Cear\u00e1, ser\u00e3o expostos os principais itens de cobran\u00e7a relativo a atos administrativos em provas de concurso.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"385\" height=\"365\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png\" alt=\"Pol\u00edcia Penal: Governan\u00e7a e Accountability\" class=\"wp-image-1407471\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png 385w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2-300x284.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2-150x142.png 150w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-policia-penal-governanca-e-accountability-governo-eletronico\">Pol\u00edcia Penal: Governan\u00e7a e Accountability &#8211; Governo Eletr\u00f4nico<\/h2>\n\n\n\n<p>Governo eletr\u00f4nico \u00e9 uma men\u00e7\u00e3o ao conceito de E<strong>-gov (E-Government), ou Governo Eletr\u00f4nico.\u00a0<\/strong>Cita-se a men\u00e7\u00e3o do referido conceito no s\u00edtio eletr\u00f4nico do Governo Federal:<\/p>\n\n\n\n<p>O conceito de <strong>Governo Eletr\u00f4nico<\/strong> surge a partir de aspectos oriundos da evolu\u00e7\u00e3o da <strong>TIC<\/strong>, especialmente a Internet, constituindo novas formas de relacionamento da Administra\u00e7\u00e3o P\u00fablica com a sociedade e vice-versa, evidenciando a presta\u00e7\u00e3o de servi\u00e7os <u>sem<\/u> a necessidade da presen\u00e7a f\u00edsica.<\/p>\n\n\n\n<p>Veja como se operacionaliza o processo do E-GOV:<\/p>\n\n\n\n<p><strong>Alta C\u00fapula<\/strong>&nbsp;&#8211; Elabora a Pol\u00edtica, ou seja, define o que deve ser feito ou qual problema tratar. (Alta Dire\u00e7\u00e3o)<\/p>\n\n\n\n<p><strong>Alta C\u00fapula Local<\/strong>&nbsp;&#8211; Ajuda na Cria\u00e7\u00e3o do Projeto, ou seja, usa sua influ\u00eancia, poder e participa\u00e7\u00e3o para definir como ser\u00e1 feito. (Gerentes de Projeto)<\/p>\n\n\n\n<p><strong>Equipe T\u00e9cnica<\/strong>&nbsp;&#8211; Implanta, Implementa&nbsp;e Operacionaliza. (Corpo t\u00e9cnico)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-servicos-e-disponibilizacao\">Servi\u00e7os e Disponibiliza\u00e7\u00e3o<\/h2>\n\n\n\n<p>Segundo a pr\u00f3pria Na\u00e7\u00f5es Unidas (2002),\u00a0<strong>governo eletr\u00f4nico<\/strong>\u00a0diz respeito<strong>\u00a0disponibiliza\u00e7\u00e3o<\/strong>\u00a0e<strong>\u00a0acesso<\/strong>\u00a0a informa\u00e7\u00f5es e servi\u00e7os p\u00fablicos via<strong>\u00a0internet<\/strong>.<\/p>\n\n\n\n<p>Alguns autores definem como uma atividade do Estado baseadas em<strong>&nbsp;TIC<\/strong>&nbsp;(Tecnologia da Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o), que possui o objetivo de&nbsp;<strong>aumentar a&nbsp;efici\u00eancia&nbsp;da gest\u00e3o p\u00fablica<\/strong>,<strong>&nbsp;melhorar os&nbsp;servi\u00e7os&nbsp;e&nbsp;a\u00e7\u00f5es&nbsp;<\/strong>governamentais dentro de uma estrutura mais&nbsp;<strong>transparente<\/strong>.<\/p>\n\n\n\n<p>A finalidade do governo eletr\u00f4nico<strong>&nbsp;transcende (vai al\u00e9m)<\/strong>&nbsp;as possibilidades de aperfei\u00e7oamento tecnol\u00f3gico.<strong>&nbsp;N\u00e3o<\/strong>&nbsp;\u00e9 uma mera evolu\u00e7\u00e3o tecnol\u00f3gica!<\/p>\n\n\n\n<p>As TICs&nbsp; possuem um&nbsp;<strong>potencial democr\u00e1tico<\/strong>&nbsp;quando alinhadas a uma pol\u00edtica de participa\u00e7\u00e3o popular e<strong>&nbsp;TRANSPAR\u00caNCIA<\/strong>.<\/p>\n\n\n\n<p>Segundo o pr\u00f3prio site do Governo Federal (2022), no Brasil, a pol\u00edtica de Governo Eletr\u00f4nico segue um conjunto de diretrizes que atuam em&nbsp;<strong>tr\u00eas&nbsp;frentes fundamentais<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Junto ao&nbsp;<strong>cidad\u00e3o<\/strong>;<\/li>\n\n\n\n<li>Na&nbsp;<strong>melhoria da&nbsp;gest\u00e3o interna<\/strong>;<\/li>\n\n\n\n<li>E&nbsp;na&nbsp;<strong>integra\u00e7\u00e3o&nbsp;com parceiros e fornecedores<\/strong>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-policia-penal-governanca-e-accountability-transparencia-e-perspectivas\">Pol\u00edcia Penal: Governan\u00e7a e Accountability &#8211; Transpar\u00eancia e Perspectivas<\/h2>\n\n\n\n<p>Por <strong>E-Gov (Governo eletr\u00f4nico)<\/strong>\u00a0entende-se que a<em>\u00a0<\/em><strong>internet<\/strong>\u00a0tem sido o canal predominante de\u00a0<strong>comunica\u00e7\u00e3o<\/strong>, e o\u00a0<strong>foco no cliente<\/strong>, um aspecto comum das\u00a0<strong>iniciativas das organiza\u00e7\u00f5es governamentais<\/strong>\u201d<br \/><br \/>Por transpar\u00eancia entende-se que <em>\u201cOs\u00a0<strong>cidad\u00e3os<\/strong>\u00a0t\u00eam direito de\u00a0<strong>acesso a informa\u00e7\u00e3o<\/strong>, e o poder p\u00fablico, o dever de\u00a0<strong>prestar informa\u00e7\u00f5es<\/strong>\u201d<\/em>.<\/p>\n\n\n\n<p>O governo eletr\u00f4nico tem como objetivo o&nbsp;<strong>fortalecimento da cidadania<\/strong>, pr\u00e1ticas democr\u00e1ticas, melhoria da governan\u00e7a intra e entre governos, o&nbsp;<strong>incremento da transpar\u00eancia e accountability governamental<\/strong>. Desta forma, torna-se claro que a acessibilidade e usabilidade dos s\u00edtios eletr\u00f4nicos \u00e9 uma das caracter\u00edsticas do governo eletr\u00f4nico.<\/p>\n\n\n\n<p>De forma ampla, &#8220;<strong>Governo Eletr\u00f4nico<\/strong>\u201d busca fornecer e disponibilizar aos cidad\u00e3os,&nbsp;<strong>de forma eletr\u00f4nica<\/strong>&nbsp;(por meio da Tecnologia da Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o -TIC), as&nbsp;<strong>informa\u00e7\u00f5es, os servi\u00e7os ou os produtos<\/strong>, com o intuito de facilitar o acesso e agregar mais valor.<\/p>\n\n\n\n<p>Nesse contexto, Lenk &amp; Traunm\u00fcllerv (2001) visualizam&nbsp;<strong>quatro perspectivas<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A\u00a0<strong>perspectiva do\u00a0cidad\u00e3o<\/strong>: o intuito \u00e9 oferecer servi\u00e7os de utilidade p\u00fablica ao cidad\u00e3o contribuinte;<\/li>\n\n\n\n<li>A<strong>\u00a0perspectiva de\u00a0processos<\/strong>: o governo eletr\u00f4nico busca repensar o modus-operandi dos processos produtivos ora existentes no Governo, em suas v\u00e1rias esferas, tais como, por exemplo, os processos de licita\u00e7\u00e3o para compras (e-procurement);<\/li>\n\n\n\n<li>\u00a0A<strong>\u00a0perspectiva da\u00a0coopera\u00e7\u00e3o<\/strong>: visa integrar os v\u00e1rios \u00f3rg\u00e3os governamentais, e estes com outras organiza\u00e7\u00f5es privadas e n\u00e3o-governamentais, de modo a o processo decis\u00f3rio possa ser agilizado, sem perda de qualidade, fragmenta\u00e7\u00e3o ou redund\u00e2ncias etc.; e<\/li>\n\n\n\n<li>\u00a0A\u00a0<strong>perspectiva da\u00a0gest\u00e3o do conhecimento<\/strong>: visa permitir ao Governo, em suas v\u00e1rias esferas, criar, gerenciar e disponibilizar em reposit\u00f3rios adequados, o conhecimento tanto gerado quanto acumulado por seus v\u00e1rios \u00f3rg\u00e3os.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-policia-penal-governanca-e-accountability-lei-de-acesso-a-informacao-lai\">Pol\u00edcia Penal: Governan\u00e7a e Accountability &#8211; Lei de acesso \u00e0 informa\u00e7\u00e3o (LAI)<\/h2>\n\n\n\n<p>A Constitui\u00e7\u00e3o Federal (CF\/88) disp\u00f5e em seu inciso XIII do art. 5o que todos t\u00eam direito a receber dos \u00f3rg\u00e3os p\u00fablicos informa\u00e7\u00f5es de seu interesse particular, ou de interesse coletivo ou geral, que ser\u00e3o prestadas no prazo da lei, sob pena de responsabilidade, ressalvadas aquelas cujo sigilo seja imprescind\u00edvel \u00e0 seguran\u00e7a da sociedade e do Estado.<\/p>\n\n\n\n<p>Al\u00e9m disso, ela tamb\u00e9m disp\u00f5e no inciso II do \u00a7 3o do art. 37 que a lei disciplinar\u00e1 as formas de participa\u00e7\u00e3o do usu\u00e1rio na administra\u00e7\u00e3o p\u00fablica direta e indireta, regulando especialmente o acesso dos usu\u00e1rios a registros administrativos e a informa\u00e7\u00f5es sobre atos de governo.<\/p>\n\n\n\n<p>A LAI (Lei no 12.527\/2011) regula o acesso o acesso \u00e0 informa\u00e7\u00e3o em toda a Administra\u00e7\u00e3o P\u00fablica, em todas as suas esferas e em todos os Poderes, incluindo os Minist\u00e9rios P\u00fablicos e os Tribunais de Contas. <\/p>\n\n\n\n<p>Al\u00e9m disso, a LAI tamb\u00e9m se aplica a organiza\u00e7\u00f5es privadas, mas sem fins lucrativos, que realizam a\u00e7\u00f5es de interesse p\u00fablico e, portanto, recebem recursos do or\u00e7amento p\u00fablico por meio de subven\u00e7\u00f5es, contrato de gest\u00e3o, termo de parceria, conv\u00eanios, acordos, ajustes e instrumentos cong\u00eaneres, estando a publicidade adstrita \u00e0 parcela de recursos p\u00fablicos que elas recebem.<\/p>\n\n\n\n<p>\u00c9 o caso das Organiza\u00e7\u00f5es Sociais, das Organiza\u00e7\u00f5es da Sociedade Civil de Interesse P\u00fablico, das Organiza\u00e7\u00f5es da Sociedade Civil, dentre outras.<\/p>\n\n\n\n<p>Al\u00e9m de assegurar o direito fundamental de acesso \u00e0 informa\u00e7\u00e3o, observados ainda os demais princ\u00edpios da administra\u00e7\u00e3o p\u00fablica, a LAI tem como diretrizes a publicidade como preceito geral (o sigilo sempre ser\u00e1 exce\u00e7\u00e3o),<\/p>\n\n\n\n<p>Assim, a divulga\u00e7\u00e3o de informa\u00e7\u00f5es de interesse p\u00fablico, mesmo que n\u00e3o haja solicita\u00e7\u00f5es (transpar\u00eancia ativa), uso de meios de comunica\u00e7\u00e3o viabilizados pela tecnologia da informa\u00e7\u00e3o (TICs), fomento \u00e0 cultura da transpar\u00eancia e desenvolvimento do controle social.<\/p>\n\n\n\n<p>Espero que tenham gostado do artigo. <\/p>\n\n\n\n<p>Bons estudos!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>No artigo de hoje, Pol\u00edcia Penal: Governan\u00e7a e accountability, tema do concurso da Secretaria de Seguran\u00e7a do Cear\u00e1, ser\u00e3o expostos os principais itens de cobran\u00e7a relativo a atos administrativos em provas de concurso. Pol\u00edcia Penal: Governan\u00e7a e Accountability &#8211; Governo Eletr\u00f4nico Governo eletr\u00f4nico \u00e9 uma men\u00e7\u00e3o ao conceito de E-gov (E-Government), ou Governo Eletr\u00f4nico.\u00a0Cita-se a [&hellip;]<\/p>\n","protected":false},"author":2020,"featured_media":1407471,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220188],"tags":[220507,221787],"tax_estado":[219969,219963],"class_list":["post-1407466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-agente-penitenciario","tag-ceara","tag-policia-penal-2","tax_estado-ce","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pol\u00edcia Penal: Governan\u00e7a e Accountability<\/title>\n<meta name=\"description\" content=\"Pol\u00edcia Penal: Governan\u00e7a e Accountability. concurso da \u00e1rea policial. Secretaria de Seguran\u00e7a. Direito Administrativo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edcia Penal: Governan\u00e7a e Accountability\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edcia Penal: Governan\u00e7a e Accountability. concurso da \u00e1rea policial. Secretaria de Seguran\u00e7a. Direito Administrativo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-16T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"385\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cliffer Ferreira da Gama Mello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cliffer Ferreira da Gama Mello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/\"},\"author\":{\"name\":\"Cliffer Ferreira da Gama Mello\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b8e0b6cacb96edae339c98851ea2ef9e\"},\"headline\":\"Pol\u00edcia Penal: Governan\u00e7a e Accountability\",\"datePublished\":\"2024-06-16T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/\"},\"wordCount\":1089,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png\",\"keywords\":[\"Cear\u00e1\",\"policia penal\"],\"articleSection\":[\"Policial (Agente Penitenci\u00e1rio)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/\",\"name\":\"Pol\u00edcia Penal: Governan\u00e7a e Accountability\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png\",\"datePublished\":\"2024-06-16T17:00:00+00:00\",\"description\":\"Pol\u00edcia Penal: Governan\u00e7a e Accountability. concurso da \u00e1rea policial. Secretaria de Seguran\u00e7a. Direito Administrativo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png\",\"width\":385,\"height\":365,\"caption\":\"Pol\u00edcia Penal: Governan\u00e7a e Accountability\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edcia Penal: Governan\u00e7a e Accountability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b8e0b6cacb96edae339c98851ea2ef9e\",\"name\":\"Cliffer Ferreira da Gama Mello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8ea9159a8bf85295ae12c25a2f1cf75a77957023872296a862393bd111377936?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ea9159a8bf85295ae12c25a2f1cf75a77957023872296a862393bd111377936?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ea9159a8bf85295ae12c25a2f1cf75a77957023872296a862393bd111377936?s=96&d=mm&r=g\",\"caption\":\"Cliffer Ferreira da Gama Mello\"},\"description\":\"Sou bacharel em Administra\u00e7\u00e3o pela Escola Naval (Ci\u00eancias Navais \u2013 Habilita\u00e7\u00e3o em Mec\u00e2nica). Aprovado em concursos das \u00e1reas Militar, Fiscal, Policial e de Controle.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/clifferestrategiagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edcia Penal: Governan\u00e7a e Accountability","description":"Pol\u00edcia Penal: Governan\u00e7a e Accountability. concurso da \u00e1rea policial. Secretaria de Seguran\u00e7a. Direito Administrativo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/","og_locale":"pt_BR","og_type":"article","og_title":"Pol\u00edcia Penal: Governan\u00e7a e Accountability","og_description":"Pol\u00edcia Penal: Governan\u00e7a e Accountability. concurso da \u00e1rea policial. Secretaria de Seguran\u00e7a. Direito Administrativo.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-06-16T17:00:00+00:00","og_image":[{"width":385,"height":365,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png","type":"image\/png"}],"author":"Cliffer Ferreira da Gama Mello","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Cliffer Ferreira da Gama Mello","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/"},"author":{"name":"Cliffer Ferreira da Gama Mello","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b8e0b6cacb96edae339c98851ea2ef9e"},"headline":"Pol\u00edcia Penal: Governan\u00e7a e Accountability","datePublished":"2024-06-16T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/"},"wordCount":1089,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png","keywords":["Cear\u00e1","policia penal"],"articleSection":["Policial (Agente Penitenci\u00e1rio)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/","name":"Pol\u00edcia Penal: Governan\u00e7a e Accountability","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png","datePublished":"2024-06-16T17:00:00+00:00","description":"Pol\u00edcia Penal: Governan\u00e7a e Accountability. concurso da \u00e1rea policial. Secretaria de Seguran\u00e7a. Direito Administrativo.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/05\/30155728\/pp-penal-2.png","width":385,"height":365,"caption":"Pol\u00edcia Penal: Governan\u00e7a e Accountability"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-governanca-accountability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edcia Penal: Governan\u00e7a e Accountability"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b8e0b6cacb96edae339c98851ea2ef9e","name":"Cliffer Ferreira da Gama Mello","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8ea9159a8bf85295ae12c25a2f1cf75a77957023872296a862393bd111377936?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ea9159a8bf85295ae12c25a2f1cf75a77957023872296a862393bd111377936?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ea9159a8bf85295ae12c25a2f1cf75a77957023872296a862393bd111377936?s=96&d=mm&r=g","caption":"Cliffer Ferreira da Gama Mello"},"description":"Sou bacharel em Administra\u00e7\u00e3o pela Escola Naval (Ci\u00eancias Navais \u2013 Habilita\u00e7\u00e3o em Mec\u00e2nica). Aprovado em concursos das \u00e1reas Militar, Fiscal, Policial e de Controle.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/clifferestrategiagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1407466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2020"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1407466"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1407466\/revisions"}],"predecessor-version":[{"id":1407472,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1407466\/revisions\/1407472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1407471"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1407466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1407466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1407466"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1407466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}