{"id":1390997,"date":"2024-06-16T14:00:00","date_gmt":"2024-06-16T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1390997"},"modified":"2024-05-13T21:53:31","modified_gmt":"2024-05-14T00:53:31","slug":"teorias-resp-estado-stn","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/","title":{"rendered":"Teorias da responsabilidade do Estado: resumo para a STN"},"content":{"rendered":"\n<p>Ol\u00e1, pessoal, tudo bem? Estudaremos, neste artigo, sobre as principais teorias da responsabilidade do Estado, com foco no concurso da <a href=\"https:\/\/www.gov.br\/tesouronacional\/pt-br\">Secretaria do Tesouro Nacional (STN)<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg\" alt=\"Teorias da responsabilidade do Estado: resumo para a STN\" class=\"wp-image-1250825\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn-300x169.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn-610x343.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn-150x84.jpg 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Bons estudos!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-aspectos-introdutorios-sobre-a-responsabilidade-civil-do-estado\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Aspectos introdut\u00f3rios sobre a responsabilidade civil do Estado<\/mark><\/strong><\/h2>\n\n\n\n<p>Em s\u00edntese, a responsabilidade civil do Estado refere-se \u00e0 sua obriga\u00e7\u00e3o de arcar com os preju\u00edzos causados a terceiros.<\/p>\n\n\n\n<p>No contexto do direito privado \u00e9 muito comum que as disposi\u00e7\u00f5es do ordenamento jur\u00eddico estejam voltadas, primordialmente, \u00e0 resolu\u00e7\u00e3o de lides relacionadas a interesses individuais.<\/p>\n\n\n\n<p>Todavia, no campo do direito p\u00fablico, verifica-se, em regra, o primordial impulso de resguardar o interesse coletivo em detrimento de demandas particulares.<\/p>\n\n\n\n<p>Ocorre que, apesar disso, existem situa\u00e7\u00f5es em que o Estado deve ser chamado a responder frente aos preju\u00edzos causados aos administrados.<\/p>\n\n\n\n<p>Nesse contexto, ao longo dos anos, houve significativa evolu\u00e7\u00e3o atinente \u00e0s teorias da responsabilidade civil do Estado.<\/p>\n\n\n\n<p>Por isso, estudaremos em maiores detalhes, no decorrer deste artigo, os principais aspectos das teorias da responsabilidade do Estado para o concurso da STN.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-teorias-da-responsabilidade-do-estado-para-a-stn-irresponsabilidade-civil\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Teorias da responsabilidade do Estado para a STN: irresponsabilidade civil<\/mark><\/strong><\/h2>\n\n\n\n<p>A primeira teoria tratada neste artigo remete \u00e0 \u00e9poca das monarquias absolutistas.<\/p>\n\n\n\n<p>Nesse per\u00edodo, entendia-se com regra a total irresponsabilidade civil do Estado, o qual n\u00e3o responderia por qualquer tipo de afronta a agentes privados.<\/p>\n\n\n\n<p>Sobre isso, marca essa teoria a seguinte m\u00e1xima: \u201cthe king can do no wrong\u201d, ou seja, o rei n\u00e3o pode errar, em tradu\u00e7\u00e3o livre.<\/p>\n\n\n\n<p>Dessa forma, os agentes p\u00fablicos, como representantes do rei, n\u00e3o poderiam causar qualquer les\u00e3o aos governados, haja vista que a atua\u00e7\u00e3o do agente p\u00fablico seria presumidamente justa e proporcional.<\/p>\n\n\n\n<p>Portanto, segundo a teoria da irresponsabilidade civil do Estado, n\u00e3o h\u00e1 o que se falar em qualquer obriga\u00e7\u00e3o indenizat\u00f3ria por parte da Administra\u00e7\u00e3o P\u00fablica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-teorias-da-responsabilidade-do-estado-para-a-stn-culpa-comum\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Teorias da responsabilidade do Estado para a STN: culpa comum<\/mark><\/strong><\/h2>\n\n\n\n<p>Por outro lado, a teoria da culpa comum surgiu como um contraponto \u00e0 teoria da irresponsabilidade civil do Estado.<\/p>\n\n\n\n<p>Nesse contexto, em meados do s\u00e9culo XIX, a teoria da culpa comum indicava que o Estado deveria responder civilmente segundo as mesmas regras aplic\u00e1veis aos particulares.<\/p>\n\n\n\n<p>Ou seja, com uma concep\u00e7\u00e3o diametralmente oposta \u00e0 da teoria da irresponsabilidade, a teoria da culpa comum objetivava igualar os interesses p\u00fablicos e privados.<\/p>\n\n\n\n<p>Conforme a doutrina, consistia em uma teoria civilista na qual o Estado seria chamado a responder como se particular fosse, em rela\u00e7\u00e3o a condutas culposas ou dolosas.<\/p>\n\n\n\n<p>Dessa forma, seria exigido que o particular prejudicado demonstrasse a conduta culposa (em sentido amplo) da Administra\u00e7\u00e3o P\u00fablica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-teorias-da-responsabilidade-do-estado-para-a-stn-culpa-administrativa\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Teorias da responsabilidade do Estado para a STN: culpa administrativa<\/mark><\/strong><\/h2>\n\n\n\n<p>Al\u00e9m disso, existe a teoria da culpa administrativa, tamb\u00e9m chamada de culpa an\u00f4nima ou falta do servi\u00e7o.<\/p>\n\n\n\n<p>Conforme a doutrina, a teoria da culpa administrativa refere-se \u00e0 responsabilidade do Estado diante de falhas no servi\u00e7o prestado.<\/p>\n\n\n\n<p>Nesse contexto, n\u00e3o seria necess\u00e1ria, para fins de responsabiliza\u00e7\u00e3o estatal, a indica\u00e7\u00e3o do agente p\u00fablico causador do eventual dano, pois somente seria imprescind\u00edvel a demonstra\u00e7\u00e3o de que o servi\u00e7o prestado apresentava v\u00edcios.<\/p>\n\n\n\n<p>Assim, eventual responsabilidade do Estado, sob a \u00e9gide da teoria da culpa administrativa, exigiria t\u00e3o somente a demonstra\u00e7\u00e3o de 3 (tr\u00eas) elementos: dano sofrido, falta do servi\u00e7o e nexo de causalidade (entre o dano e a falta).<\/p>\n\n\n\n<p>Vale ressaltar que a teoria da culpa administrativa \u00e9 adotada no Brasil em rela\u00e7\u00e3o \u00e0s condutas omissivas da Administra\u00e7\u00e3o P\u00fablica.<\/p>\n\n\n\n<p>Ademais, compete destacar, para o concurso da STN, que a doutrina aponta 3 (tr\u00eas) formas de falta do servi\u00e7o, a saber: inexist\u00eancia, mau funcionamento e retardamento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-teorias-da-responsabilidade-do-estado-para-a-stn-risco-administrativo\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Teorias da responsabilidade do Estado para a STN: risco administrativo<\/mark><\/strong><\/h2>\n\n\n\n<p>Por outro lado, a teoria do risco administrativo baseia-se no risco da atividade Administrativa para os administrados.<\/p>\n\n\n\n<p>Dessa forma, diferentemente da teoria da culpa comum, n\u00e3o se exige a demonstra\u00e7\u00e3o de culpa por parte do agente p\u00fablico.<\/p>\n\n\n\n<p>Ademais, diferentemente da teoria da culpa administrativa, n\u00e3o guarda rela\u00e7\u00e3o com qualquer tipo de m\u00e1 presta\u00e7\u00e3o do servi\u00e7o.<\/p>\n\n\n\n<p>Ou seja, para a teoria do risco administrativo \u00e9 poss\u00edvel que o servi\u00e7o p\u00fablico seja prestado a contento e mesmo assim haja a obriga\u00e7\u00e3o de a Administra\u00e7\u00e3o indenizar o particular.<\/p>\n\n\n\n<p>Por esse motivo, a doutrina indica que o risco administrativo se refere \u00e0 obriga\u00e7\u00e3o de indenizar o dano do s\u00f3 ato lesivo e injusto causado \u00e0 v\u00edtima.<\/p>\n\n\n\n<p>Para isso, faz-se necess\u00e1rio provar: o dano sofrido, a exist\u00eancia de atua\u00e7\u00e3o estatal, bem como, o nexo causal entre o dano e a atua\u00e7\u00e3o.<\/p>\n\n\n\n<p>Pessoal, diante de todo o exposto, podemos perceber que na teoria do risco administrativo a responsabiliza\u00e7\u00e3o do Estado independe de culpa do agente p\u00fablico, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p>Por esse motivo, pode-se dizer que nesta teoria a responsabilidade do Estado \u00e9 objetiva.<\/p>\n\n\n\n<p>Al\u00e9m disso, vale consignar que a doutrina e a jurisprud\u00eancia consolidada admitem a exist\u00eancia de excludentes de responsabilidade na teoria do risco administrativo.<\/p>\n\n\n\n<p>No Brasil, adota-se essa teoria para as condutas comissivas do Estado (a\u00e7\u00e3o estatal).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-teorias-da-responsabilidade-do-estado-para-a-stn-risco-integral\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Teorias da responsabilidade do Estado para a STN: risco integral<\/mark><\/strong><\/h2>\n\n\n\n<p>Por fim, a teoria do risco integral refere-se \u00e0s situa\u00e7\u00f5es em que o Estado se faz obrigado a indenizar o particular, sendo imposs\u00edvel a alega\u00e7\u00e3o de qualquer tipo de excludente de responsabilidade.<\/p>\n\n\n\n<p>No Brasil, adota-se a teoria do risco integral em algumas situa\u00e7\u00f5es bastante espec\u00edficas.<\/p>\n\n\n\n<p>Para o concurso da STN, vale citar os casos em que, no Brasil, a doutrina e a jurisprud\u00eancia reconhecem a utiliza\u00e7\u00e3o dessa teoria, a saber:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Danos causados por acidentes nucleares;<\/li>\n\n\n\n<li>Danos ambientais;<\/li>\n\n\n\n<li>Atos terroristas ou de guerra, ocorridos no Brasil ou no exterior, contra aeronaves de matr\u00edcula brasileira.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Conclus\u00e3o<\/mark><\/strong><\/h2>\n\n\n\n<p>Amigos, finalizamos aqui este resumo sobre as teorias da responsabilidade civil do Estado para o concurso da STN.<\/p>\n\n\n\n<p>Espero voc\u00eas em um pr\u00f3ximo artigo.<\/p>\n\n\n\n<p>Grande abra\u00e7o.<\/p>\n\n\n\n<p><strong>Rafael Chaves<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\">Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-stn\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso STN<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/#\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal, tudo bem? Estudaremos, neste artigo, sobre as principais teorias da responsabilidade do Estado, com foco no concurso da Secretaria do Tesouro Nacional (STN). Bons estudos! Aspectos introdut\u00f3rios sobre a responsabilidade civil do Estado Em s\u00edntese, a responsabilidade civil do Estado refere-se \u00e0 sua obriga\u00e7\u00e3o de arcar com os preju\u00edzos causados a terceiros. No [&hellip;]<\/p>\n","protected":false},"author":2261,"featured_media":1250825,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220180],"tags":[],"tax_estado":[219963],"class_list":["post-1390997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-controle-gestao","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Teorias da responsabilidade do Estado: resumo para a STN<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a os principais t\u00f3picos sobre as teorias da responsabilidade do Estado para o concurso da Secretaria do Tesouro Nacional (STN).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teorias da responsabilidade do Estado: resumo para a STN\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a os principais t\u00f3picos sobre as teorias da responsabilidade do Estado para o concurso da Secretaria do Tesouro Nacional (STN).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-16T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafael Ferreira Chaves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafael Ferreira Chaves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/\"},\"author\":{\"name\":\"Rafael Ferreira Chaves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1\"},\"headline\":\"Teorias da responsabilidade do Estado: resumo para a STN\",\"datePublished\":\"2024-06-16T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/\"},\"wordCount\":1029,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/\",\"name\":\"Teorias da responsabilidade do Estado: resumo para a STN\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg\",\"datePublished\":\"2024-06-16T17:00:00+00:00\",\"description\":\"Conhe\u00e7a os principais t\u00f3picos sobre as teorias da responsabilidade do Estado para o concurso da Secretaria do Tesouro Nacional (STN).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg\",\"width\":768,\"height\":432,\"caption\":\"concurso STN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teorias da responsabilidade do Estado: resumo para a STN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1\",\"name\":\"Rafael Ferreira Chaves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"caption\":\"Rafael Ferreira Chaves\"},\"description\":\"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fchaves01gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teorias da responsabilidade do Estado: resumo para a STN","description":"Conhe\u00e7a os principais t\u00f3picos sobre as teorias da responsabilidade do Estado para o concurso da Secretaria do Tesouro Nacional (STN).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/","og_locale":"pt_BR","og_type":"article","og_title":"Teorias da responsabilidade do Estado: resumo para a STN","og_description":"Conhe\u00e7a os principais t\u00f3picos sobre as teorias da responsabilidade do Estado para o concurso da Secretaria do Tesouro Nacional (STN).","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-06-16T17:00:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg","type":"image\/jpeg"}],"author":"Rafael Ferreira Chaves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafael Ferreira Chaves","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/"},"author":{"name":"Rafael Ferreira Chaves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1"},"headline":"Teorias da responsabilidade do Estado: resumo para a STN","datePublished":"2024-06-16T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/"},"wordCount":1029,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg","articleSection":["Concursos P\u00fablicos","Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/","name":"Teorias da responsabilidade do Estado: resumo para a STN","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg","datePublished":"2024-06-16T17:00:00+00:00","description":"Conhe\u00e7a os principais t\u00f3picos sobre as teorias da responsabilidade do Estado para o concurso da Secretaria do Tesouro Nacional (STN).","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/07\/18184652\/stn.jpg","width":768,"height":432,"caption":"concurso STN"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teorias-resp-estado-stn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Teorias da responsabilidade do Estado: resumo para a STN"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1","name":"Rafael Ferreira Chaves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","caption":"Rafael Ferreira Chaves"},"description":"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fchaves01gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1390997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2261"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1390997"}],"version-history":[{"count":6,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1390997\/revisions"}],"predecessor-version":[{"id":1391058,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1390997\/revisions\/1391058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1250825"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1390997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1390997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1390997"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1390997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}