{"id":1389046,"date":"2024-04-24T00:45:08","date_gmt":"2024-04-24T03:45:08","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1389046"},"modified":"2024-04-24T00:45:10","modified_gmt":"2024-04-24T03:45:10","slug":"informativo-stf-1131-comentado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/","title":{"rendered":"Informativo STF 1131 Comentado"},"content":{"rendered":"\n<p><\/p><p>Mais um passo em nossa caminhada jurisprudencial em 2024. Hoje, vamos para cima do Informativo n\u00ba 1131 do STF\u00a0<strong>COMENTADO.\u00a0<\/strong>Se voc\u00ea est\u00e1 ligad@ aqui\u00a0no Estrat\u00e9gia Carreiras Jur\u00eddicas, sabe a aprova\u00e7\u00e3o est\u00e1 no horizonte proximo! Simbora!<\/p>\n\n\n\n<p><\/p><p class=\"has-text-align-center\"><strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/24004442\/stf-informativo-1131.pdf\" rel=\"sponsored nofollow\">DOWNLOAD do PDF<\/a><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_PSRllH7fLTM\"><div id=\"lyte_PSRllH7fLTM\" data-src=\"\/\/i.ytimg.com\/vi\/PSRllH7fLTM\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/PSRllH7fLTM\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/PSRllH7fLTM\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div>\n<\/div><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-administrativo\"><a>DIREITO ADMINISTRATIVO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-nbsp-nbsp-nbsp-nbsp-procuradoria-municipal-impossibilidade-de-criacao-por-norma-estadual-e-de-contratacao-de-advogados-sem-concurso-publico\"><a>1.&nbsp;&nbsp;&nbsp;&nbsp; Procuradoria municipal: impossibilidade de cria\u00e7\u00e3o por norma estadual e de contrata\u00e7\u00e3o de advogados sem concurso p\u00fablico<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>\u00c9 inconstitucional \u2014 por ofensa aos postulados da autonomia municipal (CF\/1988, art. 30, I) e do concurso p\u00fablico para provimento de cargos (CF\/1988, art. 37, II) \u2014 norma de Constitui\u00e7\u00e3o estadual que obrigue a cria\u00e7\u00e3o de Procuradorias nos munic\u00edpios e permite a contrata\u00e7\u00e3o, sem concurso p\u00fablico, de advogados para nelas atuarem.<\/p>\n\n\n\n<p>ADI 6.331\/PE, relator Ministro Luiz Fux, julgamento virtual finalizado em 08.04.2024 (Info 1131)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-1-nbsp-situacao-fatica\"><a>1.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O ent\u00e3o procurador-geral da Rep\u00fablica, Augusto Aras, ajuizou no STF a ADI 6331 contra dispositivos da Constitui\u00e7\u00e3o do Estado de Pernambuco que, ao determinar a cria\u00e7\u00e3o de procuradorias nos munic\u00edpios, possibilita a contrata\u00e7\u00e3o de advogados para o exerc\u00edcio de representa\u00e7\u00e3o judicial e extrajudicial, o assessoramento e a consultoria jur\u00eddica.<\/p>\n\n\n\n<p>De acordo com Aras, a contrata\u00e7\u00e3o seria irregular, por n\u00e3o observar os princ\u00edpios da impessoalidade, da moralidade e da efici\u00eancia. O procurador-geral sustenta que a norma d\u00e1 margem a pr\u00e1ticas que podem envolver desde o repasse indevido de verbas p\u00fablicas at\u00e9 a aus\u00eancia da presta\u00e7\u00e3o dos servi\u00e7os necess\u00e1rios \u00e0 promo\u00e7\u00e3o do interesse p\u00fablico prim\u00e1rio e secund\u00e1rio nas municipalidades. A \u201cprivatiza\u00e7\u00e3o do exerc\u00edcio da Advocacia P\u00fablica\u201d, segundo Aras, mediante o exerc\u00edcio da fun\u00e7\u00e3o institucional e das atribui\u00e7\u00f5es ordin\u00e1rias da procuradoria municipal por advogados admitidos sem a realiza\u00e7\u00e3o de concurso p\u00fablico, vai de encontro ao texto constitucional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-2-nbsp-analise-estrategica\"><a>1.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>1.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>CF\/1988: \u201cArt. 37. A administra\u00e7\u00e3o p\u00fablica direta e indireta de qualquer dos Poderes da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios obedecer\u00e1 aos princ\u00edpios de legalidade, impessoalidade, moralidade, publicidade e efici\u00eancia e, tamb\u00e9m, ao seguinte: (&#8230;) II &#8211; a investidura em cargo ou emprego p\u00fablico depende de aprova\u00e7\u00e3o pr\u00e9via em concurso p\u00fablico de provas ou de provas e t\u00edtulos, de acordo com a natureza e a complexidade do cargo ou emprego, na forma prevista em lei, ressalvadas as nomea\u00e7\u00f5es para cargo em comiss\u00e3o declarado em lei de livre nomea\u00e7\u00e3o e exonera\u00e7\u00e3o;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-2-nbsp-nbsp-nbsp-privatizou-geral\"><a>1.2.2.&nbsp;&nbsp;&nbsp; Privatizou geral?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nem a pau!!!!<\/strong><\/p>\n\n\n\n<p>O texto constitucional n\u00e3o previu a obrigatoriedade de institui\u00e7\u00e3o de Procuradorias municipais (CF\/1988, arts. 131 e 132), de modo que n\u00e3o cabe \u00e0 Constitui\u00e7\u00e3o estadual restringir o poder de auto-organiza\u00e7\u00e3o dos munic\u00edpios. Ademais, <strong>n\u00e3o h\u00e1 norma constitucional de reprodu\u00e7\u00e3o obrigat\u00f3ria que vincule o poder legislativo municipal \u00e0 cria\u00e7\u00e3o de \u00f3rg\u00e3os pr\u00f3prios de advocacia p\u00fablica.<\/strong><\/p>\n\n\n\n<p>A op\u00e7\u00e3o de instituir ou n\u00e3o um corpo pr\u00f3prio de procuradores municipais \u00e9 decis\u00e3o de compet\u00eancia de cada munic\u00edpio, como ente federativo dotado de autonomia. Entretanto, feita a op\u00e7\u00e3o por sua institui\u00e7\u00e3o, o provimento de seus cargos deve ocorrer mediante pr\u00e9via aprova\u00e7\u00e3o em concurso p\u00fablico, visto que a possibilidade de contrata\u00e7\u00e3o direta e gen\u00e9rica de servi\u00e7os de representa\u00e7\u00e3o judicial e extrajudicial configura ofensa aos ditames constitucionais.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>1.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Com base nesses entendimentos, o Plen\u00e1rio, por unanimidade, julgou parcialmente procedente a a\u00e7\u00e3o para (i) conferir interpreta\u00e7\u00e3o conforme a Constitui\u00e7\u00e3o ao art. 81-A, caput, da&nbsp;Constitui\u00e7\u00e3o do Estado de Pernambuco, no sentido de que a institui\u00e7\u00e3o de Procuradorias municipais depende de escolha pol\u00edtica aut\u00f4noma de cada munic\u00edpio, no exerc\u00edcio da prerrogativa de sua auto-organiza\u00e7\u00e3o, sem que essa obrigatoriedade derive automaticamente da previs\u00e3o de normas estaduais; (ii) declarar a inconstitucionalidade dos \u00a7\u00a7 1\u00ba e 3\u00ba do art. 81-A da&nbsp;Constitui\u00e7\u00e3o do Estado de Pernambuco, tendo em vista que, feita a op\u00e7\u00e3o municipal pela cria\u00e7\u00e3o de um corpo pr\u00f3prio de procuradores, a realiza\u00e7\u00e3o de concurso p\u00fablico \u00e9 a \u00fanica forma constitucionalmente poss\u00edvel de provimento desses cargos (CF\/1988, art. 37, II), ressalvadas as situa\u00e7\u00f5es excepcionais em que tamb\u00e9m \u00e0 Uni\u00e3o, aos estados e ao Distrito Federal se possibilita a contrata\u00e7\u00e3o de advogados externos, conforme os par\u00e2metros reconhecidos pela jurisprud\u00eancia desta Corte.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-constitucional\"><a>DIREITO CONSTITUCIONAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-nbsp-nbsp-nbsp-nbsp-forcas-armadas-atribuicoes-e-competencia-do-presidente-da-republica-para-requerer-o-seu-emprego\"><a>2.&nbsp;&nbsp;&nbsp;&nbsp; For\u00e7as Armadas: atribui\u00e7\u00f5es e compet\u00eancia do Presidente da Rep\u00fablica para requerer o seu emprego<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>A miss\u00e3o institucional das For\u00e7as Armadas na defesa da P\u00e1tria, na garantia dos poderes constitucionais e na garantia da lei e da ordem n\u00e3o acomoda o exerc\u00edcio de \u201cpoder moderador\u201d entre os Poderes Executivo, Legislativo e Judici\u00e1rio.<\/p>\n\n\n\n<p>ADI 6.457\/DF, relator Ministro Luiz Fux, julgamento virtual finalizado em 08.04.2024 (Info 1131)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-1-nbsp-situacao-fatica\"><a>2.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O Partido Democr\u00e1tico Trabalhista ajuizou a ADI 6457 no STF para que a Corte delimitasse o alcance das normas jur\u00eddicas que tratam da destina\u00e7\u00e3o constitucional das For\u00e7as Armadas (artigo 142 da Constitui\u00e7\u00e3o Federal e dispositivos da Lei Complementar 97\/1999). Para o partido, \u00e9 necess\u00e1rio que o STF explicite que o emprego das For\u00e7as Armadas se limita aos casos e procedimentos previstos nos artigos 34, 136 e 137 da Constitui\u00e7\u00e3o Federal (interven\u00e7\u00e3o, estado de defesa e estado de s\u00edtio). Segundo a legenda, a provid\u00eancia \u00e9 necess\u00e1ria para repelir a inconstitucionalidade do uso das For\u00e7as Armadas na garantia dos Poderes constitucionais em conflagra\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-2-nbsp-analise-estrategica\"><a>2.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>2.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>&nbsp;Lei Complementar n\u00ba 97\/1999: \u201cArt. 1\u00ba As For\u00e7as Armadas, constitu\u00eddas pela Marinha, pelo Ex\u00e9rcito e pela Aeron\u00e1utica, s\u00e3o institui\u00e7\u00f5es nacionais permanentes e regulares, organizadas com base na hierarquia e na disciplina, sob a autoridade suprema do Presidente da Rep\u00fablica e destinam-se \u00e0 defesa da P\u00e1tria, \u00e0 garantia dos poderes constitucionais e, por iniciativa de qualquer destes, da lei e da ordem. (&#8230;) Art. 15. O emprego das For\u00e7as Armadas na defesa da P\u00e1tria e na garantia dos poderes constitucionais, da lei e da ordem, e na participa\u00e7\u00e3o em opera\u00e7\u00f5es de paz, \u00e9 de responsabilidade do Presidente da Rep\u00fablica, que determinar\u00e1 ao Ministro de Estado da Defesa a ativa\u00e7\u00e3o de \u00f3rg\u00e3os operacionais, observada a seguinte forma de subordina\u00e7\u00e3o: I &#8211; ao Comandante Supremo, por interm\u00e9dio do Ministro de Estado da Defesa, no caso de Comandos conjuntos, compostos por meios adjudicados pelas For\u00e7as Armadas e, quando necess\u00e1rio, por outros \u00f3rg\u00e3os; (Reda\u00e7\u00e3o dada pela Lei Complementar n\u00ba 136, de 2010). II &#8211; diretamente ao Ministro de Estado da Defesa, para fim de adestramento, em opera\u00e7\u00f5es conjuntas, ou por ocasi\u00e3o da participa\u00e7\u00e3o brasileira em opera\u00e7\u00f5es de paz; (Reda\u00e7\u00e3o dada pela Lei Complementar n\u00ba 136, de 2010). III &#8211; diretamente ao respectivo Comandante da For\u00e7a, respeitada a dire\u00e7\u00e3o superior do Ministro de Estado da Defesa, no caso de emprego isolado de meios de uma \u00fanica For\u00e7a. \u00a7 1\u00ba Compete ao Presidente da Rep\u00fablica a decis\u00e3o do emprego das For\u00e7as Armadas, por iniciativa pr\u00f3pria ou em atendimento a pedido manifestado por quaisquer dos poderes constitucionais, por interm\u00e9dio dos Presidentes do Supremo Tribunal Federal, do Senado Federal ou da C\u00e2mara dos Deputados. \u00a7 2\u00ba A atua\u00e7\u00e3o das For\u00e7as Armadas, na garantia da lei e da ordem, por iniciativa de quaisquer dos poderes constitucionais, ocorrer\u00e1 de acordo com as diretrizes baixadas em ato do Presidente da Rep\u00fablica, ap\u00f3s esgotados os instrumentos destinados \u00e0 preserva\u00e7\u00e3o da ordem p\u00fablica e da incolumidade das pessoas e do patrim\u00f4nio, relacionados no art. 144 da Constitui\u00e7\u00e3o Federal. \u00a7 3\u00ba Consideram-se esgotados os instrumentos relacionados no art. 144 da Constitui\u00e7\u00e3o Federal quando, em determinado momento, forem eles formalmente reconhecidos pelo respectivo Chefe do Poder Executivo Federal ou Estadual como indispon\u00edveis, inexistentes ou insuficientes ao desempenho regular de sua miss\u00e3o constitucional. (Inclu\u00eddo pela Lei Complementar n\u00ba 117, de 2004).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-2-nbsp-nbsp-nbsp-poder-moderador\"><a>2.2.2.&nbsp;&nbsp;&nbsp; Poder moderador?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>N\u00e3o exatamente&#8230;.<\/strong><\/p>\n\n\n\n<p>O emprego das For\u00e7as Armadas para a \u201cgarantia da lei e da ordem\u201d, embora n\u00e3o se restrinja \u00e0s hip\u00f3teses de interven\u00e7\u00e3o federal e de estados de defesa e de s\u00edtio, presta-se ao excepcional enfrentamento de grave e concreta viola\u00e7\u00e3o \u00e0 seguran\u00e7a p\u00fablica interna. Essa atua\u00e7\u00e3o apenas ocorrer\u00e1 em car\u00e1ter SUBSIDI\u00c1RIO, <strong>ap\u00f3s o esgotamento dos mecanismos ordin\u00e1rios e preferenciais de preserva\u00e7\u00e3o da ordem p\u00fablica e da incolumidade das pessoas e do patrim\u00f4nio, mediante a atua\u00e7\u00e3o colaborativa das institui\u00e7\u00f5es estatais e sujeita ao controle permanente dos demais Poderes, na forma da Constitui\u00e7\u00e3o e da lei<\/strong>.<\/p>\n\n\n\n<p>A chefia das For\u00e7as Armadas consiste em poder limitado, do qual se deve excluir qualquer interpreta\u00e7\u00e3o que permita sua utiliza\u00e7\u00e3o para indevidas intromiss\u00f5es no regular e independente funcionamento dos outros Poderes. Nesse contexto, a autoridade suprema do Presidente da Rep\u00fablica se relaciona apenas \u00e0s atribui\u00e7\u00f5es materiais constitucionalmente destinadas ao chefe do Executivo nacional (CF\/1988, art. 84). Al\u00e9m disso, a sua prerrogativa em autorizar o emprego das For\u00e7as Armadas, seja por iniciativa pr\u00f3pria, seja a pedido de outro poder constitucional, n\u00e3o pode ser exercida contra os pr\u00f3prios Poderes entre si.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>2.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p><a>Com base nesses e outros entendimentos, o Plen\u00e1rio, por unanimidade,&nbsp;<\/a>converteu o referendo da&nbsp;medida cautelar&nbsp;em julgamento de m\u00e9rito e julgou parcialmente procedente a a\u00e7\u00e3o para conferir interpreta\u00e7\u00e3o conforme aos artigos 1\u00ba,&nbsp;caput<em>,&nbsp;<\/em>e 15,&nbsp;caput&nbsp;e \u00a7\u00a7 1\u00ba, 2\u00ba e 3\u00ba, ambos da&nbsp;Lei Complementar n\u00ba 97\/1999, nos termos da respectiva ata de julgamento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-nbsp-nbsp-nbsp-nbsp-banco-central-do-brasil-aquisicao-de-papel-moeda-e-moeda-metalica-fabricados-fora-do-pais-por-fornecedor-estrangeiro\"><a>3.&nbsp;&nbsp;&nbsp;&nbsp; Banco Central do Brasil: aquisi\u00e7\u00e3o de papel-moeda e moeda met\u00e1lica fabricados fora do Pa\u00eds por fornecedor estrangeiro<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>\u00c9 constitucional a autoriza\u00e7\u00e3o conferida ao Banco Central do Brasil (BCB), por lei federal, para adquirir papel-moeda e moeda met\u00e1lica fabricados fora do Pa\u00eds por fornecedor estrangeiro, com o objetivo de abastecer o meio circulante nacional.<\/p>\n\n\n\n<p>ADI 6.936\/DF, relator Ministro Dias Toffoli, redator do ac\u00f3rd\u00e3o Ministro Cristiano Zanin, julgamento virtual finalizado em 08.04.2024 (Info 1131)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-1-nbsp-situacao-fatica\"><a>3.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O Partido Social Crist\u00e3o (PSC) questiona no STF a constitucionalidade de dispositivos da Lei Federal 13.416\/2017 que autorizam o Banco Central do Brasil a adquirir papel-moeda e moeda met\u00e1lica fabricados fora do pa\u00eds por fornecedor estrangeiro para abastecer o meio circulante nacional.<\/p>\n\n\n\n<p>A legisla\u00e7\u00e3o impugnada prev\u00ea que a inviabilidade ou fundada incerteza quanto ao atendimento, pela Casa da Moeda do Brasil, da moeda circulante ou do cronograma para seu abastecimento, em cada exerc\u00edcio financeiro, caracteriza situa\u00e7\u00e3o de emerg\u00eancia, para efeito de aquisi\u00e7\u00e3o de papel-moeda e de moeda met\u00e1lica de fabricantes estrangeiros por dispensa de licita\u00e7\u00e3o.<\/p>\n\n\n\n<p>Na ADI 6936, o partido alega que, ao prever a excepcionalidade da hip\u00f3tese de emiss\u00e3o da moeda no exterior, a norma colide com os princ\u00edpios da soberania e da independ\u00eancia nacionais, e afronta a compet\u00eancia da Uni\u00e3o para emitir moeda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-2-nbsp-analise-estrategica\"><a>3.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>3.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n\u00ba 13.416\/2017: \u201cArt. 1\u00ba Fica autorizado o Banco Central do Brasil a adquirir papel-moeda e moeda met\u00e1lica fabricados fora do Pa\u00eds por fornecedor estrangeiro, com o objetivo de abastecer o meio circulante nacional, observado o disposto na Lei n\u00ba 8.666, de 21 de junho de 1993. Par\u00e1grafo \u00fanico. As aquisi\u00e7\u00f5es referidas no caput obedecer\u00e3o a cronograma fixado pelo Banco Central do Brasil para cada exerc\u00edcio financeiro, observadas as diretrizes estabelecidas pelo Conselho Monet\u00e1rio Nacional. Art. 2\u00ba A inviabilidade ou fundada incerteza quanto ao atendimento, pela Casa da Moeda do Brasil, da demanda por meio circulante ou do cronograma para seu abastecimento, em cada exerc\u00edcio financeiro, caracteriza situa\u00e7\u00e3o de emerg\u00eancia, para efeito de aquisi\u00e7\u00e3o de papel-moeda e de moeda met\u00e1lica de fabricantes estrangeiros, na forma do inciso IV do caput do art. 24 da Lei n\u00ba 8.666, de 21 de junho de 1993. \u00a7 1\u00ba Caracterizam a inviabilidade ou fundada incerteza de que trata o caput: I &#8211; o atraso acumulado de 15% (quinze por cento) das quantidades contratadas, por denomina\u00e7\u00e3o, de papel-moeda ou de moeda met\u00e1lica; e II &#8211; outras hip\u00f3teses de descumprimento de cl\u00e1usula contratual, devidamente justificadas, que tornem invi\u00e1vel o atendimento da demanda por meio circulante ou do cronograma para seu abastecimento. \u00a7 2\u00ba Para fins da caracteriza\u00e7\u00e3o da situa\u00e7\u00e3o de emerg\u00eancia de que trata este artigo, o Banco Central do Brasil fica obrigado a enviar o Programa Anual de Produ\u00e7\u00e3o \u00e0 Casa da Moeda do Brasil, at\u00e9 31 de agosto de cada ano, no qual ser\u00e3o indicadas as proje\u00e7\u00f5es de demandas de papel-moeda e de moeda met\u00e1lica para o exerc\u00edcio financeiro seguinte.\u201d<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-2-nbsp-nbsp-nbsp-tudo-certo-arnaldo\"><a>3.2.2.&nbsp;&nbsp;&nbsp; Tudo certo, Arnaldo?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Segue o jogo!!!<\/strong><\/p>\n\n\n\n<p><strong>A compet\u00eancia administrativa da Uni\u00e3o para emiss\u00e3o da moeda (CF\/1988, art. 21, VII c\/c o art. 164) n\u00e3o deve ser confundida com a atividade material de confec\u00e7\u00e3o ou fabrica\u00e7\u00e3o de papel moeda e moeda met\u00e1lica.<\/strong> Assim, a exclusividade da fabrica\u00e7\u00e3o de numer\u00e1rio conferida \u00e0 Casa da Moeda \u00e9 uma op\u00e7\u00e3o de ordem legal (Lei n\u00ba 5.895\/1973) e n\u00e3o uma imposi\u00e7\u00e3o do texto constitucional, de modo que n\u00e3o h\u00e1 impedimento para que o legislador mitigue ou modifique esse regime ou, ainda, acres\u00e7a uma nova possibilidade de log\u00edstica da atividade.<\/p>\n\n\n\n<p>Na esp\u00e9cie, houve altera\u00e7\u00e3o do regime de exclusividade da Casa da Moeda e a autoriza\u00e7\u00e3o para o BCB adquirir papel-moeda e moeda met\u00e1lica fabricados fora do Pa\u00eds por fornecedor estrangeiro, a fim de abastecer o meio circulante nacional, observadas as regras de licita\u00e7\u00e3o. Ademais, previu-se que as aquisi\u00e7\u00f5es devem obedi\u00eancia ao cronograma fixado pelo BCB para cada exerc\u00edcio financeiro, observadas as diretrizes estabelecidas pelo Conselho Monet\u00e1rio Nacional.<\/p>\n\n\n\n<p>Nesse contexto, inexiste incompatibilidade com o texto constitucional ou viola\u00e7\u00e3o \u00e0 soberania nacional pela simples fabrica\u00e7\u00e3o de numer\u00e1rio no mercado estrangeiro. A lei impugnada traduz t\u00e3o somente uma ESCOLHA poss\u00edvel do legislador infraconstitucional com rela\u00e7\u00e3o ao melhor modelo para suprir a demanda por papel-moeda no Brasil.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>3.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Com base nesses entendimentos, o Plen\u00e1rio, por maioria, julgou improcedente a a\u00e7\u00e3o para reconhecer a constitucionalidade dos&nbsp;arts. 1\u00ba, caput e par\u00e1grafo \u00fanico, e 2\u00ba, caput e \u00a7\u00a7 1\u00ba e 2\u00ba, ambos da&nbsp;Lei n\u00ba 13.416\/2017.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-nbsp-nbsp-nbsp-nbsp-porte-de-arma-de-fogo-para-vigilantes-e-segurancas-de-instituicoes-publicas-ou-privadas-no-ambito-estadual\"><a>4.&nbsp;&nbsp;&nbsp;&nbsp; Porte de arma de fogo para vigilantes e seguran\u00e7as de institui\u00e7\u00f5es p\u00fablicas ou privadas no \u00e2mbito estadual<\/a><\/h2>\n\n\n\n<p><strong>A\u00c7\u00c3O DIRETA DE INCONSTITUCIONALIDADE<\/strong><\/p>\n\n\n\n<p>\u00c9 inconstitucional \u2014 por violar as compet\u00eancias da Uni\u00e3o material exclusiva para autorizar e fiscalizar a produ\u00e7\u00e3o e o com\u00e9rcio de material b\u00e9lico (CF\/1988, art. 21, VI) e legislativa privativa para dispor acerca de normas gerais sobre esses artefatos (CF\/1988, art. 22, XXI) \u2014 lei estadual que reconhece o risco da atividade e a efetiva necessidade do porte de armas de fogo a vigilantes e a seguran\u00e7as prestadores de servi\u00e7os em institui\u00e7\u00f5es privadas e p\u00fablicas.<\/p>\n\n\n\n<p>ADI 7.574\/ES, relator Ministro Dias Toffoli, julgamento virtual finalizado em 08.04.2024 (Info 1131)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-1-nbsp-situacao-fatica\"><a>4.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O presidente da Rep\u00fablica, Luiz In\u00e1cio Lula da Silva, representado pela Advocacia-Geral da Uni\u00e3o (AGU), apresentou 10 a\u00e7\u00f5es no STF contra leis estaduais e municipal que facilitam o porte de armas de fogo. A maioria das leis questionadas envolve atividades de CACs (colecionadores, atiradores e ca\u00e7adores), e outras asseguram o porte a categorias profissionais espec\u00edficas, como defensores p\u00fablicos, policiais cient\u00edficos, vigilantes, seguran\u00e7as e agentes de seguran\u00e7a socioeducativos.<\/p>\n\n\n\n<p>As peti\u00e7\u00f5es destacam que, de acordo com a Constitui\u00e7\u00e3o Federal, a compet\u00eancia para autorizar e fiscalizar o uso de material b\u00e9lico e para legislar sobre a mat\u00e9ria seria da Uni\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-2-nbsp-analise-estrategica\"><a>4.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-1-nbsp-nbsp-nbsp-arma-no-coldre\"><a>4.2.1.&nbsp;&nbsp;&nbsp; Arma no coldre<\/a>?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Arma no cofre!!!<\/strong><\/p>\n\n\n\n<p>Tendo em vista o objetivo de se instituir uma pol\u00edtica de \u00e2mbito nacional, <strong>prevalece o interesse da Uni\u00e3o no trato das mat\u00e9rias atinentes \u00e0s compet\u00eancias acima mencionadas.<\/strong><\/p>\n\n\n\n<p>Ademais, os estados e os munic\u00edpios n\u00e3o s\u00e3o competentes para ampliar o acesso ao porte de arma de fogo para al\u00e9m das hip\u00f3teses previstas na legisla\u00e7\u00e3o federal vigente, porquanto cabe \u00e0 Uni\u00e3o (CF\/1988, arts. 21, VI, e 22, I) a defini\u00e7\u00e3o dos requisitos para a concess\u00e3o do porte de arma de fogo e dos poss\u00edveis titulares de tal direito.<\/p>\n\n\n\n<p>Na esp\u00e9cie, <strong>o estado-membro que editou a lei impugnada n\u00e3o det\u00e9m compet\u00eancia formal para legislar a respeito de material b\u00e9lico e, ao dispor sobre o tema, o fez de forma contr\u00e1ria \u00e0s regulamenta\u00e7\u00f5es da Uni\u00e3o<\/strong> (Lei n\u00ba 10.826\/2003 e Decreto n\u00ba 11.615\/2023).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-2-nbsp-nbsp-nbsp-resultado-final\"><a>4.2.2.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Com base nesses entendimentos, o Plen\u00e1rio, por unanimidade, julgou procedente a a\u00e7\u00e3o para declarar a inconstitucionalidade da&nbsp;Lei n\u00ba 11.688\/2022 do Estado do Espirito Santo.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-financeiro\"><a>DIREITO FINANCEIRO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-nbsp-nbsp-nbsp-nbsp-iptu-isencao-em-favor-dos-municipes-contribuintes-considerados-carentes\"><a>5.&nbsp;&nbsp;&nbsp;&nbsp; IPTU: isen\u00e7\u00e3o em favor dos mun\u00edcipes contribuintes considerados carentes<\/a><\/h2>\n\n\n\n<p><strong>RECURSO EXTRAORDIN\u00c1RIO<\/strong><\/p>\n\n\n\n<p>A aus\u00eancia de pr\u00e9via estimativa de impacto financeiro e or\u00e7ament\u00e1rio na proposta legislativa que implique ren\u00fancia de receita tribut\u00e1ria acarreta inconstitucionalidade formal, nos termos do art. 113 do ADCT, que \u00e9 aplic\u00e1vel a todos os entes federativos.<\/p>\n\n\n\n<p>RE 1.343.429\/SP, relator Ministro Dias Toffoli, julgamento virtual finalizado em 08.04.2024 (Info 1131)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-1-nbsp-situacao-fatica\"><a>5.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O Munic\u00edpio de Itirapina-SP aprovou lei que previa isen\u00e7\u00e3o de IPTU em favor dos mun\u00edcipes considerados carentes. A aprova\u00e7\u00e3o ocorreu sem que fosse realizada pr\u00e9via estimativa do impacto financeiro e or\u00e7ament\u00e1rio, raz\u00e3o pela qual a norma foi impugnada pelo Procurador-Geral de Justi\u00e7a do Estado de S\u00e3o Paulo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-2-nbsp-analise-estrategica\"><a>5.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>5.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>ADCT: \u201cArt. 113. A proposi\u00e7\u00e3o legislativa que crie ou altere despesa obrigat\u00f3ria ou ren\u00fancia de receita dever\u00e1 ser acompanhada da estimativa do seu impacto or\u00e7ament\u00e1rio e financeiro. (Inclu\u00eddo pela Emenda Constitucional n\u00ba 95, de 2016)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-2-nbsp-nbsp-nbsp-inconstitucionalidade-formal\"><a>5.2.2.&nbsp;&nbsp;&nbsp; Inconstitucionalidade FORMAL?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Exatamente!!!<\/strong><\/p>\n\n\n\n<p>Conforme jurisprud\u00eancia do STF, a EC n\u00ba 95\/2016, ao introduzir o referido dispositivo ao ADCT, conferiu&nbsp;<em>status<\/em>&nbsp;constitucional \u00e0 obrigatoriedade da avalia\u00e7\u00e3o de impacto or\u00e7ament\u00e1rio e financeiro em qualquer proposta legislativa que crie ou altere despesa obrigat\u00f3ria ou ren\u00fancia de receita. Ademais, as normas dispostas no texto constitucional, definitivas ou transit\u00f3rias, referentes ao processo legislativo, s\u00e3o de reprodu\u00e7\u00e3o obrigat\u00f3ria pelos estados-membros.<\/p>\n\n\n\n<p>Na esp\u00e9cie, a lei municipal impugnada, que concedeu isen\u00e7\u00e3o de IPTU, n\u00e3o atendeu aos ditames do art. 113 do ADCT. Contudo, <strong>por possuir evidente car\u00e1ter social, pois beneficia mun\u00edcipes inseridos em contexto de especial vulnerabilidade, reputa-se necess\u00e1rio modular os efeitos da decis\u00e3o que reconhece o v\u00edcio de constitucionalidade<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>5.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Com base nesse entendimento, o Plen\u00e1rio,&nbsp;por unanimidade, deu provimento ao recurso extraordin\u00e1rio interposto pelo Procurador-Geral de Justi\u00e7a do Estado de S\u00e3o Paulo, para declarar a inconstitucionalidade formal da&nbsp;Lei n\u00ba 2.982\/2020 do Munic\u00edpio de Itirapina\/SP e atribuir \u00e0 decis\u00e3o efeitos&nbsp;<em>ex nunc<\/em>, a fim de que sejam produzidos apenas a partir da publica\u00e7\u00e3o da ata de julgamento do m\u00e9rito, de modo a preservar as isen\u00e7\u00f5es de IPTU concedidas at\u00e9 a mesma data.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-civil\"><a>DIREITO PROCESSUAL CIVIL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-nbsp-nbsp-nbsp-nbsp-coisa-julgada-em-materia-tributaria-nao-incidencia-de-multa-sobre-o-valor-da-csll-nao-paga\"><a>6.&nbsp;&nbsp;&nbsp;&nbsp; Coisa julgada em mat\u00e9ria tribut\u00e1ria: n\u00e3o incid\u00eancia de multa sobre o valor da CSLL n\u00e3o paga<\/a><\/h2>\n\n\n\n<p><strong>RECURSO EXTRAORDIN\u00c1RIA<\/strong><\/p>\n\n\n\n<p>O amicus curiae n\u00e3o tem legitimidade para opor embargos de declara\u00e7\u00e3o em recurso extraordin\u00e1rio com repercuss\u00e3o geral. Todavia, em sede de recurso extraordin\u00e1rio, o relator eventualmente pode ouvir os terceiros sobre a quest\u00e3o da repercuss\u00e3o geral e levar a mat\u00e9ria para esclarecimentos (RISTF, art. 323, \u00a7 3\u00ba).<\/p>\n\n\n\n<p>RE 955.227 ED e ED-segundos\/BA, relator Ministro Lu\u00eds Roberto Barroso, julgamento finalizado em 04.04.2024 (Info 1131)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-1-nbsp-situacao-fatica\"><a>6.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Trata-se de Recurso Extraordin\u00e1rio de empresas que discutindo obriga\u00e3o de recolhimento da CSLL. A mat\u00e9ria foi objeto de dois recursos extraordin\u00e1rios com repercuss\u00e3o geral reconhecida: o RE 955227 (Tema 885) e o RE 949297 (Tema 881), apresentados pela Uni\u00e3o contra decis\u00f5es que, na d\u00e9cada de 1990, consideraram inconstitucional a lei que instituiu a Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL) e deram a duas empresas o direito de n\u00e3o a recolher.<\/p>\n\n\n\n<p>Em fevereiro de 2023, o Plen\u00e1rio fixou a tese (coisa lindaaaa :) de que uma decis\u00e3o judicial, mesmo definitiva (transitada em julgado), produz efeitos apenas enquanto permanecer o quadro f\u00e1tico e jur\u00eddico que a justificou. Ou seja, havendo altera\u00e7\u00e3o no cen\u00e1rio, a decis\u00e3o anterior pode deixar de ter efic\u00e1cia.<\/p>\n\n\n\n<p>Na decis\u00e3o, ficou estabelecido que a cobran\u00e7a poderia ocorrer a partir 2007, quando o STF validou a lei que criou a CSLL (ADI 15). Nos embargos, as empresas pretendiam que a cobran\u00e7a fosse retomada apenas a partir da decis\u00e3o nos recursos, em 2023, o que foi rejeitado pelo relator sem que ningu\u00e9m fosse ouvido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-2-nbsp-analise-estrategica\"><a>6.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-1-nbsp-nbsp-nbsp-questao-juridica\"><a>6.2.1.&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>CPC\/2015: \u201cArt. 138. O juiz ou o relator, considerando a relev\u00e2ncia da mat\u00e9ria, a especificidade do tema objeto da demanda ou a repercuss\u00e3o social da controv\u00e9rsia, poder\u00e1, por decis\u00e3o irrecorr\u00edvel, de of\u00edcio ou a requerimento das partes ou de quem pretenda manifestar-se, solicitar ou admitir a participa\u00e7\u00e3o de pessoa natural ou jur\u00eddica, \u00f3rg\u00e3o ou entidade especializada, com representatividade adequada, no prazo de 15 (quinze) dias de sua intima\u00e7\u00e3o. \u00a7 1\u00ba A interven\u00e7\u00e3o de que trata o caput n\u00e3o implica altera\u00e7\u00e3o de compet\u00eancia nem autoriza a interposi\u00e7\u00e3o de recursos, ressalvadas a oposi\u00e7\u00e3o de embargos de declara\u00e7\u00e3o e a hip\u00f3tese do \u00a7 3\u00ba.\u201d<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-2-nbsp-nbsp-nbsp-o-relator-poderia-deveria-ouvir-terceiros\"><a>6.2.2.&nbsp;&nbsp;&nbsp; O relator poderia (deveria) ouvir terceiros?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Com certeza!!!!<\/strong><\/p>\n\n\n\n<p>Tendo em vista que h\u00e1 a objetiva\u00e7\u00e3o do processo com a repercuss\u00e3o geral, aplica-se ao recurso extraordin\u00e1rio a regra do n\u00e3o cabimento de recursos opostos por&nbsp;<em>amici curiae<\/em>, apesar do que disp\u00f5e o art. 138, \u00a7 1\u00ba, do CPC\/2015. Por outro lado, <strong>\u00e9 poss\u00edvel a invoca\u00e7\u00e3o do que preceituado no Regimento Interno do STF e, nesse sentido, o relator, provocado pelo&nbsp;<em>amicus curiae<\/em>&nbsp;ou por qualquer terceiro, pode levar a debate a mat\u00e9ria controvertida para esclarecimentos, caso entenda pertinente.<\/strong><\/p>\n\n\n\n<p>N\u00e3o incide multa tribut\u00e1ria de qualquer natureza sobre o valor da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL) n\u00e3o recolhida pelos contribuintes benefici\u00e1rios de decis\u00f5es transitadas em julgado \u2014 em a\u00e7\u00f5es judiciais propostas para questionar a exigibilidade do referido tributo \u2014 e cujo fato gerador tenha ocorrido at\u00e9 13.02.2023, data da publica\u00e7\u00e3o da ata do julgamento do m\u00e9rito realizado por esta Corte nos recursos extraordin\u00e1rios paradigmas dos Temas 881 e 885 da sistem\u00e1tica da repercuss\u00e3o geral. Ademais, n\u00e3o h\u00e1 qualquer possibilidade de repeti\u00e7\u00e3o de ind\u00e9bito para o contribuinte que eventualmente j\u00e1 tenha efetuado o pagamento das multas.<\/p>\n\n\n\n<p>Na situa\u00e7\u00e3o exposta, a exclus\u00e3o das multas do tributo devido \u2014 que n\u00e3o foi recolhido \u2014 levou em considera\u00e7\u00e3o: (i) a natureza jur\u00eddica das multas que, em alguma medida, s\u00e3o punitivas; (ii) a aus\u00eancia de dolo ou de m\u00e1-f\u00e9 do contribuinte; (iii) a presen\u00e7a da coisa julgada favor\u00e1vel ao jurisdicionado; (iv) a seguran\u00e7a jur\u00eddica e a prote\u00e7\u00e3o da confian\u00e7a no caso concreto; e (v) a exist\u00eancia de pronunciamento do Superior Tribunal de Justi\u00e7a, em recurso repetitivo, favor\u00e1vel ao contribuinte, especificamente quanto \u00e0 subsist\u00eancia da coisa julgada e que foi proferida ap\u00f3s a decis\u00e3o do STF pela constitucionalidade da cobran\u00e7a da CSLL.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-3-nbsp-nbsp-nbsp-resultado-final\"><a>6.2.3.&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Com base nesses e em outros entendimentos, o Plen\u00e1rio, por maioria, em aprecia\u00e7\u00e3o conjunta, resolvendo quest\u00e3o de ordem, manteve sua jurisprud\u00eancia no sentido da aus\u00eancia de legitimidade de\u00a0<em>amicus curiae<\/em>\u00a0para oposi\u00e7\u00e3o de embargos de declara\u00e7\u00e3o, registrando, todavia, a possibilidade de invoca\u00e7\u00e3o do art. 323, \u00a7 3\u00ba, do RISTF. Igualmente em vota\u00e7\u00e3o majorit\u00e1ria, o Tribunal n\u00e3o modulou os efeitos da decis\u00e3o de m\u00e9rito relativa aos Temas\u00a0881\u00a0e\u00a0885\u00a0da repercuss\u00e3o geral (noticiada no\u00a0Informativo 1082) e deu parcial provimento aos embargos de declara\u00e7\u00e3o opostos pela empresa recorrida no\u00a0RE 949.297\/CE, a fim de afastar exclusivamente as multas tribut\u00e1rias de qualquer natureza impostas aos contribuintes que tiveram decis\u00e3o favor\u00e1vel transitada em julgado em a\u00e7\u00f5es judiciais propostas para questionar a exigibilidade da CSLL e cujo fato gerador tenha ocorrido at\u00e9 a data da publica\u00e7\u00e3o da ata do julgamento de m\u00e9rito (13.02.2023), ficando preservada a incid\u00eancia dos juros de mora e da corre\u00e7\u00e3o monet\u00e1ria e vedada a repeti\u00e7\u00e3o dos valores j\u00e1 recolhidos referentes a multas de qualquer natureza.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"Incorporar PDF\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-f2506883-28c9-40f0-9df4-ced7efe1bfc9\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/24004442\/stf-informativo-1131.pdf\">stf-informativo-1131<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/24004442\/stf-informativo-1131.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f2506883-28c9-40f0-9df4-ced7efe1bfc9\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mais um passo em nossa caminhada jurisprudencial em 2024. Hoje, vamos para cima do Informativo n\u00ba 1131 do STF\u00a0COMENTADO.\u00a0Se voc\u00ea est\u00e1 ligad@ aqui\u00a0no Estrat\u00e9gia Carreiras Jur\u00eddicas, sabe a aprova\u00e7\u00e3o est\u00e1 no horizonte proximo! Simbora! DOWNLOAD do PDF DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp; Procuradoria municipal: impossibilidade de cria\u00e7\u00e3o por norma estadual e de contrata\u00e7\u00e3o de advogados sem concurso [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1389046","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STF 1131 Comentado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STF 1131 Comentado\" \/>\n<meta property=\"og:description\" content=\"Mais um passo em nossa caminhada jurisprudencial em 2024. Hoje, vamos para cima do Informativo n\u00ba 1131 do STF\u00a0COMENTADO.\u00a0Se voc\u00ea est\u00e1 ligad@ aqui\u00a0no Estrat\u00e9gia Carreiras Jur\u00eddicas, sabe a aprova\u00e7\u00e3o est\u00e1 no horizonte proximo! Simbora! DOWNLOAD do PDF DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp; Procuradoria municipal: impossibilidade de cria\u00e7\u00e3o por norma estadual e de contrata\u00e7\u00e3o de advogados sem concurso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T03:45:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T03:45:10+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STF 1131 Comentado\",\"datePublished\":\"2024-04-24T03:45:08+00:00\",\"dateModified\":\"2024-04-24T03:45:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/\"},\"wordCount\":4230,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/\",\"name\":\"Informativo STF 1131 Comentado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2024-04-24T03:45:08+00:00\",\"dateModified\":\"2024-04-24T03:45:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STF 1131 Comentado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STF 1131 Comentado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STF 1131 Comentado","og_description":"Mais um passo em nossa caminhada jurisprudencial em 2024. Hoje, vamos para cima do Informativo n\u00ba 1131 do STF\u00a0COMENTADO.\u00a0Se voc\u00ea est\u00e1 ligad@ aqui\u00a0no Estrat\u00e9gia Carreiras Jur\u00eddicas, sabe a aprova\u00e7\u00e3o est\u00e1 no horizonte proximo! Simbora! DOWNLOAD do PDF DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp; Procuradoria municipal: impossibilidade de cria\u00e7\u00e3o por norma estadual e de contrata\u00e7\u00e3o de advogados sem concurso [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-04-24T03:45:08+00:00","article_modified_time":"2024-04-24T03:45:10+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"21 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STF 1131 Comentado","datePublished":"2024-04-24T03:45:08+00:00","dateModified":"2024-04-24T03:45:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/"},"wordCount":4230,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/","name":"Informativo STF 1131 Comentado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2024-04-24T03:45:08+00:00","dateModified":"2024-04-24T03:45:10+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stf-1131-comentado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STF 1131 Comentado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1389046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1389046"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1389046\/revisions"}],"predecessor-version":[{"id":1389050,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1389046\/revisions\/1389050"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1389046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1389046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1389046"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1389046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}