{"id":138739,"date":"2018-09-04T03:55:29","date_gmt":"2018-09-04T06:55:29","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=138739"},"modified":"2018-09-04T14:31:30","modified_gmt":"2018-09-04T17:31:30","slug":"ranking-pm-mg-soldado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/","title":{"rendered":"Ranking\u00a0PM MG para Soldado: quer saber seu resultado? Preencha seu gabarito e confira o ranking"},"content":{"rendered":"<p><span style=\"font-size: 18pt;\"><strong><em>Participe do Ranking PM MG e confira seu desempenho na prova objetiva<\/em><\/strong><\/span><\/p>\n<p>O gabarito preliminar do\u00a0concurso da Pol\u00edcia Militar de Minas Gerais foi divulgado hoje, no site do Centro de Recrutamento e Sele\u00e7\u00e3o (CRS) da PMMG.<\/p>\n<p>Enquanto o resultado final n\u00e3o \u00e9 divulgado, voc\u00ea pode aliviar a ansiedade participando do <strong>Ranking PM MG.\u00a0<\/strong>Basta clicar na imagem abaixo e preencher o gabarito com as suas respostas.<\/p>\n<p>\u00c9 importante ressaltar que <strong>N\u00c3O<\/strong> \u00e9 necess\u00e1rio preencher mais de uma vez. O seu nome pode demorar um pouquinho a aparecer no ranking, mas isso \u00e9 normal. O preenchimento duplicado acaba atrapalhando a visualiza\u00e7\u00e3o correta das posi\u00e7\u00f5es (sua e dos outros candidatos).<\/p>\n<p style=\"text-align: center;\"><em><strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScvdLlG-OUbhdZqYHdOr1iYxZ4Rf8WeVMplGr4IRo8uMa_TaA\/viewform\" target=\"_blank\" rel=\"noopener\">Clique na imagem para participar do Ranking PM-MG<\/a>:<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScvdLlG-OUbhdZqYHdOr1iYxZ4Rf8WeVMplGr4IRo8uMa_TaA\/viewform\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-138727 size-full\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/07\/RANKING-PMMG-TARJA.jpg\" alt=\"Ranking PM MG\" width=\"1184\" height=\"183\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/07\/31101738\/RANKING-PMMG-TARJA.jpg 1184w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/07\/31101738\/RANKING-PMMG-TARJA.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/07\/31101738\/RANKING-PMMG-TARJA.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/07\/31101738\/RANKING-PMMG-TARJA.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/07\/31101738\/RANKING-PMMG-TARJA.jpg 610w\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\" \/><\/a><\/p>\n<p>O ranking n\u00e3o \u00e9 enviado via e-mail, portanto voc\u00ea deve conferir sua posi\u00e7\u00e3o nos ranking disponibilizados abaixo:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em><strong><span style=\"font-size: 24pt;\">Ranking PM MG (Feminino) &#8211; <a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vQKbcUQlV0w5_ZEyfJNXp3CPz-rChtbgeWK45Qs1kzPgg0yLqY9_xxbQ2dzgXuqpB1w3eAz3B6G-SgB\/pubhtml\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #ff0000; text-decoration: underline;\">Clique Aqui<\/span><\/span><\/a><\/span><\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong><span style=\"font-size: 24pt;\">Ranking PM MG (Masculino) &#8211; <a href=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vSFSIlQMVMQ4AQCvZiaQaoUxUGeyQtoOZ1DqPyiScMGa9RbuSborBFIvxOJlZGDicmbkqGTwfgJBI3R\/pubhtml\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #ff0000; text-decoration: underline;\">Clique Aqui<\/span><\/span><\/a><\/span><\/strong><\/em><\/p>\n<h2><\/h2>\n<h2>Corre\u00e7\u00e3o da prova<\/h2>\n<p>Nossos professores v\u00e3o fazer as corre\u00e7\u00f5es de forma escrita e todos os links v\u00e3o ser disponibilizados aqui mesmo, para que voc\u00ea possa comparar com suas respostas e at\u00e9 descobrir se h\u00e1 alguma quest\u00e3o pass\u00edvel de recurso.<\/p>\n<ul>\n<li><strong>Estat\u00edstica <\/strong><em><strong>&#8211; <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/estatistica-pmmg-prova-resolvida-e-gabarito\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Clique Aqui<\/span><\/a><\/strong><\/em><\/li>\n<li><strong>Direitos Humanos &#8211; <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pm-mg\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><em>Clique <\/em><\/span><span style=\"text-decoration: underline;\"><em>Aqu<\/em><\/span><span style=\"text-decoration: underline;\"><em>i<\/em><\/span><\/a><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Sobre a prova<\/h2>\n<p>Os candidatos que participaram do concurso, tiveram 3 horas para responder 40 quest\u00f5es das disciplinas de:\u00a0L\u00edngua Portuguesa,\u00a0Direito Penal,\u00a0Direito Constitucional,\u00a0Direito Penal Militar,\u00a0Estat\u00edstica,\u00a0Direitos Humanos e\u00a0Legisla\u00e7\u00e3o Extravagante.<\/p>\n<p>Alguns dias antes, a aplica\u00e7\u00e3o da prova acabou se tornando uma incerteza por conta de uma liminar que derrubou a <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/exigencia-nivel-superior-soldado-pm-mg\/\" target=\"_blank\" rel=\"noopener\">exig\u00eancia da forma\u00e7\u00e3o em N\u00edvel Superior<\/a> para o cargo de Soldado.<\/p>\n<p>O juiz de direito Mauro Pena Rocha decidiu na \u00faltima quarta-feira, suspender o concurso enquanto o edital n\u00e3o fosse retificado quanto \u00e0 escolaridade exigida aos candidatos.<\/p>\n<p>Embora ainda possa ser revista, a medida adotada pelo juiz da\u00a04\u00aa Vara da Fazenda P\u00fablica de Belo Horizonte, abriria a possibilidade para que candidatos que tenham cursado ensino m\u00e9dio concorram \u00e0s vagas.<\/p>\n<p>A Pol\u00edcia Militar de Minas Gerais\u00a0disse que\u00a0<strong><em>vai recorrer da decis\u00e3o da justi\u00e7a<\/em><\/strong>.\u00a0<em>Assim que a Pol\u00edcia Militar for notificada oficialmente da decis\u00e3o, vamos recorrer<\/em>, disse\u00a0a tenente-coronel Carla Cristina Marafelli.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34129\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2016\/02\/coruja-300x287.png\" alt=\"Enquete Ranking PM MG \" width=\"153\" height=\"146\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/29100122\/coruja.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/29100122\/coruja.png 314w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2016\/02\/29100122\/coruja.png 413w\" sizes=\"auto, (max-width: 153px) 100vw, 153px\" \/><\/p>\n<p><em><strong>Participe da nossa enquete e interaja com outros candidatos nos coment\u00e1rios:<\/strong><\/em><\/p>\n<div id=\"polls-231\" class=\"wp-polls\">\n\t<form id=\"polls_form_231\" class=\"wp-polls-form\" action=\"\/__wp__\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_231_nonce\" name=\"wp-polls-nonce\" value=\"bf6d71bf4b\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"231\" \/><\/p>\n\t\t<p><strong>Qual mat\u00e9ria foi a mais dif\u00edcil?<\/strong><\/p><div id=\"polls-231-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-821\" name=\"poll_231\" value=\"821\" \/> <label for=\"poll-answer-821\">Portugu\u00eas<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-822\" name=\"poll_231\" value=\"822\" \/> <label for=\"poll-answer-822\">Direito Penal<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-823\" name=\"poll_231\" value=\"823\" \/> <label for=\"poll-answer-823\">Direito Constitucional<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-824\" name=\"poll_231\" value=\"824\" \/> <label for=\"poll-answer-824\">Direito Penal Militar<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-825\" name=\"poll_231\" value=\"825\" \/> <label for=\"poll-answer-825\">Estat\u00edstica<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-826\" name=\"poll_231\" value=\"826\" \/> <label for=\"poll-answer-826\">Direitos Humanos<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-827\" name=\"poll_231\" value=\"827\" \/> <label for=\"poll-answer-827\">Legisla\u00e7\u00e3o Extravagante<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Voto   \" class=\"Buttons\" onclick=\"poll_vote(231);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(231); return false;\" title=\"Veja resultados desta pesquisa\">Ver resultados<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-231-loading\" class=\"wp-polls-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Carregando ...\" title=\"Carregando ...\" class=\"wp-polls-image\" \/>&nbsp;Carregando ...<\/div>\n\n<div id=\"polls-230\" class=\"wp-polls\">\n\t<form id=\"polls_form_230\" class=\"wp-polls-form\" action=\"\/__wp__\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_230_nonce\" name=\"wp-polls-nonce\" value=\"8a4db35c96\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"230\" \/><\/p>\n\t\t<p><strong>Voc\u00ea acha que o concurso ser\u00e1 posteriormente suspenso?<\/strong><\/p><div id=\"polls-230-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-819\" name=\"poll_230\" value=\"819\" \/> <label for=\"poll-answer-819\">Triste, mas acredito que sim<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-820\" name=\"poll_230\" value=\"820\" \/> <label for=\"poll-answer-820\">Espero que n\u00e3o<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Voto   \" class=\"Buttons\" onclick=\"poll_vote(230);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(230); return false;\" title=\"Veja resultados desta pesquisa\">Ver resultados<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-230-loading\" class=\"wp-polls-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Carregando ...\" title=\"Carregando ...\" class=\"wp-polls-image\" \/>&nbsp;Carregando ...<\/div>\n\n<div id=\"polls-228\" class=\"wp-polls\">\n\t<form id=\"polls_form_228\" class=\"wp-polls-form\" action=\"\/__wp__\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_228_nonce\" name=\"wp-polls-nonce\" value=\"a32a7e6717\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"228\" \/><\/p>\n\t\t<p><strong>Aconteceu alguma irregularidade antes\/durante a prova?<\/strong><\/p><div id=\"polls-228-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-814\" name=\"poll_228\" value=\"814\" \/> <label for=\"poll-answer-814\">Sim (conta nos coment\u00e1rios)<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-815\" name=\"poll_228\" value=\"815\" \/> <label for=\"poll-answer-815\">N\u00e3o. Tudo normal<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Voto   \" class=\"Buttons\" onclick=\"poll_vote(228);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(228); return false;\" title=\"Veja resultados desta pesquisa\">Ver resultados<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-228-loading\" class=\"wp-polls-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Carregando ...\" title=\"Carregando ...\" class=\"wp-polls-image\" \/>&nbsp;Carregando ...<\/div>\n\n<p>&nbsp;<\/p>\n<p><em>Ascom Estrat\u00e9gia<\/em><br \/>\nascomestrategia@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participe do Ranking PM MG e confira seu desempenho na prova objetiva O gabarito preliminar do\u00a0concurso da Pol\u00edcia Militar de Minas Gerais foi divulgado hoje, no site do Centro de Recrutamento e Sele\u00e7\u00e3o (CRS) da PMMG. Enquanto o resultado final n\u00e3o \u00e9 divulgado, voc\u00ea pode aliviar a ansiedade participando do Ranking PM MG.\u00a0Basta clicar na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":138741,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[],"tags":[],"tax_estado":[],"class_list":["post-138739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ranking PM MG para Soldado: preencha o gabarito e confira seu desempenho<\/title>\n<meta name=\"description\" content=\"Se voc\u00ea fez a prova do concurso PM MG, preencha seu gabarito no formul\u00e1rio e confira como foi seu desempenho com o Ranking PM MG para Soldado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ranking\u00a0PM MG para Soldado: quer saber seu resultado? Preencha seu gabarito e confira o ranking\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea fez a prova do concurso PM MG, preencha seu gabarito no formul\u00e1rio e confira como foi seu desempenho com o Ranking PM MG para Soldado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-04T06:55:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-04T17:31:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/31112523\/RANKING-PM-MG-e1535725531494.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"209\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Ranking\u00a0PM MG para Soldado: quer saber seu resultado? Preencha seu gabarito e confira o ranking\",\"datePublished\":\"2018-09-04T06:55:29+00:00\",\"dateModified\":\"2018-09-04T17:31:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/\"},\"wordCount\":420,\"commentCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2018\\\/09\\\/31112523\\\/RANKING-PM-MG-e1535725531494.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/\",\"name\":\"Ranking PM MG para Soldado: preencha o gabarito e confira seu desempenho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2018\\\/09\\\/31112523\\\/RANKING-PM-MG-e1535725531494.jpg\",\"datePublished\":\"2018-09-04T06:55:29+00:00\",\"dateModified\":\"2018-09-04T17:31:30+00:00\",\"description\":\"Se voc\u00ea fez a prova do concurso PM MG, preencha seu gabarito no formul\u00e1rio e confira como foi seu desempenho com o Ranking PM MG para Soldado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2018\\\/09\\\/31112523\\\/RANKING-PM-MG-e1535725531494.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2018\\\/09\\\/31112523\\\/RANKING-PM-MG-e1535725531494.jpg\",\"width\":400,\"height\":209},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/ranking-pm-mg-soldado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ranking\u00a0PM MG para Soldado: quer saber seu resultado? Preencha seu gabarito e confira o ranking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EstrategiaConcursos\",\"https:\\\/\\\/x.com\\\/EstratConcursos\"],\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/estrategia2013\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ranking PM MG para Soldado: preencha o gabarito e confira seu desempenho","description":"Se voc\u00ea fez a prova do concurso PM MG, preencha seu gabarito no formul\u00e1rio e confira como foi seu desempenho com o Ranking PM MG para Soldado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/","og_locale":"pt_BR","og_type":"article","og_title":"Ranking\u00a0PM MG para Soldado: quer saber seu resultado? Preencha seu gabarito e confira o ranking","og_description":"Se voc\u00ea fez a prova do concurso PM MG, preencha seu gabarito no formul\u00e1rio e confira como foi seu desempenho com o Ranking PM MG para Soldado.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2018-09-04T06:55:29+00:00","article_modified_time":"2018-09-04T17:31:30+00:00","og_image":[{"width":400,"height":209,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/31112523\/RANKING-PM-MG-e1535725531494.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Ranking\u00a0PM MG para Soldado: quer saber seu resultado? Preencha seu gabarito e confira o ranking","datePublished":"2018-09-04T06:55:29+00:00","dateModified":"2018-09-04T17:31:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/"},"wordCount":420,"commentCount":18,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/31112523\/RANKING-PM-MG-e1535725531494.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/","name":"Ranking PM MG para Soldado: preencha o gabarito e confira seu desempenho","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/31112523\/RANKING-PM-MG-e1535725531494.jpg","datePublished":"2018-09-04T06:55:29+00:00","dateModified":"2018-09-04T17:31:30+00:00","description":"Se voc\u00ea fez a prova do concurso PM MG, preencha seu gabarito no formul\u00e1rio e confira como foi seu desempenho com o Ranking PM MG para Soldado.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/31112523\/RANKING-PM-MG-e1535725531494.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/09\/31112523\/RANKING-PM-MG-e1535725531494.jpg","width":400,"height":209},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ranking-pm-mg-soldado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Ranking\u00a0PM MG para Soldado: quer saber seu resultado? Preencha seu gabarito e confira o ranking"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/138739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=138739"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/138739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/138741"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=138739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=138739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=138739"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=138739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}