{"id":1386869,"date":"2024-05-20T08:00:00","date_gmt":"2024-05-20T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1386869"},"modified":"2024-05-13T20:45:09","modified_gmt":"2024-05-13T23:45:09","slug":"resumo-meio-ambiente","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/","title":{"rendered":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2"},"content":{"rendered":"\n<p>No artigo de hoje vamos fazer um resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"402\" height=\"344\" data-id=\"923890\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/07082629\/image-132.png\" alt=\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2\" class=\"wp-image-923890\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/07082629\/image-132.png 402w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/12\/07082629\/image-132-300x257.png 300w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/><figcaption class=\"wp-element-caption\">Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-de-meio-ambiente-na-constituicao-federal-para-o-trf-2\">Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2<\/h2>\n\n\n\n<p>Como voc\u00ea j\u00e1 deve ter visto, foi publicado o novo edital de concurso p\u00fablico do Tribunal Regional Federal da 2\u00aa Regi\u00e3o.<\/p>\n\n\n\n<p>Assim, esse Tribunal abrange os estados do Rio de Janeiro e Esp\u00edrito Santo. O certame est\u00e1 oferecendo vagas para os cargos de\u00a0<strong>Analista e T\u00e9cnico Judici\u00e1rio<\/strong>. Tais cargos s\u00e3o de N\u00edvel Superior de escolaridade, com sal\u00e1rio inicial de at\u00e9\u00a0<strong>R$ R$ 13.994,78<\/strong>.<\/p>\n\n\n\n<p>Uma das mat\u00e9rias exigidas neste certame \u00e9 No\u00e7\u00f5es de Sustentabilidade, dentro dessa disciplina tem v\u00e1rios t\u00f3picos sobre o meio ambiente. Pensando nisso, hoje vamos tratar de um dos t\u00f3picos elencados no seu edital a respeito do meio ambiente na Constitui\u00e7\u00e3o Federal.<\/p>\n\n\n\n<p>Primeiramente, \u00e9 importante ter em mente que a Constitui\u00e7\u00e3o Federal de 1988 aborda o meio ambiente em diversos dispositivos. Assim, destaca-se a sua import\u00e2ncia e prote\u00e7\u00e3o como um direito fundamental. <\/p>\n\n\n\n<p>Assim, vamos trazer um resumo dos principais pontos relacionados ao meio ambiente na Constitui\u00e7\u00e3o Federal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-artigos-que-tratam-do-meio-ambiente-na-constituicao-federal\">Artigos que tratam do meio ambiente na Constitui\u00e7\u00e3o Federal<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-artigo-225-todos-tem-direito-ao-meio-ambiente-ecologicamente-equilibrado-bem-de-uso-comum-do-povo-e-essencial-a-sadia-qualidade-de-vida-impondo-se-ao-poder-publico-e-a-coletividade-o-dever-de-defende-lo-e-preserva-lo-para-as-presentes-e-futuras-geracoes\"><strong>Artigo 225<\/strong>: <em>&#8220;Todos t\u00eam direito ao meio ambiente ecologicamente equilibrado, bem de uso comum do povo e essencial \u00e0 sadia qualidade de vida, impondo-se ao Poder P\u00fablico e \u00e0 coletividade o dever de defend\u00ea-lo e preserv\u00e1- lo para as presentes e futuras gera\u00e7\u00f5es.&#8221;<\/em><\/h4>\n\n\n\n<p>Nesse sentido, a previs\u00e3o constitucional sobre o meio ambiente mais importante certamente \u00e9 a de que todos t\u00eam direito ao meio ambiente ecologicamente equilibrado. Portanto, o direito ao meio ambiente independe de cor, ra\u00e7a, credo, condi\u00e7\u00e3o social ou econ\u00f4mica ou quaisquer outros fatores.<\/p>\n\n\n\n<p>Ademais, n\u00e3o \u00e9 a qualquer ambiente que todos t\u00eam direito, mas sim ao meio ambiente ecologicamente equilibrado. Ou seja, aquele que mantenha os processos ecol\u00f3gicos de tal modo a possibilitar as rela\u00e7\u00f5es que mant\u00eam a qualidade ambiental e o bem-estar das popula\u00e7\u00f5es.<\/p>\n\n\n\n<p>Sendo assim, o artigo 225 \u00e9 o principal artigo que trata do meio ambiente na Constitui\u00e7\u00e3o Federal. Tal artigo estabelece que todos t\u00eam direito ao meio ambiente ecologicamente equilibrado, um bem de uso comum do povo e essencial \u00e0 sadia qualidade de vida. Assim,elenca imposi\u00e7\u00e3o ao Poder P\u00fablico e \u00e0 coletividade o dever de defend\u00ea-lo e preserv\u00e1-lo para as presentes e futuras gera\u00e7\u00f5es. <\/p>\n\n\n\n<p>Al\u00e9m disso, ele enumera princ\u00edpios importantes. Como o da preven\u00e7\u00e3o, do poluidor-pagador, da repara\u00e7\u00e3o de danos ambientais, e da coopera\u00e7\u00e3o entre os povos para a preserva\u00e7\u00e3o do meio ambiente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resumo-de-meio-ambiente-na-constituicao-federal-para-o-trf-2-0\">Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-artigo-170-vi-a-defesa-do-meio-ambiente-inclusive-mediante-tratamento-diferenciado-conforme-o-impacto-ambiental-dos-produtos-e-servicos-e-de-seus-processos-de-elaboracao-e-prestacao\"><strong>Artigo 170, VI<\/strong>: <em>&#8220;a defesa do meio ambiente, inclusive mediante tratamento diferenciado conforme o impacto ambiental dos produtos e servi\u00e7os e de seus processos de elabora\u00e7\u00e3o e presta\u00e7\u00e3o.&#8221;<\/em><\/h4>\n\n\n\n<p>Este artigo, que trata dos princ\u00edpios gerais da atividade econ\u00f4mica, inclui a defesa do meio ambiente como um dos princ\u00edpios que devem orientar a ordem econ\u00f4mica.<\/p>\n\n\n\n<p>Quanto aos princ\u00edpios gerais da atividade econ\u00f4mica, a Constitui\u00e7\u00e3o Federal determina que a ordem econ\u00f4mica, fundada na valoriza\u00e7\u00e3o do trabalho humano e na livre iniciativa, tem por fim assegurar a todos exist\u00eancia digna, de acordo com os ditames da justi\u00e7a social.<\/p>\n\n\n\n<p>Assim, deve-se observar, entre outros, o princ\u00edpio de defesa do meio ambiente. Inclusive mediante tratamento diferenciado segundo o impacto ambiental dos produtos e servi\u00e7os e de seus processos de elabora\u00e7\u00e3o e presta\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-artigo-186-ii-a-funcao-social-e-cumprida-quando-a-propriedade-rural-atende-simultaneamente-segundo-criterios-e-graus-de-exigencia-estabelecidos-em-lei-aos-seguintes-requisitos-i-utilizacao-adequada-dos-recursos-naturais-disponiveis-e-preservacao-do-meio-ambiente\"><strong>Artigo 186, II<\/strong>: <em>&#8220;A fun\u00e7\u00e3o social \u00e9 cumprida quando a propriedade rural atende, simultaneamente, segundo crit\u00e9rios e graus de exig\u00eancia estabelecidos em lei, aos seguintes requisitos: I &#8211; utiliza\u00e7\u00e3o adequada dos recursos naturais dispon\u00edveis e preserva\u00e7\u00e3o do meio ambiente.&#8221;<\/em><\/h4>\n\n\n\n<p>O artigo 186, II, menciona a fun\u00e7\u00e3o social da propriedade, incluindo a preserva\u00e7\u00e3o do meio ambiente como um de seus objetivos.<\/p>\n\n\n\n<p>Verifique que um dos requisitos para que uma propriedade rural tenha sua fun\u00e7\u00e3o social cumprida \u00e9 o de que haja a utiliza\u00e7\u00e3o adequada dos recursos naturais dispon\u00edveis e o meio ambiente seja preservado<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-artigo-225-3\u00ba-as-condutas-e-atividades-consideradas-lesivas-ao-meio-ambiente-sujeitarao-os-infratores-pessoas-fisicas-ou-juridicas-a-sancoes-penais-e-administrativas-independentemente-da-obrigacao-de-reparar-os-danos-causados\"><strong>Artigo 225, \u00a7 3\u00ba<\/strong>: <em>&#8220;As condutas e atividades consideradas lesivas ao meio ambiente sujeitar\u00e3o os infratores, pessoas f\u00edsicas ou jur\u00eddicas, a san\u00e7\u00f5es penais e administrativas, independentemente da obriga\u00e7\u00e3o de reparar os danos causados.&#8221;<\/em><\/h4>\n\n\n\n<p>Este par\u00e1grafo define que as condutas e atividades consideradas lesivas ao meio ambiente sujeitar\u00e3o os infratores, pessoas f\u00edsicas ou jur\u00eddicas, a san\u00e7\u00f5es penais e administrativas, <strong>independentemente da obriga\u00e7\u00e3o de reparar os danos causados.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-artigo-23-vi-trata-da-competencia-comum-da-uniao-dos-estados-do-distrito-federal-e-dos-municipios-vi-proteger-o-meio-ambiente-e-combater-a-poluicao-em-qualquer-de-suas-formas\"><strong>Artigo 23, VI<\/strong>: trata da compet\u00eancia comum da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios: VI &#8211; proteger o meio ambiente e combater a polui\u00e7\u00e3o em qualquer de suas formas.<\/h4>\n\n\n\n<p>O artigo 23, determina a compet\u00eancia comum da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios para proteger o meio ambiente. Al\u00e9m de combater a polui\u00e7\u00e3o em qualquer de suas formas.<\/p>\n\n\n\n<p><strong>Artigo 225, \u00a7 4\u00ba<\/strong>: Este par\u00e1grafo estabelece que a Floresta Amaz\u00f4nica brasileira, a Mata Atl\u00e2ntica, a Serra do Mar, o Pantanal Mato-Grossense e a Zona Costeira s\u00e3o patrim\u00f4nio nacional. A sua utiliza\u00e7\u00e3o far-se-\u00e1, na forma da lei, dentro de condi\u00e7\u00f5es que assegurem a preserva\u00e7\u00e3o do meio ambiente, inclusive quanto ao uso dos recursos naturais.<\/p>\n\n\n\n<p><strong>Artigo 225, \u00a7 5\u00ba<\/strong>: Este par\u00e1grafo institui que s\u00e3o indispon\u00edveis as terras devolutas ou arrecadadas pelos Estados, por a\u00e7\u00f5es discriminat\u00f3rias, necess\u00e1rias \u00e0 prote\u00e7\u00e3o dos ecossistemas naturais.<\/p>\n\n\n\n<p>Isto posto, esses s\u00e3o os principais pontos relacionados ao meio ambiente na Constitui\u00e7\u00e3o Federal, que estabelecem a base legal para a prote\u00e7\u00e3o e preserva\u00e7\u00e3o ambiental no Brasil.<\/p>\n\n\n\n<p>Espero que voc\u00ea tenha gostado do nosso artigo de hoje sobre o Resumo do meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2!<\/p>\n\n\n\n<p>Bom Estudo!<\/p>\n\n\n\n<p>Elizabeth Menezes <\/p>\n\n\n\n<p>@prof.elizabethmenezes<\/p>\n\n\n\n<p><a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm\">https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm<\/a><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_nl8pD1wvew0\"><div id=\"lyte_nl8pD1wvew0\" data-src=\"\/\/i.ytimg.com\/vi\/nl8pD1wvew0\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/nl8pD1wvew0\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/nl8pD1wvew0\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><a href=\"https:\/\/www.youtube.com\/watch?v=nl8pD1wvew0\">https:\/\/www.youtube.com\/watch?v=nl8pD1wvew0<\/a><\/figcaption><\/figure>\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-cyan-bluish-gray-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-cyan-bluish-gray-background-color has-text-color has-background\"><strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\">Concursos 2024<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No artigo de hoje vamos fazer um resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2. Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2 Como voc\u00ea j\u00e1 deve ter visto, foi publicado o novo edital de concurso p\u00fablico do Tribunal Regional Federal da 2\u00aa Regi\u00e3o. Assim, esse Tribunal abrange os [&hellip;]<\/p>\n","protected":false},"author":2277,"featured_media":1329166,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1984],"tags":[],"tax_estado":[219963,219982],"class_list":["post-1386869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais","tax_estado-concursos-federais","tax_estado-rj"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2<\/title>\n<meta name=\"description\" content=\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2. Fique por dentro de tudo sobre o meio ambiente na Constitui\u00e7\u00e3o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2\" \/>\n<meta property=\"og:description\" content=\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2. Fique por dentro de tudo sobre o meio ambiente na Constitui\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-20T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elizabeth Menezes de Pinho Alves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elizabeth Menezes de Pinho Alves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/\"},\"author\":{\"name\":\"Elizabeth Menezes de Pinho Alves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562\"},\"headline\":\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2\",\"datePublished\":\"2024-05-20T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/\"},\"wordCount\":1064,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg\",\"articleSection\":[\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/\",\"name\":\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg\",\"datePublished\":\"2024-05-20T11:00:00+00:00\",\"description\":\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2. Fique por dentro de tudo sobre o meio ambiente na Constitui\u00e7\u00e3o\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg\",\"width\":768,\"height\":432,\"caption\":\"Resumo de Estrutura Organizacional para o TRF 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562\",\"name\":\"Elizabeth Menezes de Pinho Alves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g\",\"caption\":\"Elizabeth Menezes de Pinho Alves\"},\"description\":\"Bacharel em Administra\u00e7\u00e3o pela UFPE, bacharelanda em Direito, p\u00f3s-graduada em Direito Administrativo e Constitucional. Come\u00e7ou em 2014 os estudos para concursos apenas para a \u00e1rea fiscal, por influ\u00eancia de amigos e familiares que trabalhavam na \u00e1rea. Ent\u00e3o, em 2017, com a abertura do concurso do Tribunal de Contas de Pernambuco, decidiu mudar o foco e aproveitar as oportunidades da \u00e1rea de controle, o que se mostrou uma excelente e acertada decis\u00e3o. Atualmente exerce o cargo de Auditor de Controle Externo no Tribunal de Contas do Estado de S\u00e3o Paulo, tendo tamb\u00e9m sido aprovada em: 5\u00b0 lugar para Auditor Fiscal de Garanhus - PE (2015), Auditor Fiscal de Goi\u00e2nia - GO (2016), Auditor Fiscal do Maranh\u00e3o (2016), Analista de Gest\u00e3o do TCE-PE (2017) e Auditor de Contas P\u00fablicas do TCE-PB (2018). Al\u00e9m disso, foi aprovada e nomeada em concursos de Auditor Fiscal Estadual, Municipal e da \u00e1rea de Controle.\",\"sameAs\":[\"https:\/\/www.instagram.com\/prof.elizabethmenezes\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/elizabethpinhoagmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2","description":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2. Fique por dentro de tudo sobre o meio ambiente na Constitui\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2","og_description":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2. Fique por dentro de tudo sobre o meio ambiente na Constitui\u00e7\u00e3o","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-05-20T11:00:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg","type":"image\/jpeg"}],"author":"Elizabeth Menezes de Pinho Alves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Elizabeth Menezes de Pinho Alves","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/"},"author":{"name":"Elizabeth Menezes de Pinho Alves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562"},"headline":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2","datePublished":"2024-05-20T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/"},"wordCount":1064,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg","articleSection":["Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/","name":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg","datePublished":"2024-05-20T11:00:00+00:00","description":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2. Fique por dentro de tudo sobre o meio ambiente na Constitui\u00e7\u00e3o","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/03175513\/trf-2.jpg","width":768,"height":432,"caption":"Resumo de Estrutura Organizacional para o TRF 2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-meio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo de meio ambiente na Constitui\u00e7\u00e3o Federal para o TRF 2"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bfec43f50192a82d88e5972aa7203562","name":"Elizabeth Menezes de Pinho Alves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adc11245f4ec3f9c772db5be88c959024af08ce0c083769a192acdb27e72cf92?s=96&d=mm&r=g","caption":"Elizabeth Menezes de Pinho Alves"},"description":"Bacharel em Administra\u00e7\u00e3o pela UFPE, bacharelanda em Direito, p\u00f3s-graduada em Direito Administrativo e Constitucional. Come\u00e7ou em 2014 os estudos para concursos apenas para a \u00e1rea fiscal, por influ\u00eancia de amigos e familiares que trabalhavam na \u00e1rea. Ent\u00e3o, em 2017, com a abertura do concurso do Tribunal de Contas de Pernambuco, decidiu mudar o foco e aproveitar as oportunidades da \u00e1rea de controle, o que se mostrou uma excelente e acertada decis\u00e3o. Atualmente exerce o cargo de Auditor de Controle Externo no Tribunal de Contas do Estado de S\u00e3o Paulo, tendo tamb\u00e9m sido aprovada em: 5\u00b0 lugar para Auditor Fiscal de Garanhus - PE (2015), Auditor Fiscal de Goi\u00e2nia - GO (2016), Auditor Fiscal do Maranh\u00e3o (2016), Analista de Gest\u00e3o do TCE-PE (2017) e Auditor de Contas P\u00fablicas do TCE-PB (2018). Al\u00e9m disso, foi aprovada e nomeada em concursos de Auditor Fiscal Estadual, Municipal e da \u00e1rea de Controle.","sameAs":["https:\/\/www.instagram.com\/prof.elizabethmenezes\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/elizabethpinhoagmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1386869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2277"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1386869"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1386869\/revisions"}],"predecessor-version":[{"id":1386907,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1386869\/revisions\/1386907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1329166"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1386869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1386869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1386869"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1386869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}