{"id":1380913,"date":"2024-05-15T14:00:00","date_gmt":"2024-05-15T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1380913"},"modified":"2024-05-13T20:33:48","modified_gmt":"2024-05-13T23:33:48","slug":"nocoes-gerais-padroes-projeto-caixa-ti","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/","title":{"rendered":"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)"},"content":{"rendered":"\n<p>Neste artigo veremos no\u00e7\u00f5es gerais de padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de Tecnologia da Informa\u00e7\u00e3o.<\/p>\n\n\n\n<p>A banca <a href=\"https:\/\/caixa.cesgranrio.org.br\/editais\">Cesgranrio<\/a> n\u00e3o costuma complicar muito neste assunto, pois na maioria das quest\u00f5es cobra apenas no\u00e7\u00f5es gerais de padr\u00f5es de projeto, sendo necess\u00e1rio conhecer os padr\u00f5es e suas defini\u00e7\u00f5es.<\/p>\n\n\n\n<p>Este artigo possui a seguinte estrutura:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O que s\u00e3o padr\u00f5es de projetos?<\/li>\n\n\n\n<li>Classifica\u00e7\u00e3o dos Padr\u00f5es de Projetos.<\/li>\n\n\n\n<li>Mapa Mental<\/li>\n\n\n\n<li>Conclus\u00e3o<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-sao-padroes-de-projeto\"><strong>O que s\u00e3o padr\u00f5es de projeto?<\/strong><\/h2>\n\n\n\n<p>Na engenharia de software, os padr\u00f5es de projeto desempenham um papel crucial na concep\u00e7\u00e3o e desenvolvimento de sistemas de software robustos e flex\u00edveis. Eles s\u00e3o solu\u00e7\u00f5es comprovadas para problemas recorrentes que os desenvolvedores enfrentam durante o processo de desenvolvimento.<\/p>\n\n\n\n<p>&nbsp;Os padr\u00f5es de projeto n\u00e3o apenas fornecem uma estrutura para resolver problemas comuns, mas tamb\u00e9m promovem boas pr\u00e1ticas de design e arquitetura de software. Ao compreender e aplicar esses padr\u00f5es de projeto, os desenvolvedores podem escrever software mais limpo, mais eficiente e mais f\u00e1cil de manter.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-classificacao-dos-padroes-de-projeto\"><strong>Classifica\u00e7\u00e3o dos Padr\u00f5es de Projeto<\/strong><\/h2>\n\n\n\n<p>Esses padr\u00f5es s\u00e3o amplamente categorizados em tr\u00eas grupos principais: padr\u00f5es criacionais, padr\u00f5es estruturais e padr\u00f5es comportamentais.<\/p>\n\n\n\n<p>A seguir, veremos sobre cada uma dessas categorias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-padroes-criacionais\"><strong>Padr\u00f5es Criacionais<\/strong><\/h3>\n\n\n\n<p>Os padr\u00f5es criacionais s\u00e3o focados no processo de cria\u00e7\u00e3o de objetos. Eles fornecem mecanismos para a cria\u00e7\u00e3o de objetos de forma flex\u00edvel e eficiente, garantindo que o sistema permane\u00e7a desacoplado das classes concretas que cria. Al\u00e9m disso, esses padr\u00f5es promovem a reutiliza\u00e7\u00e3o de c\u00f3digo e facilitam a manuten\u00e7\u00e3o do sistema. Alguns dos padr\u00f5es criacionais mais comuns incluem:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Singleton<\/strong>: Garante que uma classe tenha apenas uma inst\u00e2ncia e fornece um ponto global de acesso a essa inst\u00e2ncia.<\/li>\n\n\n\n<li><strong>Factory Method<\/strong>: Define uma interface para criar objetos em uma superclasse, permitindo que as subclasses alterem o tipo de objetos que ser\u00e3o criados.<\/li>\n\n\n\n<li><strong>Abstract Factory<\/strong>: Fornece uma interface para criar fam\u00edlias de objetos relacionados ou dependentes sem especificar suas classes concretas.<\/li>\n\n\n\n<li><strong>Builder<\/strong>: Separa a constru\u00e7\u00e3o de um objeto complexo de sua representa\u00e7\u00e3o, permitindo que o mesmo processo de constru\u00e7\u00e3o crie diferentes representa\u00e7\u00f5es.<\/li>\n\n\n\n<li><strong>Prototype<\/strong>: Permite a cria\u00e7\u00e3o de novos objetos duplicando um objeto existente, evitando a cria\u00e7\u00e3o de objetos complexos do zero.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-padroes-estruturais\"><strong>Padr\u00f5es Estruturais<\/strong><\/h3>\n\n\n\n<p>Os padr\u00f5es estruturais est\u00e3o preocupados com a composi\u00e7\u00e3o de classes e objetos para formar estruturas maiores. Eles ajudam a garantir que as classes e objetos sejam organizados de maneira eficiente e flex\u00edvel, promovendo a reutiliza\u00e7\u00e3o e facilitando a manuten\u00e7\u00e3o do c\u00f3digo. Alguns dos padr\u00f5es estruturais mais amplamente utilizados s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Adapter<\/strong>: Permite que interfaces incompat\u00edveis trabalhem juntas ao converter a interface de uma classe em outra interface que o cliente espera.<\/li>\n\n\n\n<li><strong>Bridge<\/strong>: Separa uma abstra\u00e7\u00e3o de sua implementa\u00e7\u00e3o, permitindo que ambas variem independentemente.<\/li>\n\n\n\n<li><strong>Composite<\/strong>: Permite que objetos individuais e composi\u00e7\u00f5es de objetos sejam tratados de maneira uniforme, formando uma estrutura em \u00e1rvore.<\/li>\n\n\n\n<li><strong>Decorator<\/strong>: Permite adicionar comportamentos adicionais a objetos dinamicamente, envolvendo-os em objetos decoradores.<\/li>\n\n\n\n<li><strong>Facade<\/strong>: Fornece uma interface unificada para um conjunto de interfaces em um subsistema, simplificando sua utiliza\u00e7\u00e3o.<\/li>\n\n\n\n<li><strong>Flyweight<\/strong>: Minimiza o uso de mem\u00f3ria ou custos computacionais compartilhando o m\u00e1ximo poss\u00edvel com objetos similares.<\/li>\n\n\n\n<li><strong>Proxy<\/strong>: Fornece um substituto ou representante para outro objeto, controlando o acesso a ele.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-padroes-comportamentais\"><strong>Padr\u00f5es Comportamentais<\/strong><\/h3>\n\n\n\n<p>Os padr\u00f5es comportamentais se concentram na intera\u00e7\u00e3o entre objetos e na responsabilidade deles no sistema. Eles definem como os objetos se comunicam entre si e como distribuem as tarefas, promovendo a flexibilidade e o desacoplamento do sistema.&nbsp;<\/p>\n\n\n\n<p>Alguns dos padr\u00f5es comportamentais mais amplamente utilizados incluem:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Observer<\/strong>: Define uma depend\u00eancia um para muitos entre objetos, de modo que quando um objeto muda de estado, todos os seus dependentes s\u00e3o notificados e atualizados automaticamente.<\/li>\n\n\n\n<li><strong>Strategy<\/strong>: Permite definir uma fam\u00edlia de algoritmos, encapsul\u00e1-los e torn\u00e1-los intercambi\u00e1veis, permitindo que o algoritmo varie independentemente dos clientes que o utilizam.<\/li>\n\n\n\n<li><strong>Command<\/strong>: Encapsula uma solicita\u00e7\u00e3o como um objeto, permitindo parametrizar clientes com opera\u00e7\u00f5es, enfileirar solicita\u00e7\u00f5es, registrar solicita\u00e7\u00f5es e suportar opera\u00e7\u00f5es de desfazer.<\/li>\n\n\n\n<li><strong>Chain of Responsibility<\/strong>: Permite passar solicita\u00e7\u00f5es ao longo de uma cadeia de manipuladores, evitando acoplamento entre o remetente de uma solicita\u00e7\u00e3o e seu receptor.<\/li>\n\n\n\n<li><strong>Interpreter<\/strong>: Define uma gram\u00e1tica para uma linguagem e fornece um interpretador para interpretar senten\u00e7as nessa linguagem.<\/li>\n\n\n\n<li><strong>Iterator<\/strong>: Fornecer uma maneira de acessar sequencialmente os elementos de um objeto agregado sem expor sua representa\u00e7\u00e3o subjacente.<\/li>\n\n\n\n<li><strong>Mediator<\/strong>: Define um objeto que encapsula como os objetos interagem, promovendo um acoplamento fraco entre eles.<\/li>\n\n\n\n<li><strong>Memento<\/strong>: Permite capturar e restaurar o estado interno de um objeto sem violar o encapsulamento.<\/li>\n\n\n\n<li><strong>State<\/strong>: Permite que um objeto altere seu comportamento quando seu estado interno muda. O objeto parecer\u00e1 ter mudado de classe.<\/li>\n\n\n\n<li><strong>Template Method<\/strong>: Define o esqueleto de um algoritmo em uma opera\u00e7\u00e3o, deixando alguns passos a serem preenchidos por subclasses.<\/li>\n\n\n\n<li><strong>Visitor<\/strong>: Representa uma opera\u00e7\u00e3o a ser executada nos elementos de uma estrutura de objeto. Permite definir uma nova opera\u00e7\u00e3o sem mudar as classes dos elementos sobre as quais opera.<\/li>\n<\/ul>\n\n\n\n<p>Essas categorias de padr\u00f5es de projeto oferecem uma abordagem sistem\u00e1tica para resolver problemas de design de software, promovendo a reutiliza\u00e7\u00e3o, a flexibilidade e a manutenibilidade do c\u00f3digo.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mapa-mental\"><strong>Mapa Mental<\/strong><\/h2>\n\n\n\n<p>Aqui est\u00e1 um mapa mental dos padr\u00f5es de projetos apresentados aqui:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/yMzz6Mc83n58VhacVcjLuyTFaTVTMNDuJP5RgEXv7LHPJCHo49MiI5dAfpLDlSwTegQRx50sIWbFcPpeznBihPAp6_S2Xmz-Ax5dbbNJ5awYCBPldTV9ViuN34CAdAQImtdNn_T2NG1z-7WGLwAHcUg\" alt=\"Mapa mental dos padr\u00f5es de projeto\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao\"><strong>Conclus\u00e3o<\/strong><\/h2>\n\n\n\n<p>Em s\u00edntese, os padr\u00f5es de projeto s\u00e3o ferramentas fundamentais para os desenvolvedores de software, oferecendo solu\u00e7\u00f5es comprovadas para desafios recorrentes de design e arquitetura. Ao aplic\u00e1-los de forma adequada, \u00e9 poss\u00edvel melhorar significativamente a qualidade, efici\u00eancia e manutenibilidade do software desenvolvido, contribuindo para o sucesso dos projetos de desenvolvimento de software. <\/p>\n\n\n\n<p>Neste artigo apresentamos apenas no\u00e7\u00f5es gerais dos padr\u00f5es de projetos, pois normalmente as quest\u00f5es cobram isso, por isso n\u00e3o aprofundamos nas implementa\u00e7\u00f5es desses padr\u00f5es.<\/p>\n\n\n\n<p>Espero que o conte\u00fado apresentado neste artigo seja de grande utilidade para sua jornada rumo \u00e0 aprova\u00e7\u00e3o. Bons estudos.<\/p>\n\n\n\n<p class=\"has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste artigo veremos no\u00e7\u00f5es gerais de padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de Tecnologia da Informa\u00e7\u00e3o. A banca Cesgranrio n\u00e3o costuma complicar muito neste assunto, pois na maioria das quest\u00f5es cobra apenas no\u00e7\u00f5es gerais de padr\u00f5es de projeto, sendo necess\u00e1rio conhecer os [&hellip;]<\/p>\n","protected":false},"author":2565,"featured_media":1380919,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[2313,1,220184],"tags":[119953,396,25],"tax_estado":[219963],"class_list":["post-1380913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreiras-bancarias","category-cursos-e-concursos","category-engenharias-e-ti","tag-informaticaparaconcursos-2","tag-cef","tag-tecnologia-da-informacao","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)<\/title>\n<meta name=\"description\" content=\"Neste artigo estudaremos sobre os padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de TI.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)\" \/>\n<meta property=\"og:description\" content=\"Neste artigo estudaremos sobre os padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de TI.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-15T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1090\" \/>\n\t<meta property=\"og:image:height\" content=\"878\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Antoniel da Silva Rego\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antoniel da Silva Rego\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/\"},\"author\":{\"name\":\"Antoniel da Silva Rego\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/65e75c615593894f0136e777b57e5d46\"},\"headline\":\"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)\",\"datePublished\":\"2024-05-15T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/\"},\"wordCount\":1076,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png\",\"keywords\":[\"#inform\u00e1ticaparaconcursos\",\"CEF\",\"Tecnologia da Informa\u00e7\u00e3o\"],\"articleSection\":[\"Banc\u00e1ria (BB, CEF e Bancos Estaduais)\",\"Concursos P\u00fablicos\",\"Engenharias e TI\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/\",\"name\":\"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png\",\"datePublished\":\"2024-05-15T17:00:00+00:00\",\"description\":\"Neste artigo estudaremos sobre os padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de TI.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png\",\"width\":1090,\"height\":878,\"caption\":\"Padr\u00f5es de projeto mapa mental\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/65e75c615593894f0136e777b57e5d46\",\"name\":\"Antoniel da Silva Rego\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b8f680af1fe7f097d3f42a127f2b204823c881cf0f4a904ff915b5991017d762?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8f680af1fe7f097d3f42a127f2b204823c881cf0f4a904ff915b5991017d762?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8f680af1fe7f097d3f42a127f2b204823c881cf0f4a904ff915b5991017d762?s=96&d=mm&r=g\",\"caption\":\"Antoniel da Silva Rego\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/tonnyelgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)","description":"Neste artigo estudaremos sobre os padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de TI.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/","og_locale":"pt_BR","og_type":"article","og_title":"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)","og_description":"Neste artigo estudaremos sobre os padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de TI.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-05-15T17:00:00+00:00","og_image":[{"width":1090,"height":878,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png","type":"image\/png"}],"author":"Antoniel da Silva Rego","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Antoniel da Silva Rego","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/"},"author":{"name":"Antoniel da Silva Rego","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/65e75c615593894f0136e777b57e5d46"},"headline":"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)","datePublished":"2024-05-15T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/"},"wordCount":1076,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png","keywords":["#inform\u00e1ticaparaconcursos","CEF","Tecnologia da Informa\u00e7\u00e3o"],"articleSection":["Banc\u00e1ria (BB, CEF e Bancos Estaduais)","Concursos P\u00fablicos","Engenharias e TI"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/","name":"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png","datePublished":"2024-05-15T17:00:00+00:00","description":"Neste artigo estudaremos sobre os padr\u00f5es de projeto, que \u00e9 um dos assuntos que constam no edital do concurso da Caixa, para o cargo de TI.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08234750\/imagem-padroes-de-projeto.png","width":1090,"height":878,"caption":"Padr\u00f5es de projeto mapa mental"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/nocoes-gerais-padroes-projeto-caixa-ti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"No\u00e7\u00f5es Gerais de Padr\u00f5es de Projeto para CEF (TI)"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/65e75c615593894f0136e777b57e5d46","name":"Antoniel da Silva Rego","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b8f680af1fe7f097d3f42a127f2b204823c881cf0f4a904ff915b5991017d762?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b8f680af1fe7f097d3f42a127f2b204823c881cf0f4a904ff915b5991017d762?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8f680af1fe7f097d3f42a127f2b204823c881cf0f4a904ff915b5991017d762?s=96&d=mm&r=g","caption":"Antoniel da Silva Rego"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/tonnyelgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1380913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2565"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1380913"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1380913\/revisions"}],"predecessor-version":[{"id":1380927,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1380913\/revisions\/1380927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1380919"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1380913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1380913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1380913"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1380913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}