{"id":1380766,"date":"2024-06-05T20:28:38","date_gmt":"2024-06-05T23:28:38","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1380766"},"modified":"2026-03-20T16:59:18","modified_gmt":"2026-03-20T19:59:18","slug":"concurso-detran-ac-edital-publicado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/","title":{"rendered":"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-salarios-iniciais-podem-alcancar-r-9-5-mil\"><em>Sal\u00e1rios iniciais podem alcan\u00e7ar R$ <\/em>9<em>,5 mil!<\/em><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e3o encerradas as inscri\u00e7\u00f5es para o <strong>edital Detran AC (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/departamento-de-transito-do-acre-detran-ac\/\" target=\"_blank\" rel=\"noreferrer noopener\">Departamento Estadual de Tr\u00e2nsito do Acre<\/a>). <\/strong>De acordo com o documento, s\u00e3o ofertadas<strong> 91 vagas de n\u00edvel superior.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sob organiza\u00e7\u00e3o do <a href=\"https:\/\/www.institutoaocp.org.br\/concursos\/607\" target=\"_blank\" rel=\"noreferrer noopener\">Instituto AOCP<\/a>, as inscri\u00e7\u00f5es puderam ser efetuadas at\u00e9 05 de junho, ao custo de R$ 80,00. As provas ser\u00e3o aplicadas em <strong>28 de julho<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As oportunidades s\u00e3o distribu\u00eddas nas carreiras de <strong>Agente de Autoridade de Tr\u00e2nsito, Analista de Sistema e de Tr\u00e2nsito, Assistente de Tr\u00e2nsito, Contador, Engenheiro Civil, Examinador de Tr\u00e2nsito e Pedagogo.<\/strong><\/p>\n\n\n\n<ul class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-list\">\n<li><strong>Detran AC<\/strong><\/li>\n\n\n\n<li><strong>Banca<\/strong>: Instituto AOCP<\/li>\n\n\n\n<li><strong>Vagas: <\/strong>91<\/li>\n\n\n\n<li><strong>Sal\u00e1rios:<\/strong> R$ 7.015,71 a R$ 9.561,76<\/li>\n\n\n\n<li><strong>Edital<\/strong>: <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08215213\/fff66a3a-8b36-4207-91c9-15e5403a1d1b.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Detran AC-2024<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-detran\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\">Concurso Detran AC<\/h2>\n        <p class=\"subtitulo-assinatura\">Cursos preparat\u00f3rios para a carreira! \u270f\ufe0f<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/departamento-de-transito-do-acre-detran-ac\/\" role=\"button\" rel=\"noopener noreferrer\">INSCREVA-SE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"situacao\">Principais datas do edital Detran AC<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inscri\u00e7\u00f5es<\/strong>: <s>23\/05 a 05\/06<\/s><\/li>\n\n\n\n<li><strong>Isen\u00e7\u00e3o da taxa<\/strong>: <s>23 a 26\/04<\/s><\/li>\n\n\n\n<li><strong>Pagamento do boleto<\/strong>: at\u00e9 05\/06<\/li>\n\n\n\n<li><strong>Prova<\/strong>: 28\/07<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cargos\">Cargos e vagas<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">CARGOS<\/th><th class=\"has-text-align-center\" data-align=\"center\">VAGAS<\/th><th class=\"has-text-align-center\" data-align=\"center\">SAL\u00c1RIOS<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Analista de Sistema<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 7.015,71<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Analista de Tr\u00e2nsito<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 7.015,71<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Assistente de Tr\u00e2nsito<\/td><td class=\"has-text-align-center\" data-align=\"center\">63<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 7.015,71<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Pedagogo<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 7.015,71<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Examinador de Tr\u00e2nsito<\/td><td class=\"has-text-align-center\" data-align=\"center\">9<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 7.528,06<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Agente de Autoridade de Tr\u00e2nsito<\/td><td class=\"has-text-align-center\" data-align=\"center\">12<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 7.695,71<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Contador<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 7.865,13<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Engenheiro Civil<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">R$ 9.561,76<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Quadro de cargos, vagas e sal\u00e1rios de n\u00edvel superior.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"846\" height=\"465\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08202536\/image-148-1.png\" alt=\"distribui\u00e7\u00e3o das vagas do concurso detran ac\" class=\"wp-image-1380800\" style=\"width:776px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08202536\/image-148-1.png 846w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08202536\/image-148-1-300x165.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08202536\/image-148-1-768x422.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08202536\/image-148-1-610x335.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08202536\/image-148-1-150x82.png 150w\" sizes=\"auto, (max-width: 846px) 100vw, 846px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Os aprovados contar\u00e3o com os seguintes benef\u00edcios: Adicional de Insalubridade no valor de R$ 512,35, Gratifica\u00e7\u00e3o de Atividade de Tr\u00e2nsito no valor de R$ 1.200,00, Aux\u00edlio Sa\u00fade no valor de R$ 900,00 e Aux\u00edlio Alimenta\u00e7\u00e3o no valor de R$ 1.500,00, que totalizam o vencimento final.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-etapas-e-provas-do-edital-detran-ac\">Etapas e provas do edital Detran AC<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os candidatos do concurso Detran AC ser\u00e3o avaliados mediante aplica\u00e7\u00e3o das seguintes etapas abaixo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prova Objetiva, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li>Prova de T\u00edtulos, de car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li>Prova de Aptid\u00e3o F\u00edsica, de car\u00e1ter eliminat\u00f3rio (apenas para Agente de Autoridade de Tr\u00e2nsito).<\/li>\n\n\n\n<li>Exame Psicot\u00e9cnico, de car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li>Exame M\u00e9dico e Toxicol\u00f3gico, de car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li>Investiga\u00e7\u00e3o Criminal e Social, de car\u00e1ter eliminat\u00f3rio; e<\/li>\n\n\n\n<li>Curso de Forma\u00e7\u00e3o, dede car\u00e1ter eliminat\u00f3rio (apenas para Agente de Autoridade de Tr\u00e2nsito e Examinador de Tr\u00e2nsito).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prova-objetiva\">Prova Objetiva<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A prova objetiva do edital Detran AC ser\u00e1 composta de 60 quest\u00f5es de m\u00faltipla escolha, sendo 5 alternativas e apenas uma considerada a correta, assim distribu\u00eddas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa &#8211; 10<\/li>\n\n\n\n<li>Racioc\u00ednio L\u00f3gico e Matem\u00e1tico &#8211; 5<\/li>\n\n\n\n<li>Inform\u00e1tica &#8211; 5<\/li>\n\n\n\n<li>Realidade \u00c9tnica, Social, Geogr\u00e1fica, Cultural, Pol\u00edtica e Econ\u00f4mica do Acre &#8211; 5<\/li>\n\n\n\n<li>Direito Constitucional e Administrativo &#8211; 10<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos &#8211; 25<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O candidato para ser aprovado na Prova Objetiva dever\u00e1, al\u00e9m de n\u00e3o ser eliminado por outros crit\u00e9rios estabelecidos no edital Detran AC:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>a) obter no m\u00ednimo 50% (cinquenta por cento) do total de pontos previstos na Prova Objetiva para n\u00e3o ser eliminado do concurso p\u00fablico;<\/li>\n\n\n\n<li>b) obter no m\u00ednimo 50% (cinquenta por cento) do total de pontos previstos no somat\u00f3rio de quest\u00f5es de conhecimentos gerais;<\/li>\n\n\n\n<li>c) obter no m\u00ednimo 50% (cinquenta por cento) do total de pontos previstos no somat\u00f3rio de quest\u00f5es de conhecimentos espec\u00edficos; e<\/li>\n\n\n\n<li>d) n\u00e3o obter nota 0 (zero) em qualquer uma das \u00e1reas de conhecimento.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prova-de-titulos\">Prova de T\u00edtulos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A prova de t\u00edtulo do certame contar\u00e1 coma  seguinte pontua\u00e7\u00e3o:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"962\" height=\"266\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204437\/image-149.png\" alt=\"\" class=\"wp-image-1380807\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204437\/image-149.png 962w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204437\/image-149-300x83.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204437\/image-149-768x212.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204437\/image-149-610x169.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204437\/image-149-150x41.png 150w\" sizes=\"auto, (max-width: 962px) 100vw, 962px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prova-de-aptidao-fisica\">Prova de Aptid\u00e3o F\u00edsica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A Prova de Aptid\u00e3o F\u00edsica do edital Detran AC ser\u00e1 realizada apenas para o cargo de Agente de Autoridade de Tr\u00e2nsito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A etapa ser\u00e1 realizada e avaliada de acordo com o descrito na tabela abaixo, na seguinte ordem: Teste de Barra Fixa; Abdominal Remador; Flex\u00e3o de Bra\u00e7o no Solo; e Corrida.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"962\" height=\"145\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204734\/image-150.png\" alt=\"prova de aptid\u00e3o f\u00edsica do concurso detran ac\" class=\"wp-image-1380808\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204734\/image-150.png 962w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204734\/image-150-300x45.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204734\/image-150-768x116.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204734\/image-150-610x92.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08204734\/image-150-150x23.png 150w\" sizes=\"auto, (max-width: 962px) 100vw, 962px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-curso-de-formacao\">Curso de Forma\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O Curso de Forma\u00e7\u00e3o, para os cargos de Agente de Autoridade de Tr\u00e2nsito e Examinador de Tr\u00e2nsito, ser\u00e1 realizado em Rio Branco, Estado do Acre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A etapa do edital Detran AC ter\u00e1 a dura\u00e7\u00e3o de 200 horas\/aula (para Agente) e de 208 horas\/aula (para Examinador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao final de cada disciplina ser\u00e1 realizada uma avalia\u00e7\u00e3o composta por 10 (dez) quest\u00f5es, com peso 1 (um) ponto cada. Ser\u00e1 reprovado no curso de forma\u00e7\u00e3o e eliminado do concurso o candidato que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>a) obtiver nota inferior a 7 (sete) pontos em qualquer uma das avalia\u00e7\u00f5es das disciplinas do curso;<\/li>\n\n\n\n<li>b) obtiver nota inferior a 7 (sete) pontos na nota final do curso de forma\u00e7\u00e3o;<\/li>\n\n\n\n<li>c) faltar mais de 25% (vinte e cinco por cento) das aulas ministradas;<\/li>\n\n\n\n<li>d) tiver m\u00e1 conduta dentro ou fora do local de realiza\u00e7\u00e3o do curso de forma\u00e7\u00e3o;<\/li>\n\n\n\n<li>e) cometer falta disciplinar considerada grave, apurada em procedimento administrativo, em que lhe seja assegurado o contradit\u00f3rio e ampla defesa, conforme se dispuser em regulamento;<\/li>\n\n\n\n<li>f) praticar fraudes, de qualquer natureza, na realiza\u00e7\u00e3o das provas ou exames do curso de forma\u00e7\u00e3o;<\/li>\n\n\n\n<li>g) revelar comportamento incompat\u00edvel com o cargo ao qual concorre; e<\/li>\n\n\n\n<li>h) envolver-se com atividade criminosa quando comprovada na Investiga\u00e7\u00e3o Criminal e Social.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-cyan-bluish-gray-background-color has-background has-medium-font-size wp-block-paragraph\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac\/\" target=\"_blank\" rel=\"noreferrer noopener\">concurso Detran Acre<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-detran\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos DETRAN<\/a><\/li>\n\n\n\n<li><a href=\"#https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\">Concursos 2024<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\">Quer estudar para o edital Detran AC?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-detran\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\">Concurso Detran AC<\/h2>\n        <p class=\"subtitulo-assinatura\">Cursos preparat\u00f3rios para a carreira! \u270f\ufe0f<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/departamento-de-transito-do-acre-detran-ac\/\" role=\"button\" rel=\"noopener noreferrer\">INSCREVA-SE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div>\n\n  <\/div>\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n     \n    <\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"632\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2025\/06\/ficha-tecnica-1-1024x632.png\" alt=\"Informa\u00e7\u00f5es do concurso Detran AC\" class=\"wp-image-702728\" style=\"width:318px;height:auto\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27101122\/ficha-tecnica-1-1024x632.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27101122\/ficha-tecnica-1-300x185.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27101122\/ficha-tecnica-1-768x474.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27101122\/ficha-tecnica-1-1536x948.png 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27101122\/ficha-tecnica-1-610x377.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/27101122\/ficha-tecnica-1.png 1571w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ficha\">Informa\u00e7\u00f5es do edital Detran AC<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Provas:<\/strong> 28\/07\/2024<\/li>\n\n\n\n<li><strong>Vagas:<\/strong> 91<\/li>\n\n\n\n<li><strong>Cargos<\/strong>: v\u00e1rios<\/li>\n\n\n\n<li><strong>Escolaridade:<\/strong> superior<\/li>\n\n\n\n<li><strong>Banca<\/strong>: Instituto AOCP<\/li>\n\n\n\n<li><strong>Edital<\/strong>: <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/04\/08215213\/fff66a3a-8b36-4207-91c9-15e5403a1d1b.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Detran AC-2024<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sal\u00e1rios iniciais podem alcan\u00e7ar R$ 9,5 mil! Est\u00e3o encerradas as inscri\u00e7\u00f5es para o edital Detran AC (Departamento Estadual de Tr\u00e2nsito do Acre). De acordo com o documento, s\u00e3o ofertadas 91 vagas de n\u00edvel superior. Sob organiza\u00e7\u00e3o do Instituto AOCP, as inscri\u00e7\u00f5es puderam ser efetuadas at\u00e9 05 de junho, ao custo de R$ 80,00. As provas [&hellip;]<\/p>\n","protected":false},"author":2134,"featured_media":794709,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"news","footnotes":""},"categories":[214992,220219],"tags":[],"tax_estado":[219964],"class_list":["post-1380766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-administrativos","category-noticias","tax_estado-ac"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!<\/title>\n<meta name=\"description\" content=\"Edital Detran AC \u00e9 publicado com 91 vagas de n\u00edvel superior, com sal\u00e1rios de at\u00e9 R$ 9,5 mil! Confira no blog os detalhes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!\" \/>\n<meta property=\"og:description\" content=\"Edital Detran AC \u00e9 publicado com 91 vagas de n\u00edvel superior, com sal\u00e1rios de at\u00e9 R$ 9,5 mil! Confira no blog os detalhes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T23:28:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T19:59:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/14135416\/detran-ac.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela Teixeira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela Teixeira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/\"},\"author\":{\"name\":\"Rafaela Teixeira\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/e75352021ea7f60781c599934f916eb1\"},\"headline\":\"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!\",\"datePublished\":\"2024-06-05T23:28:38+00:00\",\"dateModified\":\"2026-03-20T19:59:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/\"},\"wordCount\":905,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/14135416\\\/detran-ac.jpg\",\"articleSection\":[\"Executivo (Administrativa)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/\",\"name\":\"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/14135416\\\/detran-ac.jpg\",\"datePublished\":\"2024-06-05T23:28:38+00:00\",\"dateModified\":\"2026-03-20T19:59:18+00:00\",\"description\":\"Edital Detran AC \u00e9 publicado com 91 vagas de n\u00edvel superior, com sal\u00e1rios de at\u00e9 R$ 9,5 mil! Confira no blog os detalhes!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/14135416\\\/detran-ac.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2021\\\/07\\\/14135416\\\/detran-ac.jpg\",\"width\":768,\"height\":432,\"caption\":\"concurso detran ac\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/concurso-detran-ac-edital-publicado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/e75352021ea7f60781c599934f916eb1\",\"name\":\"Rafaela Teixeira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g\",\"caption\":\"Rafaela Teixeira\"},\"description\":\"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no Tribunal Regional Eleitoral de S\u00e3o Paulo (TRE-SP). Possui mais de 8 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica, an\u00e1lise de editais e pesquisa de informa\u00e7\u00f5es diretamente em \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior e \u00e9 respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de not\u00edcias, acompanhando as principais movimenta\u00e7\u00f5es e organizando prioridades para garantir a continuidade, precis\u00e3o e atualiza\u00e7\u00e3o das publica\u00e7\u00f5es.\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/rafaela-teixeira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!","description":"Edital Detran AC \u00e9 publicado com 91 vagas de n\u00edvel superior, com sal\u00e1rios de at\u00e9 R$ 9,5 mil! Confira no blog os detalhes!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/","og_locale":"pt_BR","og_type":"article","og_title":"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!","og_description":"Edital Detran AC \u00e9 publicado com 91 vagas de n\u00edvel superior, com sal\u00e1rios de at\u00e9 R$ 9,5 mil! Confira no blog os detalhes!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-06-05T23:28:38+00:00","article_modified_time":"2026-03-20T19:59:18+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/14135416\/detran-ac.jpg","type":"image\/jpeg"}],"author":"Rafaela Teixeira","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafaela Teixeira","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/"},"author":{"name":"Rafaela Teixeira","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1"},"headline":"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!","datePublished":"2024-06-05T23:28:38+00:00","dateModified":"2026-03-20T19:59:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/"},"wordCount":905,"commentCount":0,"publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/14135416\/detran-ac.jpg","articleSection":["Executivo (Administrativa)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/","name":"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/14135416\/detran-ac.jpg","datePublished":"2024-06-05T23:28:38+00:00","dateModified":"2026-03-20T19:59:18+00:00","description":"Edital Detran AC \u00e9 publicado com 91 vagas de n\u00edvel superior, com sal\u00e1rios de at\u00e9 R$ 9,5 mil! Confira no blog os detalhes!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/14135416\/detran-ac.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/07\/14135416\/detran-ac.jpg","width":768,"height":432,"caption":"concurso detran ac"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-detran-ac-edital-publicado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog-estrategia.mystagingwebsite.com\/"},{"@type":"ListItem","position":2,"name":"Edital Detran AC publicado! 91 vagas e iniciais de at\u00e9 R$ 9,5 mil!"}]},{"@type":"WebSite","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog-estrategia.mystagingwebsite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/e75352021ea7f60781c599934f916eb1","name":"Rafaela Teixeira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a349a2b22039b1ee88fc06461487c950fd6aa411ea8af8633314b43334ae793?s=96&d=mm&r=g","caption":"Rafaela Teixeira"},"description":"Rafaela Teixeira \u00e9 advogada conveniada \u00e0 Defensoria P\u00fablica de S\u00e3o Paulo pela OAB, com experi\u00eancia em reda\u00e7\u00e3o jur\u00eddica e atua\u00e7\u00e3o em institui\u00e7\u00f5es p\u00fablicas, incluindo est\u00e1gio no Tribunal Regional Eleitoral de S\u00e3o Paulo (TRE-SP). Possui mais de 8 anos de experi\u00eancia na produ\u00e7\u00e3o de conte\u00fados voltados ao nicho de concursos p\u00fablicos, com foco em apura\u00e7\u00e3o jornal\u00edstica, an\u00e1lise de editais e pesquisa de informa\u00e7\u00f5es diretamente em \u00f3rg\u00e3os e fontes oficiais. No Blog do Estrat\u00e9gia Concursos, atua como Analista de Conte\u00fado S\u00eanior e \u00e9 respons\u00e1vel pelo jornalismo do per\u00edodo noturno e da madrugada, com atua\u00e7\u00e3o transversal na cobertura de not\u00edcias, acompanhando as principais movimenta\u00e7\u00f5es e organizando prioridades para garantir a continuidade, precis\u00e3o e atualiza\u00e7\u00e3o das publica\u00e7\u00f5es.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/rafaela-teixeira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1380766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2134"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1380766"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1380766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/794709"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1380766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1380766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1380766"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1380766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}