{"id":1373960,"date":"2024-03-24T21:09:56","date_gmt":"2024-03-25T00:09:56","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1373960"},"modified":"2024-03-24T22:12:46","modified_gmt":"2024-03-25T01:12:46","slug":"gabarito-extraoficial-pm-sp-soldado-2024","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/","title":{"rendered":"Gabarito extraoficial PM SP Soldado: veja seu desempenho!"},"content":{"rendered":"\n<p>Neste domingo, 24 de mar\u00e7o de 2024, foram aplicadas as provas do <strong><\/strong><strong>concurso PM SP<\/strong> (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-militar-de-sao-paulo-pm-sp\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Militar do Estado de S\u00e3o Paulo<\/a>) para o cargo de <a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/pm-sp-soldado-pacote-pos-edital\/\" target=\"_blank\" rel=\"noreferrer noopener\">Soldado<\/a>.<\/p>\n\n\n\n<p>Sob organiza\u00e7\u00e3o da <a href=\"https:\/\/www.vunesp.com.br\/PMES2303\" target=\"_blank\" rel=\"noreferrer noopener\">Funda\u00e7\u00e3o Vunesp<\/a>, a sele\u00e7\u00e3o oferta <strong>2.700 vagas<\/strong>, com sal\u00e1rio inicial de <strong>R$ 4.852,21<\/strong>.<\/p>\n\n\n\n<p>Com o objetivo de ajud\u00e1-los em todas as etapas do certame e, claro, diminuir um pouco a ansiedade para saber deu desempenho,&nbsp;<strong>nossos professores realizaram o<\/strong>&nbsp;<strong>gabarito extraoficial da prova<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Disciplina<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Respons\u00e1vel<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">L\u00edngua Portuguesa e interpreta\u00e7\u00e3o de texto<\/td><td class=\"has-text-align-center\" data-align=\"center\">Suellen Borges<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Matem\u00e1tica<\/td><td class=\"has-text-align-center\" data-align=\"center\">Jhoni Zini<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Hist\u00f3ria Geral e do Brasil<\/td><td class=\"has-text-align-center\" data-align=\"center\">Alessandra Lopes<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Geografia Geral e do Brasil<\/td><td class=\"has-text-align-center\" data-align=\"center\">S\u00e9rgio Henrique<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Atualidades<\/td><td class=\"has-text-align-center\" data-align=\"center\">Rodolfo Gracioli<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">No\u00e7\u00f5es b\u00e1sicas de inform\u00e1tica<\/td><td class=\"has-text-align-center\" data-align=\"center\">Renato da Costa<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Administra\u00e7\u00e3o P\u00fablica (Constitucional e Constitui\u00e7\u00e3o do Estado)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Emerson Bruno<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Lei de Acesso \u00e0 Informa\u00e7\u00e3o<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ronaldo Paiva<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Agora \u00e9 a hora! Confira seu desempenho no &#8220;<strong>Gabarito extraoficial PM SP Soldado<\/strong>&#8221; e ainda receba dicas de recursos, caso haja algum.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-gabarito-extraoficial-concurso-pm-sp-soldado-2024\"><strong>Gabarito extraoficial: concurso PM SP Soldado 2024<\/strong><\/h2>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio lyte-align aligncenter\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_VPWN922tXyo\"><div id=\"lyte_VPWN922tXyo\" data-src=\"\/\/i.ytimg.com\/vi\/VPWN922tXyo\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/VPWN922tXyo\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/VPWN922tXyo\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p>Abaixo, voc\u00ea confere os gabaritos das quest\u00f5es corrigidas pelos nossos professores. Como existem diferentes tipos de provas, voc\u00ea pode conferindo o in\u00edcio da quest\u00e3o.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 1:&nbsp;<\/strong>Segundo o efeito de humor pretendido&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 2<\/strong>: No contexto, a frase \u2013 Temos que sacrificar!&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 3:<\/strong> Mantendo-se o sentido da tira&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 4:<\/strong>&nbsp;De acordo com o texto, quando se dizia&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 5:&nbsp;<\/strong>Para o narrador, a verdadeira&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 6:&nbsp;<\/strong>Considere as passagens&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 7:&nbsp;<\/strong>Na passagem \u2013 Era <strong>decerto<\/strong>&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 8:&nbsp;<\/strong>Na frase \u2013 \u2026 mas s\u00f3 para essas&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 9:&nbsp;<\/strong>Assinale a alternativa em que&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 10:&nbsp;<\/strong>No verso citado pelo&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 11:&nbsp;<\/strong>A concord\u00e2ncia verbal e a concord\u00e2ncia&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 12:<\/strong> Em conformidade com a norma-padr\u00e3o&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 13:&nbsp;<\/strong>A frase do \u00faltimo quadro&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 14:&nbsp;<\/strong>Os dois par\u00e1grafos iniciais&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 15:&nbsp;<\/strong>Os numerais empregados no primeiro&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 16:&nbsp;<\/strong>O \u00faltimo par\u00e1grafo do texto permite&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 17:<\/strong> H\u00e1 termo(s) empregado(s) em&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 18:&nbsp;<\/strong>Nas passagens \u2013 Pa\u00edses emergentes&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 19:&nbsp;<\/strong>Considere as reescritas de&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 20:&nbsp;<\/strong>O uso do acento indicativo&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 21:&nbsp;<\/strong>As informa\u00e7\u00f5es apresentadas&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 22:&nbsp;<\/strong>Com rela\u00e7\u00e3o ao n\u00famero total&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 23<\/strong>: Sabendo-se que no pr\u00f3ximo m\u00eas&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 24:&nbsp;<\/strong>Considere a seguinte informa\u00e7\u00e3o&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 25:&nbsp;<\/strong>Em um relat\u00f3rio, um policial militar&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 26:&nbsp;<\/strong>Determinada a\u00e7\u00e3o foi realizada em tr\u00eas&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 27:&nbsp;<\/strong>Em um batalh\u00e3o, a ter\u00e7a parte&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 28:&nbsp;<\/strong>Na tabela, constam informa\u00e7\u00f5es sobre a quantidade&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 29:&nbsp;<\/strong>Certo com\u00e9rcio, com uma matriz&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 30:&nbsp;<\/strong>De acordo com o Anu\u00e1rio Brasileiro&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 31:&nbsp;<\/strong>Um cubo maci\u00e7o, com uma face&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 32<\/strong>: Considere que uma taxa anual&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 33:&nbsp;<\/strong>A identifica\u00e7\u00e3o de regularidades em sequ\u00eancias&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 34:&nbsp;<\/strong>Um grande terreno retangular&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 35:<\/strong> Em certo com\u00e9rcio, h\u00e1 uma promo\u00e7\u00e3o&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 36:&nbsp;<\/strong>Associada ao antissemitismo estava a no\u00e7\u00e3o&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 37:&nbsp;<\/strong>A quest\u00e3o nacionalista mais complexa&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 38:&nbsp;<\/strong>Os ataques aos navios brasileiros foram apenas&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 39:&nbsp;<\/strong>As elei\u00e7\u00f5es legislativas foram realizadas&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 40:&nbsp;<\/strong>Ap\u00f3s definido o projeto pol\u00edtico&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 41:&nbsp;<\/strong>Em 1982, ocorreu a primeira elei\u00e7\u00e3o direta&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 42:<\/strong> A Faixa de Gaza \u00e9 um territ\u00f3rio costeiro&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 43:&nbsp;<\/strong>Analise o mapa a seguir, que apresenta as transforma\u00e7\u00f5es&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 44:<\/strong> Observe o mapa&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 45<\/strong>: O Censo Demogr\u00e1fico de 2022&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 46<\/strong>: Examine o gr\u00e1fico das fontes&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 47<\/strong>: Analise a pir\u00e2mide et\u00e1ria do Brasil&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 48:<\/strong> As florestas cobrem 31% da superf\u00edcie terrestre&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 49:&nbsp;<\/strong>Divulgados no in\u00edcio de janeiro&#8230;<br \/><strong><em>Resposta<\/em><\/strong>: E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 50:&nbsp;<\/strong>O n\u00famero de brasileiros se mudando&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 51:<\/strong> Um usu\u00e1rio entrou em uma pasta&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>\u00a0B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 52:&nbsp;<\/strong>Um usu\u00e1rio criou um novo documento vazio&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 53:<\/strong> Observe a planilha a seguir&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;E<\/p>\n\n\n\n<p><strong>Quest\u00e3o 54:&nbsp;<\/strong>Um usu\u00e1rio criou uma apresenta\u00e7\u00e3o&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 55:&nbsp;<\/strong>No gmail.com, em sua configura\u00e7\u00e3o&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 56:&nbsp;<\/strong>Considere que M\u00e1rio \u00e9 policial militar&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;D<\/p>\n\n\n\n<p><strong>Quest\u00e3o 57:&nbsp;<\/strong>Considere que Maria \u00e9 policial militar&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;A<\/p>\n\n\n\n<p><strong>Quest\u00e3o 58:&nbsp;<\/strong>A respeito dos servidores p\u00fablicos&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<p><strong>Quest\u00e3o 59:&nbsp;<\/strong>Considere que Isa\u00edas foi nomeado&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;B<\/p>\n\n\n\n<p><strong>Quest\u00e3o 60:&nbsp;<\/strong>Considere que a autoridade competente declarou&#8230;<br \/><strong><em>Resposta:<\/em><\/strong>&nbsp;C<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\">Quer estudar para o concurso PM SP?<\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-policia-militar\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\" style=\"text-align: left;\">Concurso PM SP<\/h3>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Conhe\u00e7a os cursos<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-militar-de-sao-paulo-pm-sp\/\" role=\"button\" rel=\"noopener noreferrer\">CLIQUE AQUI<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div id=\"boxes\" class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm\">\n<div id=\"box-assinatura\" class=\"estrategia\">\n<h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n<p class=\"subtitulo-assinatura\">Assinatura 1 ou 2 anos <\/p>\n<div class=\"box-botao\"><a class=\"btn-assinatura\" role=\"button\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo, 24 de mar\u00e7o de 2024, foram aplicadas as provas do concurso PM SP (Pol\u00edcia Militar do Estado de S\u00e3o Paulo) para o cargo de Soldado. Sob organiza\u00e7\u00e3o da Funda\u00e7\u00e3o Vunesp, a sele\u00e7\u00e3o oferta 2.700 vagas, com sal\u00e1rio inicial de R$ 4.852,21. Com o objetivo de ajud\u00e1-los em todas as etapas do certame e, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1374043,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[220187],"tags":[],"tax_estado":[219989],"class_list":["post-1373960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-pracas","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gabarito extraoficial PM SP Soldado: veja seu desempenho!<\/title>\n<meta name=\"description\" content=\"Gabarito extraoficial PM SP 2024: acompanhe o evento de corre\u00e7\u00e3o para o cargo de Soldado, no site do Estrat\u00e9gia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabarito extraoficial PM SP Soldado: veja seu desempenho!\" \/>\n<meta property=\"og:description\" content=\"Gabarito extraoficial PM SP 2024: acompanhe o evento de corre\u00e7\u00e3o para o cargo de Soldado, no site do Estrat\u00e9gia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-25T00:09:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T01:12:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Gabarito extraoficial PM SP Soldado: veja seu desempenho!\",\"datePublished\":\"2024-03-25T00:09:56+00:00\",\"dateModified\":\"2024-03-25T01:12:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/\"},\"wordCount\":964,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png\",\"articleSection\":[\"Policial (PM\/BM - Pra\u00e7as)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/\",\"name\":\"Gabarito extraoficial PM SP Soldado: veja seu desempenho!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png\",\"datePublished\":\"2024-03-25T00:09:56+00:00\",\"dateModified\":\"2024-03-25T01:12:46+00:00\",\"description\":\"Gabarito extraoficial PM SP 2024: acompanhe o evento de corre\u00e7\u00e3o para o cargo de Soldado, no site do Estrat\u00e9gia!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabarito extraoficial PM SP Soldado: veja seu desempenho!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gabarito extraoficial PM SP Soldado: veja seu desempenho!","description":"Gabarito extraoficial PM SP 2024: acompanhe o evento de corre\u00e7\u00e3o para o cargo de Soldado, no site do Estrat\u00e9gia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"Gabarito extraoficial PM SP Soldado: veja seu desempenho!","og_description":"Gabarito extraoficial PM SP 2024: acompanhe o evento de corre\u00e7\u00e3o para o cargo de Soldado, no site do Estrat\u00e9gia!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2024-03-25T00:09:56+00:00","article_modified_time":"2024-03-25T01:12:46+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png","type":"image\/png"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Gabarito extraoficial PM SP Soldado: veja seu desempenho!","datePublished":"2024-03-25T00:09:56+00:00","dateModified":"2024-03-25T01:12:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/"},"wordCount":964,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png","articleSection":["Policial (PM\/BM - Pra\u00e7as)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/","name":"Gabarito extraoficial PM SP Soldado: veja seu desempenho!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png","datePublished":"2024-03-25T00:09:56+00:00","dateModified":"2024-03-25T01:12:46+00:00","description":"Gabarito extraoficial PM SP 2024: acompanhe o evento de corre\u00e7\u00e3o para o cargo de Soldado, no site do Estrat\u00e9gia!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/03\/24205800\/ytb.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-pm-sp-soldado-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gabarito extraoficial PM SP Soldado: veja seu desempenho!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1373960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1373960"}],"version-history":[{"count":15,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1373960\/revisions"}],"predecessor-version":[{"id":1374058,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1373960\/revisions\/1374058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1374043"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1373960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1373960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1373960"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1373960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}