{"id":135037,"date":"2018-08-06T14:35:33","date_gmt":"2018-08-06T17:35:33","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=135037"},"modified":"2018-08-06T14:35:33","modified_gmt":"2018-08-06T17:35:33","slug":"comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/","title":{"rendered":"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP"},"content":{"rendered":"<p style=\"text-align: justify;\">Ol\u00e1! Analisamos as quest\u00f5es de Direitos Humanos aplicadas na prova de da PC-SP para o cargo de Delegado de Pol\u00edcia. S\u00e3o quest\u00f5es da VUNESP fresquinhas para voc\u00ea treinar.<\/p>\n<p style=\"text-align: justify;\">Caso voc\u00ea fique em d\u00favida, por favor, no contate:<\/p>\n<p style=\"text-align: justify;\">SITE:\u00a0<a href=\"https:\/\/sites.google.com\/prod\/view\/proftorques\">https:\/\/sites.google.com\/prod\/view\/proftorques<\/a><\/p>\n<p style=\"text-align: justify;\">INSTAGRAM:\u00a0<a href=\"https:\/\/www.instagram.com\/proftorques\/\">https:\/\/www.instagram.com\/proftorques\/<\/a><\/p>\n<p style=\"text-align: justify;\">FACEBOOK:\u00a0<a href=\"https:\/\/www.facebook.com\/direitoshumanosparaconcursos\">https:\/\/www.facebook.com\/direitoshumanosparaconcursos<\/a><\/p>\n<p style=\"text-align: justify;\">E-MAIL:\u00a0<a href=\"mailto:rst.estrategia@gmail.com\">rst.estrategia@gmail.com<\/a><\/p>\n<p style=\"text-align: justify;\">Vamos \u00e0s quest\u00f5es<\/p>\n<p style=\"text-align: justify;\"><strong>&#8212;<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>57.\u00a0\u00a0<\/strong><strong>(VUNESP\/PC-SP\/2018)<\/strong><\/p>\n<p style=\"text-align: justify;\">No tocante \u00e0 tem\u00e1tica dos direitos humanos, considerando seu surgimento e sua evolu\u00e7\u00e3o hist\u00f3rica, assinale a alternativa que contempla correta e cronologicamente seus marcos hist\u00f3ricos fundamentais.<\/p>\n<p style=\"text-align: justify;\">(A) A Magna Carta, a queda da Bastilha na Fran\u00e7a e a cria\u00e7\u00e3o da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas.<\/p>\n<p style=\"text-align: justify;\">(B) O iluminismo, o constitucionalismo e o socialismo.<\/p>\n<p style=\"text-align: justify;\">(C) O iluminismo, a Revolu\u00e7\u00e3o Francesa e o fim da Segunda Guerra Mundial.<\/p>\n<p style=\"text-align: justify;\">(D) A Magna Carta, a Constitui\u00e7\u00e3o Alem\u00e3 de Weimar e a Declara\u00e7\u00e3o de Independ\u00eancia dos Estados Unidos da Am\u00e9rica.<\/p>\n<p style=\"text-align: justify;\">(E) O cristianismo, o socialismo e o constitucionalismo.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">A quest\u00e3o cobra do candidato um conhecimento hist\u00f3rico acerca da evolu\u00e7\u00e3o dos Direitos Humanos, no \u00e2mbito internacional. Das op\u00e7\u00f5es dadas, a que traz marcos hist\u00f3ricos fundamentais dessa evolu\u00e7\u00e3o, em ordem cronol\u00f3gica, \u00e9, de fato, a <strong>alternativa C<\/strong>, gabarito da quest\u00e3o. Como sabemos, o iluminismo foi um movimento intelectual e filos\u00f3fico que come\u00e7ou a se expandir a partir do s\u00e9culo XVIII. Dele surgiram ideias fundamentais para a evolu\u00e7\u00e3o dos Direitos Humanos, como a ideia do tratamento do homem como um fim em si mesmo, de Immanuel Kant. Foram as ideias Iluministas, de um modo geral, junto com a independ\u00eancia dos EUA, que possibilitaram a Revolu\u00e7\u00e3o Francesa, ao final do S\u00e9culo XVIII (1789), outro marco fundamental dessa evolu\u00e7\u00e3o hist\u00f3rica. Da Revolu\u00e7\u00e3o, surgiram conceitos como o de que o poder emana do povo, t\u00e3o caro at\u00e9 os dias atuais, e a Declara\u00e7\u00e3o dos Direitos do Homem e do Cidad\u00e3o, documento base da evolu\u00e7\u00e3o dos Direitos Humanos ao longo da hist\u00f3ria. Depois desses eventos, o outro ponto de virada dos Direitos Humanos no mundo foi a Segunda Guerra Mundial. Do contexto da Guerra \u00e9 que surgiram a Declara\u00e7\u00e3o Universal dos Direitos Humanos, a Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas e a preocupa\u00e7\u00e3o global de se evitar as atrocidades presenciadas pela humanidade durante os anos belicosos. As demais alternativas acabam trazendo n\u00e3o os marcos, mas causas ou consequ\u00eancias desses marcos fundamentais.<\/p>\n<p style=\"text-align: justify;\">Vejamos as demais alternativas:<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta. Apesar de podermos defender a import\u00e2ncia hist\u00f3ria da Magna Carta, na limita\u00e7\u00e3o dos poderes do governante, a queda da Bastilha \u00e9 uma causa da Revolu\u00e7\u00e3o Francesa e a cria\u00e7\u00e3o da ONU \u00e9 uma consequ\u00eancia da Segunda Guerra.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta. O constitucionalismo tem uma import\u00e2ncia tremenda na evolu\u00e7\u00e3o dos Direitos Humanos, mas de um ponto de vista interno e n\u00e3o internacional. J\u00e1 o socialismo \u00e9 um modelo econ\u00f4mico e n\u00e3o pode ser considerado um marco hist\u00f3rico nessa evolu\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong> est\u00e1 incorreta. Isso, porque a Constitui\u00e7\u00e3o Alem\u00e3 de Weimar \u00e9 de 1919, enquanto a Declara\u00e7\u00e3o da Independ\u00eancia dos EUA remonta ao final do S\u00e9culo XVIII.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa E<\/strong> est\u00e1 incorreta. O cristianismo, tamb\u00e9m, foi fundamental na evolu\u00e7\u00e3o hist\u00f3rica dos Direitos Humanos, e na pr\u00f3pria conserva\u00e7\u00e3o da cultura ocidental, em especial, durante a Idade M\u00e9dia. Foram os crist\u00e3os os primeiros a defender que o escravo tamb\u00e9m era humano, tamb\u00e9m tinha alma e tamb\u00e9m devia ser tratado de forma digna por ser uma criatura de Deus. Mas, como j\u00e1 dito, o socialismo n\u00e3o foi um marco hist\u00f3rico fundamental na evolu\u00e7\u00e3o dos Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"58\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Esse documento hist\u00f3rico de remota conquista dos direitos humanos foi editado com o escopo de assegurar a Supremacia do Parlamento sobre a vontade do Rei, controlando e reduzindo os abusos cometidos pela nobreza em rela\u00e7\u00e3o aos seus s\u00faditos, em especial declarando, dentre outras conquistas, o direito de peti\u00e7\u00e3o, elei\u00e7\u00f5es livres e a proibi\u00e7\u00e3o de fian\u00e7as exorbitantes e de penas severas:<\/p>\n<p style=\"text-align: justify;\">(A) The Bill of Rights, de 1689.<\/p>\n<p style=\"text-align: justify;\">(B) Petition of Rights, de 1628.<\/p>\n<p style=\"text-align: justify;\">(C) Declara\u00e7\u00e3o de Direitos do Homem e do Cidad\u00e3o, de 1789.<\/p>\n<p style=\"text-align: justify;\">(D) Magna Carta, de 1215.<\/p>\n<p style=\"text-align: justify;\">(E) Habeas Corpus Act, de 1679.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Mais uma vez, a banca cobra um conhecimento hist\u00f3rico do candidato. Vejamos. No S\u00e9culo XVII, em especial na Inglaterra, o Estado Absolutista come\u00e7a a ser questionado. Segundo Andr\u00e9 de Carvalho Ramos, a busca pela limita\u00e7\u00e3o do poder \u00e9 consagrada em 1628, com a <em>Petition of Rights <\/em>(<strong>alternativa B<\/strong>)<em>.<\/em> Em 1679, a edi\u00e7\u00e3o do <em>Habeas Corpus Act<\/em> formaliza o mandado de prote\u00e7\u00e3o judicial aos que haviam sido injustamente presos, mandado que, antes, s\u00f3 era poss\u00edvel com base no direito consuetudin\u00e1rio ingl\u00eas (<strong>alternativa E<\/strong>). Sendo, finalmente, em 1689, ap\u00f3s a Revolu\u00e7\u00e3o Gloriosa, editada a Declara\u00e7\u00e3o Inglesa de Direitos, a <em>Bill of Rights<\/em>, que assegura a supremacia do Parlamento sobre a vontade do Rei, controlando e reduzindo os abusos cometidos pela nobreza em rela\u00e7\u00e3o aos seus s\u00faditos, declarando, al\u00e9m disso, o direito de peti\u00e7\u00e3o, elei\u00e7\u00f5es livres e a proibi\u00e7\u00e3o de fian\u00e7as exorbitantes e de penas severas.<\/p>\n<p style=\"text-align: justify;\">Assim, a <strong>alternativa A<\/strong> \u00e9 a correta e gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">A Magna Carta, de 1215, foi um documento assinado em um contexto de luta entra a burguesia e a monarquia, n\u00e3o havendo que se falar em \u201celei\u00e7\u00f5es livres\u201d ou em \u201cparlamento\u201d (<strong>alternativa D<\/strong>).<\/p>\n<p style=\"text-align: justify;\">E a Declara\u00e7\u00e3o de Direitos do Homem e do Cidad\u00e3o, de 1789, n\u00e3o tinha a menor pretens\u00e3o de limitar os poderes do monarca, mas sim de acabar com essa forma de governo (<strong>alternativa C<\/strong>).<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"59\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Assinale a alternativa correta a respeito das caracter\u00edsticas dos direitos humanos.<\/p>\n<p style=\"text-align: justify;\">(A) O Princ\u00edpio da inalterabilidade estabelece que os direitos humanos n\u00e3o sofrem altera\u00e7\u00f5es com o decurso do tempo, pois t\u00eam car\u00e1ter eterno, n\u00e3o se ganham nem se perdem com o tempo, s\u00e3o anteriores, concomitantes e posteriores aos indiv\u00edduos.<\/p>\n<p style=\"text-align: justify;\">(B) O Princ\u00edpio da essencialidade reza que os direitos humanos devem ser vistos como aquela categoria de direitos inerentes \u00e0 sociedade em determinada \u00e9poca hist\u00f3rica, podendo ser divididos em essenciais, que devem gozar de livre frui\u00e7\u00e3o, e os n\u00e3o essenciais, que ainda demandam reivindica\u00e7\u00f5es a serem conquistadas ao longo do tempo.<\/p>\n<p style=\"text-align: justify;\">(C) O Princ\u00edpio da divisibilidade prop\u00f5e que os direitos humanos devem obedecer a uma classifica\u00e7\u00e3o ret\u00f3rica, que divide e categoriza os v\u00e1rios grupos de direitos inerentes ao homem e \u00e0 sociedade, para que sejam melhor usufru\u00eddos pelos seus destinat\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">(D) O Princ\u00edpio da interrelacionariedade disp\u00f5e que os direitos humanos e os sistemas de prote\u00e7\u00e3o se inter-relacionam, permitindo \u00e0s pessoas escolher entre os mecanismos de prote\u00e7\u00e3o global ou regional, pois n\u00e3o h\u00e1 hierarquia entre eles.<\/p>\n<p style=\"text-align: justify;\">(E) O Princ\u00edpio da ilimitabilidade garante que o Estado e a sociedade n\u00e3o podem limitar a frui\u00e7\u00e3o dos direitos humanos j\u00e1 conquistados, com o objetivo de disciplinar situa\u00e7\u00f5es excepcionais que venham a reduzir o alcance desses direitos.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Dentre as diversas caracter\u00edsticas que podemos apontar para os Direitos Humanos est\u00e1 a interrelacionariedade. De acordo com essa caracter\u00edstica, podemos dizer que os direitos humanos e os sistemas de prote\u00e7\u00e3o a esses direitos se inter-relacionam, permitindo \u00e0s pessoas escolher os mecanismos de prote\u00e7\u00e3o global ou regional, pois n\u00e3o h\u00e1 hierarquia entre eles. Devemos lembrar, contudo que, apesar dessa possibilidade de escolher a qual sistema se vai recorrer, n\u00e3o se pode recorrer a mais de um sistema ao mesmo tempo (litispend\u00eancia internacional). Andr\u00e9 de Carvalho Ramos fala em interdepend\u00eancia (ou inter-rela\u00e7\u00e3o): \u201c<em>reconhecimento de que todos os direitos humanos contribuem para a realiza\u00e7\u00e3o da dignidade humana, o que exige a aten\u00e7\u00e3o integral de todos os direitos humanos, sem exclus\u00e3o<\/em>\u201d.<\/p>\n<p style=\"text-align: justify;\">Est\u00e1 correta, portanto, a <strong>alternativa D<\/strong>, gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Vejamos as demais:<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta. N\u00e3o existe algo como um \u201cprinc\u00edpio da inalterabilidade\u201d. J\u00e1 se chegou a conclus\u00e3o de que os Direitos Humanos s\u00e3o mut\u00e1veis e evoluem no tempo. O que existe, e voc\u00eas j\u00e1 sabem, \u00e9 o efeito <em>cliquet<\/em> ou \u201cproibi\u00e7\u00e3o do retrocesso\u201d.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta, porque fala em Direitos Humanos n\u00e3o essenciais, o que \u00e9 uma contradi\u00e7\u00e3o em termos. Como sabemos, Direitos Humanos s\u00e3o aqueles direitos que fazem parte da ess\u00eancia do ser humano.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta, tamb\u00e9m. O que se defende \u00e9 o contr\u00e1rio do que se afirma na alternativa. Os Direitos Humanos s\u00e3o indivis\u00edveis, havendo, inclusive, severas cr\u00edticas \u00e0 divis\u00e3o do PIDCP e do PIDESC ou a teorias como a Teoria das Gera\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa E<\/strong>, por fim, tamb\u00e9m est\u00e1 incorreta. O Estado pode limitar a frui\u00e7\u00e3o de direitos humanos em situa\u00e7\u00f5es excepcionais. Isso \u00e9 o que ocorre, por exemplo, com a limita\u00e7\u00e3o ao direito de circula\u00e7\u00e3o em caso de Guerra, como veremos em uma das quest\u00f5es abaixo.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"60\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Assinale a alternativa que contempla um tratado de direitos humanos, incorporado pelo Direito Brasileiro com o status de norma constitucional, que faz parte do que a doutrina chama de Bloco de Constitucionalidade.<\/p>\n<p style=\"text-align: justify;\">(A) Pacto Internacional dos Direitos Econ\u00f4micos, Sociais e Culturais.<\/p>\n<p style=\"text-align: justify;\">(B) Pacto Internacional dos Direitos Civis e Pol\u00edticos.<\/p>\n<p style=\"text-align: justify;\">(C) Conven\u00e7\u00e3o Relativa ao Estatuto dos Refugiados.<\/p>\n<p style=\"text-align: justify;\">(D) Conven\u00e7\u00e3o contra a tortura e outros tratamentos ou penas cru\u00e9is, desumanas e degradantes.<\/p>\n<p style=\"text-align: justify;\">(E) Conven\u00e7\u00e3o sobre os Direitos das Pessoas com Defici\u00eancia e seu Protocolo Facultativo.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Hoje, de acordo com o site do Planalto, o \u00fanico tratado de direitos humanos, incorporado pelo Direito Brasileiro com o status de norma constitucional (art. 5\u00ba \u00a7 3\u00ba, da CRFB), que faz parte do que a doutrina chama de Bloco de Constitucionalidade \u00e9 a Conven\u00e7\u00e3o sobre os Direitos das Pessoas com Defici\u00eancia e seu Protocolo Facultativo, o que torna correta a alternativa E.<\/p>\n<p style=\"text-align: justify;\">Assim, a <strong>alternativa E <\/strong>\u00e9 a \u00fanica correta e gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Os demais documentos citados t\u00eam for\u00e7a de lei infraconstitucional.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"61\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">A respeito da Comiss\u00e3o Interamericana dos Direitos Humanos, \u00e9 correto afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) a compet\u00eancia para apresentar \u00e0 Comiss\u00e3o peti\u00e7\u00f5es que contenham den\u00fancias ou queixas de viola\u00e7\u00e3o desta Conven\u00e7\u00e3o por um Estado-Parte ser\u00e1 do Minist\u00e9rio P\u00fablico Federal.<\/p>\n<p style=\"text-align: justify;\">(B) ap\u00f3s a primeira elei\u00e7\u00e3o da Comiss\u00e3o, a dura\u00e7\u00e3o do mandato dos seus membros ser\u00e1 de 4 anos e poder\u00e3o ser reeleitos por uma s\u00f3 vez.<\/p>\n<p style=\"text-align: justify;\">(C) a Comiss\u00e3o \u00e9 \u00f3rg\u00e3o auxiliar da ONU e tem como fun\u00e7\u00e3o primordial a supervis\u00e3o das obriga\u00e7\u00f5es dos Estados em virtude da Conven\u00e7\u00e3o Americana sobre Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\">(D) a Comiss\u00e3o \u00e9 um \u00f3rg\u00e3o de car\u00e1ter jurisdicional que foi criado pela Conven\u00e7\u00e3o com tripla fun\u00e7\u00e3o, a consultiva, a contenciosa e a executiva.<\/p>\n<p style=\"text-align: justify;\">(E) a Comiss\u00e3o \u00e9 composta por 7 membros eleitos, que atuam como representantes dos seus respectivos governos.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">A Comiss\u00e3o Interamericana de Direitos Humanos \u00e9 \u00f3rg\u00e3o do Sistema Interamericano de Direitos Humanos competente para conhecer dos assuntos relacionados com o cumprimento dos compromissos assumidos pelos Estados Partes na Conven\u00e7\u00e3o Americana de Direitos Humanos (Pacto de San Jos\u00e9 da Costa Rica). Ela \u00e9 composta por sete membros, eleitos a t\u00edtulo pessoal, e representa todos os membros da Organiza\u00e7\u00e3o dos Estados Americanos (Artigo 35, CADH), n\u00e3o havendo que se falar em \u201crepresentantes dos seus respectivos governos\u201d (<strong>alternativa E<\/strong>). Esses membros s\u00e3o eleitos por quatro anos e s\u00f3 poder\u00e3o ser reeleitos uma vez (Artigo 37, 1, CADH), estando, por isso, correta a <strong>alternativa B<\/strong>.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong>, portanto, \u00e9 o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Vejamos as demais alternativas:<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta, uma vez que at\u00e9 particulares podem peticionar para a Comiss\u00e3o IDH. Segundo o Artigo 44, da CADH: \u201cQualquer pessoa ou grupo de pessoas, ou entidade n\u00e3o-governamental legalmente reconhecida em um ou mais Estados membros da Organiza\u00e7\u00e3o, pode apresentar \u00e0 Comiss\u00e3o peti\u00e7\u00f5es que contenham den\u00fancias ou queixas de viola\u00e7\u00e3o desta Conven\u00e7\u00e3o por um Estado Parte\u201d.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta, uma vez que, como visto, a Comiss\u00e3o \u00e9 \u00f3rg\u00e3o da OEA e do Sistema Interamericano de Direitos Humanos, sendo incorreto afirmar que ela seja \u201c\u00f3rg\u00e3o auxiliar da ONU\u201d.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong> est\u00e1 incorreta, pois \u00e9 a Corte Interamericana de Direitos Humanos que pode ser considerada como \u00f3rg\u00e3o de car\u00e1ter jurisdicional, criado pela Conven\u00e7\u00e3o com tripla fun\u00e7\u00e3o, a consultiva, a contenciosa e a executiva.<\/p>\n<p style=\"text-align: justify;\">E a <strong>alternativa E<\/strong> tamb\u00e9m est\u00e1 incorreta, como j\u00e1 vimos acima. Os membros da Comiss\u00e3o IDH representam a OEA, n\u00e3o os seus governos.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"62\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Assinale a alternativa que est\u00e1 em conson\u00e2ncia com o Protocolo de Preven\u00e7\u00e3o, Supress\u00e3o e Puni\u00e7\u00e3o do Tr\u00e1fico de Pessoas, Especialmente Mulheres e Crian\u00e7as.<\/p>\n<p style=\"text-align: justify;\">(A) Para efeitos do Protocolo, o termo \u201ccrian\u00e7a\u201d significa qualquer pessoa com idade inferior a dezoito anos.<\/p>\n<p style=\"text-align: justify;\">(B) O recrutamento, o transporte, a transfer\u00eancia, ou o acolhimento de uma crian\u00e7a para fins de explora\u00e7\u00e3o ser\u00e3o considerados tr\u00e1fico de pessoas desde que envolvam o uso da for\u00e7a ou outras formas de coa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">(C) Quando se tratar de explora\u00e7\u00e3o para fins de prostitui\u00e7\u00e3o mediante o pagamento de benef\u00edcios, o consentimento dado pela v\u00edtima descaracteriza o tr\u00e1fico de pessoas.<\/p>\n<p style=\"text-align: justify;\">(D) Cada Estado-Parte se obriga, em virtude da relev\u00e2ncia social da preven\u00e7\u00e3o e gravidade da conduta, a afastar eventual confidencialidade dos procedimentos judiciais relativos ao tr\u00e1fico de pessoas, especialmente de mulheres e crian\u00e7as.<\/p>\n<p style=\"text-align: justify;\">(E) Cada Estado-Parte, ao aplicar as disposi\u00e7\u00f5es sobre assist\u00eancia e prote\u00e7\u00e3o das v\u00edtimas de tr\u00e1fico de pessoas, n\u00e3o poder\u00e1 fazer distin\u00e7\u00e3o quanto \u00e0 idade, ao sexo ou \u00e0s suas necessidades espec\u00edficas.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">O Protocolo de Preven\u00e7\u00e3o, Supress\u00e3o e Puni\u00e7\u00e3o do Tr\u00e1fico de Pessoas, Especialmente Mulheres e Crian\u00e7as foi internalizado pelo Brasil por meio do Decreto n\u00ba 5.017, de 12 de mar\u00e7o de 2004. Dentre suas disposi\u00e7\u00f5es, est\u00e1 o Artigo 3, que trata das defini\u00e7\u00f5es. Segundo o Artigo 3, \u201cd\u201d, para efeitos do Protocolo, o termo \u201ccrian\u00e7a\u201d significa qualquer pessoa com idade inferior a dezoito anos.<\/p>\n<p style=\"text-align: justify;\">Assim, est\u00e1 correta a <strong>alternativa A<\/strong>, gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Vejamos o erro das demais alternativas:<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta, uma vez que o recrutamento, o transporte, a transfer\u00eancia, o alojamento ou o acolhimento de uma crian\u00e7a para fins de explora\u00e7\u00e3o ser\u00e3o considerados &#8220;tr\u00e1fico de pessoas&#8221; mesmo que n\u00e3o envolvam o uso da for\u00e7a ou outras formas de coa\u00e7\u00e3o (Artigo 3, \u201cc\u201d, do Protocolo).<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta, uma vez que cria uma ressalva n\u00e3o presente no Protocolo. De acordo com o Artigo 3, \u201ca\u201d, a \u201cexplora\u00e7\u00e3o incluir\u00e1, no m\u00ednimo, a explora\u00e7\u00e3o da prostitui\u00e7\u00e3o de outrem ou outras formas de explora\u00e7\u00e3o sexual\u201d.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong> est\u00e1 incorreta, uma vez que, nos casos em que se considere apropriado e na medida em que seja permitido pelo seu direito interno, cada Estado Parte proteger\u00e1 a privacidade e a identidade das v\u00edtimas de tr\u00e1fico de pessoas, incluindo, entre outras, a confidencialidade dos procedimentos judiciais relativos a esse tr\u00e1fico (Artigo 6, 1, do Protocolo).<\/p>\n<p style=\"text-align: justify;\">E a <strong>alternativa E<\/strong> est\u00e1 incorreta, uma vez que cada Estado Parte ter\u00e1 em conta, ao aplicar as disposi\u00e7\u00f5es sobre assist\u00eancia e prote\u00e7\u00e3o das v\u00edtimas de tr\u00e1fico de pessoas, a idade, o sexo e as necessidades espec\u00edficas de cada uma delas, designadamente as necessidades espec\u00edficas das crian\u00e7as, incluindo o alojamento, a educa\u00e7\u00e3o e cuidados adequados (Artigo 6, 4, do Protocolo).<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"63\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Segundo as Regras M\u00ednimas das Na\u00e7\u00f5es Unidas para o Tratamento dos Presos (Regras de Mandela), \u00e9 correto afirmar que<\/p>\n<p style=\"text-align: justify;\">(A) as diferentes categorias de presos devem ser mantidas em estabelecimentos prisionais separados, levando em considera\u00e7\u00e3o seu sexo, idade, antecedentes criminais, raz\u00f5es da deten\u00e7\u00e3o e necessidades de tratamento, n\u00e3o podendo diferentes categorias ser mantidas no mesmo estabelecimento, ainda que em recintos internos distintos.<\/p>\n<p style=\"text-align: justify;\">(B) todos os presos devem ser tratados com respeito e dignidade. Nenhum preso dever\u00e1 ser submetido a tortura ou tratamentos ou san\u00e7\u00f5es cru\u00e9is, desumanos ou degradantes e dever\u00e1 ser protegido de tais atos, n\u00e3o sendo estes justific\u00e1veis, a n\u00e3o ser em defesa da seguran\u00e7a dos servidores prisionais, dos prestadores de servi\u00e7o e dos visitantes.<\/p>\n<p style=\"text-align: justify;\">(C) as administra\u00e7\u00f5es prisionais e autoridades competentes devem oferecer educa\u00e7\u00e3o, forma\u00e7\u00e3o profissional e trabalho, e outras formas de assist\u00eancia apropriadas e dispon\u00edveis, inclusive aquelas de natureza reparadora, moral, espiritual, social, esportiva e de sa\u00fade. Tais programas, atividades e servi\u00e7os devem ser oferecidos em conson\u00e2ncia com as necessidades individuais de tratamento dos presos.<\/p>\n<p style=\"text-align: justify;\">(D) o sistema de registro dos presos, que deve ser aberto a todos os interessados, ser\u00e1 utilizado para gerar dados confi\u00e1veis acerca de tend\u00eancias e caracter\u00edsticas da popula\u00e7\u00e3o prisional, incluindo taxas de ocupa\u00e7\u00e3o, a fim de criar as bases para a tomada de decis\u00f5es fundadas em evid\u00eancias.<\/p>\n<p style=\"text-align: justify;\">(E) ao impor uma san\u00e7\u00e3o disciplinar, deve ser levado em conta se e como uma eventual doen\u00e7a mental ou incapacidade do preso possa ter contribu\u00eddo para sua conduta ou ato que fundamentou a san\u00e7\u00e3o. Os administradores prisionais devem punir de forma compat\u00edvel e adequada a conduta do preso considerada como resultado de sua doen\u00e7a mental ou incapacidade intelectual.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Segundo as Regras de Mandela (Regras M\u00ednimas das Na\u00e7\u00f5es Unidas para o Tratamento dos Presos), os objetivos de uma senten\u00e7a de encarceramento ou de medida similar restritiva de liberdade s\u00e3o, prioritariamente, de proteger a sociedade contra a criminalidade e de reduzir a reincid\u00eancia. Tais prop\u00f3sitos s\u00f3 podem ser alcan\u00e7ados se o per\u00edodo de encarceramento for utilizado para assegurar, na medida do poss\u00edvel, a reintegra\u00e7\u00e3o de tais indiv\u00edduos \u00e0 sociedade ap\u00f3s sua soltura, para que possam levar uma vida autossuficiente, com respeito \u00e0s leis. Para esse fim, as administra\u00e7\u00f5es prisionais e demais autoridades competentes devem oferecer educa\u00e7\u00e3o, forma\u00e7\u00e3o profissional e trabalho, bem como outras formas de assist\u00eancia apropriadas e dispon\u00edveis, inclusive aquelas de natureza reparadora, moral, espiritual, social, esportiva e de sa\u00fade. Tais programas, atividades e servi\u00e7os devem ser oferecidos em conson\u00e2ncia com as necessidades individuais de tratamento dos presos (Regra 4, 2).<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong>, portanto, \u00e9 a correta e o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Vejamos as demais alternativas:<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta, uma vez que \u00e9 poss\u00edvel, sim, a manuten\u00e7\u00e3o de diferentes categorias de presos em um mesmo estabelecimento, desde que em setores diferentes (Regra 11).<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta, uma vez que os atos de tortura n\u00e3o s\u00e3o justific\u00e1veis em qualquer circunst\u00e2ncia (Regra 1).<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong> est\u00e1 incorreta, uma vez que cria uma regra que n\u00e3o existe no documento, qual seja, a de que o sistema de registro de presos deve ser aberto a todos os interessados (Regra 10).<\/p>\n<p style=\"text-align: justify;\">E a <strong>alternativa E<\/strong> tamb\u00e9m est\u00e1 incorreta, uma vez que os administradores prisionais n\u00e3o devem punir qualquer conduta do preso que seja considerada resultado de sua doen\u00e7a mental ou incapacidade intelectual (Regra 39, 3).<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"64\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Nos moldes das Regras M\u00ednimas das Na\u00e7\u00f5es Unidas para o Tratamento dos Presos (Regras de Mandela), na hip\u00f3tese de haver uma presa em estado de gravidez ou com filhos em determinado estabelecimento prisional,<\/p>\n<p style=\"text-align: justify;\">(A) se a m\u00e3e, ap\u00f3s o nascimento do filho, quiser manter a crian\u00e7a com ela no estabelecimento prisional, essa decis\u00e3o deve se basear no melhor interesse da m\u00e3e e deve ser tomada pelo Diretor da unidade prisional.<\/p>\n<p style=\"text-align: justify;\">(B) provid\u00eancias devem ser tomadas para garantir creches internas ou externas dotadas de pessoal qualificado, onde as crian\u00e7as poder\u00e3o ser deixadas quando n\u00e3o estiverem sob o cuidado de seu pai ou sua m\u00e3e.<\/p>\n<p style=\"text-align: justify;\">(C) os exames pr\u00e9 e p\u00f3s-natais n\u00e3o devem ser realizados no pr\u00f3prio estabelecimento prisional, devendo a presa ser conduzida a hospital ou cl\u00ednica especializada sempre que necessitar.<\/p>\n<p style=\"text-align: justify;\">(D) devem-se adotar as medidas para que o nascimento ocorra em hospital fora da unidade prisional, mas se a crian\u00e7a nascer no pr\u00f3prio estabelecimento prisional, este fato deve constar de sua certid\u00e3o de nascimento.<\/p>\n<p style=\"text-align: justify;\">(E) ap\u00f3s o nascimento da crian\u00e7a, esta poder\u00e1 ficar com a m\u00e3e no estabelecimento prisional, no m\u00e1ximo, at\u00e9 completar dois anos de idade.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">De acordo com a Regra 29, a decis\u00e3o de permitir uma crian\u00e7a de ficar com seu pai ou com sua m\u00e3e na unidade prisional deve se basear <u>no melhor interesse da crian\u00e7a<\/u> (<strong>alternativa A<\/strong>). Al\u00e9m disso, nas unidades prisionais que abrigam filhos de detentos, provid\u00eancias devem ser tomadas para garantir: (i) creches internas ou externas dotadas de pessoal qualificado, onde as crian\u00e7as poder\u00e3o ser deixadas quando n\u00e3o estiverem sob o cuidado de seu pai ou sua m\u00e3e (<strong>alternativa B<\/strong>); e (ii) servi\u00e7os de sa\u00fade pedi\u00e1tricos, incluindo triagem m\u00e9dica, no ingresso e monitoramento constante de seu desenvolvimento por especialistas.<\/p>\n<p style=\"text-align: justify;\">De acordo com a Regra 28, nas unidades prisionais femininas, <u>deve haver acomoda\u00e7\u00e3o especial para todas as necessidades de cuidado e tratamento pr\u00e9 e p\u00f3s<\/u><u>\u2011natais<\/u> (<strong>alternativa C<\/strong>). Al\u00e9m disso, devem\u2011se adotar procedimentos espec\u00edficos para que os nascimentos ocorram em um hospital fora da unidade prisional, mas se a crian\u00e7a nascer na unidade prisional, este fato <u>n\u00e3o<\/u> deve constar de sua certid\u00e3o de nascimento (<strong>alternativa D<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Por fim, n\u00e3o costa nenhuma regra no documento limitando o tempo m\u00e1ximo de perman\u00eancia da crian\u00e7a no estabelecimento at\u00e9 a idade de dois anos (<strong>alternativa E)<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Assim, a <strong>alternativa B<\/strong> \u00e9 a correta e \u00e9 o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"65\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">No que se refere \u00e0 pris\u00e3o civil por d\u00edvida, a Conven\u00e7\u00e3o Americana de Direitos Humanos (Pacto de S\u00e3o Jos\u00e9 da Costa Rica) estabelece que<\/p>\n<p style=\"text-align: justify;\">(A) \u00e9 autorizada para os casos de deposit\u00e1rio infiel e de devedor de obriga\u00e7\u00e3o alimentar.<\/p>\n<p style=\"text-align: justify;\">(B) \u00e9 permitida apenas para hip\u00f3tese de deposit\u00e1rio infiel.<\/p>\n<p style=\"text-align: justify;\">(C) \u00e9 permitida apenas para o caso de inadimplemento de obriga\u00e7\u00e3o alimentar.<\/p>\n<p style=\"text-align: justify;\">(D) deve ser decidida pela Constitui\u00e7\u00e3o de cada Estado- -Parte.<\/p>\n<p style=\"text-align: justify;\">(E) deve ser abolida em todos os Estados-Partes.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Como sabemos, a CADH s\u00f3 admite uma hip\u00f3tese de pris\u00e3o civil por d\u00edvidas, que \u00e9 aquela que ocorre no caso de inadimplemento de obriga\u00e7\u00e3o alimentar. De acordo com o Artigo 7, 7, da Conven\u00e7\u00e3o:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Artigo 7.\u00a0 Direito \u00e0 liberdade pessoal<\/p>\n<p style=\"text-align: justify;\">(&#8230;)<\/p>\n<p style=\"text-align: justify;\">7. Ningu\u00e9m deve ser detido por d\u00edvidas.\u00a0 Este princ\u00edpio n\u00e3o limita os mandados de autoridade judici\u00e1ria competente expedidos em virtude de inadimplemento de obriga\u00e7\u00e3o alimentar.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Assim, a <strong>alternativa C<\/strong> \u00e9 o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"66\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">O Pacto de S\u00e3o Jos\u00e9 da Costa Rica estipula que os Estados-Partes podem suspender as obriga\u00e7\u00f5es contra\u00eddas em virtude do referido Pacto, como por exemplo em situa\u00e7\u00e3o de guerra, perigo p\u00fablico, ou de outra emerg\u00eancia que ameace a sua independ\u00eancia ou sua seguran\u00e7a. Dentre os direitos que podem ser suspensos nessas hip\u00f3teses, est\u00e1<\/p>\n<p style=\"text-align: justify;\">(A) o Princ\u00edpio da Retroatividade da lei.<\/p>\n<p style=\"text-align: justify;\">(B) o Direito \u00e0 Nacionalidade.<\/p>\n<p style=\"text-align: justify;\">(C) a Liberdade de Religi\u00e3o.<\/p>\n<p style=\"text-align: justify;\">(D) o Direito ao Reconhecimento da Personalidade Jur\u00eddica.<\/p>\n<p style=\"text-align: justify;\">(E) o Direito de Circula\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rio<\/strong><\/p>\n<p style=\"text-align: justify;\">De acordo com a CADH, em caso de guerra, de perigo p\u00fablico, ou de outra emerg\u00eancia que ameace a independ\u00eancia ou seguran\u00e7a do Estado Parte, este poder\u00e1 adotar disposi\u00e7\u00f5es que, na medida e pelo tempo estritamente limitados \u00e0s exig\u00eancias da situa\u00e7\u00e3o, suspendam as obriga\u00e7\u00f5es contra\u00eddas em virtude desta Conven\u00e7\u00e3o, desde que tais disposi\u00e7\u00f5es n\u00e3o sejam incompat\u00edveis com as demais obriga\u00e7\u00f5es que lhe imp\u00f5e o Direito Internacional e n\u00e3o encerrem discrimina\u00e7\u00e3o alguma fundada em motivos de ra\u00e7a, cor, sexo, idioma, religi\u00e3o ou origem social (Artigo 27, 1).<\/p>\n<p style=\"text-align: justify;\">A Conven\u00e7\u00e3o, no entanto, limita essa disposi\u00e7\u00e3o (Artigo 27, 2), dizendo que ela n\u00e3o autoriza a suspens\u00e3o dos direitos determinados nos artigos:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">3 (Direito ao reconhecimento da personalidade jur\u00eddica) (<strong>alternativa D<\/strong>);<\/p>\n<p style=\"text-align: justify;\">4 (Direito \u00e0 vida);<\/p>\n<p style=\"text-align: justify;\">5 (Direito \u00e0 integridade pessoal);<\/p>\n<p style=\"text-align: justify;\">6 (Proibi\u00e7\u00e3o da escravid\u00e3o e servid\u00e3o);<\/p>\n<p style=\"text-align: justify;\">9 (Princ\u00edpio da legalidade e da retroatividade) (<strong>alternativa A<\/strong>);<\/p>\n<p style=\"text-align: justify;\">12 (Liberdade de consci\u00eancia e de religi\u00e3o) (<strong>alternativa C<\/strong>);<\/p>\n<p style=\"text-align: justify;\">17 (Prote\u00e7\u00e3o da fam\u00edlia);<\/p>\n<p style=\"text-align: justify;\">18 (Direito ao nome);<\/p>\n<p style=\"text-align: justify;\">19 (Direitos da crian\u00e7a);<\/p>\n<p style=\"text-align: justify;\">20 (Direito \u00e0 nacionalidade) (<strong>alternativa B<\/strong>); e<\/p>\n<p style=\"text-align: justify;\">23 (Direitos pol\u00edticos), nem das garantias indispens\u00e1veis para a prote\u00e7\u00e3o de tais direitos.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Sendo assim, o nosso gabarito s\u00f3 pode ser a <strong>alternativa E<\/strong>.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"67\">\n<li><strong>(VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">No tocante ao Tribunal Penal Internacional, considerando o disposto, expressamente, no Estatuto de Roma, o Tribunal ter\u00e1 compet\u00eancia para julgar<\/p>\n<p style=\"text-align: justify;\">(A) a tortura coletiva, o exterm\u00ednio em massa, o tr\u00e1fico de pessoas e os crimes de guerra.<\/p>\n<p style=\"text-align: justify;\">(B) os crimes de guerra, os crimes contra a humanidade, o terrorismo e os crimes hediondos.<\/p>\n<p style=\"text-align: justify;\">(C) o genoc\u00eddio, os crimes contra a humanidade, a tortura e o tr\u00e1fico internacional de entorpecentes.<\/p>\n<p style=\"text-align: justify;\">(D) o genoc\u00eddio, os crimes contra a humanidade, os crimes de guerra e os crimes de agress\u00e3o.<\/p>\n<p style=\"text-align: justify;\">(E) a tortura, o racismo, o terrorismo e os crimes contra a humanidade.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Quest\u00e3o direta que cobra do candidato o conhecimento do Artigo 5\u00ba, 1, do Estatuto de Roma. Vejamos:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Artigo 5o<\/p>\n<p style=\"text-align: justify;\">Crimes da Compet\u00eancia do Tribunal<\/p>\n<p style=\"text-align: justify;\">1. A compet\u00eancia do Tribunal restringir-se-\u00e1 aos crimes mais graves, que afetam a comunidade internacional no seu conjunto. Nos termos do presente Estatuto, o Tribunal ter\u00e1 compet\u00eancia para julgar os seguintes crimes:<\/p>\n<p style=\"text-align: justify;\">a) O crime de genoc\u00eddio;<\/p>\n<p style=\"text-align: justify;\">b) Crimes contra a humanidade;<\/p>\n<p style=\"text-align: justify;\">c) Crimes de guerra;<\/p>\n<p style=\"text-align: justify;\">d) O crime de agress\u00e3o.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">A <strong>alternativa D<\/strong>, portanto, \u00e9 a correta e o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Vejamos as demais alternativas:<\/p>\n<p style=\"text-align: justify;\">(A) a <span style=\"text-decoration: line-through;\">tortura coletiva<\/span>, o <span style=\"text-decoration: line-through;\">exterm\u00ednio em massa<\/span>, o <span style=\"text-decoration: line-through;\">tr\u00e1fico de pessoas<\/span> e os crimes de guerra.<\/p>\n<p style=\"text-align: justify;\">(B) os crimes de guerra, os crimes contra a humanidade, o <span style=\"text-decoration: line-through;\">terrorismo<\/span> e os <span style=\"text-decoration: line-through;\">crimes hediondos<\/span>.<\/p>\n<p style=\"text-align: justify;\">(C) o genoc\u00eddio, os crimes contra a humanidade, a <span style=\"text-decoration: line-through;\">tortura<\/span> e o <span style=\"text-decoration: line-through;\">tr\u00e1fico internacional de entorpecentes<\/span>.<\/p>\n<p style=\"text-align: justify;\">(E) a <span style=\"text-decoration: line-through;\">tortura<\/span>, o <span style=\"text-decoration: line-through;\">racismo<\/span>, o <span style=\"text-decoration: line-through;\">terrorismo<\/span> e os crimes contra a humanidade.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"68\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Segundo o Estatuto de Roma, o Tribunal Penal Internacional exercer\u00e1 a sua jurisdi\u00e7\u00e3o em rela\u00e7\u00e3o aos crimes nele previstos por iniciativa<\/p>\n<p style=\"text-align: justify;\">(A) de den\u00fancia do pr\u00f3prio Estado-Parte ou do Conselho de Seguran\u00e7a da ONU e por meio de inqu\u00e9rito do Procurador do Tribunal.<\/p>\n<p style=\"text-align: justify;\">(B) de den\u00fancia da Interpol ou do pr\u00f3prio Estado-Parte e de decis\u00e3o ex of\u00edcio de qualquer juiz do Tribunal.<\/p>\n<p style=\"text-align: justify;\">(C) de solicita\u00e7\u00e3o de qualquer \u00f3rg\u00e3o do Poder Judici\u00e1rio do Estado-Parte, de den\u00fancia de qualquer cidad\u00e3o do Estado-Parte e de decis\u00e3o ex of\u00edcio de qualquer juiz do Tribunal.<\/p>\n<p style=\"text-align: justify;\">(D) de den\u00fancia de qualquer pessoa, de entidades n\u00e3o- -governamentais ligadas \u00e0 defesa dos direitos humanos e por meio de inqu\u00e9rito do Procurador.<\/p>\n<p style=\"text-align: justify;\">(E) de den\u00fancia da Interpol, de solicita\u00e7\u00e3o de \u00f3rg\u00e3os de direitos humanos da ONU ou da Comiss\u00e3o Interamericana ou Europeia de Direitos Humanos.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Quest\u00e3o direta, tamb\u00e9m, que cobra do candidato o conhecimento dos legitimados para provocar o exerc\u00edcio da jurisdi\u00e7\u00e3o pelo TPI. S\u00e3o eles (Artigo 13):<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Artigo 13<\/p>\n<p style=\"text-align: justify;\">Exerc\u00edcio da Jurisdi\u00e7\u00e3o<\/p>\n<p style=\"text-align: justify;\">O Tribunal poder\u00e1 exercer a sua jurisdi\u00e7\u00e3o em rela\u00e7\u00e3o a qualquer um dos crimes a que se refere o artigo 5o, de acordo com o disposto no presente Estatuto, se:<\/p>\n<p style=\"text-align: justify;\">a) Um Estado Parte denunciar ao Procurador, nos termos do artigo 14, qualquer situa\u00e7\u00e3o em que haja ind\u00edcios de ter ocorrido a pr\u00e1tica de um ou v\u00e1rios desses crimes;<\/p>\n<p style=\"text-align: justify;\">b) O Conselho de Seguran\u00e7a, agindo nos termos do Cap\u00edtulo VII da Carta das Na\u00e7\u00f5es Unidas, denunciar ao Procurador qualquer situa\u00e7\u00e3o em que haja ind\u00edcios de ter ocorrido a pr\u00e1tica de um ou v\u00e1rios desses crimes; ou<\/p>\n<p style=\"text-align: justify;\">c) O Procurador tiver dado in\u00edcio a um inqu\u00e9rito sobre tal crime, nos termos do disposto no artigo 15.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Assim, nosso gabarito s\u00f3 pode ser a <strong>alternativa A<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Vejamos os erros das demais alternativas:<\/p>\n<p style=\"text-align: justify;\">(B) de den\u00fancia da <span style=\"text-decoration: line-through;\">Interpol<\/span> ou do pr\u00f3prio Estado-Parte e de <span style=\"text-decoration: line-through;\">decis\u00e3o ex of\u00edcio de qualquer juiz do Tribunal<\/span>.<\/p>\n<p style=\"text-align: justify;\">(C) de <span style=\"text-decoration: line-through;\">solicita\u00e7\u00e3o de qualquer \u00f3rg\u00e3o do Poder Judici\u00e1rio do Estado-Parte<\/span>, de <span style=\"text-decoration: line-through;\">den\u00fancia de qualquer cidad\u00e3o do Estado-Parte<\/span> e de <span style=\"text-decoration: line-through;\">decis\u00e3o ex of\u00edcio de qualquer juiz do Tribunal<\/span>.<\/p>\n<p style=\"text-align: justify;\">(D) de <span style=\"text-decoration: line-through;\">den\u00fancia de qualquer pessoa, de entidades n\u00e3o- -governamentais ligadas \u00e0 defesa dos direitos humanos<\/span> e por meio de inqu\u00e9rito do Procurador.<\/p>\n<p style=\"text-align: justify;\">(E) de <span style=\"text-decoration: line-through;\">den\u00fancia da Interpol<\/span>, de <span style=\"text-decoration: line-through;\">solicita\u00e7\u00e3o de \u00f3rg\u00e3os de direitos humanos da ONU<\/span> ou da <span style=\"text-decoration: line-through;\">Comiss\u00e3o Interamericana ou Europeia de Direitos Humanos<\/span>.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"69\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\u00c9 um Princ\u00edpio Geral de Direito Penal, previsto no Estatuto de Roma, aplic\u00e1vel \u00e0 jurisdi\u00e7\u00e3o do Tribunal Penal Internacional:<\/p>\n<p style=\"text-align: justify;\">(A) o Tribunal n\u00e3o ter\u00e1 jurisdi\u00e7\u00e3o sobre pessoas que, \u00e0 data da den\u00fancia da pr\u00e1tica do crime, n\u00e3o tenham ainda completado 21 anos de idade.<\/p>\n<p style=\"text-align: justify;\">(B) os crimes da compet\u00eancia do Tribunal prescrevem em 10 anos, contados do conhecimento do fato criminoso.<\/p>\n<p style=\"text-align: justify;\">(C) a previs\u00e3o de um crime ser\u00e1 estabelecida de forma precisa, sendo permitida, quando isso n\u00e3o for poss\u00edvel, o recurso \u00e0 analogia.<\/p>\n<p style=\"text-align: justify;\">(D) o erro de fato s\u00f3 excluir\u00e1 a responsabilidade criminal se eliminar o dolo requerido pelo crime.<\/p>\n<p style=\"text-align: justify;\">(E) qualquer pessoa condenada pelo Tribunal s\u00f3 poder\u00e1 ser punida em conformidade com as disposi\u00e7\u00f5es legais existentes no seu Estado-Parte.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">De acordo com o Estatuto, o erro de fato s\u00f3 excluir\u00e1 a responsabilidade criminal se eliminar o dolo requerido pelo crime (<strong>alternativa D<\/strong>), enquanto o erro de direito sobre se determinado tipo de conduta constitui crime da compet\u00eancia do Tribunal n\u00e3o ser\u00e1 considerado fundamento de exclus\u00e3o de responsabilidade criminal. Apesar disso, o erro de direito poder\u00e1 ser considerado fundamento de exclus\u00e3o de responsabilidade criminal se eliminar o dolo requerido pelo crime ou se decorrer de decis\u00e3o hier\u00e1rquica ou disposi\u00e7\u00f5es legais (tudo do Artigo 32).<\/p>\n<p style=\"text-align: justify;\">Assim, a <strong>alternativa D<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Vejamos as demais:<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa A<\/strong> est\u00e1 incorreta. Segundo o Artigo 26, do Estatuto, o TPI n\u00e3o ter\u00e1 jurisdi\u00e7\u00e3o sobre pessoas que, \u00e0 data da alegada pr\u00e1tica do crime, n\u00e3o tenham ainda completado <u>18 anos de idade<\/u>.<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa B<\/strong> est\u00e1 incorreta. Os crimes de compet\u00eancia do TPI <u>n\u00e3o prescrevem<\/u> (Artigo 29).<\/p>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong> est\u00e1 incorreta. Segundo o Estatuto, a previs\u00e3o de um crime ser\u00e1 estabelecida de forma precisa e <u>n\u00e3o<\/u> ser\u00e1 permitido o recurso \u00e0 analogia (Artigo 22, 2)<\/p>\n<p style=\"text-align: justify;\">E a <strong>alternativa E<\/strong> est\u00e1 incorreta. O que disp\u00f5e o Artigo 23, do Estatuto \u00e9: \u201cQualquer pessoa condenada pelo Tribunal s\u00f3 poder\u00e1 ser punida <u>em conformidade com as disposi\u00e7\u00f5es do presente Estatuto<\/u>\u201d.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<ol style=\"text-align: justify;\" start=\"70\">\n<li><strong> (VUNESP\/PC-SP\/2018)<\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Os ju\u00edzes da Corte Interamericana ser\u00e3o eleitos para um mandato de seis anos e s\u00f3 poder\u00e3o ser reeleitos uma vez. Na hip\u00f3tese de um dos ju\u00edzes concluir o seu mandato, mas ainda ter casos sob seu exame que se encontrem em fase de senten\u00e7a, o Estatuto da Corte estabelece que<\/p>\n<p style=\"text-align: justify;\">(A) os casos dever\u00e3o ser assumidos pelo novo juiz eleito que o substituir\u00e1, o qual dever\u00e1 proferir as respectivas senten\u00e7as de acordo com seu livre convencimento.<\/p>\n<p style=\"text-align: justify;\">(B) o juiz dever\u00e1 concluir a instru\u00e7\u00e3o de todos os processos em sua posse e entreg\u00e1-los prontos para a senten\u00e7a que ser\u00e1 proferida pelo novo juiz que o substituir\u00e1.<\/p>\n<p style=\"text-align: justify;\">(C) o juiz continuar\u00e1 conhecendo desses casos a que se tiver dedicado, para cujo efeito n\u00e3o ser\u00e1 substitu\u00eddo pelo novo juiz eleito.<\/p>\n<p style=\"text-align: justify;\">(D) o juiz presidente da Corte receber\u00e1 os casos no estado em que se encontram e far\u00e1 a sua redistribui\u00e7\u00e3o por sorteio aos demais ju\u00edzes.<\/p>\n<p style=\"text-align: justify;\">(E) dever\u00e3o os casos ser redistribu\u00eddos, igualitariamente, aos ju\u00edzes que permanecem na Corte, iniciando-se a transfer\u00eancia pelo integrante mais novo.<\/p>\n<p style=\"text-align: justify;\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify;\">Quest\u00e3o direta que cobra do candidato o conhecimento do Artigo 54, 3, da CADH. Vejamos:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Artigo 54<\/p>\n<p style=\"text-align: justify;\">(&#8230;)<\/p>\n<p style=\"text-align: justify;\">3.Os ju\u00edzes permanecer\u00e3o em fun\u00e7\u00f5es at\u00e9 o t\u00e9rmino dos seus mandatos.\u00a0 Entretanto, continuar\u00e3o funcionando nos casos de que j\u00e1 houverem tomado conhecimento e que se encontrem em fase de senten\u00e7a e, para tais efeitos, n\u00e3o ser\u00e3o substitu\u00eddos pelos novos ju\u00edzes eleitos.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">A <strong>alternativa C<\/strong>, portanto, \u00e9 o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">As demais alternativas est\u00e3o em desacordo com o previsto no Artigo 54, 3, da Conven\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<p style=\"text-align: justify;\">\u00c9 isso. Bons estudos!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1! Analisamos as quest\u00f5es de Direitos Humanos aplicadas na prova de da PC-SP para o cargo de Delegado de Pol\u00edcia. S\u00e3o quest\u00f5es da VUNESP fresquinhas para voc\u00ea treinar. Caso voc\u00ea fique em d\u00favida, por favor, no contate: SITE:\u00a0https:\/\/sites.google.com\/prod\/view\/proftorques INSTAGRAM:\u00a0https:\/\/www.instagram.com\/proftorques\/ FACEBOOK:\u00a0https:\/\/www.facebook.com\/direitoshumanosparaconcursos E-MAIL:\u00a0rst.estrategia@gmail.com Vamos \u00e0s quest\u00f5es &#8212; 57.\u00a0\u00a0(VUNESP\/PC-SP\/2018) No tocante \u00e0 tem\u00e1tica dos direitos humanos, considerando seu [&hellip;]<\/p>\n","protected":false},"author":180,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[525,3866,867],"tax_estado":[],"class_list":["post-135037","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-direitos-humanos","tag-pc-sp","tag-prova-comentada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1! Analisamos as quest\u00f5es de Direitos Humanos aplicadas na prova de da PC-SP para o cargo de Delegado de Pol\u00edcia. S\u00e3o quest\u00f5es da VUNESP fresquinhas para voc\u00ea treinar. Caso voc\u00ea fique em d\u00favida, por favor, no contate: SITE:\u00a0https:\/\/sites.google.com\/prod\/view\/proftorques INSTAGRAM:\u00a0https:\/\/www.instagram.com\/proftorques\/ FACEBOOK:\u00a0https:\/\/www.facebook.com\/direitoshumanosparaconcursos E-MAIL:\u00a0rst.estrategia@gmail.com Vamos \u00e0s quest\u00f5es &#8212; 57.\u00a0\u00a0(VUNESP\/PC-SP\/2018) No tocante \u00e0 tem\u00e1tica dos direitos humanos, considerando seu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ricardo.s.torques\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-06T17:35:33+00:00\" \/>\n<meta name=\"author\" content=\"Ricardo Torques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Torques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/\"},\"author\":{\"name\":\"Ricardo Torques\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2\"},\"headline\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP\",\"datePublished\":\"2018-08-06T17:35:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/\"},\"wordCount\":5586,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"keywords\":[\"Direitos Humanos\",\"PC SP\",\"prova comentada\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/\",\"name\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2018-08-06T17:35:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2\",\"name\":\"Ricardo Torques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"caption\":\"Ricardo Torques\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ricardo.s.torques\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardotorquesestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP","og_description":"Ol\u00e1! Analisamos as quest\u00f5es de Direitos Humanos aplicadas na prova de da PC-SP para o cargo de Delegado de Pol\u00edcia. S\u00e3o quest\u00f5es da VUNESP fresquinhas para voc\u00ea treinar. Caso voc\u00ea fique em d\u00favida, por favor, no contate: SITE:\u00a0https:\/\/sites.google.com\/prod\/view\/proftorques INSTAGRAM:\u00a0https:\/\/www.instagram.com\/proftorques\/ FACEBOOK:\u00a0https:\/\/www.facebook.com\/direitoshumanosparaconcursos E-MAIL:\u00a0rst.estrategia@gmail.com Vamos \u00e0s quest\u00f5es &#8212; 57.\u00a0\u00a0(VUNESP\/PC-SP\/2018) No tocante \u00e0 tem\u00e1tica dos direitos humanos, considerando seu [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/ricardo.s.torques","article_published_time":"2018-08-06T17:35:33+00:00","author":"Ricardo Torques","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ricardo Torques","Est. tempo de leitura":"28 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/"},"author":{"name":"Ricardo Torques","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2"},"headline":"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP","datePublished":"2018-08-06T17:35:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/"},"wordCount":5586,"commentCount":2,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"keywords":["Direitos Humanos","PC SP","prova comentada"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/","name":"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2018-08-06T17:35:33+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direitos-humanos-da-pc-sp-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Coment\u00e1rios \u00e0s quest\u00f5es de Direitos Humanos da PC-SP"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2","name":"Ricardo Torques","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","caption":"Ricardo Torques"},"sameAs":["https:\/\/www.facebook.com\/ricardo.s.torques"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardotorquesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/135037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/180"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=135037"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/135037\/revisions"}],"predecessor-version":[{"id":135040,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/135037\/revisions\/135040"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=135037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=135037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=135037"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=135037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}