{"id":1337648,"date":"2024-01-18T07:15:00","date_gmt":"2024-01-18T10:15:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1337648"},"modified":"2024-02-26T17:49:15","modified_gmt":"2024-02-26T20:49:15","slug":"concurso-cnpq-recursos-administracao-de-pessoal","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/","title":{"rendered":"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong><em>Quer interpor recursos contra o gabarito do cargo 8 do concurso CNPq? Confira as possibilidades neste artigo!<\/em><\/strong><\/p>\n\n\n\n<p>O <strong>concurso CNPq<\/strong> (<a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/conselho-nacional-de-desenvolvimento-cientifico-e-tecnologico-cnpq\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico<\/a>) teve suas \u00faltimas provas aplicadas no \u00faltimo domingo, 14 de janeiro. Com isso, j\u00e1 foram divulgados os gabaritos preliminares da etapa.&nbsp;<\/p>\n\n\n\n<p>Pretende <strong>interpor recurso para o concurso <\/strong><strong>CNPq<\/strong>? Todo o processo deve ser realizado <span style=\"text-decoration: underline;\">no per\u00edodo de 17 e 18 de janeiro<\/span>, no <a href=\"https:\/\/www.cebraspe.org.br\/concursos\/CNPQ_23\" target=\"_blank\" rel=\"noreferrer noopener\">site do Cebraspe<\/a>.<\/p>\n\n\n\n<p>E para te ajudar, nossos professores analisaram os gabaritos provis\u00f3rios do <strong>cargo de Analista em Ci\u00eancia e Tecnologia Pleno I: Administra\u00e7\u00e3o de Pessoal<\/strong> e identificaram algumas possibilidades de recursos. Confira abaixo e n\u00e3o perca o prazo:<\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"indice\">\n<li><a href=\"#dir-prev\">Recursos de Direito Previdenci\u00e1rio<\/a><\/li>\n\n\n\n<li><a href=\"#port\">Recursos de Portugu\u00eas<\/a><\/li>\n\n\n\n<li><a href=\"#orcamento\">Recursos de Conhecimentos Gerais<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-cyan-bluish-gray-background-color has-background\" id=\"dir-prev\">Concurso CNPq: recursos de Direito Previdenci\u00e1rio<\/h2>\n\n\n\n<p>Julgue os itens subsequentes, a respeito da organiza\u00e7\u00e3o e dos princ\u00edpios da <strong><u>Seguridade Social<\/u><\/strong>.<\/p>\n\n\n\n<p><strong>QUEST\u00c3O 118<\/strong>. O reajustamento dos benef\u00edcios visando preservar-lhes o <strong><u>valor real<\/u><\/strong>, previsto no texto constitucional, \u00e9 consequ\u00eancia do <strong><u>princ\u00edpio da irredutibilidade do valor dos benef\u00edcios<\/u><\/strong>. (grifos nossos)<\/p>\n\n\n\n<p>Gabarito oficial preliminar da banca: <strong>CERTO<\/strong><\/p>\n\n\n\n<p>Gabarito pleiteado: <strong>ERRADO<\/strong><\/p>\n\n\n\n<p><strong>Exposi\u00e7\u00e3o de motivos<\/strong><\/p>\n\n\n\n<p>O <strong>princ\u00edpio da Irredutibilidade do Valor dos Benef\u00edcios<\/strong>, objeto da quest\u00e3o, est\u00e1 elencado no art. 194, \u00a7 \u00fanico, IV da CF\/88.<strong><\/strong><\/p>\n\n\n\n<p>Conforme entendimento do <strong><em>Supremo Tribunal Federal \u2013 STF<\/em><\/strong>, tal princ\u00edpio constitucional, quando aplic\u00e1vel \u00e0 <strong>Seguridade Social<\/strong>, visa apenas proteger o <strong><u>valor nominal do benef\u00edcio<\/u><\/strong> (e n\u00e3o seu valor real), uma vez que o valor real dos benef\u00edcios est\u00e1 protegido pelo <strong>princ\u00edpio da preserva\u00e7\u00e3o do valor real dos benef\u00edcios<\/strong>, nos termos do art. 201, \u00a74\u00ba da CF\/88 e aplica-se APENAS \u00e0 Previd\u00eancia Social (e n\u00e3o \u00e0 Seguridade Social), sen\u00e3o vejamos:<\/p>\n\n\n\n<p><em>STF, RE 263252\/PR, Rel. Min. Moreira Alves, 1\u00aa T., DJ 23\/06\/2000. \u201cEMENTA: &#8211; Previd\u00eancia social. Irredutibilidade do benef\u00edcio. Preserva\u00e7\u00e3o permanente de seu valor real. &#8211; No caso n\u00e3o houve redu\u00e7\u00e3o do benef\u00edcio, porquanto j\u00e1 se firmou a jurisprud\u00eancia desta Corte no sentido de que o princ\u00edpio da irredutibilidade \u00e9 garantia contra a redu\u00e7\u00e3o do \u201cquantum\u201d que se recebe, e n\u00e3o daquilo que se pretende receber para que n\u00e3o haja perda do poder aquisitivo em decorr\u00eancia da infla\u00e7\u00e3o. &#8211; De outra parte, a preserva\u00e7\u00e3o permanente do valor real do benef\u00edcio &#8211; e, portanto, a garantia contra a perda do poder aquisitivo &#8211; se faz, como preceitua o artigo 201, \u00a7 2\u00ba, da Carta Magna, conforme crit\u00e9rios definidos em lei, cabendo, portanto, a esta estabelec\u00ea-los\u201d.<\/em><\/p>\n\n\n\n<p>Na mesma linha de racioc\u00ednio, podemos citar entendimento do TRF4 sobre o tema, conforme segue:<\/p>\n\n\n\n<p><em>JURISPRUD\u00caNCIA \u2013 TRF4 \u201cPREVIDENCI\u00c1RIO. REVIS\u00c3O. URV. CONVERS\u00c3O DOS BENEF\u00cdCIOS. PRINC\u00cdPIO DA IRREDUTIBIILIDADE. INEXIST\u00caNCIA DE VIOLA\u00c7\u00c3O. (&#8230;) &nbsp;2. N\u00e3o havendo demonstra\u00e7\u00e3o da ocorr\u00eancia de redu\u00e7\u00e3o do valor nominal do benef\u00edcio (em moeda corrente), n\u00e3o procede a alega\u00e7\u00e3o de ofensa ao princ\u00edpio da irredutibilidade preconizado no art. 194, IV da CF\/88 (Agravo Regimental na Apela\u00e7\u00e3o C\u00edvel, Processo n\u00ba 2003.71.00.082188-8, DJU de 28\/09\/2005, p. 1024).\u201d<\/em><\/p>\n\n\n\n<p>Nos termos do caput do art. 194 da CF\/88, temos que \u201cA <strong><u>Seguridade Social<\/u><\/strong> compreende um conjunto integrado de a\u00e7\u00f5es de iniciativa dos Poderes P\u00fablicos e da sociedade, destinadas a assegurar os direitos relativos \u00e0 <strong><u>sa\u00fade<\/u><\/strong>, \u00e0 <strong><u>previd\u00eancia<\/u><\/strong> e \u00e0 <strong><u>assist\u00eancia social<\/u><\/strong>.\u201d<\/p>\n\n\n\n<p>Podemos dizer, portanto, que a <strong>Seguridade Social<\/strong> \u00e9 g\u00eanero, das quais s\u00e3o esp\u00e9cies Sa\u00fade, Assist\u00eancia Social e Previd\u00eancia Social.<\/p>\n\n\n\n<p>A assertiva em an\u00e1lise, que trata da <strong><u>Seguridade Social<\/u><\/strong> (segundo o comando da quest\u00e3o) afirma que \u201co reajustamento dos benef\u00edcios visando <strong><u>preservar-lhes o valor real<\/u><\/strong>, previsto no texto constitucional, \u00e9 consequ\u00eancia do princ\u00edpio da irredutibilidade do valor dos benef\u00edcios\u201d.<\/p>\n\n\n\n<p>Tal afirma\u00e7\u00e3o somente poderia estar correta (e com ressalvas) se o comando da quest\u00e3o fosse <strong><u>exclusivamente acerca da Previd\u00eancia Social<\/u><\/strong>. Contudo, n\u00e3o \u00e9 o caso. O comando da quest\u00e3o refere-se \u00e0 <strong><u>Seguridade Social<\/u><\/strong>, formada pela sa\u00fade, previd\u00eancia e assist\u00eancia social. Assim sendo, n\u00e3o h\u00e1 como tal princ\u00edpio (princ\u00edpio da irredutibilidade do valor dos benef\u00edcios) preservar o valor real dos benef\u00edcios de Seguridade Social, pois o valor real dos benef\u00edcios somente \u00e9 garantido e aplic\u00e1vel a uma das tr\u00eas \u00e1reas da Seguridade Social, qual seja, a \u201cPrevid\u00eancia Social\u201d.<\/p>\n\n\n\n<p>Outrossim, quem garante a manuten\u00e7\u00e3o do valor real para os benef\u00edcios da Previd\u00eancia Social \u00e9 o art. 201, \u00a74\u00ba da CF\/88 (e n\u00e3o o art. 194, \u00a7 \u00fanico, IV da CF\/88, que trata do <strong>princ\u00edpio da irredutibilidade do valor dos benef\u00edcios<\/strong>).<\/p>\n\n\n\n<p>Nesta linha, como bem destacado pelo professor Hugo Goes: \u201cFica claro que, conforme a jurisprud\u00eancia predominante no STF, o princ\u00edpio da irredutibilidade <strong><u>veda apenas a redu\u00e7\u00e3o do valor nominal dos benef\u00edcios<\/u><\/strong>\u201d (In Manual de Direito Previdenci\u00e1rio, Rio de Janeiro: Forense; S\u00e3o Paulo: M\u00e9todo, 2020, p. 20). (grifos nossos)<\/p>\n\n\n\n<p>Sobre a inexist\u00eancia de garantia \u00e0 preserva\u00e7\u00e3o do valor real em mat\u00e9ria de benef\u00edcios assistenciais, preciso o ensinamento de Ivan Kertzman:<\/p>\n\n\n\n<p>\u201capenas o valor real dos <strong><u>benef\u00edcios previdenci\u00e1rios<\/u><\/strong> s\u00e3o protegidos pela Constitui\u00e7\u00e3o, \u00e9 poss\u00edvel afirmar que os benef\u00edcios assistenciais pecuni\u00e1rios, a exemplo do bolsa fam\u00edlia, <strong><u>n\u00e3o precisam, necessariamente, ser reajustados de forma a preservar o seu valor real<\/u><\/strong>\u201d. (Curso Pr\u00e1tico de Direito Previdenci\u00e1rio, 2016, p. 59). (grifos nossos)<\/p>\n\n\n\n<p>Ademais, a banca do presente concurso (CESPE\/CEBRASPE), em uma quest\u00e3o para Juiz Federal\/TRF -1\u00aa\/2013 abordou o tema em tela:<\/p>\n\n\n\n<p>\u201cCom rela\u00e7\u00e3o \u00e0 seguridade social e seus princ\u00edpios, assinale a op\u00e7\u00e3o correta.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A) A seguridade social compreende um conjunto integrado de a\u00e7\u00f5es de iniciativa dos poderes p\u00fablicos e da sociedade destinadas a assegurar os direitos relativos ao trabalho, \u00e0 sa\u00fade, \u00e0 previd\u00eancia e \u00e0 assist\u00eancia social.<\/li>\n\n\n\n<li>B) A gest\u00e3o tripartite do sistema previdenci\u00e1rio, com participa\u00e7\u00e3o dos trabalhadores, dos empregadores e dos aposentados e decorrente do car\u00e1ter democr\u00e1tico e descentralizado da administra\u00e7\u00e3o, garante a seguran\u00e7a e a moralidade na administra\u00e7\u00e3o desse sistema.<\/li>\n\n\n\n<li>C) O equil\u00edbrio financeiro e atuarial do sistema previdenci\u00e1rio consiste na observa\u00e7\u00e3o dos crit\u00e9rios que preservem a sua solv\u00eancia financeira, de modo a fornecer seguran\u00e7a e tranquilidade aos segurados e garantir o fomento p\u00fablico em situa\u00e7\u00f5es de instabilidade econ\u00f4mica.<\/li>\n\n\n\n<li>D) Constituem objetivos da seguridade social a universalidade e a uniformidade da cobertura e do atendimento e a inequidade na forma de participa\u00e7\u00e3o no custeio.<\/li>\n\n\n\n<li><strong>E) Segundo a jurisprud\u00eancia majorit\u00e1ria do STF, o princ\u00edpio da irredutibilidade do valor dos benef\u00edcios refere-se apenas ao valor nominal desses benef\u00edcios, n\u00e3o resultando na garantia da concess\u00e3o de reajustes peri\u00f3dicos, caracter\u00edstica relativa \u00e0 preserva\u00e7\u00e3o do valor real.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>GABARITO: E<\/p>\n\n\n\n<p>Como podemos confirmar pela argumenta\u00e7\u00e3o apresentada acima e pelo pr\u00f3prio entendimento da banca (CESPE\/CEBRASPE, ao considerar a alternativa \u201cE\u201d correta, \u00e9 que:<\/p>\n\n\n\n<p><strong>ALTERNATIVA E (CORRETA):<\/strong> \u201c<em>Segundo a jurisprud\u00eancia majorit\u00e1ria do STF, <strong><u>o princ\u00edpio da irredutibilidade do valor dos benef\u00edcios refere-se apenas ao valor nominal desses benef\u00edcios<\/u><\/strong>, n\u00e3o resultando na garantia da concess\u00e3o de reajustes peri\u00f3dicos, caracter\u00edstica relativa \u00e0 preserva\u00e7\u00e3o do valor real\u201d. (grifos nossos).<\/em><\/p>\n\n\n\n<p><strong>Conclus\u00e3o:<\/strong><\/p>\n\n\n\n<p>Como vimos, n\u00e3o devemos confundir a garantia estampada no art. 201, \u00a74\u00ba, da CF\/88 (reajuste dos benef\u00edcios previdenci\u00e1rios, para preserva\u00e7\u00e3o do valor real), com a previs\u00e3o do art. 194, par\u00e1grafo \u00fanico, IV, da CF\/88 (que encampa o princ\u00edpio da irredutibilidade do valor dos benef\u00edcios), isto porque a previs\u00e3o do art. 194 \u00e9 mais abrangente (aplica-se \u00e0 toda Seguridade Social, que \u00e9 g\u00eanero com rela\u00e7\u00e3o \u00e0 Previd\u00eancia), e garante a manuten\u00e7\u00e3o do valor nominal de benef\u00edcios de Seguridade Social. J\u00e1 a preserva\u00e7\u00e3o do valor real, \u00e9 de aplica\u00e7\u00e3o espec\u00edfica aos benef\u00edcios previdenci\u00e1rios.<\/p>\n\n\n\n<p>O princ\u00edpio da irredutibilidade, por si s\u00f3, n\u00e3o assegura o reajustamento dos benef\u00edcios. O que assegura o reajustamento dos benef\u00edcios do RGPS, de acordo com os crit\u00e9rios definidos em lei ordin\u00e1ria, \u00e9 o princ\u00edpio da preserva\u00e7\u00e3o do valor real dos benef\u00edcios, previsto no \u00a74\u00ba do art. 201 da Constitui\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Pedido:<\/strong><\/p>\n\n\n\n<p>Diante do exposto, requer-se a altera\u00e7\u00e3o do gabarito da quest\u00e3o em ep\u00edgrafe (QUEST\u00c3O 118 &#8211; CARGO 8: ANALISTA EM CI\u00caNCIA E TECNOLOGIA PLENO I \u2013 ESPECIALIDADE: ADMINISTRA\u00c7\u00c3O DE PESSOAL) de <strong>CERTO<\/strong> para <strong>ERRADO<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-cyan-bluish-gray-background-color has-background\" id=\"port\">Concurso CNPq: recursos de Portugu\u00eas<\/h2>\n\n\n\n<p><strong>QUEST\u00c3O 1<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/g8UMUuKrbQmHrOrOFvJr-4Ztx0CaAR1cHiX3sXhOTFS1NFclFhG8l4tOlsGaa4_9ZRpzPX7643X2mRCzzWaDkPLb_yKnNyWDm876T2p-DirulTaWi8xcLAaBA6iEhOtJxSuKfBJ8PiY4Jqtos7Va-Ws\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>GABARITO PRELIMINAR DA BANCA: ERRADO<\/strong><\/p>\n\n\n\n<p><strong>GABARITO PRETENDIDO: CERTO<\/strong><\/p>\n\n\n\n<p><strong>FUNDAMENTA\u00c7\u00c3O:<\/strong><\/p>\n\n\n\n<p>O texto, que possui trechos expositivos e narrativos, traz, em seu segundo par\u00e1grafo, o relato da cria\u00e7\u00e3o do CNPq: \u201cFoi nesse caldo cultural que o almirante \u00c1lvaro Alberto ganhou mais argumento para persuadir o governo brasileiro [&#8230;]. Depois de uma longa tramita\u00e7\u00e3o na C\u00e2mara dos Deputados e no Senado Federal, nascia o CNPq [&#8230;].\u201d&nbsp;<\/p>\n\n\n\n<p>A participa\u00e7\u00e3o do f\u00edsico C\u00e9sar Lattes \u00e9 elucidada j\u00e1 no primeiro par\u00e1grafo, quando o texto destaca a sua import\u00e2ncia para a valoriza\u00e7\u00e3o da ci\u00eancia no Brasil: \u201cC\u00e9sar Lattes causou grande impacto nos meios cient\u00edficos internacionais e conquistou reconhecimento [&#8230;]\u201d. Foi a partir da institucionaliza\u00e7\u00e3o da f\u00edsica no Brasil (resultado do trabalho de divulga\u00e7\u00e3o cient\u00edfica de Lattes) que se criou um cen\u00e1rio prop\u00edcio \u00e0 cria\u00e7\u00e3o do CNPq.<\/p>\n\n\n\n<p>Com base nisso, solicita-se a altera\u00e7\u00e3o do gabarito de ERRADO para CERTO.<\/p>\n\n\n\n<p><strong>QUEST\u00c3O 3<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/fJb8yoRV0Z275Pk9DvF2lRxf3jMubaYnmd1OpwYqjJG_-JCwEd9SF3Im6Rayj7oi-EEkW1wt5STOi-45CB-nr-qEBo71-QR_tglePVCpIsLEk4_55YMTpRSxOjzMSQhQ0PUsa4WVXgJMbUD05oRep04\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>GABARITO PRELIMINAR DA BANCA: CERTO<\/strong><\/p>\n\n\n\n<p><strong>GABARITO PRETENDIDO: ERRADO<\/strong><\/p>\n\n\n\n<p><strong>FUNDAMENTA\u00c7\u00c3O:<\/strong><\/p>\n\n\n\n<p>O texto permite inferir que havia \u00e0 \u00e9poca um cen\u00e1rio internacional j\u00e1 consolidado no que tange ao fazer cient\u00edfico. Por outro lado, o Brasil ainda estava no caminho para conquistar seu espa\u00e7o: \u201cToda imprensa mundial e brasileira aclamou a descoberta, e a ci\u00eancia brasileira saiu do por\u00e3o para a sala de visitas\u201d.<\/p>\n\n\n\n<p>Quando da cria\u00e7\u00e3o do CNPq, a ci\u00eancia brasileira ainda n\u00e3o possu\u00eda&nbsp; poder de influ\u00eancia na pol\u00edtica, sendo, naquele momento, apenas uma previs\u00e3o: \u201cDutra enviou ao Congresso Nacional um anteprojeto para a cria\u00e7\u00e3o do Conselho Nacional de Pesquisas, j\u00e1 <strong>prevendo <\/strong>seu papel na pol\u00edtica nuclear\u201d (<em>grifo meu<\/em>).&nbsp;<\/p>\n\n\n\n<p>Portanto, seria um equ\u00edvoco afirmar que naquela \u00e9poca a f\u00edsica nuclear j\u00e1 se apresentava como um campo de conhecimento estrat\u00e9gico na pol\u00edtica nacional. Dessa forma, solicita-se a altera\u00e7\u00e3o do gabarito de CERTO para ERRADO.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-cyan-bluish-gray-background-color has-background\" id=\"orcamento\">Concurso CNPq: recursos de Or\u00e7amento P\u00fablico<\/h2>\n\n\n\n<p><strong>QUEST\u00c3O 39.<\/strong> O elemento organizativo central do plano plurianual (PPA) \u00e9 o programa, que consiste em um conjunto articulado de a\u00e7\u00f5es or\u00e7ament\u00e1rias, na forma de projetos, atividades e opera\u00e7\u00f5es especiais, e a\u00e7\u00f5es n\u00e3o or\u00e7ament\u00e1rias, com intuito de alcan\u00e7ar um objetivo espec\u00edfico.<\/p>\n\n\n\n<p><strong>Gabarito preliminar: CERTO<\/strong><\/p>\n\n\n\n<p><strong><u>Gabarito sugerido: ERRADO<\/u><\/strong><\/p>\n\n\n\n<p>Consolante O Manual T\u00e9cnico do Plano Plurianual 2024-2027<\/p>\n\n\n\n<p><em>\u201c<\/em><em>Os Programas cumprem o papel de materializar os objetivos estrat\u00e9gicos declarados na Dimens\u00e3o Estrat\u00e9gica do plano. Os Programas do PPA representam o conjunto coordenado de a\u00e7\u00f5es governamentais financiadas por recursos or\u00e7ament\u00e1rios e n\u00e3o or\u00e7ament\u00e1rios visando \u00e0 concretiza\u00e7\u00e3o do objetivo.\u201d<\/em><\/p>\n\n\n\n<p><em>Nota-se que o PPA \u00e9 composto por programas, que representam o conjunto coordenado de a\u00e7\u00f5es governamentais financiadas por recursos or\u00e7ament\u00e1rios e n\u00e3o or\u00e7ament\u00e1rios visando \u00e0 concretiza\u00e7\u00e3o do objetivo. Entretanto, o mesmo Manual elenca que<\/em><\/p>\n\n\n\n<p><em>\u201cas opera\u00e7\u00f5es especiais se constituem naquelas \u201cdespesas que n\u00e3o contribuem para a manuten\u00e7\u00e3o, expans\u00e3o ou aperfei\u00e7oamento das a\u00e7\u00f5es de governo no \u00e2mbito da Uni\u00e3o, das quais n\u00e3o resulta um produto e n\u00e3o geram contrapresta\u00e7\u00e3o direta sob a forma de bens ou servi\u00e7os. (&#8230;)<\/em><\/p>\n\n\n\n<p><strong><em>O PPA 2024-2027 n\u00e3o possui Programas \u201cOpera\u00e7\u00f5es Especiais\u201d, mas podem existir a\u00e7\u00f5es desta tipologia vinculadas \u00e0 programas final\u00edsticos.<\/em><\/strong><em> (&#8230;)<\/em><\/p>\n\n\n\n<p><em>A dimens\u00e3o operacional compreende o conjunto de a\u00e7\u00f5es or\u00e7ament\u00e1rias inclu\u00eddas na Lei Or\u00e7ament\u00e1ria Anual (LOA), bem como a\u00e7\u00f5es n\u00e3o or\u00e7ament\u00e1rias presentes nos Programas Final\u00edsticos do PPA.\u201d<\/em><em><\/em><\/p>\n\n\n\n<p>Tais defini\u00e7\u00f5es tamb\u00e9m constam no Manual T\u00e9cnico de Elabora\u00e7\u00e3o do PPA 2020-2023. Assim, a quest\u00e3o, da forma como consta no enunciado, ao inserir \u201cprograma, que consiste em um conjunto articulado de a\u00e7\u00f5es or\u00e7ament\u00e1rias, na forma de projetos, atividades e opera\u00e7\u00f5es especiais\u201d torna-se incorreta, uma vez que os programas de opera\u00e7\u00f5es especiais n\u00e3o constam no PPA, embora possa existir a\u00e7\u00f5es desta tipologia vinculadas \u00e0 programas final\u00edsticos.<\/p>\n\n\n\n<p>Caso o enunciado elencasse que o programa \u00e9 composto de RECURSOS or\u00e7ament\u00e1rios e n\u00e3o or\u00e7ament\u00e1rios, a\u00ed sim poder-se-ia considerar como CORRETA, uma vez que RECURSOS n\u00e3o se confunde com A\u00c7\u00c3O. As a\u00e7\u00f5es or\u00e7ament\u00e1rias (compostas por projetos, atividades e opera\u00e7\u00f5es especiais) constam no Or\u00e7amento Anual (LOA) e as n\u00e3o -or\u00e7ament\u00e1rias constam no PPA, quando associadas a programas final\u00edsticos do Governo Federal.<\/p>\n\n\n\n<p>Conforme o Manual \u201cOr\u00e7amento P\u00fablico \u2013 Or\u00e7amentos B\u00e1sicos (ENAP)\u201d<\/p>\n\n\n\n<p><em>\u201cos programas \u201copera\u00e7\u00f5es especiais\u201d, compostos integralmente por a\u00e7\u00f5es do tipo \u201copera\u00e7\u00f5es especiais\u201d.<\/em><\/p>\n\n\n\n<p><em>Esses programas figuram apenas nos or\u00e7amentos anuais e n\u00e3o constam do PPA.\u201d<\/em><\/p>\n\n\n\n<p>Al\u00e9m disso, conforme a Lei n\u00ba 13.071\/2019 (PPA 2020-2023)<\/p>\n\n\n\n<p><em>\u201cArt. 4\u00ba&nbsp; O PPA 2020-2023 reflete pol\u00edticas p\u00fablicas, orienta a atua\u00e7\u00e3o governamental e define diretrizes, objetivos, metas e programas.<\/em><\/p>\n\n\n\n<p><strong><em>\u00a7 1\u00ba&nbsp; N\u00e3o integram o PPA 2020-2023 os programas destinados exclusivamente a opera\u00e7\u00f5es especiais.\u201d [grifos nossos]<\/em><\/strong><\/p>\n\n\n\n<p>O que se repete, ainda, na Lei n\u00ba 14.802\/2024<\/p>\n\n\n\n<p><em>\u201cArt. 6\u00ba Integram o PPA 2024-2027:<\/em><\/p>\n\n\n\n<p><strong><em>\u00a7 3\u00ba N\u00e3o integram o PPA 2024-2027 os programas destinados exclusivamente a opera\u00e7\u00f5es especiais.\u201d [grifos nossos]<\/em><\/strong><\/p>\n\n\n\n<p>Dessa forma, solicita-se da estimada banca a altera\u00e7\u00e3o de gabarito para <strong>ERRADO<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-cyan-bluish-gray-background-color has-background has-medium-font-size\" id=\"cursos-assinatura\">Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso do CNPq<\/a><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos federais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"banner-estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Cursos para CNPq<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Estude conosco<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/conselho-nacional-de-desenvolvimento-cientifico-e-tecnologico-cnpq\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a os cursos<\/a>\r\n        <\/div>\r\n      <\/div>\r\n     \r\n    <\/div>\r\n\r\n  <\/div>\r\n<\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quer interpor recursos contra o gabarito do cargo 8 do concurso CNPq? Confira as possibilidades neste artigo! O concurso CNPq (Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico) teve suas \u00faltimas provas aplicadas no \u00faltimo domingo, 14 de janeiro. Com isso, j\u00e1 foram divulgados os gabaritos preliminares da etapa.&nbsp; Pretende interpor recurso para o concurso CNPq? [&hellip;]<\/p>\n","protected":false},"author":1206,"featured_media":741279,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[214992,220219],"tags":[],"tax_estado":[219963],"class_list":["post-1337648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos-administrativos","category-noticias","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal<\/title>\n<meta name=\"description\" content=\"Confira as possibilidades de recursos contra o gabarito das provas do concurso p\u00fablico CNPq. Acesse aqui nosso site!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal\" \/>\n<meta property=\"og:description\" content=\"Confira as possibilidades de recursos contra o gabarito das provas do concurso p\u00fablico CNPq. Acesse aqui nosso site!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-18T10:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-26T20:49:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruna de Andrade Fran\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna de Andrade Fran\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/\"},\"author\":{\"name\":\"Bruna de Andrade Fran\u00e7a\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855\"},\"headline\":\"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal\",\"datePublished\":\"2024-01-18T10:15:00+00:00\",\"dateModified\":\"2024-02-26T20:49:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/\"},\"wordCount\":2340,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg\",\"articleSection\":[\"Executivo (Administrativa)\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/\",\"name\":\"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg\",\"datePublished\":\"2024-01-18T10:15:00+00:00\",\"dateModified\":\"2024-02-26T20:49:15+00:00\",\"description\":\"Confira as possibilidades de recursos contra o gabarito das provas do concurso p\u00fablico CNPq. Acesse aqui nosso site!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg\",\"width\":768,\"height\":432,\"caption\":\"concurso CNPq\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855\",\"name\":\"Bruna de Andrade Fran\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g\",\"caption\":\"Bruna de Andrade Fran\u00e7a\"},\"description\":\"Bruna de Andrade Fran\u00e7a \u00e9 publicit\u00e1ria com p\u00f3s-gradua\u00e7\u00e3o em Marketing &amp; Growth, atuando h\u00e1 mais de 6 anos no universo dos concursos p\u00fablicos. Desde 2021, lidera no Blog do Estrat\u00e9gia Concursos a cobertura editorial especializada em Concursos Policiais (PF, PRF, PM, PC, etc.), al\u00e9m das frentes de concursos banc\u00e1rios, de sa\u00fade e da \u00e1rea legislativa. Especialista em reda\u00e7\u00e3o, com pr\u00e1ticas de SEO e Copywriting, possui tamb\u00e9m atua\u00e7\u00e3o pr\u00e1tica de contato direto com \u00f3rg\u00e3os p\u00fablicos respons\u00e1veis por editais, permitindo acesso antecipado a informa\u00e7\u00f5es, desdobramentos importantes e atualiza\u00e7\u00e3o eficiente dos concursos p\u00fablicos.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/bruna-andrade\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal","description":"Confira as possibilidades de recursos contra o gabarito das provas do concurso p\u00fablico CNPq. Acesse aqui nosso site!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal","og_description":"Confira as possibilidades de recursos contra o gabarito das provas do concurso p\u00fablico CNPq. Acesse aqui nosso site!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-01-18T10:15:00+00:00","article_modified_time":"2024-02-26T20:49:15+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg","type":"image\/jpeg"}],"author":"Bruna de Andrade Fran\u00e7a","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Bruna de Andrade Fran\u00e7a","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/"},"author":{"name":"Bruna de Andrade Fran\u00e7a","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855"},"headline":"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal","datePublished":"2024-01-18T10:15:00+00:00","dateModified":"2024-02-26T20:49:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/"},"wordCount":2340,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg","articleSection":["Executivo (Administrativa)","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/","name":"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg","datePublished":"2024-01-18T10:15:00+00:00","dateModified":"2024-02-26T20:49:15+00:00","description":"Confira as possibilidades de recursos contra o gabarito das provas do concurso p\u00fablico CNPq. Acesse aqui nosso site!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/05\/14154828\/cnpq-2.jpg","width":768,"height":432,"caption":"concurso CNPq"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cnpq-recursos-administracao-de-pessoal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso CNPq: os recursos para Administra\u00e7\u00e3o de Pessoal"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6630f91134abc08115cca62ce6372855","name":"Bruna de Andrade Fran\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6316d36d50cea0fadae28ed3015b8870cc90a2d3d8a95c37b44006af36a00e3?s=96&d=mm&r=g","caption":"Bruna de Andrade Fran\u00e7a"},"description":"Bruna de Andrade Fran\u00e7a \u00e9 publicit\u00e1ria com p\u00f3s-gradua\u00e7\u00e3o em Marketing &amp; Growth, atuando h\u00e1 mais de 6 anos no universo dos concursos p\u00fablicos. Desde 2021, lidera no Blog do Estrat\u00e9gia Concursos a cobertura editorial especializada em Concursos Policiais (PF, PRF, PM, PC, etc.), al\u00e9m das frentes de concursos banc\u00e1rios, de sa\u00fade e da \u00e1rea legislativa. Especialista em reda\u00e7\u00e3o, com pr\u00e1ticas de SEO e Copywriting, possui tamb\u00e9m atua\u00e7\u00e3o pr\u00e1tica de contato direto com \u00f3rg\u00e3os p\u00fablicos respons\u00e1veis por editais, permitindo acesso antecipado a informa\u00e7\u00f5es, desdobramentos importantes e atualiza\u00e7\u00e3o eficiente dos concursos p\u00fablicos.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/bruna-andrade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1337648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1206"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1337648"}],"version-history":[{"count":16,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1337648\/revisions"}],"predecessor-version":[{"id":1337853,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1337648\/revisions\/1337853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/741279"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1337648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1337648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1337648"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1337648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}