{"id":1335949,"date":"2024-02-21T11:00:00","date_gmt":"2024-02-21T14:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1335949"},"modified":"2024-02-05T21:01:14","modified_gmt":"2024-02-06T00:01:14","slug":"incidencia-icms-sefaz-ac","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/","title":{"rendered":"Incid\u00eancia do ICMS para SEFAZ AC"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-1024x683.jpg\" alt=\"Incid\u00eancia do ICMS para SEFAZ AC\" class=\"wp-image-1335987\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-1024x683.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-768x512.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-1536x1024.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-2048x1365.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-610x407.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15095813\/lago-rodeado-por-paisagem-rochosa-150x100.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Fala, concurseiro(a) batalhador(a)!! Neste artigo, vamos abordar a incid\u00eancia do ICMS para SEFAZ AC. Em breve, lan\u00e7aremos outros artigos complementando o C\u00f3digo Tribut\u00e1rio do Acre.&nbsp;<\/p>\n\n\n\n<p>Assim, destacaremos os pontos mais importantes da legisla\u00e7\u00e3o, sem nos furtamos de acrescentar alguns esclarecimentos para proporcionar uma melhor compreens\u00e3o do tema.&nbsp;<\/p>\n\n\n\n<p>Ainda, temos outros resumos sobre v\u00e1rios pontos da mat\u00e9ria, se quiser conferir, basta acessar a minha p\u00e1gina: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/robat07gmail-com\/\">https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/robat07gmail-com\/<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-incidencia-do-icms-para-sefaz-ac\"><strong>Incid\u00eancia do ICMS para SEFAZ AC<\/strong><\/h2>\n\n\n\n<p>O imposto sobre Opera\u00e7\u00f5es Relativas \u00e0 Circula\u00e7\u00e3o de Mercadorias tem como fato gerador, ( este \u00e9 o chamado aspecto temporal da hip\u00f3tese de incid\u00eancia):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Na sa\u00edda de mercadoria <\/strong>do estabelecimento:\n<ul class=\"wp-block-list\">\n<li>a <strong>qualquer t\u00edtulo ( o motivo n\u00e3o importa<\/strong>); mesmo que para outro estabelecimento do mesmo titular;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Na sa\u00edda de <strong>ouro<\/strong>:\n<ul class=\"wp-block-list\">\n<li>Na opera\u00e7\u00e3o em que este <strong>n\u00e3o for ativo financeiro ou instrumento cambial<\/strong> (\u00e9 aquele ouro adquirido <strong>para especula\u00e7\u00e3o e\/ou reserva<\/strong>);<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><mark style=\"background-color:#00d084\" class=\"has-inline-color\">Hip\u00f3teses em que <strong>n\u00e3o se pode precisar a sa\u00edda f\u00edsica<\/strong>:<\/mark>\n<ul class=\"wp-block-list\">\n<li>No <strong>desembara\u00e7o aduaneiro<\/strong> de mercadoria\/bem importado. (\u00e9 o momento que o bem est\u00e1 juridicamente \u201cliberado\u201d pela alf\u00e2ndega).<\/li>\n\n\n\n<li>Na aquisi\u00e7\u00e3o em<strong> licita\u00e7\u00e3o p\u00fablica<\/strong> de mercadorias ou bens <strong>importados <\/strong>do exterior e <strong>apreendidos ou abandonados<\/strong>;<\/li>\n\n\n\n<li>Na <strong>transmiss\u00e3o a terceiro<\/strong> de mercadoria depositada em armaz\u00e9m geral ou em dep\u00f3sito fechado, no Estado do Acre;\n<ul class=\"wp-block-list\">\n<li>a) <strong>armaz\u00e9m geral \u00e9 um local que guarda bens de terceiros<\/strong>; contrasta com dep\u00f3sito fechado, que \u00e9 um local de guarda do pr\u00f3prio contribuinte;&nbsp;<\/li>\n\n\n\n<li>Nesse caso, n\u00e3o h\u00e1 uma sa\u00edda do estabelecimento, j\u00e1 que ele est\u00e1 e outro lugar. Por isso, o uso do termo \u201ctransmiss\u00e3o\u201d, seria <strong>a circula\u00e7\u00e3o apenas jur\u00eddica do bem.<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>da <strong>transmiss\u00e3o de propriedade<\/strong> de mercadoria, ou do t\u00edtulo que a represente, quando esta <strong>n\u00e3o transitar pelo estabelecimento transmitente;<\/strong>\n<ul class=\"wp-block-list\">\n<li>Similar \u00e0 situa\u00e7\u00e3o anterior.<strong> <\/strong>Aqui<strong> a mercadoria \u00e9 remetida diretamente ao destinat\u00e1rio.<\/strong><\/li>\n\n\n\n<li>Seria o caso de um loja de varejo do uma ind\u00fastria de m\u00f3veis.<strong> <\/strong>A loja vende uma estante que ainda est\u00e1 na f\u00e1brica.<strong> Assim, que h\u00e1 a transmiss\u00e3o de propriedade, a f\u00e1brica remete o m\u00f3vel ao consumidor final.<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fornecimento de <strong>alimenta\u00e7\u00e3o, bebidas<\/strong> e outras mercadorias, por qualquer estabelecimento, <strong>inclu\u00eddos os servi\u00e7os prestados<\/strong>;\n<ul class=\"wp-block-list\">\n<li>Pela <strong>literalidade<\/strong>, at\u00e9 mesmo as<strong> gorjetas est\u00e3o na base de c\u00e1lculo<\/strong>.<\/li>\n\n\n\n<li>Aten\u00e7\u00e3o para o fato de que o Conv\u00eanio CONFAZ n\u00b0 78\/2017 autorizou a exclus\u00e3o dessa rubrica da BC do ICMS, desde que limitada a 10%. Mas a efetividade disso depende de cada uma das unidades federadas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-topicos-agrupados\">T\u00f3picos Agrupados<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">Situa\u00e7\u00f5es de incid\u00eancia do ICMS em que a mercadoria \u00e9 tributada na <strong>Entrada do Acre, <\/strong>proveniente de outra unidade federada<strong>:<\/strong><\/mark>\n<ul class=\"wp-block-list\">\n<li>Quando a mercadoria estiver <strong>sujeita ao regime de pagamento antecipado<\/strong> do imposto, <strong>exceto quando se tratar de servi\u00e7o de transporte proveniente do exterior<\/strong>;<\/li>\n\n\n\n<li>bens ou servi\u00e7os, adquiridos por contribuinte do imposto,<strong> destinados ao uso, consumo ou ativo permanente;<\/strong><\/li>\n\n\n\n<li>lubrificantes e combust\u00edveis l\u00edquidos e gasosos derivados de <strong>petr\u00f3leo e energia el\u00e9trica<\/strong>;\n<ul class=\"wp-block-list\">\n<li><strong>quando n\u00e3o destinados \u00e0 comercializa\u00e7\u00e3o ou \u00e0 industrializa\u00e7\u00e3o.<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>mercadoria a ser comercializada<strong> sem destinat\u00e1rio certo<\/strong> ou destinada a estabelecimento em situa\u00e7\u00e3o cadastral irregular;\n<ul class=\"wp-block-list\">\n<li>Caso de um vendedor itinerante, que vende seus produtos \u201cpelo caminho\u201d.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><mark style=\"background-color:#8ed1fc\" class=\"has-inline-color\">Situa\u00e7\u00f5es de<strong> incid\u00eancia diversa da circula\u00e7\u00e3o de mercadorias<\/strong>:<\/mark>\n<ul class=\"wp-block-list\">\n<li>No <strong>in\u00edcio da presta\u00e7\u00e3o de servi\u00e7os de transporte:<\/strong>\n<ul class=\"wp-block-list\">\n<li>&nbsp;interestadual e intermunicipal, <strong>por qualquer via,<\/strong> de pessoas, bens, mercadorias ou valores;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Na presta\u00e7\u00e3o<strong> onerosa de servi\u00e7os de comunica\u00e7\u00e3o<\/strong>, por qualquer meio, inclusive a gera\u00e7\u00e3o, a emiss\u00e3o, a recep\u00e7\u00e3o, a transmiss\u00e3o, a retransmiss\u00e3o, a repeti\u00e7\u00e3o e a amplia\u00e7\u00e3o de comunica\u00e7\u00e3o de qualquer natureza;\n<ul class=\"wp-block-list\">\n<li>A presta\u00e7\u00e3o desse servi\u00e7o de forma gratuita \u00e9 um caso de imunidade (al\u00ednea d do inciso X do \u00a7 2\u00ba do art. 155 da CF\/88).<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>No recebimento<\/strong>, pelo destinat\u00e1rio, de servi\u00e7o prestado ou cujas presta\u00e7\u00f5es tenham <strong>sido iniciadas no exterior;<\/strong>\n<ul class=\"wp-block-list\">\n<li>Essa \u00e9 a hip\u00f3tese de um <strong>servi\u00e7o de comunica\u00e7\u00e3o<\/strong> proveniente do exterior<strong>.<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>No <strong>ato final <\/strong>do<strong> transporte iniciado no exterior<\/strong>;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><mark style=\"background-color:#00d084\" class=\"has-inline-color\">Incid\u00eancias antievasivas (as hip\u00f3teses seguintes t\u00eam a clara ideia de colaborar com a fiscaliza\u00e7\u00e3o tribut\u00e1ria):<\/mark>\n<ul class=\"wp-block-list\">\n<li>da<strong> entrada ou do recebimento<\/strong> de mercadoria, do bem ou do servi\u00e7o no estabelecimento do adquirente ou em outro por ele indicado, para <strong>efeito de exig\u00eancia do imposto por substitui\u00e7\u00e3o tribut\u00e1ria;&nbsp;<\/strong>\n<ul class=\"wp-block-list\">\n<li>Se o contribuinte j\u00e1 foi designado como substituto, n\u00e3o h\u00e1 por que aguardar outro momento para a incid\u00eancia tribut\u00e1ria.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>da <strong>constata\u00e7\u00e3o da exist\u00eancia de estabelecimento em situa\u00e7\u00e3o cadastral irregular<\/strong>, em rela\u00e7\u00e3o ao estoque de mercadorias nele encontrado;<\/li>\n\n\n\n<li>da verifica\u00e7\u00e3o da exist\u00eancia de mercadoria ou servi\u00e7o de <strong>situa\u00e7\u00e3o irregular;<\/strong><\/li>\n\n\n\n<li>do<strong> encerramento das atividades<\/strong> do contribuinte.<\/li>\n\n\n\n<li>da<strong> utiliza\u00e7\u00e3o<\/strong>,<strong> por contribuinte,<\/strong> de servi\u00e7o cuja presta\u00e7\u00e3o se tenha <strong>iniciado em outro Estado<\/strong> e <strong>n\u00e3o esteja vinculada<\/strong> a opera\u00e7\u00e3o ou presta\u00e7\u00e3o subsequente;\n<ul class=\"wp-block-list\">\n<li>Se n\u00e3o \u00e9 poss\u00edvel atingir o prestador de outra localidade e n\u00e3o h\u00e1 opera\u00e7\u00e3o subsequente, \u201ccobra-se\u201d&nbsp; o contribuinte no Estado, na utiliza\u00e7\u00e3o.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>do<strong> in\u00edcio da presta\u00e7\u00e3o de servi\u00e7o de transporte<\/strong> interestadual, nas presta\u00e7\u00f5es <strong>n\u00e3o vinculadas <\/strong>a opera\u00e7\u00e3o ou presta\u00e7\u00e3o subsequente;\n<ul class=\"wp-block-list\">\n<li>cujo <strong>tomador n\u00e3o seja contribuinte<\/strong> do imposto <strong>domiciliado <\/strong>ou estabelecido no Acre;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>da <strong>sa\u00edda<\/strong>, de estabelecimento de contribuinte, de bem ou mercadoria <strong>destinado a consumidor final n\u00e3o contribuinte<\/strong> do imposto domiciliado no Acre.\n<ul class=\"wp-block-list\">\n<li>Como \u201ccobrar\u201d o Jo\u00e3ozinho da esquina? melhor que haja a incid\u00eancia na loja que vendeu para o Jo\u00e3ozinho.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-icms-iss-incidencia-do-icms-para-sefaz-ac\"><strong>ICMS + ISS &#8211; Incid\u00eancia do ICMS para SEFAZ AC<\/strong><\/h2>\n\n\n\n<p>A legisla\u00e7\u00e3o ainda equipara certas situa\u00e7\u00f5es a sa\u00eddas de mercadoria, vamos a elas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>fornecimento de mercadorias com presta\u00e7\u00e3o de servi\u00e7os:\n<ul class=\"wp-block-list\">\n<li>quando <strong>ressalvado pela lei de incid\u00eancia do ISS<\/strong>( vide LC 116\/03- apresentaremos os itens de forma sintetizada). <\/li>\n\n\n\n<li>Nos itens seguintes, h\u00e1 situa\u00e7\u00f5es de<strong> incid\u00eancia cumulativa<\/strong> do ICMS (sobre mercadoria) com ISS (sobre servi\u00e7os) <strong>e situa\u00e7\u00f5es de incid\u00eancia exclusiva do ICMS <\/strong>(sobre o servi\u00e7o e a mercadoria) a depender de determinada situa\u00e7\u00e3o:\n<ol class=\"wp-block-list\">\n<li>mercadorias produzidas pelo prestador de servi\u00e7os<strong> fora do local da presta\u00e7\u00e3o<\/strong> &#8211; Execu\u00e7\u00e3o de obras. <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">(ICMS sobre mercadorias)<\/mark><\/li>\n\n\n\n<li>mercadorias produzidas pelo prestador de servi\u00e7os <strong>fora do local da presta\u00e7\u00e3o<\/strong> &#8211; \u00a0 Repara\u00e7\u00e3o, conserva\u00e7\u00e3o e reforma de edif\u00edcios, etc. <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">(ICMS sobre mercadorias)<\/mark><\/li>\n\n\n\n<li>Composi\u00e7\u00e3o gr\u00e1fica (\u201cfolhetos\u201d) <strong>para posterior opera\u00e7\u00e3o de comercializa\u00e7\u00e3o e industrializa\u00e7\u00e3o.<\/strong> <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">(ICMS sobre mercadorias)<\/mark><\/li>\n\n\n\n<li><strong>Pe\u00e7as<\/strong> empregadas em <strong>conserto<\/strong> de m\u00e1quinas.<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">(ICMS sobre mercadorias)<\/mark><\/li>\n\n\n\n<li>Pe\u00e7as empregadas em<strong> recondicionamento de motores.<\/strong> <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">(ICMS sobre mercadorias)<\/mark><\/li>\n\n\n\n<li>Fornecimento de <strong>alimenta\u00e7\u00e3o em festas (buf\u00ea)<\/strong> &#8211; o fornecimento de alimenta\u00e7\u00e3o e bebidas fica sujeito ao ICMS.<\/li>\n\n\n\n<li>O produto do servi\u00e7o de <strong>alfaiataria com material fornecido pela loja<\/strong>. &#8211;<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-pink-color\">ICMS sobre tudo<\/mark> ( esse \u00e9 o caso de quem compra uma camisa em uma loja de departamento, ou alfaiate que tem todo o material, em vez de ir a um estabelecimento levando os tecidos que ser\u00e3o cosidos.)<\/li>\n\n\n\n<li>Instala\u00e7\u00e3o e montagem de aparelhos <strong>quando o instalador al\u00e9m do servi\u00e7o leva o equipamento a ser instalado.<\/strong> <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-pink-color\">ICMS sobre tudo<\/mark><\/li>\n\n\n\n<li>Coloca\u00e7\u00e3o de <strong>tapetes com material fornecido pelo prestador<\/strong> do servi\u00e7o. <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-light-green-cyan-color\">ICMS sobre tudo<\/mark><\/li>\n<\/ol>\n<\/li>\n\n\n\n<li>quando o fornecimento da mercadoria n\u00e3o tiver rela\u00e7\u00e3o com o servi\u00e7o, ou seja, <strong>quando fora do campo de incid\u00eancia do ISS.<\/strong> \n<ul class=\"wp-block-list\">\n<li>ICMS incide normalmente sobre a mercadoria.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-1024x684.jpg\" alt=\"Fatos irrelevantes para a incid\u00eancia do ICMS\" class=\"wp-image-1336003\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-1024x684.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-768x513.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-1536x1025.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-2048x1367.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-610x407.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101233\/ainda-vida-da-representacao-da-cadeia-de-suprimentos-150x100.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao-incidencia-do-icms-para-sefaz-ac\"><strong>Conclus\u00e3o- <\/strong>Incid\u00eancia do ICMS para SEFAZ AC<\/h2>\n\n\n\n<p>Cabe destacar que esse resumo \u00e9 focado na legisla\u00e7\u00e3o, n\u00e3o \u00e9 um estudo completo da mat\u00e9ria. Ressaltamos ainda que nem todos os artigos e par\u00e1grafos da legisla\u00e7\u00e3o est\u00e3o aqui, trazemos apenas o que possui maior cobran\u00e7a em provas.<\/p>\n\n\n\n<p>Ademais, o aluno deve procurar as aulas em PDF, pois nelas o professor aborda a jurisprud\u00eancia e a doutrina associadas a cada um dos itens estudados. Apenas assim, o aluno consegue dominar completamente a banca escolhida.<\/p>\n\n\n\n<p>Por fim, na assinatura Platinum, \u00e9 poss\u00edvel um acompanhamento profissional para lhes indicar o caminho correto a tomar, o que estudar e como estudar: esse \u00e9 nosso servi\u00e7o de Coaching. Nos vemos l\u00e1!<\/p>\n\n\n\n<p>Um abra\u00e7o.<\/p>\n\n\n\n<p>Rodrigo Batalha<\/p>\n\n\n\n<p><a href=\"https:\/\/www.instagram.com\/coach.rodrigobatalha\/\">https:\/\/www.instagram.com\/coach.rodrigobatalha\/<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos<\/h2>\n\n\n\n<p class=\"has-text-align-center has-black-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\">Concursos 2024<\/a><\/p>\n\n\n\n<p>imagens: <\/p>\n\n\n\n<p>Imagem de &lt;a href=&#8221;<a href=\"https:\/\/br.freepik.com\/fotos-gratis\/ainda-vida-da-representacao-da-cadeia-de-suprimentos_33412396.htm#query=circula%C3%A7%C3%A3o%20mercadoria&amp;position=16&amp;from_view=search&amp;track=ais&amp;uuid=b8e7fa43-1c8e-47fc-a8b8-2e901b4940da\">https:\/\/br.freepik.com\/fotos-gratis\/ainda-vida-da-representacao-da-cadeia-de-suprimentos_33412396.htm#query=circula%C3%A7%C3%A3o%20mercadoria&amp;position=16&amp;from_view=search&amp;track=ais&amp;uuid=b8e7fa43-1c8e-47fc-a8b8-2e901b4940da<\/a>&#8220;&gt;Freepik&lt;\/a&gt;<\/p>\n\n\n\n<p>Imagem de &lt;a href=&#8221;https:\/\/br.freepik.com\/fotos-gratis\/lago-rodeado-por-paisagem-rochosa_4885987.htm#query=Rio%20Branco&amp;position=14&amp;from_view=search&amp;track=ais&amp;uuid=37fe0d28-4eb2-46c6-be00-5ea20447dcfa&#8221;&gt;Freepik&lt;\/a&gt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fala, concurseiro(a) batalhador(a)!! Neste artigo, vamos abordar a incid\u00eancia do ICMS para SEFAZ AC. Em breve, lan\u00e7aremos outros artigos complementando o C\u00f3digo Tribut\u00e1rio do Acre.&nbsp; Assim, destacaremos os pontos mais importantes da legisla\u00e7\u00e3o, sem nos furtamos de acrescentar alguns esclarecimentos para proporcionar uma melhor compreens\u00e3o do tema.&nbsp; Ainda, temos outros resumos sobre v\u00e1rios pontos da [&hellip;]<\/p>\n","protected":false},"author":2202,"featured_media":1336006,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[220252,50294,221703,40],"tax_estado":[219964,219963],"class_list":["post-1335949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-concursosfiscais","tag-estudaqueavidamuda","tag-sefazac","tag-concurso","tax_estado-ac","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Incid\u00eancia do ICMS para SEFAZ AC<\/title>\n<meta name=\"description\" content=\"Aten\u00e7\u00e3o futuros auditores!! super resumo da incid\u00eancia do ICMS para SEFAZ AC. Material com a qualidade do Estrat\u00e9gia e de gra\u00e7a, n\u00e3o perca!!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incid\u00eancia do ICMS para SEFAZ AC\" \/>\n<meta property=\"og:description\" content=\"Aten\u00e7\u00e3o futuros auditores!! super resumo da incid\u00eancia do ICMS para SEFAZ AC. Material com a qualidade do Estrat\u00e9gia e de gra\u00e7a, n\u00e3o perca!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-21T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rodrigo Augusto Batalha Alves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rodrigo Augusto Batalha Alves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/\"},\"author\":{\"name\":\"Rodrigo Augusto Batalha Alves\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f\"},\"headline\":\"Incid\u00eancia do ICMS para SEFAZ AC\",\"datePublished\":\"2024-02-21T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/\"},\"wordCount\":1525,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg\",\"keywords\":[\"#concursosfiscais\",\"#estudaqueavidamuda\",\"#sefazac\",\"Concurso\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/\",\"name\":\"Incid\u00eancia do ICMS para SEFAZ AC\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg\",\"datePublished\":\"2024-02-21T14:00:00+00:00\",\"description\":\"Aten\u00e7\u00e3o futuros auditores!! super resumo da incid\u00eancia do ICMS para SEFAZ AC. Material com a qualidade do Estrat\u00e9gia e de gra\u00e7a, n\u00e3o perca!!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incid\u00eancia do ICMS para SEFAZ AC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f\",\"name\":\"Rodrigo Augusto Batalha Alves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g\",\"caption\":\"Rodrigo Augusto Batalha Alves\"},\"description\":\"Cargo Atual: Auditor Fiscal da Receita do Distrito Federal; Aprova\u00e7\u00f5es: SEFAZ DF, Analista de Controle Externo do TCE PE, TRE RJ, TRE SP, Ag\u00eancia Nacional de Minera\u00e7\u00e3o (ANM), Col\u00e9gio Naval; Mestre em Direito pela Universidade Cat\u00f3lica de Bras\u00edlia; P\u00f3s-graduado em Direito Tribut\u00e1rio e Direito Econ\u00f4mico e Financeiro Graduado em Ci\u00eancias Atuariais.\",\"sameAs\":[\"https:\/\/www.instagram.com\/rd.batalha\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/robat07gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Incid\u00eancia do ICMS para SEFAZ AC","description":"Aten\u00e7\u00e3o futuros auditores!! super resumo da incid\u00eancia do ICMS para SEFAZ AC. Material com a qualidade do Estrat\u00e9gia e de gra\u00e7a, n\u00e3o perca!!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/","og_locale":"pt_BR","og_type":"article","og_title":"Incid\u00eancia do ICMS para SEFAZ AC","og_description":"Aten\u00e7\u00e3o futuros auditores!! super resumo da incid\u00eancia do ICMS para SEFAZ AC. Material com a qualidade do Estrat\u00e9gia e de gra\u00e7a, n\u00e3o perca!!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-02-21T14:00:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg","type":"image\/jpeg"}],"author":"Rodrigo Augusto Batalha Alves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rodrigo Augusto Batalha Alves","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/"},"author":{"name":"Rodrigo Augusto Batalha Alves","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f"},"headline":"Incid\u00eancia do ICMS para SEFAZ AC","datePublished":"2024-02-21T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/"},"wordCount":1525,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg","keywords":["#concursosfiscais","#estudaqueavidamuda","#sefazac","Concurso"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/","name":"Incid\u00eancia do ICMS para SEFAZ AC","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg","datePublished":"2024-02-21T14:00:00+00:00","description":"Aten\u00e7\u00e3o futuros auditores!! super resumo da incid\u00eancia do ICMS para SEFAZ AC. Material com a qualidade do Estrat\u00e9gia e de gra\u00e7a, n\u00e3o perca!!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2024\/01\/15101356\/lago-rodeado-por-paisagem-rochosa-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/incidencia-icms-sefaz-ac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Incid\u00eancia do ICMS para SEFAZ AC"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/aa0bf103f86069bff16b1ddfb510b18f","name":"Rodrigo Augusto Batalha Alves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54f78a13020d62df814fe30a9ecf7fac2702db4f0b5ec9af6f0bc06ea8f1c178?s=96&d=mm&r=g","caption":"Rodrigo Augusto Batalha Alves"},"description":"Cargo Atual: Auditor Fiscal da Receita do Distrito Federal; Aprova\u00e7\u00f5es: SEFAZ DF, Analista de Controle Externo do TCE PE, TRE RJ, TRE SP, Ag\u00eancia Nacional de Minera\u00e7\u00e3o (ANM), Col\u00e9gio Naval; Mestre em Direito pela Universidade Cat\u00f3lica de Bras\u00edlia; P\u00f3s-graduado em Direito Tribut\u00e1rio e Direito Econ\u00f4mico e Financeiro Graduado em Ci\u00eancias Atuariais.","sameAs":["https:\/\/www.instagram.com\/rd.batalha\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/robat07gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1335949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2202"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1335949"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1335949\/revisions"}],"predecessor-version":[{"id":1347659,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1335949\/revisions\/1347659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1336006"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1335949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1335949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1335949"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1335949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}