{"id":1324215,"date":"2024-01-30T14:00:00","date_gmt":"2024-01-30T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1324215"},"modified":"2024-01-10T17:19:09","modified_gmt":"2024-01-10T20:19:09","slug":"sumula-663-stj","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/","title":{"rendered":"S\u00famula 663 do STJ: publicada em 2023"},"content":{"rendered":"\n<p>Hoje, vamos conhecer um pouco a respeito da <strong>s\u00famula 663 do STJ<\/strong>, publicada em <strong>13\/11\/2023<\/strong>, dando enfoque aos temas mais cobrados na \u00e1rea dos <strong>concursos de carreira jur\u00eddica<\/strong>.<\/p>\n\n\n\n<p>Vamos l\u00e1!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/20121004\/pensao-morte-1024x640.jpg\" alt=\"S\u00famula 663 do STJ\" class=\"wp-image-1324216\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/20121004\/pensao-morte-1024x640.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/20121004\/pensao-morte-300x188.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/20121004\/pensao-morte-768x480.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/20121004\/pensao-morte-610x381.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/20121004\/pensao-morte-150x94.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/20121004\/pensao-morte.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">S\u00famula 663 do STJ<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-sumula-663-do-stj-redacao\">1<strong>. S\u00famula 663 do STJ: reda\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p>O STJ, recentemente, editou a seguinte s\u00famula:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>S\u00famula 663 \u2013<\/strong> A pens\u00e3o por morte de servidor p\u00fablico federal pode ser concedida ao filho <strong><mark style=\"background-color:#7bdcb5\" class=\"has-inline-color\">inv\u00e1lido<\/mark><\/strong> de <strong><mark style=\"background-color:#8ed1fc\" class=\"has-inline-color\">qualquer idade<\/mark><\/strong>, <strong>desde que a invalidez seja <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">anterior<\/mark> ao \u00f3bito<\/strong>.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Como se v\u00ea, a nova s\u00famula trata a respeito da pens\u00e3o por morte de servidor p\u00fablico federal destinada ao <strong>filho inv\u00e1lido<\/strong>.<\/p>\n\n\n\n<p>Vejamos, adiante, algumas <strong>peculiaridades<\/strong> acerca do novo entendimento sumular exarado pelo STJ, bem como alguns assuntos correlatos ao tema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-sumula-663-do-stj-conceitos-relevantes\">2. <strong>S\u00famula 663 do STJ: conceitos relevantes<\/strong><\/h2>\n\n\n\n<p>A <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8112cons.htm\">Lei 8.112\/90<\/a> disp\u00f5e sobre o <strong>regime jur\u00eddico dos servidores p\u00fablicos civis<\/strong> <strong>da Uni\u00e3o<\/strong>, das autarquias e das funda\u00e7\u00f5es p\u00fablicas federais. Em rela\u00e7\u00e3o \u00e0 <strong>pens\u00e3o por morte do servidor<\/strong>, assim estabelece o art. 215 da aludida lei:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Art. 215, Lei 8.112\/90 <\/strong>&#8211; Por morte do servidor, os seus <strong>dependentes<\/strong>, nas hip\u00f3teses legais, fazem jus \u00e0 <strong>pens\u00e3o por morte<\/strong>, observados os limites estabelecidos no&nbsp;<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/Constituicao\/Constituicao.htm#art37xi\">inciso XI do caput do art. 37 da Constitui\u00e7\u00e3o Federal<\/a>&nbsp;e no&nbsp;<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_Ato2004-2006\/2004\/Lei\/L10.887.htm#art2\">art. 2\u00ba da Lei n\u00ba 10.887, de 18 de junho de 2004<\/a>.&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Al\u00e9m disso, o <strong>art. 217 da <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8112cons.htm\">Lei 8.112\/90<\/a><\/strong> estabelece quais s\u00e3o os <strong>benefici\u00e1rios<\/strong> da pens\u00e3o. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-nesse-sentido\">Nesse sentido:<\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Art.&nbsp;217, Lei 8.112\/90<\/strong> <strong>&#8211;<\/strong>&nbsp;S\u00e3o <strong>benefici\u00e1rios<\/strong> das pens\u00f5es:<br \/><strong>I &#8211; <\/strong>o c\u00f4njuge;&nbsp;<br \/><strong>II &#8211; <\/strong>o c\u00f4njuge divorciado ou separado judicialmente ou de fato, com percep\u00e7\u00e3o de pens\u00e3o aliment\u00edcia estabelecida judicialmente;&nbsp;<br \/><strong>III &#8211;<\/strong> o companheiro ou companheira que comprove uni\u00e3o est\u00e1vel como entidade familiar;<br \/><strong>IV &#8211;<\/strong> o <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">filho<\/mark><\/strong> de qualquer condi\u00e7\u00e3o que <strong>atenda a UM<\/strong> dos seguintes requisitos:&nbsp;&nbsp;&nbsp;<br \/><strong>a) <\/strong>seja <strong>menor de 21 (vinte e um) anos<\/strong>;<br \/><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">b) seja inv\u00e1lido;<\/mark><\/strong><br \/><strong>c)<\/strong> tenha <strong>defici\u00eancia <\/strong>grave; ou&nbsp;&nbsp;&nbsp;<br \/><strong>d) <\/strong>tenha <strong>defici\u00eancia<\/strong> intelectual ou mental;&nbsp;&nbsp;<br \/><strong>V &#8211; <\/strong>a m\u00e3e e o pai que comprovem depend\u00eancia econ\u00f4mica do servidor; e&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br \/><strong>VI &#8211; <\/strong>o irm\u00e3o de qualquer condi\u00e7\u00e3o que comprove depend\u00eancia econ\u00f4mica do servidor e atenda a um dos requisitos previstos no inciso IV.&nbsp;<br \/><strong>\u00a7 1<sup>o<\/sup>&nbsp;<\/strong>A concess\u00e3o de pens\u00e3o aos benefici\u00e1rios de que tratam os <strong>incisos I a IV <\/strong>do<strong>&nbsp;<\/strong>caput&nbsp;<strong>exclui <\/strong>os benefici\u00e1rios referidos nos<strong> incisos V e VI<\/strong>.&nbsp;<br \/><strong>\u00a7 2<sup>o<\/sup><\/strong>&nbsp;A concess\u00e3o de pens\u00e3o aos benefici\u00e1rios de que trata o <strong>inciso V<\/strong> do&nbsp;caput&nbsp;<strong>exclui <\/strong>o benefici\u00e1rio referido no<strong> inciso VI<\/strong>.&nbsp;<br \/><strong>\u00a7 3<sup>o<\/sup>&nbsp;<\/strong>O enteado e o menor tutelado <strong>equiparam-se a filho <\/strong>mediante declara\u00e7\u00e3o do servidor e desde que comprovada <strong>depend\u00eancia econ\u00f4mica<\/strong>, na forma estabelecida em regulamento.&nbsp;&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">ATEN\u00c7\u00c3O<\/mark><\/strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">:<\/mark> observe que o filho do servidor, para fazer jus \u00e0 pens\u00e3o por morte, necessita preencher <strong>APENAS UM <\/strong>dos requisitos elencados nas al\u00edneas do inciso IV do art.\u00a0217 da Lei 8.112\/90. Portanto, <strong>n\u00e3o<\/strong> s\u00e3o <strong>exig\u00eancias cumulativas<\/strong>.<\/p>\n\n\n\n<p>Visto essas premissas, passemos \u00e0 an\u00e1lise das peculiaridades da <strong>s\u00famula 663 do STJ<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-sumula-663-do-stj-peculiaridades\"><strong>3. S\u00famula 663 do STJ: peculiaridades<\/strong><\/h2>\n\n\n\n<p>Conforme o art. 217, IV, b, da <strong><a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8112cons.htm\">Lei 8.112\/90<\/a><\/strong>, o <strong>filho inv\u00e1lido<\/strong> \u00e9 benefici\u00e1rio da <strong>pens\u00e3o por morte<\/strong>. Nesse ponto, a s\u00famula 663 do STJ vem trazer algumas caracter\u00edsticas, a saber:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>O filho inv\u00e1lido pode ter <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">QUALQUER IDADE<\/mark><\/strong>;<\/li>\n\n\n\n<li>A invalidez deve ocorrer <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">ANTES<\/mark><\/strong> do \u00f3bito.<\/li>\n<\/ol>\n\n\n\n<p>Para maiores esclarecimentos, vejamos o seguinte exemplo:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Rafael \u00e9 servidor p\u00fablico federal e no dia <strong>01\/01\/2024<\/strong> falece em decorr\u00eancia de um mal s\u00fabito. No dia <strong>02\/01\/2024<\/strong>, seu filho M\u00e1rcio, de 28 anos, fica inv\u00e1lido em raz\u00e3o de um acidente de tr\u00e2nsito. <strong>Questiona-se: <\/strong>o filho M\u00e1rcio ter\u00e1 direito \u00e0 pens\u00e3o por morte?<br \/>Segundo entendimento do STJ exarado na <strong>s\u00famula 663<\/strong>, o filho n\u00e3o ter\u00e1 direito \u00e0 pens\u00e3o, visto que a invalidez ocorreu <strong>AP\u00d3S<\/strong> o \u00f3bito do servidor.<br \/>Por\u00e9m, se a invalidez tivesse ocorrido <strong>ANTES<\/strong> do \u00f3bito (por exemplo, no dia 31\/12\/2023), o filho teria direito \u00e0 pens\u00e3o por morte.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Vencido esse ponto, vejamos, no pr\u00f3ximo t\u00f3pico, a jurisprud\u00eancia correlata.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-sumula-663-do-stj-jurisprudencia-correlata\"><strong>4. S\u00famula 663 do STJ: jurisprud\u00eancia correlata<\/strong><\/h2>\n\n\n\n<p>O entendimento firmado pelo STJ na s\u00famula 663 j\u00e1 vinha sendo aplicado em diversos julgados. Nesse sentido:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Para ter direito \u00e0&nbsp;pens\u00e3o&nbsp;por&nbsp;morte,&nbsp;a norma legal (inciso IV do artigo 217 da Lei n. 8.112\/1990) <strong>n\u00e3o condiciona que a invalidez deva preceder \u00e0 maioridade da autora.<\/strong> N\u00e3o cabe ao Poder Judici\u00e1rio dar interpreta\u00e7\u00e3o extensiva proibitiva sobre aquilo que n\u00e3o est\u00e1 contido no texto legal e que n\u00e3o corresponde \u00e0 vontade literal do legislador, sobretudo, para justificar a retirada de um direito&#8221; (REsp n\u00ba 1.954.926\/PB, Rel. Min. Benedito Gon\u00e7alves, decis\u00e3o publicada no DJe de 01\/09\/2021).<br \/>4. &#8220;A Segunda Turma desta Corte, em reiterados julgados, tem se posicionado no sentido de que a&nbsp;pens\u00e3o&nbsp;por&nbsp;morte&nbsp;tempor\u00e1ria prevista no art. 217 da Lei n.\u00b0 8.112\/1990 pode ser concedida ao&nbsp;filho inv\u00e1lido&nbsp;de <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">qualquer idade<\/mark><\/strong>, independentemente da data em que se iniciou a invalidez, <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">desde que anterior ao&nbsp;\u00f3bito&nbsp;do instituidor<\/mark><\/strong> (STJ, REsp n\u00ba 1.899.272\/PE, Rel. Min. Og Fernandes, DJe de 29\/03\/2021). <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-filho-invalido-e-insuficiencia-economica\"><strong>5. Filho inv\u00e1lido e insufici\u00eancia econ\u00f4mica<\/strong><\/h2>\n\n\n\n<p>No estudo da s\u00famula 663 do STJ, \u00e9 importante fazermos o seguinte questionamento: todo e qualquer filho inv\u00e1lido de servidor p\u00fablico federal falecido, <strong>independentemente de sua situa\u00e7\u00e3o econ\u00f4mica<\/strong>, ter\u00e1 direito \u00e0 pens\u00e3o por morte?<\/p>\n\n\n\n<p>Da <strong>an\u00e1lise meramente literal<\/strong> da legisla\u00e7\u00e3o sobre o tema, \u00e9 poss\u00edvel verificar que <strong>n\u00e3o existe qualquer questionamento sobre a quest\u00e3o econ\u00f4mica<\/strong> para a concess\u00e3o da pens\u00e3o por morte. <\/p>\n\n\n\n<p>Por\u00e9m, \u00e9 necess\u00e1rio realizar uma <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">interpreta\u00e7\u00e3o <\/mark><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">teleol\u00f3gica ou finalista <\/mark><\/strong>na legisla\u00e7\u00e3o de reg\u00eancia, isto \u00e9, buscar a <strong>verdadeira finalidade<\/strong> da norma jur\u00eddica. Aplicando essa exegese, \u00e9 poss\u00edvel concluir que a norma tem por <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">finalidade <\/mark>proteger ECONOMICAMENTE o filho inv\u00e1lido cujo genitor faleceu<\/strong>. <\/p>\n\n\n\n<p>Em verdade, existe uma <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">presun\u00e7\u00e3o<\/mark><\/strong> de que, uma vez sendo inv\u00e1lido o filho, ele n\u00e3o possui condi\u00e7\u00f5es de manter o seu pr\u00f3prio sustento. Todavia, essa <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">presun\u00e7\u00e3o \u00e9 relativa<\/mark><\/strong>, admitindo prova em contr\u00e1rio acerca da situa\u00e7\u00e3o econ\u00f4mica favor\u00e1vel do filho. <\/p>\n\n\n\n<p>Assim, em caso de <strong>situa\u00e7\u00e3o econ\u00f4mica favor\u00e1vel<\/strong>, o filho inv\u00e1lido <strong>n\u00e3o <\/strong>ter\u00e1 direito \u00e0 pens\u00e3o por morte, sob pena de <strong>enriquecimento il\u00edcito<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-como-consequencia-podemos-afirmar\">Como consequ\u00eancia, podemos afirmar:<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se o filho \u00e9 inv\u00e1lido e <strong>N\u00c3O<\/strong> tem condi\u00e7\u00f5es econ\u00f4micas de prover seu pr\u00f3prio sustento: <strong>tem direito \u00e0 pens\u00e3o por morte<\/strong>;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se o filho \u00e9 inv\u00e1lido, mas <strong>TEM<\/strong> condi\u00e7\u00f5es econ\u00f4micas de prover seu pr\u00f3prio sustento: <strong>n\u00e3o <\/strong>tem direito \u00e0 pens\u00e3o por morte.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-nesse-sentido-assim-decidiu-o-stj-2022\">Nesse sentido, assim decidiu o <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">STJ-2022<\/mark><\/strong>:<\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>IV. Todavia, o Tribunal de origem, com base no exame dos elementos f\u00e1ticos dos autos, reformou a senten\u00e7a de proced\u00eancia, consignando que <strong>n\u00e3o obstante a Lei n\u00ba 8.112\/90 n\u00e3o exigir prova da insufici\u00eancia econ\u00f4mica para a concess\u00e3o de&nbsp;pens\u00e3o&nbsp;por&nbsp;morte&nbsp;ao&nbsp;filho inv\u00e1lido<\/strong>,&nbsp;pois se entende que tal depend\u00eancia \u00e9 presumida, o entendimento desta Quarta Turma \u00e9 no sentido de que a<strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> finalidade <\/mark><\/strong>da lei \u00e9 dar amparo alimentar aos benefici\u00e1rios do&nbsp;servidor&nbsp;falecido, assim a <strong>presun\u00e7\u00e3o de depend\u00eancia econ\u00f4mica do&nbsp;filho&nbsp;maior e&nbsp;inv\u00e1lido&nbsp;\u00e9 relativa<\/strong>, admitindo prova em contr\u00e1rio a fim de <strong>evitar enriquecimento il\u00edcito do benefici\u00e1rio<\/strong>, quando houver nos autos prova capaz de desconstituir tal presun\u00e7\u00e3o. No caso concreto, verifica-se da documenta\u00e7\u00e3o acostada aos autos que o autor det\u00e9m <strong>aposentadoria por invalidez<\/strong> pelo Regime Geral da Previd\u00eancia cujo valor bruto \u00e9 no montante de R$ 5.965,26 (cinco mil, novecentos e sessenta e cinco reais e vinte e seis centavos), o que lhe retira a condi\u00e7\u00e3o de dependente da servidora falecida. <strong>O fato de o autor ter o plano de sa\u00fade por sua genitora, n\u00e3o o faz dependente economicamente<\/strong>, at\u00e9 porque n\u00e3o h\u00e1 provas outras que possam demonstrar a depend\u00eancia em rela\u00e7\u00e3o \u00e0 ex-servidora, nem mesmo a coabita\u00e7\u00e3o. As despesas m\u00e9dicas apresentadas n\u00e3o representam fator de depend\u00eancia, visto que a renda percebida pelo autor permite custe\u00e1-las, n\u00e3o prejudicando os meios de prover sua subsist\u00eancia, de forma que n\u00e3o faz jus o autor \u00e0 concess\u00e3o do benef\u00edcio requerido (STJ, T2, AgInt no REsp 1962256 \/ AL, Rel. Ministra Assusete Magalh\u1ebds, DJe em 15\/06\/2022).<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Diante das considera\u00e7\u00f5es acima, resta evidente que a <strong>quest\u00e3o econ\u00f4mica \u00e9 de suma import\u00e2ncia<\/strong> no momento da an\u00e1lise de concess\u00e3o ou n\u00e3o da pens\u00e3o por morte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-hipoteses-de-perda-do-direito-a-pensao-por-morte\"><strong>6. Hip\u00f3teses de perda do direito \u00e0 pens\u00e3o por morte<\/strong><\/h2>\n\n\n\n<p>Por fim, vale a pena relembrarmos as hip\u00f3teses de <strong>perda do direito \u00e0 pens\u00e3o por morte <\/strong>previstas na lei.<\/p>\n\n\n\n<p>O <strong>art. 220 da <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8112cons.htm\">Lei 8.112\/90<\/a><\/strong> estabelece as hip\u00f3teses em que o benefici\u00e1rio <strong>perde tal direito<\/strong>. Nesse sentido:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">HIP\u00d3TESES<\/mark><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">COMENT\u00c1RIO<\/mark><\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>I &#8211; <\/strong>ap\u00f3s o <strong>tr\u00e2nsito em julgado<\/strong>, o benefici\u00e1rio <strong>condenado<\/strong> pela pr\u00e1tica de <strong>crime<\/strong> de que tenha <strong>dolosamente<\/strong> resultado a <strong>morte do servidor<\/strong>;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Perceba que o crime deve ser praticado <strong>dolosamente<\/strong>, vale dizer, quando a pessoa quer o resultado ou assume o risco de produzi-lo. No caso, o resultado \u00e9 a <strong>morte do servidor <\/strong>p\u00fablico.<br \/>Al\u00e9m disso, <strong>n\u00e3o basta a decis\u00e3o meramente condenat\u00f3ria<\/strong>, sendo essencial o seu <strong>tr\u00e2nsito em julgado<\/strong>.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>II &#8211;<\/strong> o <strong>c\u00f4njuge<\/strong>, o <strong>companheiro<\/strong> ou a companheira se comprovada, a <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">qualquer tempo<\/mark><\/strong>, <strong>simula\u00e7\u00e3o ou fraude no casamento ou na uni\u00e3o est\u00e1vel<\/strong>, ou a formaliza\u00e7\u00e3o desses com o fim exclusivo de constituir benef\u00edcio previdenci\u00e1rio, apuradas em <strong>processo judicial <\/strong>no qual ser\u00e1 assegurado o direito ao contradit\u00f3rio e \u00e0 ampla defesa.&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Observe que a prova pode ser produzida a <strong>qualquer tempo<\/strong>, apurada via <strong>processo judicial<\/strong>.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Feitas essas considera\u00e7\u00f5es, finalizamos, assim, mais um importante tema pertinente \u00e0 <strong>s\u00famula 663 do STJ<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusao\"><strong>Conclus\u00e3o<\/strong><\/h2>\n\n\n\n<p>Hoje, vimos um pouco a respeito da <strong>s\u00famula 663 do STJ<\/strong>, em especial acerca de sua <strong>extens\u00e3o<\/strong> e <strong>caracter\u00edsticas<\/strong> principais.<\/p>\n\n\n\n<p>Finalizamos, por ora, mais um tema empolgante para os que almejam a sonhada carreira jur\u00eddica.<\/p>\n\n\n\n<p>Advertimos que <strong>esse artigo<\/strong>, juntamente com as quest\u00f5es do <a href=\"https:\/\/concursos.estrategia.com\/\"><u><strong>Sistema de Quest\u00f5es do Estrat\u00e9gia Concursos<\/strong><\/u><\/a>, serve como complemento ao estudo do tema proposto, devendo-se priorizar o material te\u00f3rico, em <strong>PDF<\/strong> ou <strong>videoaula<\/strong>, do curso.<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Quer saber mais sobre os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a> e <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2024\/\">Concursos 2024<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje, vamos conhecer um pouco a respeito da s\u00famula 663 do STJ, publicada em 13\/11\/2023, dando enfoque aos temas mais cobrados na \u00e1rea dos concursos de carreira jur\u00eddica. Vamos l\u00e1! 1. S\u00famula 663 do STJ: reda\u00e7\u00e3o O STJ, recentemente, editou a seguinte s\u00famula: S\u00famula 663 \u2013 A pens\u00e3o por morte de servidor p\u00fablico federal pode [&hellip;]<\/p>\n","protected":false},"author":2703,"featured_media":1324411,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,2185],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1324215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-carreiras-juridicas","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S\u00famula 663 do STJ: publicada em 2023<\/title>\n<meta name=\"description\" content=\"Hoje, vamos conhecer a s\u00famula 663 do STJ, publicada em 13\/11\/2023, dando enfoque aos temas mais cobrados na \u00e1rea dos concursos jur\u00eddicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00famula 663 do STJ: publicada em 2023\" \/>\n<meta property=\"og:description\" content=\"Hoje, vamos conhecer a s\u00famula 663 do STJ, publicada em 13\/11\/2023, dando enfoque aos temas mais cobrados na \u00e1rea dos concursos jur\u00eddicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heloana Albuquerque\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heloana Albuquerque\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/\"},\"author\":{\"name\":\"Heloana Albuquerque\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0a914cb3dc4c9fb549b38d2d5528f23c\"},\"headline\":\"S\u00famula 663 do STJ: publicada em 2023\",\"datePublished\":\"2024-01-30T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/\"},\"wordCount\":1812,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Jur\u00eddico\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/\",\"name\":\"S\u00famula 663 do STJ: publicada em 2023\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg\",\"datePublished\":\"2024-01-30T17:00:00+00:00\",\"description\":\"Hoje, vamos conhecer a s\u00famula 663 do STJ, publicada em 13\/11\/2023, dando enfoque aos temas mais cobrados na \u00e1rea dos concursos jur\u00eddicos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00famula 663 do STJ: publicada em 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0a914cb3dc4c9fb549b38d2d5528f23c\",\"name\":\"Heloana Albuquerque\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/24ae914faa49e70cf228cfa75150ff826756fa9dbbadf55254a1c17b67917d8a?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/24ae914faa49e70cf228cfa75150ff826756fa9dbbadf55254a1c17b67917d8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/24ae914faa49e70cf228cfa75150ff826756fa9dbbadf55254a1c17b67917d8a?s=96&d=mm&r=g\",\"caption\":\"Heloana Albuquerque\"},\"description\":\"Aprovada para Oficial de Justi\u00e7a Avaliador Federal, Analista Judici\u00e1rio do Tribunal de Justi\u00e7a, Analista do Minist\u00e9rio P\u00fablico, Procurador Municipal e Juiz Leigo do JEC.\",\"award\":[\"L\u00e1urea universit\u00e1ria no Curso de Direito\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/heloana_olehhotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S\u00famula 663 do STJ: publicada em 2023","description":"Hoje, vamos conhecer a s\u00famula 663 do STJ, publicada em 13\/11\/2023, dando enfoque aos temas mais cobrados na \u00e1rea dos concursos jur\u00eddicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/","og_locale":"pt_BR","og_type":"article","og_title":"S\u00famula 663 do STJ: publicada em 2023","og_description":"Hoje, vamos conhecer a s\u00famula 663 do STJ, publicada em 13\/11\/2023, dando enfoque aos temas mais cobrados na \u00e1rea dos concursos jur\u00eddicos.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-01-30T17:00:00+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg","type":"image\/jpeg"}],"author":"Heloana Albuquerque","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Heloana Albuquerque","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/"},"author":{"name":"Heloana Albuquerque","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0a914cb3dc4c9fb549b38d2d5528f23c"},"headline":"S\u00famula 663 do STJ: publicada em 2023","datePublished":"2024-01-30T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/"},"wordCount":1812,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg","articleSection":["Concursos P\u00fablicos","Jur\u00eddico"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/","name":"S\u00famula 663 do STJ: publicada em 2023","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg","datePublished":"2024-01-30T17:00:00+00:00","description":"Hoje, vamos conhecer a s\u00famula 663 do STJ, publicada em 13\/11\/2023, dando enfoque aos temas mais cobrados na \u00e1rea dos concursos jur\u00eddicos.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/12\/21063118\/pensao-morte-1.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/sumula-663-stj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"S\u00famula 663 do STJ: publicada em 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/0a914cb3dc4c9fb549b38d2d5528f23c","name":"Heloana Albuquerque","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/24ae914faa49e70cf228cfa75150ff826756fa9dbbadf55254a1c17b67917d8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/24ae914faa49e70cf228cfa75150ff826756fa9dbbadf55254a1c17b67917d8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/24ae914faa49e70cf228cfa75150ff826756fa9dbbadf55254a1c17b67917d8a?s=96&d=mm&r=g","caption":"Heloana Albuquerque"},"description":"Aprovada para Oficial de Justi\u00e7a Avaliador Federal, Analista Judici\u00e1rio do Tribunal de Justi\u00e7a, Analista do Minist\u00e9rio P\u00fablico, Procurador Municipal e Juiz Leigo do JEC.","award":["L\u00e1urea universit\u00e1ria no Curso de Direito"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/heloana_olehhotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1324215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2703"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1324215"}],"version-history":[{"count":34,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1324215\/revisions"}],"predecessor-version":[{"id":1328397,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1324215\/revisions\/1328397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1324411"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1324215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1324215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1324215"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1324215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}