{"id":1299376,"date":"2024-01-08T14:00:00","date_gmt":"2024-01-08T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1299376"},"modified":"2023-12-12T22:13:18","modified_gmt":"2023-12-13T01:13:18","slug":"domicilio-tributario-hipotese-incidencia","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/","title":{"rendered":"O Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia"},"content":{"rendered":"\n<p>Ol\u00e1 turma, como est\u00e3o os estudos? Estamos aqui para comentar um caso importante julgado pelo STF que atestou a diferen\u00e7a entre dois institutos do direito tribut\u00e1rio: o domic\u00edlio tribut\u00e1rio e o aspecto espacial (ou territorial) da hip\u00f3tese de incid\u00eancia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"303\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png\" alt=\"Aspecto espacial de hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS.\" class=\"wp-image-712716\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png 445w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4-300x204.png 300w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><figcaption class=\"wp-element-caption\">Aspecto espacial de hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS<\/figcaption><\/figure>\n\n\n\n<p>Conforme a doutrina especializada<a id=\"_ftnref1\" href=\"#_ftn1\"><sup>[1]<\/sup><\/a>, a obriga\u00e7\u00e3o tribut\u00e1ria surge a partir da ocorr\u00eancia, no mundo dos fatos, de determinada situa\u00e7\u00e3o hipot\u00e9tica prevista em lei em sentido estrito, a qual \u00e9 denominada, em geral, de hip\u00f3tese de incid\u00eancia ou fato gerador.<\/p>\n\n\n\n<p>A hip\u00f3tese de incid\u00eancia, por sua vez, possui determinados aspectos f\u00e1ticos, os quais autorizam a conclus\u00e3o de sua ocorr\u00eancia em concreto. A doutrina<a id=\"_ftnref2\" href=\"#_ftn2\"><sup>[2]<\/sup><\/a> aponta que, \u201cPara efeitos did\u00e1ticos a hip\u00f3tese de incid\u00eancia pode ser cindida em cinco aspectos ou crit\u00e9rios: no antecedente, figuram os aspectos material, espacial, e temporal; no consequente, os crit\u00e9rios pessoal e quantitativo\u201d.<\/p>\n\n\n\n<p>No aspecto quantitativo do consequente da hip\u00f3tese de incid\u00eancia, encontramos as al\u00edquotas e a base de c\u00e1lculo dos tributos, que permitem aferir a quantia que deve ser desembolsada pelo sujeito passivo da obriga\u00e7\u00e3o tribut\u00e1ria em favor do fisco.<\/p>\n\n\n\n<p>J\u00e1 no antecedente, aparece o aspecto material da norma tribut\u00e1ria, que define a hip\u00f3tese de incid\u00eancia, caracterizado pelo pr\u00f3prio fato ou estado objeto da tributa\u00e7\u00e3o.<\/p>\n\n\n\n<p>O aspecto temporal indica o momento em que se deve considerar ocorrido o fato gerador. E, no que importa ao presente texto, o aspecto espacial aponta o \u201cterrit\u00f3rio em que a ocorr\u00eancia do fato implica o surgimento da obriga\u00e7\u00e3o tribut\u00e1ria\u201d<a id=\"_ftnref3\" href=\"#_ftn3\"><sup>[3]<\/sup><\/a>.<\/p>\n\n\n\n<p>O  objetivo do presente texto \u00e9 apresentar uma distin\u00e7\u00e3o entre o aspecto espacial da hip\u00f3tese de incid\u00eancia e a no\u00e7\u00e3o de domic\u00edlio tribut\u00e1rio do contribuinte realizada pelo STF.<\/p>\n\n\n\n<p>Com efeito, relacionado \u00e0 ideia de obriga\u00e7\u00e3o tribut\u00e1ria, encontramos a no\u00e7\u00e3o de domic\u00edlio tribut\u00e1rio do sujeito passivo (contribuinte ou respons\u00e1vel tribut\u00e1rio). Segundo Eduardo Sabbag<a id=\"_ftnref4\" href=\"#_ftn4\"><sup>[4]<\/sup><\/a>, \u201cEm Direito Tribut\u00e1rio, domic\u00edlio \u00e9 o lugar onde o sujeito passivo \u00e9 chamado a cumprir seus deveres de ordem tribut\u00e1ria\u201d.<\/p>\n\n\n\n<p>As caracter\u00edsticas do domic\u00edlio tribut\u00e1rio est\u00e3o positivadas no art. 127 do CTN, sendo, como regra, declarado pelo pr\u00f3prio sujeito passivo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Art. 127. Na falta de elei\u00e7\u00e3o, pelo contribuinte ou respons\u00e1vel, de domic\u00edlio tribut\u00e1rio, na forma da legisla\u00e7\u00e3o aplic\u00e1vel, considera-se como tal: I &#8211; quanto \u00e0s pessoas naturais, a sua resid\u00eancia habitual, ou, sendo esta incerta ou desconhecida, o centro habitual de sua atividade; II &#8211; quanto \u00e0s pessoas jur\u00eddicas de direito privado ou \u00e0s firmas individuais, o lugar da sua sede, ou, em rela\u00e7\u00e3o aos atos ou fatos que derem origem \u00e0 obriga\u00e7\u00e3o, o de cada estabelecimento; III &#8211; quanto \u00e0s pessoas jur\u00eddicas de direito p\u00fablico, qualquer de suas reparti\u00e7\u00f5es no territ\u00f3rio da entidade tributante.<\/li>\n\n\n\n<li>\u00a7 1\u00ba Quando n\u00e3o couber a aplica\u00e7\u00e3o das regras fixadas em qualquer dos incisos deste artigo, considerar-se-\u00e1 como domic\u00edlio tribut\u00e1rio do contribuinte ou respons\u00e1vel o lugar da situa\u00e7\u00e3o dos bens ou da ocorr\u00eancia dos atos ou fatos que deram origem \u00e0 obriga\u00e7\u00e3o.<\/li>\n\n\n\n<li>\u00a7 2\u00ba A autoridade administrativa pode recusar o domic\u00edlio eleito, quando impossibilite ou dificulte a arrecada\u00e7\u00e3o ou a fiscaliza\u00e7\u00e3o do tributo, aplicando-se ent\u00e3o a regra do par\u00e1grafo anterior.<\/li>\n<\/ul>\n\n\n\n<p>Conforme alerta a doutrina especializada, \u201c\u00e9 comum as pessoas, f\u00edsicas e jur\u00eddicas, terem pluralidade de domic\u00edlios fiscais. Basta que a pessoa f\u00edsica seja propriet\u00e1ria de um im\u00f3vel em outra cidade, que n\u00e3o aquela em que fixou seu domic\u00edlio para efeitos do IR e j\u00e1 ter\u00e1 dois, sendo o outro para fins de IPTU. Com as pessoas jur\u00eddicas, ent\u00e3o, \u00e9 fato corriqueiro, se houver matriz e filiais, porquanto o princ\u00edpio da autonomia do estabelecimento faz de cada filial uma unidade independente, nos casos do IPI e do ICMS\u201d<a id=\"_ftnref5\" href=\"#_ftn5\"><sup>[5]<\/sup><\/a>.<\/p>\n\n\n\n<p>Ademais, \u00e9 de se notar que o tema do domic\u00edlio tribut\u00e1rio est\u00e1 diretamente relacionado ao aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria, o que implica \u201climites l\u00f3gicos\u201d a impedir o legislador de fixar o domic\u00edlio tribut\u00e1rio para al\u00e9m das fronteiras geogr\u00e1ficas alcan\u00e7adas pela norma tribut\u00e1ria<a id=\"_ftnref6\" href=\"#_ftn6\"><sup>[6]<\/sup><\/a>.<\/p>\n\n\n\n<p>Entretanto, o Supremo Tribunal Federal estabeleceu, em s\u00edntese, que a lei tribut\u00e1ria precisa definir o aspecto espacial da sua hip\u00f3tese de incid\u00eancia, ainda que este n\u00e3o coincida com o domic\u00edlio tribut\u00e1rio do sujeito passivo, sob pena de inconstitucionalidade por afronta ao princ\u00edpio da seguran\u00e7a jur\u00eddica.<\/p>\n\n\n\n<p>Vejamos as justificativas apresentadas pelo STF.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-domicilio-tributario-e-o-aspecto-espacial-d-a-hipotese-de-incidencia-do-iss\"><strong>Domic\u00edlio tribut\u00e1rio e <\/strong><strong>o aspecto espacial d<\/strong>a hip\u00f3tese de incid\u00eancia do ISS<\/h2>\n\n\n\n<p>Vamos analisar agora o seguinte problema: qual a rela\u00e7\u00e3o entre o domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia em seu aspecto espacial?<\/p>\n\n\n\n<p>Conforme ensina a doutrina, a lei que veicula a hip\u00f3tese de incid\u00eancia tribut\u00e1ria deve apresentar, ainda que implicitamente, todos os aspectos indispens\u00e1veis para que se possa atestar a exist\u00eancia e o conte\u00fado da da obriga\u00e7\u00e3o tribut\u00e1ria<a id=\"_ftnref7\" href=\"#_ftn7\"><sup>[7]<\/sup><\/a>.<\/p>\n\n\n\n<p>Nesses termos, a referida lei deve indicar \u201cqual a situa\u00e7\u00e3o geradora da obriga\u00e7\u00e3o tribut\u00e1ria (aspecto material da hip\u00f3tese de incid\u00eancia), onde a sua ocorr\u00eancia \u00e9 relevante (aspecto espacial) e quando se deve considerar ocorrida (aspecto temporal), bem como quem est\u00e1 obrigado ao pagamento (aspecto pessoal: sujeito passivo), em favor de quem (aspecto pessoal: sujeito ativo), e qual o montante devido (aspecto quantitativo)<a id=\"_ftnref8\" href=\"#_ftn8\"><sup>[8]<\/sup><\/a>\u201d.<\/p>\n\n\n\n<p>Esses aspectos fazem parte de um todo indissoci\u00e1vel, devendo ser harm\u00f4nicos entre si, de modo que uma norma que almeja impor determinada hip\u00f3tese de incid\u00eancia tribut\u00e1ria, se for incompleta, por insufici\u00eancia de dados relativos aos seus aspectos, n\u00e3o permite ao sujeito passivo aferir a certeza da obriga\u00e7\u00e3o, nem o seu conte\u00fado, sendo incapaz de constituir a obriga\u00e7\u00e3o tribut\u00e1ria<a id=\"_ftnref9\" href=\"#_ftn9\"><sup>[9]<\/sup><\/a>.<\/p>\n\n\n\n<p>Nesses termos, verifica-se a rela\u00e7\u00e3o entre o domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia com o princ\u00edpio constitucional da seguran\u00e7a jur\u00eddica.<\/p>\n\n\n\n<p>Com base nessa linha argumentativa, o STF, na ADI 5835 e na ADPF 499, recebida como a\u00e7\u00e3o direta, reconheceu a inconstitucionalidade, por afronta ao princ\u00edpio da seguran\u00e7a jur\u00eddica, das Leis Complementares n. 157\/2016 e 175\/2020, as quais alteraram a LC n. 116\/2023, com o objetivo de fixar o aspecto espacial do Imposto sobre servi\u00e7os de qualquer natureza (ISS\/ISSQN \u2013 art. 156, III, da CF\/1988) no domic\u00edlio do tomador dos servi\u00e7os, em determinadas hip\u00f3teses de incid\u00eancia.<\/p>\n\n\n\n<p>Com efeito, as referidas leis complementares pretenderam fixaram, no domic\u00edlio do tomador, a hip\u00f3tese de incid\u00eancia do ISS quanto aos seguintes servi\u00e7os:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>planos de medicina de grupo ou individual&nbsp; (subitens 4.22 e 4.23 da lista anexa \u00e0 LC 116\/2003);<\/li>\n\n\n\n<li>administra\u00e7\u00e3o de fundos quaisquer e de carteira de cliente;<\/li>\n\n\n\n<li>administra\u00e7\u00e3o de cons\u00f3rcios;<\/li>\n\n\n\n<li>administra\u00e7\u00e3o de cart\u00e3o de cr\u00e9dito, cart\u00e3o de d\u00e9bito e cong\u00eaneres (subitem 15.01 da lista anexa \u00e0 LC 116\/2003);<\/li>\n\n\n\n<li>arrendamento mercantil.<\/li>\n<\/ul>\n\n\n\n<p>Num primeiro momento, a LC n. 157\/2016 definiu tamb\u00e9m que, em rela\u00e7\u00e3o ao arrendamento mercantil, o valor do imposto seria devido ao Munic\u00edpio declarado como <strong>domic\u00edlio tribut\u00e1rio<\/strong> da pessoa jur\u00eddica ou f\u00edsica tomadora do servi\u00e7o, conforme informa\u00e7\u00e3o prestada por esta.<\/p>\n\n\n\n<p>O STF, por ocasi\u00e3o do pedido liminar, suspendeu a vig\u00eancia da LC 157\/16, pois n\u00e3o trouxe com clareza o conceito de \u201ctomador de servi\u00e7os\u201d, gerando inseguran\u00e7a jur\u00eddica, risco de dupla tributa\u00e7\u00e3o, al\u00e9m da inexist\u00eancia de correta incid\u00eancia tribut\u00e1ria e da impossibilidade de aplica\u00e7\u00e3o pr\u00e1tica da norma.<\/p>\n\n\n\n<p>Nesse contexto, o legislador editou a LC n. 175\/2020, objetivando delimitar o conceito de tomador de servi\u00e7os, no seguinte sentido:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00a0Como regra geral, o tomador ser\u00e1 o contratante do servi\u00e7o, salvo nas situa\u00e7\u00f5es descritas a seguir (art. 3\u00ba, \u00a7 5\u00ba);<\/li>\n\n\n\n<li>No caso de plano de sa\u00fade (subitens 4.22 e 4.23), o tomador ser\u00e1 a pessoa f\u00edsica benefici\u00e1ria vinculada \u00e0 operadora por meio de conv\u00eanio ou contrato (art. 3\u00ba, \u00a7 6\u00ba);<\/li>\n\n\n\n<li>No caso de administra\u00e7\u00e3o de cart\u00e3o de cr\u00e9dito, cart\u00e3o de d\u00e9bito e cong\u00eaneres (subitem 15.01), o tomador ser\u00e1 o primeiro titular do cart\u00e3o (art. 3\u00ba, \u00a7 8\u00ba);<\/li>\n\n\n\n<li>No caso de transfer\u00eancias realizadas por meio de cart\u00e3o de cr\u00e9dito ou d\u00e9bito, ou a eles conexo, por bandeira, por credenciadoras ou por emissoras (subitem 15.01), o local do estabelecimento credenciado ser\u00e1 considerado o domic\u00edlio do tomador (art. 3\u00ba, \u00a7 9\u00ba);<\/li>\n\n\n\n<li>No caso de administra\u00e7\u00e3o de carteira de valores mobili\u00e1rios, de fundos e clubes de investimento (subitem 15.01), o tomador ser\u00e1 o cotista (art. 3\u00ba, \u00a7 10);<\/li>\n\n\n\n<li>No caso de administra\u00e7\u00e3o de cons\u00f3rcios, o tomador ser\u00e1 o consorciado (art. 3\u00ba, \u00a7 11);<\/li>\n\n\n\n<li>No caso de arrendamento mercantil, o tomador ser\u00e1 o arrendat\u00e1rio ou benefici\u00e1rio (art. 3\u00ba, \u00a7 12);<\/li>\n<\/ul>\n\n\n\n<p>Entretanto, mesmo tendo havido a conceitua\u00e7\u00e3o da figura do tomador de servi\u00e7os pelo legislador, o STF manteve seu entendimento quanto \u00e0 afronta ao princ\u00edpio da seguran\u00e7a jur\u00eddica, pois n\u00e3o houve uma adequada defini\u00e7\u00e3o do domic\u00edlio desse tomador de servi\u00e7os.<\/p>\n\n\n\n<p>De fato, a norma n\u00e3o identificou corretamente o aspecto espacial da hip\u00f3tese de incid\u00eancia por ela previsto (o domic\u00edlio do tomador de servi\u00e7os), mesmo tendo como objetivo fazer incidir o ISS em favor do munic\u00edpio desse tomador, o qual, nas hip\u00f3teses de incid\u00eancia afetadas pela lei, poderia ser, por exemplo, o endere\u00e7o cadastrado no momento da contrata\u00e7\u00e3o, o domic\u00edlio civil do tomador ou \u201cmesmo o seu domic\u00edlio fiscal\u201d<a id=\"_ftnref10\" href=\"#_ftn10\"><sup>[10]<\/sup><\/a>.<\/p>\n\n\n\n<p>Com efeito, n\u00e3o teriam sido solucionadas ainda quest\u00f5es atinentes \u00e0 hip\u00f3tese de o tomador ter domic\u00edlio no exterior, de ele ter mais de um domic\u00edlio, de qual esp\u00e9cie de domic\u00edlio est\u00e1-se a tratar (civil, domic\u00edlio tribut\u00e1rio ou o declarado), das modifica\u00e7\u00f5es de domic\u00edlio em um mesmo exerc\u00edcio financeiro etc.<\/p>\n\n\n\n<p>A indetermina\u00e7\u00e3o das Leis n. 157 e 175, em rela\u00e7\u00e3o ao aspecto espacial da regra-matriz da hip\u00f3tese de incid\u00eancia do ISSQN gera at\u00e9 risco de guerra fiscal, porquanto h\u00e1 \u2018\u2018espa\u00e7o consider\u00e1vel para mais de um sujeito ativo estar legitimado\u201d[12].<\/p>\n\n\n\n<p>Ressalte-se que o STF, no mesmo julgamento, admitiu que o legislador complementar poderia ter adotado qualquer local para fins de hip\u00f3tese de incid\u00eancia do ISS, desde que n\u00e3o fosse \u201cdesconexo com a presta\u00e7\u00e3o dos respectivos servi\u00e7os\u201d<a id=\"_ftnref11\" href=\"#_ftn11\"><sup>[11]<\/sup><\/a>.<\/p>\n\n\n\n<p>Em outras palavras, o Supremo entendeu que o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria podem ser diferentes em rela\u00e7\u00e3o ao imposto sobre servi\u00e7os.<\/p>\n\n\n\n<p>Ademais, pode-se extrair desse julgado o entendimento preconizado por Leandro Paulsen, segundo o qual a norma impositiva incompleta, por insufici\u00eancia de dados acerca dos aspectos da sua hip\u00f3tese de incid\u00eancia,<strong> \u201cn\u00e3o pode ser suplementada por regulamento em face da reserva absoluta de lei<\/strong>\u201d<a id=\"_ftnref13\" href=\"#_ftn13\"><sup>[13]<\/sup><\/a>.<\/p>\n\n\n\n<p>Com efeito, a LC 175 chegou a estabelecer um sistema padronizado de obriga\u00e7\u00f5es acess\u00f3rias relativas ao ISS, o qual, segundo o Ministro Nunes Marques \u2013 que ficou vencido no julgamento da ADI 5835 \u2013, possibilitaria resolver as pend\u00eancias referentes ao local em que devido o imposto (aspecto espacial da hip\u00f3tese de incid\u00eancia), sem a interfer\u00eancia do legislador complementar<a id=\"_ftnref14\" href=\"#_ftn14\"><sup>[14]<\/sup><\/a>.<\/p>\n\n\n\n<p>Entretanto, infere-se do entendimento da maioria do STF que essa possibilidade n\u00e3o foi suficiente para afastar a viola\u00e7\u00e3o \u00e0 seguran\u00e7a jur\u00eddica pelas normas impugnadas, pois essas pend\u00eancias deveriam estar resolvidas na pr\u00f3pria lei.<\/p>\n\n\n\n<p>Em outras palavras, nos termos da doutrina de Leandro Paulsen e do entendimento do STF, o aspecto espacial da hip\u00f3tese de incid\u00eancia deve estar delimitado, ainda que implicitamente, na pr\u00f3pria lei e n\u00e3o em normas infralegais. <\/p>\n\n\n\n<p>Ademais, pode-se concluir tamb\u00e9m que o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia n\u00e3o precisam necessariamente coincidir, em rela\u00e7\u00e3o ao ISS. De fato, o domic\u00edlio tribut\u00e1rio de um contribuinte pode ser em um munic\u00edpio e esse mesmo contribuinte pode ser devedor de ISS cuja hip\u00f3tese de incid\u00eancia foi considerada ocorrida em outro, diferente do de seu domic\u00edlio tribut\u00e1rio.<\/p>\n\n\n\n<p>Enfim, podemos sintetizar o entendimento do STF nos seguintes termos: sob pena de inconstitucionalidade por afronta ao princ\u00edpio da seguran\u00e7a jur\u00eddica, a lei que objetiva impor a cobran\u00e7a do ISS deve estabelecer em si pr\u00f3pria o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria, o qual pode ser diverso do domic\u00edlio tribut\u00e1rio do sujeito passivo desse imposto, desde que n\u00e3o seja \u201ctotalmente desconexo com a presta\u00e7\u00e3o dos respectivos servi\u00e7os\u201d<a href=\"#_ftn15\" id=\"_ftnref15\"><sup>[15]<\/sup><\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\"><sup>[1]<\/sup><\/a> COSTA, Regina Helena. Curso de Direito Tribut\u00e1rio. S\u00e3o Paulo: Saraiva, 4. Ed., 2013. P. 219.<\/p>\n\n\n\n<p><a href=\"#_ftnref2\" id=\"_ftn2\"><sup>[2]<\/sup><\/a> Idem, p. 227.<\/p>\n\n\n\n<p><a href=\"#_ftnref3\" id=\"_ftn3\"><sup>[3]<\/sup><\/a> PAULSEN, Leandro. Curso de Direito Tribut\u00e1rio Completo. S\u00e3o Paulo: Saraiva, 11. Ed., 2020. P. 313.<\/p>\n\n\n\n<p><a href=\"#_ftnref4\" id=\"_ftn4\"><sup>[4]<\/sup><\/a> SABBAG, Eduardo. C\u00f3digo Tribunal Nacional Comentado. S\u00e3o Paulo: M\u00e9todo. 2. Ed. 2018. P. 397.<\/p>\n\n\n\n<p><a href=\"#_ftnref5\" id=\"_ftn5\"><sup>[5]<\/sup><\/a> CARVALHO, Paulo de Barros. Curso de Direito Tribut\u00e1rio. S\u00e3o Paulo: Saraiva, 30. Ed., 2019. P. 389.<\/p>\n\n\n\n<p><a href=\"#_ftnref6\" id=\"_ftn6\"><sup>[6]<\/sup><\/a> Idem, p. 390.<\/p>\n\n\n\n<p><a href=\"#_ftnref7\" id=\"_ftn7\"><sup>[7]<\/sup><\/a> PAULSEN, Leandro. Curso de Direito Tribut\u00e1rio Completo. S\u00e3o Paulo: Saraiva, 11. Ed., 2020. P. 313.<\/p>\n\n\n\n<p><a href=\"#_ftnref8\" id=\"_ftn8\"><sup>[8]<\/sup><\/a> Idem, p. 314.<\/p>\n\n\n\n<p><a href=\"#_ftnref9\" id=\"_ftn9\"><sup>[9]<\/sup><\/a> Ibidem, p. 314.<\/p>\n\n\n\n<p><a id=\"_ftn10\" href=\"#_ftnref10\"><sup>[10]<\/sup><\/a> <a href=\"https:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=TP&amp;docID=769402168\">ADI 5835, Relator(a): ALEXANDRE DE MORAES, Tribunal Pleno, julgado em 05-06-2023, PROCESSO ELETR\u00d4NICO DJe-s\/n DIVULG 26-07-2023 PUBLIC 27-07-2023. P. 52<\/a>.<\/p>\n\n\n\n<p><a href=\"#_ftnref11\" id=\"_ftn11\"><sup>[11]<\/sup><\/a> Idem, p. 42.<\/p>\n\n\n\n<p><a href=\"#_ftnref12\" id=\"_ftn12\"><sup>[12]<\/sup><\/a> Idem, p. 52.<\/p>\n\n\n\n<p><a href=\"#_ftnref13\" id=\"_ftn13\"><sup>[13]<\/sup><\/a> PAULSEN, Leandro. Curso de Direito Tribut\u00e1rio Completo. S\u00e3o Paulo: Saraiva, 11. Ed., 2020. P. 314.<\/p>\n\n\n\n<p><a href=\"#_ftnref14\" id=\"_ftn14\"><sup>[14]<\/sup><\/a> ADI 5835, Relator(a): ALEXANDRE DE MORAES, Tribunal Pleno, julgado em 05-06-2023, PROCESSO ELETR\u00d4NICO DJe-s\/n DIVULG 26-07-2023 PUBLIC 27-07-2023. P. 67.<\/p>\n\n\n\n<p><a id=\"_ftn15\" href=\"#_ftnref15\"><sup>[15]<\/sup><\/a> Idem, p. 42.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS.<\/p>\n","protected":false},"author":2637,"featured_media":712716,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[40,535,212800,212798],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1299376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-concurso","tag-direito-tributario","tag-domicilio-tributario","tag-fato-gerador","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia<\/title>\n<meta name=\"description\" content=\"A diferen\u00e7a entre o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS, segundo a jurisprud\u00eancia do STF.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia\" \/>\n<meta property=\"og:description\" content=\"A diferen\u00e7a entre o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS, segundo a jurisprud\u00eancia do STF.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"445\" \/>\n\t<meta property=\"og:image:height\" content=\"303\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Mendes Lima Aguiar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Mendes Lima Aguiar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/\"},\"author\":{\"name\":\"Jos\u00e9 Mendes Lima Aguiar\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad\"},\"headline\":\"O Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia\",\"datePublished\":\"2024-01-08T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/\"},\"wordCount\":2318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png\",\"keywords\":[\"Concurso\",\"Direito Tribut\u00e1rio\",\"domic\u00edlio tribut\u00e1rio\",\"fato gerador\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/\",\"name\":\"Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png\",\"datePublished\":\"2024-01-08T17:00:00+00:00\",\"description\":\"A diferen\u00e7a entre o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS, segundo a jurisprud\u00eancia do STF.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png\",\"width\":445,\"height\":303,\"caption\":\"Aspecto espacial de hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad\",\"name\":\"Jos\u00e9 Mendes Lima Aguiar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g\",\"caption\":\"Jos\u00e9 Mendes Lima Aguiar\"},\"description\":\"Juiz de Direito do TJBA. Ex-assessor de ministro do STJ. Aprovado nos seguintes concursos: - Promotor do MPCE. - Juiz de Direito do TJMA. - Procurador do Estado de MG. - Procurador Jur\u00eddico da CONAB. - Professor de Direito da UnDF. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do STJ. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TST. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TJDFT. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TST. - T\u00e9cnico Administrativo da Secretaria de Sa\u00fade do DF.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/j-mendes405hotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia","description":"A diferen\u00e7a entre o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS, segundo a jurisprud\u00eancia do STF.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/","og_locale":"pt_BR","og_type":"article","og_title":"O Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia","og_description":"A diferen\u00e7a entre o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS, segundo a jurisprud\u00eancia do STF.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-01-08T17:00:00+00:00","og_image":[{"width":445,"height":303,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png","type":"image\/png"}],"author":"Jos\u00e9 Mendes Lima Aguiar","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jos\u00e9 Mendes Lima Aguiar","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/"},"author":{"name":"Jos\u00e9 Mendes Lima Aguiar","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad"},"headline":"O Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia","datePublished":"2024-01-08T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/"},"wordCount":2318,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png","keywords":["Concurso","Direito Tribut\u00e1rio","domic\u00edlio tribut\u00e1rio","fato gerador"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/","name":"Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png","datePublished":"2024-01-08T17:00:00+00:00","description":"A diferen\u00e7a entre o domic\u00edlio tribut\u00e1rio e o aspecto espacial da hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS, segundo a jurisprud\u00eancia do STF.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/04\/12203051\/imposto-sobre-servicos-4.png","width":445,"height":303,"caption":"Aspecto espacial de hip\u00f3tese de incid\u00eancia tribut\u00e1ria do ISS."},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/domicilio-tributario-hipotese-incidencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O Domic\u00edlio tribut\u00e1rio e a hip\u00f3tese de incid\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad","name":"Jos\u00e9 Mendes Lima Aguiar","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g","caption":"Jos\u00e9 Mendes Lima Aguiar"},"description":"Juiz de Direito do TJBA. Ex-assessor de ministro do STJ. Aprovado nos seguintes concursos: - Promotor do MPCE. - Juiz de Direito do TJMA. - Procurador do Estado de MG. - Procurador Jur\u00eddico da CONAB. - Professor de Direito da UnDF. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do STJ. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TST. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TJDFT. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TST. - T\u00e9cnico Administrativo da Secretaria de Sa\u00fade do DF.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/j-mendes405hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1299376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2637"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1299376"}],"version-history":[{"count":53,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1299376\/revisions"}],"predecessor-version":[{"id":1309968,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1299376\/revisions\/1309968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/712716"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1299376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1299376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1299376"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1299376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}