{"id":128913,"date":"2018-06-28T10:35:54","date_gmt":"2018-06-28T13:35:54","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=128913"},"modified":"2018-06-28T10:35:54","modified_gmt":"2018-06-28T13:35:54","slug":"comentarios-as-questoes-de-direito-eleitoral-da-ale-rr","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/","title":{"rendered":"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR"},"content":{"rendered":"<p style=\"text-align: justify\">Neste artigo analisamos as quest\u00f5es aplicadas pela FUNRIO no concurso para a ALE-RR. S\u00e3o quest\u00f5es interessantes e atuais para quem quiser treinar Direito Eleitoral.<\/p>\n<p style=\"text-align: justify\">Antes, convido-o para acompanhar nossas redes sociais:<\/p>\n<p style=\"text-align: justify\">https:\/\/www.facebook.com\/eleitoralparaconcurso\/<\/p>\n<p style=\"text-align: justify\">A prova foi anulada, por problemas de viola\u00e7\u00e3o do lacre das provas. Contudo, usaremos as quest\u00f5es para nossos estudos. Duas das quest\u00f5es foram mal elaboradas e seriam pass\u00edveis de recurso.<\/p>\n<p style=\"text-align: justify\">Vamos aos coment\u00e1rios!<\/p>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 77 &#8211; (FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">De acordo com a Lei No 9.504 de 1997, \u00e9 CORRETO afirmar que<\/p>\n<p style=\"text-align: justify\">(A) nas elei\u00e7\u00f5es proporcionais, contam-se como v\u00e1lidos apenas os votos dados a candidatos regularmente inscritos e \u00e0s legendas partid\u00e1rias.<\/p>\n<p style=\"text-align: justify\">(B) \u00e9 obrigat\u00f3rio aos partidos pol\u00edticos, dentro da mesma circunscri\u00e7\u00e3o, celebrar coliga\u00e7\u00f5es para elei\u00e7\u00e3o majorit\u00e1ria, proporcional, ou para ambas.<\/p>\n<p style=\"text-align: justify\">(C) as normas para a escolha e substitui\u00e7\u00e3o dos candidatos e para a forma\u00e7\u00e3o de coliga\u00e7\u00f5es ser\u00e3o estabelecidas por lei complementar.<\/p>\n<p style=\"text-align: justify\">(D) \u00e9 facultado ao partido ou coliga\u00e7\u00e3o substituir candidato que for considerado ineleg\u00edvel, renunciar ou falecer ap\u00f3s o termo final do prazo do registro ou, ainda, tiver seu registro cassado.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">A quest\u00e3o cobra do candidato conhecimentos sobre a Lei das Elei\u00e7\u00f5es (Lei n. 9.504\/97). Vejamos:<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa A<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. De acordo com o art. 5\u00ba, da Lei de Elei\u00e7\u00f5es, nas elei\u00e7\u00f5es proporcionais, contam-se como v\u00e1lidos apenas os votos dados a candidatos regularmente inscritos e \u00e0s legendas partid\u00e1rias.<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa B<\/strong> est\u00e1 incorreta. A alternativa contraria o disposto no art. 6\u00ba, da Lei de Elei\u00e7\u00f5es, segundo a qual \u00e9 <u>facultado<\/u> aos partidos pol\u00edticos, dentro da mesma circunscri\u00e7\u00e3o, celebrar coliga\u00e7\u00f5es para elei\u00e7\u00e3o majorit\u00e1ria, proporcional, ou para ambas, podendo, neste \u00faltimo caso, formar-se mais de uma coliga\u00e7\u00e3o para a elei\u00e7\u00e3o proporcional dentre os partidos que integram a coliga\u00e7\u00e3o para o pleito majorit\u00e1rio.<\/p>\n<p style=\"text-align: justify\">Devemos lembrar que com a EC 97\/17 ficou vedada a celebra\u00e7\u00e3o de coliga\u00e7\u00f5es nas elei\u00e7\u00f5es proporcionais. Percebam que isso n\u00e3o prejudica a quest\u00e3o, uma vez que o examinador se precaveu cobrando \u201cDe acordo com a Lei No 9.504&#8230;\u201d. Vale a reprodu\u00e7\u00e3o do art. 17, \u00a7 1\u00ba, da CF, para memoriza\u00e7\u00e3o:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>\u00a7 1\u00ba \u00c9 assegurada aos partidos pol\u00edticos autonomia para definir sua estrutura interna e estabelecer regras sobre escolha, forma\u00e7\u00e3o e dura\u00e7\u00e3o de seus \u00f3rg\u00e3os permanentes e provis\u00f3rios e sobre sua organiza\u00e7\u00e3o e funcionamento e para adotar os crit\u00e9rios de escolha e o regime de suas coliga\u00e7\u00f5es nas elei\u00e7\u00f5es majorit\u00e1rias, vedada a sua celebra\u00e7\u00e3o nas elei\u00e7\u00f5es proporcionais, sem obrigatoriedade de vincula\u00e7\u00e3o entre as candidaturas em \u00e2mbito nacional, estadual, distrital ou municipal, devendo seus estatutos estabelecer normas de disciplina e fidelidade partid\u00e1ria. (Reda\u00e7\u00e3o dada pela Emenda Constitucional n\u00ba 97, de 2017)<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A <strong>alternativa C<\/strong> est\u00e1 incorreta. A Lei das Elei\u00e7\u00f5es n\u00e3o define nada a ser estabelecido em lei complementar. Confiram o art. 7\u00ba, <em>caput, <\/em>de onde a alternativa for retirada:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 7\u00ba As normas para a escolha e substitui\u00e7\u00e3o dos candidatos e para a forma\u00e7\u00e3o de coliga\u00e7\u00f5es ser\u00e3o estabelecidas no estatuto do partido, observadas as disposi\u00e7\u00f5es desta Lei.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A <strong>alternativa D<\/strong>, por fim, tamb\u00e9m est\u00e1 incorreta. A intelig\u00eancia do art. 13, da Lei de Elei\u00e7\u00f5es fala em registro indeferido ou cancelado, n\u00e3o \u201ccassado\u201d, como sugere a alternativa. Confiram:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 13. \u00c9 facultado ao partido ou coliga\u00e7\u00e3o substituir candidato que for considerado ineleg\u00edvel, renunciar ou falecer ap\u00f3s o termo final do prazo do registro ou, ainda, tiver seu registro indeferido ou cancelado.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 78 &#8211; (FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">No que concerne \u00e0 literalidade do C\u00f3digo Eleitoral, \u00e9 CORRETO afirmar que<\/p>\n<p style=\"text-align: justify\">(A) somente cidad\u00e3o brasileiro nato pode pretender investidura em cargo eletivo, respeitadas as condi\u00e7\u00f5es constitucionais e legais de elegibilidade e incompatibilidade.<\/p>\n<p style=\"text-align: justify\">(B) s\u00e3o eleitores apenas os brasileiros maiores de 16 anos que se alistarem na forma da lei.<\/p>\n<p style=\"text-align: justify\">(C) n\u00e3o se podem alistar eleitores: os analfabetos; os que n\u00e3o saibam se exprimir na l\u00edngua portuguesa; os que estejam privados, transit\u00f3ria ou permanentemente, dos direitos pol\u00edticos.<\/p>\n<p style=\"text-align: justify\">(D) os militares s\u00e3o alist\u00e1veis, desde que oficiais, aspirantes a oficiais, guardas-marinha, subtenentes ou suboficiais, sargentos ou alunos das escolas militares de ensino superior para forma\u00e7\u00e3o de oficiais.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">A banca utiliza a express\u00e3o: \u201cNo que concerne \u00e0 literalidade do C\u00f3digo Eleitoral&#8230;\u201d, sendo assim, n\u00e3o temos que buscar pela alternativa juridicamente mais correta, mas pela alternativa que se amolda ao que est\u00e1 escrito no C\u00f3digo. Vejamos:<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa A <\/strong>est\u00e1 incorreta, porque contraria a literalidade do art. 3\u00ba, do CE. Vejam:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 3\u00ba Qualquer cidad\u00e3o pode pretender investidura em cargo eletivo, respeitadas as condi\u00e7\u00f5es constitucionais e legais de elegibilidade e incompatibilidade.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A <strong>alternativa B<\/strong>, igualmente, est\u00e1 incorreta. Vejam a disposi\u00e7\u00e3o do art. 4\u00ba, <em>caput, <\/em>do CE:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 4\u00ba S\u00e3o eleitores os brasileiros maiores de 18 anos que se alistarem na forma da lei.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Percebam que s\u00e3o eleitores, tamb\u00e9m, os maiores de 16 anos que se alistarem na forma da lei, o que est\u00e1 disciplinado na Constitui\u00e7\u00e3o Federal (art. 14, \u00a7 \u00ba, II, \u201cc\u201d), que diz que o voto \u00e9 facultativo para os maiores de dezesseis e menores de dezoito. Mas percebam tamb\u00e9m que isso \u00e9 irrelevante nesta quest\u00e3o, simplesmente porque n\u00e3o se adequa \u00e0 literalidade do C\u00f3digo Eleitoral<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa C<\/strong> tamb\u00e9m est\u00e1 incorreta. Apesar de tudo que foi dito at\u00e9 agora, aqui, eu considero que houve um exagero. A diferen\u00e7a do que diz o C\u00f3digo para o que diz a assertiva \u00e9 uma diferen\u00e7a de sin\u00f4nimos e, apesar de o que vem trazido na alternativa n\u00e3o corresponder, literalmente, ao que est\u00e1 no CE, ela \u00e9 correta, como voc\u00eas poder\u00e3o conferir. Tudo o que o examinador fez foi trocar as express\u00f5es \u201cl\u00edngua nacional\u201d por \u201cl\u00edngua portuguesa\u201d e \u201ctempor\u00e1ria ou definitivamente\u201d por \u201ctransit\u00f3ria ou permanentemente\u201d. Confiram:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 5\u00ba N\u00e3o podem alistar-se eleitores:<\/em><\/p>\n<p style=\"text-align: justify\"><em>I &#8211; os analfabetos;<\/em><\/p>\n<p style=\"text-align: justify\"><em>II &#8211; os que n\u00e3o saibam exprimir-se na l\u00edngua nacional;<\/em><\/p>\n<p style=\"text-align: justify\"><em>III &#8211; os que estejam privados, tempor\u00e1ria ou definitivamente dos direitos pol\u00edticos.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Fica clara, em quest\u00f5es como essa, a necessidade de o candidato ler a lei seca.<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa D<\/strong>, ao final, \u00e9 a correta. Ela corresponde, literalmente, ao par\u00e1grafo \u00fanico do art. 5\u00ba:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Par\u00e1grafo \u00fanico &#8211; Os militares s\u00e3o alist\u00e1veis, desde que oficiais, aspirantes a oficiais, guardas-marinha, subtenentes ou suboficiais, sargentos ou alunos das escolas militares de ensino superior para forma\u00e7\u00e3o de oficiais.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 79 &#8211;<\/strong> <strong>(FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">Com rela\u00e7\u00e3o \u00e0 Lei No 9.096, que regulamenta os partidos pol\u00edticos, pode-se afirmar o seguinte:<\/p>\n<p style=\"text-align: justify\">(A) a responsabilidade por viola\u00e7\u00e3o dos deveres partid\u00e1rios deve ser apurada e punida pelo competente \u00f3rg\u00e3o, na conformidade do que disponha o estatuto de cada partido.<\/p>\n<p style=\"text-align: justify\">(B) \u00e9 assegurada aos partidos pol\u00edticos autonomia para definir sua estrutura interna e estabelecer regras sobre escolha, forma\u00e7\u00e3o e dura\u00e7\u00e3o de seus \u00f3rg\u00e3os permanentes e provis\u00f3rios e sobre sua organiza\u00e7\u00e3o e funcionamento.<\/p>\n<p style=\"text-align: justify\">(C) os partidos pol\u00edticos, ap\u00f3s adquirirem personalidade jur\u00eddica, na forma da lei civil, registrar\u00e3o seus estatutos no Tribunal Superior Eleitoral.<\/p>\n<p style=\"text-align: justify\">(D) \u00e9 livre a cria\u00e7\u00e3o, fus\u00e3o, incorpora\u00e7\u00e3o e extin\u00e7\u00e3o de partidos pol\u00edticos, resguardados a soberania nacional, o regime democr\u00e1tico, o pluripartidarismo e os direitos fundamentais da pessoa humana.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">Aqui, mais uma quest\u00e3o envolvendo a literalidade dos dispositivos de uma lei, no caso, a Lei dos Partidos Pol\u00edticos. Nessa quest\u00e3o, por\u00e9m, caberia recurso<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa A <\/strong>est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o, conforme a banca. De acordo com o art. 23 da Lei dos Partidos Pol\u00edticos:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 23. A responsabilidade por viola\u00e7\u00e3o dos deveres partid\u00e1rios deve ser apurada e punida pelo competente \u00f3rg\u00e3o, na conformidade do que disponha o estatuto de cada partido.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A <strong>alternativa B <\/strong>est\u00e1 incorreta. De fato, n\u00e3o h\u00e1 previs\u00e3o na Lei referente \u00e0 forma\u00e7\u00e3o e dura\u00e7\u00e3o de \u00f3rg\u00e3os permanentes e provis\u00f3rios dos partidos. Limita-se o art. 3\u00ba a dizer que \u201c\u00c9 assegurada, ao partido pol\u00edtico, autonomia para definir sua estrutura interna, organiza\u00e7\u00e3o e funcionamento\u201d.<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa C<\/strong> foi considerada incorreta pela banca, todavia, a alternativa praticamente reproduz o preceito do art. 7\u00ba, da Lei. Vejam:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 7\u00ba O partido pol\u00edtico, ap\u00f3s adquirir personalidade jur\u00eddica na forma da lei civil, registra seu estatuto no Tribunal Superior Eleitoral.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A diferen\u00e7a entre a assertiva trazida pela banca e a disposi\u00e7\u00e3o do C\u00f3digo \u00e9 que uma est\u00e1 no plural e a outra n\u00e3o.<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa D<\/strong> pela mesma l\u00f3gica, foi considerada incorreta pela banca. Contudo, reproduz o Art. 2\u00ba, da Lei, e a assertiva da quest\u00e3o. Vejam:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 2\u00ba \u00c9 livre a cria\u00e7\u00e3o, fus\u00e3o, incorpora\u00e7\u00e3o e extin\u00e7\u00e3o de partidos pol\u00edticos cujos programas respeitem a soberania nacional, o regime democr\u00e1tico, o pluripartidarismo e os direitos fundamentais da pessoa humana.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Assim, a <strong>quest\u00e3o n\u00e3o possui gabarito<\/strong>, pois as alternativas A, C e D est\u00e3o corretas.<\/p>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 80 &#8211;<\/strong> <strong>(FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">No que se refere \u00e0s condi\u00e7\u00f5es de elegibilidade, analise os itens a seguir.<\/p>\n<p style=\"text-align: justify\">I. A nacionalidade brasileira ou certid\u00e3o de naturalizado<\/p>\n<p style=\"text-align: justify\">II. O pleno exerc\u00edcio dos direitos pol\u00edticos<\/p>\n<p style=\"text-align: justify\">III. Domic\u00edlio eleitoral na circunscri\u00e7\u00e3o<\/p>\n<p style=\"text-align: justify\">IV. A filia\u00e7\u00e3o partid\u00e1ria e comprovante de alistamento militar<\/p>\n<p style=\"text-align: justify\">Assinale a alternativa que contempla plenamente todos os itens CORRETOS.<\/p>\n<p style=\"text-align: justify\">(A) I e II.<\/p>\n<p style=\"text-align: justify\">(B) II e III.<\/p>\n<p style=\"text-align: justify\">(C) III e IV.<\/p>\n<p style=\"text-align: justify\">(D) II.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">A quest\u00e3o cobra do aluno conhecimento do art. 13, \u00a7 3\u00ba, da CRFB. Vejamos:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>\u00a7 3\u00ba S\u00e3o condi\u00e7\u00f5es de elegibilidade, na forma da lei:<\/em><\/p>\n<p style=\"text-align: justify\"><em>I &#8211; a <u>nacionalidade brasileira<\/u>;<\/em><\/p>\n<p style=\"text-align: justify\"><em>II &#8211; o <u>pleno exerc\u00edcio dos direitos pol\u00edticos<\/u>;<\/em><\/p>\n<p style=\"text-align: justify\"><em>III &#8211; o <u>alistamento eleitoral<\/u>;<\/em><\/p>\n<p style=\"text-align: justify\"><em>IV &#8211; o <u>domic\u00edlio eleitoral na circunscri\u00e7\u00e3o<\/u>;<\/em><\/p>\n<p style=\"text-align: justify\"><em>V &#8211; a filia\u00e7\u00e3o partid\u00e1ria; Regulamento<\/em><\/p>\n<p style=\"text-align: justify\"><em>VI &#8211; a idade m\u00ednima de:<\/em><\/p>\n<p style=\"text-align: justify\"><em>a) trinta e cinco anos para Presidente e Vice-Presidente da Rep\u00fablica e Senador;<\/em><\/p>\n<p style=\"text-align: justify\"><em>b) trinta anos para Governador e Vice-Governador de Estado e do Distrito Federal;<\/em><\/p>\n<p style=\"text-align: justify\"><em>c) vinte e um anos para Deputado Federal, Deputado Estadual ou Distrital, Prefeito, Vice-Prefeito e juiz de paz;<\/em><\/p>\n<p style=\"text-align: justify\"><em>d) dezoito anos para Vereador.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Desse modo, podemos perceber que a assertiva I est\u00e1 incorreta, por extrapolar a disposi\u00e7\u00e3o do \u00a7 3\u00ba, I, e a assertiva IV tamb\u00e9m est\u00e1 incorreta, por extrapolar o conte\u00fado do inciso III.<\/p>\n<p style=\"text-align: justify\">Estando apenas as assertivas II e III corretas (incisos II e IV, respectivamente), a <strong>alternativa B<\/strong> \u00e9 o gabarito da quest\u00e3o.<\/p>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 81 &#8211; (FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">Gilberto \u00e9 candidato a prefeito no munic\u00edpio de Buritis\/RR. Sua esposa Roberta \u00e9 candidata \u00e0 governadora no estado de Roraima. Michele, filha adotiva do casal, \u00e9 vereadora em Buritis\/RR e candidata \u00e0 reelei\u00e7\u00e3o. Tendo em vista o caso exposto, \u00e9 CORRETO afirmar que<\/p>\n<p style=\"text-align: justify\">(A) Gilberto \u00e9 ineleg\u00edvel.<\/p>\n<p style=\"text-align: justify\">(B) Roberta poder\u00e1 se candidatar para o cargo de governadora.<\/p>\n<p style=\"text-align: justify\">(C) Michele n\u00e3o ter\u00e1 problemas em sua candidatura \u00e0 reelei\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify\">(D) Roberta e Michele est\u00e3o impedidas de prosseguir com as candidaturas.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">A quest\u00e3o cobra do candidato a aplica\u00e7\u00e3o do conceito de inelegibilidade reflexa, trazido pelo \u00a7 7\u00ba, do art. 14, da CF. Vejamos:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>\u00a7 7\u00ba S\u00e3o ineleg\u00edveis, no territ\u00f3rio de jurisdi\u00e7\u00e3o do titular, o c\u00f4njuge e os parentes consang\u00fc\u00edneos ou afins, at\u00e9 o segundo grau ou por ado\u00e7\u00e3o, do Presidente da Rep\u00fablica, de Governador de Estado ou Territ\u00f3rio, do Distrito Federal, de Prefeito ou de quem os haja substitu\u00eddo dentro dos seis meses anteriores ao pleito, salvo se j\u00e1 titular de mandato eletivo e candidato \u00e0 reelei\u00e7\u00e3o.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Algumas considera\u00e7\u00f5es:<\/p>\n<ul style=\"text-align: justify\">\n<li>Apenas cargos do Poder Executivo geram a inelegibilidade reflexa (Presidente, Governador e Prefeito)<\/li>\n<li>O titular de cargo eletivo candidato \u00e0 reelei\u00e7\u00e3o \u00e9 exce\u00e7\u00e3o \u00e0 regra<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Com base nessas duas considera\u00e7\u00f5es, analisemos:<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa A<\/strong> est\u00e1 incorreta. Gilberto n\u00e3o \u00e9 ineleg\u00edvel. N\u00e3o h\u00e1 nenhum elemento no enunciado que leve a essa conclus\u00e3o. Se a esposa de Gilberto fosse Governadora, ele seria ineleg\u00edvel, mas ela \u00e9 apenas candidata. E a filha de Gilberto, Michele, n\u00e3o enseja inelegibilidade, porque investida em cargo do Poder Legislativo.<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa B<\/strong> est\u00e1 correta. Roberta poder\u00e1 se candidatar ao cargo de Governadora. O fato de Gilberto ser candidato a Prefeito nada influencia na candidatura de Roberta, assim como o fato da sua filha ser Vereadora, como vimos acima.<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa C<\/strong> tamb\u00e9m est\u00e1 correta e foi considerada o gabarito da quest\u00e3o. Michele n\u00e3o ter\u00e1 problemas na sua candidatura \u00e0 reelei\u00e7\u00e3o justamente por conta da exce\u00e7\u00e3o prevista no art. 14, \u00a7 7\u00ba, parte final.<\/p>\n<p style=\"text-align: justify\">E a <strong>alternativa D<\/strong> est\u00e1 incorreta. Nem Roberta nem Michele est\u00e3o impedidas de prosseguir com as candidaturas. N\u00e3o h\u00e1 elementos no enunciado em que basear essa afirma\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify\">Sendo assim, tanto a alternativa B quanto a alternativa C est\u00e3o corretas, o que deve ensejar a <strong>anula\u00e7\u00e3o da quest\u00e3o<\/strong>.<\/p>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 82 &#8211;<\/strong> <strong>(FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">Amauri \u00e9 governador no Estado do Esp\u00edrito Santo, mas devido a sucessivas crises entre ele e o partido, decidiu candidatar-se a prefeito da capital Vit\u00f3ria, por outro partido pol\u00edtico.<\/p>\n<p style=\"text-align: justify\">Nesse sentido, pode-se afirmar que Amauri<\/p>\n<p style=\"text-align: justify\">(A) n\u00e3o poder\u00e1 concorrer a prefeito de Vit\u00f3ria, at\u00e9 o final do mandato de Governador.<\/p>\n<p style=\"text-align: justify\">(B) ter\u00e1 que renunciar ao respectivo mandato de governador at\u00e9 seis meses antes do pleito \u2014 instituto da desincompatibiliza\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify\">(C) ter\u00e1 esse conduto vedado, porque ele trocou de partido pol\u00edtico.<\/p>\n<p style=\"text-align: justify\">(D) ter\u00e1 que renunciar ao respectivo mandato de governador at\u00e9 cinco meses antes do pleito, para se candidatar a prefeito.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">A quest\u00e3o cobra do candidato conhecimento sobre o instituto da desincompatibiliza\u00e7\u00e3o de que trata o art. 14, \u00a7 6\u00ba, da CF. Vejamos:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>\u00a7 6\u00ba Para concorrerem a outros cargos, o Presidente da Rep\u00fablica, os Governadores de Estado e do Distrito Federal e os Prefeitos devem renunciar aos respectivos mandatos at\u00e9 seis meses antes do pleito.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">Sendo assim, vejamos:<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa A <\/strong>est\u00e1 incorreta. De acordo com o disposto transcrito, Amauri pode candidatar-se a Prefeito da capital, desde que renuncie ao respectivo mandato at\u00e9 seis meses antes do pleito.<\/p>\n<p style=\"text-align: justify\">A <strong>Alternativa B<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. De fato, Amauri ter\u00e1 que renunciar ao respectivo mandato de Governador at\u00e9 seis meses antes do pleito, o que se traduz no instituto da desincompatibiliza\u00e7\u00e3o (art. 14, \u00a7 6\u00ba, da CF).<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa C<\/strong> est\u00e1 incorreta. O fato de Amauri ter trocado de partido n\u00e3o o impede de se candidatar. Como o enunciado diz que Amauri e o partido passaram por sucessivas crises, podemos interpretar que ele se desfiliou do partido com justa causa (art. 22-A, par\u00e1grafo \u00fanico, da Lei n. 9.096). Vejam:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 22-A.\u00a0 Perder\u00e1 o mandato o detentor de cargo eletivo que se desfiliar, sem justa causa, do partido pelo qual foi eleito.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><\/p>\n<p style=\"text-align: justify\"><em>Par\u00e1grafo \u00fanico.\u00a0 Consideram-se justa causa para a desfilia\u00e7\u00e3o partid\u00e1ria somente as seguintes hip\u00f3teses:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><\/p>\n<p style=\"text-align: justify\"><em>I &#8211; mudan\u00e7a substancial ou desvio reiterado do programa partid\u00e1rio;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><\/p>\n<p style=\"text-align: justify\"><em>II &#8211; grave discrimina\u00e7\u00e3o pol\u00edtica pessoal; e<\/em><\/p>\n<p style=\"text-align: justify\"><em>III &#8211; mudan\u00e7a de partido efetuada durante o per\u00edodo de trinta dias que antecede o prazo de filia\u00e7\u00e3o exigido em lei para concorrer \u00e0 elei\u00e7\u00e3o, majorit\u00e1ria ou proporcional, ao t\u00e9rmino do mandato vigente<\/em>.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A <strong>alternativa D<\/strong> tamb\u00e9m est\u00e1 incorreta. Como j\u00e1 vimos, a ren\u00fancia deve ocorrer com seis meses de anteced\u00eancia.<\/p>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 83 <\/strong>&#8211; <strong>(FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">De acordo com a Constitui\u00e7\u00e3o Federal de 1988, \u00e9 livre a cria\u00e7\u00e3o, fus\u00e3o, incorpora\u00e7\u00e3o e extin\u00e7\u00e3o de partidos pol\u00edticos, resguardados a soberania nacional, o regime democr\u00e1tico, o pluripartidarismo, os direitos fundamentais da pessoa humana e observados os seguintes preceitos, EXCETO a\/o<\/p>\n<p style=\"text-align: justify\">(A) presta\u00e7\u00e3o de contas ao Tribunal Superior Eleitoral (TSE) e STF, respectivamente.<\/p>\n<p style=\"text-align: justify\">(B) proibi\u00e7\u00e3o de recebimento de recursos financeiros de entidade ou governo estrangeiros ou de subordina\u00e7\u00e3o a eles.<\/p>\n<p style=\"text-align: justify\">(C) car\u00e1ter nacional.<\/p>\n<p style=\"text-align: justify\">(D) funcionamento parlamentar de acordo com a lei.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">A quest\u00e3o cobra do candidato o conhecimento do art. 17, da CF, e dos seus incisos. Vejamos:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>Art. 17. \u00c9 livre a cria\u00e7\u00e3o, fus\u00e3o, incorpora\u00e7\u00e3o e extin\u00e7\u00e3o de partidos pol\u00edticos, resguardados a soberania nacional, o regime democr\u00e1tico, o pluripartidarismo, os direitos fundamentais da pessoa humana e observados os seguintes preceitos: <\/em><\/p>\n<p style=\"text-align: justify\"><em>I &#8211; <u>car\u00e1ter nacional<\/u>;<\/em><\/p>\n<p style=\"text-align: justify\"><em>II &#8211; <u>proibi\u00e7\u00e3o de recebimento de recursos financeiros de entidade ou governo estrangeiros ou de subordina\u00e7\u00e3o a estes<\/u>;<\/em><\/p>\n<p style=\"text-align: justify\"><em>III &#8211; presta\u00e7\u00e3o de contas \u00e0 Justi\u00e7a Eleitoral;<\/em><\/p>\n<p style=\"text-align: justify\"><em>IV &#8211; <u>funcionamento parlamentar de acordo com a lei<\/u>.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">De acordo com o art. 17, a <strong>alternativa A<\/strong> \u00e9 a \u00fanica incorreta, e gabarito da quest\u00e3o. N\u00e3o que se falar em presta\u00e7\u00e3o de contas ao STF e ao TSE, mas sim \u00e0 Justi\u00e7a Eleitoral<\/p>\n<p style=\"text-align: justify\">&#8212;<\/p>\n<p style=\"text-align: justify\"><strong>Quest\u00e3o 84 &#8211; (FUNRIO\/ALE-RR\/2018)<\/strong><\/p>\n<p style=\"text-align: justify\">De acordo com o entendimento sumulado do TSE, assinale a alternativa CORRETA.<\/p>\n<p style=\"text-align: justify\">(A) O exerc\u00edcio de mandato eletivo, por si s\u00f3, \u00e9 circunst\u00e2ncia capaz de comprovar a condi\u00e7\u00e3o de alfabetizado do candidato.<\/p>\n<p style=\"text-align: justify\">(B) Cabe recurso especial eleitoral para simples reexame do conjunto f\u00e1tico-probat\u00f3rio.<\/p>\n<p style=\"text-align: justify\">(C) S\u00f3 \u00e9 admiss\u00edvel recurso especial eleitoral por viola\u00e7\u00e3o \u00e0 legisla\u00e7\u00e3o municipal ou estadual, ao regimento interno dos tribunais eleitorais ou \u00e0s normas partid\u00e1rias.<\/p>\n<p style=\"text-align: justify\">(D) A suspens\u00e3o de direitos pol\u00edticos decorrente de condena\u00e7\u00e3o criminal transitada em julgado cessa com o cumprimento ou a extin\u00e7\u00e3o da pena, independendo de reabilita\u00e7\u00e3o ou de prova de repara\u00e7\u00e3o dos danos.<\/p>\n<p style=\"text-align: justify\"><strong>Coment\u00e1rios<\/strong><\/p>\n<p style=\"text-align: justify\">A quest\u00e3o cobra do candidato o conhecimento dos enunciados das s\u00famulas do TSE. Vejamos:<\/p>\n<p style=\"text-align: justify\">A <strong>alternativa A <\/strong>est\u00e1 incorreta, por contrariar a literalidade do enunciado da S\u00famula-TSE nn\u00ba 15. Confiram:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>O exerc\u00edcio de mandato eletivo <u>n\u00e3o<\/u> \u00e9 circunst\u00e2ncia capaz, por si s\u00f3, de comprovar a condi\u00e7\u00e3o de alfabetizado do candidato.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A <strong>alternativa B<\/strong> tamb\u00e9m est\u00e1 incorreta. N\u00e3o cabe recurso eleitoral para simples reexame do conjunto f\u00e1tico-probat\u00f3rio (S\u00famula-TSE n\u00ba 24). Vejam:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>N\u00e3o cabe recurso especial eleitoral para simples reexame do conjunto f\u00e1tico-probat\u00f3rio.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">A <strong>alternativa C<\/strong> tamb\u00e9m est\u00e1 incorreta. Confiram o enunciado da S\u00famula-TSE n\u00ba 32:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>\u00c9 inadmiss\u00edvel recurso especial eleitoral por viola\u00e7\u00e3o \u00e0 legisla\u00e7\u00e3o municipal ou estadual, ao Regimento Interno dos Tribunais Eleitorais ou \u00e0s normas partid\u00e1rias.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\">E, por fim, a <strong>alternativa D<\/strong> est\u00e1 correta e \u00e9 o gabarito da quest\u00e3o. Vejam o enunciado da S\u00famula-TSE n\u00ba 9:<\/p>\n<blockquote>\n<p style=\"text-align: justify\"><em>A suspens\u00e3o de direitos pol\u00edticos decorrente de condena\u00e7\u00e3o criminal transitada em julgado cessa com o cumprimento ou a extin\u00e7\u00e3o da pena, independendo de reabilita\u00e7\u00e3o ou de prova de repara\u00e7\u00e3o dos danos.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify\"><em>&#8212;<\/em><\/p>\n<p style=\"text-align: justify\">\u00c9 isso!<\/p>\n<p style=\"text-align: justify\">Qualquer d\u00favida, deixei seu coment\u00e1rio ou nos procure nas redes sociais.<\/p>\n<p style=\"text-align: justify\">Bons estudos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste artigo analisamos as quest\u00f5es aplicadas pela FUNRIO no concurso para a ALE-RR. S\u00e3o quest\u00f5es interessantes e atuais para quem quiser treinar Direito Eleitoral. Antes, convido-o para acompanhar nossas redes sociais: https:\/\/www.facebook.com\/eleitoralparaconcurso\/ A prova foi anulada, por problemas de viola\u00e7\u00e3o do lacre das provas. Contudo, usaremos as quest\u00f5es para nossos estudos. Duas das quest\u00f5es foram [&hellip;]<\/p>\n","protected":false},"author":180,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1],"tags":[3614,3765,528,314],"tax_estado":[],"class_list":["post-128913","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","tag-ale-rr","tag-comentadas","tag-direito-eleitoral","tag-questoes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR\" \/>\n<meta property=\"og:description\" content=\"Neste artigo analisamos as quest\u00f5es aplicadas pela FUNRIO no concurso para a ALE-RR. S\u00e3o quest\u00f5es interessantes e atuais para quem quiser treinar Direito Eleitoral. Antes, convido-o para acompanhar nossas redes sociais: https:\/\/www.facebook.com\/eleitoralparaconcurso\/ A prova foi anulada, por problemas de viola\u00e7\u00e3o do lacre das provas. Contudo, usaremos as quest\u00f5es para nossos estudos. Duas das quest\u00f5es foram [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ricardo.s.torques\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-28T13:35:54+00:00\" \/>\n<meta name=\"author\" content=\"Ricardo Torques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Torques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/\"},\"author\":{\"name\":\"Ricardo Torques\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/aa39cf5ddb518e5bdce27c35788405e2\"},\"headline\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR\",\"datePublished\":\"2018-06-28T13:35:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/\"},\"wordCount\":3150,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"keywords\":[\"ALE RR\",\"comentadas\",\"Direito Eleitoral\",\"quest\u00f5es\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/\",\"name\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\"},\"datePublished\":\"2018-06-28T13:35:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/aa39cf5ddb518e5bdce27c35788405e2\",\"name\":\"Ricardo Torques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g\",\"caption\":\"Ricardo Torques\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ricardo.s.torques\"],\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/ricardotorquesestrategiaconcursos-com-br\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/","og_locale":"pt_BR","og_type":"article","og_title":"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR","og_description":"Neste artigo analisamos as quest\u00f5es aplicadas pela FUNRIO no concurso para a ALE-RR. S\u00e3o quest\u00f5es interessantes e atuais para quem quiser treinar Direito Eleitoral. Antes, convido-o para acompanhar nossas redes sociais: https:\/\/www.facebook.com\/eleitoralparaconcurso\/ A prova foi anulada, por problemas de viola\u00e7\u00e3o do lacre das provas. Contudo, usaremos as quest\u00f5es para nossos estudos. Duas das quest\u00f5es foram [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/ricardo.s.torques","article_published_time":"2018-06-28T13:35:54+00:00","author":"Ricardo Torques","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Ricardo Torques","Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/"},"author":{"name":"Ricardo Torques","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2"},"headline":"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR","datePublished":"2018-06-28T13:35:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/"},"wordCount":3150,"commentCount":1,"publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"keywords":["ALE RR","comentadas","Direito Eleitoral","quest\u00f5es"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/","name":"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website"},"datePublished":"2018-06-28T13:35:54+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/comentarios-as-questoes-de-direito-eleitoral-da-ale-rr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog-estrategia.mystagingwebsite.com\/"},{"@type":"ListItem","position":2,"name":"Coment\u00e1rios \u00e0s quest\u00f5es de Direito Eleitoral da ALE-RR"}]},{"@type":"WebSite","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog-estrategia.mystagingwebsite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/aa39cf5ddb518e5bdce27c35788405e2","name":"Ricardo Torques","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce9ac6c3cff25fe86d15ed568ebc64d1724baf5c0693133bcb1f6073f712f92a?s=96&d=mm&r=g","caption":"Ricardo Torques"},"sameAs":["https:\/\/www.facebook.com\/ricardo.s.torques"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/ricardotorquesestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/128913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/180"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=128913"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/128913\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=128913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=128913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=128913"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=128913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}