{"id":1288885,"date":"2024-02-08T11:00:00","date_gmt":"2024-02-08T14:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1288885"},"modified":"2025-05-09T10:37:54","modified_gmt":"2025-05-09T13:37:54","slug":"resumo-acao-exigir-contas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/","title":{"rendered":"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg\" alt=\"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC\" class=\"wp-image-1159931\" style=\"width:524px;height:350px\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg 1000w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2-768x512.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2-610x407.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2-150x100.jpg 150w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC<\/figcaption><\/figure>\n\n\n\n<p>Fala, pessoal, tudo certo? Hoje traremos um resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC (C\u00f3digo de Processo Civil).<\/p>\n\n\n\n<p>Trata-se de assunto relevante da mat\u00e9ria de Direito Processual Civil, no que cinge aos procedimentos especiais.<\/p>\n\n\n\n<p>Portanto, vamos nessa!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-acao-de-exigir-contas-nbsp\">A\u00e7\u00e3o de Exigir Contas&nbsp;<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-previsao-legal-cabimento-e-objetivo\">Previs\u00e3o legal, cabimento e objetivo<\/h3>\n\n\n\n<p>Primeiramente, destacamos que a A\u00e7\u00e3o de Exigir Contas possui previs\u00e3o no CPC dentre seus <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm#:~:text=DA%20A%C3%87%C3%83O%20DE%20EXIGIR%20CONTAS\" target=\"_blank\" rel=\"noreferrer noopener\">artigos 550 e 553<\/a>.\u00a0Embora aparentemente se trate de um tema curto no C\u00f3digo, h\u00e1 algumas particularidades que abordaremos abaixo.<\/p>\n\n\n\n<p>Seu <strong>objetivo <\/strong>\u00e9 descrito por Humberto Theodoro J\u00fanior como sendo o <em>&#8220;de <strong>liquidar um relacionamento jur\u00eddico existente entre as partes no seu aspecto econ\u00f4mico<\/strong>, de tal modo que, afinal, se <strong>determine, com exatid\u00e3o, a exist\u00eancia ou n\u00e3o de um saldo<\/strong>, fixando, no caso positivo, o seu montante, com efeito de condena\u00e7\u00e3o judicial contra a parte que se qualifica como devedora&#8221;<\/em>.<\/p>\n\n\n\n<p>O Superior Tribunal de Justi\u00e7a entende que o interesse processual na a\u00e7\u00e3o de exigir contas <strong>pressup\u00f5e a exist\u00eancia de controv\u00e9rsia entre as partes da rela\u00e7\u00e3o jur\u00eddica,<\/strong> <strong>cuja caracteriza\u00e7\u00e3o depende da presen\u00e7a de alguma das seguintes hip\u00f3teses:\u00a0<\/strong><\/p>\n\n\n\n<p>a) recusa ou mora em prestar as contas;&nbsp;<\/p>\n\n\n\n<p>b) n\u00e3o aprova\u00e7\u00e3o das contas prestadas; <strong><span style=\"text-decoration: underline;\">ou<\/span><\/strong>\u00a0<\/p>\n\n\n\n<p>c) diverg\u00eancia quanto \u00e0 exist\u00eancia ou o montante do saldo credor ou devedor.&nbsp;<\/p>\n\n\n\n<p>Ou seja, havendo algum desses casos, o interessado poder\u00e1 ajuizar uma a\u00e7\u00e3o de exigir contas. Vamos ver agora quais s\u00e3o as fases desse procedimento!<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-fases-da-acao-de-exigir-contas-no-cpc\">Fases da A\u00e7\u00e3o de Exigir Contas no CPC<\/h3>\n\n\n\n<p>Embora o C\u00f3digo de Processo Civil n\u00e3o deixe claro que existe mais de uma fase na a\u00e7\u00e3o de exigir contas, o Superior Tribunal de Justi\u00e7a e a doutrina entendem que h\u00e1 <strong>02 (duas) fases distintas<\/strong> na A\u00e7\u00e3o de Exigir Contas.<\/p>\n\n\n\n<p><strong>Na 1\u00aa fase<\/strong> <strong>da A\u00e7\u00e3o de Exigir Contas<\/strong> o Poder Judici\u00e1rio ir\u00e1 analisar se o direito de exigir contas existe. Ou seja, se a pessoa que est\u00e1 ajuizando a a\u00e7\u00e3o (polo ativo) realmente pode exigir as contas daquele que ir\u00e1 figurar como devedor das contas (polo passivo). <\/p>\n\n\n\n<p><span style=\"text-decoration: underline;\">Caso a resposta seja negativa<\/span> (n\u00e3o tiver o direito de exigir as contas), encerra-se o processo com resolu\u00e7\u00e3o de m\u00e9rito, n\u00e3o podendo mais ajuizar a mesma a\u00e7\u00e3o novamente. <\/p>\n\n\n\n<p><span style=\"text-decoration: underline;\">Por\u00e9m, caso se conclua que a parte autora possui direito<\/span> de exigir contas da parte r\u00e9, ou caso esta \u00faltima apresente voluntariamente as contas no prazo de 15 dias, a partir de ent\u00e3o inicia-se a 2\u00aa fase.<\/p>\n\n\n\n<p><strong>Na 2\u00aa fase da A\u00e7\u00e3o de Exigir Contas <\/strong>a an\u00e1lise que o \u00f3rg\u00e3o julgador far\u00e1 ir\u00e1 recair sobre a adequa\u00e7\u00e3o das contas prestadas, determinando-se a exist\u00eancia ou n\u00e3o de saldo credor ou devedor.\u00a0<\/p>\n\n\n\n<p>Ou seja, enquanto na  primeira fase o Judici\u00e1rio est\u00e1 analisando se existe o direito de exigir contas; na segunda fase ir\u00e1 analisar se existe algo a ser exigido. <\/p>\n\n\n\n<p><strong>ATEN\u00c7\u00c3O! Nesse momento, \u00e9 importante destacar que a presta\u00e7\u00e3o de contas poder\u00e1 resultar em desfavor da parte autora da a\u00e7\u00e3o!! <\/strong>Isso mesmo: pode ser que a decis\u00e3o da a\u00e7\u00e3o aponte que, na verdade, a parte r\u00e9 da a\u00e7\u00e3o (de quem est\u00e1 se exigindo as contas) \u00e9 que possua saldo em seu favor. <strong>\u00c9 o que se chama de natureza d\u00faplice<\/strong> (pode ser que a a\u00e7\u00e3o ajuizada pelo autor na verdade resulte no reconhecimento do direito do r\u00e9u).<\/p>\n\n\n\n<p>Independentemente de quem possua saldo em seu favor (autor ou r\u00e9u da a\u00e7\u00e3o), passaremos \u00e0 fase de cumprimento de senten\u00e7a e o polo ativo dessa fase execut\u00f3ria ser\u00e1 assumido por quem a senten\u00e7a reconhecer como credor do outro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-peticao-inicial-nbsp\">Peti\u00e7\u00e3o inicial&nbsp;<\/h3>\n\n\n\n<p>J\u00e1 vimos quais s\u00e3o as fases da a\u00e7\u00e3o de exigir contas. Agora, vamos destacar como elas &#8220;se materializam&#8221; no curso do processo. A 1\u00aa fase inicia-se com o protocolo da peti\u00e7\u00e3o inicial por aquele que afirma ser titular do direito de exigir contas.<\/p>\n\n\n\n<p>A partir disso, a parte autora dever\u00e1 requerer a cita\u00e7\u00e3o do r\u00e9u para que<strong> <\/strong>este <strong>preste as contas ou ofere\u00e7a contesta\u00e7\u00e3o no prazo de 15 (quinze) dias.<\/strong><\/p>\n\n\n\n<p>Os motivos pelos quais se exige contas s\u00e3o in\u00fameros, podendo decorrer de lei ou de contrato. Desse modo, <strong>o autor dever\u00e1 especificar detalhadamente as raz\u00f5es pelas quais est\u00e1 exigindo as contas<\/strong>, instruindo a peti\u00e7\u00e3o inicial com os documentos comprobat\u00f3rios dessa necessidade, se existirem.<\/p>\n\n\n\n<p>Humberto Theodoro Junior exemplifica casos em que a A\u00e7\u00e3o de Exigir Contas tem cabimento:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-small-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>(&#8230;) Uma abertura de cr\u00e9dito, por exemplo, em que o credor aplica recursos no custeio de obriga\u00e7\u00f5es do devedor; ou o prestador de servi\u00e7os que aplica bens e valores pr\u00f3prios na realiza\u00e7\u00e3o de obra de outrem; ou o banco que periodicamente efetua lan\u00e7amentos na conta de dep\u00f3sito de seu cliente s\u00e3o casos em que a a\u00e7\u00e3o de presta\u00e7\u00e3o de contas tem cabimento, n\u00e3o obstante os recursos manejados sejam daquele que faz os lan\u00e7amentos. O importante \u00e9 que o resultado dessas opera\u00e7\u00f5es afeta a esfera jur\u00eddica de outrem e, surgindo d\u00favida, reclamam acertamento por meio de procedimento pr\u00f3prio para apura\u00e7\u00e3o de contas.<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-contestacao-ou-prestacao-de-contas\">Contesta\u00e7\u00e3o ou presta\u00e7\u00e3o de contas<\/h3>\n\n\n\n<p>Como dito acima, o r\u00e9u, no prazo de 15 dias de sua cita\u00e7\u00e3o, poder\u00e1 (i) prestar contas; (ii) contestar a a\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Caso resolva prestar as contas, o autor ter\u00e1 15 (quinze) dias para se manifestar, <\/strong>prosseguindo-se o processo na forma do <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm#:~:text=CAP%C3%8DTULO%20X%0ADO%20JULGAMENTO%20CONFORME%20O%20ESTADO%20DO%20PROCESSO\" target=\"_blank\" rel=\"noreferrer noopener\">Cap\u00edtulo X &#8211; Do Julgamento Conforme o Estado do Processo<\/a>. A impugna\u00e7\u00e3o, pelo autor, das contas apresentadas pelo r\u00e9u dever\u00e1 ser fundamentada e espec\u00edfica, com refer\u00eancia expressa ao lan\u00e7amento questionado.<\/p>\n\n\n\n<p>Se o r\u00e9u resolver apresentar contesta\u00e7\u00e3o, o juiz dever\u00e1 analisar o m\u00e9rito da demanda e, conforme for o caso, proceder \u00e0 instru\u00e7\u00e3o probat\u00f3ria.&nbsp;<\/p>\n\n\n\n<p>Por\u00e9m, caso n\u00e3o conteste o pedido, haver\u00e1 julgamento antecipado do m\u00e9rito, na forma do <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm#art355:~:text=Do%20Julgamento%20Antecipado%20do%20M%C3%A9rito\" target=\"_blank\" rel=\"noreferrer noopener\">artigo 355 do CPC<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-sentenca-na-1\u00aa-fase-e-inicio-da-2\u00aa-fase-da-acao-de-exigir-contas\">Senten\u00e7a na 1\u00aa fase e in\u00edcio da 2\u00aa fase da A\u00e7\u00e3o de Exigir Contas<\/h3>\n\n\n\n<p>A decis\u00e3o que julgar procedente o pedido <strong>condenar\u00e1 o r\u00e9u a prestar as contas no prazo de 15 (quinze) dias, sob pena de n\u00e3o lhe ser l\u00edcito impugnar as que o autor apresentar<\/strong>.<\/p>\n\n\n\n<p>Sendo assim, se ele apresentar as contas no prazo correto, prosseguir-se-\u00e1 o processo na forma do Cap\u00edtulo X &#8211; Do Julgamento Conforme o Estado do Processo. <strong>Ou seja, \u00e9 o mesmo efeito pr\u00e1tico de que se j\u00e1 tivesse apresentado as contas anteriormente.<\/strong><\/p>\n\n\n\n<p>Todavia, caso n\u00e3o as apresente, <strong>o autor apresent\u00e1-las-\u00e1 no prazo de 15 (quinze) dias, podendo o juiz determinar a realiza\u00e7\u00e3o de exame pericial, se necess\u00e1rio.<\/strong><\/p>\n\n\n\n<p>Vejam, portanto, que se o r\u00e9u n\u00e3o cumprir a determina\u00e7\u00e3o da senten\u00e7a da 1\u00aa fase e n\u00e3o apresentar as contas no prazo de 15 dias, n\u00e3o ter\u00e1 direito a impugnar as contas que o autor apresentar, o que pode lhe prejudicar no momento da apura\u00e7\u00e3o do <em>quantum <\/em>devido na segunda fase.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-2\u00aa-fase-da-acao-de-exigir-contas\">2\u00aa fase da A\u00e7\u00e3o de Exigir Contas<\/h4>\n\n\n\n<p>As contas do autor ser\u00e3o apresentadas na forma adequada, j\u00e1 instru\u00eddas com os documentos justificativos, especificando-se as receitas, a aplica\u00e7\u00e3o das despesas e os investimentos, se houver, bem como o respectivo saldo.<\/p>\n\n\n\n<p>Outrossim, o r\u00e9u deve apresentar suas contas especificando as mesmas quest\u00f5es.<\/p>\n\n\n\n<p>Por\u00e9m, havendo impugna\u00e7\u00e3o espec\u00edfica e fundamentada pelo autor, o juiz estabelecer\u00e1 prazo razo\u00e1vel para que o r\u00e9u apresente os documentos justificativos dos lan\u00e7amentos individualmente impugnados.<\/p>\n\n\n\n<p>Desse modo, <strong>a senten\u00e7a apurar\u00e1 o saldo e constituir\u00e1 t\u00edtulo executivo judicial<\/strong>, o que, como j\u00e1 dissemos, pode revelar resultado favor\u00e1vel a qualquer das partes (natureza d\u00faplice).<\/p>\n\n\n\n<p>Por fim, o que vem a seguir \u00e9 o cumprimento de senten\u00e7a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-prestacao-de-contas-dos-administradores-judiciais\">Presta\u00e7\u00e3o de contas dos administradores judiciais<\/h3>\n\n\n\n<p>O artigo 553 do CPC disp\u00f5e para n\u00f3s:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-small-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Art. 553. As contas do inventariante, do tutor, do curador, do deposit\u00e1rio e de qualquer outro administrador ser\u00e3o prestadas em apenso aos autos do processo em que tiver sido nomeado.<\/p>\n\n\n\n<p>Par\u00e1grafo \u00fanico. Se qualquer dos referidos no caput for condenado a pagar o saldo e n\u00e3o o fizer no prazo legal, o juiz poder\u00e1 destitu\u00ed-lo, sequestrar os bens sob sua guarda, glosar o pr\u00eamio ou a gratifica\u00e7\u00e3o a que teria direito e determinar as medidas executivas necess\u00e1rias \u00e0 recomposi\u00e7\u00e3o do preju\u00edzo.<\/p>\n<\/blockquote>\n\n\n\n<p>Humberto Theodoro J\u00fanior, comentando o tema, destaca a possibilidade de as contas dos administradores judiciais serem exigidas tanto por meio da A\u00e7\u00e3o de Exigir Contas quanto de of\u00edcio pelo juiz da demanda em que houver ocorrido a nomea\u00e7\u00e3o:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-small-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Para essas presta\u00e7\u00f5es tanto se pode agir por via de a\u00e7\u00e3o como por meio de delibera\u00e7\u00e3o <em>ex officio<\/em> do pr\u00f3prio juiz. Quando, por exemplo, o juiz age, por for\u00e7a da hierarquia, para exigir as contas do tutor ou curador, n\u00e3o h\u00e1 que se cogitar de a\u00e7\u00e3o no sentido t\u00e9cnico, mas de procedimento administrativo. Quando, por\u00e9m, \u00e9 o herdeiro que demanda as contas do inventariante, a hip\u00f3tese \u00e9 tipicamente de a\u00e7\u00e3o e de procedimento judicial contencioso.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es finais<\/h2>\n\n\n\n<p>Portanto, pessoal, finalizamos por aqui nosso breve resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC\u00a0para Concursos P\u00fablicos. Como vimos, h\u00e1 duas fases distintas e esta a\u00e7\u00e3o possui natureza d\u00faplice, o que a diferencia nesse ponto dos demais procedimentos previstos no C\u00f3digo de Processo Civil.<\/p>\n\n\n\n<p>Considerando que n\u00e3o esgotamos aqui o tema, n\u00e3o deixe de revisar o assunto em seu material de estudos e praticar com diversas quest\u00f5es sobre o tema.<\/p>\n\n\n\n<p>No mais, desejamos um excelente estudo a todos!!<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2020\/09\/18141901\/Coruja_Concursos%404x-506x1024.png\" alt=\"Concursos 2024 Estrat\u00e9gia Concursos\" class=\"wp-image-574355\" style=\"aspect-ratio:0.5;width:30px;height:auto\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\">Concursos 2025<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-estrat-corj\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\" style=\"text-align: left;\">Concursos 2025<\/h3>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Explore os cursos preparat\u00f3rios completos! \u2728<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\" role=\"button\" rel=\"noopener noreferrer\">CLIQUE AQUI<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fala, pessoal, tudo certo? Hoje traremos um resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC (C\u00f3digo de Processo Civil). Trata-se de assunto relevante da mat\u00e9ria de Direito Processual Civil, no que cinge aos procedimentos especiais. Portanto, vamos nessa! A\u00e7\u00e3o de Exigir Contas&nbsp; Previs\u00e3o legal, cabimento e objetivo Primeiramente, destacamos que a A\u00e7\u00e3o de Exigir [&hellip;]<\/p>\n","protected":false},"author":2567,"featured_media":1159931,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1288885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC<\/title>\n<meta name=\"description\" content=\"Confira neste artigo as principais informa\u00e7\u00f5es sobre a A\u00e7\u00e3o de Exigir Contas no CPC em um resumo para Concursos P\u00fablicos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC\" \/>\n<meta property=\"og:description\" content=\"Confira neste artigo as principais informa\u00e7\u00f5es sobre a A\u00e7\u00e3o de Exigir Contas no CPC em um resumo para Concursos P\u00fablicos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-08T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T13:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/\"},\"author\":{\"name\":\"Frederico Tadeu Borlot Peixoto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\"},\"headline\":\"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC\",\"datePublished\":\"2024-02-08T14:00:00+00:00\",\"dateModified\":\"2025-05-09T13:37:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/\"},\"wordCount\":1699,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/\",\"name\":\"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg\",\"datePublished\":\"2024-02-08T14:00:00+00:00\",\"dateModified\":\"2025-05-09T13:37:54+00:00\",\"description\":\"Confira neste artigo as principais informa\u00e7\u00f5es sobre a A\u00e7\u00e3o de Exigir Contas no CPC em um resumo para Concursos P\u00fablicos!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\",\"name\":\"Frederico Tadeu Borlot Peixoto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"caption\":\"Frederico Tadeu Borlot Peixoto\"},\"description\":\"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/proffrederico\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC","description":"Confira neste artigo as principais informa\u00e7\u00f5es sobre a A\u00e7\u00e3o de Exigir Contas no CPC em um resumo para Concursos P\u00fablicos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC","og_description":"Confira neste artigo as principais informa\u00e7\u00f5es sobre a A\u00e7\u00e3o de Exigir Contas no CPC em um resumo para Concursos P\u00fablicos!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2024-02-08T14:00:00+00:00","article_modified_time":"2025-05-09T13:37:54+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg","type":"image\/jpeg"}],"author":"Frederico Tadeu Borlot Peixoto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Frederico Tadeu Borlot Peixoto","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/"},"author":{"name":"Frederico Tadeu Borlot Peixoto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb"},"headline":"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC","datePublished":"2024-02-08T14:00:00+00:00","dateModified":"2025-05-09T13:37:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/"},"wordCount":1699,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/","name":"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg","datePublished":"2024-02-08T14:00:00+00:00","dateModified":"2025-05-09T13:37:54+00:00","description":"Confira neste artigo as principais informa\u00e7\u00f5es sobre a A\u00e7\u00e3o de Exigir Contas no CPC em um resumo para Concursos P\u00fablicos!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/26202500\/cpc2.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/resumo-acao-exigir-contas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo sobre a A\u00e7\u00e3o de Exigir Contas no CPC"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb","name":"Frederico Tadeu Borlot Peixoto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","caption":"Frederico Tadeu Borlot Peixoto"},"description":"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/","sameAs":["https:\/\/www.instagram.com\/proffrederico\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1288885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2567"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1288885"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1288885\/revisions"}],"predecessor-version":[{"id":1573690,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1288885\/revisions\/1573690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1159931"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1288885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1288885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1288885"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1288885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}