{"id":1282845,"date":"2023-09-27T19:52:00","date_gmt":"2023-09-27T22:52:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1282845"},"modified":"2023-09-27T19:52:40","modified_gmt":"2023-09-27T22:52:40","slug":"concurso-ses-df-recursos-avas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/","title":{"rendered":"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS"},"content":{"rendered":"\n<p>Ap\u00f3s a aplica\u00e7\u00e3o das provas <strong>concurso SES DF<\/strong> ao cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS) no \u00faltimo domingo (24), foi divulgado o gabarito provis\u00f3rio da etapa.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Concurso SES DF: <a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/27171359\/avas-2.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">gabarito provis\u00f3rio AVAS<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>Com isso, o per\u00edodo para interposi\u00e7\u00e3o de recursos contra o gabarito de AVAS do concurso SES DF segue aberto at\u00e9 3 de outubro, no site da banca <a href=\"https:\/\/funatec.selecao.net.br\/informacoes\/2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Funatec<\/a>.<\/p>\n\n\n\n<p>O Estrat\u00e9gia Concursos esteve presente durante toda a sua prepara\u00e7\u00e3o, realizou a corre\u00e7\u00e3o da prova e apresentou o <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-extraoficial-agente-ambiental-ses-df\/\" target=\"_blank\" rel=\"noreferrer noopener\">gabarito extraoficial<\/a>.<\/strong> Por isso, nosso time de professores elaborou sugest\u00f5es de recursos para te ajudar em nessa etapa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-cyan-bluish-gray-background-color has-background\" id=\"h-concurso-ses-df-sugestao-de-recursos-para-avas\">Concurso SES DF: sugest\u00e3o de recursos para AVAS<\/h3>\n\n\n\n<p style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.098), 15px);\"><em>Aten\u00e7\u00e3o: a prova utilizada para elaborar os recursos foi do <strong>tipo B<\/strong>. Voc\u00ea pode conferir cada quest\u00e3o pelo enunciado.<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quest\u00e3o 24<\/strong><\/p>\n\n\n\n<p>Gabarito provis\u00f3rio: item C<\/p>\n\n\n\n<p>Letra A: ERRADA. O per\u00edodo de reuni\u00e3o se d\u00e1 a cada 4 anos e \u00e9 convocada pelo Poder Executivo ou, extraordinariamente, por esta ou pelo Conselho de Sa\u00fade.<\/p>\n\n\n\n<p>\u201c\u00a7 1\u00b0 A Confer\u00eancia de Sa\u00fade reunir-se-\u00e1 a cada quatro anos com a representa\u00e7\u00e3o dos v\u00e1rios segmentos sociais, para avaliar a situa\u00e7\u00e3o de sa\u00fade e propor as diretrizes para a formula\u00e7\u00e3o da pol\u00edtica de sa\u00fade nos n\u00edveis correspondentes, convocada pelo Poder Executivo ou, extraordinariamente, por esta ou pelo Conselho de Sa\u00fade.\u201d<\/p>\n\n\n\n<p>Letra B ERRADA. Apresenta composi\u00e7\u00e3o deficiente.<\/p>\n\n\n\n<p>\u201c\u00a7 2\u00b0 O Conselho de Sa\u00fade, em car\u00e1ter permanente e deliberativo, \u00f3rg\u00e3o colegiado composto por representantes do governo, prestadores de servi\u00e7o, profissionais de sa\u00fade e usu\u00e1rios, atua na formula\u00e7\u00e3o de estrat\u00e9gias e no controle da execu\u00e7\u00e3o da pol\u00edtica de sa\u00fade na inst\u00e2ncia correspondente, inclusive nos aspectos econ\u00f4micos e financeiros, cujas decis\u00f5es ser\u00e3o homologadas pelo chefe do poder legalmente constitu\u00eddo em cada esfera do governo.\u201d<\/p>\n\n\n\n<p>Letra C &#8211; Conforme Artigo 1 \u00a7 3\u00b0 O Conselho Nacional de Secret\u00e1rios de Sa\u00fade (Conass) e o Conselho Nacional de Secret\u00e1rios Municipais de Sa\u00fade (Conasems) ter\u00e3o representa\u00e7\u00e3o no <strong>Conselho Nacional de Sa\u00fade<\/strong> e <strong>N\u00c3O NA CONFER\u00caNCIA DE SA\u00daDE, portanto, est\u00e1 INCORRETA!<\/strong><\/p>\n\n\n\n<p>Letra D &#8211; O texto \u00e9 id\u00eantico ao que consta no Art. 1 \u00a7 4\u00b0.<\/p>\n\n\n\n<p><strong>Conclus\u00e3o: Solicitar troca de gabarito de &#8220;C&#8221; para &#8220;D&#8221;.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quest\u00e3o 49<\/strong><\/p>\n\n\n\n<p>As quest\u00f5es 49 e 69 abordam o conhecimento relacionado \u00e0 Portaria 2914\/2011.<\/p>\n\n\n\n<p>Apesar de concordar com o gabarito da quest\u00e3o, cabe ressaltar, que de acordo com o edital de retifica\u00e7\u00e3o n\u00famero 4, editado em 23\/08\/2023 a Portaria 2914\/2011 <strong>foi exclu\u00edda<\/strong> do conte\u00fado program\u00e1tico do concurso.<\/p>\n\n\n\n<p><strong>Conclus\u00e3o: sendo assim, solicita-se a anula\u00e7\u00e3o, uma vez que a cobran\u00e7a da Portaria 2914\/2011 extrapola o conte\u00fado solicitado no edital.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quest\u00e3o 57<\/strong><\/p>\n\n\n\n<p>Considerando as compet\u00eancias da Vigil\u00e2ncia Sanit\u00e1ria no \u00e2mbito do SUS do Distrito Federal de acordo com o disposto na Lei 5.321\/2014 que incluem medidas de controle sanit\u00e1rio em estabelecimentos e produtos de interesse direto ou indireto para a sa\u00fade, \u00e9 imperativo ressaltar que n\u00e3o \u00e9 exclusivo ao Poder P\u00fablico a prote\u00e7\u00e3o contra os riscos que podem ensejar a ocorr\u00eancia de danos irrevers\u00edveis \u00e0 vida, \u00e0 sa\u00fade individual e coletiva e ao meio ambiente, haja vista que as atribui\u00e7\u00f5es dos \u00f3rg\u00e3os devem ser articuladas entre si, como demonstra o Par\u00e1grafo \u00danico da Lei 5.321\/2014:<\/p>\n\n\n\n<p>Par\u00e1grafo \u00fanico. As atribui\u00e7\u00f5es elencadas nos incisos anteriores devem ser exercidas de modo articulado com \u00f3rg\u00e3os e sistemas de outros setores do Poder P\u00fablico do Distrito Federal que atuam na vigil\u00e2ncia e na fiscaliza\u00e7\u00e3o de mat\u00e9rias de interesse direto ou indireto para a sa\u00fade.<\/p>\n\n\n\n<p>Desta forma, compete ao SUS do Distrito Federal no \u00e2mbito do poder P\u00fablico, Vigil\u00e2ncia Sanit\u00e1ria, Epidemiol\u00f3gica e Ambiental em Sa\u00fade a an\u00e1lise dos riscos e danos irrevers\u00edveis \u00e0 sa\u00fade coletiva, individual e ao meio ambiente.<\/p>\n\n\n\n<p><strong>Conclus\u00e3o: Solicitamos anula\u00e7\u00e3o da quest\u00e3o, uma vez que a alternativa B est\u00e1 prevista na legisla\u00e7\u00e3o, portanto n\u00e3o considerada uma exce\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quest\u00e3o 67<\/strong><\/p>\n\n\n\n<p>Gabarito provis\u00f3rio: item C<\/p>\n\n\n\n<p>Quest\u00e3o trata do Artigo segundo da Lei 8142 90.<\/p>\n\n\n\n<p><em>Art. 2\u00b0 Os recursos do Fundo Nacional de Sa\u00fade (FNS) ser\u00e3o alocados como:<\/em><\/p>\n\n\n\n<p><em>I &#8211; despesas de custeio e de capital do Minist\u00e9rio da Sa\u00fade, seus \u00f3rg\u00e3os e entidades, da administra\u00e7\u00e3o direta e indireta;<\/em><\/p>\n\n\n\n<p><em>II &#8211; investimentos previstos em lei or\u00e7ament\u00e1ria, de iniciativa do Poder Legislativo e aprovados pelo Congresso Nacional;<\/em><\/p>\n\n\n\n<p><em>III &#8211; investimentos previstos no Plano Q\u00fcinq\u00fcenal do Minist\u00e9rio da Sa\u00fade;<\/em><\/p>\n\n\n\n<p><em>IV &#8211; cobertura das a\u00e7\u00f5es e servi\u00e7os de sa\u00fade a serem implementados pelos Munic\u00edpios, Estados e Distrito Federal.<\/em><\/p>\n\n\n\n<p>Letra A: ERRADA n\u00e3o consta na lista de possibilidade de aloca\u00e7\u00e3o de recursos, portanto, certamente \u00e9 a alternativa errada, conforme comando da quest\u00e3o.<\/p>\n\n\n\n<p>Letra B: CERTA. Coerente com o item I do Art. 2<\/p>\n\n\n\n<p>Letra C: CERTA. Coerente com o item III do Art. 2 (portanto, n\u00e3o pode ser o gabarito, j\u00e1 que a quest\u00e3o pede a errada!)<\/p>\n\n\n\n<p>Letra D: ERRADA. Se assemelha ao item III do Art. 2, no entanto, a literalidade diz &#8220;investimentos previstos&#8221; e n\u00e3o esfor\u00e7os e tamb\u00e9m n\u00e3o seria do financiamento do Minist\u00e9rio da Sa\u00fade.<\/p>\n\n\n\n<p><strong>Conclus\u00e3o: solicitar anula\u00e7\u00e3o da quest\u00e3o visto que a A \u00e9 sabidamente errada, no entanto, a D n\u00e3o representa com exatid\u00e3o o que consta na referida Lei.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quest\u00e3o 69<\/strong><\/p>\n\n\n\n<p>A quest\u00e3o 69 aborda o conhecimento relacionado a Portaria 2914\/2011, especificamente os casos onde \u00e9 necess\u00e1ria a notifica\u00e7\u00e3o.<\/p>\n\n\n\n<p>A banca considerou correta a Letra C \u201cDeteriora\u00e7\u00f5es que coloquem em risco os sistemas de abastecimento&#8221;<\/p>\n\n\n\n<p>No entanto, cabe ressaltar, as seguintes pondera\u00e7\u00f5es:<\/p>\n\n\n\n<p>Portaria 2914\/2011.<\/p>\n\n\n\n<p>Art. 26. Compete ao respons\u00e1vel pela opera\u00e7\u00e3o do sistema de abastecimento de \u00e1gua para consumo humano <strong>notificar \u00e0 autoridade de sa\u00fade p\u00fablica e informar \u00e0 respectiva entidade reguladora e \u00e0 popula\u00e7\u00e3o, identificando per\u00edodos e locais, sempre que houver:<\/strong><\/p>\n\n\n\n<p>I &#8211; situa\u00e7\u00f5es de emerg\u00eancia com potencial para atingir a seguran\u00e7a de pessoas e bens;<\/p>\n\n\n\n<p>II &#8211; interrup\u00e7\u00e3o, press\u00e3o negativa ou intermit\u00eancia no sistema de abastecimento;<\/p>\n\n\n\n<p>III &#8211; necessidade de realizar opera\u00e7\u00e3o programada na rede de distribui\u00e7\u00e3o, que possa submeter trechos a press\u00e3o negativa;<\/p>\n\n\n\n<p>IV &#8211; modifica\u00e7\u00f5es ou melhorias de qualquer natureza nos sistemas de abastecimento; e<\/p>\n\n\n\n<p>V &#8211; situa\u00e7\u00f5es que possam oferecer risco \u00e0 sa\u00fade.<\/p>\n\n\n\n<p>Assim, entende-se que a notifica\u00e7\u00e3o deve acontecer em:<\/p>\n\n\n\n<p>&nbsp;\u201cSitua\u00e7\u00f5es de emerg\u00eancia com potencial para atingir a seguran\u00e7a de pessoas e bens\u201d; <strong>informa\u00e7\u00e3o compat\u00edvel com a alternativa A.<\/strong><\/p>\n\n\n\n<p>\u201c Interrup\u00e7\u00e3o, press\u00e3o negativa ou intermit\u00eancia no sistema de abastecimento;\u201d&nbsp; <strong>informa\u00e7\u00e3o compat\u00edvel com a letra B, pois, interrup\u00e7\u00e3o press\u00e3o negativa ou intermit\u00eancia s\u00e3o sin\u00f4nimos de descontinuidade do sistema de abastecimento.<\/strong><\/p>\n\n\n\n<p><strong>Conclus\u00e3o: portanto, solicita-se a anula\u00e7\u00e3o da quest\u00e3o, uma vez que possui compatibilidade com mais de uma alternativa.<\/strong><\/p>\n\n\n\n<p><em>Para saber mais informa\u00e7\u00f5es sobre o concurso SES DF, acesse o artigo completo e exclusivo no blog do Estrat\u00e9gia Concursos!<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-cyan-bluish-gray-background-color has-background\" id=\"concurso-secretaria-de-saude-df\" style=\"font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.49), 19px);\">Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso Secretaria de Sa\u00fade DF<\/a><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2024<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"banner-medicina\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Concurso SES DF<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/secretaria-de-saude-df\/\" role=\"button\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a>\r\n        <\/div>\r\n      <\/div>\r\n    \r\n\r\n  <\/div>\r\n<\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div>\r\n     \r\n    <\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a aplica\u00e7\u00e3o das provas concurso SES DF ao cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS) no \u00faltimo domingo (24), foi divulgado o gabarito provis\u00f3rio da etapa. Com isso, o per\u00edodo para interposi\u00e7\u00e3o de recursos contra o gabarito de AVAS do concurso SES DF segue aberto at\u00e9 3 de outubro, no site da [&hellip;]<\/p>\n","protected":false},"author":2041,"featured_media":1052777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[1981,220219],"tags":[],"tax_estado":[219970],"class_list":["post-1282845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude","category-noticias","tax_estado-df"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS<\/title>\n<meta name=\"description\" content=\"Concurso SES DF: confira as sugest\u00f5es de recursos contra o gabarito provis\u00f3rio do cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS\" \/>\n<meta property=\"og:description\" content=\"Concurso SES DF: confira as sugest\u00f5es de recursos contra o gabarito provis\u00f3rio do cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T22:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-27T22:52:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thiago Cavalcante Gomes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thiago Cavalcante Gomes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/\"},\"author\":{\"name\":\"Thiago Cavalcante Gomes\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4970184533d0a3ffa5b0299ae0a2b21f\"},\"headline\":\"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS\",\"datePublished\":\"2023-09-27T22:52:00+00:00\",\"dateModified\":\"2023-09-27T22:52:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/\"},\"wordCount\":1251,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg\",\"articleSection\":[\"Sa\u00fade\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/\",\"name\":\"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg\",\"datePublished\":\"2023-09-27T22:52:00+00:00\",\"dateModified\":\"2023-09-27T22:52:40+00:00\",\"description\":\"Concurso SES DF: confira as sugest\u00f5es de recursos contra o gabarito provis\u00f3rio do cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg\",\"width\":300,\"height\":169,\"caption\":\"concurso ses df\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4970184533d0a3ffa5b0299ae0a2b21f\",\"name\":\"Thiago Cavalcante Gomes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"Thiago Cavalcante Gomes\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/thiago-gomes\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS","description":"Concurso SES DF: confira as sugest\u00f5es de recursos contra o gabarito provis\u00f3rio do cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS","og_description":"Concurso SES DF: confira as sugest\u00f5es de recursos contra o gabarito provis\u00f3rio do cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS).","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-09-27T22:52:00+00:00","article_modified_time":"2023-09-27T22:52:40+00:00","og_image":[{"width":300,"height":169,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg","type":"image\/jpeg"}],"author":"Thiago Cavalcante Gomes","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Thiago Cavalcante Gomes","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/"},"author":{"name":"Thiago Cavalcante Gomes","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4970184533d0a3ffa5b0299ae0a2b21f"},"headline":"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS","datePublished":"2023-09-27T22:52:00+00:00","dateModified":"2023-09-27T22:52:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/"},"wordCount":1251,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg","articleSection":["Sa\u00fade","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/","name":"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg","datePublished":"2023-09-27T22:52:00+00:00","dateModified":"2023-09-27T22:52:40+00:00","description":"Concurso SES DF: confira as sugest\u00f5es de recursos contra o gabarito provis\u00f3rio do cargo de Agente de Vigil\u00e2ncia Ambiental em Sa\u00fade (AVAS).","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/06\/30064521\/ses-df-edital-autorizado.jpg","width":300,"height":169,"caption":"concurso ses df"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-ses-df-recursos-avas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso SES DF: confira a sugest\u00e3o de recursos de AVAS"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/4970184533d0a3ffa5b0299ae0a2b21f","name":"Thiago Cavalcante Gomes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Thiago Cavalcante Gomes"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/thiago-gomes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1282845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2041"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1282845"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1282845\/revisions"}],"predecessor-version":[{"id":1284473,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1282845\/revisions\/1284473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1052777"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1282845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1282845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1282845"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1282845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}