{"id":1282215,"date":"2023-10-15T08:00:00","date_gmt":"2023-10-15T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1282215"},"modified":"2025-06-30T17:14:28","modified_gmt":"2025-06-30T20:14:28","slug":"intervencao-estado-propriedade-cnu","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/","title":{"rendered":"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU"},"content":{"rendered":"\n<p>Bem-vindos! Neste artigo abordaremos pontos importantes a respeito das modalidades de Interven\u00e7\u00e3o do Estado na Propriedade, voltado para o t\u00e3o aguardado concurso do Concurso Nacional Unificado (CNU).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"853\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-1024x853.jpg\" alt=\"Interven\u00e7\u00e3o do Estado na Propriedade\" class=\"wp-image-1282217\" style=\"width:465px;height:388px\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-1024x853.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-300x250.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-768x640.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-1536x1280.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-2048x1707.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-610x508.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-150x125.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Inicialmente, vale ressaltar que o Governo Federal apresentou detalhes da proposta para realiza\u00e7\u00e3o de concurso unificado para os \u00f3rg\u00e3os que comp\u00f5em a sua estrutura, com edital previsto at\u00e9 20 de dezembro do ano de 2023, com aplica\u00e7\u00e3o das provas em meados ou fim de mar\u00e7o de 2024.<\/p>\n\n\n\n<p>Portanto, \u00e9 certo que o tema abordado aqui estar\u00e1 presente na prova, uma vez que a disciplina de Direito Administrativo \u00e9 componente frequente na maioria dos editais.<\/p>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><ul><li><a href=\"#h-introducao\" data-level=\"2\">Introdu\u00e7\u00e3o<\/a><\/li><li><a href=\"#h-servidao-administrativa-primeira-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\" data-level=\"2\">Servid\u00e3o Administrativa \u2013 Primeira modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/a><\/li><li><a href=\"#h-requisicao-administrativa-segunda-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\" data-level=\"2\">Requisi\u00e7\u00e3o Administrativa \u2013 Segunda modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/a><\/li><li><a href=\"#h-ocupacao-temporaria-terceira-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\" data-level=\"2\">Ocupa\u00e7\u00e3o Tempor\u00e1ria &#8211; Terceira modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/a><\/li><li><a href=\"#h-limitacoes-administrativa-quarta-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\" data-level=\"2\">Limita\u00e7\u00f5es Administrativa &#8211; Quarta modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/a><\/li><li><a href=\"#h-tombamento-quinta-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\" data-level=\"2\">Tombamento &#8211; Quinta modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/a><\/li><li><a href=\"#h-desapropriacao-sexta-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\" data-level=\"2\">Desapropria\u00e7\u00e3o &#8211; Sexta modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/a><\/li><li><a href=\"#h-conclusao\" data-level=\"2\">Conclus\u00e3o<\/a><\/li><li><a href=\"#cursos-assinatura\" data-level=\"2\">Quer estudar para o pr\u00f3ximo Concurso Nacional Unificado (CNU)?<\/a><\/li><li><a href=\"#h-quer-saber-tudo-sobre-concursos-previstos-confira-os-nossos-artigos\" data-level=\"2\">Quer saber tudo sobre concursos previstos? Confira os nossos artigos!<\/a><\/li><\/ul><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n\n    <div class=\"col-sm\">\n      <div class=\"banner-federais\" id=\"box-assinatura\">\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Cursos para o CNU<\/h2>\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepare-se para o &#8220;Enem dos Concursos&#8221;!<\/p>\n        <div class=\"box-botao\" style=\"text-align: left;\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/concurso-nacional-unificado-cnu\/\" role=\"button\" rel=\"noopener noreferrer\">Confira os pacotes!<\/a>\n        <\/div>\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-introducao\">Introdu\u00e7\u00e3o<\/h2>\n\n\n\n<p>A interven\u00e7\u00e3o do Estado na propriedade privada \u00e9 sempre uma quest\u00e3o sens\u00edvel, envolvendo um equil\u00edbrio delicado entre o interesse p\u00fablico e os direitos individuais dos propriet\u00e1rios.<\/p>\n\n\n\n<p>Primeiramente, tenhamos em mente que a <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm\">Carta Magna<\/a> <strong>prev\u00ea o direito fundamental \u00e0 propriedade, o qual dever\u00e1 atender sua fun\u00e7\u00e3o social<\/strong>, insculpido no artigo 5<sup>o<\/sup>, XXII e XXIII.<\/p>\n\n\n\n<p>Ocorre que, como todo direito fundamental, o<strong> direito \u00e0 propriedade n\u00e3o \u00e9 absoluto e possui limita\u00e7\u00f5es<\/strong>.<\/p>\n\n\n\n<p>Assim, h\u00e1 diversas hip\u00f3teses em que o poder p\u00fablico poder\u00e1 intervir &#8211; limitar os poderes inerentes \u00e0 propriedade de um bem alheio &#8211; sob o pretexto de cumprir a fun\u00e7\u00e3o social da propriedade, utilizando-se do princ\u00edpio pilar da Supremacia do Interesse P\u00fablico, abordadas a seguir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-servidao-administrativa-primeira-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\">Servid\u00e3o Administrativa \u2013 Primeira modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/h2>\n\n\n\n<p>A servid\u00e3o administrativa uma das modalidades mais comuns de interven\u00e7\u00e3o do estado na propriedade. \u00c9 <strong>direito real <\/strong>p\u00fablico, que permite o uso de parte de im\u00f3vel particular pela Administra\u00e7\u00e3o P\u00fablica para executar obras ou servi\u00e7os de interesse coletivo.<\/p>\n\n\n\n<p>Exemplificando, temos as situa\u00e7\u00f5es em que \u00e9 necess\u00e1ria a passagem pela propriedade de cabos de fibra \u00f3tica, ou a mais comum: a instala\u00e7\u00e3o de placas de orienta\u00e7\u00e3o nos muros, cal\u00e7adas ou fachadas.<\/p>\n\n\n\n<p>Logo, a servid\u00e3o sempre recai sobre<strong> bens im\u00f3veis, possui car\u00e1ter de perpetuidade<\/strong> e, para que produza <strong>efeito contra terceiros<\/strong>, <strong>deve ser registrada no Cart\u00f3rio de Registro de Im\u00f3veis.<\/strong><\/p>\n\n\n\n<p>Ainda, como regra, <strong>n\u00e3o enseja o pagamento de indeniza\u00e7\u00e3o<\/strong> pelo mero uso de parte do im\u00f3vel pelo poder p\u00fablico. Exce\u00e7\u00e3o \u00e9 o caso de comprovado dano ao particular que suporta sacrif\u00edcio desproporcional pela servid\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-requisicao-administrativa-segunda-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\">Requisi\u00e7\u00e3o Administrativa \u2013 Segunda modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/h2>\n\n\n\n<p>Por sua vez, a Requisi\u00e7\u00e3o ocorre quando o Estado toma<strong> temporariamente<\/strong> o controle de bens m\u00f3veis ou im\u00f3veis para atender a necessidades p\u00fablicas urgentes. Nas palavras da CRFB\/88 em seu artigo 5<sup>o<\/sup>, inciso XXV,<strong> quando houver iminente perigo p\u00fablico<\/strong>.<\/p>\n\n\n\n<p>Assim, \u00e9 utilizada nos casos de calamidade p\u00fablica como inunda\u00e7\u00f5es, inc\u00eandios, cat\u00e1strofes ou pandemias como a do Coronav\u00edrus (COVID-19), em que hospitais privados sofreram a interven\u00e7\u00e3o na busca de disponibiliza\u00e7\u00e3o de leitos de SUS, em meio ao colapso na rede de sa\u00fade.<\/p>\n\n\n\n<p>Entretanto, deve-se atentar ao fato que, <strong>caso haja dano, \u00e9 assegurada ao propriet\u00e1rio indeniza\u00e7\u00e3o ulterior<\/strong>. A regra \u00e9 que o particular n\u00e3o seja indenizado.<\/p>\n\n\n\n<p>Outrossim, o <a href=\"https:\/\/portal.stf.jus.br\/noticias\/verNoticiaDetalhe.asp?idConteudo=489371&amp;ori=1\">Supremo Tribunal Federal entendeu<\/a> ser inconstitucional esta modalidade de interven\u00e7\u00e3o restritiva de bens de uma unidade federativa por outra.<\/p>\n\n\n\n<p>Portanto, <strong>sob pena de violar-se o pacto federativo<\/strong>, a Uni\u00e3o, Estado e Munic\u00edpio <strong>n\u00e3o podem requisitar administrativamente os bens uns dos outros<\/strong>, em situa\u00e7\u00e3o de normalidade, excepcionada a situa\u00e7\u00e3o de Estado de Defesa ou de S\u00edtio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-ocupacao-temporaria-terceira-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\">Ocupa\u00e7\u00e3o Tempor\u00e1ria &#8211; Terceira modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/h2>\n\n\n\n<p>Por conseguinte, a ocupa\u00e7\u00e3o tempor\u00e1ria, similar \u00e0 \u00faltima hip\u00f3tese de interven\u00e7\u00e3o do estado na propriedade, envolve a utiliza\u00e7\u00e3o por <strong>prazo determinado<\/strong> de bens privados para fins p\u00fablicos, como a execu\u00e7\u00e3o de obras p\u00fablicas ou a presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos.<\/p>\n\n\n\n<p>Nestes termos, em situa\u00e7\u00f5es <strong>n\u00e3o emergenciais<\/strong>, ser\u00e1 assegurado ao particular <strong>compensa\u00e7\u00e3o pecuni\u00e1ria <\/strong>para, por exemplo, alojar em determinado bem im\u00f3vel maquin\u00e1rios ou equipamentos voltados para obras p\u00fablicas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-limitacoes-administrativa-quarta-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\">Limita\u00e7\u00f5es Administrativa &#8211; Quarta modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/h2>\n\n\n\n<p>Por sua vez, as limita\u00e7\u00f5es administrativas <strong>envolvem obriga\u00e7\u00f5es de fazer ou n\u00e3o fazer, visando que a propriedade privada atenda sua fun\u00e7\u00e3o social.<\/strong><\/p>\n\n\n\n<p>Dessa forma, temos determina\u00e7\u00f5es gerais que incluem limitar constru\u00e7\u00f5es para adequa\u00e7\u00e3o ao Plano Diretor Municipal, limitar contidas nas Leis de Uso e Ocupa\u00e7\u00e3o do Solo, ou mesmo visando a prote\u00e7\u00e3o ambiental.<\/p>\n\n\n\n<p>Como regra, <strong>n\u00e3o h\u00e1 direito \u00e0 indeniza\u00e7\u00e3o aos particulares afetados<\/strong> por esta interven\u00e7\u00e3o estatal, salvo quando ocorrerem danos desproporcionais ou quando a limita\u00e7\u00e3o for t\u00e3o dominante que impossibilite a utiliza\u00e7\u00e3o do bem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-tombamento-quinta-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\">Tombamento &#8211; Quinta modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/h2>\n\n\n\n<p>Em sequ\u00eancia, temos o tombamento. Esta modalidade de interven\u00e7\u00e3o da Administra\u00e7\u00e3o P\u00fablica na propriedade<strong> busca <a href=\"http:\/\/portal.iphan.gov.br\/pagina\/detalhes\/126#:~:text=Sob%20a%20tutela%20do%20Iphan,hist%C3%B3ricos%2C%20terreiros%20e%20s%C3%ADtios%20arqueol%C3%B3gicos.\">a prote\u00e7\u00e3o dos patrim\u00f4nios hist\u00f3ricos, art\u00edsticos e culturais do pa\u00eds.<\/a><\/strong><\/p>\n\n\n\n<p><strong>Os entes federativos podem tombar os bens, inclusive uns dos outros<\/strong>, inscrevendo-os nos Livros do Tombo, para evitar destrui\u00e7\u00e3o ou deteriora\u00e7\u00e3o do bem.<\/p>\n\n\n\n<p>No entanto, o tombamento n\u00e3o gera direito \u00e0 indeniza\u00e7\u00e3o, uma vez que continuar\u00e1 exercendo os direitos inerentes \u00e0 propriedade, com limita\u00e7\u00f5es para preservar a integridade do bem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-desapropriacao-sexta-modalidade-de-intervencao-do-estado-na-propriedade-para-o-cnu\">Desapropria\u00e7\u00e3o &#8211; Sexta modalidade de Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/h2>\n\n\n\n<p>Por fim, como \u00faltima forma de interven\u00e7\u00e3o do Estado na propriedade alheia, tem-se a dr\u00e1stica medida de desapropria\u00e7\u00e3o, em que o Estado <strong>adquire propriedade privada de forma permanente<\/strong> e em regra,<strong> indeniza o propriet\u00e1rio de maneira pr\u00e9via, justa e em dinheiro.<\/strong><\/p>\n\n\n\n<p>Portanto, <strong>quando houver necessidade p\u00fablica, utilidade p\u00fablica ou interesse social<\/strong>, o Estado poder\u00e1 valer-se da medida.<\/p>\n\n\n\n<p>Ademais, \u00e9 importante destacar que a <strong>Uni\u00e3o, Estados, Distrito Federal e Munic\u00edpios possuem hierarquia para utiliza\u00e7\u00e3o da desapropria\u00e7\u00e3o de bens sobre outro ente federativo.<\/strong><\/p>\n\n\n\n<p>Ou seja, a Uni\u00e3o poder\u00e1 desapropriar bens dos Estados, do DF e dos Munic\u00edpios, mas estes n\u00e3o poder\u00e3o faz\u00ea-lo em face da Uni\u00e3o. A mesma l\u00f3gica vale para os Estados em desfavor dos Munic\u00edpios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-conclusao\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Finalmente, a interven\u00e7\u00e3o estatal na propriedade \u00e9 um tema complexo e fundamental na \u00e1rea de Direito Administrativo. \u00c9 essencial compreender as v\u00e1rias modalidades de interven\u00e7\u00e3o e as circunst\u00e2ncias espec\u00edficas que as envolvem, especialmente em prepara\u00e7\u00e3o para o Concurso Nacional Unificado (CNU).<\/p>\n\n\n\n<p>\u00c9 importante manter-se atualizado, estudar por materiais de qualidade e acompanhar as mudan\u00e7as na legisla\u00e7\u00e3o e na jurisprud\u00eancia, pr\u00e1ticas essenciais para um estudo eficaz. <\/p>\n\n\n\n<p>Este artigo e as quest\u00f5es dispon\u00edveis no Sistema de Quest\u00f5es do Estrat\u00e9gia Concursos podem ser usados como complemento ao estudo. Priorize sempre o material te\u00f3rico apresentado nos PDFs das aulas.<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima! Bons estudos!<\/p>\n\n\n\n<p class=\"has-text-align-center has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-nacional-unificado\/\" target=\"_blank\" rel=\"noreferrer noopener\">CNU<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"cursos-assinatura\"><em>Quer estudar para o pr\u00f3ximo Concurso Nacional Unificado (CNU)?<\/em><\/h2>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"banner-federais\" id=\"box-assinatura\">\r\n        <h2 class=\"titulo-assinatura\" style=\"text-align: left;\">Cursos para o CNU<\/h2>\r\n        <p class=\"subtitulo-assinatura\" style=\"text-align: left;\">Prepare-se para o &#8220;Enem dos Concursos&#8221;!<\/p>\r\n        <div class=\"box-botao\" style=\"text-align: left;\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/concurso-nacional-unificado-cnu\/\" role=\"button\" rel=\"noopener noreferrer\">Confira os pacotes!<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"container\" id=\"boxes\">\r\n  <div class=\"row\">\r\n\r\n    <div class=\"col-sm\">\r\n      <div class=\"estrategia\" id=\"box-assinatura\">\r\n        <h3 class=\"titulo-assinatura\">Assinatura Concursos<\/h3>\r\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\r\n        <div class=\"box-botao\">\r\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\r\n        <\/div>\r\n      <\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos-confira-os-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira os nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-left\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2026<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-federais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Federais<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bem-vindos! Neste artigo abordaremos pontos importantes a respeito das modalidades de Interven\u00e7\u00e3o do Estado na Propriedade, voltado para o t\u00e3o aguardado concurso do Concurso Nacional Unificado (CNU). Inicialmente, vale ressaltar que o Governo Federal apresentou detalhes da proposta para realiza\u00e7\u00e3o de concurso unificado para os \u00f3rg\u00e3os que comp\u00f5em a sua estrutura, com edital previsto at\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2667,"featured_media":1282217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,214992],"tags":[],"tax_estado":[219963],"class_list":["post-1282215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-concursos-administrativos","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Interven\u00e7\u00e3o do Estado na Propriedade para o CNU<\/title>\n<meta name=\"description\" content=\"Aprenda mais sobre o tema Interven\u00e7\u00e3o do Estado na Propriedade voltado para o Concurso Nacional Unificado (CNU).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU\" \/>\n<meta property=\"og:description\" content=\"Aprenda mais sobre o tema Interven\u00e7\u00e3o do Estado na Propriedade voltado para o Concurso Nacional Unificado (CNU).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-15T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T20:14:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Boscioni Bearsi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Boscioni Bearsi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/\"},\"author\":{\"name\":\"Gabriel Boscioni Bearsi\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bc447e28b914ddacff5a58e269383e14\"},\"headline\":\"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU\",\"datePublished\":\"2023-10-15T11:00:00+00:00\",\"dateModified\":\"2025-06-30T20:14:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/\"},\"wordCount\":1362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Executivo (Administrativa)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/\",\"name\":\"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg\",\"datePublished\":\"2023-10-15T11:00:00+00:00\",\"dateModified\":\"2025-06-30T20:14:28+00:00\",\"description\":\"Aprenda mais sobre o tema Interven\u00e7\u00e3o do Estado na Propriedade voltado para o Concurso Nacional Unificado (CNU).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg\",\"width\":2560,\"height\":2133,\"caption\":\"Direito de Propriedade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bc447e28b914ddacff5a58e269383e14\",\"name\":\"Gabriel Boscioni Bearsi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3ca2fe751506a8b2ae34ff7bc7c5cd8764f2cdb29eb1e129a6400ef48f516fa2?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ca2fe751506a8b2ae34ff7bc7c5cd8764f2cdb29eb1e129a6400ef48f516fa2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ca2fe751506a8b2ae34ff7bc7c5cd8764f2cdb29eb1e129a6400ef48f516fa2?s=96&d=mm&r=g\",\"caption\":\"Gabriel Boscioni Bearsi\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gboscionibearsigmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU","description":"Aprenda mais sobre o tema Interven\u00e7\u00e3o do Estado na Propriedade voltado para o Concurso Nacional Unificado (CNU).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/","og_locale":"pt_BR","og_type":"article","og_title":"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU","og_description":"Aprenda mais sobre o tema Interven\u00e7\u00e3o do Estado na Propriedade voltado para o Concurso Nacional Unificado (CNU).","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-10-15T11:00:00+00:00","article_modified_time":"2025-06-30T20:14:28+00:00","og_image":[{"width":2560,"height":2133,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg","type":"image\/jpeg"}],"author":"Gabriel Boscioni Bearsi","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Gabriel Boscioni Bearsi","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/"},"author":{"name":"Gabriel Boscioni Bearsi","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bc447e28b914ddacff5a58e269383e14"},"headline":"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU","datePublished":"2023-10-15T11:00:00+00:00","dateModified":"2025-06-30T20:14:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/"},"wordCount":1362,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg","articleSection":["Concursos P\u00fablicos","Executivo (Administrativa)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"accessibilityFeature":["tableOfContents"]},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/","name":"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg","datePublished":"2023-10-15T11:00:00+00:00","dateModified":"2025-06-30T20:14:28+00:00","description":"Aprenda mais sobre o tema Interven\u00e7\u00e3o do Estado na Propriedade voltado para o Concurso Nacional Unificado (CNU).","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/09\/23020230\/intervencao-do-estado-na-propriedade-cnu-scaled.jpg","width":2560,"height":2133,"caption":"Direito de Propriedade"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/intervencao-estado-propriedade-cnu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Interven\u00e7\u00e3o do Estado na Propriedade para o CNU"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/bc447e28b914ddacff5a58e269383e14","name":"Gabriel Boscioni Bearsi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ca2fe751506a8b2ae34ff7bc7c5cd8764f2cdb29eb1e129a6400ef48f516fa2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ca2fe751506a8b2ae34ff7bc7c5cd8764f2cdb29eb1e129a6400ef48f516fa2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ca2fe751506a8b2ae34ff7bc7c5cd8764f2cdb29eb1e129a6400ef48f516fa2?s=96&d=mm&r=g","caption":"Gabriel Boscioni Bearsi"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gboscionibearsigmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1282215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2667"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1282215"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1282215\/revisions"}],"predecessor-version":[{"id":1598735,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1282215\/revisions\/1598735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1282217"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1282215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1282215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1282215"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1282215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}