{"id":127865,"date":"2018-06-21T14:45:20","date_gmt":"2018-06-21T17:45:20","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=127865"},"modified":"2018-06-21T14:45:20","modified_gmt":"2018-06-21T17:45:20","slug":"gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/","title":{"rendered":"Gabarito comentado &#8211; Delegado da Pol\u00edcia Civil do Piaui 2018 &#8211; CRIMINOLOGIA"},"content":{"rendered":"<p><strong>Criminologia PC PI<\/strong><\/p>\n<p>Sauda\u00e7\u00f5es guerreiros (as), espero que todos tenham ido bem nessa prova de Delegado da Pol\u00edcia Civil do Piaui. Analisando a prova, \u00e9 percept\u00edvel que os alunos do nosso curso, tiveram acesso a todo conte\u00fado de criminologia!<\/p>\n<p>Antes de resolvemos as quest\u00f5es e formularmos o GABARITO COMENTADO, deixarei um gr\u00e1fico demonstrando o que foi cobrado pela Banca!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5982\" src=\"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg\" alt=\"\" width=\"417\" height=\"245\" \/><\/p>\n<p>Visto o \u00edndice de cada pergunta, vamos agora solucionar todas as quest\u00f5es, alternativa por alternativa!!<\/p>\n<p>Sem mais delongas, vamos resolver todas as quest\u00f5es do concurso!<\/p>\n<p>Quer saber mais sobre Criminologia e Direito Penal? Ent\u00e3o me siga das redes sociais!<\/p>\n<p>Instagram https:\/\/www.instagram.com\/fernandotadeumarques\/<\/p>\n<p>Facebook https:\/\/web.facebook.com\/proffernandotadeumarques\/<\/p>\n<p>https:\/\/web.facebook.com\/fernandotadeumarques<\/p>\n<p>Vamos l\u00e1?<\/p>\n<p><strong>Quest\u00e3o 91. Sociologia Criminal-Aula 03.<\/strong><\/p>\n<p>O crime \u00e9 um comportamento valorado pelo direito. Acerca da Sociologia Criminal, podemos afirmar<\/p>\n<p>a) Ci\u00eancia que tem como finalidade o estudo do criminoso-nato, sob seu aspecto amplo e integral: psicol\u00f3gico, social, econ\u00f4mico e jur\u00eddico.<\/p>\n<p>b) Ci\u00eancia que explica a correla\u00e7\u00e3o crime sociedade, sua motiva\u00e7\u00e3o, bem como sua perpetua\u00e7\u00e3o.<\/p>\n<p>c) Busca, precipuamente, explicar e justificar os fatores psicol\u00f3gicos que levam ao crime.<\/p>\n<p>d) Tem como objetivo maior, a ressocializa\u00e7\u00e3o do preso, estabelecendo estudos de inclus\u00e3o social.<\/p>\n<p>e) Ci\u00eancia que estuda as rela\u00e7\u00f5es entre as pessoas que pertencem a uma comunidade, e se ocupa em estudar a vida social humana.<\/p>\n<p>Coment\u00e1rios: Vejamos alternativa por alternativa:<\/p>\n<p><strong>Alternativa A, errada.<\/strong> O estudo do criminoso pertence a Escola Positiva, que pertenceu a antropologia criminal.<\/p>\n<p><strong>Alternativa B, certa.<\/strong> Por meio de uma diversidade de teorias, sejam estas do consenso ou do conflito a Sociologia Criminal \u00e9 uma ci\u00eancia que explica a correla\u00e7\u00e3o crime sociedade, sua motiva\u00e7\u00e3o, bem como sua perpetua\u00e7\u00e3o.<\/p>\n<p><strong>Alternativa C, errada.\u00a0 <\/strong>A Sociologia Criminal \u00e9 uma ci\u00eancia que explica a correla\u00e7\u00e3o crime sociedade, sua motiva\u00e7\u00e3o, bem como sua perpetua\u00e7\u00e3o, valorando os fatores ex\u00f3genos e n\u00e3o end\u00f3genos.<\/p>\n<p><strong>Alternativa D, errada.<\/strong> A ressocializa\u00e7\u00e3o do recluso \u00e9 conte\u00fado que pertence a preven\u00e7\u00e3o do crime.<\/p>\n<p><strong>Alternativa E, errada.<\/strong> N\u00e3o busca entender as rela\u00e7\u00f5es entre as pessoas que pertencem a uma comunidade, e\u00a0 n\u00e3o se ocupa em estudar a vida social humana, visa explicar a correla\u00e7\u00e3o crime e sociedade.<\/p>\n<p><strong>Quest\u00e3o 92.\u00a0 Vitimologia- Aula 03<\/strong><\/p>\n<p>Sobre a Vitimologia, assinale a alternativa CORRETA.<\/p>\n<p>a) De acordo com a classifica\u00e7\u00e3o das v\u00edtimas, formulada por Mendelsohn, a v\u00edtima simuladora \u00e9 aquela que volunt\u00e1ria ou imprudentemente, colabora com o \u00e2nimo criminoso do agente.<\/p>\n<p>b) \u00c9 denominada terci\u00e1ria a vitimiza\u00e7\u00e3o que corresponde aos danos causados \u00e0 v\u00edtima em decorr\u00eancia do crime.<\/p>\n<p>c) De acordo com a ONU, apenas s\u00e3o consideradas v\u00edtimas as pessoas que, individual ou coletivamente, tenham sofrido les\u00f5es f\u00edsicas ou mentais, por atos ou omiss\u00f5es que representem viola\u00e7\u00f5es \u00e0s leis penais, inclu\u00eddas as leis referentes ao abuso criminoso do poder.<\/p>\n<p>d) O surgimento da Vitimologia ocorreu no in\u00edcio do s\u00e9culo XVIII, com os estudos pioneiros de Hans Von Hentig, seguido por Mendelsohn.<\/p>\n<p>e) \u00c9 denominada secund\u00e1ria a vitimiza\u00e7\u00e3o causada pelas inst\u00e2ncias formais de controle social, no decorrer do processo de registro e apura\u00e7\u00e3o do crime.<\/p>\n<p>Coment\u00e1rios: Coment\u00e1rios: Vejamos alternativa por alternativa:<\/p>\n<p><strong>Alternativa A, errada.<\/strong> A v\u00edtima simuladora \u00e9 aquela que por sua conduta acaba que justificando a conduta de seu agressor, assim sua a\u00e7\u00e3o \u00e9 considerada como leg\u00edtima defesa. A defini\u00e7\u00e3o dada pelo enunciado, se refere a v\u00edtima provocadora.<\/p>\n<p><strong>Alternativa B, errada. <\/strong>O enunciado retrata a vitimiza\u00e7\u00e3o prim\u00e1ria e n\u00e3o terci\u00e1ria. A vitimiza\u00e7\u00e3o terci\u00e1ria consiste no preconceito da sociedade em face da v\u00edtima, o pr\u00f3prio grupo social por vezes incentiva a v\u00edtima a calar-se diante do crime. Majoritariamente esse processo de vitimiza\u00e7\u00e3o se faz presente nos crimes sexuais, que ofendem a dignidade da v\u00edtima.<\/p>\n<p><strong>Alternativa C, errada.<\/strong> Resolu\u00e7\u00e3o 40\/34 da Assembleia Geral das Na\u00e7\u00f5es Unidas, de 29 de Novembro de 1985 a respeito da defini\u00e7\u00e3o de v\u00edtima:\u00a0 \u201cPessoa que, individual ou colectivamente, tenha sofrido danos, inclusive les\u00f5es f\u00edsicas ou mentais, sofrimento emocional, perda financeira ou diminui\u00e7\u00e3o substancial de seus direitos fundamentais, como consequ\u00eancias de a\u00e7\u00f5es ou omiss\u00f5es que violem a legisla\u00e7\u00e3o penal vigente, nos Estados \u2013 Membros, inclu\u00edda a que prescreve o abuso de poder\u201d.<\/p>\n<p><strong>Alternativa D, errada.<\/strong> O estudo das v\u00edtimas tiveram in\u00edcio em 1901 na figura de Hans Gross, todavia somente na d\u00e9cada de 1940, que o estudo passou a ganhar uma sistem\u00e1tica com Von Hentig e Benjamim Mendelsohn.<\/p>\n<p><strong>Alternativa E, certa.<\/strong> A vitimiza\u00e7\u00e3o secund\u00e1ria consiste no preju\u00edzo da interven\u00e7\u00e3o estatal, dado seu descaso com a v\u00edtima. Desse modo, a v\u00edtima sofre o descaso do aparelho estatal, logo na fase inicial da persecu\u00e7\u00e3o penal (fase investigativa), sendo tratada com desconfian\u00e7a. Atrelada a esta vitimiza\u00e7\u00e3o, est\u00e1 o que conhecemos de cifra negra, que consiste em um conjunto de crimes que n\u00e3o chegam ao conhecimento do Estado, ou quando chegam, n\u00e3o recebem a tutela adequada .<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Aula 93. Conceito de Criminologia- Aula 01<\/strong><\/p>\n<p>Sobre a Criminologia \u00e9 CORRETO afirmar:<\/p>\n<p>a) o crime \u00e9 um fen\u00f4meno social.<\/p>\n<p>b) estuda o crime, o criminoso, mas n\u00e3o a v\u00edtima.<\/p>\n<p>c) \u00e9 uma ci\u00eancia normativa e valorativa.<\/p>\n<p>d) o crime \u00e9 um fen\u00f4meno filos\u00f3fico.<\/p>\n<p>e) n\u00e3o tem por base a observa\u00e7\u00e3o e a experi\u00eancia.<\/p>\n<p>Coment\u00e1rios: Vejamos alternativa por alternativa:<\/p>\n<p><strong>Alternativa A, certa. <\/strong>O CRIME quando estudado na criminologia ganha um panorama diferente de observa\u00e7\u00e3o, uma vez que nesta enfatiza-se para o crime como um problema social e comunit\u00e1rio. Aborda-se neste sentido uma diversidade de elementos para entender o fen\u00f4meno social, como o aumento populacional.<\/p>\n<p><strong>Alternativa B, errada. <\/strong>A criminologia tem por objeto de estudo, o crime, a v\u00edtima, o criminoso e o controle social.<\/p>\n<p><strong>Alternativa C, errada. <\/strong>Antonio Garc\u00eda Pablos Molina e Lu\u00eds Fl\u00e1vio Gomes, em comento ao m\u00e9todo de estudo da criminologia, afirmaram que a criminologia \u00e9 uma ci\u00eancia do ser, emp\u00edrica (ou seja, pautada na observa\u00e7\u00e3o da criminalidade), enquanto que, o Direito \u00e9 uma ci\u00eancia cultural do dever ser, normativa.<\/p>\n<p><strong>Alternativa D, errada. <\/strong>O crime \u00e9 um fen\u00f4meno social.<\/p>\n<p><strong>Alternativa E, errada.<\/strong> A criminologia \u00e9 uma ci\u00eancia do ser, emp\u00edrica ou seja, pautada na observa\u00e7\u00e3o da criminalidade. \u00c9 uma ci\u00eancia emp\u00edrica e interdisciplinar.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Quest\u00e3o 94. Hist\u00f3ria da Criminologia- Aula 02.<\/strong><\/p>\n<p>Acerca da Hist\u00f3ria da Criminologia, marque a alternativa CORRETA:<\/p>\n<p>a) Desde a Antiguidade, o Direito Penal, em concreto, passou a ser compilado em C\u00f3digos e \u00e2mbitos jur\u00eddicos, tal qual como nos dias de hoje, entretanto, algumas vezes eram imprecisos.<\/p>\n<p>b) O C\u00f3digo de Hamurabi (Babil\u00f4nia) possu\u00eda dispositivos, punindo furtos, roubos, mas n\u00e3o considerava crime, a corrup\u00e7\u00e3o praticada por altos funcion\u00e1rios p\u00fablicos.<\/p>\n<p>c) Durante a Antiguidade, o crime era considerado pecado, somente na Idade M\u00e9dia, \u00e9 que a dignidade da pessoa humana passou a ser considerada, e as puni\u00e7\u00f5es deixaram de ser cru\u00e9is.<\/p>\n<p>d) Em sua obra \u201cA Pol\u00edtica\u201d, Arist\u00f3teles, ressaltou que a mis\u00e9ria causa rebeli\u00e3o e delito. Para o referido fil\u00f3sofo, os delitos mais graves eram os cometidos para possuir o voluptu\u00e1rio, o sup\u00e9rfluo.<\/p>\n<p>e) Da Antiguidade \u00e0 Modernidade, o furto fam\u00e9lico (roubar para comer) nunca foi considerado crime.<\/p>\n<p>Coment\u00e1rios: Vejamos alternativa por alternativa:<\/p>\n<p><strong>Alternativa A, errada. <\/strong>Na antiguidade n\u00e3o se tinha compila\u00e7\u00f5es do Direito Penal, o costume preponderava.<\/p>\n<p><strong>Alternativa B, errada<\/strong>. O C\u00f3digo de Hamurabi tamb\u00e9m fazia previs\u00e3o de penas para os altos funcion\u00e1rios p\u00fablicos. Tal c\u00f3digo no cap\u00edtulo que trata dos direitos e deveres dos oficiais, dos greg\u00e1rios e dos vassalos em geral, prev\u00ea uma diversidade de penas para os altos funcion\u00e1rios p\u00fablicos.<\/p>\n<p><strong>Alternativa C, errada. <\/strong>A alternativa est\u00e1 totalmente equivocada no per\u00edodo da idade m\u00e9dia, teve-se uma forte influ\u00eancia da Igreja no Direito Penal, assim o crime era visto como um pecado, esse entendimento, inclusive fez parte da concep\u00e7\u00e3o de criminoso, da Escola Cl\u00e1ssica.<\/p>\n<p><strong>Alternativa D, certa. <\/strong>Como vimos em sala, Arist\u00f3teles seguiu a mesma linha de pensamento de Plat\u00e3o, assim para eles a gan\u00e2ncia, a cobi\u00e7a ou cupidez geram a criminalidade. Estudo da etiologia do crime, an\u00e1lise das causas da criminalidade.<\/p>\n<p><strong>Alternativa E, errada.<\/strong> A t\u00edtulo de exemplo, o C\u00f3digo de Hamurabi n\u00e3o previa tal modalidade de furto.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Classifica\u00e7\u00e3o dos Criminosos- Aula 04<\/strong><\/p>\n<p>Quest\u00e3o 95. Marque a alternativa CORRETA, no que diz respeito \u00e0 classifica\u00e7\u00e3o do criminoso, segundo Lombroso:<\/p>\n<p>a) Criminoso louco: \u00e9 o tipo de criminoso que tem instinto para a pr\u00e1tica de delitos, \u00e9 uma esp\u00e9cie de selvagem para a sociedade.<\/p>\n<p>b) Criminoso nato: \u00e9 aquele tipo de criminoso malvado, perverso, que deve sobreviver em manic\u00f4mios.<\/p>\n<p>c) Criminoso por paix\u00e3o: aquele que utiliza de viol\u00eancia para resolver problemas passionais, geralmente \u00e9 nervoso, irritado e leviano.<\/p>\n<p>d) Criminoso por paix\u00e3o: este aponta uma tend\u00eancia heredit\u00e1ria, possui h\u00e1bitos criminosos influenciados pela ocasi\u00e3o.<\/p>\n<p>e) Criminoso louco: \u00e9 o criminoso s\u00f3rdido com defici\u00eancia do senso moral e com h\u00e1bitos criminosos influenciados pela situa\u00e7\u00e3o.<\/p>\n<p>Coment\u00e1rios: Vejamos alternativa por alternativa:<\/p>\n<p><strong>Alternativa A, errada. <\/strong>Os criminosos loucos devem ficar segregados da sociedade, em um manic\u00f4mio, uma vez que s\u00e3o perversos, loucos morais, alienados mentais.<\/p>\n<p><strong>Alternativa B, errada.<\/strong> O criminoso nato \u00e9 aquele degenerado de cabe\u00e7a pequena, deformada, fronte fugidia, sobrancelhas salientes, ma\u00e7\u00e3s afastadas, orelhas malformadas, bra\u00e7os compridos, face enorme, tatuado, impulsivo, mentiroso e falador de g\u00edrias etc. Sofre influ\u00eancia biol\u00f3gica . \u00c9 um indiv\u00edduo que, sofre alguma forma de epilepsia, com suas correspondentes les\u00f5es cerebrais.<\/p>\n<p><strong>Alternativa C, certa<\/strong>. Os criminosos por paix\u00e3o se utilizam da viol\u00eancia como forma de resolu\u00e7\u00e3o de conflitos passionais, possuem por caracter\u00edstica a exalta\u00e7\u00e3o, o nervosismo.<\/p>\n<p><strong>Alternativa D, errada.<\/strong> Os criminosos por paix\u00e3o se utilizam da viol\u00eancia como forma de resolu\u00e7\u00e3o de conflitos passionais, possuem por caracter\u00edstica a exalta\u00e7\u00e3o, o nervosismo.<\/p>\n<p><strong>Alternativa E, errada.<\/strong> Os criminosos loucos devem ficar segregados da sociedade, em um manic\u00f4mio, uma vez que s\u00e3o perversos, loucos morais, alienados mentais.<\/p>\n<p>Espero que tenha conseguido alcan\u00e7ar uma boa pontua\u00e7\u00e3o.<\/p>\n<p>Conte sempre comigo,\u00a0 e com meu assistente Jhonatan!<\/p>\n<p>Abra\u00e7os.<\/p>\n<p>Prof. Fernando Tadeu Marques<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Criminologia PC PI Sauda\u00e7\u00f5es guerreiros (as), espero que todos tenham ido bem nessa prova de Delegado da Pol\u00edcia Civil do Piaui. Analisando a prova, \u00e9 percept\u00edvel que os alunos do nosso curso, tiveram acesso a todo conte\u00fado de criminologia! Antes de resolvemos as quest\u00f5es e formularmos o GABARITO COMENTADO, deixarei um gr\u00e1fico demonstrando o que [&hellip;]<\/p>\n","protected":false},"author":548,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,2185,1988],"tags":[2239,1573,376,503],"tax_estado":[],"class_list":["post-127865","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","category-carreiras-juridicas","category-policia","tag-carreiras-juridicas","tag-carreiras-policiais","tag-criminologia","tag-direito-penal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gabarito comentado - Delegado da Pol\u00edcia Civil do Piaui 2018 - CRIMINOLOGIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabarito comentado - Delegado da Pol\u00edcia Civil do Piaui 2018 - CRIMINOLOGIA\" \/>\n<meta property=\"og:description\" content=\"Criminologia PC PI Sauda\u00e7\u00f5es guerreiros (as), espero que todos tenham ido bem nessa prova de Delegado da Pol\u00edcia Civil do Piaui. Analisando a prova, \u00e9 percept\u00edvel que os alunos do nosso curso, tiveram acesso a todo conte\u00fado de criminologia! Antes de resolvemos as quest\u00f5es e formularmos o GABARITO COMENTADO, deixarei um gr\u00e1fico demonstrando o que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-21T17:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg\" \/>\n<meta name=\"author\" content=\"Fernando Tadeu Marques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Tadeu Marques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/\"},\"author\":{\"name\":\"Fernando Tadeu Marques\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6384118f85a8d5d2e47f382adb5212ac\"},\"headline\":\"Gabarito comentado &#8211; Delegado da Pol\u00edcia Civil do Piaui 2018 &#8211; CRIMINOLOGIA\",\"datePublished\":\"2018-06-21T17:45:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/\"},\"wordCount\":1769,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg\",\"keywords\":[\"carreiras jur\u00eddicas\",\"carreiras policiais\",\"criminologia\",\"Direito Penal\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Jur\u00eddico\",\"Policial (Agente, Escriv\u00e3o e Investigador)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/\",\"name\":\"Gabarito comentado - Delegado da Pol\u00edcia Civil do Piaui 2018 - CRIMINOLOGIA\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg\",\"datePublished\":\"2018-06-21T17:45:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage\",\"url\":\"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg\",\"contentUrl\":\"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabarito comentado &#8211; Delegado da Pol\u00edcia Civil do Piaui 2018 &#8211; CRIMINOLOGIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6384118f85a8d5d2e47f382adb5212ac\",\"name\":\"Fernando Tadeu Marques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/db46753d1710d516e196d843432ec2430c6e9516c37d5ab61d5d2bcc0ca28a01?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db46753d1710d516e196d843432ec2430c6e9516c37d5ab61d5d2bcc0ca28a01?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db46753d1710d516e196d843432ec2430c6e9516c37d5ab61d5d2bcc0ca28a01?s=96&d=mm&r=g\",\"caption\":\"Fernando Tadeu Marques\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fernandotmarqueshotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gabarito comentado - Delegado da Pol\u00edcia Civil do Piaui 2018 - CRIMINOLOGIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/","og_locale":"pt_BR","og_type":"article","og_title":"Gabarito comentado - Delegado da Pol\u00edcia Civil do Piaui 2018 - CRIMINOLOGIA","og_description":"Criminologia PC PI Sauda\u00e7\u00f5es guerreiros (as), espero que todos tenham ido bem nessa prova de Delegado da Pol\u00edcia Civil do Piaui. Analisando a prova, \u00e9 percept\u00edvel que os alunos do nosso curso, tiveram acesso a todo conte\u00fado de criminologia! Antes de resolvemos as quest\u00f5es e formularmos o GABARITO COMENTADO, deixarei um gr\u00e1fico demonstrando o que [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2018-06-21T17:45:20+00:00","og_image":[{"url":"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg","type":"","width":"","height":""}],"author":"Fernando Tadeu Marques","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Fernando Tadeu Marques","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/"},"author":{"name":"Fernando Tadeu Marques","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6384118f85a8d5d2e47f382adb5212ac"},"headline":"Gabarito comentado &#8211; Delegado da Pol\u00edcia Civil do Piaui 2018 &#8211; CRIMINOLOGIA","datePublished":"2018-06-21T17:45:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/"},"wordCount":1769,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage"},"thumbnailUrl":"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg","keywords":["carreiras jur\u00eddicas","carreiras policiais","criminologia","Direito Penal"],"articleSection":["Concursos P\u00fablicos","Jur\u00eddico","Policial (Agente, Escriv\u00e3o e Investigador)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/","name":"Gabarito comentado - Delegado da Pol\u00edcia Civil do Piaui 2018 - CRIMINOLOGIA","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage"},"thumbnailUrl":"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg","datePublished":"2018-06-21T17:45:20+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#primaryimage","url":"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg","contentUrl":"https:\/\/s3-sa-east-1.amazonaws.com\/estrategia-blogs-prod\/oab\/wp-content\/uploads\/2018\/06\/12013724\/Estatistica-quest%C3%B5es-Concurso-de-investigador1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/gabarito-comentado-delegado-da-policia-civil-do-piaui-2018-criminologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gabarito comentado &#8211; Delegado da Pol\u00edcia Civil do Piaui 2018 &#8211; CRIMINOLOGIA"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/6384118f85a8d5d2e47f382adb5212ac","name":"Fernando Tadeu Marques","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/db46753d1710d516e196d843432ec2430c6e9516c37d5ab61d5d2bcc0ca28a01?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/db46753d1710d516e196d843432ec2430c6e9516c37d5ab61d5d2bcc0ca28a01?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db46753d1710d516e196d843432ec2430c6e9516c37d5ab61d5d2bcc0ca28a01?s=96&d=mm&r=g","caption":"Fernando Tadeu Marques"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fernandotmarqueshotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/127865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/548"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=127865"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/127865\/revisions"}],"predecessor-version":[{"id":127870,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/127865\/revisions\/127870"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=127865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=127865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=127865"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=127865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}