{"id":1265703,"date":"2023-09-11T08:00:00","date_gmt":"2023-09-11T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1265703"},"modified":"2023-08-30T10:34:09","modified_gmt":"2023-08-30T13:34:09","slug":"prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/","title":{"rendered":"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ"},"content":{"rendered":"\n<p>Ol\u00e1 turma, como est\u00e3o os estudos? Estamos aqui para comentar o entendimento do STF e do STJ acerca da prescri\u00e7\u00e3o e da decad\u00eancia relacionadas \u00e0 concess\u00e3o e\/ou \u00e0 revis\u00e3o de benef\u00edcios previdenci\u00e1rios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1-1024x682.jpg\" alt=\"Benef\u00edcios previdenci\u00e1rios\n\" class=\"wp-image-987819\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1-1024x682.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1-300x200.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1-768x512.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1-1536x1024.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1-2048x1365.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1-610x407.jpg 610w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Benef\u00edcios previdenci\u00e1rios<\/figcaption><\/figure>\n\n\n\n<p>Apesar da especializa\u00e7\u00e3o do direito previdenci\u00e1rio, a cl\u00e1ssica doutrina do professor Agnelo Amorim Filho<a id=\"sdfootnote1anc\" href=\"#sdfootnote1sym\"><sup>1<\/sup><\/a> aplica-se aos conceitos de prescri\u00e7\u00e3o e decad\u00eancia nessa seara. Nesse sentido, segundo o ilustre professor da UFPB, a prescri\u00e7\u00e3o atinge indiretamente as a\u00e7\u00f5es condenat\u00f3rias e a decad\u00eancia atinge de modo indireto as a\u00e7\u00f5es constitutivas, cujo direito potestativo protegido tem prazo espec\u00edfico para ser exercido.<\/p>\n\n\n\n<p>O direito a benef\u00edcios previdenci\u00e1rios sujeita-se \u00e0 incid\u00eancia de prazos prescricionais e\/ou decadenciais, conforme a pretens\u00e3o buscada pelo benefici\u00e1rio, sendo que essa tem\u00e1tica, desde o ano de 2012, vem sendo reiteradamente modificada de forma legislativa e\/ou jurisprudencial. No presente texto, essas altera\u00e7\u00f5es ser\u00e3o examinadas.<\/p>\n\n\n\n<p>Nesse contexto, conforme elucidam Carlos Alberto Pereira de Castro e Jo\u00e3o Batista Lazzari<a href=\"#sdfootnote2sym\" id=\"sdfootnote2anc\"><sup>2<\/sup><\/a>, deve-se atentar inicialmente que, &#8220;pela sua natureza de direito fundamental, inexiste qualquer prazo prescricional, que atinja o fundo de direito, na hip\u00f3tese de pleito de concess\u00e3o inicial de benef\u00edcio previdenci\u00e1rio ou assistencial, ainda que haja ocorrido indeferimento administrativa, ressalvada eventual prescri\u00e7\u00e3o das parcelas vencidas&#8221;.<\/p>\n\n\n\n<p>No pr\u00f3ximo t\u00f3pico, veremos que inexiste tamb\u00e9m prazo decadencial a fulminar pleito de concess\u00e3o ou de altera\u00e7\u00e3o judicial de indeferimento administrativo de benef\u00edcio previdenci\u00e1rio, ante sua natureza de direito fundamental.<\/p>\n\n\n\n<p>Entretanto, ainda veremos a seguir que o pleito de revis\u00e3o de benef\u00edcio previdenci\u00e1rio anteriormente concedido pelo INSS sujeita-se \u00e0 prescri\u00e7\u00e3o parcial, assim como a prazo decadencial, segundo reconhecido pela jurisprud\u00eancia atual do STF e do STJ.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-prescricao-e-decadencia-de-beneficios-previdenciarios-inicio-da-discussao\">Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios: in\u00edcio da discuss\u00e3o<\/h2>\n\n\n\n<p>Segundo as li\u00e7\u00f5es de Carlos Alberto Pereira de Castro e Jo\u00e3o Batista Lazzari<a id=\"sdfootnote3anc\" href=\"#sdfootnote3sym\"><sup>3<\/sup><\/a>, no direito positivo brasileiro, inexistia qualquer prazo de decad\u00eancia relacionado a benef\u00edcios previdenci\u00e1rios no per\u00edodo transcorrido entre a vig\u00eancia da <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8213cons.htm\">Lei n. 8.213\/1991<\/a> e o ano de 1997, com o advento da <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/mpv\/1996-2000\/1523-9.htm#:~:text=1523%2D9&amp;text=MEDIDA%20PROVIS%C3%93RIA%20No%201.523,27%20DE%20JUNHO%20DE%201997.&amp;text=Altera%20dispositivos%20das%20Leis%20n%C2%BAs,que%20lhe%20confere%20o%20art.\">Medida Provis\u00f3ria n. 1.523-9\/1997<\/a>.<\/p>\n\n\n\n<p>Quanto \u00e0 prescri\u00e7\u00e3o, no \u00e2mbito do Direito Previdenci\u00e1rio, aplica-se o <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/decreto\/antigos\/d20910.htm\">Decreto n. 20.910\/1932<\/a>, tendo os tribunais firmado entendimento acerca da incid\u00eancia do prazo quinquenal a extinguir pedidos de presta\u00e7\u00f5es mensais relativas a benef\u00edcios previdenci\u00e1rios<a id=\"sdfootnote4anc\" href=\"#sdfootnote4sym\"><sup>4<\/sup><\/a>, sem afetar, contudo, o fundo de direito dessa pretens\u00e3o, ante a natureza fundamental dos benef\u00edcios previdenci\u00e1rios.<\/p>\n\n\n\n<p>Essa jurisprud\u00eancia foi consolidada em enunciados sumulares do STF, do extinto Tribunal Federal de Recursos e do STJ. Confiram-se:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>S\u00famula n. 443\/STF: A prescri\u00e7\u00e3o das presta\u00e7\u00f5es anteriores ao per\u00edodo previsto em lei n\u00e3o ocorre, quando n\u00e3o tiver sido negado, antes daquele prazo, o pr\u00f3prio direito reclamado, ou a situa\u00e7\u00e3o jur\u00eddica de que ele resulta.<\/li>\n\n\n\n<li>S\u00famula n. 107\/TRF: A a\u00e7\u00e3o de cobran\u00e7a de cr\u00e9dito previdenci\u00e1rio contra a Fazenda P\u00fablica est\u00e1 sujeita \u00e0 prescri\u00e7\u00e3o quinquenal estabelecida no Decreto n. 20.910, de 1932.<\/li>\n\n\n\n<li>S\u00famula n. 85\/STJ: Nas rela\u00e7\u00f5es jur\u00eddicas de trato sucessivo, em que a Fazenda P\u00fablica figure como devedora, quando n\u00e3o tiver sido negado o pr\u00f3prio direito reclamado, a prescri\u00e7\u00e3o atinge apenas as presta\u00e7\u00f5es vencidas antes do quinqu\u00eanio anterior \u00e0 propositura da a\u00e7\u00e3o.<\/li>\n<\/ul>\n\n\n\n<p>Com a vig\u00eancia da MP 1.523\/1997 (1\u00ba\/8\/1997), que deu nova reda\u00e7\u00e3o ao art. 103 da Lei n. 8.213\/1991, inaugurou-se o prazo decadencial para o benefici\u00e1rio postular a revis\u00e3o do ato de concess\u00e3o do direito previdenci\u00e1rio. Tal prazo, inicialmente previsto em 5 (cinco) anos, foi majorado para 10 (dez) anos com a <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2004-2006\/2004\/lei\/l10.839.htm\">Lei n. 10.839\/2004<\/a>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Art. 103. \u00c9 de dez anos o prazo de decad\u00eancia de todo e qualquer direito ou a\u00e7\u00e3o do segurado ou benefici\u00e1rio <strong>para a revis\u00e3o do ato de concess\u00e3o de benef\u00edcio<\/strong>, a contar do dia primeiro do m\u00eas seguinte ao do recebimento da primeira presta\u00e7\u00e3o ou, quando for o caso, do dia em que tomar conhecimento da decis\u00e3o indeferit\u00f3ria definitiva no \u00e2mbito administrativo.<\/li>\n<\/ul>\n\n\n\n<p>A partir da previs\u00e3o desse prazo decadencial, iniciou-se uma discuss\u00e3o jurisprudencial sobre a aplica\u00e7\u00e3o da decad\u00eancia e da prescri\u00e7\u00e3o para se buscar o deferimento de benef\u00edcios previdenci\u00e1rios, a qual ganhou novos cap\u00edtulos com o advento da Lei n. 13.846\/2019, que objetivou ampliar a aplica\u00e7\u00e3o da decad\u00eancia em mat\u00e9ria de benef\u00edcios previdenci\u00e1rio, dando ao referido art. 103 a seguinte reda\u00e7\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Art. 103. O prazo de decad\u00eancia do direito ou da a\u00e7\u00e3o do segurado ou benefici\u00e1rio para a <strong>revis\u00e3o do ato de concess\u00e3o, indeferimento, cancelamento ou cessa\u00e7\u00e3o de benef\u00edcio e do ato de deferimento, indeferimento ou n\u00e3o concess\u00e3o de revis\u00e3o de benef\u00edcio<\/strong> \u00e9 de 10 (dez) anos [&#8230;]<\/li>\n<\/ul>\n\n\n\n<p>\u00c9 essa discuss\u00e3o que se pretende analisar no presente texto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-legitimidade-da-decadencia-para-a-revisao-de-beneficio-ja-concedido\">Legitimidade da decad\u00eancia para a revis\u00e3o de benef\u00edcio j\u00e1 concedido<\/h2>\n\n\n\n<p>O debate jurisprudencial teve in\u00edcio em 2012, com o julgado repetitivo do STJ, no qual ficou definido que &#8220;O suporte de incid\u00eancia do prazo decadencial previsto no art. 103 da Lei 8.213\/1991 \u00e9 o direito de revis\u00e3o dos benef\u00edcios, e n\u00e3o o direito ao benef\u00edcio previdenci\u00e1rio&#8221;, com termo <em>a quo<\/em> a contar da sua vig\u00eancia (28.6.1997)&#8221; (<u><a href=\"https:\/\/scon.stj.jus.br\/SCON\/GetInteiroTeorDoAcordao?num_registro=201200330130&amp;dt_publicacao=04\/06\/2013\">REsp n. 1.309.529\/PR, relator Ministro Herman Benjamin, Primeira Se\u00e7\u00e3o, julgado em 28\/11\/2012, DJe de 4\/6\/2013<\/a>)<\/u>.<\/p>\n\n\n\n<p>Posteriormente, com o julgamento, pelo STF, do <u><a href=\"https:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=TP&amp;docID=6760827\">RE n. 626.489\/SE<\/a><\/u>, o tema voltou a ser debatido, tendo o Supremo analisado a constitucionalidade do estabelecimento de um prazo decadencial na seara previdenci\u00e1ria em desfavor do benefici\u00e1rio, tendo por base o art. 103 da Lei n. 8.213\/1991, com reda\u00e7\u00e3o dada pela Lei n. 10.839\/2004.<\/p>\n\n\n\n<p>Nessa oportunidade, o STF consolidou o entendimento j\u00e1 presente em julgados anteriores, segundo o qual &#8220;O direito \u00e0 previd\u00eancia social constitui direito fundamental e, uma vez implementados os pressupostos de sua aquisi\u00e7\u00e3o, n\u00e3o deve ser afetado pelo decurso do tempo. Como consequ\u00eancia, inexiste prazo decadencial para a concess\u00e3o inicial do benef\u00edcio previdenci\u00e1rio&#8221;.<\/p>\n\n\n\n<p>Por\u00e9m, nesse mesmo julgamento, o Supremo reconheceu a legitimidade da previs\u00e3o legal de um prazo decadencial contra o benefici\u00e1rio, especificamente para &#8220;a revis\u00e3o de benef\u00edcio j\u00e1 concedido&#8221;, tendo por fundamento o princ\u00edpio da seguran\u00e7a jur\u00eddica, manifestado no interesse de se evitar a eterniza\u00e7\u00e3o dos lit\u00edgios, al\u00e9m do argumento pragm\u00e1tico da necessidade de equil\u00edbrio financeiro e atuarial do sistema previdenci\u00e1rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-prescricao-e-decadencia-para-a-concessao-de-beneficio-previdenciario\">Prescri\u00e7\u00e3o e decad\u00eancia para a concess\u00e3o de benef\u00edcio previdenci\u00e1rio<\/h2>\n\n\n\n<p>Conforme antecipado acima, em 2019, a Lei n. 13.846, fruto da convers\u00e3o da MP n. 871\/2019, alterou a reda\u00e7\u00e3o do art. 103 da Lei n. 8.213\/1991, objetivando expandir a decad\u00eancia na seara previdenci\u00e1ria para casos de concess\u00e3o, indeferimento, deferimento, cancelamento ou cessa\u00e7\u00e3o de benef\u00edcio.<\/p>\n\n\n\n<p>Analisando a nova reda\u00e7\u00e3o do art. 103 da Lei n. 8.213\/1991 e a conclus\u00e3o adotada pelo STF, ao julgar o RE n. 626.489\/SE, o Superior Tribunal de Justi\u00e7a fixou entendimento repetitivo no final de 2019, no sentido de que o prazo decadencial de 10 (dez) anos \u00e9 aplic\u00e1vel mesmo &#8220;\u00e0s hip\u00f3teses em que a quest\u00e3o controvertida n\u00e3o foi apreciada no ato administrativo de an\u00e1lise de concess\u00e3o de benef\u00edcio previdenci\u00e1rio&#8221; (<u><a href=\"https:\/\/scon.stj.jus.br\/SCON\/GetInteiroTeorDoAcordao?num_registro=201603308183&amp;dt_publicacao=04\/08\/2020\">REsp n. 1.644.191\/RS, relator Ministro Herman Benjamin, Primeira Se\u00e7\u00e3o, julgado em 11\/12\/2019, DJe de 4\/8\/2020<\/a><\/u>).<\/p>\n\n\n\n<p>O STJ, examinando pedido de benef\u00edcio previdenci\u00e1rio de regime pr\u00f3prio, analisou novamente a conclus\u00e3o adotada pelo STF, nos autos do RE n. 626.489\/SE, e entendeu que, apenas quando inexistir manifesta\u00e7\u00e3o expressa da Administra\u00e7\u00e3o, negando o direito reclamado, \u00e9 que haveria imprescritibilidade do fundo de direito ao benef\u00edcio previdenci\u00e1rio, incidindo, nesses casos, somente a prescri\u00e7\u00e3o das presta\u00e7\u00f5es vencidas no quinqu\u00eanio anterior ao ajuizamento da a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por outro lado, nessa mesma assentada, o STJ estabeleceu que, existindo expresso indeferimento do pedido administrativo referente ao benef\u00edcio previdenci\u00e1rio, o interessado teria o prazo prescricional de 5 (cinco) anos, com base no art. 1\u00ba do Decreto-Lei 20.910\/1932, para requerer judicialmente esse direito, sob pena de prescri\u00e7\u00e3o do pr\u00f3prio fundo de direito (<u><a href=\"https:\/\/scon.stj.jus.br\/SCON\/GetInteiroTeorDoAcordao?num_registro=201200989264&amp;dt_publicacao=01\/10\/2021\">EDcl nos EREsp n. 1.269.726\/MG, relator Ministro Manoel Erhardt (Desembargador Convocado do TRF5), Primeira Se\u00e7\u00e3o, julgado em 25\/8\/2021, DJe de 1\/10\/2021<\/a><\/u>).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-imprescritibilidade-para-a-concessao-de-beneficio-previdenciario\">Imprescritibilidade para a concess\u00e3o de benef\u00edcio previdenci\u00e1rio<\/h2>\n\n\n\n<p>A nova reda\u00e7\u00e3o do art. 103 da Lei n. 8.213\/1991, fixada pelo <u><a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2019-2022\/2019\/lei\/l13846.htm\">art. 24 da Lei n. 13.846\/2019<\/a><\/u>, foi impugnada via controle concentrado, na <u><a href=\"https:\/\/redir.stf.jus.br\/paginadorpub\/paginador.jsp?docTP=TP&amp;docID=754482392\">ADI 6.096\/DF<\/a><\/u>. Nessa oportunidade, o STF reafirmou o entendimento outrora chancelado nos autos do RE n. 626.489\/SE, segundo o qual \u00e9 v\u00e1lida a decad\u00eancia relacionada \u00e0 revis\u00e3o de benef\u00edcios previdenci\u00e1rios anteriormente deferidos, &#8220;porque atingida t\u00e3o somente a pretens\u00e3o de rediscutir a gradua\u00e7\u00e3o pecuni\u00e1ria do benef\u00edcio, isto \u00e9, a forma de c\u00e1lculo ou o valor final da presta\u00e7\u00e3o, j\u00e1 que, concedida a pretens\u00e3o que visa ao recebimento do benef\u00edcio, encontra-se preservado o pr\u00f3prio fundo do direito&#8221;.<\/p>\n\n\n\n<p>Por\u00e9m, nesse momento, o Supremo ampliou o entendimento outrora por ele definido, a fim de estabelecer que &#8220;O n\u00facleo essencial do direito fundamental \u00e0 previd\u00eancia social \u00e9 <strong>imprescrit\u00edvel<\/strong>, irrenunci\u00e1vel e indispon\u00edvel, motivo pelo qual n\u00e3o deve ser afetada pelos efeitos do tempo e da in\u00e9rcia de seu titular a pretens\u00e3o relativa ao direito ao recebimento de benef\u00edcio previdenci\u00e1rio&#8221;.<\/p>\n\n\n\n<p>Nesse contexto, o STF reconheceu a inconstitucionalidade da aplica\u00e7\u00e3o de decad\u00eancia ou de prescri\u00e7\u00e3o &#8220;para o caso de indeferimento, cancelamento ou cessa\u00e7\u00e3o&#8221; de benef\u00edcio previdenci\u00e1rio, visto que n\u00e3o se preserva o fundo de direito, na hip\u00f3tese em que negado o benef\u00edcio, se for inviabilizada pelo decurso do tempo a rediscuss\u00e3o da negativa, comprometendo assim o exerc\u00edcio do direito material \u00e0 sua obten\u00e7\u00e3o.<\/p>\n\n\n\n<p>O STF chegou a essa conclus\u00e3o com base na li\u00e7\u00e3o do professor Agnelo Amorim Filho, citada acima, segundo a qual &#8220;as a\u00e7\u00f5es declarat\u00f3rias n\u00e3o se submetem aos institutos da prescri\u00e7\u00e3o e da decad\u00eancia, haja vista que n\u00e3o pretende o autor obter bem da vida assegurado pela lei&#8221;.<\/p>\n\n\n\n<p>Tendo por base esse \u00faltimo entendimento do Supremo, o STJ, no ano de 2023, iniciou uma altera\u00e7\u00e3o em sua jurisprud\u00eancia, a fim de superar a conclus\u00e3o resultante do julgamento dos Edcl nos EREsp n. 1.269.726\/MG. <\/p>\n\n\n\n<p>O Tribunal da Cidadania vem decidindo, em 2023, que &#8220;O Supremo Tribunal Federal, no julgamento da ADI 6.096\/DF, da relatoria do Ministro Edson Fachin, ao declarar a inconstitucionalidade do art. 24 da Lei 13.846\/2019, na parte em que foi dada nova reda\u00e7\u00e3o ao art. 103 da Lei 8.213\/1991, destacou que, mesmo nos casos de indeferimento, cancelamento ou cessa\u00e7\u00e3o de benef\u00edcio, n\u00e3o h\u00e1 falar em prescri\u00e7\u00e3o do fundo de direito, porque nessas hip\u00f3teses nega-se o benef\u00edcio em si considerado&#8221; (<a href=\"https:\/\/scon.stj.jus.br\/SCON\/GetInteiroTeorDoAcordao?num_registro=201600638139&amp;dt_publicacao=15\/05\/2023\">AgInt no REsp n. 1.590.354\/MG, relator Ministro Paulo S\u00e9rgio Domingues, Primeira Turma, julgado em 9\/5\/2023, DJe de 15\/5\/2023<\/a>).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stj-conclusoes\">Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ: conclus\u00f5es<\/h2>\n\n\n\n<p>Diante do atual panorama legal e jurisprudencial acima tra\u00e7ado, podemos chegar \u00e0s seguintes conclus\u00f5es acerca da incid\u00eancia da prescri\u00e7\u00e3o e da decad\u00eancia relacionadas a benef\u00edcios previdenci\u00e1rios:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>n\u00e3o prescreve o fundo de direito e n\u00e3o h\u00e1 decad\u00eancia relacionada ao direito \u00e0 concess\u00e3o de benef\u00edcio previdenci\u00e1rio. Assim, eventual negativa administrativa pode ser impugnada judicialmente sem limita\u00e7\u00e3o de prazo;<\/li>\n\n\n\n<li>uma vez concedido administrativamente o benef\u00edcio previdenci\u00e1rio, o benefici\u00e1rio tem o prazo decadencial de 10 (dez) anos para requerer a revis\u00e3o do valor desse benef\u00edcio, mesmo que a Administra\u00e7\u00e3o P\u00fablica n\u00e3o tenha examinado previamente o fundamento da revis\u00e3o postulada;<\/li>\n\n\n\n<li>incide a prescri\u00e7\u00e3o quinquenal sobre as parcelas mensais requeridas judicialmente pelo benefici\u00e1rio, sejam aquelas oriundas da revis\u00e3o judicial do valor de benef\u00edcio anteriormente concedido pela Administra\u00e7\u00e3o P\u00fablica, sejam as decorrentes da reforma judicial do indeferimento administrativo de benef\u00edcio previdenci\u00e1rio (S\u00famulas n. 85 do STJ e 443 do STF, al\u00e9m da ADI n. 6096\/DF).<\/li>\n<\/ul>\n\n\n\n<p><a href=\"#sdfootnote1anc\" id=\"sdfootnote1sym\">1<\/a>Agnelo Amorim Filho, Crit\u00e9rio cient\u00edfico para distinguir a prescri\u00e7\u00e3o da decad\u00eancia e para identificar as a\u00e7\u00f5es imprescrit\u00edveis. Revista de Direito Processual Civil. S\u00e3o Paulo, v. 3\u00ba, p. 95-132, jan.\/jun. 1961.<\/p>\n\n\n\n<p><a href=\"#sdfootnote2anc\" id=\"sdfootnote2sym\">2<\/a>CASTRO, Carlos Alberto Pereira; LAZZARI, Jo\u00e3o Batista. Manual de Direito Previdenci\u00e1rio. Rio de Janeiro: Forense, 2023, p. 22.371 da vers\u00e3o digital.<\/p>\n\n\n\n<p><a href=\"#sdfootnote3anc\" id=\"sdfootnote3sym\">3<\/a>Idem. p. 22.363 da vers\u00e3o digital.<\/p>\n\n\n\n<p><a id=\"sdfootnote4sym\" href=\"#sdfootnote4anc\">4<\/a>Idem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios<\/p>\n","protected":false},"author":2637,"featured_media":987819,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,2185,220193,220195,220196,220197,1984,220737,214710],"tags":[40,21],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1265703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-carreiras-juridicas","category-defensoria-publica","category-magistratura","category-procuradorias","category-promotor-de-justica","category-tribunais","category-tribunais-tribunais","category-tribunais-de-contas","tag-concurso","tag-direito-previdenciario","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios<\/title>\n<meta name=\"description\" content=\"Prescri\u00e7\u00e3o e decad\u00eancia para concess\u00e3o ou revis\u00e3o de benef\u00edcios previdenci\u00e1rios, segundo a jurisprud\u00eancia do STF e do STJ.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ\" \/>\n<meta property=\"og:description\" content=\"Prescri\u00e7\u00e3o e decad\u00eancia para concess\u00e3o ou revis\u00e3o de benef\u00edcios previdenci\u00e1rios, segundo a jurisprud\u00eancia do STF e do STJ.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-11T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Mendes Lima Aguiar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Mendes Lima Aguiar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/\"},\"author\":{\"name\":\"Jos\u00e9 Mendes Lima Aguiar\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad\"},\"headline\":\"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ\",\"datePublished\":\"2023-09-11T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/\"},\"wordCount\":2139,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg\",\"keywords\":[\"Concurso\",\"Direito Previdenci\u00e1rio\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Jur\u00eddico\",\"Jur\u00eddico - Defensoria P\u00fablica\",\"Jur\u00eddico - Magistratura\",\"Jur\u00eddico - Procuradorias\",\"Jur\u00eddico - Promotor de Justi\u00e7a\",\"Tribunais\",\"Tribunais\",\"Tribunais de Contas (TCU, TCE, TCM)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/\",\"name\":\"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg\",\"datePublished\":\"2023-09-11T11:00:00+00:00\",\"description\":\"Prescri\u00e7\u00e3o e decad\u00eancia para concess\u00e3o ou revis\u00e3o de benef\u00edcios previdenci\u00e1rios, segundo a jurisprud\u00eancia do STF e do STJ.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"INSS e a aplica\u00e7\u00e3o da Pir\u00e2mide da Aprendizagem\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad\",\"name\":\"Jos\u00e9 Mendes Lima Aguiar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g\",\"caption\":\"Jos\u00e9 Mendes Lima Aguiar\"},\"description\":\"Juiz de Direito do TJBA. Ex-assessor de ministro do STJ. Aprovado nos seguintes concursos: - Promotor do MPCE. - Juiz de Direito do TJMA. - Procurador do Estado de MG. - Procurador Jur\u00eddico da CONAB. - Professor de Direito da UnDF. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do STJ. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TST. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TJDFT. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TST. - T\u00e9cnico Administrativo da Secretaria de Sa\u00fade do DF.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/j-mendes405hotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios","description":"Prescri\u00e7\u00e3o e decad\u00eancia para concess\u00e3o ou revis\u00e3o de benef\u00edcios previdenci\u00e1rios, segundo a jurisprud\u00eancia do STF e do STJ.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/","og_locale":"pt_BR","og_type":"article","og_title":"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ","og_description":"Prescri\u00e7\u00e3o e decad\u00eancia para concess\u00e3o ou revis\u00e3o de benef\u00edcios previdenci\u00e1rios, segundo a jurisprud\u00eancia do STF e do STJ.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-09-11T11:00:00+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg","type":"image\/jpeg"}],"author":"Jos\u00e9 Mendes Lima Aguiar","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jos\u00e9 Mendes Lima Aguiar","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/"},"author":{"name":"Jos\u00e9 Mendes Lima Aguiar","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad"},"headline":"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ","datePublished":"2023-09-11T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/"},"wordCount":2139,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg","keywords":["Concurso","Direito Previdenci\u00e1rio"],"articleSection":["Concursos P\u00fablicos","Jur\u00eddico","Jur\u00eddico - Defensoria P\u00fablica","Jur\u00eddico - Magistratura","Jur\u00eddico - Procuradorias","Jur\u00eddico - Promotor de Justi\u00e7a","Tribunais","Tribunais","Tribunais de Contas (TCU, TCE, TCM)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/","name":"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg","datePublished":"2023-09-11T11:00:00+00:00","description":"Prescri\u00e7\u00e3o e decad\u00eancia para concess\u00e3o ou revis\u00e3o de benef\u00edcios previdenci\u00e1rios, segundo a jurisprud\u00eancia do STF e do STJ.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/03\/15104442\/previdenciasocial-fachada-inss-05jan2022-3-scaled-1.jpg","width":2560,"height":1706,"caption":"INSS e a aplica\u00e7\u00e3o da Pir\u00e2mide da Aprendizagem"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/prescricao-e-decadencia-de-beneficios-previdenciarios-segundo-a-jurisprudencia-do-stf-e-do-stjprescricao-decadencia-beneficios-previdenciarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Prescri\u00e7\u00e3o e decad\u00eancia de benef\u00edcios previdenci\u00e1rios segundo a jurisprud\u00eancia do STF e do STJ"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/24513e41f02abcebdbbdccdb5f8699ad","name":"Jos\u00e9 Mendes Lima Aguiar","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9de6360b81109e7efcabd12f27cceb9f2aaa24687eff693fcfce9d1ac42b44a4?s=96&d=mm&r=g","caption":"Jos\u00e9 Mendes Lima Aguiar"},"description":"Juiz de Direito do TJBA. Ex-assessor de ministro do STJ. Aprovado nos seguintes concursos: - Promotor do MPCE. - Juiz de Direito do TJMA. - Procurador do Estado de MG. - Procurador Jur\u00eddico da CONAB. - Professor de Direito da UnDF. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do STJ. - Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TST. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TJDFT. - T\u00e9cnico Judici\u00e1rio - \u00c1rea Administrativa do TST. - T\u00e9cnico Administrativo da Secretaria de Sa\u00fade do DF.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/j-mendes405hotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1265703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2637"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1265703"}],"version-history":[{"count":12,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1265703\/revisions"}],"predecessor-version":[{"id":1270481,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1265703\/revisions\/1270481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/987819"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1265703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1265703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1265703"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1265703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}