{"id":1265236,"date":"2023-09-06T08:00:00","date_gmt":"2023-09-06T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1265236"},"modified":"2023-08-30T10:19:00","modified_gmt":"2023-08-30T13:19:00","slug":"embargos-terceiro-trt-sc","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/","title":{"rendered":"Embargos de Terceiro para o TRT-SC"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg\" alt=\"Embargos de Terceiro para o TRT-SC\n\" class=\"wp-image-1103442\" style=\"width:646px;height:363px\" width=\"646\" height=\"363\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc-300x169.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc-610x343.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc-150x84.jpg 150w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><figcaption class=\"wp-element-caption\">Embargos de Terceiro para o TRT-SC <\/figcaption><\/figure>\n\n\n\n<p>Fala, pessoal, tudo certo? Hoje falaremos sobre os Embargos de Terceiro para o<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-trt-sc\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Concurso do TRT-SC (Tribunal Regional do Trabalho de Santa Catarina &#8211; TRT da 12\u00aa Regi\u00e3o<\/a>).<\/p>\n\n\n\n<p>O assunto est\u00e1 previsto no <a href=\"https:\/\/www.concursosfcc.com.br\/concursos\/trt12123\/trt12123_edital_de_abertura_completo_retificado.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">edital do Concurso do TRT-SC<\/a> para os cargos de Analista Judici\u00e1rio &#8211; \u00c1rea Judici\u00e1ria Sem Especialidade, Especialidade Oficial de Justi\u00e7a Avaliador Federal e para T\u00e9cnico Judici\u00e1rio &#8211; \u00c1rea Administrativa.<\/p>\n\n\n\n<p>Portanto, primeiro falaremos sobre o conceito, cabimento e legitimidade para oposi\u00e7\u00e3o dos embargos de terceiro. Depois, falaremos sobre sua previs\u00e3o legal e seu procedimento. Por fim, abordaremos o momento processual, os prazos e a possibilidade de concess\u00e3o de liminar.<\/p>\n\n\n\n<p>Vamos l\u00e1, rumo ao TRT 12!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-embargos-de-terceiro\">Embargos de Terceiro<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-conceito-e-cabimento-nbsp\">Conceito e cabimento&nbsp;<\/h3>\n\n\n\n<p>Primeiramente, em termos simples, podemos definir que <strong>os embargos de terceiro como sendo o meio pelo qual uma pessoa alheia \u00e0 rela\u00e7\u00e3o processual busca defender interesse jur\u00eddico pr\u00f3prio que est\u00e1 amea\u00e7ado de sofrer ou que sofreu constri\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Nesse sentido, Humberto Theodoro J\u00fanior conceitua os embargos de terceiro como sendo \u201c<em>uma a\u00e7\u00e3o de natureza constitutiva, que busca desconstituir o ato judicial abusivo, restituindo as partes ao estado anterior \u00e0 apreens\u00e3o impugnada\u201d<\/em>.<\/p>\n\n\n\n<p>Portanto, podemos concluir que os embargos de terceiro consistem em <strong>a\u00e7\u00e3o aut\u00f4noma, de natureza constitutiva<\/strong>, uma vez que, caso julgado procedente, haver\u00e1 o reconhecimento do dom\u00ednio, da manuten\u00e7\u00e3o da posse ou da reintegra\u00e7\u00e3o definitiva do bem ou do direito ao embargante, vide artigo 681 do CPC:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-small-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Art. 681. Acolhido o pedido inicial, o ato de constri\u00e7\u00e3o judicial indevida ser\u00e1 cancelado, com o reconhecimento do dom\u00ednio, da manuten\u00e7\u00e3o da posse ou da reintegra\u00e7\u00e3o definitiva do bem ou do direito ao embargante.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Com efeito, \u00e9 importante destacar em qual contexto se insere a a\u00e7\u00e3o de embargos de terceiro.<\/p>\n\n\n\n<p>Isso porque \u00e9 uma a\u00e7\u00e3o que <strong>pressup\u00f5e uma a\u00e7\u00e3o anterior (\u201ca\u00e7\u00e3o principal\u201d)<\/strong>, no bojo da qual algum ato processual causou constri\u00e7\u00e3o (ou amea\u00e7ou causar) sobre o bem\/direito desse terceiro ora embargante.&nbsp;<\/p>\n\n\n\n<p>Desse modo, o terceiro, por se sentir lesado juridicamente, oferece os embargos de terceiro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-legitimidade-dos-embargos-de-terceiro\">Legitimidade dos embargos de terceiro<\/h3>\n\n\n\n<p>Ser parte leg\u00edtima significa dizer que aquela pessoa preenche as condi\u00e7\u00f5es essenciais para poder ajuizar determinada a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Portanto, <strong>uma condi\u00e7\u00e3o essencial para ser considerado \u201cterceiro\u201d \u00e9 N\u00c3O ser parte no processo principal<\/strong>.<\/p>\n\n\n\n<p>O CPC ainda autoriza que tanto o <strong>terceiro propriet\u00e1rio<\/strong>, <span style=\"text-decoration: underline;\">inclusive fiduci\u00e1rio<\/span>, quanto o <strong>terceiro possuidor<\/strong> ajuizem os embargos.<\/p>\n\n\n\n<p>Esses conceitos de propriedade e de posse constam nos artigos 1.228 e 1.196 do C\u00f3digo Civil, respectivamente.<\/p>\n\n\n\n<p>Por fim, o CPC ainda permite a extens\u00e3o do conceito de terceiro para os seguintes sujeitos processuais:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-small-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00a7 2\u00ba Considera-se terceiro, para ajuizamento dos embargos:<\/em><\/p>\n\n\n\n<p><em>I &#8211; o c\u00f4njuge ou companheiro, quando defende a posse de bens pr\u00f3prios ou de sua mea\u00e7\u00e3o, ressalvado o disposto no art. 843 ;<\/em><\/p>\n\n\n\n<p><em>II &#8211; o adquirente de bens cuja constri\u00e7\u00e3o decorreu de decis\u00e3o que declara a inefic\u00e1cia da aliena\u00e7\u00e3o realizada em fraude \u00e0 execu\u00e7\u00e3o;<\/em><\/p>\n\n\n\n<p><em>III &#8211; quem sofre constri\u00e7\u00e3o judicial de seus bens por for\u00e7a de desconsidera\u00e7\u00e3o da personalidade jur\u00eddica, de cujo incidente n\u00e3o fez parte;<\/em><\/p>\n\n\n\n<p><em>IV &#8211; o credor com garantia real para obstar expropria\u00e7\u00e3o judicial do objeto de direito real de garantia, caso n\u00e3o tenha sido intimado, nos termos legais dos atos expropriat\u00f3rios respectivos.<\/em><\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-previsao-legal-e-procedimento-dos-embargos-de-terceiro\">Previs\u00e3o legal e procedimento dos embargos de terceiro<\/h3>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-oposicao-dos-embargos-de-terceiro\">Oposi\u00e7\u00e3o dos embargos de terceiro<\/h4>\n\n\n\n<p>Os embargos de terceiro, por serem ajuizados em a\u00e7\u00e3o aut\u00f4noma, s\u00e3o <strong>distribu\u00eddos por depend\u00eancia<\/strong> ao ju\u00edzo que ordenou a constri\u00e7\u00e3o e autuados em apartado.<\/p>\n\n\n\n<p>Por\u00e9m, se o ato de constri\u00e7\u00e3o for realizado por <strong>carta precat\u00f3ria,<\/strong> <strong>os embargos ser\u00e3o oferecidos no ju\u00edzo deprecado<\/strong>, <span style=\"text-decoration: underline;\">salvo se (i) indicado pelo ju\u00edzo deprecante o bem constrito ou (ii) se j\u00e1 devolvida a carta<\/span>.<\/p>\n\n\n\n<p>Obs.: o ju\u00edzo deprecante \u00e9 aquele que enviou a carta precat\u00f3ria e pediu para que o ato fosse realizado; o ju\u00edzo deprecado \u00e9 aquele que recebe a precat\u00f3ria.<\/p>\n\n\n\n<p>Al\u00e9m disso, o embargante, ao oferecer os embargos, deve <strong>provar sumariamente<\/strong> sua posse ou seu dom\u00ednio e qualidade de terceiro.<\/p>\n\n\n\n<p>Isso significa dizer que deve <strong>provar de forma objetiva e clara <\/strong>desde o in\u00edcio do expediente processual. Para tanto, deve oferecer <strong>documentos e arrolar testemunhas<\/strong>, sendo facultada, ainda, a designa\u00e7\u00e3o pelo juiz de <strong>audi\u00eancia preliminar para que o embargante prove a posse<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Caso o terceiro seja possuidor direto, ou seja, esteja diretamente em contato com o bem, poder\u00e1 alegar, al\u00e9m da posse direta, que aquele bem \u00e9 de propriedade de outrem.<\/p>\n\n\n\n<p>Geralmente, o embargado (a quem a constri\u00e7\u00e3o aproveita) estar\u00e1 cadastrado nos autos da a\u00e7\u00e3o principal (de onde se originou a constri\u00e7\u00e3o). Por\u00e9m, se n\u00e3o estiver, sua cita\u00e7\u00e3o ser\u00e1 pessoal.<\/p>\n\n\n\n<p>Por fim, destaca-se que <strong>o embargado (legitimado passivo) pode ser (i) tanto aquele a quem a constri\u00e7\u00e3o aproveita<\/strong> quanto (ii) o <strong>advers\u00e1rio do embargado no processo principal quando tiver indicado o bem<\/strong> para a constri\u00e7\u00e3o judicial.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-momento-processual-prazos-e-liminar\">Momento processual, prazos e liminar<\/h4>\n\n\n\n<p>Primeiramente, aponta-se que os embargos de terceiro podem ser opostos, em regra, a qualquer tempo, desde que se observe:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">A qualquer tempo no no processo de conhecimento<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Enquanto n\u00e3o transitada em julgado a senten\u00e7a<\/strong>&nbsp;<br \/><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">A qualquer tempo no cumprimento de senten\u00e7a ou no processo de execu\u00e7\u00e3o&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Desde que at\u00e9 5 (cinco) dias DEPOIS <\/strong>da adjudica\u00e7\u00e3o, da aliena\u00e7\u00e3o por iniciativa particular ou da arremata\u00e7\u00e3o, <strong>mas SEMPRE ANTES da assinatura da respectiva carta.<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" colspan=\"2\" rowspan=\"2\">Caso identifique a exist\u00eancia de terceiro titular de interesse em embargar o ato, o juiz mandar\u00e1 intim\u00e1-lo pessoalmente, a fim de oportunizar o direito de a\u00e7\u00e3o no momento processual adequado.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>A parte embargada poder\u00e1 contestar os embargos no <strong>prazo de 15 (quinze) dias<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Ap\u00f3s isso, o processo seguir\u00e1 as regras do procedimento comum.<\/p>\n\n\n\n<p>No entanto, \u00e9 importante destacar que o embargado, caso tenha que se defender contra embargos opostos por terceiro que possui garantia real (<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/2002\/l10406compilada.htm#:~:text=T%C3%8DTULO%20X-,Do%20Penhor%2C%20da%20Hipoteca%20e%20da%20Anticrese,-CAP%C3%8DTULO%20I%0ADisposi%C3%A7%C3%B5es\" target=\"_blank\" rel=\"noreferrer noopener\">Penhor, Hipoteca e Anticrese<\/a>), somente poder\u00e1 alegar quest\u00f5es bem espec\u00edficas, quais sejam:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-small-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Art. 680. (&#8230;)<\/em><\/p>\n\n\n\n<p><em>I &#8211; o devedor comum \u00e9 insolvente;<\/em><\/p>\n\n\n\n<p><em>II &#8211; o t\u00edtulo \u00e9 nulo ou n\u00e3o obriga a terceiro;<\/em><\/p>\n\n\n\n<p><em>III &#8211; outra \u00e9 a coisa dada em garantia.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Por fim, evidencia-se que <strong>o CPC autoriza que o juiz conceda medida liminar<\/strong> desde o in\u00edcio do processo referente aos embargos de terceiro.<\/p>\n\n\n\n<p>Por\u00e9m, <strong>\u00e9 necess\u00e1rio que reconhe\u00e7a que est\u00e1 suficientemente provado o dom\u00ednio ou a posse<\/strong>.<\/p>\n\n\n\n<p>Nesse caso, determinar\u00e1 a <strong>suspens\u00e3o das medidas constritivas<\/strong> sobre os bens litigiosos objeto dos embargos.<\/p>\n\n\n\n<p>Tamb\u00e9m poder\u00e1 determinar <strong>a manuten\u00e7\u00e3o ou a reintegra\u00e7\u00e3o provis\u00f3ria da posse<\/strong>, desde que haja requerimento do embargante. No entanto, o juiz <strong>pode condicionar a concess\u00e3o dessas medidas \u00e0 presta\u00e7\u00e3o de cau\u00e7\u00e3o pelo requerente<\/strong> (exceto se a parte embargante for economicamente hipossuficiente).<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"h-conclusao\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Portanto, pessoal, esse foi nosso resumo sobre os Embargos de Terceiro para o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-trt-sc\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso do TRT-SC<\/a>!<\/p>\n\n\n\n<p>Por fim, n\u00e3o deixe de conferir a literalidade dos dispositivos que se relacionam com este tema direto no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm#:~:text=DOS%20EMBARGOS%20DE%20TERCEIRO\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3digo de Processo Civil<\/a>.<\/p>\n\n\n\n<p>No mais, desejamos uma excelente prova a todos!!<\/p>\n\n\n\n<p class=\"has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Confira os concursos p\u00fablicos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/cj.estrategia.com\/portal\/concursos-abertos-carreiras-juridicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos Carreiras Jur\u00eddicas<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"assinatura-de-concursos\">Assinatura de Concursos<\/h3>\n\n\n\n<p>Assinatura de 1 ano ou 2 anos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noreferrer noopener\">ASSINE AGORA<\/a><\/p>\n\n\n\n<p>Agora, confira as vagas e oportunidades dos&nbsp;<strong>concursos 2023<\/strong>&nbsp;navegando atrav\u00e9s do \u00edndice abaixo:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concursos-e-vagas-previstas-para-2023\">Concursos e vagas previstas para 2023:<\/h2>\n\n\n\n<p>Ademais, al\u00e9m deste artigo sobre os Embargos de Terceiro para o concurso do TRT-SC, confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#policial\">Concursos Policiais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#fiscal\">Concursos Fiscais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#controle\">Concursos Controle<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#tribunais\">Concursos Tribunais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#ministerios-publicos\">Concursos em Minist\u00e9rios P\u00fablicos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#defensorias-publicas\">Concursos em Defensorias<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#legislativa\">Concursos Legislativos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#saude\">Concursos da \u00e1rea da Sa\u00fade<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#bancaria\">Concursos da \u00e1rea banc\u00e1ria<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#educacao\">Concursos da \u00e1rea da Educa\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#prefeituras\">Concursos para Prefeituras<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#outros\">Concursos outras oportunidades<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#concursos-estado\">Concursos 2023 por Estado<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><strong>Veja tamb\u00e9m: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\" style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><em><strong>Quer saber tudo sobre os concursos previstos? Confira nossos artigos completos:<\/strong><\/em><\/p>\n\n\n\n<p>Ademais, al\u00e9m deste artigo sobre os Embargos de Terceiro para o concurso do TRT-SC, confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-trt-sc\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso TRT-SC<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Fala, pessoal, tudo certo? Hoje falaremos sobre os Embargos de Terceiro para o Concurso do TRT-SC (Tribunal Regional do Trabalho de Santa Catarina &#8211; TRT da 12\u00aa Regi\u00e3o). O assunto est\u00e1 previsto no edital do Concurso do TRT-SC para os cargos de Analista Judici\u00e1rio &#8211; \u00c1rea Judici\u00e1ria Sem Especialidade, Especialidade Oficial de Justi\u00e7a Avaliador Federal [&hellip;]<\/p>\n","protected":false},"author":2567,"featured_media":1103442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1984,220737],"tags":[],"tax_estado":[219963,219987],"class_list":["post-1265236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-tribunais","category-tribunais-tribunais","tax_estado-concursos-federais","tax_estado-sc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Embargos de Terceiro para o TRT-SC<\/title>\n<meta name=\"description\" content=\"Confira as principais informa\u00e7\u00f5es sobre os Embargos de Terceiro para o Concurso do TRT da 12\u00aa Regi\u00e3o (TRT-SC), banca FCC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embargos de Terceiro para o TRT-SC\" \/>\n<meta property=\"og:description\" content=\"Confira as principais informa\u00e7\u00f5es sobre os Embargos de Terceiro para o Concurso do TRT da 12\u00aa Regi\u00e3o (TRT-SC), banca FCC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-06T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/\"},\"author\":{\"name\":\"Frederico Tadeu Borlot Peixoto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\"},\"headline\":\"Embargos de Terceiro para o TRT-SC\",\"datePublished\":\"2023-09-06T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/\"},\"wordCount\":1372,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Tribunais\",\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/\",\"name\":\"Embargos de Terceiro para o TRT-SC\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg\",\"datePublished\":\"2023-09-06T11:00:00+00:00\",\"description\":\"Confira as principais informa\u00e7\u00f5es sobre os Embargos de Terceiro para o Concurso do TRT da 12\u00aa Regi\u00e3o (TRT-SC), banca FCC.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg\",\"width\":768,\"height\":432,\"caption\":\"Dos per\u00edodos de descanso para TRT-SC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embargos de Terceiro para o TRT-SC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\",\"name\":\"Frederico Tadeu Borlot Peixoto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"caption\":\"Frederico Tadeu Borlot Peixoto\"},\"description\":\"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/proffrederico\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Embargos de Terceiro para o TRT-SC","description":"Confira as principais informa\u00e7\u00f5es sobre os Embargos de Terceiro para o Concurso do TRT da 12\u00aa Regi\u00e3o (TRT-SC), banca FCC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/","og_locale":"pt_BR","og_type":"article","og_title":"Embargos de Terceiro para o TRT-SC","og_description":"Confira as principais informa\u00e7\u00f5es sobre os Embargos de Terceiro para o Concurso do TRT da 12\u00aa Regi\u00e3o (TRT-SC), banca FCC.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-09-06T11:00:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg","type":"image\/jpeg"}],"author":"Frederico Tadeu Borlot Peixoto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Frederico Tadeu Borlot Peixoto","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/"},"author":{"name":"Frederico Tadeu Borlot Peixoto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb"},"headline":"Embargos de Terceiro para o TRT-SC","datePublished":"2023-09-06T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/"},"wordCount":1372,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg","articleSection":["Concursos P\u00fablicos","Tribunais","Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/","name":"Embargos de Terceiro para o TRT-SC","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg","datePublished":"2023-09-06T11:00:00+00:00","description":"Confira as principais informa\u00e7\u00f5es sobre os Embargos de Terceiro para o Concurso do TRT da 12\u00aa Regi\u00e3o (TRT-SC), banca FCC.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/09\/30170124\/trt_sc.jpg","width":768,"height":432,"caption":"Dos per\u00edodos de descanso para TRT-SC"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/embargos-terceiro-trt-sc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Embargos de Terceiro para o TRT-SC"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb","name":"Frederico Tadeu Borlot Peixoto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","caption":"Frederico Tadeu Borlot Peixoto"},"description":"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/","sameAs":["https:\/\/www.instagram.com\/proffrederico\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1265236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2567"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1265236"}],"version-history":[{"count":5,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1265236\/revisions"}],"predecessor-version":[{"id":1265247,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1265236\/revisions\/1265247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1103442"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1265236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1265236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1265236"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1265236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}