{"id":1236169,"date":"2023-07-20T14:00:00","date_gmt":"2023-07-20T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1236169"},"modified":"2023-07-04T15:12:19","modified_gmt":"2023-07-04T18:12:19","slug":"concurso-tse-unificado-irdr","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/","title":{"rendered":"Concurso TSE Unificado: IRDR no Processo Civil"},"content":{"rendered":"\n<p>Fala, pessoal, tudo certo? Vamos estudar hoje o assunto Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.<\/p>\n\n\n\n<p>Como ainda n\u00e3o h\u00e1 banca definida, vamos focar na legisla\u00e7\u00e3o, bem assim em eventual jurisprud\u00eancia relacionada.<\/p>\n\n\n\n<p>Vamos nessa, rumo \u00e0 Justi\u00e7a Eleitoral!<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw\" alt=\"Concurso TSE Unificado: IRDR no Processo Civil\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Considera\u00e7\u00f5es iniciais<\/h2>\n\n\n\n<p>Primeiramente, \u00e9 importante ter em mente que o C\u00f3digo de Processo Civil atual, publicado em 2015, teve como um de seus objetivos instituir par\u00e2metros de estabiliza\u00e7\u00e3o e uniformiza\u00e7\u00e3o da jurisprud\u00eancia.<\/p>\n\n\n\n<p>Tanto \u00e9 assim que os artigos 926 e 927 determinam que os tribunais p\u00e1trios uniformizem sua jurisprud\u00eancia e a mantenham est\u00e1vel, \u00edntegra e coerente, apontando, ademais, determinados tipos de precedentes que devem ser, necessariamente, observados pelos ju\u00edzos e tribunais do pa\u00eds.<\/p>\n\n\n\n<p>Para tanto, dentre outras medidas, instituiu-se a figura do incidente de resolu\u00e7\u00e3o de demandas repetitivas (IRDR) e manteve-se a do julgamento de recursos especial e extraordin\u00e1rio repetitivos, j\u00e1 existente no \u00e2mbito do CPC\/1973.<\/p>\n\n\n\n<p>Nesse sentido, o artigo 928 do CPC\/15:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Art. 928. Para os fins deste C\u00f3digo, considera-se julgamento de casos repetitivos a decis\u00e3o proferida em:<\/em><\/p>\n\n\n\n<p><em>I &#8211; incidente de resolu\u00e7\u00e3o de demandas repetitivas;<\/em><\/p>\n\n\n\n<p><em>II &#8211; recursos especial e extraordin\u00e1rio repetitivos.<\/em><\/p>\n\n\n\n<p><em>Par\u00e1grafo \u00fanico. O julgamento de casos repetitivos tem por objeto quest\u00e3o de direito material ou processual.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Assim, com essa ideia de estabiliza\u00e7\u00e3o da jurisprud\u00eancia, vamos ao que interessa!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR)<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Cabimento, legitima\u00e7\u00e3o e pedido de instaura\u00e7\u00e3o do IRDR<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Cabimento do IRDR<\/h4>\n\n\n\n<p>A instaura\u00e7\u00e3o do IRDR exige duas condi\u00e7\u00f5es simult\u00e2neas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>a presen\u00e7a de<strong> efetiva repeti\u00e7\u00e3o de processos<\/strong> que contenham controv\u00e9rsia sobre a mesma <strong>quest\u00e3o <span style=\"text-decoration: underline;\">unicamente<\/span> de direito<\/strong>;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\">\n<li><strong><span style=\"text-decoration: underline;\">risco<\/span> <\/strong>de ofensa \u00e0 <strong>isonomia <\/strong>e \u00e0 <strong>seguran\u00e7a jur\u00eddica<\/strong>.<\/li>\n<\/ol>\n\n\n\n<p>Portanto, notem que <strong>n\u00e3o serve a repeti\u00e7\u00e3o de controv\u00e9rsia sobre <\/strong><strong>fatos<\/strong>, mas sim aquela sobre mat\u00e9ria de direito, jur\u00eddica.<\/p>\n\n\n\n<p>Ademais, <strong>n\u00e3o se exige a <\/strong><strong>efetiva<\/strong><strong> viola\u00e7\u00e3o<\/strong> \u00e0 isonomia e \u00e0 seguran\u00e7a jur\u00eddica, bastando que haja o risco a tais preceitos.<\/p>\n\n\n\n<p>Al\u00e9m disso, <strong>n\u00e3o caber\u00e1 IRDR quando um dos tribunais superiores<\/strong>, no \u00e2mbito de sua respectiva compet\u00eancia,<strong> j\u00e1 tiver afetado recurso para defini\u00e7\u00e3o de tese sobre quest\u00e3o<\/strong> de direito material ou processual repetitiva.&nbsp;<\/p>\n\n\n\n<p>O \u00faltimo par\u00e1grafo, em verdade, apenas visa a impedir a instaura\u00e7\u00e3o de IRDR (inciso I do art. 928 do CPC) quando j\u00e1 instaurado procedimento relativo ao inciso II do mesmo dispositivo legal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Legitimados&nbsp;<\/h4>\n\n\n\n<p>Desse modo, uma vez presentes tais requisitos, qualquer um dos <strong>legitimados <\/strong>poder\u00e1 requerer a instaura\u00e7\u00e3o do incidente, <strong>dirigindo seu pedido ao presidente do respectivo tribunal<\/strong>.<\/p>\n\n\n\n<p>S\u00e3o <strong>legitimados<\/strong> a pedir a instaura\u00e7\u00e3o do IRDR:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>o pr\u00f3prio juiz ou relator do processo, de of\u00edcio;<\/li>\n\n\n\n<li>as partes (polo ativo e passivo);<\/li>\n\n\n\n<li>o Minist\u00e9rio P\u00fablico;<\/li>\n\n\n\n<li>a Defensoria P\u00fablica.<\/li>\n<\/ul>\n\n\n\n<p>Ademais, <strong>se o Minist\u00e9rio P\u00fablico n\u00e3o for aquele que requereu a instaura\u00e7\u00e3o, dever\u00e1 intervir obrigatoriamente como <em>custos legis<\/em><\/strong> e, no caso de desist\u00eancia ou abandono do incidente pela parte requerente, assumir\u00e1 a titularidade do feito.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Instaura\u00e7\u00e3o do IRDR<\/h4>\n\n\n\n<p>Como dito, o pedido de instaura\u00e7\u00e3o ser\u00e1 direito ao presidente do respectivo tribunal, devendo conter os documentos necess\u00e1rios comprovando que o preenchimento dos requisitos legais para instaura\u00e7\u00e3o do IRDR.<\/p>\n\n\n\n<p>Ademais, dar-se-\u00e1 ampla e espec\u00edfica divulga\u00e7\u00e3o e publicidade \u00e0 instaura\u00e7\u00e3o.<\/p>\n\n\n\n<p>Assim, ap\u00f3s o presidente de tribunal receber a peti\u00e7\u00e3o\/of\u00edcio de IRDR, encaminhar\u00e1 ao \u00f3rg\u00e3o do tribunal respons\u00e1vel pelo julgamento do incidente, conforme dispuser o regimento interno respectivo.&nbsp;<\/p>\n\n\n\n<p>Aten\u00e7\u00e3o: <strong>o mesmo \u00f3rg\u00e3o respons\u00e1vel pelo julgamento do IRDR julgar\u00e1 igualmente<\/strong> o recurso, a remessa necess\u00e1ria ou o processo de compet\u00eancia origin\u00e1ria de onde se originou o incidente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Procedimento e julgamento do IRDR<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Procedimento<\/h4>\n\n\n\n<p>Prosseguindo, uma vez que o presidente do tribunal encaminhe o processo ao \u00f3rg\u00e3o competente para o julgamento, este proceder\u00e1 ao ju\u00edzo de admissibilidade do feito. <em>Como assim?<\/em><\/p>\n\n\n\n<p>Ou seja, o \u00f3rg\u00e3o competente analisar\u00e1 se de fato o IRDR \u00e9 cab\u00edvel e se preenche todos os pressupostos acima elencados.&nbsp;<\/p>\n\n\n\n<p>Essa an\u00e1lise ser\u00e1 feita pelo relator do incidente, que, uma vez que admita o IRDR, adotar\u00e1 as seguintes medidas (artigo 982 do CPC):<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>I &#8211; suspender\u00e1 os processos pendentes, individuais ou coletivos, que tramitam no Estado ou na regi\u00e3o, conforme o caso;<\/em><\/p>\n\n\n\n<p><em>II &#8211; poder\u00e1 requisitar informa\u00e7\u00f5es a \u00f3rg\u00e3os em cujo ju\u00edzo tramita processo no qual se discute o objeto do incidente, que as prestar\u00e3o no prazo de 15 (quinze) dias;<\/em><\/p>\n\n\n\n<p><em>III &#8211; intimar\u00e1 o Minist\u00e9rio P\u00fablico para, querendo, manifestar-se no prazo de 15 (quinze) dias.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>A suspens\u00e3o de que trata o inciso I ser\u00e1 comunicada aos \u00f3rg\u00e3os jurisdicionais competentes e poder\u00e1, mediante requerimento a ser endere\u00e7ado a Tribunal Superior pelo meio cab\u00edvel, se estender a todos os processos individuais ou coletivos em curso no territ\u00f3rio nacional que versem sobre a quest\u00e3o objeto do incidente j\u00e1 instaurado.<\/p>\n\n\n\n<p>Outrossim, \u00e9 importante destacar que <strong>o prazo para o MP se manifestar como fiscal da lei (<\/strong><strong><em>custos legis<\/em><\/strong><strong>) \u00e9 de 15 dias, diferentemente do prazo gen\u00e9rico de 30 dias<\/strong> previsto no artigo 178 do CPC.<\/p>\n\n\n\n<p>Al\u00e9m disso, o relator ouvir\u00e1 as partes e interessados no <strong>prazo <span style=\"text-decoration: underline;\">comum<\/span> de 15 (quinze) dias<\/strong>, as quais poder\u00e3o requerer medidas instrut\u00f3rias. Na sequ\u00eancia, por igual per\u00edodo, ter\u00e1 vista dos autos o MP.<\/p>\n\n\n\n<p>Todavia, caso n\u00e3o caiba o incidente, ser\u00e1 inadmitido. <strong>Essa inadmiss\u00e3o, no entanto, n\u00e3o impede que, uma vez satisfeito o requisito, seja o incidente novamente suscitado.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Julgamento<\/h4>\n\n\n\n<p>No julgamento do Incidente, o relator explicar\u00e1 o tema de direito a ser julgado e, em seguida, os sujeitos processuais poder\u00e3o se manifestar, sucessivamente, na seguinte ordem:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Autor<\/td><td class=\"has-text-align-center\" data-align=\"center\">30 minutos<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">R\u00e9u<\/td><td class=\"has-text-align-center\" data-align=\"center\">30 minutos<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">MP<\/td><td class=\"has-text-align-center\" data-align=\"center\">30 minutos<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Outros interessados<\/td><td class=\"has-text-align-center\" data-align=\"center\">30 minutos divididos entre todos, desde que requeiram com 02 dias de anteced\u00eancia<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>O CPC ainda permite a amplia\u00e7\u00e3o dos prazos acima mencionados, no caso de o n\u00famero de inscritos justificar a medida.<\/p>\n\n\n\n<p>Sendo assim, uma vez finalizado o julgamento, o ac\u00f3rd\u00e3o abranger\u00e1 a an\u00e1lise de todos os fundamentos suscitados concernentes \u00e0 tese jur\u00eddica discutida, sejam favor\u00e1veis ou contr\u00e1rios.<\/p>\n\n\n\n<p>Ademais,<strong> a tese jur\u00eddica ser\u00e1 aplicada a todos os processo<\/strong>s, individuais ou coletivos, <strong>que versem sobre a quest\u00e3o e tramitem na jurisdi\u00e7\u00e3o do respectivo tribunal,<\/strong> bem assim aos casos futuros.<\/p>\n\n\n\n<p>Por fim,<strong> caso a parte que requereu a instaura\u00e7\u00e3o desista ou abandone a causa, tal fato n\u00e3o impedir\u00e1 o julgamento de m\u00e9rito do Incidente e, nesse caso, o MP assumir\u00e1 a titularidade do feito.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recursos e impugna\u00e7\u00f5es envolvendo IRDR<\/h3>\n\n\n\n<p>Por fim, no que diz respeito \u00e0 tese firmada, poder\u00e3o as partes recorrerem.<\/p>\n\n\n\n<p>Assim, <strong>ser\u00e1 cab\u00edvel tanto recurso especial quanto recurso extraordin\u00e1rio, os quais ter\u00e3o efeito suspensivo<\/strong>, presumindo-se a repercuss\u00e3o geral de quest\u00e3o constitucional eventualmente discutida.<\/p>\n\n\n\n<p>Para o <a href=\"https:\/\/scon.stj.jus.br\/SCON\/GetInteiroTeorDoAcordao?num_registro=202103910075&amp;dt_publicacao=20\/06\/2023\" target=\"_blank\" rel=\"noreferrer noopener\">Superior Tribunal de Justi\u00e7a<\/a>, uma vez interposto um dos recursos supracitados, haver\u00e1 suspens\u00e3o dos processos, que s\u00f3 cessar\u00e1 com o julgamento dos referidos recursos, n\u00e3o sendo necess\u00e1rio, entretanto, aguardar o tr\u00e2nsito em julgado, mas apenas o julgamento de m\u00e9rito.<\/p>\n\n\n\n<p>Por outro lado, quando o recurso for julgado, a tese jur\u00eddica adotada pelo STF ou pelo STJ ser\u00e1 aplicada no territ\u00f3rio nacional a todos os processos individuais ou coletivos que versem sobre id\u00eantica quest\u00e3o de direito.<\/p>\n\n\n\n<p>Igualmente, importante registrar que, <strong>caso a tese firmada em IRDR, ou nos respectivos recursos, venha a ser desrespeitada, ser\u00e1 poss\u00edvel o manejo de <span style=\"text-decoration: underline;\">reclama\u00e7\u00e3o<\/span><\/strong>, nos termos do \u00a7 1\u00ba do artigo 985 c\/c inciso IV do artigo 988, ambos do CPC.<\/p>\n\n\n\n<p>Por fim, aponta-se ser poss\u00edvel a revis\u00e3o da tese jur\u00eddica firmada. Essa revis\u00e3o, no entanto, s\u00f3 pode ser feita <strong>de of\u00edcio<\/strong> ou <strong>mediante requerimento<\/strong> <strong>do MP ou da Defensoria P\u00fablica<\/strong>. Isso \u00e9, <strong>as partes n\u00e3o poder\u00e3o requerer a revis\u00e3o da tese.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Portanto, pessoal, esse foi nosso resumo sobre o Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.<\/p>\n\n\n\n<p>Por fim, n\u00e3o deixe de conferir a<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm\" target=\"_blank\" rel=\"noreferrer noopener\"> literalidade dos dispositivos<\/a> que envolvem o tema no C\u00f3digo de Processo Civil (artigos 976 a 987) e resolver muitas quest\u00f5es sobre o assunto.<\/p>\n\n\n\n<p>Bons estudos, pessoal!<\/p>\n\n\n\n<p class=\"has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Confira os concursos p\u00fablicos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/cj.estrategia.com\/portal\/concursos-abertos-carreiras-juridicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos Carreiras Jur\u00eddicas<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"assinatura-de-concursos\">Assinatura de Concursos<\/h3>\n\n\n\n<p>Al\u00e9m deste resumo sobre IRDR no Processo Civil para o Concurso TSE Unificado, confira:<\/p>\n\n\n\n<p>Assinatura de 1 ano ou 2 anos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noreferrer noopener\">ASSINE AGORA<\/a><\/p>\n\n\n\n<p>Al\u00e9m disso, confira as vagas e oportunidades dos&nbsp;<strong>concursos 2023<\/strong>&nbsp;navegando atrav\u00e9s do \u00edndice abaixo:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concursos-e-vagas-previstas-para-2023\">Concursos e vagas previstas para 2023:<\/h2>\n\n\n\n<p>Al\u00e9m deste resumo sobre IRDR no Processo Civil para o Concurso TSE Unificado, confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#policial\">Concursos Policiais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#fiscal\">Concursos Fiscais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#controle\">Concursos Controle<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#tribunais\">Concursos Tribunais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#ministerios-publicos\">Concursos em Minist\u00e9rios P\u00fablicos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#defensorias-publicas\">Concursos em Defensorias<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#legislativa\">Concursos Legislativos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#saude\">Concursos da \u00e1rea da Sa\u00fade<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#bancaria\">Concursos da \u00e1rea banc\u00e1ria<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#educacao\">Concursos da \u00e1rea da Educa\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#prefeituras\">Concursos para Prefeituras<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#outros\">Concursos outras oportunidades<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/#concursos-estado\">Concursos 2023 por Estado<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background\" style=\"font-size:clamp(14.642px, 0.915rem + ((1vw - 3.2px) * 0.721), 22px);\"><strong>Veja tamb\u00e9m: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\" style=\"font-size:clamp(16.293px, 1.018rem + ((1vw - 3.2px) * 0.854), 25px);\"><em><strong>Quer saber tudo sobre os concursos previstos? Confira nossos artigos completo<\/strong>s:<\/em><\/p>\n\n\n\n<p>Al\u00e9m deste resumo sobre IRDR no Processo Civil para o Concurso TSE Unificado, confira:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso TSE Unificado<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Fala, pessoal, tudo certo? Vamos estudar hoje o assunto Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado. Como ainda n\u00e3o h\u00e1 banca definida, vamos focar na legisla\u00e7\u00e3o, bem assim em eventual jurisprud\u00eancia relacionada. Vamos nessa, rumo \u00e0 Justi\u00e7a Eleitoral! Considera\u00e7\u00f5es iniciais Primeiramente, \u00e9 importante ter em mente que [&hellip;]<\/p>\n","protected":false},"author":2567,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1984],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1236169","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos","category-tribunais","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso TSE Unificado: IRDR no Processo Civil<\/title>\n<meta name=\"description\" content=\"Principais aspectos quanto ao Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso TSE Unificado: IRDR no Processo Civil\" \/>\n<meta property=\"og:description\" content=\"Principais aspectos quanto ao Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/18152341\/tse_unificado-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frederico Tadeu Borlot Peixoto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/\"},\"author\":{\"name\":\"Frederico Tadeu Borlot Peixoto\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\"},\"headline\":\"Concurso TSE Unificado: IRDR no Processo Civil\",\"datePublished\":\"2023-07-20T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/\"},\"wordCount\":1568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/\",\"name\":\"Concurso TSE Unificado: IRDR no Processo Civil\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw\",\"datePublished\":\"2023-07-20T17:00:00+00:00\",\"description\":\"Principais aspectos quanto ao Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage\",\"url\":\"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw\",\"contentUrl\":\"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso TSE Unificado: IRDR no Processo Civil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb\",\"name\":\"Frederico Tadeu Borlot Peixoto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g\",\"caption\":\"Frederico Tadeu Borlot Peixoto\"},\"description\":\"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/proffrederico\/\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso TSE Unificado: IRDR no Processo Civil","description":"Principais aspectos quanto ao Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso TSE Unificado: IRDR no Processo Civil","og_description":"Principais aspectos quanto ao Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-07-20T17:00:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/18152341\/tse_unificado-1.jpg","type":"image\/jpeg"}],"author":"Frederico Tadeu Borlot Peixoto","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Frederico Tadeu Borlot Peixoto","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/"},"author":{"name":"Frederico Tadeu Borlot Peixoto","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb"},"headline":"Concurso TSE Unificado: IRDR no Processo Civil","datePublished":"2023-07-20T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/"},"wordCount":1568,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage"},"thumbnailUrl":"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw","articleSection":["Concursos P\u00fablicos","Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/","name":"Concurso TSE Unificado: IRDR no Processo Civil","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage"},"thumbnailUrl":"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw","datePublished":"2023-07-20T17:00:00+00:00","description":"Principais aspectos quanto ao Incidente de Resolu\u00e7\u00e3o de Demandas Repetitivas (IRDR) no Processo Civil para o Concurso TSE Unificado.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#primaryimage","url":"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw","contentUrl":"https:\/\/lh3.googleusercontent.com\/elvJNZ8sT5UcSa7EWqTWBlDvG8iDijngcc_6ihlmSw0VhdLr4A-a13hjRI-BpCW0DvZ-cqkXLOxEExpQacHjOo3jKofkkRFUOLctsYTE549wVrz8NbAW8o2sbfsccZYZCUOachYvTRc9oQLh7VLCPBw"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-tse-unificado-irdr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso TSE Unificado: IRDR no Processo Civil"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/48a7e085e45aee7c3d4596399af50ebb","name":"Frederico Tadeu Borlot Peixoto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df8a49e2321c1e32f85e9e7c2a9c92c688f1f53a947220f40017ff5858b09fdb?s=96&d=mm&r=g","caption":"Frederico Tadeu Borlot Peixoto"},"description":"Analista Judici\u00e1rio - \u00c1rea Judici\u00e1ria do TRF da 4\u00aa regi\u00e3o. Bacharel em Direito. P\u00f3s-graduado em Direito Administrativo, Legisla\u00e7\u00e3o Penal Especial, Direito Penal e Direito Processual Penal. Tamb\u00e9m nomeado no TRF da 3\u00aa regi\u00e3o (8\u00ba lugar); SPPREV (3\u00ba lugar); IFES (2\u00ba lugar); e PMES. https:\/\/www.instagram.com\/proffrederico\/","sameAs":["https:\/\/www.instagram.com\/proffrederico\/"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/xfredericohotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1236169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2567"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1236169"}],"version-history":[{"count":4,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1236169\/revisions"}],"predecessor-version":[{"id":1236219,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1236169\/revisions\/1236219"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1236169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1236169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1236169"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1236169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}