{"id":1233205,"date":"2023-07-15T14:00:00","date_gmt":"2023-07-15T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1233205"},"modified":"2023-07-04T15:04:29","modified_gmt":"2023-07-04T18:04:29","slug":"lrf-iss-sp","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/","title":{"rendered":"Lei de Responsabilidade Fiscal para o ISS SP"},"content":{"rendered":"\n<p>Para ajudar voc\u00ea a garantir uma vaga, vamos reunir aqui as principais informa\u00e7\u00f5es que precisa saber sobre a Lei de Responsabilidade Fiscal \u2013 LRF para o ISS SP, pois o edital do concurso acaba de ser publicado e \u00e9 uma excelente oportunidade.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg\" alt=\"LRF para o ISS SP\" class=\"wp-image-1056301\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp-300x169.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp-610x343.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp-150x84.jpg 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Vamos come\u00e7ar!<\/p>\n\n\n\n<p>A banca organizadora do concurso do ISS SP ser\u00e1 a VUNESP, e o edital prev\u00ea 60 vagas.<\/p>\n\n\n\n<p>Ser\u00e3o <strong>50 vagas<\/strong> destinadas para o cargo de <strong>Auditor Fiscal Tribut\u00e1rio Municipal \u2013 \u00c1rea de Especializa\u00e7\u00e3o: Gest\u00e3o Tribut\u00e1ria<\/strong> e 10 vagas para <strong>Auditor Fiscal Tribut\u00e1rio Municipal \u2013 \u00c1rea de Especializa\u00e7\u00e3o: Tecnologia da Informa\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>A remunera\u00e7\u00e3o inicial da carreira para ambos os cargos \u00e9 de R$ 26.049,51 para uma carga hor\u00e1ria semanal de 44 horas.<\/p>\n\n\n\n<p>Os altos sal\u00e1rios oferecidos pelo \u00f3rg\u00e3o s\u00e3o um grande atrativo, por isso com certeza a concorr\u00eancia ser\u00e1 bastante acirrada, por isso voc\u00ea precisa estudar com efici\u00eancia nesta fase p\u00f3s-edital e chegar na prova pronto para garantir a sua vaga.<\/p>\n\n\n\n<p>O concurso ser\u00e1 formado por <strong>prova objetiva<\/strong> e <strong>prova dissertativa<\/strong>.<\/p>\n\n\n\n<p>A realiza\u00e7\u00e3o das provas ser\u00e1 dividida entres os dias 24.09.2023 e 01.10.2023.<\/p>\n\n\n\n<p>Entendidos os pontos mais relevantes do concurso, vamos passar agora para o estudo das principais informa\u00e7\u00f5es sobre a <strong>Lei de Responsabilidade Fiscal<\/strong> que constam no edital do ISS SP e ser\u00e3o cobradas na sua prova.<\/p>\n\n\n\n<p>O conhecimento da LRF ser\u00e1 cobrado juntamente com os <strong>conhecimentos espec\u00edficos<\/strong>, dentro do t\u00f3pico do edital de Contabilidade P\u00fablica.<\/p>\n\n\n\n<p>A Lei de Responsabilidade Fiscal \u00e9 a Lei Complementar n\u00ba 101\/2000 e foi editada para refor\u00e7ar a responsabilidade na gest\u00e3o fiscal, mediante limites de endividamento, gastos de pessoal, limita\u00e7\u00f5es de empenho, bem como para refor\u00e7ar a transpar\u00eancia na gest\u00e3o p\u00fablica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-lrf-para-o-iss-sp-renuncia-de-receita\">LRF para o ISS SP: Ren\u00fancia de Receita<\/h2>\n\n\n\n<p>Vamos iniciar nossa an\u00e1lise da <strong>LRF para o ISS SP pela ren\u00fancia de receita<\/strong>.<\/p>\n\n\n\n<p>O estabelecimento de <strong>limites e condi\u00e7\u00f5es para a realiza\u00e7\u00e3o da ren\u00fancia de receita <\/strong>faz parte da <strong>responsabilidade na gest\u00e3o fiscal <\/strong>estabelecida pela LRF. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Assim, para que os entes p\u00fablicos realizem a ren\u00fancia de receita de forma respons\u00e1vel e sem comprometer os gastos p\u00fablicos, a LRF definiu como tal ren\u00fancia dever\u00e1 ocorrer.<\/p>\n\n\n\n<p>Inicialmente, a Lei exige que sempre que o \u00f3rg\u00e3o <strong>conceder ou ampliar um incentivo ou um benef\u00edcio tribut\u00e1rio<\/strong>, quando ocasionar a ren\u00fancia da receita, dever\u00e1 emitir um documento denominado de <strong>estimativa do impacto or\u00e7ament\u00e1rio-financeiro<\/strong>.<\/p>\n\n\n\n<p>Esta estimativa deve analisar quais os impactos decorrer\u00e3o da ren\u00fancia de receita no exerc\u00edcio em que a ren\u00fancia iniciar, bem como nos 2 exerc\u00edcios seguintes.<\/p>\n\n\n\n<p>Al\u00e9m disso, o ato da ren\u00fancia de receita deve <strong>atender a Lei de Diretrizes Or\u00e7ament\u00e1rias<\/strong>. Deve tamb\u00e9m <strong>demonstrar que a ren\u00fancia foi considerada na estimativa da receita e n\u00e3o afetar\u00e1 as metas estabelecidas ou demonstrar as medidas para aumento da receita, de forma a compensar a ren\u00fancia<\/strong>.<\/p>\n\n\n\n<p>A Lei de Responsabilidade Fiscal estabelece que as disposi\u00e7\u00f5es sobre a ren\u00fancia de receita n\u00e3o ser\u00e3o aplic\u00e1veis ao <strong>cancelamento de d\u00e9bitos que forem inferiores aos custos de cobran\u00e7a<\/strong>, bem como as altera\u00e7\u00f5es nas al\u00edquotas tribut\u00e1rias realizadas nos seguintes impostos: <strong>II, IE, IPI, IOF<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LRF para o ISS SP: Gera\u00e7\u00e3o de despesas e despesa obrigat\u00f3ria de car\u00e1ter continuado<\/h2>\n\n\n\n<p>Continuando a an\u00e1lise da <strong>LRF para o ISS SP<\/strong>, vamos verificar o que a lei prev\u00ea quanto \u00e0 <strong>gera\u00e7\u00e3o da despesa e \u00e0 cria\u00e7\u00e3o de despesas obrigat\u00f3rias de car\u00e1ter continuado<\/strong>.<\/p>\n\n\n\n<p>Ainda dentro do intuito de tornar as contas dos entes p\u00fablicos mais respons\u00e1veis, a Lei de Responsabilidade Fiscal reservou um cap\u00edtulo inteiro para tratar da despesa p\u00fablica. &nbsp;<\/p>\n\n\n\n<p>No que tange \u00e0 cria\u00e7\u00e3o de despesa, a Lei determinou que deve ser <strong>acompanhada de estimativa do impacto or\u00e7ament\u00e1rio-financeiro no exerc\u00edcio de sua cria\u00e7\u00e3o, bem como nos 2 exerc\u00edcios seguintes<\/strong>, nos mesmos moldes exigidos para a ren\u00fancia da receita.<\/p>\n\n\n\n<p>Tamb\u00e9m, al\u00e9m da evidencia\u00e7\u00e3o do impacto or\u00e7ament\u00e1rio-financeiro, deve ser demonstrado que a cria\u00e7\u00e3o de despesa possui <strong>adequa\u00e7\u00e3o or\u00e7ament\u00e1ria e financeira com a Lei Or\u00e7ament\u00e1ria Anual e \u00e9 compat\u00edvel com o previsto no Plano Plurianual e na Lei de Diretrizes Or\u00e7ament\u00e1rias<\/strong>.<\/p>\n\n\n\n<p>Essas exig\u00eancias citadas s\u00e3o <strong>condi\u00e7\u00e3o<\/strong> para a <strong>emiss\u00e3o de empenho e realiza\u00e7\u00e3o de licita\u00e7\u00e3o<\/strong> para bens, servi\u00e7os e execu\u00e7\u00e3o de obras, bem como para a <strong>desapropria\u00e7\u00e3o de im\u00f3veis urbanos<\/strong>, contudo n\u00e3o se aplicam para as <strong>despesas consideradas irrelevantes<\/strong>.<\/p>\n\n\n\n<p>J\u00e1 as <strong>despesas obrigat\u00f3rias de car\u00e1ter continuado<\/strong> s\u00e3o <strong>despesas correntes<\/strong> que obrigam os entes por mais de 2 exerc\u00edcios e derivam de <strong>lei, medida provis\u00f3ria ou ato administrativo normativo<\/strong>.<\/p>\n\n\n\n<p>Em nome da gest\u00e3o p\u00fablica equilibrada, a Lei de Responsabilidade Fiscal exige alguns requisitos para a cria\u00e7\u00e3o ou expans\u00e3o das despesas obrigat\u00f3rias de car\u00e1ter continuado.<\/p>\n\n\n\n<p>Esses requisitos s\u00e3o os seguintes:<\/p>\n\n\n\n<p>&#8211; <strong>estimativa<\/strong> do impacto or\u00e7ament\u00e1rio-financeiro;<\/p>\n\n\n\n<p>&nbsp;&#8211; evidenciar a <strong>origem<\/strong> dos recursos para custeio;<\/p>\n\n\n\n<p>&#8211; comprova\u00e7\u00e3o de que a despesa <strong>n\u00e3o afetar\u00e1 as metas <\/strong>de resultados fiscais;<\/p>\n\n\n\n<p>&nbsp;&#8211; <strong>compensa\u00e7\u00e3o<\/strong> dos efeitos financeiros pelo aumento permanente da receita ou pela redu\u00e7\u00e3o da despesa;<\/p>\n\n\n\n<p>&#8211; exame de <strong>compatibilidade<\/strong> da despesa com o Plano Plurianual e a Lei de Diretrizes Or\u00e7ament\u00e1rias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LRF: D\u00edvida e endividamento<\/h2>\n\n\n\n<p>Vamos prosseguir na an\u00e1lise da LRF para o ISS SP avaliando agora as principais disposi\u00e7\u00f5es da Lei sobre a <strong>d\u00edvida p\u00fablica<\/strong> e o <strong>endividamento<\/strong>.<\/p>\n\n\n\n<p>Abaixo, reunimos de forma resumida as defini\u00e7\u00f5es da Lei de Responsabilidade Fiscal, referente \u00e0 d\u00edvida: &nbsp;&nbsp;<\/p>\n\n\n\n<p>&#8211; <strong>d\u00edvida p\u00fablica consolidada\/fundada<\/strong>: montante total, sem duplicidade, das obriga\u00e7\u00f5es financeiras assumidas em virtude de leis, contratos, conv\u00eanios ou tratados e da realiza\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9dito com prazo superior a 12 meses;<\/p>\n\n\n\n<p>&#8211; <strong>d\u00edvida p\u00fablica mobili\u00e1ria<\/strong>: t\u00edtulos emitidos pelos entes (incluindo os t\u00edtulos do Banco Central do Brasil na d\u00edvida da Uni\u00e3o);<\/p>\n\n\n\n<p>&#8211; <strong>opera\u00e7\u00e3o de cr\u00e9dito<\/strong>: somat\u00f3rio dos compromissos financeiros assumidos pelo ente, incluindo-se m\u00fatuo, abertura de cr\u00e9dito, emiss\u00e3o e aceite de t\u00edtulo, aquisi\u00e7\u00e3o financiada de bens, recebimento antecipado de valores decorrente de venda de bens e servi\u00e7os, arrendamento mercantil e outras opera\u00e7\u00f5es semelhantes;<\/p>\n\n\n\n<p>&#8211; <strong>concess\u00e3o de garantia<\/strong>: assun\u00e7\u00e3o de compromisso de adimpl\u00eancia de obriga\u00e7\u00e3o financeira ou contratual;<\/p>\n\n\n\n<p>&#8211; <strong>refinanciamento da d\u00edvida mobili\u00e1ria<\/strong>: emiss\u00e3o de t\u00edtulos para pagamento do principal da d\u00edvida mobili\u00e1ria, acrescido da atualiza\u00e7\u00e3o monet\u00e1ria.<\/p>\n\n\n\n<p>Devido \u00e0 import\u00e2ncia do tema, sugerimos que voc\u00ea saiba diferenciar todas as defini\u00e7\u00f5es trazidas acima, pois s\u00e3o grandes as chances de cobran\u00e7a na prova.<\/p>\n\n\n\n<p>Al\u00e9m disso, t\u00e3o importante quanto saber as defini\u00e7\u00f5es sobre a d\u00edvida p\u00fablica \u00e9 saber o que o ente deve fazer caso sejam ultrapassados os limites de endividamento.<\/p>\n\n\n\n<p>Caso os <strong>limites da d\u00edvida consolidada, mobili\u00e1ria e das opera\u00e7\u00f5es de cr\u00e9dito internas e externas<\/strong> sejam ultrapassados, enquanto perdurar o excesso, o ente estar\u00e1 <strong>proibido de realizar opera\u00e7\u00e3o de cr\u00e9dito<\/strong>, salvo para pagamento da d\u00edvida mobili\u00e1ria, e dever\u00e1 <strong>obter o resultado prim\u00e1rio<\/strong> necess\u00e1rio para reconduzir a d\u00edvida ao limite m\u00e1ximo permitido.<\/p>\n\n\n\n<p>Caso o ente n\u00e3o consiga retornar ao limite da d\u00edvida no prazo, ficar\u00e1 tamb\u00e9m impedido de receber transfer\u00eancias volunt\u00e1rias.<\/p>\n\n\n\n<p>Ainda, dentro do cap\u00edtulo que trata da d\u00edvida, a Lei de Responsabilidade Fiscal reservou um artigo especificamente para tratar sobre os <strong>restos a pagar<\/strong>.<\/p>\n\n\n\n<p>Os restos a pagar s\u00e3o despesas que passaram pelo est\u00e1gio do empenho, liquidadas ou n\u00e3o, mas que n\u00e3o puderam ser pagas dentro do mesmo exerc\u00edcio de emiss\u00e3o do empenho.<\/p>\n\n\n\n<p>Assim, a Lei veda, nos <strong>\u00faltimos 2 quadrimestres do mandato<\/strong> do titular de Poder, a contrata\u00e7\u00e3o de despesa que n\u00e3o possa ser liquidada dentro do mandato. Fica vedada tamb\u00e9m a realiza\u00e7\u00e3o de despesas que deixe parcelas a serem pagas em exerc\u00edcio subsequente, sem suficiente disponibilidade de caixa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LRF para o ISS SP: Relat\u00f3rio de Gest\u00e3o Fiscal e Relat\u00f3rio Resumido da Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria<\/h2>\n\n\n\n<p>Vamos finalizar nosso estudo da Lei de Responsabilidade Fiscal para o concurso do ISS SP com dois instrumentos de extrema import\u00e2ncia para os entes p\u00fablicos: o <strong>Relat\u00f3rio de Gest\u00e3o Fiscal<\/strong> (RGF) e o <strong>Relat\u00f3rio Resumido da Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria<\/strong> (RREO).<\/p>\n\n\n\n<p>O <strong>RREO<\/strong> j\u00e1 estava previsto na Constitui\u00e7\u00e3o Federal e deve ser publicado bimestralmente pelo Poder Executivo.<\/p>\n\n\n\n<p>Este demonstrativo deve ser composto dos seguintes documentos:<\/p>\n\n\n\n<p>&#8211; <strong>balan\u00e7o or\u00e7ament\u00e1rio<\/strong>, evidenciando por categoria econ\u00f4mica as receitas por fonte e despesas por grupo de natureza;<\/p>\n\n\n\n<p>&#8211; <strong>demonstrativos<\/strong> da execu\u00e7\u00e3o das receitas, por categoria econ\u00f4mica e fonte; despesas, por categoria econ\u00f4mica e grupo de natureza da despesa; despesas por fun\u00e7\u00e3o e subfun\u00e7\u00e3o.<\/p>\n\n\n\n<p>O RREO deve ser acompanhado dos demonstrativos seguintes:<\/p>\n\n\n\n<p><strong>&#8211; apura\u00e7\u00e3o da receita corrente l\u00edquida;<\/strong><\/p>\n\n\n\n<p><strong>&#8211; receitas e despesas previdenci\u00e1rias;<\/strong><\/p>\n\n\n\n<p><strong>&#8211; resultados nominal e prim\u00e1rio;<\/strong><\/p>\n\n\n\n<p><strong>&#8211; despesas com juros;<\/strong><\/p>\n\n\n\n<p><strong>&#8211; restos a pagar.<\/strong><\/p>\n\n\n\n<p>O RREO do \u00faltimo bimestre de cada exerc\u00edcio ser\u00e1 acompanhado ainda dos seguintes demonstrativos:<\/p>\n\n\n\n<p>&#8211; atendimento da regra de ouro, dispositivo constitucional que veda que a realiza\u00e7\u00e3o de opera\u00e7\u00f5es de cr\u00e9ditos seja superior \u00e0s despesas de capital;<\/p>\n\n\n\n<p>&#8211; proje\u00e7\u00f5es atuariais dos regimes de previd\u00eancia social;<\/p>\n\n\n\n<p>&#8211; varia\u00e7\u00e3o patrimonial, evidenciando a aliena\u00e7\u00e3o de ativos e a aplica\u00e7\u00e3o dos recursos.<\/p>\n\n\n\n<p>Se necess\u00e1rio, o RREO dever\u00e1 apresentar as justificativas para a limita\u00e7\u00e3o de empenho e para a frustra\u00e7\u00e3o de receitas.<\/p>\n\n\n\n<p>Por outro lado, o <strong>RGF <\/strong>ser\u00e1 apresentado quadrimestralmente pelos titulares de Poderes e \u00f3rg\u00e3os e conter\u00e1 o seguinte:<\/p>\n\n\n\n<p>&#8211; comparativo dos montantes com os <strong>limites<\/strong> m\u00e1ximos de despesa total com pessoal, d\u00edvidas consolidada e mobili\u00e1ria, concess\u00e3o de garantias, opera\u00e7\u00f5es de cr\u00e9dito;<\/p>\n\n\n\n<p>&#8211; indica\u00e7\u00e3o das <strong>medidas corretivas<\/strong> se ultrapassado algum dos limites;<\/p>\n\n\n\n<p>&#8211; no <strong>\u00faltimo quadrimestre,<\/strong> o montante das disponibilidades de caixa em 31 de dezembro, a evidencia\u00e7\u00e3o da inscri\u00e7\u00e3o em restos a pagar e o cumprimento das exig\u00eancias quanto a opera\u00e7\u00f5es de cr\u00e9dito por antecipa\u00e7\u00e3o de receita.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Todas as considera\u00e7\u00f5es pertinentes sobre a LRF para o concurso do ISS SP apresentadas aqui devem ser levadas com bastante clareza para a prova, pois s\u00e3o muito importantes e o \u00edndice de cobran\u00e7a \u00e9 super alto.<\/p>\n\n\n\n<p>O concurso do ISS SP \u00e9 uma excelente oportunidade para seguir carreira, ent\u00e3o d\u00ea foco total na sua prepara\u00e7\u00e3o agora na reta final deste concurso.<\/p>\n\n\n\n<p>Al\u00e9m de um \u00f3timo sal\u00e1rio, o edital veio com um n\u00famero significativo de vagas previstas, ent\u00e3o sabemos que essa ser\u00e1 uma oportunidade \u00fanica.<\/p>\n\n\n\n<p>Atue de forma comprometida nos estudos, aja com efetividade nessas \u00faltimas semanas antes da prova e garanta a sua vaga.<\/p>\n\n\n\n<p>Bons estudos!<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background\">Quer estudar para o concurso do ISS SP? Confira <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/iss-sp-17\/?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=ec-fis-vd-gsh-ISSSP&amp;gclid=CjwKCAjwkLCkBhA9EiwAka9QRlJYL7mWKoSwWwOxaAyE0Q8ofwc_J1B0FKkT0QoGZccwRjRdZHLzhhoCj2gQAvD_BwE\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a> todos os cursos que preparamos para voc\u00ea.<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size\">Quer saber tudo sobre os concursos previstos?<\/p>\n\n\n\n<p class=\"has-text-align-center has-large-font-size\">Confira nossos artigos!<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos 2023<\/strong><\/a><\/p>\n\n\n\n<p>Link utilizado:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.vunesp.com.br\/SMGE2304\">https:\/\/www.vunesp.com.br\/SMGE2304<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para ajudar voc\u00ea a garantir uma vaga, vamos reunir aqui as principais informa\u00e7\u00f5es que precisa saber sobre a Lei de Responsabilidade Fiscal \u2013 LRF para o ISS SP, pois o edital do concurso acaba de ser publicado e \u00e9 uma excelente oportunidade. Vamos come\u00e7ar! A banca organizadora do concurso do ISS SP ser\u00e1 a VUNESP, [&hellip;]<\/p>\n","protected":false},"author":2461,"featured_media":1056301,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220183],"tags":[],"tax_estado":[219963,219989],"class_list":["post-1233205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-municipal","tax_estado-concursos-federais","tax_estado-sp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LRF para o ISS SP<\/title>\n<meta name=\"description\" content=\"Saiba aqui as principais informa\u00e7\u00f5es sobre a Lei de Responsabilidade Fiscal, e aproveite a excelente oportunidade que \u00e9 o concurso do ISS SP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lei de Responsabilidade Fiscal para o ISS SP\" \/>\n<meta property=\"og:description\" content=\"Saiba aqui as principais informa\u00e7\u00f5es sobre a Lei de Responsabilidade Fiscal, e aproveite a excelente oportunidade que \u00e9 o concurso do ISS SP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-15T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maiara Anger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maiara Anger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/\"},\"author\":{\"name\":\"Maiara Anger\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8fc96f7f7728e195db482f9d8160b155\"},\"headline\":\"Lei de Responsabilidade Fiscal para o ISS SP\",\"datePublished\":\"2023-07-15T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/\"},\"wordCount\":1919,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Municipal (ISS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/\",\"name\":\"LRF para o ISS SP\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg\",\"datePublished\":\"2023-07-15T17:00:00+00:00\",\"description\":\"Saiba aqui as principais informa\u00e7\u00f5es sobre a Lei de Responsabilidade Fiscal, e aproveite a excelente oportunidade que \u00e9 o concurso do ISS SP.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg\",\"width\":768,\"height\":432,\"caption\":\"iss sp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lei de Responsabilidade Fiscal para o ISS SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8fc96f7f7728e195db482f9d8160b155\",\"name\":\"Maiara Anger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1bfd018c87b73c778d016238d0c7c212ecf417543a9f8423e47fefc011c2925f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1bfd018c87b73c778d016238d0c7c212ecf417543a9f8423e47fefc011c2925f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1bfd018c87b73c778d016238d0c7c212ecf417543a9f8423e47fefc011c2925f?s=96&d=mm&r=g\",\"caption\":\"Maiara Anger\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/maiaraangermx2-unisc-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LRF para o ISS SP","description":"Saiba aqui as principais informa\u00e7\u00f5es sobre a Lei de Responsabilidade Fiscal, e aproveite a excelente oportunidade que \u00e9 o concurso do ISS SP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Lei de Responsabilidade Fiscal para o ISS SP","og_description":"Saiba aqui as principais informa\u00e7\u00f5es sobre a Lei de Responsabilidade Fiscal, e aproveite a excelente oportunidade que \u00e9 o concurso do ISS SP.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-07-15T17:00:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg","type":"image\/jpeg"}],"author":"Maiara Anger","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Maiara Anger","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/"},"author":{"name":"Maiara Anger","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8fc96f7f7728e195db482f9d8160b155"},"headline":"Lei de Responsabilidade Fiscal para o ISS SP","datePublished":"2023-07-15T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/"},"wordCount":1919,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg","articleSection":["Concursos P\u00fablicos","Fiscal - Municipal (ISS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/","name":"LRF para o ISS SP","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg","datePublished":"2023-07-15T17:00:00+00:00","description":"Saiba aqui as principais informa\u00e7\u00f5es sobre a Lei de Responsabilidade Fiscal, e aproveite a excelente oportunidade que \u00e9 o concurso do ISS SP.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/07\/06133946\/iss_sp.jpg","width":768,"height":432,"caption":"iss sp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/lrf-iss-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Lei de Responsabilidade Fiscal para o ISS SP"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8fc96f7f7728e195db482f9d8160b155","name":"Maiara Anger","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1bfd018c87b73c778d016238d0c7c212ecf417543a9f8423e47fefc011c2925f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bfd018c87b73c778d016238d0c7c212ecf417543a9f8423e47fefc011c2925f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bfd018c87b73c778d016238d0c7c212ecf417543a9f8423e47fefc011c2925f?s=96&d=mm&r=g","caption":"Maiara Anger"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/maiaraangermx2-unisc-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1233205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2461"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1233205"}],"version-history":[{"count":10,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1233205\/revisions"}],"predecessor-version":[{"id":1243289,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1233205\/revisions\/1243289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1056301"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1233205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1233205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1233205"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1233205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}