{"id":1231045,"date":"2023-06-13T02:12:06","date_gmt":"2023-06-13T05:12:06","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1231045"},"modified":"2023-06-13T02:12:09","modified_gmt":"2023-06-13T05:12:09","slug":"informativo-stj-774-comentado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/","title":{"rendered":"Informativo STJ 774 Comentado"},"content":{"rendered":"\n<p>Informativo n\u00ba 774 do STJ\u00a0<strong>COMENTADO<\/strong>\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/06\/13021155\/stj-informativo-774.pdf\" rel=\"sponsored nofollow\">DOWNLOAD do PDF AQUI!<\/a><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL__QWgqKIrJX0\"><div id=\"lyte__QWgqKIrJX0\" data-src=\"\/\/i.ytimg.com\/vi\/_QWgqKIrJX0\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/_QWgqKIrJX0\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/_QWgqKIrJX0\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-administrativo\"><a>DIREITO ADMINISTRATIVO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-termo-inicial-dos-juros-de-mora-em-acao-de-cobranca-de-valores-preteritos-ao-ajuizamento-de-anterior-mandado-de-seguranca-que-reconheceu-o-direito\"><a>1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Termo inicial dos juros de mora em a\u00e7\u00e3o de cobran\u00e7a de valores pret\u00e9ritos ao ajuizamento de anterior mandado de seguran\u00e7a que reconheceu o direito<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>O termo inicial dos juros de mora, em a\u00e7\u00e3o de cobran\u00e7a de valores pret\u00e9ritos ao ajuizamento de anterior mandado de seguran\u00e7a que reconheceu o direito, \u00e9 a data da notifica\u00e7\u00e3o da autoridade coatora no mandado de seguran\u00e7a, quando o devedor \u00e9 constitu\u00eddo em mora (arts. 405 do C\u00f3digo Civil e 240 do CPC).<\/p>\n\n\n\n<p>REsp 1.925.235-SP, Rel. Ministra Assusete Magalh\u00e3es, Primeira Se\u00e7\u00e3o, por unanimidade, julgado em 10\/5\/2023 (Tema 1133). (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-1-situacao-fatica\"><a>1.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Policiais militares inativos ajuizaram uma a\u00e7\u00e3o em face do Estado de S\u00e3o Paulo e S\u00e3o Paulo Previd\u00eancia &#8211; SPPREV, objetivando o pagamento das parcelas referentes ao Adicional Local de Exerc\u00edcio &#8211; ALE, no per\u00edodo que antecedeu \u00e0 impetra\u00e7\u00e3o de Mandado de Seguran\u00e7a Coletivo em que se reconheceu o direito \u00e0 incorpora\u00e7\u00e3o da verba aos proventos de aposentadoria e pens\u00f5es.<\/p>\n\n\n\n<p>A senten\u00e7a julgou o pedido procedente e reconheceu o direito ao pagamento do Adicional em quest\u00e3o, no per\u00edodo pleiteado, fixando o termo inicial dos juros de mora a partir da cita\u00e7\u00e3o dos r\u00e9us, na a\u00e7\u00e3o de cobran\u00e7a. Inconformados, os policiais interpuseram recurso no qual sustentam que o termo inicial dos juros de mora deve ser fixado na data da notifica\u00e7\u00e3o da autoridade coatora do mandado de seguran\u00e7a que a embasou.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-2-analise-estrategica\"><a>1.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-1-questao-juridica\"><a>1.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo Civil:<\/p>\n\n\n\n<p>Art. 405. Contam-se os juros de mora desde a cita\u00e7\u00e3o inicial.<\/p>\n\n\n\n<p>CPC2015:<\/p>\n\n\n\n<p>Art. 240. A cita\u00e7\u00e3o v\u00e1lida, ainda quando ordenada por ju\u00edzo incompetente, induz litispend\u00eancia, torna litigiosa a coisa e constitui em mora o devedor, ressalvado o disposto nos arts. 397 e 398 da Lei n\u00ba 10.406, de 10 de janeiro de 2002 (C\u00f3digo Civil) .<\/p>\n\n\n\n<p><a><\/a>\u00a7 1\u00ba A interrup\u00e7\u00e3o da prescri\u00e7\u00e3o, operada pelo despacho que ordena a cita\u00e7\u00e3o, ainda que proferido por ju\u00edzo incompetente, retroagir\u00e1 \u00e0 data de propositura da a\u00e7\u00e3o.<\/p>\n\n\n\n<p><a><\/a>\u00a7 2\u00ba Incumbe ao autor adotar, no prazo de 10 (dez) dias, as provid\u00eancias necess\u00e1rias para viabilizar a cita\u00e7\u00e3o, sob pena de n\u00e3o se aplicar o disposto no \u00a7 1\u00ba.<\/p>\n\n\n\n<p><a><\/a>\u00a7 3\u00ba A parte n\u00e3o ser\u00e1 prejudicada pela demora imput\u00e1vel exclusivamente ao servi\u00e7o judici\u00e1rio.<\/p>\n\n\n\n<p><a><\/a>\u00a7 4\u00ba O efeito retroativo a que se refere o \u00a7 1\u00ba aplica-se \u00e0 decad\u00eancia e aos demais prazos extintivos previstos em lei.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-2-qual-o-termo-inicial-a-ser-observado\"><a>1.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Qual o termo inicial a ser observado?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>A data da notifica\u00e7\u00e3o no MS!!!!<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia consiste em definir se o termo inicial dos juros de mora, em a\u00e7\u00e3o de cobran\u00e7a de valores pret\u00e9ritos ao ajuizamento de anterior mandado de seguran\u00e7a, deve ser contado a partir da cita\u00e7\u00e3o, na a\u00e7\u00e3o de cobran\u00e7a, ou da notifica\u00e7\u00e3o da autoridade coatora, quando da impetra\u00e7\u00e3o do mandado de seguran\u00e7a.<\/p>\n\n\n\n<p>O pressuposto b\u00e1sico para configura\u00e7\u00e3o da mora \u00e9 a viabilidade no cumprimento da obriga\u00e7\u00e3o: em que pese a impossibilidade transit\u00f3ria de satisfaz\u00ea-la, a presta\u00e7\u00e3o ainda \u00e9 poss\u00edvel e \u00fatil.<\/p>\n\n\n\n<p>Na quest\u00e3o jur\u00eddica posta incide a mora&nbsp;<em>solvendi<\/em>, uma vez que \u00e9 concernente ao n\u00e3o pagamento, pelo Estado de S\u00e3o Paulo, de Adicional de Local de Exerc\u00edcio &#8211; ALE, devido a policiais militares inativos, no caso, no per\u00edodo que antecedeu \u00e0 impetra\u00e7\u00e3o da a\u00e7\u00e3o mandamental coletiva, na qual foi reconhecido o direito. Tem-se, portanto, obriga\u00e7\u00e3o de natureza positiva e il\u00edquida, exig\u00edvel por for\u00e7a de decis\u00e3o judicial.<\/p>\n\n\n\n<p><strong>A impetra\u00e7\u00e3o de mandado de seguran\u00e7a repercutir\u00e1 na a\u00e7\u00e3o de cobran\u00e7a sob os seguintes aspectos<\/strong>: I) interromper\u00e1 o prazo prescricional para ajuizamento do feito; II) delimitar\u00e1 o pedido formulado, a partir do quinqu\u00eanio que antecedeu \u00e0 propositura do writ, e III) constituir\u00e1 em mora o devedor.<\/p>\n\n\n\n<p>A partir do regramento previsto para a constitui\u00e7\u00e3o em mora do devedor, nas obriga\u00e7\u00f5es il\u00edquidas (art. 405 do C\u00f3digo Civil c\/c art. 240 do CPC\/2015), extrai-se que a notifica\u00e7\u00e3o da autoridade coatora em mandado de seguran\u00e7a cientifica formalmente o Poder P\u00fablico do n\u00e3o cumprimento da obriga\u00e7\u00e3o (mora&nbsp;<em>ex persona<\/em>). \u00c9, portanto, irrelevante, para fins de constitui\u00e7\u00e3o em mora, a via processual eleita, pelo titular do direito, para pleitear a consecu\u00e7\u00e3o da obriga\u00e7\u00e3o.<\/p>\n\n\n\n<p>Desse modo, em se tratando de a\u00e7\u00e3o mandamental, cujos efeitos patrimoniais pret\u00e9ritos dever\u00e3o ser reclamados administrativamente, ou pela via judicial pr\u00f3pria (S\u00famula 271\/STF), a mora \u00e9 formalizada pelo ato de notifica\u00e7\u00e3o da autoridade coatora, sem preju\u00edzo da posterior liquida\u00e7\u00e3o do&nbsp;<em>quantum debeatur<\/em>&nbsp;da presta\u00e7\u00e3o.<\/p>\n\n\n\n<p>No ponto, cumpre esclarecer que a aludida limita\u00e7\u00e3o sumular apenas tem por escopo obstar o manejo do&nbsp;<em>writ of mandamus<\/em>&nbsp;como substitutivo da a\u00e7\u00e3o de cobran\u00e7a (S\u00famula 269\/STF), em nada interferindo na aplica\u00e7\u00e3o da regra de direito material referente \u00e0 constitui\u00e7\u00e3o em mora, a qual ocorre uma \u00fanica vez, no \u00e2mbito da mesma rela\u00e7\u00e3o obrigacional.<\/p>\n\n\n\n<p>A cita\u00e7\u00e3o v\u00e1lida da Fazenda P\u00fablica, entre outros efeitos, tem o cond\u00e3o de constitu\u00ed-la em atraso no tocante ao direito que a parte autora entende titularizar (art. 405 do C\u00f3digo Civil de 2002), sendo desimportantes as eventuais limita\u00e7\u00f5es impostas pelo meio processual eleito para fazer valer, concretamente, o bem jur\u00eddico em discuss\u00e3o. Entender de modo contr\u00e1rio implicaria admitir que o instrumento processual manejado (no caso, a\u00e7\u00e3o de cobran\u00e7a) \u00e9 o par\u00e2metro adequado para a fixa\u00e7\u00e3o do termo inicial dos respectivos juros de mora, em detrimento do arcabou\u00e7o normativo previsto pelo C\u00f3digo Civil de 2002, o qual, via de regra, considera a natureza da obriga\u00e7\u00e3o para a constitui\u00e7\u00e3o formal do devedor em mora.<\/p>\n\n\n\n<p>Portanto, <strong>em rela\u00e7\u00e3o \u00e0s parcelas pret\u00e9ritas, cujo direito foi reconhecido, na via mandamental, o termo inicial dos juros de mora, na a\u00e7\u00e3o de cobran\u00e7a, deve ser fixado na data da notifica\u00e7\u00e3o da autoridade coatora, pois \u00e9 o momento em que, nos termos do art. 405 do C\u00f3digo Civil c\/c art. 240 do Diploma Processual, houve a interrup\u00e7\u00e3o do prazo prescricional e a constitui\u00e7\u00e3o em mora do devedor<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-3-resultado-final\"><a>1.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>O termo inicial dos juros de mora, em a\u00e7\u00e3o de cobran\u00e7a de valores pret\u00e9ritos ao ajuizamento de anterior mandado de seguran\u00e7a que reconheceu o direito, \u00e9 a data da notifica\u00e7\u00e3o da autoridade coatora no mandado de seguran\u00e7a, quando o devedor \u00e9 constitu\u00eddo em mora (arts. 405 do C\u00f3digo Civil e 240 do CPC).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-im-possibilidade-de-remocao-por-motivo-de-saude-de-conjuge-de-membro-do-mpu\"><a>2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (Im)Possibilidade de remo\u00e7\u00e3o por motivo de sa\u00fade de c\u00f4njuge de membro do MPU<\/a><\/h2>\n\n\n\n<p><strong>PROCESSO SOB SEGREDO DE JUSTI\u00c7A<\/strong><\/p>\n\n\n\n<p>A norma do art. 36, III, &#8220;b&#8221;, da Lei n. 8.112\/1990 n\u00e3o pode ser aplicada de maneira subsidi\u00e1ria aos membros do Minist\u00e9rio P\u00fablico da Uni\u00e3o.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Gurgel de Faria, Primeira Turma, por unanimidade, julgado em 9\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-1-situacao-fatica\"><a>2.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creide, membro do MPU lotada no interior de certo estado, teve um filho diagnosticado com autismo severo. Em raz\u00e3o disso, solicitou remo\u00e7\u00e3o para sua cidade natal, local que oferece diversas op\u00e7\u00f5es de terapia e acompanhamento do filho. Creide sustenta que o direito \u00e0 remo\u00e7\u00e3o por motivos de sa\u00fade do dependente est\u00e1 previsto no art. 36, III, \u201cb\u201d da Lei 8.112\/1990. Alega que o referido dispositivo legal seria aplic\u00e1vel aos membros do MPU.<\/p>\n\n\n\n<p>Processo sob segredo de justi\u00e7a. Caso imaginado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-2-analise-estrategica\"><a>2.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-1-questao-juridica\"><a>2.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 8.112\/1990:<\/p>\n\n\n\n<p>Art.&nbsp;36.&nbsp;&nbsp;Remo\u00e7\u00e3o \u00e9 o deslocamento do servidor, a pedido ou de of\u00edcio, no \u00e2mbito do mesmo quadro, com ou sem mudan\u00e7a de sede.<\/p>\n\n\n\n<p>III&nbsp;&#8211;&nbsp; a pedido, para outra localidade, independentemente do interesse da Administra\u00e7\u00e3o:&nbsp;<\/p>\n\n\n\n<p>a)&nbsp;para acompanhar c\u00f4njuge ou companheiro, tamb\u00e9m servidor p\u00fablico civil ou militar, de qualquer dos Poderes da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios, que foi deslocado no interesse da Administra\u00e7\u00e3o<\/p>\n\n\n\n<p>b)&nbsp;por motivo de sa\u00fade do servidor, c\u00f4njuge, companheiro ou dependente que viva \u00e0s suas expensas e conste do seu assentamento funcional, condicionada \u00e0 comprova\u00e7\u00e3o por junta m\u00e9dica oficial;<\/p>\n\n\n\n<p>LC n. 75\/1993 :<\/p>\n\n\n\n<p><a><\/a>Art. 287. Aplicam-se subsidiariamente aos membros do Minist\u00e9rio P\u00fablico da Uni\u00e3o as disposi\u00e7\u00f5es gerais referentes aos servidores p\u00fablicos, respeitadas, quando for o caso, as normas especiais contidas nesta lei complementar.<\/p>\n\n\n\n<p>Constitui\u00e7\u00e3o Federal:<\/p>\n\n\n\n<p>Art. 227. \u00c9 dever da fam\u00edlia, da sociedade e do Estado assegurar \u00e0 crian\u00e7a, ao adolescente e ao jovem, com absoluta prioridade, o direito \u00e0 vida, \u00e0 sa\u00fade, \u00e0 alimenta\u00e7\u00e3o, \u00e0 educa\u00e7\u00e3o, ao lazer, \u00e0 profissionaliza\u00e7\u00e3o, \u00e0 cultura, \u00e0 dignidade, ao respeito, \u00e0 liberdade e \u00e0 conviv\u00eancia familiar e comunit\u00e1ria, al\u00e9m de coloc\u00e1-los a salvo de toda forma de neglig\u00eancia, discrimina\u00e7\u00e3o, explora\u00e7\u00e3o, viol\u00eancia, crueldade e opress\u00e3o.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-2-possivel-a-aplicacao-subsidiaria-da-norma\"><a>2.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Poss\u00edvel a aplica\u00e7\u00e3o subsidi\u00e1ria da norma?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nooops!!!!<\/strong><\/p>\n\n\n\n<p>O art. 36, III, &#8220;b&#8221;, da Lei n. 8.112\/1990 disciplina a possibilidade de o servidor p\u00fablico federal ser removido a pedido, para outra localidade, independentemente do interesse da Administra\u00e7\u00e3o, por motivo de sa\u00fade do servidor, c\u00f4njuge, companheiro ou dependente que viva \u00e0s suas expensas e conste do seu assentamento funcional, condicionada \u00e0 comprova\u00e7\u00e3o por junta m\u00e9dica oficial.<\/p>\n\n\n\n<p>A pretens\u00e3o de aplica\u00e7\u00e3o subsidi\u00e1ria da referida norma aos membros do Minist\u00e9rio P\u00fablico da Uni\u00e3o se assenta no argumento de que o disposto no art. 287,&nbsp;<em>caput<\/em>, da LC n. 75\/1993 assegura que &#8220;aplicam-se subsidiariamente aos membros do Minist\u00e9rio P\u00fablico da Uni\u00e3o as disposi\u00e7\u00f5es gerais referentes aos servidores p\u00fablicos, respeitadas, quando for o caso, as normas especiais contidas nesta lei complementar&#8221;.<\/p>\n\n\n\n<p>Todavia, a partir da leitura do pr\u00f3prio art. 287,&nbsp;<em>caput<\/em>, da LC n. 75\/1993, tem-se que a aplica\u00e7\u00e3o do Estatuto dos Servidores P\u00fablicos Federais em rela\u00e7\u00e3o aos membros do Minist\u00e9rio P\u00fablico somente pode ocorrer quando a legisla\u00e7\u00e3o desta \u00faltima carreira mencionada n\u00e3o preveja instituto pr\u00f3prio para solucionar a quest\u00e3o jur\u00eddica controvertida.<\/p>\n\n\n\n<p><strong>A LC n. 75\/1993, posterior \u00e0 Lei n. 8.112\/1990 (que se pretende aplicar subsidiariamente), poderia ter criado o direito \u00e0 remo\u00e7\u00e3o nessas hip\u00f3teses, mas optou por tratar da quest\u00e3o mediante instituto pr\u00f3prio (a licen\u00e7a),<\/strong> devendo prevalecer tal previs\u00e3o especial.<\/p>\n\n\n\n<p>Al\u00e9m disso, o n\u00famero de agentes de poder que gozam de inamovibilidade (a exemplo dos membros do MP e os magistrados) \u00e9 sempre inferior ao de servidores que comp\u00f5em as carreiras de apoio, fora o fato de que aqueles necessariamente desempenham as atribui\u00e7\u00f5es de chefia e gest\u00e3o. Assim, os impactos de uma remo\u00e7\u00e3o de of\u00edcio em rela\u00e7\u00e3o aos promotores, procuradores e magistrados s\u00e3o muito maiores em termos log\u00edsticos do que aqueles gerados pela remo\u00e7\u00e3o de of\u00edcio de um servidor, a justificar a diferen\u00e7a de tratamento legal: para os primeiros reservou-se o direito do gozo de licen\u00e7a; para os segundos o direito \u00e0 remo\u00e7\u00e3o em si.<\/p>\n\n\n\n<p>Ainda, se se entender que o art. 36 da Lei n. 8.112\/1990 pode ser aplicado subsidiariamente, nos casos em que o procurador tiver como c\u00f4njuge servidor e esse for removido de of\u00edcio (art. 36, III, &#8220;a&#8221;), o primeiro tamb\u00e9m ter\u00e1 direito \u00e0 remo\u00e7\u00e3o, ampliando-se bastante as hip\u00f3teses de remo\u00e7\u00e3o de membro de poder, em detrimento da organiza\u00e7\u00e3o do servi\u00e7o p\u00fablico e da criteriosa lista de antiguidade.<\/p>\n\n\n\n<p><strong>\u00c9 l\u00edcito concluir que a omiss\u00e3o na lei pr\u00f3pria do MPU a respeito da remo\u00e7\u00e3o para tratamento de sa\u00fade de familiar n\u00e3o se tratou de omiss\u00e3o at\u00e9cnica do legislador, mas caso de sil\u00eancio eloquente\/op\u00e7\u00e3o nesse aspecto<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-3-entao-manda-a-creide-volta\">2.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Ent\u00e3o manda a Creide volta?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>N\u00e3o \u00e9 bem assim&#8230;<\/strong><\/p>\n\n\n\n<p>Colhe-se do caso concreto que a recorrida se encontra removida para tratar filho menor (com autismo) desde 2016, constando ainda do ac\u00f3rd\u00e3o recorrido que foi produzida vasta e incontroversa prova no sentido de que: (a) o infante deve permanecer no local onde iniciou as terapias relacionadas ao autismo e manter seu conv\u00edvio familiar, social, terap\u00eautico e escolar, o mais estruturado poss\u00edvel, sem altera\u00e7\u00f5es significativas; (b) quaisquer varia\u00e7\u00f5es no ambiente de viv\u00eancia do menor, mesmo que m\u00ednimas, reverberam sobejamente na progress\u00e3o\/regress\u00e3o da doen\u00e7a, dada a sua sensibilidade psicol\u00f3gica; (c) a cidade de lota\u00e7\u00e3o origin\u00e1ria da autora n\u00e3o disp\u00f5e de quadro de profissionais que pudessem atender \u00e0s necessidades da crian\u00e7a; (d) ficou evidenciada a extrema import\u00e2ncia da presen\u00e7a da m\u00e3e junto \u00e0 crian\u00e7a para que essa apresente desenvolvimento saud\u00e1vel, bem como os impactos negativos, com comprometimento de sintomas e do processo de desenvolvimento, em caso de aus\u00eancia da genitora; e (e) poderia haver preju\u00edzos \u00e0 crian\u00e7a em caso de mudan\u00e7a de domic\u00edlio, com afastamento de outros familiares, pois o filho da recorrida estaria saindo do &#8220;seu mundo autista, para ele intoc\u00e1vel e s\u00f3 dele, para algo diferente e estranho onde o processo de socializa\u00e7\u00e3o ser\u00e1 afetado de forma brutal, acarretando preju\u00edzo na poss\u00edvel melhora de seus sintomas e um progn\u00f3stico reservado&#8221;.<\/p>\n\n\n\n<p>Todo esse contexto demonstra que<strong>, a despeito de a tese jur\u00eddica defendida pela Uni\u00e3o ser a correta, no caso concreto, a restaura\u00e7\u00e3o da estrita legalidade, com a mudan\u00e7a da autora e do filho (pessoa com defici\u00eancia) para a lota\u00e7\u00e3o de origem ocasionaria muito mais danos sociais que a manuten\u00e7\u00e3o da situa\u00e7\u00e3o consolidada<\/strong> (teoria do fato consumado\/consolidado).<\/p>\n\n\n\n<p>O STJ entende que em demandas envolvendo interesse de crian\u00e7a, como no caso, a solu\u00e7\u00e3o da controv\u00e9rsia deve sempre observar o princ\u00edpio do melhor interesse do menor, introduzido em nosso sistema jur\u00eddico como corol\u00e1rio da doutrina da prote\u00e7\u00e3o integral, consagrada pelo art. 227 da Constitui\u00e7\u00e3o Federal, o qual deve orientar a atua\u00e7\u00e3o tanto do legislador quanto do aplicador da norma jur\u00eddica, vinculando-se o ordenamento infraconstitucional aos seus contornos (STJ, HC 776.461\/SC, relator Ministro Marco Aur\u00e9lio Bellizze, Terceira Turma, julgado em 29\/11\/2022, DJe 1\u00ba\/12\/2022).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-4-resultado-final\"><a>2.2.4.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>A norma do art. 36, III, &#8220;b&#8221;, da Lei n. 8.112\/1990 n\u00e3o pode ser aplicada de maneira subsidi\u00e1ria aos membros do Minist\u00e9rio P\u00fablico da Uni\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-supervisao-de-investigacao-contra-detentor-de-prerrogativa-de-foro-no-ambito-de-inqueritos-civis-e-acoes-de-improbidade-administrativa-e-usurpacao-de-competencia-do-tribunal-de-justica\"><a>3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Supervis\u00e3o de investiga\u00e7\u00e3o contra detentor de prerrogativa de foro no \u00e2mbito de inqu\u00e9ritos civis e a\u00e7\u00f5es de improbidade administrativa e usurpa\u00e7\u00e3o de compet\u00eancia do Tribunal de Justi\u00e7a<\/a><\/h2>\n\n\n\n<p><a><strong>PROCESSO SOB SEGREDO DE JUSTI\u00c7A<\/strong><\/a><\/p>\n\n\n\n<p>N\u00e3o h\u00e1 usurpa\u00e7\u00e3o de compet\u00eancia do Tribunal de Justi\u00e7a local quanto \u00e0 supervis\u00e3o de investiga\u00e7\u00e3o contra detentor de prerrogativa de foro no \u00e2mbito de inqu\u00e9ritos civis e a\u00e7\u00f5es de improbidade administrativa.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Ribeiro Dantas, Quinta Turma, por unanimidade, julgado em 24\/4\/2023, DJe 27\/4\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-1-situacao-fatica\"><a>3.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Membro do MP instaurou Procedimento Preparat\u00f3rio para apurar irregularidades configuradoras de improbidade administrativa supostamente cometidas pelo prefeito local. Expirado o prazo de vig\u00eancia do referido procedimento, este foi convertido em Inqu\u00e9rito Civil P\u00fablico.<\/p>\n\n\n\n<p>O prefeito acusado afirma que a den\u00fancia que culminou em sua condena\u00e7\u00e3o pela pr\u00e1tica do delito previsto no art. 89 da Lei n. 8.666\/1993 foi oferecida sem pr\u00e9via instaura\u00e7\u00e3o de inqu\u00e9rito policial (IP) ou de procedimento investigat\u00f3rio criminal (PIC), tendo sido instru\u00edda com a c\u00f3pia do referido Inqu\u00e9rito Civil P\u00fablico, em uma manobra processual para se usurpar a compet\u00eancia do Tribunal de Justi\u00e7a local na supervis\u00e3o das investiga\u00e7\u00f5es, em viola\u00e7\u00e3o ao princ\u00edpio do juiz natural.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-2-analise-estrategica\"><a>3.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-1-houve-usurpacao-da-competencia-do-tj\"><a>3.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Houve usurpa\u00e7\u00e3o da compet\u00eancia do TJ?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nooops!!!!!<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia consiste em definir se houve usurpa\u00e7\u00e3o de compet\u00eancia do Tribunal de Justi\u00e7a local ao n\u00e3o determinar a instaura\u00e7\u00e3o de inqu\u00e9rito policial (ou procedimento de investiga\u00e7\u00e3o criminal) em investiga\u00e7\u00e3o para apurar suposto ato de improbidade administrativa praticado por prefeito &#8211; detentor de prerrogativa de foro.<\/p>\n\n\n\n<p>No caso, o representante ministerial instaurou Procedimento Preparat\u00f3rio para apurar irregularidades configuradoras de improbidade administrativa. Expirado o prazo de vig\u00eancia do referido procedimento, este foi convertido em Inqu\u00e9rito Civil P\u00fablico.<\/p>\n\n\n\n<p>No entanto, o acusado reafirma que a den\u00fancia que culminou em sua condena\u00e7\u00e3o pela pr\u00e1tica do delito previsto no art. 89 da Lei n. 8.666\/1993 foi oferecida sem pr\u00e9via instaura\u00e7\u00e3o de inqu\u00e9rito policial (IP) ou de procedimento investigat\u00f3rio criminal (PIC), tendo sido instru\u00edda com a c\u00f3pia do referido Inqu\u00e9rito Civil P\u00fablico, em uma manobra processual para se usurpar a compet\u00eancia do Tribunal de Justi\u00e7a local na supervis\u00e3o das investiga\u00e7\u00f5es, em viola\u00e7\u00e3o ao princ\u00edpio do juiz natural.<\/p>\n\n\n\n<p>De fato, a inicial acusat\u00f3ria, que deu origem \u00e0 A\u00e7\u00e3o Penal, n\u00e3o foi precedida de pr\u00e9via instaura\u00e7\u00e3o de IP ou de PIC. Apoiou-se em elementos extra\u00eddos no Inqu\u00e9rito Civil P\u00fablico.<\/p>\n\n\n\n<p>Em que pese as raz\u00f5es do acusado, \u00e9 plenamente leg\u00edtimo &#8220;o oferecimento de den\u00fancia com esc\u00f3lio em inqu\u00e9rito civil p\u00fablico&#8221; (APn 527\/MT, relatora Ministra Eliana Calmon, Corte Especial, julgado em 6\/3\/2013, DJe de 17\/4\/2013), n\u00e3o sendo o inqu\u00e9rito policial ou o procedimento investigativo criminal pressuposto necess\u00e1rio \u00e0 propositura da a\u00e7\u00e3o penal.<\/p>\n\n\n\n<p>Portanto, <strong>embora o investigado exercesse cargo com foro privilegiado, n\u00e3o havia nenhum ato de investiga\u00e7\u00e3o criminal iniciado na origem, mas apenas o inqu\u00e9rito de natureza civil<\/strong>. N\u00e3o havendo que se falar, at\u00e9 aquele momento, em usurpa\u00e7\u00e3o da compet\u00eancia do Tribunal de Justi\u00e7a local quanto \u00e0 supervis\u00e3o da investiga\u00e7\u00e3o, uma vez que &#8220;n\u00e3o existe foro privilegiado por prerrogativa de fun\u00e7\u00e3o para o processamento e julgamento da a\u00e7\u00e3o civil p\u00fablica de improbidade administrativa&#8221; (AgRg na AIA 32\/AM, Rel. Ministro Jo\u00e3o Ot\u00e1vio de Noronha, Corte Especial, DJe 13\/5\/2016).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-2-resultado-final\"><a>3.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>N\u00e3o h\u00e1 usurpa\u00e7\u00e3o de compet\u00eancia do Tribunal de Justi\u00e7a local quanto \u00e0 supervis\u00e3o de investiga\u00e7\u00e3o contra detentor de prerrogativa de foro no \u00e2mbito de inqu\u00e9ritos civis e a\u00e7\u00f5es de improbidade administrativa.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-civil\"><a>DIREITO CIVIL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-im-possibilidade-do-reconhecimento-da-figura-do-consumidor-por-equiparacao-na-hipotese-de-danos-individuais-decorrentes-do-exercicio-de-atividade-de-exploracao-de-potencial-hidroenergetico-causadora-de-impacto-ambiental\"><a>4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (Im)Possibilidade do reconhecimento da figura do consumidor por equipara\u00e7\u00e3o na hip\u00f3tese de danos individuais decorrentes do exerc\u00edcio de atividade de explora\u00e7\u00e3o de potencial hidroenerg\u00e9tico causadora de impacto ambiental<\/a><\/h2>\n\n\n\n<p><a><strong>RECURSO ESPECIAL<\/strong><\/a><\/p>\n\n\n\n<p>\u00c9 poss\u00edvel o reconhecimento da figura do consumidor por equipara\u00e7\u00e3o na hip\u00f3tese de danos individuais decorrentes do exerc\u00edcio de atividade de explora\u00e7\u00e3o de potencial hidroenerg\u00e9tico causadora de impacto ambiental, em virtude da caracteriza\u00e7\u00e3o do acidente de consumo.<\/p>\n\n\n\n<p>REsp 2.018.386-BA, Rel. Ministra Nancy Andrighi, Segunda Se\u00e7\u00e3o, por unanimidade, julgado em 10\/5\/2023, DJe 12\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-1-situacao-fatica\"><a>4.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Crementina, pescadora, ajuizou a\u00e7\u00e3o de indeniza\u00e7\u00e3o por danos materiais e morais em face de Vetor Energias em virtude da ocorr\u00eancia de supostos danos causados em raz\u00e3o da instala\u00e7\u00e3o de Usina Hidrel\u00e9trica.<\/p>\n\n\n\n<p>Na a\u00e7\u00e3o, alegou que a atividade desenvolvida pelas sociedades empres\u00e1rias de produ\u00e7\u00e3o de energia el\u00e9trica, apresenta defeito que ultrapassa os limites do ato de explora\u00e7\u00e3o de potencial hidroel\u00e9trico a ponto de causar danos materiais e morais em raz\u00e3o do impacto causado no desenvolvimento da atividade pesqueira e de mariscagem.<\/p>\n\n\n\n<p>Ao julgar o tema, o Tribunal local entendeu pela n\u00e3o aplicabilidade do CDC e pela compet\u00eancia de uma das varas c\u00edveis do local, em vez de uma das varas de rela\u00e7\u00e3o de consumo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-2-analise-estrategica\"><a>4.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-1-questao-juridica\"><a>4.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo de Defesa do Consumidor:<\/p>\n\n\n\n<p>Art. 2\u00b0 Consumidor \u00e9 toda pessoa f\u00edsica ou jur\u00eddica que adquire ou utiliza produto ou servi\u00e7o como destinat\u00e1rio final,<\/p>\n\n\n\n<p>Par\u00e1grafo \u00fanico. Equipara-se a consumidor a coletividade de pessoas, ainda que indetermin\u00e1veis, que haja intervindo nas rela\u00e7\u00f5es de consumo.<\/p>\n\n\n\n<p>Art. 12. O fabricante, o produtor, o construtor, nacional ou estrangeiro, e o importador respondem, independentemente da exist\u00eancia de culpa, pela repara\u00e7\u00e3o dos danos causados aos consumidores por defeitos decorrentes de projeto, fabrica\u00e7\u00e3o, constru\u00e7\u00e3o, montagem, f\u00f3rmulas, manipula\u00e7\u00e3o, apresenta\u00e7\u00e3o ou acondicionamento de seus produtos, bem como por informa\u00e7\u00f5es insuficientes ou inadequadas sobre sua utiliza\u00e7\u00e3o e riscos.<\/p>\n\n\n\n<p>Art. 14. O fornecedor de servi\u00e7os responde, independentemente da exist\u00eancia de culpa, pela repara\u00e7\u00e3o dos danos causados aos consumidores por defeitos relativos \u00e0 presta\u00e7\u00e3o dos servi\u00e7os, bem como por informa\u00e7\u00f5es insuficientes ou inadequadas sobre sua frui\u00e7\u00e3o e riscos.<\/p>\n\n\n\n<p>Art. 17. Para os efeitos desta Se\u00e7\u00e3o, equiparam-se aos consumidores todas as v\u00edtimas do evento.<\/p>\n\n\n\n<p>CC\/2002:<\/p>\n\n\n\n<p>Art. 83. Consideram-se m\u00f3veis para os efeitos legais:<\/p>\n\n\n\n<p>I &#8211; as energias que tenham valor econ\u00f4mico;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-2-possivel-o-reconhecimento-da-figura-do-consumidor-por-equiparacao\"><a>4.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Poss\u00edvel o reconhecimento da figura do consumidor por equipara\u00e7\u00e3o?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeaph!!!!<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia consiste em definir o ju\u00edzo competente para processar e julgar a\u00e7\u00e3o de indeniza\u00e7\u00e3o por danos materiais e morais em virtude da ocorr\u00eancia de supostos danos decorrentes de atividade de explora\u00e7\u00e3o de complexo hidroel\u00e9trico, o que demanda que se verifique se as v\u00edtimas de supostos danos podem ser consideradas consumidores por equipara\u00e7\u00e3o (<em>bystander<\/em>).<\/p>\n\n\n\n<p>Na hip\u00f3tese, sustenta-se que a atividade desenvolvida pelas sociedades empres\u00e1rias de produ\u00e7\u00e3o de energia el\u00e9trica, apresenta defeito que ultrapassa os limites do ato de explora\u00e7\u00e3o de potencial hidroel\u00e9trico a ponto de causar danos materiais e morais em raz\u00e3o do impacto causado no desenvolvimento da atividade pesqueira e de mariscagem.<\/p>\n\n\n\n<p><strong>O conceito de consumidor est\u00e1 previsto no art. 2\u00ba do C\u00f3digo de Defesa do Consumidor (CDC), que o define como toda pessoa f\u00edsica ou jur\u00eddica que adquire ou utiliza produto ou servi\u00e7o como destinat\u00e1rio final<\/strong>.<\/p>\n\n\n\n<p>A legisla\u00e7\u00e3o consumerista, ao tratar da responsabilidade pelo fato do produto e do servi\u00e7o, ampliou o conceito para abranger todas as v\u00edtimas do evento danoso. Trata-se da figura do consumidor por equipara\u00e7\u00e3o (<em>bystander<\/em>), prevista no art. 17 do CDC.<\/p>\n\n\n\n<p>A equipara\u00e7\u00e3o, no entanto, aplica-se apenas nas hip\u00f3teses de fato do produto ou servi\u00e7o, nas quais, segundo a doutrina, &#8220;a utiliza\u00e7\u00e3o do produto ou servi\u00e7o \u00e9 capaz de gerar riscos \u00e0 seguran\u00e7a do consumidor ou de terceiros, podendo ocasionar um evento danoso, denominado de &#8216;acidente de consumo'&#8221;.<\/p>\n\n\n\n<p>Como j\u00e1 entendeu o STJ, &#8220;o defeito (arts. 12 a 17 do CDC) est\u00e1 vinculado a um acidente de consumo, um defeito exterior que ultrapassa o objeto e provoca les\u00f5es, gerando risco \u00e0 seguran\u00e7a f\u00edsica e ps\u00edquica do consumidor. O v\u00edcio (arts. 18 a 25 do CDC), por sua vez, causa preju\u00edzo exclusivamente patrimonial e \u00e9 intr\u00ednseco ao produto ou servi\u00e7o, tornando-o impr\u00f3prio para o fim que se destina ou diminuindo-lhe as fun\u00e7\u00f5es, mas sem colocar em risco a sa\u00fade ou seguran\u00e7a do consumidor&#8221; (AgRg no REsp 1.000.329\/SC, Quarta Turma, julgado em 10\/8\/2010, DJe 19\/8\/2010).<\/p>\n\n\n\n<p>No \u00e2mbito jurisprudencial, <strong>o STJ admite, nos termos do art. 17 do CDC, a exist\u00eancia da figura do consumidor por equipara\u00e7\u00e3o nas hip\u00f3teses de danos ambientais<\/strong>.<\/p>\n\n\n\n<p>Desse modo, na hip\u00f3tese de danos individuais decorrentes do exerc\u00edcio de atividade empresarial destinada \u00e0 fabrica\u00e7\u00e3o de produtos ou presta\u00e7\u00e3o de servi\u00e7os, \u00e9 poss\u00edvel, em virtude da caracteriza\u00e7\u00e3o do acidente de consumo, o reconhecimento da figura do consumidor por equipara\u00e7\u00e3o, o que atrai a incid\u00eancia das disposi\u00e7\u00f5es do C\u00f3digo de Defesa do Consumidor.<\/p>\n\n\n\n<p>Observa-se, n\u00e3o obstante, que os danos alegados decorrem do processo de produ\u00e7\u00e3o de energia el\u00e9trica como um todo, isto \u00e9, da pr\u00f3pria atividade desenvolvida, o que, a teor dos arts. 12 e 14 do CDC, \u00e9 suficiente para atrair a disciplina normativa da responsabilidade por fato do produto ou do servi\u00e7o e a caracteriza\u00e7\u00e3o da figura do consumidor por equipara\u00e7\u00e3o.<\/p>\n\n\n\n<p>N\u00e3o se pode olvidar, nesse contexto, que a atividade empresarial desenvolvida, na esp\u00e9cie, destina-se \u00e0 produ\u00e7\u00e3o de um verdadeiro produto, pois, nos termos do inciso I do art. 83 do CC\/2002, as energias que tenham valor econ\u00f4mico possuem natureza jur\u00eddica de bem m\u00f3vel.<\/p>\n\n\n\n<p>Al\u00e9m disso, pouco ou nada importa perquirir se a energia produzida \u00e9 utilizada pelas pr\u00f3prias r\u00e9s, se \u00e9 distribu\u00edda ao cidad\u00e3o como usu\u00e1rio final ou se \u00e9 entregue a alguma entidade da Administra\u00e7\u00e3o P\u00fablica para posterior distribui\u00e7\u00e3o. Isso porque, em qualquer das hip\u00f3teses, observa-se que as recorridas exploram o complexo hidroel\u00e9trico em prol da atividade empresarial por elas desenvolvida.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-3-resultado-final\"><a>4.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>\u00c9 poss\u00edvel o reconhecimento da figura do consumidor por equipara\u00e7\u00e3o na hip\u00f3tese de danos individuais decorrentes do exerc\u00edcio de atividade de explora\u00e7\u00e3o de potencial hidroenerg\u00e9tico causadora de impacto ambiental, em virtude da caracteriza\u00e7\u00e3o do acidente de consumo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-direito-de-tapagem-e-direito-ao-compartilhamento-de-gastos-decorrentes-da-construcao-de-muro-comum-aos-proprietarios-lindeiros\"><a>5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Direito de tapagem e direito ao compartilhamento de gastos decorrentes da constru\u00e7\u00e3o de muro comum aos propriet\u00e1rios lindeiros<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>O direito de tapagem disposto do art. 1.297 do C\u00f3digo Civil prev\u00ea o direito ao compartilhamento de gastos decorrentes da constru\u00e7\u00e3o de muro comum aos propriet\u00e1rios lindeiros.<\/p>\n\n\n\n<p>REsp 2.035.008-SP, Rel. Ministra Maria Isabel Gallotti, Quarta Turma, por unanimidade, julgado em 2\/5\/2023, DJe 5\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-1-situacao-fatica\"><a>5.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Virso adquiriu uma casa ao lado do im\u00f3vel de Nirso. Ocorre que a divisa dos im\u00f3veis era demarcada por uma simples cerca. Virso, rapaz que prefere uma privacidade maior, resolveu construir um muro na divis\u00f3ria dos im\u00f3veis, ato contra o qual n\u00e3o se op\u00f4s Nirso.<\/p>\n\n\n\n<p>Constru\u00eddo o muro, Virso resolveu cobrar 50% do valor dos gastos de seu vizinho. Este n\u00e3o concordou com o pagamento, pois nada fora acordado previamente. Inconformado, Virso ajuizou a\u00e7\u00e3o de cobran\u00e7a, mas o TJ local entendeu que s\u00f3 caberia o pagamento se comprovada a anu\u00eancia anterior.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-2-analise-estrategica\"><a>5.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-1-questao-juridica\"><a>5.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>CC:<\/p>\n\n\n\n<p>Art. 1.297. O propriet\u00e1rio tem direito a cercar, murar, valar ou tapar de qualquer modo o seu pr\u00e9dio, urbano ou rural, e pode constranger o seu confinante a proceder com ele \u00e0 demarca\u00e7\u00e3o entre os dois pr\u00e9dios, a aviventar rumos apagados e a renovar marcos destru\u00eddos ou arruinados, repartindo-se proporcionalmente entre os interessados as respectivas despesas.<\/p>\n\n\n\n<p>\u00a7 1 o Os intervalos, muros, cercas e os tapumes divis\u00f3rios, tais como sebes vivas, cercas de arame ou de madeira, valas ou banquetas, presumem-se, at\u00e9 prova em contr\u00e1rio, pertencer a ambos os propriet\u00e1rios confinantes, sendo estes obrigados, de conformidade com os costumes da localidade, a concorrer, em partes iguais, para as despesas de sua constru\u00e7\u00e3o e conserva\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-2-gastos-devem-ser-compartilhados\"><a>5.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Gastos devem ser compartilhados?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeaph!!!!<\/strong><\/p>\n\n\n\n<p>Cinge-se a controv\u00e9rsia a determinar se \u00e9 necess\u00e1rio o pr\u00e9vio acordo de vontades para que o propriet\u00e1rio de im\u00f3vel confinante possa ser compelido a concorrer para as despesas de constru\u00e7\u00e3o de tapumes divis\u00f3rios.<\/p>\n\n\n\n<p>Se o tapume \u00e9 feito na divisa, a presun\u00e7\u00e3o legal \u00e9 de que \u00e9 comum e n\u00e3o particular (CC, art. 1.297, \u00a7 1\u00ba). O interesse do que fez o tapume nada tem que ver com a inten\u00e7\u00e3o do confrontante de adquirir-lhe ou n\u00e3o a mea\u00e7\u00e3o. <strong>O seu interesse \u00e9 o de receber a metade das despesas a que o seu confrontante est\u00e1 obrigado por expressa disposi\u00e7\u00e3o de lei<\/strong>. Aceitar a tese de que, construindo o tapume sem pr\u00e9vio acordo ou sem senten\u00e7a, a parte estaria renunciando ao direito ao ressarcimento que a lei lhe assegura, equivale a presumir uma doa\u00e7\u00e3o de seu direito, ao vizinho. Mas doa\u00e7\u00e3o \u00e9 neg\u00f3cio SOLENTE, que n\u00e3o se pode presumir, por isso mesmo.<\/p>\n\n\n\n<p>\u00c9 claro que, tomando a iniciativa unilateral de erguer o muro ou a cerca, correr\u00e1 a parte o risco de ver sua obra impugnada pelo vizinho, quanto a custo e natureza, na contesta\u00e7\u00e3o do feito, ao ensejo em que postular a indeniza\u00e7\u00e3o pela metade dos gastos. Mas, <strong>se a prova acabar por demonstrar que o tapume foi normalmente feito segundo as posturas municipais ou os costumes do lugar, e por custo razo\u00e1vel, s\u00f3 mesmo por um capricho ou um formalismo injustific\u00e1vel ser\u00e1 poss\u00edvel negar ao autor o reembolso da metade das despesas feitas<\/strong>. De acordo com a doutrina, \u00e9 o condom\u00ednio for\u00e7ado estabelecido sobre as obras de confins de pr\u00e9dios cont\u00edguos, o que justifica a obriga\u00e7\u00e3o dos propriet\u00e1rios em contribuir com as despesas do tapume comum.<\/p>\n\n\n\n<p>Adotar-se o entendimento diverso significaria tornar letra morta o dispositivo citado. <strong>O dever jur\u00eddico s\u00f3 existiria caso houvesse o acordo e, existente este, seria o bastante, sup\u00e9rflua a norma legal<\/strong>. O anterior concerto servir\u00e1 para que se tenha como indiscut\u00edvel que as obras s\u00e3o necess\u00e1rias e para fazer incontroverso o respectivo valor. Se o confinante, entretanto, se op\u00f5e \u00e0 realiza\u00e7\u00e3o de trabalhos de conserva\u00e7\u00e3o, efetivamente reclamados, n\u00e3o ser\u00e1 s\u00f3 por isso que ficar\u00e1 livre de concorrer para as despesas. N\u00e3o se ter\u00e1, por\u00e9m, como indispens\u00e1vel, deixando ao alvedrio da parte concorrer ou n\u00e3o para a constru\u00e7\u00e3o e conserva\u00e7\u00e3o das cercas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-3-resultado-final\"><a>5.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>O direito de tapagem disposto do art. 1.297 do C\u00f3digo Civil prev\u00ea o direito ao compartilhamento de gastos decorrentes da constru\u00e7\u00e3o de muro comum aos propriet\u00e1rios lindeiros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-existencia-de-clausula-contrato-de-seguro-relacionado-a-cedula-de-credito-rural-e-perda-dos-atributos-de-exequibilidade-proprios-do-titulo\"><a>6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Exist\u00eancia de cl\u00e1usula\/contrato de seguro relacionado \u00e0 c\u00e9dula de cr\u00e9dito rural e perda dos atributos de exequibilidade pr\u00f3prios do t\u00edtulo<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO INTERNO NO AGRAVO EM RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>A exist\u00eancia de cl\u00e1usula\/contrato de seguro relacionado \u00e0 c\u00e9dula de cr\u00e9dito rural n\u00e3o retira os atributos de exequibilidade pr\u00f3prios do t\u00edtulo.<\/p>\n\n\n\n<p>AgInt no AREsp 2.144.537-GO, Rel. Ministro Marco Buzzi, Quarta Turma, por unanimidade, julgado em 17\/4\/2023, DJe 20\/4\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-1-situacao-fatica\"><a>6.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Banco Brasa firmou c\u00e9dula rural pignorat\u00edcia com Creosvaldo. No t\u00edtulo, constava que, ocorrendo a inadimpl\u00eancia da parte segurada, o Banco poderia acionar o seguro e pleitear a liquida\u00e7\u00e3o do sinistro a fim de receber a indeniza\u00e7\u00e3o e liquidar o d\u00e9bito, ainda que parcialmente.<\/p>\n\n\n\n<p>Creosvaldo, mais liso que jundi\u00e1 ensaboado, sustenta que a institui\u00e7\u00e3o financeira n\u00e3o pode vir cobrar dele em caso de inadimplemento, j\u00e1 que tal pretens\u00e3o estaria condicionada \u00e0 liquida\u00e7\u00e3o do sinistro <em>junto \u00e0 seguradora<\/em>, mediante a apura\u00e7\u00e3o da ocorr\u00eancia ou n\u00e3o do evento coberto pelas cl\u00e1usulas contratuais. Em suma, de acordo com a defesa de Creosvaldo, comprovada a exist\u00eancia do seguro agr\u00edcola com a comunica\u00e7\u00e3o do sinistro, n\u00e3o haveria a exigibilidade do t\u00edtulo enquanto n\u00e3o efetivada a sua liquida\u00e7\u00e3o pela institui\u00e7\u00e3o financeira junto a seguradora.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-2-analise-estrategica\"><a>6.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-1-questao-juridica\"><a>6.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Decreto-lei n. 167\/67:<\/p>\n\n\n\n<p>Art. 10. A c\u00e9dula de cr\u00e9dito rural \u00e9 t\u00edtulo civil, l\u00edquido e certo, transfer\u00edvel e de livre negocia\u00e7\u00e3o, exig\u00edvel pelo seu valor ou pelo valor de seu endosso, al\u00e9m dos juros, da comiss\u00e3o de fiscaliza\u00e7\u00e3o, se houver, e das demais despesas feitas pelo credor para a seguran\u00e7a, a regularidade e a realiza\u00e7\u00e3o de seu direito credit\u00f3rio.<\/p>\n\n\n\n<p>C\u00f3digo de Processo Civil:<\/p>\n\n\n\n<p>&nbsp;<a><\/a>Art. 125. \u00c9 admiss\u00edvel a denuncia\u00e7\u00e3o da lide, promovida por qualquer das partes:<\/p>\n\n\n\n<p><a><\/a>II &#8211; \u00e0quele que estiver obrigado, por lei ou pelo contrato, a indenizar, em a\u00e7\u00e3o regressiva, o preju\u00edzo de quem for vencido no processo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-2-o-seguro-retira-a-exequibilidade-da-cedula\"><a>6.2.2.&nbsp;&nbsp;&nbsp;&nbsp; O seguro retira a exequibilidade da c\u00e9dula<\/a>?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>De jeito nenhum!!!!<\/strong><\/p>\n\n\n\n<p>Discute-se a respeito da inexigibilidade de c\u00e9dula de cr\u00e9dito rural, tendo em vista a necessidade de sua liquida\u00e7\u00e3o, uma vez que pelo menos parte do seu valor seria coberto por seguro agr\u00edcola contratado pelo devedor, estando a pretens\u00e3o &#8220;condicionada \u00e0 liquida\u00e7\u00e3o do sinistro junto \u00e0 seguradora, mediante a apura\u00e7\u00e3o da ocorr\u00eancia ou n\u00e3o do evento coberto pelas cl\u00e1usulas contratuais, quando ent\u00e3o poder\u00e1 exigir, total ou parcialmente o seu cr\u00e9dito&#8221;.<\/p>\n\n\n\n<p>O entendimento pac\u00edfico do STJ \u00e9 na linha de <strong>ser a c\u00e9dula de cr\u00e9dito rural t\u00edtulo l\u00edquido, certo e exig\u00edvel por for\u00e7a do art. 10 do Decreto-lei n. 167\/67<\/strong>. O fato de existir contrato de seguro atrelado ao t\u00edtulo n\u00e3o interfere na sua exequibilidade, e decis\u00e3o contr\u00e1ria a este entendimento pode incorrer em&nbsp;<em>error in judicando<\/em><em>.<\/em><\/p>\n\n\n\n<p>No caso, o credor foi apenas o estipulante do referido ajuste, sendo-lhe conferida a FACULDADE &#8211; <strong>n\u00e3o obriga\u00e7\u00e3o<\/strong> &#8211; de empreender todos os atos relacionados \u00e0 liquida\u00e7\u00e3o do sinistro, caso assim lhe aprouvesse, mas n\u00e3o uma imposi\u00e7\u00e3o sem a qual a c\u00e9dula rural perderia suas caracter\u00edsticas de liquidez, certeza e exigibilidade.<\/p>\n\n\n\n<p>A exist\u00eancia do seguro autoriza, por parte do benefici\u00e1rio, a realiza\u00e7\u00e3o da denuncia\u00e7\u00e3o da lide (art. 125, II, do C\u00f3digo de Processo Civil), provid\u00eancia que poderia ter sido realizada pelo recorrido, por\u00e9m n\u00e3o existe a necessidade de pr\u00e9vio acionamento do seguro para posterior liquida\u00e7\u00e3o da c\u00e9dula rural.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-3-resultado-final\"><a>6.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>A exist\u00eancia de cl\u00e1usula\/contrato de seguro relacionado \u00e0 c\u00e9dula de cr\u00e9dito rural n\u00e3o retira os atributos de exequibilidade pr\u00f3prios do t\u00edtulo.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-civil\"><a>DIREITO PROCESSUAL CIVIL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-cabimento-da-liquidacao-do-titulo-executivo-judicial-coletivo-em-foro-aleatorio-sem-nenhuma-relacao-com-as-comarcas-de-domicilio-dos-beneficiarios\"><a>7.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cabimento da liquida\u00e7\u00e3o do t\u00edtulo executivo judicial coletivo em foro aleat\u00f3rio, sem nenhuma rela\u00e7\u00e3o com as comarcas de domic\u00edlio dos benefici\u00e1rios<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>N\u00e3o \u00e9 cab\u00edvel promover a liquida\u00e7\u00e3o do t\u00edtulo executivo judicial coletivo em foro aleat\u00f3rio, sem nenhuma rela\u00e7\u00e3o com as comarcas de domic\u00edlio dos benefici\u00e1rios, ainda que se trate do foro de domic\u00edlio do substituto processual extraordin\u00e1rio, sob pena de afronta ao princ\u00edpio do Juiz natural.<\/p>\n\n\n\n<p>REsp 1.866.440-AL, Rel. Ministro Marco Aur\u00e9lio Bellizze, Terceira Turma, por unanimidade, julgado em 9\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-1-situacao-fatica\"><a>7.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O Instituto dos Poupadores, associa\u00e7\u00e3o privada, promoveu, na comarca de Macei\u00f3, a liquida\u00e7\u00e3o do t\u00edtulo executivo judicial constitu\u00eddo em A\u00e7\u00e3o Civil P\u00fablica que tramitara perante Vara C\u00edvel de Bras\u00edlia, em que fora condenado o Banco do Brasil S.A. ao pagamento expurgos inflacion\u00e1rios decorrentes de plano econ\u00f4mico. O TJ local reconheceu a incompet\u00eancia do Ju\u00edzo de primeiro grau.<\/p>\n\n\n\n<p>Inconformada, a associa\u00e7\u00e3o interp\u00f4s recursos nos quais sustenta a compet\u00eancia da comarca de Macei\u00f3\/AL para processamento e julgamento da liquida\u00e7\u00e3o de senten\u00e7a coletiva, pois seria o domic\u00edlio do substituto processual dos poupadores e, tamb\u00e9m, da institui\u00e7\u00e3o financeira devedora, ainda que os substitu\u00eddos residam em outra unidade da federa\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-2-analise-estrategica\"><a>7.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-1-questao-juridica\"><a>7.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil:<\/p>\n\n\n\n<p>Art. 711. Aplicam-se ao regulador de avarias os arts. 156 a 158 , no que couber.<\/p>\n\n\n\n<p>Art. 781. A execu\u00e7\u00e3o fundada em t\u00edtulo extrajudicial ser\u00e1 processada perante o ju\u00edzo competente, observando-se o seguinte:<\/p>\n\n\n\n<p><a><\/a>I &#8211; a execu\u00e7\u00e3o poder\u00e1 ser proposta no foro de domic\u00edlio do executado, de elei\u00e7\u00e3o constante do t\u00edtulo ou, ainda, de situa\u00e7\u00e3o dos bens a ela sujeitos;<\/p>\n\n\n\n<p><a><\/a>II &#8211; tendo mais de um domic\u00edlio, o executado poder\u00e1 ser demandado no foro de qualquer deles;<\/p>\n\n\n\n<p><a><\/a>III &#8211; sendo incerto ou desconhecido o domic\u00edlio do executado, a execu\u00e7\u00e3o poder\u00e1 ser proposta no lugar onde for encontrado ou no foro de domic\u00edlio do exequente;<\/p>\n\n\n\n<p><a><\/a>IV &#8211; havendo mais de um devedor, com diferentes domic\u00edlios, a execu\u00e7\u00e3o ser\u00e1 proposta no foro de qualquer deles, \u00e0 escolha do exequente;<\/p>\n\n\n\n<p><a><\/a>V &#8211; a execu\u00e7\u00e3o poder\u00e1 ser proposta no foro do lugar em que se praticou o ato ou em que ocorreu o fato que deu origem ao t\u00edtulo, mesmo que nele n\u00e3o mais resida o executado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-2-cabe-a-liquidacao-em-foro-aleatorio\"><a>7.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Cabe a liquida\u00e7\u00e3o em foro aleat\u00f3rio?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Obviamente que N\u00c3O!!!<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia est\u00e1 em definir se o foro de domic\u00edlio do substituto processual \u00e9 competente para processar e julgar a liquida\u00e7\u00e3o de senten\u00e7a coletiva.<\/p>\n\n\n\n<p>Depreende-se dos autos que determinada associa\u00e7\u00e3o privada promoveu, na comarca de Macei\u00f3, a liquida\u00e7\u00e3o do t\u00edtulo executivo judicial constitu\u00eddo em A\u00e7\u00e3o Civil P\u00fablica que tramitara perante a 12\u00aa Vara C\u00edvel de Bras\u00edlia, em que fora condenado o Banco do Brasil S.A. aos expurgos inflacion\u00e1rios de 42,72% decorrentes de plano econ\u00f4mico. A Primeira C\u00e2mara C\u00edvel do Tribunal de Justi\u00e7a de Alagoas reconheceu a incompet\u00eancia do Ju\u00edzo de primeiro grau.<\/p>\n\n\n\n<p>O voto condutor do aresto&nbsp;<em>a quo<\/em>&nbsp;destacou que nenhum dos benefici\u00e1rios representados pelo instituto agravado no processo em tr\u00e2mite na primeira inst\u00e2ncia \u00e9 domiciliado na cidade de Macei\u00f3 ou qualquer outra cidade do Estado de Alagoas, sendo incontroverso o fato de que todos eles possuem domic\u00edlio no Estado de S\u00e3o Paulo.<\/p>\n\n\n\n<p>A despeito de se oportunizar ao consumidor que promova a liquida\u00e7\u00e3o no foro de seu domic\u00edlio ou no foro em que o t\u00edtulo executivo judicial foi proferido, n\u00e3o caberia, de outro lado, a elei\u00e7\u00e3o de uma comarca aleat\u00f3ria, sem nenhuma justificativa plaus\u00edvel.<\/p>\n\n\n\n<p>Quanto ao tema, importante destacar que <strong>a Segunda Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a, em julgamento de recurso especial repetitivo, que versava sobre o cumprimento individual da senten\u00e7a proferida no julgamento da A\u00e7\u00e3o Civil P\u00fablica pela 12\u00aa Vara C\u00edvel de Bras\u00edlia\/DF, possibilitou o ajuizamento do cumprimento de senten\u00e7a tanto no Distrito Federal quanto no domic\u00edlio dos benefici\u00e1rios da referida decis\u00e3o coletiva<\/strong>.<\/p>\n\n\n\n<p>Portanto, o entendimento prevalente no STJ \u00e9 de que a compet\u00eancia poder\u00e1 ser do foro em que prolatada a decis\u00e3o da a\u00e7\u00e3o civil p\u00fablica ou do domic\u00edlio dos benefici\u00e1rios ou seus sucessores, e n\u00e3o do local de domic\u00edlio de legitimado extraordin\u00e1rio.<\/p>\n\n\n\n<p>A compet\u00eancia da Comarca de Macei\u00f3 n\u00e3o pode ser amparada nos arts. 46, 53, III, b, 516, par\u00e1grafo \u00fanico, 711 e 781 do C\u00f3digo de Processo Civil, ao argumento de que o banco tamb\u00e9m teria domic\u00edlio naquela Comarca.<\/p>\n\n\n\n<p>Isso porque, conforme exposto, <strong>a compet\u00eancia territorial para processar e julgar a execu\u00e7\u00e3o coletiva est\u00e1 subordinada \u00e0 regra legal espec\u00edfica, n\u00e3o sendo aplic\u00e1veis as regras gerais do C\u00f3digo de Processo Civil de 2015, haja vista que a fixa\u00e7\u00e3o da compet\u00eancia territorial em fun\u00e7\u00e3o de um dos domic\u00edlios do r\u00e9u dever\u00e1 ser observada<\/strong> somente quando a ag\u00eancia ou sucursal esteja diretamente relacionada com o dano, o que n\u00e3o se observa na hip\u00f3tese.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-3-resultado-final\"><a>7.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>N\u00e3o \u00e9 cab\u00edvel promover a liquida\u00e7\u00e3o do t\u00edtulo executivo judicial coletivo em foro aleat\u00f3rio, sem nenhuma rela\u00e7\u00e3o com as comarcas de domic\u00edlio dos benefici\u00e1rios, ainda que se trate do foro de domic\u00edlio do substituto processual extraordin\u00e1rio, sob pena de afronta ao princ\u00edpio do Juiz natural.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-conhecimento-tecnico-de-juiz-acerca-do-mercado-imobiliario-e-necessidade-de-realizacao-de-pericia-tecnica\"><a>8.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Conhecimento t\u00e9cnico de juiz acerca do mercado imobili\u00e1rio e necessidade de realiza\u00e7\u00e3o de per\u00edcia t\u00e9cnica<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>O conhecimento t\u00e9cnico ou cient\u00edfico de juiz sobre determinado mercado imobili\u00e1rio n\u00e3o pode ser equiparado \u00e0s regras de experi\u00eancia comum previstas no art. 375 do C\u00f3digo de Processo Civil, sendo indispens\u00e1vel a realiza\u00e7\u00e3o de per\u00edcia para avaliar bem im\u00f3vel objeto de penhora.<\/p>\n\n\n\n<p>REsp 1.786.046-RJ, Rel. Ministro Moura Ribeiro, Terceira Turma, por unanimidade, julgado em 9\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-1-situacao-fatica\"><a>8.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>RDR ajuizou a\u00e7\u00e3o de execu\u00e7\u00e3o em face de Associa\u00e7\u00e3o \u00darsula. No curso da execu\u00e7\u00e3o, foi penhorado im\u00f3vel avaliado pelo perito em certo valor, cujo laudo foi homologado pelo juiz da causa. A associa\u00e7\u00e3o interp\u00f4s recurso alegando que o im\u00f3vel valeria no m\u00ednimo tr\u00eas vezes mais, inclusive tendo juntado laudos de penhora realizados na Justi\u00e7a do Trabalho neste valor. O TJ local houve por bem majorar o valor da avalia\u00e7\u00e3o em 50%, invocando para tanto o art. 375 do CPC, que autoriza o juiz a valer-se das regras da experi\u00eancia comum para julgar o feito.<\/p>\n\n\n\n<p>Inconformada, \u00darsula interp\u00f4s recurso alegando que o valor do bem deveria ser necessariamente fixado por nova per\u00edcia, n\u00e3o sendo l\u00edcito ao juiz valer-se das regras da experi\u00eancia para essa finalidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-2-analise-estrategica\"><a>8.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-1-questao-juridica\"><a>8.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil:<\/p>\n\n\n\n<p>Art. 375. O juiz aplicar\u00e1 as regras de experi\u00eancia comum subministradas pela observa\u00e7\u00e3o do que ordinariamente acontece e, ainda, as regras de experi\u00eancia t\u00e9cnica, ressalvado, quanto a estas, o exame pericial.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-2-deve-ser-realizada-nova-pericia\"><a>8.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Deve ser realizada nova per\u00edcia?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Com certeza!!!!<\/strong><\/p>\n\n\n\n<p>Discute-se nos autos se o im\u00f3vel penhorado para pagamento da d\u00edvida deve ser avaliado necessariamente por per\u00edcia ou se, ao contr\u00e1rio, pode seu valor ser fixado pelo pr\u00f3prio julgador com base nas m\u00e1ximas da experi\u00eancia de que trata o art. 375 do C\u00f3digo de Processo Civil.<\/p>\n\n\n\n<p><strong>As regras (ou m\u00e1ximas) da experi\u00eancia designam um conjunto de ju\u00edzos que podem ser formulados pelo homem m\u00e9dio a partir da observa\u00e7\u00e3o do que normalmente acontece<\/strong>. Re\u00fanem proposi\u00e7\u00f5es muito variadas, que v\u00e3o desde conhecimentos cient\u00edficos consolidados como o de que corpos met\u00e1licos dilatam no calor at\u00e9 conven\u00e7\u00f5es mais ou menos generalizadas, como a de que as praias s\u00e3o mais frequentadas aos finais de semana.<\/p>\n\n\n\n<p>Muito embora constituam um conhecimento pr\u00f3prio do juiz, n\u00e3o se confundem com o conhecimento pessoal que ele tem a respeito de algum fato concreto, em rela\u00e7\u00e3o ao qual, exige-se, de qualquer forma, a produ\u00e7\u00e3o de prova espec\u00edfica, sob o crivo do contradit\u00f3rio.<\/p>\n\n\n\n<p>Conquanto <strong>se possa admitir que o julgador, por conhecer o mercado imobili\u00e1rio de determinada regi\u00e3o e tamb\u00e9m o im\u00f3vel penhorado, pudesse saber o seu real valor, n\u00e3o h\u00e1 como afirmar que essa seja uma informa\u00e7\u00e3o de conhecimento p\u00fablico<\/strong>.<\/p>\n\n\n\n<p>Imposs\u00edvel sustentar, nesses termos, que bem im\u00f3vel possa ser avaliado sem produ\u00e7\u00e3o de prova pericial, pelo pr\u00f3prio julgador, com base no art. 375 do CPC.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-3-resultado-final\"><a>8.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>O conhecimento t\u00e9cnico ou cient\u00edfico de juiz sobre determinado mercado imobili\u00e1rio n\u00e3o pode ser equiparado \u00e0s regras de experi\u00eancia comum previstas no art. 375 do C\u00f3digo de Processo Civil, sendo indispens\u00e1vel a realiza\u00e7\u00e3o de per\u00edcia para avaliar bem im\u00f3vel objeto de penhora.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-9-competencia-para-julgamento-de-acao-de-indenizacao-por-danos-morais-decorrente-de-ofensas-proferidas-em-rede-social\"><a>9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Compet\u00eancia para julgamento de a\u00e7\u00e3o de indeniza\u00e7\u00e3o por danos morais decorrente de ofensas proferidas em rede social<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>A compet\u00eancia para julgamento de a\u00e7\u00e3o de indeniza\u00e7\u00e3o por danos morais, decorrente de ofensas proferidas em rede social, \u00e9 do foro do domic\u00edlio da v\u00edtima, em raz\u00e3o da ampla divulga\u00e7\u00e3o do ato il\u00edcito.<\/p>\n\n\n\n<p>REsp 2.032.427-SP, Rel. Ministro Antonio Carlos Ferreira, Quarta Turma, por unanimidade, julgado em 27\/4\/2023, DJe 4\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-1-situacao-fatica\"><a>9.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creosvaldo ofendeu Crementina em uma rede social. Inconformada, Crementina ajuizou a\u00e7\u00e3o por meio da qual pretendia a condena\u00e7\u00e3o de Creosvaldo ao pagamento de danos morais. A a\u00e7\u00e3o foi ajuizada no foro do domic\u00edlio de Crementina, mas o ju\u00edzo local entendeu que a compet\u00eancia seguiria a regra geral do art. 46 do CPC, que prev\u00ea que as a\u00e7\u00f5es devem ser propostas no foro do domic\u00edlio do r\u00e9u.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-2-analise-estrategica\"><a>9.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-1-questao-juridica\"><a>9.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo de Processo Civil:<\/p>\n\n\n\n<p>Art. 46. A a\u00e7\u00e3o fundada em direito pessoal ou em direito real sobre bens m\u00f3veis ser\u00e1 proposta, em regra, no foro de domic\u00edlio do r\u00e9u.<\/p>\n\n\n\n<p>Art. 53. \u00c9 competente o foro:<\/p>\n\n\n\n<p>IV &#8211; do lugar do ato ou fato para a a\u00e7\u00e3o:<\/p>\n\n\n\n<p><a><\/a>a) de repara\u00e7\u00e3o de dano;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-2-a-quem-compete-julgar\"><a>9.2.2.&nbsp;&nbsp;&nbsp;&nbsp; A quem compete julgar?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Ju\u00edzo do FORO DO DOM\u00cdCILIO DA V\u00cdTIMA!!!<\/strong><\/p>\n\n\n\n<p>O Tribunal de origem consignou que a\u00e7\u00f5es fundadas em direito pessoal devem ser propostas no domic\u00edlio do r\u00e9u, ponderando que o il\u00edcito praticado pela internet n\u00e3o constaria do rol das exce\u00e7\u00f5es \u00e0 regra da compet\u00eancia (art. 46 do C\u00f3digo de Processo Civil).<\/p>\n\n\n\n<p>Contudo, o STJ firmou o entendimento de que, havendo divulga\u00e7\u00e3o de ofensas por redes sociais, a compet\u00eancia para julgamento da a\u00e7\u00e3o \u00e9 do foro do domic\u00edlio da v\u00edtima, em raz\u00e3o da ampla divulga\u00e7\u00e3o do ato il\u00edcito. Nesse sentido: (REsp n. 1.347.097\/SE, Relator Ministro Paulo de Tarso Sanseverino, Terceira Turma, julgado em 3\/4\/2014, DJe de 10\/4\/2014 e AgRg no Ag 808.075\/DF. Relator Ministro Fernando Gon\u00e7alves, Quarta Turma, DJe 17\/12\/2007).<\/p>\n\n\n\n<p>Da mesma forma, no julgamento do Conflito de Compet\u00eancia n. 154.928\/SP, decidiu-se que &#8220;<strong>a compet\u00eancia para apreciar as demandas que envolvam danos morais por ofensas proferidas na internet \u00e9 o local em que reside e trabalha a pessoa prejudicada, local de maior repercuss\u00e3o das supostas ofensas<\/strong>&#8220;.<\/p>\n\n\n\n<p>Apesar de os precedentes citados terem sido proferidos sob a \u00e9gide do C\u00f3digo de Processo Civil de 1973 (art. 100, V, &#8220;a&#8221;), o art. 53, IV, &#8220;a&#8221;, do atual C\u00f3digo reproduziu id\u00eantica norma processual.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-3-resultado-final\"><a>9.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>A compet\u00eancia para julgamento de a\u00e7\u00e3o de indeniza\u00e7\u00e3o por danos morais, decorrente de ofensas proferidas em rede social, \u00e9 do foro do domic\u00edlio da v\u00edtima, em raz\u00e3o da ampla divulga\u00e7\u00e3o do ato il\u00edcito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-10-via-processual-adequada-para-a-retomada-pelo-proprietario-da-posse-direta-de-imovel-locado\"><a>10.&nbsp; Via processual adequada para a retomada, pelo propriet\u00e1rio, da posse direta de im\u00f3vel locado<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>A via processual adequada para a retomada, pelo propriet\u00e1rio, da posse direta de im\u00f3vel locado \u00e9 a a\u00e7\u00e3o de despejo, na forma do art. 5\u00ba da Lei n. 8.245\/1991, n\u00e3o servindo para esse prop\u00f3sito o ajuizamento de a\u00e7\u00e3o possess\u00f3ria.<\/p>\n\n\n\n<p>REsp 1.812.987-RJ, Rel. Ministro Antonio Carlos Ferreira, Quarta Turma, por unanimidade, julgado em 27\/4\/2023, DJe 4\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-1-situacao-fatica\"><a>10.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creiton ajuizou a\u00e7\u00e3o de reintegra\u00e7\u00e3o de posse em face de Creosvalda, com o intuito de reaver im\u00f3vel de propriedade de seu falecido pai. Ocorre que o im\u00f3vel estava locado para Creosvalda.<\/p>\n\n\n\n<p>O tribunal local, apesar de afirmar que a a\u00e7\u00e3o correta seria a de despejo, manteve a senten\u00e7a por entender ser dever do magistrado apreciar o pedido do autor, em raz\u00e3o do princ\u00edpio da mihi factum, dabo tibi ius (d\u00e1-me os fatos que lhe darei o direito).<\/p>\n\n\n\n<p>Inconformada, Creosvalda interp\u00f4s recurso especial no qual sustenta que, n\u00e3o obstante o reconhecimento da exist\u00eancia da rela\u00e7\u00e3o locat\u00edcia que impunha a propositura de a\u00e7\u00e3o de despejo e n\u00e3o a a\u00e7\u00e3o de reintegra\u00e7\u00e3o de posse, deixou-se de considerar a inadequa\u00e7\u00e3o da via eleita.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-2-analise-estrategica\"><a>10.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-1-questao-juridica\"><a>10.2.1. Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 8.245\/1991:<\/p>\n\n\n\n<p>Art. 5\u00ba Seja qual for o fundamento do t\u00e9rmino da loca\u00e7\u00e3o, a a\u00e7\u00e3o do locador para reaver o im\u00f3vel \u00e9 a de despejo.<\/p>\n\n\n\n<p>CPC\/2015:<\/p>\n\n\n\n<p>Art. 554. A propositura de uma a\u00e7\u00e3o possess\u00f3ria em vez de outra n\u00e3o obstar\u00e1 a que o juiz conhe\u00e7a do pedido e outorgue a prote\u00e7\u00e3o legal correspondente \u00e0quela cujos pressupostos estejam provados.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-2-qual-a-via-processual-adequada\"><a>10.2.2. Qual a via processual adequada?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>A\u00e7\u00e3o de DESPEJO!!!!<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia cinge-se \u00e0 possibilidade de conhecimento de a\u00e7\u00e3o possess\u00f3ria de reintegra\u00e7\u00e3o de posse ajuizada para reaver o im\u00f3vel alugado, ao inv\u00e9s da a\u00e7\u00e3o de despejo, que, por for\u00e7a de expressa disposi\u00e7\u00e3o na Lei n. 8.245\/1991, \u00e9 a via judicial adequada para a retomada do bem locado: Art. 5\u00ba Seja qual for o fundamento do t\u00e9rmino da loca\u00e7\u00e3o, a a\u00e7\u00e3o do locador para reaver o im\u00f3vel \u00e9 a de despejo.<\/p>\n\n\n\n<p><strong>O art. 554 do CPC\/2015 prev\u00ea a fungibilidade entre as a\u00e7\u00f5es possess\u00f3rias<\/strong> &#8211; reintegra\u00e7\u00e3o de posse (que decorre de esbulho), manuten\u00e7\u00e3o de posse (decorrente de turba\u00e7\u00e3o) e interdito proibit\u00f3rio (em raz\u00e3o de amea\u00e7a \u00e0 posse de algu\u00e9m) -, isso porque todas as tr\u00eas t\u00eam como aspecto relevante unicamente a posse, enquanto fato, sem refer\u00eancia a pr\u00e9vio direito obrigacional ou contratual.<\/p>\n\n\n\n<p>Por outro lado, na a\u00e7\u00e3o de despejo h\u00e1 uma rela\u00e7\u00e3o contratual locat\u00edcia subjacente, de onde derivam diversos direitos e deveres do locador e do locat\u00e1rio, podendo da\u00ed resultar em uma situa\u00e7\u00e3o de posse indevida.<\/p>\n\n\n\n<p><strong>Embora o pedido da reintegra\u00e7\u00e3o de posse e da a\u00e7\u00e3o de despejo seja a posse leg\u00edtima do bem im\u00f3vel, tratam-se de pretens\u00f5es judiciais com natureza e fundamento jur\u00eddico DISTINTOS<\/strong> pois, enquanto a primeira baseia-se na situa\u00e7\u00e3o f\u00e1tica possess\u00f3ria da coisa, a segunda se fundamenta em pr\u00e9via rela\u00e7\u00e3o contratual locat\u00edcia, regida por norma ESPECIAL, o que consequentemente impossibilita sua fungibilidade.<\/p>\n\n\n\n<p>Ao se permitir o ajuizamento de a\u00e7\u00e3o possess\u00f3ria em substitui\u00e7\u00e3o da a\u00e7\u00e3o de despejo, nega-se vig\u00eancia ao conjunto de regras especiais da Lei de Loca\u00e7\u00e3o, tais como prazos, penalidades e garantias processuais.<\/p>\n\n\n\n<p>A jurisprud\u00eancia do STJ firmou-se no sentido de que, havendo comprovada rela\u00e7\u00e3o locat\u00edcia, a pretens\u00e3o de retomada do bem im\u00f3vel deve ocorrer por rito pr\u00f3prio, pelo ajuizamento da a\u00e7\u00e3o de despejo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-3-resultado-final\"><a><\/a><a><\/a><a>10.2.3. Resultado final.<\/a><\/h4>\n\n\n\n<p>A via processual adequada para a retomada, pelo propriet\u00e1rio, da posse direta de im\u00f3vel locado \u00e9 a a\u00e7\u00e3o de despejo, na forma do art. 5\u00ba da Lei n. 8.245\/1991, n\u00e3o servindo para esse prop\u00f3sito o ajuizamento de a\u00e7\u00e3o possess\u00f3ria.<a><\/a><a><\/a><\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-tributario\"><a>DIREITO TRIBUT\u00c1RIO<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-11-icms-como-parte-da-base-de-calculo-do-irpj-e-da-csll-e-lucro-presumido\"><a>11.&nbsp; ICMS como parte da base de c\u00e1lculo do IRPJ e da CSLL e lucro presumido<\/a><\/h2>\n\n\n\n<p><a><strong>RECURSO ESPECIAL<\/strong><\/a><\/p>\n\n\n\n<p>O ICMS comp\u00f5e a base de c\u00e1lculo do Imposto de Renda da Pessoa Jur\u00eddica (IRPJ) e da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL), quando apurados na sistem\u00e1tica do lucro presumido.<\/p>\n\n\n\n<p>REsp 1.767.631-SC, Rel. Ministra Regina Helena Costa, Rel. para ac\u00f3rd\u00e3o Ministro Gurgel de Faria, Primeira Se\u00e7\u00e3o, por maioria, julgado em 10\/5\/2023. (Tema 1008). (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-1-situacao-fatica\"><a>11.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Cer\u00e2mica CTT ajuizou a\u00e7\u00e3o por meio da qual intentava ter reconhecido o direito \u00e0 exclus\u00e3o de valores de ICMS nas bases de c\u00e1lculo do Imposto sobre a Renda de Pessoa Jur\u00eddica &#8211; IRPJ e da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido &#8211; CSLL quando apuradas pela sistem\u00e1tica do lucro presumido. Para a empresa, haveria bitributa\u00e7\u00e3o, estando ela a pagar imposto sobre imposto.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-2-analise-estrategica\"><a>11.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-1-questao-juridica\"><a>11.2.1. Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Constitui\u00e7\u00e3o Federal:<\/p>\n\n\n\n<p>Art. 195. A seguridade social ser\u00e1 financiada por toda a sociedade, de forma direta e indireta, nos termos da lei, mediante recursos provenientes dos or\u00e7amentos da Uni\u00e3o, dos Estados, do Distrito Federal e dos Munic\u00edpios, e das seguintes contribui\u00e7\u00f5es sociais:<\/p>\n\n\n\n<p>I &#8211; do empregador, da empresa e da entidade a ela equiparada na forma da lei, incidentes sobre:&nbsp;<\/p>\n\n\n\n<p>b) a receita ou o faturamento<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-2-icms-compoe-a-bc-mesmo-na-sistematica-do-lucro-presumido\"><a>11.2.2. ICMS comp\u00f5e a BC mesmo na sistem\u00e1tica do lucro presumido?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Aparentemente, SIM!!!!<\/strong><\/p>\n\n\n\n<p><strong>O lucro presumido, como a pr\u00f3pria express\u00e3o sugere, constitui modalidade de tributa\u00e7\u00e3o do Imposto sobre a renda de pessoa jur\u00eddica (IRPJ) e da Contribui\u00e7\u00e3o social sobre o lucro l\u00edquido (CSLL) que envolve presun\u00e7\u00f5es em mat\u00e9ria tribut\u00e1ria<\/strong>. Utiliza-se a receita bruta como par\u00e2metro a ser considerado para aplica\u00e7\u00e3o do percentual destinado \u00e0 apura\u00e7\u00e3o do lucro presumido, que \u00e9 a base de c\u00e1lculo sobre o qual incidir\u00e1 a al\u00edquota, alcan\u00e7ando-se, assim, o valor devido.<\/p>\n\n\n\n<p>Diante da circunst\u00e2ncia de que a receita representa, portanto, a grandeza que, em \u00faltima an\u00e1lise, serve para o c\u00e1lculo dos tributos em exame, busca-se na esp\u00e9cie, em ess\u00eancia, a observ\u00e2ncia da&nbsp;<em>ratio decidendi<\/em>&nbsp;do Tema 69\/STF, a fim de que seja afastado de sua composi\u00e7\u00e3o o ICMS.<\/p>\n\n\n\n<p>Com efeito, o Supremo Tribunal Federal, sob o regime da repercuss\u00e3o geral, nos autos do RE 574.706\/PR, decidiu, em car\u00e1ter definitivo, por meio de precedente vinculante, que os conceitos de faturamento e receita, contidos no art. 195, I, &#8220;b&#8221;, da Constitui\u00e7\u00e3o Federal, para fins de incid\u00eancia da Contribui\u00e7\u00e3o ao PIS e da COFINS, n\u00e3o albergam o ICMS, considerado aquele destacado na nota fiscal, pois os valores correspondentes a tal tributo estadual n\u00e3o se incorporaram ao patrim\u00f4nio dos contribuintes.<\/p>\n\n\n\n<p>Foi firmada a seguinte tese da repercuss\u00e3o geral: &#8220;O ICMS n\u00e3o comp\u00f5e a base de c\u00e1lculo para a incid\u00eancia do PIS e da COFINS&#8221; (Tema 69\/STF).<\/p>\n\n\n\n<p><strong>Ocorre que esse entendimento deve ser aplicado t\u00e3o somente \u00e0 Contribui\u00e7\u00e3o ao PIS e \u00e0 COFINS<\/strong>, porquanto realizado exclusivamente \u00e0 luz do art. 195, I, &#8220;b&#8221;, da Constitui\u00e7\u00e3o Federal, sendo indevida a extens\u00e3o indiscriminada dessa compreens\u00e3o para outros tributos, tais como o IRPJ e CSLL.<\/p>\n\n\n\n<p>A fim de corroborar a referida afirma\u00e7\u00e3o, basta ver que a pr\u00f3pria Suprema Corte, ao julgar o Tema 1048\/STF, concluiu pela constitucionalidade da inclus\u00e3o do ICMS na base de c\u00e1lculo da Contribui\u00e7\u00e3o Previdenci\u00e1ria sobre a Receita Bruta (CPRB) &#8211; a qual inclusive \u00e9 uma contribui\u00e7\u00e3o social, mas de car\u00e1ter substitutivo, que tamb\u00e9m utiliza a receita como base de c\u00e1lculo.<\/p>\n\n\n\n<p>Observe-se, portanto, que o Supremo Tribunal Federal, ao julgar o Tema 1048\/STF, tratou a CPRB como benef\u00edcio fiscal, notadamente quando passou a ser modalidade facultativa de tributa\u00e7\u00e3o. A&nbsp;<em>ratio decidendi<\/em>&nbsp;do mencionado caso paradigma traz consigo uma relevante peculiaridade: <strong>para o STF, a facultatividade do regime impede a aplica\u00e7\u00e3o pura e simples da tese fixada no julgamento do Tema 69\/STF da repercuss\u00e3o geral, porquanto caracterizaria a cria\u00e7\u00e3o incab\u00edvel de um terceiro g\u00eanero de tributa\u00e7\u00e3o mais ben\u00e9fico<\/strong>.<\/p>\n\n\n\n<p>Salienta-se que quando do julgamento do Tema 1048\/STF, o Ministro Marco Aur\u00e9lio (ent\u00e3o relator do recurso extraordin\u00e1rio) desenvolveu voto no sentido de que o alcance e a defini\u00e7\u00e3o dos institutos de receita e faturamento extra\u00eddos do julgamento do Tema 69\/STF deveriam se aplicar de maneira ampla. Para o eminente Ministro, &#8220;admitir a volatilidade dos institutos previstos na Lei Maior com base no regime fiscal ao qual submetido o contribuinte implica interpretar a Constitui\u00e7\u00e3o Federal a partir da legisla\u00e7\u00e3o comum, afastando a supremacia que lhe \u00e9 pr\u00f3pria&#8221;.<\/p>\n\n\n\n<p><strong>Ocorre que essa linha de pensamento (que agora se confunde com a pretens\u00e3o recursal analisada) foi expressamente debatida e vencida.<\/strong><\/p>\n\n\n\n<p>Isto \u00e9, o pr\u00f3prio Supremo, ao interpretar seu precedente (Tema 69\/STF), entendeu que esse seria inaplic\u00e1vel \u00e0s hip\u00f3teses em que se oferecesse benef\u00edcio fiscal ao contribuinte, vale dizer, n\u00e3o se aplicaria quando houvesse facultatividade quanto ao regime de tributa\u00e7\u00e3o, exatamente o que acontece no caso.<\/p>\n\n\n\n<p>Ressalte-se que, para a Contribui\u00e7\u00e3o ao PIS e a COFINS, a receita constitui a pr\u00f3pria base de c\u00e1lculo, enquanto para o IRPJ e a CSLL, apurados na sistem\u00e1tica do lucro presumido, representa apenas par\u00e2metro de tributa\u00e7\u00e3o, sendo essa outra distin\u00e7\u00e3o relevante.<\/p>\n\n\n\n<p>Com efeito, o Tema 69\/STF apresenta-se aplic\u00e1vel t\u00e3o somente \u00e0 Contribui\u00e7\u00e3o ao PIS e \u00e0 COFINS. N\u00e3o h\u00e1 que falar na ado\u00e7\u00e3o de &#8220;tese filhote&#8221; para albergar outros tributos, disciplinados por normas jur\u00eddicas pr\u00f3prias. Por conseguinte, n\u00e3o h\u00e1 inconstitucionalidade na circunst\u00e2ncia de o ICMS integrar a receita como base impon\u00edvel das demais exa\u00e7\u00f5es.<\/p>\n\n\n\n<p>Nesse ponto, \u00e9 importante ressaltar que, diante da orienta\u00e7\u00e3o dessa \u00faltima tese (Tema 69\/STF), a Primeira Turma, \u00e0 unanimidade, ao julgar o REsp 1.599.065\/DF (Rel. Ministra Regina Helena Costa, julgado em 9\/11\/2021, DJe 2\/12\/2021), excluiu da base de c\u00e1lculo das referidas contribui\u00e7\u00f5es os valores auferidos por empresas prestadoras de servi\u00e7o de telefonia pelo uso de suas estruturas para interconex\u00e3o e&nbsp;<em>roaming<\/em>, porquanto n\u00e3o se incorporam ao patrim\u00f4nio do contribuinte, por for\u00e7a da legisla\u00e7\u00e3o de reg\u00eancia.<\/p>\n\n\n\n<p>Cabe rememorar, por\u00e9m, que, naquela hip\u00f3tese, a discuss\u00e3o se deu justamente no \u00e2mbito da Contribui\u00e7\u00e3o ao PIS e da COFINS, ou seja, os mesmos tributos tratados no Tema 69\/STF da repercuss\u00e3o geral e \u00e0 luz dos atos normativos de natureza infraconstitucional que tratam do servi\u00e7o de&nbsp;<em>roaming&nbsp;<\/em>e interconex\u00e3o. Da\u00ed a observ\u00e2ncia daquela&nbsp;<em>ratio decidendi<\/em>, que, como visto, n\u00e3o pode ser reproduzida no presente caso.<\/p>\n\n\n\n<p>Em outras palavras, extrai-se dos julgados acima referidos que o pr\u00f3prio Supremo Tribunal Federal compreende que n\u00e3o foi exclu\u00eddo, em car\u00e1ter definitivo e autom\u00e1tico, o ICMS do conceito constitucional de receita para todos os fins tribut\u00e1rios.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-3-resultado-final\"><a>11.2.3. Resultado final.<\/a><\/h4>\n\n\n\n<p>O ICMS comp\u00f5e a base de c\u00e1lculo do Imposto de Renda da Pessoa Jur\u00eddica (IRPJ) e da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL), quando apurados na sistem\u00e1tica do lucro presumido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-12-entrega-da-declaracao-de-debito-e-creditos-tributarios-federais-dctf-como-elemento-constituidor-do-credito-tributario-e-afastamento-da-decadencia\"><a>12.&nbsp; Entrega da Declara\u00e7\u00e3o de D\u00e9bito e Cr\u00e9ditos Tribut\u00e1rios Federais &#8211; DCTF como elemento constituidor do cr\u00e9dito tribut\u00e1rio e afastamento da decad\u00eancia<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><\/p>\n\n\n\n<p>A entrega da Declara\u00e7\u00e3o de D\u00e9bito e Cr\u00e9ditos Tribut\u00e1rios Federais &#8211; DCTF constitui cr\u00e9dito tribut\u00e1rio, que pode ser cobrado ap\u00f3s a compensa\u00e7\u00e3o ser considerada n\u00e3o declarada pela autoridade competente, sendo afastada, portanto, a decad\u00eancia.<\/p>\n\n\n\n<p>REsp 1.826.743-RS, Rel. Ministro Francisco Falc\u00e3o, Segunda Turma, por unanimidade, julgado em 9\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-12-1-situacao-fatica\"><a>12.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>PagonadaSA recebeu cess\u00e3o dos cr\u00e9ditos e em idos de 2000 transmitiu a respectiva Declara\u00e7\u00e3o de D\u00e9bito e Cr\u00e9ditos Tribut\u00e1rios Federais &#8211; <strong>DCTF<\/strong> referentes aos cr\u00e9ditos de PIS e COFINS, requerendo compensa\u00e7\u00e3o com cr\u00e9ditos de terceiros. A receita se recusou a processar tais pedidos, com fundamento no impedimento de utiliza\u00e7\u00e3o de cr\u00e9ditos de terceiros. Pagonada ent\u00e3o impetrou MS e conseguiu ordem judicial determinando o processamento.<\/p>\n\n\n\n<p>Em 2012 (a coisa demooooora), o MS foi julgado em favor da Fazenda Nacional, recha\u00e7ando-se a compensa\u00e7\u00e3o de d\u00e9bitos pr\u00f3prios com cr\u00e9ditos de terceiros. A Receita ent\u00e3o apontou que as compensa\u00e7\u00f5es seriam consideradas N\u00c3O DECLARADAS, nos termos do art. 74, \u00a7 12, II, &#8220;b&#8221; e &#8220;d&#8221;, e no \u00a7 13, da Lei n. 9.430\/1996.<\/p>\n\n\n\n<p>No despacho administrativo, a autoridade fiscal fez constar que a hip\u00f3tese n\u00e3o comportava a possibilidade de apresenta\u00e7\u00e3o de <em>manifesta\u00e7\u00e3o de inconformidade<\/em>. Realizadas as intima\u00e7\u00f5es cab\u00edveis sem o consequente pagamento dos cr\u00e9ditos tribut\u00e1rios, a Fazenda Nacional promoveu a inscri\u00e7\u00e3o em d\u00edvida ativa e a respectiva cobran\u00e7a judicial, na qual foram opostos os embargos \u00e0 execu\u00e7\u00e3o fiscal que alegam a ocorr\u00eancia da DECAD\u00caNCIA.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-12-2-analise-estrategica\"><a>12.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-12-2-1-questao-juridica\"><a>12.2.1. Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 9.430\/1996:<\/p>\n\n\n\n<p>Art. 74. O sujeito passivo que apurar cr\u00e9dito, inclusive os judiciais com tr\u00e2nsito em julgado, relativo a tributo ou contribui\u00e7\u00e3o administrado pela Secretaria da Receita Federal, pass\u00edvel de restitui\u00e7\u00e3o ou de ressarcimento, poder\u00e1 utiliz\u00e1-lo na compensa\u00e7\u00e3o de d\u00e9bitos pr\u00f3prios relativos a quaisquer tributos e contribui\u00e7\u00f5es administrados por aquele \u00d3rg\u00e3o.<\/p>\n\n\n\n<p>&nbsp;\u00a7 9o \u00c9 facultado ao sujeito passivo, no prazo referido no \u00a7 7o, apresentar manifesta\u00e7\u00e3o de inconformidade contra a n\u00e3o-homologa\u00e7\u00e3o da compensa\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>\u00a7 10. Da decis\u00e3o que julgar improcedente a manifesta\u00e7\u00e3o de inconformidade caber\u00e1 recurso ao Conselho de Contribuintes.<\/p>\n\n\n\n<p>\u00a7 12. Ser\u00e1 considerada n\u00e3o declarada a compensa\u00e7\u00e3o nas hip\u00f3teses:<\/p>\n\n\n\n<p>II &#8211; em que o cr\u00e9dito:&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>b) refira-se a &#8220;cr\u00e9dito-pr\u00eamio&#8221; institu\u00eddo pela art. 1o do Decreto-Lei no 491, de 5 de mar\u00e7o de 1969;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>d) seja decorrente de decis\u00e3o judicial n\u00e3o transitada em julgado; ou<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-12-2-2-a-entrega-da-dctf-constitui-o-credito-tributario\"><a>12.2.2. A entrega da DCTF constitui o cr\u00e9dito tribut\u00e1rio?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Com certeza!!!<\/strong><\/p>\n\n\n\n<p>Trata-se, na origem, de embargos \u00e0 execu\u00e7\u00e3o fiscal opostos com o intuito de obstar a cobran\u00e7a de cr\u00e9ditos tribut\u00e1rios relacionados a pedidos de compensa\u00e7\u00e3o com cr\u00e9ditos de terceiro advindos de a\u00e7\u00e3o ordin\u00e1ria cujo objeto era o ressarcimento de cr\u00e9ditos de IPI na aquisi\u00e7\u00e3o de insumos utilizados na fabrica\u00e7\u00e3o e exporta\u00e7\u00e3o de produtos industrializados.<\/p>\n\n\n\n<p><a>Ap\u00f3s a cess\u00e3o dos cr\u00e9ditos em seu favor, a contribuinte transmitiu, em 29\/3\/2000 e 13\/12\/2000, Declara\u00e7\u00e3o de D\u00e9bito e Cr\u00e9ditos Tribut\u00e1rios Federais &#8211; DCTF referente aos cr\u00e9ditos tribut\u00e1rios de Programa de Integra\u00e7\u00e3o Social &#8211; PIS e da Contribui\u00e7\u00e3o para o Financiamento da Seguridade Social &#8211; COFINS, atrelados a pedidos de compensa\u00e7\u00e3o. Entretanto, os pedidos foram processados somente em virtude da determina\u00e7\u00e3o judicial oriunda de mandado de seguran\u00e7a para que fosse admitida a compensa\u00e7\u00e3o com cr\u00e9ditos de terceiros.<\/a><\/p>\n\n\n\n<p>Em 2012, a discuss\u00e3o originada em mandado de seguran\u00e7a encerrou-se a favor da Fazenda Nacional, oportunidade em que foi recha\u00e7ada a compensa\u00e7\u00e3o de d\u00e9bitos pr\u00f3prios com cr\u00e9ditos de terceiros. Com o tr\u00e2nsito em julgado, a Receita Federal do Brasil analisou os pedidos de compensa\u00e7\u00e3o apresentados pela agravante, com fundamento no impedimento de utiliza\u00e7\u00e3o de cr\u00e9ditos de terceiros, apontando, ainda, que as compensa\u00e7\u00f5es seriam consideradas n\u00e3o declaradas, nos termos do art. 74, \u00a7 12, II, &#8220;b&#8221; e &#8220;d&#8221;, e no \u00a7 13, da Lei n. 9.430\/1996. No despacho administrativo, a autoridade fiscal fez constar que a hip\u00f3tese n\u00e3o comportava a possibilidade de apresenta\u00e7\u00e3o de manifesta\u00e7\u00e3o de inconformidade, prevista no art. 74, \u00a7\u00a7 9\u00ba e 10, da Lei n. 9.430\/1996. Realizadas as intima\u00e7\u00f5es cab\u00edveis, sem o consequente pagamento dos cr\u00e9ditos tribut\u00e1rios, a Fazenda Nacional promoveu a inscri\u00e7\u00e3o em d\u00edvida ativa e a respectiva cobran\u00e7a judicial, na qual foram opostos os embargos \u00e0 execu\u00e7\u00e3o fiscal de onde se origina o presente caso.<\/p>\n\n\n\n<p>O Tribunal&nbsp;<em>a quo<\/em>&nbsp;proferiu ac\u00f3rd\u00e3o anulando a Certid\u00e3o de D\u00edvida Ativa &#8211; CDA sob a justificativa de que a autoridade administrativa tem o dever de verificar a regularidade dos cr\u00e9ditos compensados e emitir decis\u00e3o fundamentada acerca do requerimento do contribuinte, dando oportunidade de oferecimento de impugna\u00e7\u00e3o administrativa, em respeito ao princ\u00edpio do contradit\u00f3rio.<\/p>\n\n\n\n<p>A Fazenda Nacional interp\u00f4s recurso especial, com fundamento no art. 105, III, a, da Constitui\u00e7\u00e3o Federal, alegando que o ac\u00f3rd\u00e3o de origem violou o art. 1\u00b0, \u00a7 2\u00b0, do Decreto-Lei n. 1.737\/1959; o art. 5\u00b0 do Decreto-Lei n. 2.124\/1984 e o art. 38, par\u00e1grafo \u00fanico, da Lei n. 6.830\/1980, porque teria ocorrido a ren\u00fancia ao direito de discutir administrativamente o cr\u00e9dito tribut\u00e1rio. Ap\u00f3s julgamento monocr\u00e1tico do recurso especial, a contribuinte interp\u00f4s agravo interno.<\/p>\n\n\n\n<p>Em suas raz\u00f5es recursais, a agravante afirma que n\u00e3o impetrou o mandado de seguran\u00e7a para discutir o cr\u00e9dito tribut\u00e1rio, mas para garantir que os seus pedidos de compensa\u00e7\u00e3o fossem operacionalizados.<\/p>\n\n\n\n<p>De fato, possui raz\u00e3o a agravante ao afirmar que n\u00e3o ajuizou a\u00e7\u00e3o para discutir o cr\u00e9dito tribut\u00e1rio, alega\u00e7\u00e3o que corresponde \u00e0s raz\u00f5es recursais apresentadas pela Fazenda Nacional, que defende a ren\u00fancia \u00e0 discuss\u00e3o administrativa decorrente do mandado de seguran\u00e7a impetrado com a finalidade de operacionalizar seus pedidos de compensa\u00e7\u00e3o com cr\u00e9dito de terceiro, sem o \u00f3bice imposto pela Instru\u00e7\u00e3o Normativa n. 41\/2000.<\/p>\n\n\n\n<p>Nesse contexto, <strong>n\u00e3o h\u00e1 que se falar em discuss\u00e3o administrativa quando a mat\u00e9ria objeto de eventual manifesta\u00e7\u00e3o de inconformidade foi antecipada no m\u00e9rito do mandado de seguran\u00e7a, ainda que este tenha sido impetrado por terceiro em benef\u00edcio da agravante,<\/strong> com o devido tr\u00e2nsito em julgado a favor da Fazenda Nacional. Ou seja, a discuss\u00e3o j\u00e1 havia sido definida pelo Poder Judici\u00e1rio. Carece de sentido, portanto, a afirma\u00e7\u00e3o contida no ac\u00f3rd\u00e3o de origem, no sentido de ter sido negado o direito ao contradit\u00f3rio e \u00e0 ampla defesa na esfera administrativa.<\/p>\n\n\n\n<p>Outrossim, a manifesta\u00e7\u00e3o de inconformidade que poderia vir a ser apresentada pela agravante n\u00e3o poderia ter por finalidade discuss\u00e3o acerca de decad\u00eancia ou prescri\u00e7\u00e3o do cr\u00e9dito tribut\u00e1rio, as quais foram apresentadas em sede de embargos \u00e0 execu\u00e7\u00e3o fiscal. Nesse ponto, \u00e9 mister deixar registrado que a manifesta\u00e7\u00e3o de inconformidade pode ser manejada pelo contribuinte t\u00e3o somente para questionar os motivos do indeferimento da compensa\u00e7\u00e3o, n\u00e3o sendo o instrumento h\u00e1bil para alega\u00e7\u00f5es outras acerca do cr\u00e9dito tribut\u00e1rio que se pretende compensar.<\/p>\n\n\n\n<p>Noutro vi\u00e9s, no \u00ednterim da discuss\u00e3o no Mandado de Seguran\u00e7a finalizada em 2012, o pedido de compensa\u00e7\u00e3o foi transformado em PER\/DCOMP desde o seu protocolo, para os efeitos previstos no art. 74, \u00a7 4\u00ba, da Lei n. 9.430\/1996. Frise-se que as altera\u00e7\u00f5es promovidas no art. 74 da Lei n. 9.430\/1996 s\u00e3o aplic\u00e1veis aos pedidos de compensa\u00e7\u00e3o pendentes por expressa disposi\u00e7\u00e3o legal, de modo que coube \u00e0 autoridade administrativa observ\u00e1-las ap\u00f3s findo o writ acima mencionado.<\/p>\n\n\n\n<p><strong>Para al\u00e9m do fato de os cr\u00e9ditos indicados no pedido de compensa\u00e7\u00e3o serem de terceiro, situa\u00e7\u00e3o esta decidida no mandado de seguran\u00e7a, o encontro de contas envolvia cr\u00e9dito-pr\u00eamio e indica\u00e7\u00e3o de cr\u00e9dito que, \u00e0 \u00e9poca do pedido frente \u00e0 Administra\u00e7\u00e3o, era oriundo de decis\u00e3o n\u00e3o transitada em julgada<\/strong>. Em tais hip\u00f3teses (incluindo neste rol a compensa\u00e7\u00e3o com cr\u00e9ditos de terceiros), a compensa\u00e7\u00e3o \u00e9 considerada n\u00e3o declarada, sendo incab\u00edvel a manifesta\u00e7\u00e3o de inconformidade, nos termos do art. 74, \u00a7 12, II, e no \u00a7 13 da Lei n. 9.430\/1996. Portanto, ainda que o presente caso n\u00e3o envolvesse ren\u00fancia ao direito de discutir na seara administrativa, a agravante n\u00e3o poderia discutir administrativamente a compensa\u00e7\u00e3o n\u00e3o declarada por meio de manifesta\u00e7\u00e3o de inconformidade.<\/p>\n\n\n\n<p>N\u00e3o obstante a jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a ter se firmado no sentido da exig\u00eancia do lan\u00e7amento de of\u00edcio nas hip\u00f3teses em que os pedidos de compensa\u00e7\u00e3o indeferidos foram apresentados antes 31\/10\/2003, o presente caso comporta o devido&nbsp;<em>distinguishing<\/em>. Nesse diapas\u00e3o, a entrega da DCTF pela agravante constituiu o cr\u00e9dito tribut\u00e1rio, que pode ser cobrado ap\u00f3s a compensa\u00e7\u00e3o ser considerada n\u00e3o declarada pela autoridade competente, sendo afastada, portanto, a decad\u00eancia.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-12-2-3-resultado-final\"><a>12.2.3. Resultado final.<\/a><\/h4>\n\n\n\n<p>A entrega da Declara\u00e7\u00e3o de D\u00e9bito e Cr\u00e9ditos Tribut\u00e1rios Federais &#8211; DCTF constitui cr\u00e9dito tribut\u00e1rio, que pode ser cobrado ap\u00f3s a compensa\u00e7\u00e3o ser considerada n\u00e3o declarada pela autoridade competente, sendo afastada, portanto, a decad\u00eancia.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-penal\"><a>DIREITO PROCESSUAL PENAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-13-mera-sinalizacao-do-cao-de-faro-seguida-de-abordagem-a-suposto-usuario-saindo-do-local-como-justificativa-da-dispensa-do-mandado-judicial-para-o-ingresso-em-domicilio\"><a>13.&nbsp; Mera sinaliza\u00e7\u00e3o do c\u00e3o de faro, seguida de abordagem a suposto usu\u00e1rio saindo do local como justificativa da dispensa do mandado judicial para o ingresso em domic\u00edlio<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO REGIMENTAL NO HABEAS CORPUS<\/strong><\/p>\n\n\n\n<p>A <a>mera sinaliza\u00e7\u00e3o do c\u00e3o de faro, seguida de abordagem a suposto usu\u00e1rio saindo do local, desacompanhada de qualquer outra dilig\u00eancia investigativa ou outro elemento concreto indicando a necessidade de imediata a\u00e7\u00e3o policial, n\u00e3o justifica a dispensa do mandado judicial para o ingresso em domic\u00edlio<\/a>.<\/p>\n\n\n\n<p>AgRg no HC 729.836-MS, Rel. Ministra Laurita Vaz, Sexta Turma, por unanimidade, julgado em 27\/4\/2023, DJe 02\/5\/2023. (Info 774)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-13-1-situacao-fatica\"><a>13.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A PM fazia uma ronda quando encontrou um cidad\u00e3o em comportamento suspeito. Abordado, o rapaz admitiu que comprou pequena quantidade de droga em uma casa pr\u00f3xima \u2014 propriedade de Creitinho.<\/p>\n\n\n\n<p>A PM foi at\u00e9 a resid\u00eancia e l\u00e1 o c\u00e3o policial Maradona indicou a exist\u00eancia de drogas nas proximidades. A PM ent\u00e3o entrou no domic\u00edlio onde encontrou quantidades significativas de drogas em v\u00e1rios c\u00f4modos.<\/p>\n\n\n\n<p>Ap\u00f3s a senten\u00e7a condenat\u00f3ria, a defesa de Creitinho impetrou HC no qual alega a nulidade da condena\u00e7\u00e3o diante do ingresso for\u00e7ado no domic\u00edlio do Agravante sem fundadas raz\u00f5es e sem o devido mandado judicial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-13-2-analise-estrategica\"><a>13.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-13-2-1-justificado-o-ingresso-no-domicilio\"><a>13.2.1. Justificado o ingresso no domic\u00edlio?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nooops!!!!<\/strong><\/p>\n\n\n\n<p>De in\u00edcio, destaca-se que &#8220;<strong>\u00e9 pac\u00edfico, nesta Corte, o entendimento de que, nos crimes permanentes, tal qual o tr\u00e1fico de drogas, o estado de flagr\u00e2ncia se protrai no tempo, o que n\u00e3o \u00e9 suficiente, por si s\u00f3, para justificar busca domiciliar desprovida de mandado judicial, exigindo-se a demonstra\u00e7\u00e3o de ind\u00edcios m\u00ednimos de que naquele momento, dentro da resid\u00eancia, haveria situa\u00e7\u00e3o de flagrante delito<\/strong>&#8221; (AgRg no AREsp 1.512.826\/PR, Rel. Ministro Nefi Cordeiro, Sexta Turma, julgado em 18\/2\/2020, DJe 27\/2\/2020).<\/p>\n\n\n\n<p>No caso, o Tribunal de origem consignou que durante abordagem realizada na casa do vizinho do acusado, na qual os policiais utilizavam-se de um c\u00e3o de faro, o animal sinalizou para a casa do Paciente, ocasi\u00e3o em que este foi abordado e franqueou a entrada dos policiais no im\u00f3vel.<\/p>\n\n\n\n<p>Todavia, n\u00e3o h\u00e1 nenhuma comprova\u00e7\u00e3o documental de que houve autoriza\u00e7\u00e3o volunt\u00e1ria e livre de coa\u00e7\u00e3o para o ingresso no domic\u00edlio do acusado. Al\u00e9m disso, <strong>a palavra dos agentes policiais acerca da suposta autoriza\u00e7\u00e3o n\u00e3o encontra respaldo em nenhum outro elemento probat\u00f3rio<\/strong>, sendo certo que no depoimento extrajudicial do acusado n\u00e3o h\u00e1 registro sobre o seu consentimento.<\/p>\n\n\n\n<p>Ressalta-se que o Superior Tribunal de Justi\u00e7a firmou o entendimento de que &#8220;<strong>como forma de n\u00e3o deixar d\u00favidas sobre a sua legalidade, a prova da voluntariedade do consentimento para o ingresso na resid\u00eancia do suspeito incumbe ao Estado, devendo ser realizada com declara\u00e7\u00e3o assinada pela pessoa que autorizou o ingresso domiciliar, indicando-se, sempre que poss\u00edvel, testemunhas do ato<\/strong>&#8221; (HC 728.920\/GO, Rel. Ministro Olindo Menezes, Desembargador Convocado do TRF da 1\u00aa Regi\u00e3o, Sexta Turma, julgado em 14\/6\/2022, DJe 20\/6\/2022).<\/p>\n\n\n\n<p>No mais, a mera sinaliza\u00e7\u00e3o do c\u00e3o de faro, seguida da abordagem de um suposto usu\u00e1rio &#8211; que n\u00e3o foi ouvido em ju\u00edzo &#8211; saindo do local, desacompanhada de qualquer outra dilig\u00eancia investigativa ou outro elemento concreto indicando a necessidade de imediata a\u00e7\u00e3o policial naquele momento, n\u00e3o justifica, por si s\u00f3, a dispensa do mandado judicial para o ingresso em domic\u00edlio.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-13-2-2-resultado-final\"><a>13.2.2. Resultado final.<\/a><\/h4>\n\n\n\n<p>A mera sinaliza\u00e7\u00e3o do c\u00e3o de faro, seguida de abordagem a suposto usu\u00e1rio saindo do local, desacompanhada de qualquer outra dilig\u00eancia investigativa ou outro elemento concreto indicando a necessidade de imediata a\u00e7\u00e3o policial, n\u00e3o justifica a dispensa do mandado judicial para o ingresso em domic\u00edlio.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"Incorporar PDF\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-f68ab8f6-a780-47d5-9315-f7f9229a4aa3\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/06\/13021155\/stj-informativo-774.pdf\">stj-informativo-774<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/06\/13021155\/stj-informativo-774.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f68ab8f6-a780-47d5-9315-f7f9229a4aa3\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informativo n\u00ba 774 do STJ\u00a0COMENTADO\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Termo inicial dos juros de mora em a\u00e7\u00e3o de cobran\u00e7a de valores pret\u00e9ritos ao ajuizamento de anterior mandado de seguran\u00e7a que reconheceu o direito RECURSO ESPECIAL O termo inicial dos [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1231045","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STJ 774 Comentado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STJ 774 Comentado\" \/>\n<meta property=\"og:description\" content=\"Informativo n\u00ba 774 do STJ\u00a0COMENTADO\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Termo inicial dos juros de mora em a\u00e7\u00e3o de cobran\u00e7a de valores pret\u00e9ritos ao ajuizamento de anterior mandado de seguran\u00e7a que reconheceu o direito RECURSO ESPECIAL O termo inicial dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-13T05:12:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-13T05:12:09+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"61 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STJ 774 Comentado\",\"datePublished\":\"2023-06-13T05:12:06+00:00\",\"dateModified\":\"2023-06-13T05:12:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/\"},\"wordCount\":12110,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/\",\"name\":\"Informativo STJ 774 Comentado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2023-06-13T05:12:06+00:00\",\"dateModified\":\"2023-06-13T05:12:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STJ 774 Comentado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STJ 774 Comentado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STJ 774 Comentado","og_description":"Informativo n\u00ba 774 do STJ\u00a0COMENTADO\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! DIREITO ADMINISTRATIVO 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Termo inicial dos juros de mora em a\u00e7\u00e3o de cobran\u00e7a de valores pret\u00e9ritos ao ajuizamento de anterior mandado de seguran\u00e7a que reconheceu o direito RECURSO ESPECIAL O termo inicial dos [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-06-13T05:12:06+00:00","article_modified_time":"2023-06-13T05:12:09+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"61 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STJ 774 Comentado","datePublished":"2023-06-13T05:12:06+00:00","dateModified":"2023-06-13T05:12:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/"},"wordCount":12110,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/","name":"Informativo STJ 774 Comentado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2023-06-13T05:12:06+00:00","dateModified":"2023-06-13T05:12:09+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-774-comentado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STJ 774 Comentado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1231045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1231045"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1231045\/revisions"}],"predecessor-version":[{"id":1231048,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1231045\/revisions\/1231048"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1231045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1231045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1231045"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1231045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}