{"id":1216520,"date":"2023-06-16T08:00:00","date_gmt":"2023-06-16T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1216520"},"modified":"2023-05-26T13:33:06","modified_gmt":"2023-05-26T16:33:06","slug":"processo-penal-militar-pmsc","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/","title":{"rendered":"Processo penal militar para PM-SC: cautelares pessoais"},"content":{"rendered":"\n<p><strong>QAP, combatente?!<\/strong> Tudo bem contigo? Espero que sim! Neste material, iremos discorrer sobre uma das tem\u00e1ticas mais relevantes do processo penal militar para PM-SC: as cautelares pessoais. Tal conte\u00fado recorrentemente aparece nos concursos policiais militares, em raz\u00e3o das diferen\u00e7as existentes com a legisla\u00e7\u00e3o comum.<\/p>\n\n\n\n<p>A princ\u00edpio, devemos saber \u2013 para fins do processo penal militar para PM-SC \u2013 que <strong>as cautelares pessoais consistem em medidas processuais que possuem a finalidade de garantir a aplica\u00e7\u00e3o da lei penal militar, assim como assegurar a ordem do processo<\/strong>. Ent\u00e3o, aplicam-se tais medidas desde a investiga\u00e7\u00e3o militar at\u00e9 o final do processo, com o tr\u00e2nsito em julgado da decis\u00e3o judicial.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A aplica\u00e7\u00e3o das cautelares pessoais deve ser motivada<\/strong> com fundamento em elementos concretos, n\u00e3o podendo ser justificada de maneira abstrata;<\/li>\n\n\n\n<li><strong>Deve-se assegurar a todos os cidad\u00e3os<\/strong>, inclusive os acusados em processo penal militar, <strong>as garantias dispostas na Constitui\u00e7\u00e3o Cidad\u00e3<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Devido a isso, no t\u00f3pico inaugural, falaremos das <strong>pris\u00f5es cautelares<\/strong> que est\u00e3o dispostas no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/del1002.htm\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3digo de Processo Penal Militar<\/a> (CPPM). Logo, apresentaremos as <strong>principais distin\u00e7\u00f5es com rela\u00e7\u00e3o ao processo penal comum<\/strong> (utilizando quadro-comparativo), assim como destacando os t\u00f3picos mais relevantes acerca do tema.<\/p>\n\n\n\n<p>Nesse sentido, tamb\u00e9m exibiremos os pontos mais relevantes a respeito da<strong> menagem <\/strong>e da<strong> liberdade provis\u00f3ria<\/strong> nos termos do processo penal militar, apontando \u2013 entre outras observa\u00e7\u00f5es \u2013 a finalidade e as circunst\u00e2ncias que permitem a aplica\u00e7\u00e3o dessas ferramentas jur\u00eddicas.<\/p>\n\n\n\n<p>Por fim, <strong>recomendamos a leitura dos artigos 220 a 276 do CPPM<\/strong>, visto que a banca examinadora constantemente aborda o tema exigindo o conhecimento literal dos dispositivos.<\/p>\n\n\n\n<p><strong>Vamos nessa!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-as-prisoes-cautelares-no-processo-penal-militar-para-pm-sc\">As pris\u00f5es cautelares no processo penal militar para PM-SC<\/h2>\n\n\n\n<p>Candidato, <strong>admite-se o cerceamento da liberdade ambulatorial no \u00e2mbito do processo penal militar com rol de hip\u00f3teses mais ampla do que na seara comum<\/strong>. Tal possibilidade deriva de <strong>expressa previs\u00e3o constitucional<\/strong> que, embora trate a pris\u00e3o como exce\u00e7\u00e3o, prev\u00ea as seguintes possibilidades:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Flagrante delito;<\/li>\n\n\n\n<li>Decorrente de ordem escrita e fundamentada de autoridade judici\u00e1ria competente; e<\/li>\n\n\n\n<li>No caso de transgress\u00e3o militar ou crime propriamente militar.<\/li>\n<\/ul>\n\n\n\n<p>Ademais, saibamos que <strong>se realiza a pris\u00e3o de militar por meio de outro militar que possua posto ou gradua\u00e7\u00e3o superior ao custodiado<\/strong>. Contudo, <strong>se o n\u00edvel hier\u00e1rquico for igual, quem realiza a pris\u00e3o deve ser mais antigo do que o militar que foi preso<\/strong>.<\/p>\n\n\n\n<p>No caso da <strong>pris\u00e3o decorrente do cometimento de crime propriamente militar<\/strong>, essa <strong>poder\u00e1 ocorrer independentemente de flagrante delito<\/strong>, conforme o artigo 18 do CPPM. Assim, <strong>o indiciado poder\u00e1 ficar detido durante as investiga\u00e7\u00f5es policiais por at\u00e9 30 dias<\/strong>, devendo ocorrer <strong>comunica\u00e7\u00e3o \u00e0 autoridade judici\u00e1ria competente<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mediante solicita\u00e7\u00e3o fundamentada do encarregado inqu\u00e9rito e por via hier\u00e1rquica, o comandante poder\u00e1 prorrogar \u2013 por mais vinte dias \u2013 a deten\u00e7\u00e3o do indiciado.<\/li>\n<\/ul>\n\n\n\n<p>Por sua vez, <strong>quanto \u00e0 pris\u00e3o proveniente de transgress\u00e3o militar, a natureza jur\u00eddica dessa \u00e9 administrativa ou disciplinar<\/strong>, mas n\u00e3o penal. Por isso, regula-se por normas do direito administrativo militar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-a-regulamentacao-das-prisoes-cautelares-no-cppm\">A regulamenta\u00e7\u00e3o das pris\u00f5es cautelares no CPPM<\/h3>\n\n\n\n<p>Em primeiro lugar, adentrando nas hip\u00f3teses constitucionais de cerceamento da liberdade ambulatorial, passaremos a estudar a <strong>pris\u00e3o em flagrante delito<\/strong>. Em rela\u00e7\u00e3o a essa cautelar pessoal, <strong>diferentemente da legisla\u00e7\u00e3o processual comum, o CPPM n\u00e3o traz o flagrante obrigat\u00f3rio para autoridades policiais e seus agentes, apenas para os militares<\/strong>.<\/p>\n\n\n\n<p>Nesse contexto, o artigo 244 do CPPM apresenta que ser\u00e1 considerado em flagrante delito o agente que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Est\u00e1 cometendo o crime \u2013 Flagrante pr\u00f3prio;<\/li>\n\n\n\n<li>Acaba de comet\u00ea-lo \u2013 Flagrante pr\u00f3prio;<\/li>\n\n\n\n<li>Logo ap\u00f3s o fato delituoso, \u00e9 perseguido em situa\u00e7\u00e3o que fa\u00e7a acredita ser ele o seu autor \u2013 Flagrante Impr\u00f3prio;<\/li>\n\n\n\n<li>Logo depois, \u00e9 encontrado com instrumentos, objetos, material ou pap\u00e9is que fa\u00e7am presumir a sua participa\u00e7\u00e3o no fato delituoso \u2013 Flagrante presumido.<\/li>\n<\/ul>\n\n\n\n<p>Ademais, <strong>a nota de culpa ser\u00e1 entregue ao preso, ap\u00f3s vinte e quatro horas da realiza\u00e7\u00e3o da sua pris\u00e3o<\/strong>. Essa conter\u00e1 a assinatura da autoridade que lavrou o seu flagrante, com o motivo da pris\u00e3o, o nome do condutor e das testemunhas.<\/p>\n\n\n\n<p>Em segundo lugar, a <strong>pris\u00e3o preventiva<\/strong> requer a <strong>demonstra\u00e7\u00e3o da prova do fato delituoso<\/strong> e os <strong>ind\u00edcios suficientes de autorias<\/strong> cuja <strong>decreta\u00e7\u00e3o se realiza pelo auditor ou pelo Conselho de Justi\u00e7a<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>De of\u00edcio<\/strong>, durante a investiga\u00e7\u00e3o ou o processo;<\/li>\n\n\n\n<li><strong>A requerimento do Minist\u00e9rio P\u00fablico<\/strong>, em qualquer fase da investiga\u00e7\u00e3o ou do processo; ou<\/li>\n\n\n\n<li><strong>Mediante representa\u00e7\u00e3o da autoridade encarregada do inqu\u00e9rito policial militar<\/strong>, durante o tr\u00e2mite do procedimento.<\/li>\n<\/ul>\n\n\n\n<p>Al\u00e9m disso, a decreta\u00e7\u00e3o dessa cautelar pessoal possui alguns <strong>fundamentos<\/strong> diferentes quando os comparamos com a legisla\u00e7\u00e3o penal comum. Vejamos:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084651\/quadro-comparativo-fundamentos-da-pp.png\" alt=\"Fundamentos da Pris\u00e3o Preventiva - Quadro-comparativo - Processo penal militar para PM-SC\" class=\"wp-image-1217385\" width=\"540\" height=\"230\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084651\/quadro-comparativo-fundamentos-da-pp.png 868w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084651\/quadro-comparativo-fundamentos-da-pp-300x128.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084651\/quadro-comparativo-fundamentos-da-pp-768x327.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084651\/quadro-comparativo-fundamentos-da-pp-610x260.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084651\/quadro-comparativo-fundamentos-da-pp-150x64.png 150w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">Quadro-comparativo &#8211; Processo penal militar para PM-SC<\/figcaption><\/figure>\n\n\n\n<p>Por fim, inadmite-se a decreta\u00e7\u00e3o da pris\u00e3o preventiva quando o juiz verificar que o agente praticou o fato por <strong>erro de direito<\/strong>, <strong>coa\u00e7\u00e3o irresist\u00edvel ou obedi\u00eancia hier\u00e1rquica<\/strong>, <strong>estado de necessidade exculpante <\/strong>e <strong>estado de necessidade justificante, leg\u00edtima defesa, estrito cumprimento do dever legal, exerc\u00edcio regular do direito e estado de necessidade coativo<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os institutos jur\u00eddicos da menagem e da liberdade provis\u00f3ria no processo penal militar para PM-SC<\/h2>\n\n\n\n<p>A princ\u00edpio, Estrategista, <strong>a menagem possui rela\u00e7\u00e3o parcial com a liberdade provis\u00f3ria<\/strong>. Todavia, ser\u00e1 cab\u00edvel em hip\u00f3teses onde a referida n\u00e3o \u00e9 poss\u00edvel. Sendo assim, <strong>o juiz poder\u00e1 conceder a menagem \u2013 observando a natureza do delito e os antecedentes do acusado \u2013 nos crimes cujo m\u00e1ximo da pena privativa de liberdade n\u00e3o exceda a quatro anos<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Antes da concess\u00e3o, haver\u00e1 manifesta\u00e7\u00e3o do Minist\u00e9rio P\u00fablico por meio de parecer no prazo de tr\u00eas dias;<\/li>\n\n\n\n<li>N\u00e3o se admite a concess\u00e3o para quem \u00e9 reincidente;<\/li>\n\n\n\n<li>Cessa-se com a senten\u00e7a condenat\u00f3ria, ainda que n\u00e3o haja o tr\u00e2nsito em julgado.<\/li>\n<\/ul>\n\n\n\n<p>Outrossim, <strong>o local de cumprimento da menagem ser\u00e1 diferente a depender se o sujeito \u00e9 militar ou civil<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084746\/menagem.png\" alt=\"Quadro-comparativo menagem a militar e a civil\" class=\"wp-image-1217387\" width=\"625\" height=\"202\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084746\/menagem.png 862w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084746\/menagem-300x97.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084746\/menagem-768x249.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084746\/menagem-610x198.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/05\/17084746\/menagem-150x49.png 150w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><figcaption class=\"wp-element-caption\">Quadro-comparativo &#8211; Processo penal militar para PM-SC<\/figcaption><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quando a menagem ocorrer em lugar sujeito \u00e0 administra\u00e7\u00e3o militar, requer-se informa\u00e7\u00e3o, acerca da sua conveni\u00eancia, \u00e0 autoridade respons\u00e1vel pelo respectivo comando ou dire\u00e7\u00e3o;<\/li>\n\n\n\n<li>Caso a concess\u00e3o ocorra em resid\u00eancia ou cidade, n\u00e3o haver\u00e1 detra\u00e7\u00e3o do tempo de cumprimento em eventual pena.<\/li>\n<\/ul>\n\n\n\n<p>Para encerrar, a <strong>liberdade provis\u00f3ria<\/strong> possui duas modalidades: a <strong>obrigat\u00f3ria<\/strong> e a <strong>facultativa<\/strong>.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao tipo obrigat\u00f3rio, <strong>no caso de infra\u00e7\u00e3o que n\u00e3o se comine pena privativa de liberdade, ao sujeito deve se conceder a liberdade provis\u00f3ria<\/strong>.<\/p>\n\n\n\n<p>Por sua vez, quanto a outra esp\u00e9cie, <strong>o sujeito poder\u00e1 livrar-se solto nos casos de infra\u00e7\u00e3o culposa<\/strong> (salvo quando essa estiver prevista no rol de crimes contra a seguran\u00e7a externa do pa\u00eds) <strong>e de infra\u00e7\u00e3o punida com pena de deten\u00e7\u00e3o n\u00e3o superior a dois anos<\/strong>, ressalvados os seguintes crimes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Viol\u00eancia contra superior;<\/li>\n\n\n\n<li>Desrespeito a superior;<\/li>\n\n\n\n<li>Desrespeito a s\u00edmbolo nacional;<\/li>\n\n\n\n<li>Despojamento desprez\u00edvel;<\/li>\n\n\n\n<li>Recusa de obedi\u00eancia;<\/li>\n\n\n\n<li>Oposi\u00e7\u00e3o a ordem de sentinela;<\/li>\n\n\n\n<li>Publica\u00e7\u00e3o ou cr\u00edtica indevida;<\/li>\n\n\n\n<li>Abuso de requisi\u00e7\u00e3o militar;<\/li>\n\n\n\n<li>Ofensa aviltante a inferior;<\/li>\n\n\n\n<li>Resist\u00eancia mediante amea\u00e7a ou viol\u00eancia;<\/li>\n\n\n\n<li>Fuga de preso ou internado;<\/li>\n\n\n\n<li>Deser\u00e7\u00e3o;<\/li>\n\n\n\n<li>Deser\u00e7\u00e3o por invas\u00e3o ou fuga;<\/li>\n\n\n\n<li>Desacato a militar; e<\/li>\n\n\n\n<li>Ingresso clandestino.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Considera\u00e7\u00f5es Finais<\/h2>\n\n\n\n<p>Desse modo, trouxemos todas as informa\u00e7\u00f5es essenciais para a sua compreens\u00e3o acerca dessa tem\u00e1tica do processo penal militar para PM-SC cujo conhecimento ser\u00e1 primordial para a conquista da sua aprova\u00e7\u00e3o <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-pm-sc\/\" target=\"_blank\" rel=\"noreferrer noopener\">no certame<\/a>.<\/p>\n\n\n\n<p>Outrossim, reiteramos que \u00e9 fundamental o dom\u00ednio literal das normas, uma vez que os examinadores costumam abordar as cautelares pessoais e temas correlatos nessa modalidade de conhecimento. Assim sendo, <strong>realize a leitura dos artigos 220 a 276 do CPPM<\/strong>, principalmente destacando os pontos que assinalamos neste material.<\/p>\n\n\n\n<p>Quer aprofundar mais ainda os seus conhecimentos? <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/policia-militar-de-santa-catarina-pm-sc\/?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=ec-pol-vd-gsh-pmsc&amp;gclid=CjwKCAjw9pGjBhB-EiwAa5jl3Cfa7417ukx9Lv0I-jx9USRyw9NQZVi5XiogsMzKIkGOXUsBrU1MGhoCNEwQAvD_BwE\" target=\"_blank\" rel=\"noreferrer noopener\">Venha conosco!<\/a><\/strong><\/p>\n\n\n\n<p>Desejo muita resili\u00eancia nos estudos e perseveran\u00e7a em seus objetivos!<\/p>\n\n\n\n<p><strong>A vit\u00f3ria \u00e9 certa para quem n\u00e3o desiste!<\/strong><\/p>\n\n\n\n<p><strong>Bons estudos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-pale-cyan-blue-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>QAP, combatente?! Tudo bem contigo? Espero que sim! Neste material, iremos discorrer sobre uma das tem\u00e1ticas mais relevantes do processo penal militar para PM-SC: as cautelares pessoais. Tal conte\u00fado recorrentemente aparece nos concursos policiais militares, em raz\u00e3o das diferen\u00e7as existentes com a legisla\u00e7\u00e3o comum. A princ\u00edpio, devemos saber \u2013 para fins do processo penal militar [&hellip;]<\/p>\n","protected":false},"author":2566,"featured_media":874654,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220186,220187],"tags":[1573,2717,820],"tax_estado":[219963,219987],"class_list":["post-1216520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-policial-oficial","category-policial-pracas","tag-carreiras-policiais","tag-concurso-pmsc-oficial","tag-concursos-publicos","tax_estado-concursos-federais","tax_estado-sc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Processo penal militar para PM-SC: cautelares pessoais<\/title>\n<meta name=\"description\" content=\"Confira agora os t\u00f3picos fundamentais e garanta quest\u00f5es sobre as cautelares pessoais no processo penal militar para PM-SC!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Processo penal militar para PM-SC: cautelares pessoais\" \/>\n<meta property=\"og:description\" content=\"Confira agora os t\u00f3picos fundamentais e garanta quest\u00f5es sobre as cautelares pessoais no processo penal militar para PM-SC!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-16T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Rocha da Gra\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Rocha da Gra\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/\"},\"author\":{\"name\":\"Gabriel Rocha da Gra\u00e7a\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b7dbf284f7775e26e8fafbe6a56c1fc0\"},\"headline\":\"Processo penal militar para PM-SC: cautelares pessoais\",\"datePublished\":\"2023-06-16T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/\"},\"wordCount\":1375,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg\",\"keywords\":[\"carreiras policiais\",\"concurso pmsc oficial\",\"concursos p\u00fablicos\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Policial (PM\/BM - Oficial)\",\"Policial (PM\/BM - Pra\u00e7as)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/\",\"name\":\"Processo penal militar para PM-SC: cautelares pessoais\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg\",\"datePublished\":\"2023-06-16T11:00:00+00:00\",\"description\":\"Confira agora os t\u00f3picos fundamentais e garanta quest\u00f5es sobre as cautelares pessoais no processo penal militar para PM-SC!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg\",\"width\":768,\"height\":432,\"caption\":\"concurso pm sc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Processo penal militar para PM-SC: cautelares pessoais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b7dbf284f7775e26e8fafbe6a56c1fc0\",\"name\":\"Gabriel Rocha da Gra\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/01dc6deaaf49f7195b1b726afb16234e5589513d0df3f1687499d49775ccfb8c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/01dc6deaaf49f7195b1b726afb16234e5589513d0df3f1687499d49775ccfb8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/01dc6deaaf49f7195b1b726afb16234e5589513d0df3f1687499d49775ccfb8c?s=96&d=mm&r=g\",\"caption\":\"Gabriel Rocha da Gra\u00e7a\"},\"description\":\"Sou Bacharel em Direito e possuo cinco especializa\u00e7\u00f5es, entre as quais destaco a minha P\u00f3s-Gradua\u00e7\u00e3o em Ci\u00eancias Criminais e meus MBAs em Gest\u00e3o da Seguran\u00e7a P\u00fablica e em Gest\u00e3o de Pol\u00edcia Ostensiva. Ademais, fui aprovado, de primeira, no XXX Exame da Ordem dos Advogados do Brasil, bem como conquistei diversas aprova\u00e7\u00f5es em concursos p\u00fablicos, entre as quais destaco os \\\"top-5\\\" nos concursos do CFO PM-GO, CFO PM-RN, Delegado\/BA e Soldado PM\/SE. Atualmente, estou Aspirante a Oficial na Pol\u00edcia Militar do Estado de Goi\u00e1s.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabrieldagracayahoo-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Processo penal militar para PM-SC: cautelares pessoais","description":"Confira agora os t\u00f3picos fundamentais e garanta quest\u00f5es sobre as cautelares pessoais no processo penal militar para PM-SC!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/","og_locale":"pt_BR","og_type":"article","og_title":"Processo penal militar para PM-SC: cautelares pessoais","og_description":"Confira agora os t\u00f3picos fundamentais e garanta quest\u00f5es sobre as cautelares pessoais no processo penal militar para PM-SC!","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-06-16T11:00:00+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg","type":"image\/jpeg"}],"author":"Gabriel Rocha da Gra\u00e7a","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Gabriel Rocha da Gra\u00e7a","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/"},"author":{"name":"Gabriel Rocha da Gra\u00e7a","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b7dbf284f7775e26e8fafbe6a56c1fc0"},"headline":"Processo penal militar para PM-SC: cautelares pessoais","datePublished":"2023-06-16T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/"},"wordCount":1375,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg","keywords":["carreiras policiais","concurso pmsc oficial","concursos p\u00fablicos"],"articleSection":["Concursos P\u00fablicos","Policial (PM\/BM - Oficial)","Policial (PM\/BM - Pra\u00e7as)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/","name":"Processo penal militar para PM-SC: cautelares pessoais","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg","datePublished":"2023-06-16T11:00:00+00:00","description":"Confira agora os t\u00f3picos fundamentais e garanta quest\u00f5es sobre as cautelares pessoais no processo penal militar para PM-SC!","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/09\/30160834\/pm-sc.jpg","width":768,"height":432,"caption":"concurso pm sc"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/processo-penal-militar-pmsc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Processo penal militar para PM-SC: cautelares pessoais"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b7dbf284f7775e26e8fafbe6a56c1fc0","name":"Gabriel Rocha da Gra\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/01dc6deaaf49f7195b1b726afb16234e5589513d0df3f1687499d49775ccfb8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01dc6deaaf49f7195b1b726afb16234e5589513d0df3f1687499d49775ccfb8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01dc6deaaf49f7195b1b726afb16234e5589513d0df3f1687499d49775ccfb8c?s=96&d=mm&r=g","caption":"Gabriel Rocha da Gra\u00e7a"},"description":"Sou Bacharel em Direito e possuo cinco especializa\u00e7\u00f5es, entre as quais destaco a minha P\u00f3s-Gradua\u00e7\u00e3o em Ci\u00eancias Criminais e meus MBAs em Gest\u00e3o da Seguran\u00e7a P\u00fablica e em Gest\u00e3o de Pol\u00edcia Ostensiva. Ademais, fui aprovado, de primeira, no XXX Exame da Ordem dos Advogados do Brasil, bem como conquistei diversas aprova\u00e7\u00f5es em concursos p\u00fablicos, entre as quais destaco os \"top-5\" nos concursos do CFO PM-GO, CFO PM-RN, Delegado\/BA e Soldado PM\/SE. Atualmente, estou Aspirante a Oficial na Pol\u00edcia Militar do Estado de Goi\u00e1s.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/gabrieldagracayahoo-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1216520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2566"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1216520"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1216520\/revisions"}],"predecessor-version":[{"id":1217396,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1216520\/revisions\/1217396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/874654"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1216520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1216520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1216520"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1216520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}