{"id":1212620,"date":"2023-06-05T14:00:00","date_gmt":"2023-06-05T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1212620"},"modified":"2023-05-26T13:17:26","modified_gmt":"2023-05-26T16:17:26","slug":"banco-dados-atomicidade","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/","title":{"rendered":"Banco de Dados: Propriedade Atomicidade"},"content":{"rendered":"\n<p>Banco de Dados: Propriedade Atomicidade &#8211; Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"626\" height=\"404\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg\" alt=\"Banco de Dados: Propriedade Atomicidade\" class=\"wp-image-953107\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg 626w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1-300x194.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1-610x394.jpg 610w\" sizes=\"auto, (max-width: 626px) 100vw, 626px\" \/><figcaption class=\"wp-element-caption\">Banco de Dados: Propriedade Atomicidade<\/figcaption><\/figure>\n\n\n\n<p>Ol\u00e1, pessoal! Tudo certo com voc\u00eas!?<\/p>\n\n\n\n<p>A disciplina Tecnologia da Informa\u00e7\u00e3o tem sido cada vez mais cobrada nos editais de concursos p\u00fablicos, especialmente no que se refere aos concursos para as \u00e1reas fiscal e de controle, sem contar nos concursos espec\u00edficos para a \u00e1rea de Tecnologia da Informa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Dentro dessa importante disciplina, um assunto \u00e9 destaque e est\u00e1 constantemente nos editais dos principais certames e bancas, qual seja, o das propriedades das transa\u00e7\u00f5es em bancos de dados, conforme segue:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"a\">\n<li>Atomicidade;<\/li>\n\n\n\n<li>Consist\u00eancia;<\/li>\n\n\n\n<li>Isolamento; e<\/li>\n\n\n\n<li>Durabilidade.<\/li>\n<\/ol>\n\n\n\n<p>Essas propriedades s\u00e3o cobradas frequentemente em quest\u00f5es da disciplina de Tecnologia da Informa\u00e7\u00e3o e s\u00e3o conhecidas pelo mnem\u00f4nico \u201cACID\u201d (<strong>A<\/strong>tomicidade, <strong>C<\/strong>onsist\u00eancia, <strong>I<\/strong>solamento e <strong>D<\/strong>urabilidade).<\/p>\n\n\n\n<p>Dessa forma, no artigo de hoje esmiu\u00e7aremos os principais detalhes de uma dessas propriedades: a atomicidade.<\/p>\n\n\n\n<p>Sendo assim, <strong>o objetivo do presente artigo \u00e9 apresentar para voc\u00eas um resumo sobre a propriedade atomicidade em bancos de dados<\/strong>.<\/p>\n\n\n\n<p>Isso, com o intuito de ajud\u00e1-los na prepara\u00e7\u00e3o para as excelentes oportunidades dispon\u00edveis atualmente na \u00e1rea de concursos p\u00fablicos em nosso pa\u00eds!<\/p>\n\n\n\n<p>Preparados!?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Introdu\u00e7\u00e3o \u2013 Banco de Dados: Propriedade Atomicidade<\/h2>\n\n\n\n<p><strong>A propriedade atomicidade, como j\u00e1 explicado anteriormente, \u00e9 uma das quatro propriedades que devem ser impostas pelos m\u00e9todos de controle de concorr\u00eancia e recupera\u00e7\u00e3o do Sistema Gerenciador de Bancos de Dados \u2013 SGBD<\/strong>.<\/p>\n\n\n\n<p>A presen\u00e7a dessas propriedades, como a atomicidade, garante que as transa\u00e7\u00f5es sejam realizadas de maneira adequada.<\/p>\n\n\n\n<p>Vista essa breve introdu\u00e7\u00e3o, vejamos agora os demais detalhes que envolvem essa importante propriedade para os bancos de dados: a atomicidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O Que \u00e9 Uma Transa\u00e7\u00e3o? \u2013 Banco de Dados: Propriedade Atomicidade<\/h2>\n\n\n\n<p>Antes de adentrarmos no estudo da propriedade atomicidade, \u00e9 importante conhecermos o que \u00e9 uma <a href=\"https:\/\/www.alura.com.br\/artigos\/transacoes-no-sql-mantendo-os-dados-integros\" target=\"_blank\" rel=\"noreferrer noopener\">transa\u00e7\u00e3o<\/a> no \u00e2mbito dos bancos de dados.<\/p>\n\n\n\n<p>Assim, <strong>uma transa\u00e7\u00e3o \u00e9 um programa em execu\u00e7\u00e3o ou um processo que inclui um ou diversos acessos ou opera\u00e7\u00f5es em um banco de dados<\/strong>.<\/p>\n\n\n\n<p>Dessa forma, nada mais \u00e9, por exemplo, do que uma leitura, exclus\u00e3o ou atualiza\u00e7\u00e3o de dados contidos em um banco de dados, ou seja, <strong>a transa\u00e7\u00e3o \u00e9 uma unidade l\u00f3gica de um processo que executa um determinado conjunto de opera\u00e7\u00f5es em um banco de dados espec\u00edfico<\/strong>.<\/p>\n\n\n\n<p>Visto o que \u00e9 uma transa\u00e7\u00e3o, vamos adiante em nosso estudo acerca da propriedade atomicidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Propriedade Atomicidade \u2013 Principais Caracter\u00edsticas<\/h2>\n\n\n\n<p>Dentre as quatro propriedades que devem estar presentes em uma transa\u00e7\u00e3o de um banco de dados, <strong>a atomicidade \u00e9 aquela que assegura que a transa\u00e7\u00e3o deve ser encarada como uma unidade de processamento at\u00f4mica<\/strong>.<\/p>\n\n\n\n<p>Assim, <strong>a transa\u00e7\u00e3o deve ser vista como uma unidade indivis\u00edvel, ou seja, ou \u00e9 totalmente realizada ou n\u00e3o o \u00e9<\/strong> \u2013 em outras palavras, a propriedade atomicidade demanda que uma transa\u00e7\u00e3o seja executada at\u00e9 o fim.<\/p>\n\n\n\n<p>Dessa forma, <strong>no caso da ocorr\u00eancia de uma falha no sistema durante uma transa\u00e7\u00e3o, por exemplo, os efeitos dessa transa\u00e7\u00e3o precisam ser desfeitos, o que \u00e9 feito por meio do comando \u201crollback\u201d<\/strong>, que reverte uma transa\u00e7\u00e3o ao come\u00e7o da transa\u00e7\u00e3o ou a um ponto de salvamento anterior.<\/p>\n\n\n\n<p>Por outro lado, <strong>na inexist\u00eancia de falha no sistema, a transa\u00e7\u00e3o deve ser confirmada e gravada no banco de dados, o que \u00e9 realizado por meio do comando \u201ccommit\u201d<\/strong>.<\/p>\n\n\n\n<p>Frisa-se, por fim, que <strong>o respons\u00e1vel por garantir a propriedade atomicidade, no \u00e2mbito de um banco de dados, \u00e9 o subsistema de recupera\u00e7\u00e3o de transa\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Assim, <strong>guarde essas principais caracter\u00edsticas da propriedade atomicidade:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A transa\u00e7\u00e3o deve ser encarada como uma unidade at\u00f4mica;<\/strong><\/li>\n\n\n\n<li><strong>A transa\u00e7\u00e3o deve ser realizada at\u00e9 o fim ou n\u00e3o deve ser realizada de jeito nenhum;<\/strong><\/li>\n\n\n\n<li><strong>O comando \u201ccommit\u201d confirma a transa\u00e7\u00e3o;<\/strong><\/li>\n\n\n\n<li><strong>O comando \u201crollback\u201d reverte a transa\u00e7\u00e3o; e<\/strong><\/li>\n\n\n\n<li><strong>O subsistema de recupera\u00e7\u00e3o \u00e9 o respons\u00e1vel por garantir a propriedade atomicidade.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Com os detalhes que vimos acima j\u00e1 \u00e9 poss\u00edvel resolver a imensa maioria das quest\u00f5es que exploram o tema atomicidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Considera\u00e7\u00f5es Finais &#8211; Banco de Dados: Propriedade Atomicidade<\/h2>\n\n\n\n<p>Dessa forma, chegamos ao final do nosso resumo sobre a propriedade atomicidade no \u00e2mbito dos bancos de dados.<\/p>\n\n\n\n<p>Como vimos, \u00e9 um assunto n\u00e3o muito extenso, mas que \u00e9 comumente \u00e9 cobrado nas provas que envolvem a disciplina de Tecnologia da Informa\u00e7\u00e3o. Assim, n\u00e3o deixe de estudar essa importante propriedade das transa\u00e7\u00f5es em bancos de dados: a atomicidade.<\/p>\n\n\n\n<p>No entanto, <strong>para se preparar bem para as provas, recomendamos n\u00e3o s\u00f3 a resolu\u00e7\u00e3o de diversas quest\u00f5es, mas tamb\u00e9m o uso de um material de estudo de qualidade, como os oferecidos pelo Estrat\u00e9gia Concursos, <\/strong><strong>dispon\u00edveis por meio do link ao final deste artigo.<\/strong><\/p>\n\n\n\n<p>Frisamos, ainda, que o presente resumo sobre a propriedade atomicidade deve ser utilizado como um balizador em seus estudos, e n\u00e3o como material principal, haja vista que nem todos os detalhes acerca da propriedade atomicidade puderam ser abordados.<\/p>\n\n\n\n<p>Sendo assim, hoje era o que t\u00ednhamos para apresentar!<\/p>\n\n\n\n<p>Um grande abra\u00e7o,<\/p>\n\n\n\n<p>Leonardo Coelho Br\u00fcggemann<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Conhe\u00e7a as Assinaturas do Estrat\u00e9gia Concursos \u2013 Banco de Dados: Propriedade Atomicidade<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Planos de 1 ou 2 Anos: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" target=\"_blank\" rel=\"noreferrer noopener\">ASSINE AGORA<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos Abertos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banco de Dados: Propriedade Atomicidade &#8211; Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade. Ol\u00e1, pessoal! Tudo certo com voc\u00eas!? A disciplina Tecnologia da Informa\u00e7\u00e3o tem sido cada vez mais cobrada nos editais de concursos p\u00fablicos, especialmente no que se refere aos concursos para as \u00e1reas fiscal e de controle, [&hellip;]<\/p>\n","protected":false},"author":2392,"featured_media":953107,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220180,220184,1983,220182,220183],"tags":[221438,1193,40,221439],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1212620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-controle-gestao","category-engenharias-e-ti","category-fiscal-estadual","category-fiscal-federal","category-fiscal-municipal","tag-atomicidade","tag-banco-de-dados","tag-concurso","tag-propriedade-das-transacoes","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Banco de Dados: Propriedade Atomicidade<\/title>\n<meta name=\"description\" content=\"Banco de Dados: Propriedade Atomicidade - Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco de Dados: Propriedade Atomicidade\" \/>\n<meta property=\"og:description\" content=\"Banco de Dados: Propriedade Atomicidade - Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Coelho Br\u00fcggemann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Coelho Br\u00fcggemann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/\"},\"author\":{\"name\":\"Leonardo Coelho Br\u00fcggemann\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9cca55b0a994ead7534957759c97a815\"},\"headline\":\"Banco de Dados: Propriedade Atomicidade\",\"datePublished\":\"2023-06-05T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/\"},\"wordCount\":889,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg\",\"keywords\":[\"Atomicidade\",\"banco de dados\",\"Concurso\",\"Propriedade das Transa\u00e7\u00f5es\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)\",\"Engenharias e TI\",\"Fiscal - Estadual (ICMS)\",\"Fiscal - Federal (RFB e AFT)\",\"Fiscal - Municipal (ISS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/\",\"name\":\"Banco de Dados: Propriedade Atomicidade\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg\",\"datePublished\":\"2023-06-05T17:00:00+00:00\",\"description\":\"Banco de Dados: Propriedade Atomicidade - Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg\",\"width\":626,\"height\":404},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco de Dados: Propriedade Atomicidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9cca55b0a994ead7534957759c97a815\",\"name\":\"Leonardo Coelho Br\u00fcggemann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1bfe31ed277514f55cfb4e96c670dd08662f5c13907392c1584353c7e6cc90da?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1bfe31ed277514f55cfb4e96c670dd08662f5c13907392c1584353c7e6cc90da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1bfe31ed277514f55cfb4e96c670dd08662f5c13907392c1584353c7e6cc90da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Coelho Br\u00fcggemann\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardo-bruggemannoutlook-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Banco de Dados: Propriedade Atomicidade","description":"Banco de Dados: Propriedade Atomicidade - Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Banco de Dados: Propriedade Atomicidade","og_description":"Banco de Dados: Propriedade Atomicidade - Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-06-05T17:00:00+00:00","og_image":[{"width":626,"height":404,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg","type":"image\/jpeg"}],"author":"Leonardo Coelho Br\u00fcggemann","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Leonardo Coelho Br\u00fcggemann","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/"},"author":{"name":"Leonardo Coelho Br\u00fcggemann","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9cca55b0a994ead7534957759c97a815"},"headline":"Banco de Dados: Propriedade Atomicidade","datePublished":"2023-06-05T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/"},"wordCount":889,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg","keywords":["Atomicidade","banco de dados","Concurso","Propriedade das Transa\u00e7\u00f5es"],"articleSection":["Concursos P\u00fablicos","Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)","Engenharias e TI","Fiscal - Estadual (ICMS)","Fiscal - Federal (RFB e AFT)","Fiscal - Municipal (ISS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/","name":"Banco de Dados: Propriedade Atomicidade","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg","datePublished":"2023-06-05T17:00:00+00:00","description":"Banco de Dados: Propriedade Atomicidade - Veja neste artigo um resumo com os principais pontos relacionados a essa propriedade.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2022\/01\/24113925\/pol-dados-abertos-2-1.jpg","width":626,"height":404},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/banco-dados-atomicidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Banco de Dados: Propriedade Atomicidade"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/9cca55b0a994ead7534957759c97a815","name":"Leonardo Coelho Br\u00fcggemann","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1bfe31ed277514f55cfb4e96c670dd08662f5c13907392c1584353c7e6cc90da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bfe31ed277514f55cfb4e96c670dd08662f5c13907392c1584353c7e6cc90da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bfe31ed277514f55cfb4e96c670dd08662f5c13907392c1584353c7e6cc90da?s=96&d=mm&r=g","caption":"Leonardo Coelho Br\u00fcggemann"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/leonardo-bruggemannoutlook-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1212620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2392"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1212620"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1212620\/revisions"}],"predecessor-version":[{"id":1212629,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1212620\/revisions\/1212629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/953107"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1212620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1212620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1212620"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1212620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}