{"id":1208289,"date":"2023-05-23T14:00:00","date_gmt":"2023-05-23T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1208289"},"modified":"2023-07-19T14:55:13","modified_gmt":"2023-07-19T17:55:13","slug":"o-que-e-lei-de-execucao-fiscal","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/","title":{"rendered":"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!"},"content":{"rendered":"\n<p>Aprenda neste artigo sobre a Lei 6.830\/80, a<strong> Lei de Execu\u00e7\u00e3o Fiscal<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"405\" height=\"293\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png\" alt=\"Lei de Execu\u00e7\u00e3o Fiscal 6.830\/80\" class=\"wp-image-1208307\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png 405w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290-300x217.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290-150x109.png 150w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/><\/figure>\n\n\n\n<p>Ol\u00e1, pessoal! Tudo bem com voc\u00eas?<\/p>\n\n\n\n<p>A <strong>execu\u00e7\u00e3o fiscal<\/strong> ocorre quando a <strong>Fazenda P\u00fablica<\/strong> aciona o<strong> Poder Judici\u00e1rio<\/strong> para demandar os pagamentos das <strong>d\u00edvidas ativas<\/strong> que pessoas, f\u00edsicas ou jur\u00eddicas, possuem com o Poder P\u00fablico.<\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Assim, a <strong>Lei 6.830\/80<\/strong>, a chamada<strong> Lei de Execu\u00e7\u00e3o Fiscal<\/strong>, foi criada para regulamentar os procedimentos a serem seguidos durante a <strong>cobran\u00e7a judicial das d\u00edvidas ativas<\/strong> dos cidad\u00e3os com o Estado.<\/mark><\/p>\n\n\n\n<div id=\"boxes\" class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm\">\n<div id=\"box-assinatura\" class=\"banner-fiscal-01\">\n<h3 class=\"titulo-assinatura\">Carreiras Fiscais<\/h3>\n<p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n<div class=\"box-botao\"><a class=\"btn-assinatura\" role=\"button\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/area-fiscal-fiscos-estaduais-e-municipais-410\/\" target=\"_blank\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a><\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-e-a-lei-de-execucao-fiscal\">O que \u00e9 a lei de Execu\u00e7\u00e3o Fiscal?<\/h2>\n\n\n\n<p>Como j\u00e1 citamos, a Lei de Execu\u00e7\u00e3o Fiscal disp\u00f5e sobre a<strong> cobran\u00e7a judicial<\/strong> da <strong>d\u00edvida ativa <\/strong>da Uni\u00e3o, dos Estados, do Distrito Federal, e dos Munic\u00edpios, bem como das suas respectivas autarquias.<\/p>\n\n\n\n<p>Assim, qualquer valor, cuja cobran\u00e7a seja atribu\u00edda \u00e0s entidades acima, ser\u00e1 considerado d\u00edvida ativa da Fazenda P\u00fablica.<\/p>\n\n\n\n<p>\u00c9 importante destacar que a d\u00edvida ativa da Fazenda n\u00e3o \u00e9 constitu\u00edda apenas pelas d\u00edvidas <strong>tribut\u00e1rias<\/strong>, mas tamb\u00e9m pelas <strong>n\u00e3o tribut\u00e1rias<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-inscricao-da-divida-ativa\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Inscri\u00e7\u00e3o da d\u00edvida ativa<\/mark><\/h3>\n\n\n\n<p>Primeiramente, para um d\u00e9bito ser considerado d\u00edvida ativa, ele precisa ser <strong>inscrito <\/strong>nos \u00f3rg\u00e3os competentes, para apurar a <strong>liquidez <\/strong>e <strong>certeza <\/strong>do cr\u00e9dito.<\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Tal inscri\u00e7\u00e3o <strong>suspender\u00e1 a prescri\u00e7\u00e3o<\/strong>, por <strong>180 dias<\/strong>, ou at\u00e9 a distribui\u00e7\u00e3o da execu\u00e7\u00e3o fiscal, se esta ocorrer antes deste prazo.<\/mark><\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Contudo, \u00e9 importante salientar que o STJ j\u00e1 decidiu que essa inscri\u00e7\u00e3o suspende apenas as <strong>d\u00edvidas n\u00e3o tribut\u00e1rias<\/strong>, visto que a suspens\u00e3o de d\u00edvida tribut\u00e1ria necessita de previs\u00e3o em lei complementar, e n\u00e3o em mera lei ordin\u00e1ria.<\/mark><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-responsaveis-pela-divida-ativa\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Respons\u00e1veis pela d\u00edvida ativa<\/mark><\/h3>\n\n\n\n<p>A <strong>execu\u00e7\u00e3o <\/strong>da d\u00edvida ativa poder\u00e1 ser realizada em face n\u00e3o apenas do <strong>devedor<\/strong>, mas tamb\u00e9m contra:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>o fiador;<\/li>\n\n\n\n<li>o esp\u00f3lio;<\/li>\n\n\n\n<li>a massa;<\/li>\n\n\n\n<li>o respons\u00e1vel por d\u00edvidas, tribut\u00e1rias ou n\u00e3o, de pessoas f\u00edsicas ou pessoas jur\u00eddicas de direito privado; e<\/li>\n\n\n\n<li>os sucessores a qualquer t\u00edtulo.<\/li>\n<\/ul>\n\n\n\n<p>Entretanto, todos estes citados acima poder\u00e3o <strong>nomear <\/strong>bens livres e desembara\u00e7ados do devedor, para a satisfa\u00e7\u00e3o da d\u00edvida. Contudo, caso os bens do devedor sejam <strong>insuficientes <\/strong>para satisfazer a d\u00edvida, os bens dos <strong>respons\u00e1veis <\/strong>tamb\u00e9m ficar\u00e3o sujeitos \u00e0 execu\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-peticao-inicial-lei-de-execucao-fiscal\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Peti\u00e7\u00e3o inicial &#8211; Lei de Execu\u00e7\u00e3o Fiscal<\/mark><\/h4>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 peti\u00e7\u00e3o inicial, ela apenas dever\u00e1 <strong>indicar <\/strong>o <strong>juiz <\/strong>a quem \u00e9 dirigida, o <strong>pedido<\/strong>, al\u00e9m do requerimento para a <strong>cita\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>\u00c9 importante destacar que a <strong>produ\u00e7\u00e3o de provas<\/strong> pela Fazenda P\u00fablica <strong>independe <\/strong>de requerimento na peti\u00e7\u00e3o inicial. Assim, mesmo se n\u00e3o houver a solicita\u00e7\u00e3o na peti\u00e7\u00e3o, a Fazenda poder\u00e1 produzir as provas que julgar necess\u00e1rias.<\/p>\n\n\n\n<p>Ap\u00f3s a cita\u00e7\u00e3o pelo juiz, o executado dever\u00e1, no prazo de <strong>5 dias<\/strong>, <strong>pagar <\/strong>a d\u00edvida indicada na Certid\u00e3o de D\u00edvida Ativa, ou garantir a execu\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-penhora-lei-de-execucao-fiscal\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Penhora &#8211; Lei de Execu\u00e7\u00e3o Fiscal<\/mark><\/h4>\n\n\n\n<p>Caso <strong>n\u00e3o haja o pagamento<\/strong> da d\u00edvida no prazo citado acima, tampouco a garantia da execu\u00e7\u00e3o, poder\u00e1 ser realizada <strong>penhora <\/strong>de qualquer bem do executado, <strong>salvo <\/strong>aqueles considerados por lei como <strong>absolutamente impenhor\u00e1veis.<\/strong><\/p>\n\n\n\n<p>Contudo, a penhora dever\u00e1 seguir uma <strong>ordem <\/strong>entre os bens, a qual pode ser vista abaixo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>dinheiro;<\/li>\n\n\n\n<li>t\u00edtulo da d\u00edvida p\u00fablica, bem como t\u00edtulo de cr\u00e9dito, que tenham cota\u00e7\u00e3o em bolsa;<\/li>\n\n\n\n<li>pedras e metais preciosos;<\/li>\n\n\n\n<li>im\u00f3veis;<\/li>\n\n\n\n<li>navios e aeronaves;<\/li>\n\n\n\n<li>ve\u00edculos;<\/li>\n\n\n\n<li>m\u00f3veis ou semoventes; e<\/li>\n\n\n\n<li>direitos e a\u00e7\u00f5es.<\/li>\n<\/ul>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>A SABER: <\/strong>De maneira <strong>excepcional<\/strong>, a penhora tamb\u00e9m poder\u00e1 ser feita sobre <strong>estabelecimento <\/strong>comercial, industrial ou agr\u00edcola, bem como em <strong>planta\u00e7\u00f5es <\/strong>ou <strong>edif\u00edcios <\/strong>em constru\u00e7\u00e3o.<\/mark><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-embargos-lei-de-execucao-fiscal\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Embargos &#8211; Lei de Execu\u00e7\u00e3o Fiscal<\/mark><\/h4>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">O <strong>executado <\/strong>ter\u00e1 o direito de <strong>oferecer embargos<\/strong>, dentro do prazo de <strong>30 dias,<\/strong> contados:<\/mark><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>do dep\u00f3sito;<\/li>\n\n\n\n<li>da juntada da prova da fian\u00e7a banc\u00e1ria ou do seguro garantia;&nbsp;&nbsp;<\/li>\n\n\n\n<li>da intima\u00e7\u00e3o da penhora.<\/li>\n<\/ul>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><strong>EXCE\u00c7\u00c3O<\/strong>: Contudo, \u00e9 importante destacar que <strong>n\u00e3o ser\u00e3o admitidos<\/strong> os embargos oferecidos <strong>antes <\/strong>de <strong>garantida a execu\u00e7\u00e3o<\/strong>.<\/mark><\/p>\n\n\n\n<p><a><\/a>Durante o prazo dos embargos, \u00e9 dever do executado alegar toda mat\u00e9ria \u00fatil \u00e0 defesa, al\u00e9m de requerer provas e juntar aos autos os documentos e rol de testemunhas.<\/p>\n\n\n\n<p>Ap\u00f3s o recebimento dos embargos, a Fazenda poder\u00e1 <strong>impugn\u00e1-los<\/strong>, no prazo de <strong>30 dias<\/strong>, a partir da intima\u00e7\u00e3o, realizando-se, em seguida, audi\u00eancia de instru\u00e7\u00e3o e julgamento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-demais-disposicoes-da-lei-de-execucao-fiscal\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Demais disposi\u00e7\u00f5es da Lei de Execu\u00e7\u00e3o Fiscal<\/mark><\/h2>\n\n\n\n<p>No caso de a inscri\u00e7\u00e3o da d\u00edvida ativa ser <strong>cancelada antes <\/strong>da decis\u00e3o de <strong>primeira inst\u00e2ncia<\/strong>, a execu\u00e7\u00e3o fiscal ser\u00e1 <strong>extinta<\/strong>, sem qualquer \u00f4nus para as partes.<\/p>\n\n\n\n<p>Quando houver processos de <strong>fal\u00eancia<\/strong>, concordata, liquida\u00e7\u00e3o, invent\u00e1rio, arrolamento ou concurso de credores, n\u00e3o poder\u00e1 ser autorizada nenhuma aliena\u00e7\u00e3o, mesmo que judicialmente, caso n\u00e3o haja prova de quita\u00e7\u00e3o da D\u00edvida Ativa ou a concord\u00e2ncia da Fazenda P\u00fablica.<\/p>\n\n\n\n<p>Por fim, poder\u00e1 ser <strong>suspensa a execu\u00e7\u00e3o judicial<\/strong>, pelo juiz, enquanto n\u00e3o for localizado o devedor ou encontrados bens penhor\u00e1veis. Al\u00e9m disso, nesses casos, tamb\u00e9m n\u00e3o correr\u00e1 o prazo de prescri\u00e7\u00e3o.<\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Caso n\u00e3o sejam localizados o devedor ou bens penhor\u00e1veis, dentro do prazo de <strong>1 ano,<\/strong> os autos ser\u00e3o <strong>arquivados <\/strong>por determina\u00e7\u00e3o do juiz.<\/mark><\/p>\n\n\n\n<p>Contudo, caso sejam encontrados ap\u00f3s esse prazo, os autos ser\u00e3o <strong>desarquivados <\/strong>e a execu\u00e7\u00e3o continuar\u00e1.<\/p>\n\n\n\n<p>Bom, pessoal! Chegamos ao final do nosso artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal.<\/p>\n\n\n\n<p>Caso queira se preparar para chegar&nbsp;<strong>competitivo&nbsp;<\/strong>nesta prova, invista nos <a href=\"https:\/\/www.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>cursos do Estrat\u00e9gia Concursos<\/strong><\/a>. L\u00e1 voc\u00ea encontrar\u00e1&nbsp;<strong>aulas completas e detalhadas, com os melhores professores do mercado<\/strong>.<\/p>\n\n\n\n<p>Conhe\u00e7a tamb\u00e9m o&nbsp;<a href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sistema de Quest\u00f5es do Estrat\u00e9gia<\/strong><\/a>. Afinal, a \u00fanica maneira de&nbsp;<strong>consolidar o conte\u00fado&nbsp;<\/strong>de maneira satisfat\u00f3ria \u00e9 atrav\u00e9s da&nbsp;<strong>resolu\u00e7\u00e3o de quest\u00f5es.<\/strong><\/p>\n\n\n\n<p>Bons estudos a todos e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos Abertos<\/mark><\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\">Concursos 2023<\/mark><\/strong><\/a><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div><\/div><\/div>\n\n\n\n<div id=\"boxes\" class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm\">\n<div id=\"box-assinatura\" class=\"banner-fiscal-01\">\n<h3 class=\"titulo-assinatura\">Carreiras Fiscais<\/h3>\n<p class=\"subtitulo-assinatura\">Conhe\u00e7a os cursos<\/p>\n<div class=\"box-botao\"><a class=\"btn-assinatura\" role=\"button\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/area-fiscal-fiscos-estaduais-e-municipais-410\/\" target=\"_blank\" rel=\"noopener noreferrer\">Conhe\u00e7a mais<\/a><\/div>\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aprenda neste artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal. Ol\u00e1, pessoal! Tudo bem com voc\u00eas? A execu\u00e7\u00e3o fiscal ocorre quando a Fazenda P\u00fablica aciona o Poder Judici\u00e1rio para demandar os pagamentos das d\u00edvidas ativas que pessoas, f\u00edsicas ou jur\u00eddicas, possuem com o Poder P\u00fablico. Assim, a Lei 6.830\/80, a chamada Lei de [&hellip;]<\/p>\n","protected":false},"author":1976,"featured_media":1208307,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,1983,220182,220183],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1208289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-estadual","category-fiscal-federal","category-fiscal-municipal","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!<\/title>\n<meta name=\"description\" content=\"Aprenda neste artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal, sobre a cobran\u00e7a judicial de D\u00edvida Ativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!\" \/>\n<meta property=\"og:description\" content=\"Aprenda neste artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal, sobre a cobran\u00e7a judicial de D\u00edvida Ativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-23T17:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-19T17:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png\" \/>\n\t<meta property=\"og:image:width\" content=\"405\" \/>\n\t<meta property=\"og:image:height\" content=\"293\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kassio Henrique Sobral Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kassio Henrique Sobral Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/\"},\"author\":{\"name\":\"Kassio Henrique Sobral Rocha\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5\"},\"headline\":\"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!\",\"datePublished\":\"2023-05-23T17:00:00+00:00\",\"dateModified\":\"2023-07-19T17:55:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/\"},\"wordCount\":1082,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Estadual (ICMS)\",\"Fiscal - Federal (RFB e AFT)\",\"Fiscal - Municipal (ISS)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/\",\"name\":\"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png\",\"datePublished\":\"2023-05-23T17:00:00+00:00\",\"dateModified\":\"2023-07-19T17:55:13+00:00\",\"description\":\"Aprenda neste artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal, sobre a cobran\u00e7a judicial de D\u00edvida Ativa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png\",\"width\":405,\"height\":293,\"caption\":\"Lei 6.830\/80: A Lei de Execu\u00e7\u00e3o Fiscal.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5\",\"name\":\"Kassio Henrique Sobral Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g\",\"caption\":\"Kassio Henrique Sobral Rocha\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/kassio-rochayahoo-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!","description":"Aprenda neste artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal, sobre a cobran\u00e7a judicial de D\u00edvida Ativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!","og_description":"Aprenda neste artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal, sobre a cobran\u00e7a judicial de D\u00edvida Ativa.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-05-23T17:00:00+00:00","article_modified_time":"2023-07-19T17:55:13+00:00","og_image":[{"width":405,"height":293,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png","type":"image\/png"}],"author":"Kassio Henrique Sobral Rocha","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Kassio Henrique Sobral Rocha","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/"},"author":{"name":"Kassio Henrique Sobral Rocha","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5"},"headline":"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!","datePublished":"2023-05-23T17:00:00+00:00","dateModified":"2023-07-19T17:55:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/"},"wordCount":1082,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png","articleSection":["Concursos P\u00fablicos","Fiscal - Estadual (ICMS)","Fiscal - Federal (RFB e AFT)","Fiscal - Municipal (ISS)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/","name":"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png","datePublished":"2023-05-23T17:00:00+00:00","dateModified":"2023-07-19T17:55:13+00:00","description":"Aprenda neste artigo sobre a Lei 6.830\/80, a Lei de Execu\u00e7\u00e3o Fiscal, sobre a cobran\u00e7a judicial de D\u00edvida Ativa.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/04\/28093028\/image-290.png","width":405,"height":293,"caption":"Lei 6.830\/80: A Lei de Execu\u00e7\u00e3o Fiscal."},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/o-que-e-lei-de-execucao-fiscal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 lei de execu\u00e7\u00e3o fiscal? Confira!"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f0c830e07cfe11c231c0ea5dbb036df5","name":"Kassio Henrique Sobral Rocha","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d10350cbdad043facd8ec77a377f86f9026afee3348e463b04854fd4490ce759?s=96&d=mm&r=g","caption":"Kassio Henrique Sobral Rocha"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/kassio-rochayahoo-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1208289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1976"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1208289"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1208289\/revisions"}],"predecessor-version":[{"id":1251470,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1208289\/revisions\/1251470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1208307"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1208289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1208289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1208289"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1208289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}