{"id":1195693,"date":"2023-05-09T14:00:00","date_gmt":"2023-05-09T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1195693"},"modified":"2023-04-24T15:20:26","modified_gmt":"2023-04-24T18:20:26","slug":"decadencia-resumo","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/","title":{"rendered":"Decad\u00eancia Penal: Resumo para Carreiras Policiais"},"content":{"rendered":"\n<p><\/p><p><\/p><p><span style=\"font-size: revert; color: initial;\">No presente resumo sobre<\/span><strong style=\"font-size: revert; color: initial;\"> a decad\u00eancia<\/strong><span style=\"font-size: revert; color: initial;\"> continuaremos nossa s\u00e9rie de artigos sobre as causas de extin\u00e7\u00e3o da punibilidade, <\/span><span style=\"background-color: rgba(0, 0, 0, 0.2); color: initial; font-size: revert;\">tema de alta incid\u00eancia nos concursos das carreiras policiais.    <\/span><\/p><span style=\"color: initial; font-size: revert;\">Os concursos da \u00e1rea de Seguran\u00e7a P\u00fablica prometem in\u00fameras vagas neste ano. <\/span>   <p><span style=\"font-size: revert; color: initial;\">Confira <\/span><a style=\"font-size: revert;\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-de-policia\/\">aqui <\/a><span style=\"font-size: revert; color: initial;\">o levantamento realizado pela equipe do Estrat\u00e9gia.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"506\" data-id=\"1153174\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/16103826\/policia-cientifica-go-1024x506.jpeg\" alt=\"Decad\u00eancia: Resumo para Carreiras Policiais\" class=\"wp-image-1153174\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/16103826\/policia-cientifica-go-1024x506.jpeg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/16103826\/policia-cientifica-go-300x148.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/16103826\/policia-cientifica-go-768x380.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/16103826\/policia-cientifica-go-610x302.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/16103826\/policia-cientifica-go-150x74.jpeg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/16103826\/policia-cientifica-go.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>T\u00f3picos a serem vistos<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Aspectos Introdut\u00f3rios<\/li>\n\n\n\n<li>Contagem do Prazo<\/li>\n\n\n\n<li>Quest\u00f5es de Concurso<\/li>\n<\/ul>\n\n\n\n<p>Vamos l\u00e1.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-aspectos-introdutorios\"><em>ASPECTOS INTRODUT\u00d3RIOS<\/em><\/h2>\n\n\n\n<p><\/p><p><\/p><p><span style=\"font-size: revert; color: initial;\">O C\u00f3digo Penal, em seu art. 107, inciso IV, assim disp\u00f5e:<\/span> <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em><strong>A<\/strong>rt. 107 &#8211; Extingue-se a punibilidade:&nbsp;<\/em><\/p>\n\n\n\n<p><em>IV &#8211; pela prescri\u00e7\u00e3o, <strong>decad\u00eancia<\/strong> ou peremp\u00e7\u00e3o;<\/em><\/p>\n<\/blockquote>\n<\/blockquote>\n\n\n\n<p><span style=\"font-size: revert; color: initial;\">Dessa forma, inicialmente, cabe destacar a natureza jur\u00eddica da decad\u00eancia de <\/span><strong style=\"font-size: revert; color: initial;\">causa extintiva da punibilidade <\/strong><span style=\"font-size: revert; color: initial;\">do agente.<\/span> <\/p>\n\n\n\n<p>Consiste em uma san\u00e7\u00e3o jur\u00eddica aplicada \u00e0 v\u00edtima por sua in\u00e9rcia.<\/p>\n\n\n\n<p>Em tal caso, o ofendido perder\u00e1 o seu direito de queixa ou de representa\u00e7\u00e3o em virtude do decurso de determinado lapso temporal.<\/p>\n\n\n\n<p>O instituto \u00e9 disciplinado pelo art. 103 do C\u00f3digo Penal, <em>in verbis:<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>Decad\u00eancia do direito de queixa ou de representa\u00e7\u00e3o<\/em><\/strong><\/p>\n\n\n\n<p><em>Art. 103 &#8211; Salvo disposi\u00e7\u00e3o expressa em contr\u00e1rio, o ofendido <strong>decai do direito de queixa ou de representa\u00e7\u00e3o se n\u00e3o o exerce dentro do prazo de 6 (seis) meses, contado do dia em que veio a saber quem \u00e9 o autor do crime<\/strong>, ou, <strong>no caso do \u00a7 3\u00ba do art. 100 deste C\u00f3digo, do dia em que se esgota o prazo para oferecimento da den\u00fancia.<\/strong>&nbsp;&nbsp;<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/1980-1988\/L7209.htm#art103\">(Reda\u00e7\u00e3o dada pela Lei n\u00ba 7.209, de 11.7.1984)<\/a><\/em><\/p>\n\n\n\n<p>Nota-se, assim, que o instituto se aplica \u00e0 <strong>a\u00e7\u00e3o penal privada e \u00e0 a\u00e7\u00e3o penal privada subsidi\u00e1ria da p\u00fablica<\/strong>(<em>art. 100<\/em>, <em>\u00a7 3\u00ba<\/em>, do CP), bem como \u00e0 <strong>a\u00e7\u00e3o penal p\u00fablica condicionada \u00e0 representa\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Refor\u00e7a-se que n\u00e3o h\u00e1 decad\u00eancia nos crimes de a\u00e7\u00e3o penal p\u00fablica incondicionada, bem como nos de a\u00e7\u00e3o penal p\u00fablica condicionada \u00e0 requisi\u00e7\u00e3o do Ministro da Justi\u00e7a.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-contagem-do-prazo-decadencia-penal\">CONTAGEM DO PRAZO &#8211; DECAD\u00caNCIA PENAL<\/h2>\n\n\n\n<p>Por ter a natureza jur\u00eddica de causa extintiva da punibilidade do agente(art.107 do CP),<strong> a decad\u00eancia segue a regra do art. 10 do C\u00f3digo Penal <\/strong>e n\u00e3o a do art. 798, &nbsp;\u00a7 1\u00ba , do CPP, incluindo-se na contagem o primeiro dia. Veja-se:<\/p>\n\n\n\n<p><em>Art. 10 &#8211; O dia do come\u00e7o inclui-se no c\u00f4mputo do prazo. Contam-se os dias, os meses e os anos pelo calend\u00e1rio comum.<\/em><\/p>\n\n\n\n<p>Destaca-se que <strong>o prazo de 6(seis) meses \u00e9 contado do dia em que o ofendido vem a saber quem \u00e9 o autor do crime<\/strong>(CP, art. 103). Nota-se que o prazo n\u00e3o \u00e9 contado da data do crime, mas sim da data do conhecimento da autoria por parte do ofendido.<\/p>\n\n\n\n<p>Nas li\u00e7\u00f5es de Rog\u00e9rio Greco(GRECO, Rog\u00e9rio.&nbsp;Curso de Direito Penal: Parte Geral.&nbsp;16 ed.&nbsp;Rio de Janeiro: Impetus, 2014):<\/p>\n\n\n\n<p><em>&#8220;No crime de les\u00e3o corporal de natureza culposa, cuja a\u00e7\u00e3o penal \u00e9 de iniciativa p\u00fablica condicionada \u00e0 representa\u00e7\u00e3o do ofendido, o prazo decadencial tem in\u00edcio a partir do momento em que o ofendido toma conhecimento de que foi v\u00edtima dessa infra\u00e7\u00e3o penal, a exemplo do que ocorre nos casos do chamado &#8220;erro m\u00e9dico&#8221;. Pode acontecer que a v\u00edtima tenha sofrido uma les\u00e3o corporal de natureza culposa, ap\u00f3s ter-se submetido a uma interven\u00e7\u00e3o m\u00e9dica qualquer, produzida em raz\u00e3o da imper\u00edcia do profissional, que, a todo custo, tentou ocult\u00e1-la. Mais tarde, mesmo depois de decorridos seis meses da primeira interven\u00e7\u00e3o na qual ocorreram as les\u00f5es, a v\u00edtima descobriu o suposto erro m\u00e9dico. A partir desse instante \u00e9 que se tem por iniciado o prazo decadencial.&#8221;<\/em><\/p>\n\n\n\n<p>Por fim, ressalta-se que,<strong> nos casos de a\u00e7\u00e3o penal privada subsidi\u00e1ria da p\u00fablica, o prazo de 6 meses ser\u00e1 contado do dia em que se esgota o prazo para oferecimento da den\u00fancia por parte do Minist\u00e9rio P\u00fablico<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-questoes-de-concurso\"><em>QUEST\u00d5ES DE CONCURSO<\/em><\/h2>\n\n\n\n<p><strong>CESPE\/CEBRASPE &#8211; ALE CE &#8211; Analista Legislativo &#8211; \u00c1rea Direito &#8211; 2021 &#8211; Adaptada<\/strong><\/p>\n\n\n\n<p>A decad\u00eancia opera-se ap\u00f3s in\u00e9rcia do interessado pelo decurso do prazo de seis meses depois da data de ci\u00eancia da autoria do delito<\/p>\n\n\n\n<p>Gabarito: C<\/p>\n\n\n\n<p><strong>CESPE\/CEBRASPE &#8211; PM AL &#8211; Soldado Combatente &#8211; 2018<\/strong><\/p>\n\n\n\n<p>Situa\u00e7\u00e3o hipot\u00e9tica: Maria, de 21 anos de idade, tendo sido, h\u00e1 um ano e dois meses, v\u00edtima de crime cuja a\u00e7\u00e3o penal se processa mediante queixa e tendo conseguido identificar, na oportunidade, o agressor, pretende, agora, oferecer queixa para obter a condena\u00e7\u00e3o do autor do crime. <\/p>\n\n\n\n<p>Assertiva: N\u00e3o ser\u00e1 poss\u00edvel ocorrer a condena\u00e7\u00e3o do criminoso, em raz\u00e3o da extin\u00e7\u00e3o da punibilidade pela decad\u00eancia.<\/p>\n\n\n\n<p>Gabarito: C<\/p>\n\n\n\n<p><strong>CESPE\/CEBRASPE &#8211; DPF &#8211; Escriv\u00e3o de Pol\u00edcia &#8211; 2013<\/strong><\/p>\n\n\n\n<p>A contagem do prazo para efeito da decad\u00eancia, causa extintiva da punibilidade, obedece aos crit\u00e9rios processuais penais, computando-se o dia do come\u00e7o. Todavia, se este recair em domingos ou feriados, o in\u00edcio do prazo ser\u00e1 o dia \u00fatil imediatamente subsequente.<\/p>\n\n\n\n<p>Gabarito: E<\/p>\n\n\n\n<p>Obs. A contagem do prazo de decad\u00eancia segue a regra do art. 10 do C\u00f3digo Penal, computando-se o dia do come\u00e7o, independentemente desse cair em domingo ou feriado. Aplica-se aqui a mesma l\u00f3gica do da contagem do prazo para as pris\u00f5es.<\/p>\n\n\n\n<p><em>Art. 10 &#8211; O dia do come\u00e7o inclui-se no c\u00f4mputo do prazo. Contam-se os dias, os meses e os anos pelo calend\u00e1rio comum.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-finalizando-decadencia\"><em>FINALIZANDO &#8211; DECAD\u00caNCIA<\/em><\/h2>\n\n\n\n<p> <span style=\"font-size: revert; color: initial;\">Chegamos ao fim do nosso resumo sobre o instituto da decad\u00eancia.   <\/span><\/p>\n\n\n\n<p><\/p><p><span style=\"font-size: revert; color: initial;\">Caso queira ter a mais completa prepara\u00e7\u00e3o para o seu concurso p\u00fablico, invista nos&nbsp;<\/span><a style=\"font-size: revert;\" href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\"><u>cursos completos&nbsp;<\/u><\/a><span style=\"font-size: revert; color: initial;\">do&nbsp;<\/span><strong style=\"font-size: revert; color: initial;\">Estrat\u00e9gia Concursos<\/strong><span style=\"font-size: revert; color: initial;\">.<\/span> <span style=\"font-size: revert; color: initial;\">L\u00e1 voc\u00ea encontrar\u00e1 tudo o que precisa para atingir o cargo dos seus sonhos.    <\/span>   <\/p><p><span style=\"font-size: revert; color: initial;\">Al\u00e9m disso, \u00e9 essencial acompanhar a evolu\u00e7\u00e3o dos seus estudos por meio do&nbsp;<\/span><a style=\"font-size: revert;\" href=\"https:\/\/questoes.estrategiaconcursos.com.br\/\">Sistema de Quest\u00f5es do Estrat\u00e9gia<\/a><span style=\"font-size: revert; color: initial;\">, n\u00e3o deixe para marcar o \u201cx\u201d somente no dia da prova.<\/span><\/p><span style=\"font-size: revert; color: initial; background-color: rgba(0, 0, 0, 0.2);\">Grande abra\u00e7o a todos.<\/span><span style=\"font-size: revert; color: initial;\">   <\/span>   <p><span style=\"background-color: rgba(0, 0, 0, 0.2); font-size: revert; color: initial;\">Victor Baio<\/span><\/p>\n\n\n\n<p><\/p><p><\/p><p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>   <p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No presente resumo sobre a decad\u00eancia continuaremos nossa s\u00e9rie de artigos sobre as causas de extin\u00e7\u00e3o da punibilidade, tema de alta incid\u00eancia nos concursos das carreiras policiais. Os concursos da \u00e1rea de Seguran\u00e7a P\u00fablica prometem in\u00fameras vagas neste ano. Confira aqui o levantamento realizado pela equipe do Estrat\u00e9gia. T\u00f3picos a serem vistos Vamos l\u00e1. ASPECTOS [&hellip;]<\/p>\n","protected":false},"author":2343,"featured_media":892545,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[220188,1988,220189,220190,220186,220187],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1195693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial-agente-penitenciario","category-policia","category-policial-guarda-civis","category-policial-peritos","category-policial-oficial","category-policial-pracas","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Decad\u00eancia Penal: Resumo para Carreiras Policiais<\/title>\n<meta name=\"description\" content=\"Decad\u00eancia. Fique por dentro dessa tema de alta relev\u00e2ncia para a sua aprova\u00e7\u00e3o nos concursos das Carreiras Policiais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decad\u00eancia Penal: Resumo para Carreiras Policiais\" \/>\n<meta property=\"og:description\" content=\"Decad\u00eancia. Fique por dentro dessa tema de alta relev\u00e2ncia para a sua aprova\u00e7\u00e3o nos concursos das Carreiras Policiais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-09T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Victor Baio do Carmo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victor Baio do Carmo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/\"},\"author\":{\"name\":\"Victor Baio do Carmo\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec\"},\"headline\":\"Decad\u00eancia Penal: Resumo para Carreiras Policiais\",\"datePublished\":\"2023-05-09T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/\"},\"wordCount\":1017,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg\",\"articleSection\":[\"Policial (Agente Penitenci\u00e1rio)\",\"Policial (Agente, Escriv\u00e3o e Investigador)\",\"Policial (Guardas Civis)\",\"Policial (Peritos, Papiloscopistas)\",\"Policial (PM\/BM - Oficial)\",\"Policial (PM\/BM - Pra\u00e7as)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/\",\"name\":\"Decad\u00eancia Penal: Resumo para Carreiras Policiais\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg\",\"datePublished\":\"2023-05-09T17:00:00+00:00\",\"description\":\"Decad\u00eancia. Fique por dentro dessa tema de alta relev\u00e2ncia para a sua aprova\u00e7\u00e3o nos concursos das Carreiras Policiais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Pena de multa: Resumo para Carreiras Policiais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decad\u00eancia Penal: Resumo para Carreiras Policiais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec\",\"name\":\"Victor Baio do Carmo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g\",\"caption\":\"Victor Baio do Carmo\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victorbaio93gmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Decad\u00eancia Penal: Resumo para Carreiras Policiais","description":"Decad\u00eancia. Fique por dentro dessa tema de alta relev\u00e2ncia para a sua aprova\u00e7\u00e3o nos concursos das Carreiras Policiais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/","og_locale":"pt_BR","og_type":"article","og_title":"Decad\u00eancia Penal: Resumo para Carreiras Policiais","og_description":"Decad\u00eancia. Fique por dentro dessa tema de alta relev\u00e2ncia para a sua aprova\u00e7\u00e3o nos concursos das Carreiras Policiais.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-05-09T17:00:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg","type":"image\/jpeg"}],"author":"Victor Baio do Carmo","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Victor Baio do Carmo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/"},"author":{"name":"Victor Baio do Carmo","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec"},"headline":"Decad\u00eancia Penal: Resumo para Carreiras Policiais","datePublished":"2023-05-09T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/"},"wordCount":1017,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg","articleSection":["Policial (Agente Penitenci\u00e1rio)","Policial (Agente, Escriv\u00e3o e Investigador)","Policial (Guardas Civis)","Policial (Peritos, Papiloscopistas)","Policial (PM\/BM - Oficial)","Policial (PM\/BM - Pra\u00e7as)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/","name":"Decad\u00eancia Penal: Resumo para Carreiras Policiais","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg","datePublished":"2023-05-09T17:00:00+00:00","description":"Decad\u00eancia. Fique por dentro dessa tema de alta relev\u00e2ncia para a sua aprova\u00e7\u00e3o nos concursos das Carreiras Policiais.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/10\/25144221\/concurso-policia-civil-mg-2018-1280x720-1.jpg","width":1280,"height":720,"caption":"Pena de multa: Resumo para Carreiras Policiais"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/decadencia-resumo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Decad\u00eancia Penal: Resumo para Carreiras Policiais"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/52a5e7b42bb3c34ccdf208f25a312eec","name":"Victor Baio do Carmo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/148fc18f2878ea373246778f423b66b836c3535ba972328844adc004c2a998d5?s=96&d=mm&r=g","caption":"Victor Baio do Carmo"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/victorbaio93gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1195693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2343"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1195693"}],"version-history":[{"count":3,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1195693\/revisions"}],"predecessor-version":[{"id":1206061,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1195693\/revisions\/1206061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/892545"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1195693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1195693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1195693"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1195693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}