{"id":1189546,"date":"2023-03-21T01:36:37","date_gmt":"2023-03-21T04:36:37","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1189546"},"modified":"2023-03-21T01:36:39","modified_gmt":"2023-03-21T04:36:39","slug":"informativo-stj-764-parte-2-comentado","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/","title":{"rendered":"Informativo STJ 764 (Parte 2) Comentado"},"content":{"rendered":"\n<p>Informativo n\u00ba 764 (Parte 2) do STJ\u00a0<strong>COMENTADO<\/strong>\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas!<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/21013614\/stj-764-parte-2.pdf\" rel=\"sponsored nofollow\">DOWNLOAD do PDF AQUI!<\/a><\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_khT2HzId-g4\"><div id=\"lyte_khT2HzId-g4\" data-src=\"\/\/i.ytimg.com\/vi\/khT2HzId-g4\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/khT2HzId-g4\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/khT2HzId-g4\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-empresarial\"><a>DIREITO EMPRESARIAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-responsabilidade-do-importador-nacional-pelos-valores-pagos-pelo-banco-confirmador-ao-exportador-estrangeiro-na-hipotese-de-insolvencia-do-banco-emissor-de-carta-de-credito-internacional\"><a>1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Responsabilidade do importador nacional pelos valores pagos pelo banco confirmador ao exportador estrangeiro, na hip\u00f3tese de insolv\u00eancia do banco emissor de carta de cr\u00e9dito internacional<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><strong><\/strong><\/p>\n\n\n\n<p>O importador nacional responde pelos valores pagos pelo banco confirmador ao exportador estrangeiro, na hip\u00f3tese de insolv\u00eancia do banco emissor de carta de cr\u00e9dito internacional (letter of credit &#8211; L\/C) emitida ao amparo de opera\u00e7\u00e3o de importa\u00e7\u00e3o.<\/p>\n\n\n\n<p>REsp 1.324.978-SP, Rel. Ministro Raul Ara\u00fajo, Quarta Turma, por unanimidade, julgado em 14\/2\/2023. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-1-situacao-fatica\"><a>1.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>A empresa brasileira Compas queria adquirir umas mercadorias no exterior (importar umas gr\u00e3-finagens). S\u00f3 que os exportadores estavam desconfiados do poder de pagamento da empresa. Para garantir a opera\u00e7\u00e3o, o Banco Brasa ent\u00e3o emitiu, por solicita\u00e7\u00e3o da empresa Compas, cartas de cr\u00e9dito internacional em benef\u00edcio dos exportadores. Para reafirmar o neg\u00f3cio, a financeira Califa Trust figurou como banco confirmador e efetivamente efetuou o pagamento das mercadorias adquiridas pela Compas dos exportadores estrangeiros.<\/p>\n\n\n\n<p>Por\u00e9m, o BACEN acabou intervindo no Banco Brasa, o que resultou na fal\u00eancia deste. Califa Trust ent\u00e3o requereu informa\u00e7\u00f5es acerca do pagamento das cartas, mas Compas negou a exist\u00eancia de rela\u00e7\u00e3o com o banco confirmador e alegou que os contratos e cartas foram firmados unicamente com o Banco Brasa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-2-analise-estrategica\"><a>1.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-1-ha-relacao-entre-importador-a-banco-confirmador\"><a>1.2.1.&nbsp;&nbsp;&nbsp;&nbsp; H\u00e1 rela\u00e7\u00e3o entre importador a banco confirmador<\/a>?<\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Com certeza!!!!<\/strong><\/p>\n\n\n\n<p><strong>A carta de cr\u00e9dito internacional (<em>letter of credit<\/em>) \u00e9 uma modalidade de cr\u00e9dito utilizada para viabilizar opera\u00e7\u00f5es de com\u00e9rcio internacional, envolvendo importa\u00e7\u00e3o e exporta\u00e7\u00e3o de mercadorias, a fim de GARANTIR o pagamento dos bens adquiridos no estrangeiro<\/strong>. Em geral, o importador (tomador ou proponente) contrata o cr\u00e9dito com uma institui\u00e7\u00e3o financeira (banco emitente), que emite as cartas de cr\u00e9dito e se responsabiliza pelo pagamento da transa\u00e7\u00e3o ao exportador (benefici\u00e1rio) e, ao final, o importador deve pagar os valores contratados diretamente ao banco emitente.<\/p>\n\n\n\n<p>Trata-se de um cr\u00e9dito document\u00e1rio, ou cr\u00e9dito documentado, uma vez que o pagamento dos valores contratados se vincula \u00e0 entrega, pelo exportador estrangeiro, dos documentos de embarque, que comprovam o cumprimento dos termos e condi\u00e7\u00f5es apostos na carta de cr\u00e9dito.<\/p>\n\n\n\n<p>No tocante \u00e0 quest\u00e3o, a Quarta Turma j\u00e1 se manifestou no sentido de que o cr\u00e9dito document\u00e1rio, ou cr\u00e9dito documentado, consiste &#8220;(&#8230;) no ajuste, geralmente, entre o comprador de mercadoria e institui\u00e7\u00e3o financeira, para que esta libere o cr\u00e9dito ao vendedor da mercadoria, mediante apresenta\u00e7\u00e3o dos documentos exigidos. Contrato caracterizado pela triangulariza\u00e7\u00e3o de transa\u00e7\u00f5es entre comprador, vendedor e institui\u00e7\u00e3o financeira, com libera\u00e7\u00e3o do cr\u00e9dito condicionada \u00e0 apresenta\u00e7\u00e3o da documenta\u00e7\u00e3o da venda, comumente chamado de vendor&#8221; (REsp n. 1.022.034\/SP, relator Ministro Luis Felipe Salom\u00e3o, Quarta Turma, julgado em 12\/3\/2013, DJe 18\/4\/2013).<\/p>\n\n\n\n<p>Adicionalmente, \u00e9 poss\u00edvel que as partes fa\u00e7am uso da figura de um segundo banco, normalmente domiciliado no pa\u00eds do exportador, chamado de banco confirmador, o que enseja dupla garantia de pagamento dos valores ao exportador. Trata-se de uma obriga\u00e7\u00e3o aut\u00f4noma na qual o banco confirmador se compromete a atender \u00e0s obriga\u00e7\u00f5es assumidas pelo banco emitente perante o exportador.<\/p>\n\n\n\n<p>No caso ora em exame, o banco confirmador, cumprindo suas obriga\u00e7\u00f5es e compromissos para com o banco emissor da carta de cr\u00e9dito e os benefici\u00e1rios exportadores, diante do inadimplemento do banco emitente, realizou os pagamentos diretamente aos exportadores estrangeiros, quitando a obriga\u00e7\u00e3o principal irrevog\u00e1vel e, assim, sub-rogou-se na condi\u00e7\u00e3o de credor inerente ao banco emissor perante o importador nacional, devedor principal, o qual recebeu as mercadorias importadas e nada comprovou haver quitado, at\u00e9 esta parte, seja junto ao banco emissor, seja junto aos exportadores estrangeiros.<\/p>\n\n\n\n<p>Cumpre ressaltar que, nos termos da UCP 500 (<em>Uniform Customs and Practice for Documentary Credits<\/em>), vigente \u00e0 \u00e9poca da contra\u00e7\u00e3o, que estabelece costumes e pr\u00e1ticas uniformes para cr\u00e9ditos document\u00e1rios, sendo amplamente adotada pelos bancos quanto \u00e0 delimita\u00e7\u00e3o de responsabilidades das partes envolvidas na contrata\u00e7\u00e3o de cr\u00e9ditos document\u00e1rios, ao autorizar ou solicitar outro banco para adicionar sua confirma\u00e7\u00e3o na carta de cr\u00e9dito, o banco emitente autoriza o banco confirmador, ao cumprir suas obriga\u00e7\u00f5es perante o benefici\u00e1rio, desde que os documentos apresentados aparentem estar em conformidade com os termos e condi\u00e7\u00f5es da carta de cr\u00e9dito, se comprometendo a reembols\u00e1-lo, o que constitui um compromisso adicional ao do banco emissor.<\/p>\n\n\n\n<p>Ainda, conforme disp\u00f5e a UCP 500, as cartas de cr\u00e9dito, por sua natureza, s\u00e3o transa\u00e7\u00f5es separadas dos contratos de compra venda ou de quaisquer outros contratos firmados durante a opera\u00e7\u00e3o, n\u00e3o estando os bancos vinculados por tais contratos, ainda que a carta de cr\u00e9dito fa\u00e7a refer\u00eancia a eles. Isso significa que o banco confirmador \u00e9 um t\u00edpico terceiro interessado, pois seu compromisso de cumprir com as obriga\u00e7\u00f5es decorrentes da carta de cr\u00e9dito n\u00e3o est\u00e1 sujeito a reclama\u00e7\u00f5es ou oposi\u00e7\u00e3o de exce\u00e7\u00f5es pessoais pelo tomador (importador nacional), em decorr\u00eancia de suas rela\u00e7\u00f5es com o banco emitente ou com o benefici\u00e1rio (exportador estrangeiro).<\/p>\n\n\n\n<p>Nesse contexto, considerando a cadeia de rela\u00e7\u00f5es existentes na contrata\u00e7\u00e3o do cr\u00e9dito document\u00e1rio, irrecus\u00e1vel a rela\u00e7\u00e3o jur\u00eddica que obriga a importadora, junto ao banco confirmador, sub-rogado nos direitos e obriga\u00e7\u00f5es do banco emitente, podendo este exigir o pagamento dos valores relativos \u00e0s cartas de cr\u00e9dito diretamente da importadora.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-1-2-2-resultado-final\"><a>1.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>O importador nacional responde pelos valores pagos pelo banco confirmador ao exportador estrangeiro, na hip\u00f3tese de insolv\u00eancia do banco emissor de carta de cr\u00e9dito internacional (letter of credit &#8211; L\/C) emitida ao amparo de opera\u00e7\u00e3o de importa\u00e7\u00e3o.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-do-consumidor\"><a>DIREITO DO CONSUMIDOR<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-requisitos-para-a-cobertura-do-tratamento-de-psicoterapia-sem-limite-de-sessoes\"><a>2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Requisitos para a cobertura do tratamento de psicoterapia sem limite de sess\u00f5es<\/a><\/h2>\n\n\n\n<p><strong>PROCESSO EM SEGREDO DE JUSTI\u00c7A<\/strong><strong><\/strong><\/p>\n\n\n\n<p>\u00c9 devida a cobertura do tratamento de psicoterapia, sem limite de sess\u00f5es, admitindo-se que est\u00e1 previsto no rol da ANS, nos seguintes termos: a) para o tratamento de autismo, n\u00e3o h\u00e1 mais limita\u00e7\u00e3o de sess\u00f5es no Rol; b) as psicoterapias pelo m\u00e9todo ABA est\u00e3o contempladas no Rol, na sess\u00e3o de psicoterapia; c) em relat\u00f3rio de recomenda\u00e7\u00e3o da Comiss\u00e3o Nacional de Incorpora\u00e7\u00e3o de Tecnologias no Sistema \u00danico de Sa\u00fade &#8211; CONITEC, de novembro de 2021, elucida-se que \u00e9 adequada a utiliza\u00e7\u00e3o do m\u00e9todo da An\u00e1lise do Comportamento Aplicada &#8211; ABA.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Marco Buzzi, Quarta Turma, por unanimidade, julgado em 12\/12\/2022, DJe 16\/12\/2022. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-1-situacao-fatica\"><a>2.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Raquel foi diagnosticada com uma doen\u00e7a que requer tratamento de psicoterapia, sem limite fixado de sess\u00f5es. Mas seu plano de sa\u00fade negou a cobertura sob a alega\u00e7\u00e3o de que tal modalidade de tratamento seria limitada a um n\u00famero de sess\u00f5es, n\u00e3o havendo previs\u00e3o que ampare a cobertura sem limite.<\/p>\n\n\n\n<p>* Processo sob segredo de justi\u00e7a. Caso imaginado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-2-analise-estrategica\"><a>2.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-1-devida-a-cobertura-sem-limite-de-sessoes\"><a>2.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Devida a cobertura sem limite de sess\u00f5es?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Desde que presentes os requisitos, SIM!!!!<\/strong><\/p>\n\n\n\n<p>A Quarta Turma do STJ, em julgamento realizado em dezembro de 2019, firmou entendimento no sentido de que <strong>o rol da ANS n\u00e3o pode ser considerado meramente exemplificativo, sob pena de se inviabilizar a sa\u00fade suplementar<\/strong>. A necessidade de cobertura de procedimentos ou medicamentos n\u00e3o previstos no rol da ANS deve ser observada CASO A CASO, podendo ser admitida, de forma excepcional, desde que amparada em crit\u00e9rios t\u00e9cnicos. N\u00e3o basta, portanto, apenas a prescri\u00e7\u00e3o do m\u00e9dico que acompanha o paciente, devendo ser observados, prioritariamente, os procedimentos e medicamentos previstos no rol de cobertura m\u00ednima.<\/p>\n\n\n\n<p>Nesse sentido, a Segunda Se\u00e7\u00e3o deste STJ, em recente julgamento (EREsps 1.886.929\/SP e 1.889.704\/SP) reafirmou o entendimento da Quarta Turma, fixando premissas que devem orientar a an\u00e1lise da controv\u00e9rsia. Especificamente quanto ao tratamento multidisciplinar para o TEA (transtorno do espectro autista), a orienta\u00e7\u00e3o consignada \u00e9 no sentido de ser devida a cobertura do tratamento de psicoterapia, sem limite de sess\u00f5es, admitindo-se que est\u00e1 previsto no rol da ANS, nos seguintes termos: &#8220;a) para o tratamento de autismo, n\u00e3o h\u00e1 mais limita\u00e7\u00e3o de sess\u00f5es no Rol; b) as psicoterapias pelo m\u00e9todo ABA est\u00e3o contempladas no Rol, na sess\u00e3o de psicoterapia; c) em relat\u00f3rio de recomenda\u00e7\u00e3o da Comiss\u00e3o Nacional de Incorpora\u00e7\u00e3o de Tecnologias no Sistema \u00danico de Sa\u00fade (CONITEC), de novembro de 2021, elucida-se que \u00e9 adequada a utiliza\u00e7\u00e3o do m\u00e9todo da An\u00e1lise do Comportamento Aplicada (ABA)&#8221;.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-2-2-2-resultado-final\"><a>2.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>\u00c9 devida a cobertura do tratamento de psicoterapia, sem limite de sess\u00f5es, admitindo-se que est\u00e1 previsto no rol da ANS, nos seguintes termos: a) para o tratamento de autismo, n\u00e3o h\u00e1 mais limita\u00e7\u00e3o de sess\u00f5es no Rol; b) as psicoterapias pelo m\u00e9todo ABA est\u00e3o contempladas no Rol, na sess\u00e3o de psicoterapia; c) em relat\u00f3rio de recomenda\u00e7\u00e3o da Comiss\u00e3o Nacional de Incorpora\u00e7\u00e3o de Tecnologias no Sistema \u00danico de Sa\u00fade &#8211; CONITEC, de novembro de 2021, elucida-se que \u00e9 adequada a utiliza\u00e7\u00e3o do m\u00e9todo da An\u00e1lise do Comportamento Aplicada &#8211; ABA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-convencoes-internacionais-e-dano-moral-no-transporte-aereo-internacional\"><a>3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Conven\u00e7\u00f5es internacionais e dano moral no transporte a\u00e9reo internacional.<\/a><\/h2>\n\n\n\n<p><a><strong>AGRAVO INTERNO NO RECURSO ESPECIAL<\/strong><\/a><\/p>\n\n\n\n<p>As Conven\u00e7\u00f5es de Vars\u00f3via e Montreal n\u00e3o regularam o dano moral no transporte a\u00e9reo internacional, ao qual deve ser aplicada a lei geral interna, no caso, o C\u00f3digo de Defesa do Consumidor.<\/p>\n\n\n\n<p>AgInt no REsp 1.944.528-SP, Rel. Ministro Raul Ara\u00fajo, Quarta Turma, por unanimidade, julgado em 12\/12\/2022, DJe 14\/12\/2022. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-1-situacao-fatica\"><a>3.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creosvaldo comprou passagens para uma viagem internacional. Planejou a viagem em seus m\u00ednimos detalhes, reservou hotel, passagens e ingressos para eventos e shows com a devida anteced\u00eancia.<\/p>\n\n\n\n<p>Ocorre que no dia da viagem, o voo atrasou muito, raz\u00e3o pela qual boa parte do planejamento restou comprometido. Inconformado, ajuizou a\u00e7\u00e3o em face da companhia a\u00e9rea requerendo a condena\u00e7\u00e3o em danos morais.<\/p>\n\n\n\n<p>A CIA a\u00e9rea sustenta que ao caso devem ser aplicadas as Conven\u00e7\u00f5es de Vars\u00f3via e Montreal ao inv\u00e9s do CDC.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-2-analise-estrategica\"><a>3.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-1-questao-juridica\"><a>3.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>CDC:<\/p>\n\n\n\n<p>&nbsp;Art. 27. Prescreve em cinco anos a pretens\u00e3o \u00e0 repara\u00e7\u00e3o pelos danos causados por fato do produto ou do servi\u00e7o prevista na Se\u00e7\u00e3o II deste Cap\u00edtulo, iniciando-se a contagem do prazo a partir do conhecimento do dano e de sua autoria.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-2-aplicavel-o-cdc\"><a>3.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Aplic\u00e1vel o CDC?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeaph!!!!<\/strong><\/p>\n\n\n\n<p>Cinge-se a controv\u00e9rsia acerca do prazo prescricional para passageiro reclamar danos morais no caso de atraso em voo internacional.<\/p>\n\n\n\n<p>Conforme o atual entendimento do Supremo Tribunal Federal, &#8220;ao julgar o RE 636.331, Rel. Min. Gilmar Mendes, paradigma do tema n. 210 da repercuss\u00e3o geral, este Supremo Tribunal Federal decidiu sobre a preval\u00eancia das conven\u00e7\u00f5es internacionais sobre o C\u00f3digo de Defesa do Consumidor apenas com rela\u00e7\u00e3o \u00e0s pretens\u00f5es de indeniza\u00e7\u00e3o por danos MATERIAIS&#8221;.<\/p>\n\n\n\n<p><strong>N\u00e3o foi reconhecida a exist\u00eancia, em acordo internacional sobre transporte a\u00e9reo, de regula\u00e7\u00e3o de repara\u00e7\u00e3o por danos MORAIS<\/strong>, aplicando-se a lei interna, no caso, o prazo prescricional previsto no art. 27 do <a>CDC<\/a>.<\/p>\n\n\n\n<p>No caso, &#8220;A orienta\u00e7\u00e3o jurisprudencial do Supremo Tribunal Federal \u00e9 no sentido de ser inaplic\u00e1vel a Conven\u00e7\u00e3o de Montreal para contagem do prazo prescricional para as indeniza\u00e7\u00f5es por danos morais&#8221; (RE 1.374.196, Rel. Ministro Roberto Barroso, Primeira Turma, julgado em 24\/10\/2022, DJe 10\/11\/2022).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-3-2-3-resultado-final\"><a>3.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>As Conven\u00e7\u00f5es de Vars\u00f3via e Montreal n\u00e3o regularam o dano moral no transporte a\u00e9reo internacional, ao qual deve ser aplicada a lei geral interna, no caso, o C\u00f3digo de Defesa do Consumidor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-im-possibilidade-de-substituicao-da-associacao-autora-de-acp-pelo-mp-em-razao-de-dissolucao-por-decisao-judicial\"><a>4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (Im)Possibilidade de substitui\u00e7\u00e3o da associa\u00e7\u00e3o autora de ACP pelo MP em raz\u00e3o de dissolu\u00e7\u00e3o por decis\u00e3o judicial<\/a><\/h2>\n\n\n\n<p><a><strong>AGRAVO INTERNO NO RECURSO ESPECIAL<\/strong><\/a><strong><\/strong><\/p>\n\n\n\n<p>Em caso de dissolu\u00e7\u00e3o, por decis\u00e3o judicial, da associa\u00e7\u00e3o autora de a\u00e7\u00e3o civil p\u00fablica, \u00e9 poss\u00edvel a substitui\u00e7\u00e3o processual pelo Minist\u00e9rio P\u00fablico.<\/p>\n\n\n\n<p>AgInt no REsp 1.582.243-SP, Rel. Ministra Maria Isabel Gallotti, Quarta Turma, por unanimidade, julgado em 14\/2\/2023. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-1-situacao-fatica\"><a>4.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>ANADEC (Associa\u00e7\u00e3o Nacional de Defesa do Consumidor) ajuizou ACP contra Fiado Cons\u00f3rcios para declarar a nulidade de cl\u00e1usula supostamente abusiva existente nos contratos de desta.<\/p>\n\n\n\n<p>Enquanto o processo seguia, A ANADEC teve sua dissolu\u00e7\u00e3o determinada judicialmente. Fiado ent\u00e3o requereu o provimento de recurso para acolher a preliminar de ilegitimidade passiva da autora. A ANADEC, por sua vez, requereu a intima\u00e7\u00e3o do MP para que se habilitasse como substituto processual no feito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-2-analise-estrategica\"><a>4.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-1-questao-juridica\"><a>4.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei de A\u00e7\u00e3o Civil P\u00fablica:<\/p>\n\n\n\n<p>Art. 5o&nbsp; T\u00eam legitimidade para propor a a\u00e7\u00e3o principal e a a\u00e7\u00e3o cautelar:<\/p>\n\n\n\n<p>\u00a7 3\u00ba Em caso de desist\u00eancia infundada ou abandono da a\u00e7\u00e3o por associa\u00e7\u00e3o legitimada, o Minist\u00e9rio P\u00fablico ou outro legitimado assumir\u00e1 a titularidade ativa.<\/p>\n\n\n\n<p>Lei n. 4.717\/65:<\/p>\n\n\n\n<p>Art. 9\u00ba Se o autor desistir da a\u00e7\u00e3o ou der motiva \u00e0 absolvi\u00e7\u00e3o da inst\u00e2ncia, ser\u00e3o publicados editais nos prazos e condi\u00e7\u00f5es previstos no art. 7\u00ba, inciso II, ficando assegurado a qualquer cidad\u00e3o, bem como ao representante do Minist\u00e9rio P\u00fablico, dentro do prazo de 90 (noventa) dias da \u00faltima publica\u00e7\u00e3o feita, promover o prosseguimento da a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Lei n. 7.347\/85:<\/p>\n\n\n\n<p>Art. 5o&nbsp; T\u00eam legitimidade para propor a a\u00e7\u00e3o principal e a a\u00e7\u00e3o cautelar<\/p>\n\n\n\n<p>\u00a7 3\u00ba Em caso de desist\u00eancia infundada ou abandono da a\u00e7\u00e3o por associa\u00e7\u00e3o legitimada, o Minist\u00e9rio P\u00fablico ou outro legitimado assumir\u00e1 a titularidade ativa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-2-possivel-a-substituicao-pelo-mpe\"><a>4.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Poss\u00edvel a substitui\u00e7\u00e3o pelo MPE?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeaph!!!!<\/strong><\/p>\n\n\n\n<p>Cinge-se a controv\u00e9rsia a determinar a possibilidade de interpreta\u00e7\u00e3o extensiva do art. 5\u00ba, \u00a7 3\u00ba, da Lei de A\u00e7\u00e3o Civil P\u00fablica (LACP) no caso em que a associa\u00e7\u00e3o que ajuizara a a\u00e7\u00e3o \u00e9 dissolvida por decis\u00e3o judicial em que se reconhece a aus\u00eancia de representatividade adequada e o desvio de finalidade, permitindo-se a sua substitui\u00e7\u00e3o pelo Minist\u00e9rio P\u00fablico.<\/p>\n\n\n\n<p><strong>Como n\u00e3o cabe ao int\u00e9rprete estabelecer distin\u00e7\u00f5es onde a pr\u00f3pria lei n\u00e3o distinguiu, \u00e9 IRRELEVANTE ao deferimento da substitui\u00e7\u00e3o processual a circunst\u00e2ncia de a associa\u00e7\u00e3o haver sido extinta por decis\u00e3o judicial<\/strong>. Nesse sentido, tamb\u00e9m o STJ j\u00e1 deixou claro que &#8220;se o dispositivo n\u00e3o restringiu, n\u00e3o pode o aplicador do direito interpretar a norma a ponto de criar uma restri\u00e7\u00e3o nela n\u00e3o prevista&#8221; (REsp 1.113.175\/DF, Rel. Ministro Castro Meira, Corte Especial, julgado em 24\/5\/2012, DJe 7\/8\/2012). O que importa \u00e9 que tanto nos casos de desist\u00eancia infundada ou de abandono da a\u00e7\u00e3o quanto na hip\u00f3tese de extin\u00e7\u00e3o da associa\u00e7\u00e3o por decis\u00e3o judicial, o objetivo leg\u00edtimo consiste em n\u00e3o deixar desprotegidas as pessoas que de fato tinham o interesse naquela tutela e at\u00e9 ent\u00e3o eram substitu\u00eddas pela associa\u00e7\u00e3o. Assim sendo, <strong>o fundamento para o deferimento da substitui\u00e7\u00e3o processual n\u00e3o depende de se tratar de desist\u00eancia infundada ou de abandono da a\u00e7\u00e3o, mas, sim, da necessidade de proteger os consumidores.<\/strong><\/p>\n\n\n\n<p>Nesse sentido, &#8220;consoante previs\u00e3o dos arts. 9\u00ba da Lei n. 4.717\/65 e 5\u00ba, \u00a7 3\u00ba, da <a>Lei n. 7.347\/85<\/a>, tendo ocorrido a dissolu\u00e7\u00e3o da autora coletiva origin\u00e1ria, deve ser possibilitado aos outros legitimados coletivos a assun\u00e7\u00e3o do polo ativo, como forma de se privilegiar a coletividade envolvida no processo e a economia dos atos processuais&#8221; (REsp 1.800.726\/MG, Rel. Ministra Nancy Andrighi, Terceira Turma, julgado em 2\/4\/2019, DJe 4\/4\/2019).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-4-2-3-resultado-final\"><a>4.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Em caso de dissolu\u00e7\u00e3o, por decis\u00e3o judicial, da associa\u00e7\u00e3o autora de a\u00e7\u00e3o civil p\u00fablica, \u00e9 poss\u00edvel a substitui\u00e7\u00e3o processual pelo Minist\u00e9rio P\u00fablico.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-penal\"><a>DIREITO PENAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-legitimidade-do-mp-para-propor-a-acao-penal-publica-incondicionada-destinada-a-verificar-a-pratica-de-crimes-sexuais-contra-criancas\"><a>5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Legitimidade do MP para propor a a\u00e7\u00e3o penal p\u00fablica incondicionada destinada a verificar a pr\u00e1tica de crimes sexuais contra crian\u00e7as<\/a><\/h2>\n\n\n\n<p><strong>PROCESSO EM SEGREDO DE JUSTI\u00c7A<\/strong><strong><\/strong><\/p>\n\n\n\n<p>Antes das altera\u00e7\u00f5es introduzidas pela Lei n. 12.015\/2009, o Minist\u00e9rio P\u00fablico j\u00e1 era parte leg\u00edtima para propor a a\u00e7\u00e3o penal p\u00fablica incondicionada destinada a verificar a pr\u00e1tica de crimes sexuais contra crian\u00e7as.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministro Reynaldo Soares da Fonseca, Quinta Turma, por unanimidade, julgado em 28\/11\/2022, DJe 1\u00ba\/12\/2022. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-1-situacao-fatica\"><a>5.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Uma crian\u00e7a foi abusada repetidamente entre os anos de 2006 a 2008. Os fatos somente vieram \u00e0 tona em 2016. O MP ent\u00e3o ajuizou a\u00e7\u00e3o em face do meliante, mas a defesa alega a ilegitimidade do MP para tanto, uma vez que os fatos teriam ocorrido antes da vig\u00eancia da Lei 12.015\/2009.<\/p>\n\n\n\n<p>* Processo sob segredo de justi\u00e7a. Caso imaginado,<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-2-analise-estrategica\"><a>5.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-1-questao-juridica\"><a>5.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo Penal:<\/p>\n\n\n\n<p><strong>A\u00e7\u00e3o penal<\/strong><\/p>\n\n\n\n<p>Art. 225.&nbsp; Nos crimes definidos nos Cap\u00edtulos I e II deste T\u00edtulo, procede-se mediante a\u00e7\u00e3o penal p\u00fablica incondicionada.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-2-o-mp-ja-era-parte-legitima\"><a>5.2.2.&nbsp;&nbsp;&nbsp;&nbsp; O MP j\u00e1 era parte leg\u00edtima?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeaph!!!!<\/strong><\/p>\n\n\n\n<p>A jurisprud\u00eancia do STJ \u00e9 no sentido de que, mesmo antes das altera\u00e7\u00f5es introduzidas pela Lei n. 12.015\/2009, o Minist\u00e9rio P\u00fablico j\u00e1 era parte leg\u00edtima para propor a a\u00e7\u00e3o penal p\u00fablica incondicionada destinada a verificar a pr\u00e1tica de crimes sexuais contra crian\u00e7as, pois a prote\u00e7\u00e3o integral \u00e0 inf\u00e2ncia \u00e9 DEVER do Estado, conforme previsto na Constitui\u00e7\u00e3o Federal.<\/p>\n\n\n\n<p>A Corte de origem, no tocante a alegada decad\u00eancia, consignou que, com o advento da Lei n. 12.015\/2009, os delitos de estupro passaram a exigir a condi\u00e7\u00e3o de procedibilidade consistente na representa\u00e7\u00e3o. No caso, a representa\u00e7\u00e3o somente ocorreu em 2016 porque nesse ano \u00e9 que os fatos vieram \u00e0 tona, mas estes foram praticados entre os anos de 2006 e 2008, ou seja, quando a v\u00edtima era ainda uma crian\u00e7a. Logo, n\u00e3o h\u00e1 falar em necessidade de representa\u00e7\u00e3o, pois a a\u00e7\u00e3o penal era p\u00fablica incondicionada em raz\u00e3o da sua menoridade, a teor do art. 225 do <a>C\u00f3digo Penal<\/a>.<\/p>\n\n\n\n<p>Assim, <strong>n\u00e3o se pode condicionar \u00e0 op\u00e7\u00e3o dos representantes legais da v\u00edtima, ou ao crit\u00e9rio econ\u00f4mico, a persecu\u00e7\u00e3o penal dos crimes definidos pela Constitui\u00e7\u00e3o Federal como hediondos, excluindo da prote\u00e7\u00e3o do Estado as crian\u00e7as submetidas \u00e0 pr\u00e1tica de delitos dessa natureza<\/strong>. Vale dizer, \u00e9 DESCABIDA a necessidade de iniciativa dos pais quando o bem jur\u00eddico protegido \u00e9 indispon\u00edvel, qual seja, a liberdade sexual de crian\u00e7a, que, conquanto n\u00e3o tenha sofrido viol\u00eancia real, n\u00e3o possui capacidade plena para determina\u00e7\u00e3o dos seus atos, dada a sua vulnerabilidade.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-5-2-3-resultado-final\"><a>5.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>Antes das altera\u00e7\u00f5es introduzidas pela Lei n. 12.015\/2009, o Minist\u00e9rio P\u00fablico j\u00e1 era parte leg\u00edtima para propor a a\u00e7\u00e3o penal p\u00fablica incondicionada destinada a verificar a pr\u00e1tica de crimes sexuais contra crian\u00e7as.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-garantia-por-contrato-de-seguro-em-execucao-fiscal-e-a-descaracterizacao-da-materialidade-dos-crimes-fiscais\"><a>6.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Garantia por contrato de seguro em execu\u00e7\u00e3o fiscal e a descaracteriza\u00e7\u00e3o da materialidade dos crimes fiscais<\/a><\/h2>\n\n\n\n<p><strong>PROCESSO SOB SEGREDO DE JUSTI\u00c7A<\/strong><strong><\/strong><\/p>\n\n\n\n<p>O fato de a referida d\u00edvida ativa estar garantida por contrato de seguro no bojo de execu\u00e7\u00e3o fiscal movida contra o contribuinte n\u00e3o descaracteriza a materialidade dos crimes fiscais.<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Min. Reynaldo Soares da Fonseca, Quinta Turma, por unanimidade, julgado em 14\/2\/2023. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-1-situacao-fatica\"><a>6.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Os administradores de uma empresa, agindo em conluio, suprimiram ICMS, mediante fraude \u00e0 fiscaliza\u00e7\u00e3o tribut\u00e1ria, inserindo elementos inexatos, em documento ou livro exigido pela lei fiscal, indicando como isentas mercadorias tribut\u00e1veis e, mediante vendas sem emiss\u00e3o de notas fiscais. Ap\u00f3s a tramita\u00e7\u00e3o dos Procedimentos Administrativos Tribut\u00e1rios cab\u00edveis, os d\u00e9bitos tribut\u00e1rios foram definitivamente lan\u00e7ados e inscritos na d\u00edvida ativa.<\/p>\n\n\n\n<p>Oferecida a den\u00fancia pelos crimes fiscais, a defesa dos administradores sustenta que o fato de a referida d\u00edvida ativa estar garantida por contrato de seguro no bojo da execu\u00e7\u00e3o fiscal descaracterizaria a materialidade dos crimes fiscais.<\/p>\n\n\n\n<p>* Processo sob segredo de justi\u00e7a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-2-analise-estrategica\"><a>6.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-1-questao-juridica\"><a>6.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 8.137\/1990:<\/p>\n\n\n\n<p>Art. 1\u00b0 Constitui crime contra a ordem tribut\u00e1ria suprimir ou reduzir tributo, ou contribui\u00e7\u00e3o social e qualquer acess\u00f3rio, mediante as seguintes condutas:<\/p>\n\n\n\n<p><a><\/a>II &#8211; fraudar a fiscaliza\u00e7\u00e3o tribut\u00e1ria, inserindo elementos inexatos, ou omitindo opera\u00e7\u00e3o de qualquer natureza, em documento ou livro exigido pela lei fiscal;<\/p>\n\n\n\n<p><a><\/a><a><\/a>V &#8211; negar ou deixar de fornecer, quando obrigat\u00f3rio, nota fiscal ou documento equivalente, relativa a venda de mercadoria ou presta\u00e7\u00e3o de servi\u00e7o, efetivamente realizada, ou fornec\u00ea-la em desacordo com a legisla\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-2-descaracterizada-a-materialidade-dos-crimes-fiscais\"><a>6.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Descaracterizada a materialidade dos crimes fiscais?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nem a pau (Juvenal)!!!!<\/strong><\/p>\n\n\n\n<p>Os administradores da empresa, agindo em conluio, suprimiram tributo estadual (ICMS), mediante fraude \u00e0 fiscaliza\u00e7\u00e3o tribut\u00e1ria, inserindo elementos inexatos, em documento ou livro exigido pela lei fiscal, indicando como isentas mercadorias tribut\u00e1veis (art. 1\u00ba, inciso II, da Lei n. 8.137\/1990) e, mediante vendas sem emiss\u00e3o de notas fiscais (art. 1\u00ba, inciso V, da Lei n. 8.137\/1990). Ap\u00f3s a tramita\u00e7\u00e3o dos Procedimentos Administrativos Tribut\u00e1rios cab\u00edveis, os d\u00e9bitos tribut\u00e1rios foram definitivamente lan\u00e7ados e inscritos na d\u00edvida ativa.<\/p>\n\n\n\n<p>O fato de a referida d\u00edvida ativa estar garantida por contrato de seguro no bojo de execu\u00e7\u00e3o fiscal movida contra o contribuinte n\u00e3o descaracteriza a materialidade dos crimes fiscais. Consta da inicial acusat\u00f3ria que &#8220;o preju\u00edzo causado aos cofres p\u00fablicos do Estado da Para\u00edba, com consequente preju\u00edzo \u00e0 coletividade, \u00e9 de grande vulto e indiscut\u00edvel, ante as constitui\u00e7\u00f5es definitivas dos cr\u00e9ditos tribut\u00e1rios&#8221;. A constitui\u00e7\u00e3o definitiva do cr\u00e9dito tribut\u00e1rio, pressuposto material do crime fiscal, n\u00e3o \u00e9 afastada pela mera garantia do d\u00e9bito em execu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Sobre o tema, a jurisprud\u00eancia do STJ possui entendimento de que &#8220;<strong>conquanto o d\u00e9bito fiscal tenha sido garantido na origem, o certo \u00e9 que n\u00e3o se equipara ao pagamento do tributo, raz\u00e3o pela qual n\u00e3o enseja, imediata e obrigatoriamente, o trancamento da a\u00e7\u00e3o penal, como almejado<\/strong>&#8221; (AgRg no AREsp 1.230.863\/SP, Rel. Ministro Jorge Mussi, Quinta Turma, DJe 7\/5\/2019).<\/p>\n\n\n\n<p>Acrescente-se, n\u00e3o tendo sido afastada a constitui\u00e7\u00e3o definitiva do d\u00e9bito tribut\u00e1rio por sua garantia no \u00e2mbito da execu\u00e7\u00e3o fiscal, tamb\u00e9m n\u00e3o \u00e9 obrigat\u00f3ria e legalmente impositiva a suspens\u00e3o da a\u00e7\u00e3o penal.<\/p>\n\n\n\n<p>Nesse sentido, &#8220;<strong>a garantia do cr\u00e9dito tribut\u00e1rio na execu\u00e7\u00e3o fiscal &#8211; procedimento necess\u00e1rio para que o executado possa oferecer embargos &#8211; n\u00e3o possui, consoante o C\u00f3digo Tribut\u00e1rio Nacional, natureza de pagamento volunt\u00e1rio ou de parcelamento da exa\u00e7\u00e3o e, portanto, n\u00e3o fulmina a justa causa para a persecu\u00e7\u00e3o penal, pois n\u00e3o configura hip\u00f3tese taxativa de extin\u00e7\u00e3o da punibilidade ou de suspens\u00e3o do processo penal<\/strong>&#8221; (RHC 65.221\/PE, Sexta Turma, Rel. Ministro Rog\u00e9rio Schietti Cruz, DJe 27\/6\/2016).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-6-2-3-resultado-final\"><a>6.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>O fato de a referida d\u00edvida ativa estar garantida por contrato de seguro no bojo de execu\u00e7\u00e3o fiscal movida contra o contribuinte n\u00e3o descaracteriza a materialidade dos crimes fiscais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-elevacao-da-pena-em-razao-da-confirmacao-pelo-tribunal-do-juri-da-dissimulacao-e-do-uso-de-meio-que-dificultou-a-defesa-da-vitima\"><a>7.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Eleva\u00e7\u00e3o da pena em raz\u00e3o da confirma\u00e7\u00e3o pelo tribunal do j\u00fari da dissimula\u00e7\u00e3o e do uso de meio que dificultou a defesa da v\u00edtima<\/a><\/h2>\n\n\n\n<p><strong>PROCESSO SOB SEGREDO DE JUSTI\u00c7A<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A confirma\u00e7\u00e3o pelo tribunal do j\u00fari da dissimula\u00e7\u00e3o e do uso de meio que dificultou a defesa da v\u00edtima deve ensejar uma \u00fanica eleva\u00e7\u00e3o em decorr\u00eancia da qualificadora contida no art. 121, \u00a7 2\u00ba, inciso IV, do C\u00f3digo Penal, ainda que quesitadas individualmente e n\u00e3o guardem rela\u00e7\u00e3o de interdepend\u00eancia entre si.<\/p>\n\n\n\n<p>Processo sob segredo de justi\u00e7a, Rel. Ministra Laurita Vaz, Sexta Turma, por unanimidade, julgado em 7\/2\/2023. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-1-situacao-fatica\"><a>7.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Em um julgamento pelo Tribunal do J\u00fari, foram reconhecidas as qualificadoras do uso de dissimula\u00e7\u00e3o e meio que dificultou a defesa da v\u00edtima. Em raz\u00e3o das circunst\u00e2ncias da dissimula\u00e7\u00e3o e do uso de meio que dificultou ou impossibilitou a defesa da v\u00edtima terem sido quesitadas e confirmadas, individualmente, pelo Conselho de Senten\u00e7a, o Ju\u00edzo sentenciante as reconheceu como duas qualificadoras aut\u00f4nomas.<\/p>\n\n\n\n<p>Inconformada, a defesa alega que deveria ter ocorrido uma \u00fanica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-2-analise-estrategica\"><a>7.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-1-questao-juridica\"><a>7.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo Penal:<\/p>\n\n\n\n<p><strong>Homic\u00eddio simples<\/strong><\/p>\n\n\n\n<p>Art. 121. Matar algu\u00e9m:<\/p>\n\n\n\n<p>Pena &#8211; reclus\u00e3o, de seis a vinte anos.<\/p>\n\n\n\n<p><strong>Homic\u00eddio qualificado<\/strong><\/p>\n\n\n\n<p>\u00a7 2\u00b0 Se o homic\u00eddio \u00e9 cometido:<\/p>\n\n\n\n<p>IV &#8211; \u00e0 trai\u00e7\u00e3o, de emboscada, ou mediante dissimula\u00e7\u00e3o ou outro recurso que dificulte ou torne imposs\u00edvel a defesa do ofendido;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-2-somente-uma-elevacao-e-devida\"><a>7.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Somente uma eleva\u00e7\u00e3o \u00e9 devida?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeaph!!!!<\/strong><\/p>\n\n\n\n<p>A controv\u00e9rsia consiste em definir se as circunst\u00e2ncias reconhecidas pelo Conselho de Senten\u00e7a devem trazer repercuss\u00e3o, de forma individual, na dosimetria da pena.<\/p>\n\n\n\n<p>No caso, em raz\u00e3o das circunst\u00e2ncias da dissimula\u00e7\u00e3o e do uso de meio que dificultou ou impossibilitou a defesa da v\u00edtima terem sido quesitadas e confirmadas, individualmente, pelo Conselho de Senten\u00e7a, o Ju\u00edzo sentenciante as reconheceu como duas qualificadoras aut\u00f4nomas.<\/p>\n\n\n\n<p>Contudo, <strong>a resposta positiva do Conselho de Senten\u00e7a aos referidos quesitos deve ensejar o reconhecimento uno da qualificadora contida no art. 121, \u00a7 2\u00ba, inciso IV, do C\u00f3digo Penal, ainda que n\u00e3o guardem rela\u00e7\u00e3o de interdepend\u00eancia entre si<\/strong>.<\/p>\n\n\n\n<p>Portanto, ainda que o Tribunal do J\u00fari tenha reconhecido a configura\u00e7\u00e3o da dissimula\u00e7\u00e3o usada para entrar na casa da v\u00edtima e o uso de meio que dificultou a defesa da v\u00edtima, deve incidir uma \u00fanica eleva\u00e7\u00e3o em decorr\u00eancia da qualificadora do art. 121, \u00a7 2\u00ba, inciso IV, do C\u00f3digo Penal, a fim de EVITAR&nbsp;<em>bis in idem<\/em>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-7-2-3-resultado-final\"><a>7.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>A confirma\u00e7\u00e3o pelo tribunal do j\u00fari da dissimula\u00e7\u00e3o e do uso de meio que dificultou a defesa da v\u00edtima deve ensejar uma \u00fanica eleva\u00e7\u00e3o em decorr\u00eancia da qualificadora contida no art. 121, \u00a7 2\u00ba, inciso IV, do C\u00f3digo Penal, ainda que quesitadas individualmente e n\u00e3o guardem rela\u00e7\u00e3o de interdepend\u00eancia entre si.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-cabimento-da-remicao-penal-por-aprovacao-no-enem-ao-reeducando-que-ja-havia-concluido-o-ensino-medio-antes-de-ingressar-no-sistema-prisional\"><a>8.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Cabimento da remi\u00e7\u00e3o penal por aprova\u00e7\u00e3o no ENEM ao reeducando que j\u00e1 havia conclu\u00eddo o ensino m\u00e9dio antes de ingressar no sistema prisional.<\/a><\/h2>\n\n\n\n<p><strong>RECURSO ESPECIAL<\/strong><strong><\/strong><\/p>\n\n\n\n<p>N\u00e3o \u00e9 cab\u00edvel a remi\u00e7\u00e3o penal por aprova\u00e7\u00e3o no ENEM ao reeducando que j\u00e1 havia conclu\u00eddo o ensino m\u00e9dio antes de ingressar no sistema prisional.<\/p>\n\n\n\n<p>REsp 1.913.757-SP, Rel. Ministro Rogerio Schietti Cruz, Sexta Turma, por unanimidade, julgado em 7\/2\/2023. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-1-situacao-fatica\"><a>8.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creitinho, atualmente reeducando, obteve aprova\u00e7\u00e3o no ENEM. Sua defesa requereu a remi\u00e7\u00e3o de pena, o que foi negado em raz\u00e3o do fato de Creitinho j\u00e1 possuir a certifica\u00e7\u00e3o de conclus\u00e3o do ensino m\u00e9dico conclu\u00eddo antes do in\u00edcio da execu\u00e7\u00e3o de sua pena.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-2-analise-estrategica\"><a>8.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-1-questao-juridica\"><a>8.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>LEP:<\/p>\n\n\n\n<p>Art. 126.&nbsp; O condenado que cumpre a pena em regime fechado ou semiaberto poder\u00e1 remir, por trabalho ou por estudo, parte do tempo de execu\u00e7\u00e3o da pena.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-2-cabivel-a-remicao-penal\"><a>8.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Cab\u00edvel a remi\u00e7\u00e3o penal?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Nooops!!!<\/strong><\/p>\n\n\n\n<p>Cinge-se a controv\u00e9rsia a definir se o sentenciado que j\u00e1 ostentava o conhecimento relativo ao ensino m\u00e9dio quando ingressou no sistema prisional faz jus \u00e0 remi\u00e7\u00e3o por estudo autodidata, do mesmo grau de ensino, em decorr\u00eancia de aprova\u00e7\u00e3o no Exame Nacional do Ensino M\u00e9dio (ENEM).<\/p>\n\n\n\n<p>O condenado que cumpre a pena em regime fechado ou semiaberto poder\u00e1 remir, por trabalho ou por estudo, parte do tempo de execu\u00e7\u00e3o da pena. Na \u00faltima hip\u00f3tese, o c\u00e1lculo do benef\u00edcio ser\u00e1 feito \u00e0 raz\u00e3o de 1 (um) dia de pena a cada 12 (doze) horas de frequ\u00eancia escolar.<\/p>\n\n\n\n<p>A Recomenda\u00e7\u00e3o n. 44\/2013 do CNJ prestigiou a interpreta\u00e7\u00e3o EXTENSIVA do art. 126 da LEP, de modo a premiar o estudo autodidata da educa\u00e7\u00e3o b\u00e1sica, se comprovado por aprova\u00e7\u00e3o em exames nacionais.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao ENEM (que n\u00e3o certifica a conclus\u00e3o do ensino m\u00e9dio desde 2017), hoje substitu\u00eddo pelo ENCEJJA, a certifica\u00e7\u00e3o dos conhecimentos do ensino m\u00e9dio destinava-se somente aos candidatos que estavam fora do sistema escolar e ainda n\u00e3o possu\u00edam o diploma do n\u00edvel de escolaridade.<\/p>\n\n\n\n<p>A atividade ressocializadora do estudo (e n\u00e3o a realiza\u00e7\u00e3o de prova ou vestibular) continua a ser o fato gerador da remi\u00e7\u00e3o. A Resolu\u00e7\u00e3o n. 391 do CNJ n\u00e3o elencou a realiza\u00e7\u00e3o do ENEM ou ENCEJJA como hip\u00f3tese de abatimento da pena, mas apenas como instrumento de avalia\u00e7\u00e3o e certifica\u00e7\u00e3o do aprendizado por esfor\u00e7o do pr\u00f3prio preso. A resolu\u00e7\u00e3o estabeleceu diretrizes a serem observados pelo Poder Judici\u00e1rio para o reconhecimento do direito previsto no art. 126 da LEP.<\/p>\n\n\n\n<p>Por isso, se o diploma oficial atesta que o ensino m\u00e9dio n\u00e3o foi cursado durante os regimes fechado ou semiaberto, n\u00e3o \u00e9 cab\u00edvel a remi\u00e7\u00e3o penal por aprova\u00e7\u00e3o no ENEM ao reeducando que concluiu os estudos m\u00e9dios antes de ingressar no sistema prisional, pois o aprendizado para conclus\u00e3o da educa\u00e7\u00e3o b\u00e1sica ocorre apenas UMA vez.<\/p>\n\n\n\n<p>Portanto, &#8220;<strong>tendo o apenado conclu\u00eddo o ensino m\u00e9dio [&#8230;] antes do in\u00edcio do cumprimento da pena, incab\u00edvel a remi\u00e7\u00e3o penal por aprova\u00e7\u00e3o no Exame Nacional do Ensino M\u00e9dio (ENEM)<\/strong>&#8221; (AgRg no AREsp 2.083.985\/SP, relator Ministro Ribeiro Dantas, Quinta Turma, DJe de 10\/8\/2022).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-8-2-3-resultado-final\"><a>8.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>N\u00e3o \u00e9 cab\u00edvel a remi\u00e7\u00e3o penal por aprova\u00e7\u00e3o no ENEM ao reeducando que j\u00e1 havia conclu\u00eddo o ensino m\u00e9dio antes de ingressar no sistema prisional.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-direito-processual-penal\"><a>DIREITO PROCESSUAL PENAL<\/a><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-9-i-legalidade-do-compartilhamento-com-a-controladoria-geral-da-uniao-de-informacoes-coletadas-em-inquerito-em-que-se-apura-suposta-pratica-de-crimes-de-organizacao-criminosa-lavagem-de-dinheiro-e-corrupcao-ativa-e-passiva\"><a>9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (I)Legalidade do compartilhamento com a Controladoria-Geral da Uni\u00e3o de informa\u00e7\u00f5es coletadas em inqu\u00e9rito em que se apura suposta pr\u00e1tica de crimes de organiza\u00e7\u00e3o criminosa, lavagem de dinheiro e corrup\u00e7\u00e3o ativa e passiva<\/a><\/h2>\n\n\n\n<p><strong>PROCESSO SOB SEGREDO DE JUSTI\u00c7A<\/strong><strong><\/strong><\/p>\n\n\n\n<p>\u00c9 legal o compartilhamento com a Controladoria-Geral da Uni\u00e3o de informa\u00e7\u00f5es coletadas em inqu\u00e9rito em que se apura suposta pr\u00e1tica de crimes de organiza\u00e7\u00e3o criminosa, lavagem de dinheiro e corrup\u00e7\u00e3o ativa e passiva<\/p>\n\n\n\n<p>Processo em segredo de justi\u00e7a, Rel. Ministra Nancy Andrighi, Corte Especial, por unanimidade, julgado em 15\/2\/2023. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-1-situacao-fatica\"><a>9.1.&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Crementino foi denunciado pelos crimes de organiza\u00e7\u00e3o criminosa, lavagem de dinheiro e corrup\u00e7\u00e3o. A defesa impetrou HC alegando a ilegalidade do compartilhamento das informa\u00e7\u00f5es do inqu\u00e9rito com o CGU \u2014 Crementino caiu na rede do Minist\u00e9rio P\u00fablico ap\u00f3s o compartilhamento de informa\u00e7\u00f5es colhidas pela Controladoria-Geral da Uni\u00e3o em procedimento administrativo para apurar a responsabilidade de pessoas f\u00edsicas e jur\u00eddicas relacionadas \u00e0s eventuais infra\u00e7\u00f5es penais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-2-analise-estrategica\"><a>9.2.&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-1-questao-juridica\"><a>9.2.1.&nbsp;&nbsp;&nbsp;&nbsp; Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 12.850\/2013:<\/p>\n\n\n\n<p>Art. 3\u00ba Em qualquer fase da persecu\u00e7\u00e3o penal, ser\u00e3o permitidos, sem preju\u00edzo de outros j\u00e1 previstos em lei, os seguintes meios de obten\u00e7\u00e3o da prova:<\/p>\n\n\n\n<p><a><\/a><a><\/a>VIII &#8211; coopera\u00e7\u00e3o entre institui\u00e7\u00f5es e \u00f3rg\u00e3os federais, distritais, estaduais e municipais na busca de provas e informa\u00e7\u00f5es de interesse da investiga\u00e7\u00e3o ou da instru\u00e7\u00e3o criminal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-2-tudo-certo-arnaldo\"><a>9.2.2.&nbsp;&nbsp;&nbsp;&nbsp; Tudo certo, Arnaldo?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Segue o jogo!!!!<\/strong><\/p>\n\n\n\n<p>A Controladoria-Geral da Uni\u00e3o instaurou procedimento administrativo, a fim de apurar a responsabilidade de pessoas f\u00edsicas e jur\u00eddicas relacionadas a eventuais infra\u00e7\u00f5es penais investigadas no curso de inqu\u00e9rito em se apura suposta pr\u00e1tica de crimes de organiza\u00e7\u00e3o criminosa, lavagem de dinheiro e corrup\u00e7\u00e3o ativa e passiva.<\/p>\n\n\n\n<p>O compartilhamento de informa\u00e7\u00f5es coletadas em inqu\u00e9rito com a Controladoria-Geral da Uni\u00e3o encontra respaldo no art. 3\u00ba, VIII, da <a>Lei n. 12.850\/2013 <\/a>e em Tratados promulgados pelo Brasil e introduzidos no ordenamento p\u00e1trio com&nbsp;<em>status<\/em>&nbsp;de lei ordin\u00e1ria, conforme decidido no AgRg na CauInomCrim 69\/DF (Corte Especial, julgado em 7\/12\/2022).<\/p>\n\n\n\n<p>O referido dispositivo prev\u00ea textualmente a possibilidade de coopera\u00e7\u00e3o entre \u00f3rg\u00e3os federais na busca de provas e informa\u00e7\u00f5es de interesse da investiga\u00e7\u00e3o criminal. Essa previs\u00e3o legal foi inserida na legisla\u00e7\u00e3o penal especial em cumprimento a Tratados firmados pela Rep\u00fablica Federativa do Brasil.<\/p>\n\n\n\n<p>A Conven\u00e7\u00e3o de Palermo (Conven\u00e7\u00e3o das Na\u00e7\u00f5es Unidas contra o Crime Organizado Transnacional), promulgada pelo Decreto n. 5.015\/2004, constitui o principal instrumento global de combate ao crime organizado.<\/p>\n\n\n\n<p>O referido documento, aplic\u00e1vel aos delitos de crime organizado, lavagem de capitais e corrup\u00e7\u00e3o, prev\u00ea que cada Estado-parte garantir\u00e1 que as autoridades respons\u00e1veis pela detec\u00e7\u00e3o, repress\u00e3o e combate \u00e0 lavagem de dinheiro tenham a capacidade de cooperar e trocar informa\u00e7\u00f5es em \u00e2mbito nacional, criando, inclusive, canais de comunica\u00e7\u00e3o para facilitar a r\u00e1pida e segura troca de informa\u00e7\u00f5es relativas a todos os aspectos das infra\u00e7\u00f5es previstas na presente Conven\u00e7\u00e3o (arts. 7, item 1, e 27, item 1).<\/p>\n\n\n\n<p>O compartilhamento de informa\u00e7\u00f5es, encontra, ainda, suporte no art. 14, item 1, da Conven\u00e7\u00e3o de M\u00e9rida (Conven\u00e7\u00e3o das Na\u00e7\u00f5es Unidas contra a corrup\u00e7\u00e3o, documento promulgado pelo Decreto n. 5.687\/2006), Tratado em que cada Estado-parte se comprometeu a garantir que as autoridades de administra\u00e7\u00e3o e as encarregadas de combater a lavagem de dinheiro sejam capazes de intercambiar informa\u00e7\u00f5es no \u00e2mbito nacional, fortalecendo medidas para combater de forma mais eficaz a corrup\u00e7\u00e3o.<\/p>\n\n\n\n<p>No mesmo sentido, destaca-se a Conven\u00e7\u00e3o Interamericana contra a Corrup\u00e7\u00e3o (Conven\u00e7\u00e3o de Caracas), promulgada pelo Decreto n. 4.410\/2002, documento que, em seu artigo II, destaca o fortalecimento, por cada um dos Estados-partes, dos mecanismos necess\u00e1rios para prevenir, detectar, punir e erradicar a corrup\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-9-2-3-resultado-final\"><a>9.2.3.&nbsp;&nbsp;&nbsp;&nbsp; Resultado final.<\/a><\/h4>\n\n\n\n<p>\u00c9 legal o compartilhamento com a Controladoria-Geral da Uni\u00e3o de informa\u00e7\u00f5es coletadas em inqu\u00e9rito em que se apura suposta pr\u00e1tica de crimes de organiza\u00e7\u00e3o criminosa, lavagem de dinheiro e corrup\u00e7\u00e3o ativa e passiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-10-competencia-para-processar-e-julgar-o-pedido-de-medidas-protetivas-de-urgencia-em-situacoes-de-violencia-domestica\"><a>10.&nbsp; Compet\u00eancia para processar e julgar o pedido de medidas protetivas de urg\u00eancia em situa\u00e7\u00f5es de viol\u00eancia dom\u00e9stica.<\/a><\/h2>\n\n\n\n<p><strong>CONFLITO DE COMPET\u00caNCIA<\/strong><strong><\/strong><\/p>\n\n\n\n<p>O ju\u00edzo do domic\u00edlio da v\u00edtima em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica \u00e9 competente para processar e julgar o pedido de medidas protetivas de urg\u00eancia, independentemente de as supostas condutas criminosas que motivaram o pedido terem ocorrido enquanto o autor e a v\u00edtima encontravam-se em viagem fora do domic\u00edlio desta.<\/p>\n\n\n\n<p>CC 190.666-MG, Rel. Ministra Laurita Vaz, Terceira Se\u00e7\u00e3o, por unanimidade, julgado em 8\/2\/2023, DJe 14\/2\/2023. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-1-situacao-fatica\"><a>10.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>Creide visitava a fam\u00edlia em sua cidade natal quando foi v\u00edtima de viol\u00eancia dom\u00e9stica por parte de seu marido Craudi\u00e3o. Compareceu a delegacia e relatou os fatos, o que levou o Juiz local a deferir medidas protetivas de urg\u00eancia. Alguns dias depois, Creide retornou a sua casa, j\u00e1 em outro munic\u00edpio. O juiz que deferiu as medidas de urg\u00eancia determinou a redistribui\u00e7\u00e3o dos feitos para a cidade de domic\u00edlio da v\u00edtima.<\/p>\n\n\n\n<p>Ao receber os autos, o Juiz do domic\u00edlio suscitou conflito de compet\u00eancia por entender que houve perpetua\u00e7\u00e3o da compet\u00eancia pelo ju\u00edzo que deferiu as medidas de urg\u00eancia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-2-analise-estrategica\"><a>10.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-1-questao-juridica\"><a>10.2.1. Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>Lei n. 11.340\/2006:<\/p>\n\n\n\n<p>Art. 13. Ao processo, ao julgamento e \u00e0 execu\u00e7\u00e3o das causas c\u00edveis e criminais decorrentes da pr\u00e1tica de viol\u00eancia dom\u00e9stica e familiar contra a mulher aplicar-se-\u00e3o as normas dos C\u00f3digos de Processo Penal e Processo Civil e da legisla\u00e7\u00e3o espec\u00edfica relativa \u00e0 crian\u00e7a, ao adolescente e ao idoso que n\u00e3o conflitarem com o estabelecido nesta Lei.<\/p>\n\n\n\n<p>Lei n. 8.069\/1990:<\/p>\n\n\n\n<p>Art. 147. A compet\u00eancia ser\u00e1 determinada:<\/p>\n\n\n\n<p>I &#8211; pelo domic\u00edlio dos pais ou respons\u00e1vel;<\/p>\n\n\n\n<p>II &#8211; pelo lugar onde se encontre a crian\u00e7a ou adolescente, \u00e0 falta dos pais ou respons\u00e1vel.<\/p>\n\n\n\n<p>Lei n. 10.741\/2003:<\/p>\n\n\n\n<p>&nbsp;Art. 80. As a\u00e7\u00f5es previstas neste Cap\u00edtulo ser\u00e3o propostas no foro do domic\u00edlio da pessoa idosa, cujo ju\u00edzo ter\u00e1 compet\u00eancia absoluta para processar a causa, ressalvadas as compet\u00eancias da Justi\u00e7a Federal e a compet\u00eancia origin\u00e1ria dos Tribunais Superiores.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-2-a-quem-compete-julgar-os-pedidos-medidas-protetivas-de-urgencia\"><a>10.2.2. A quem compete julgar os pedidos medidas protetivas de urg\u00eancia?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Ao Ju\u00edzo do DOMIC\u00cdLIO da v\u00edtima!!!!<\/strong><\/p>\n\n\n\n<p>A interpreta\u00e7\u00e3o SISTEM\u00c1TICA do art. 13 da Lei n. 11.340\/2006, em conjunto com o art. 147, incisos I e II, da Lei n. 8.069\/1990 (Estatuto da Crian\u00e7a e do Adolescente) e do art. 80 da Lei n. 10.741\/2003 (Estatuto do Idoso), <strong>permite a aplica\u00e7\u00e3o do princ\u00edpio do ju\u00edzo imediato \u00e0s a\u00e7\u00f5es em que se pleiteiam medidas protetivas de urg\u00eancia de car\u00e1ter penal no contexto de viol\u00eancia dom\u00e9stica e familiar contra a mulher<\/strong>.<\/p>\n\n\n\n<p>De fato, a aplica\u00e7\u00e3o do princ\u00edpio do ju\u00edzo imediato na aprecia\u00e7\u00e3o dos pedidos de medidas protetivas de urg\u00eancia n\u00e3o entra em conflito com as demais disposi\u00e7\u00f5es da Lei n. 11.340\/2006. Ao contr\u00e1rio, essa medida facilita o acesso da mulher v\u00edtima de viol\u00eancia dom\u00e9stica a uma r\u00e1pida presta\u00e7\u00e3o jurisdicional, que \u00e9 o principal objetivo perseguido pelas normas processuais especiais que integram o microssistema de prote\u00e7\u00e3o de pessoas vulner\u00e1veis que j\u00e1 se delineia no ordenamento jur\u00eddico brasileiro.<\/p>\n\n\n\n<p>O acesso r\u00e1pido e efetivo \u00e0 tutela jurisdicional assume especial relevo na situa\u00e7\u00e3o de risco em que a mulher se encontra quando solicita medidas protetivas de urg\u00eancia. <strong>\u00c9 justamente o seu car\u00e1ter de urg\u00eancia que reclama a aplica\u00e7\u00e3o do princ\u00edpio do ju\u00edzo imediato, tendo em vista que o ju\u00edzo do domicilio normalmente \u00e9 o primeiro ao qual a mulher tem acesso e o que tem intera\u00e7\u00e3o mais pr\u00f3xima com a v\u00edtima<\/strong>.<\/p>\n\n\n\n<p>Assim, diante da aplica\u00e7\u00e3o do princ\u00edpio do ju\u00edzo imediato e n\u00e3o havendo d\u00favidas de que o ju\u00edzo do domic\u00edlio da v\u00edtima \u00e9 o que possui melhores condi\u00e7\u00f5es de acompanhar a situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica e familiar na situa\u00e7\u00e3o concreta, afirma-se a sua compet\u00eancia para processar e julgar o pedido de medidas protetivas de urg\u00eancia, independentemente do local onde tenham inicialmente ocorrido as supostas condutas criminosas que motivaram o pedido de medidas protetivas.<\/p>\n\n\n\n<p>Ressalte-se, por fim, que a compet\u00eancia do ju\u00edzo do domic\u00edlio da v\u00edtima para conhecer e julgar o pedido de medidas protetivas de car\u00e1ter urgente n\u00e3o altera ou modifica a compet\u00eancia do ju\u00edzo natural para o processamento e julgamento de eventual a\u00e7\u00e3o penal, que deve ser definida conforme as regras gerais do C\u00f3digo de Processo Penal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-10-2-3-resultado-final\"><a>10.2.3. Resultado final.<\/a><\/h4>\n\n\n\n<p>O ju\u00edzo do domic\u00edlio da v\u00edtima em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica \u00e9 competente para processar e julgar o pedido de medidas protetivas de urg\u00eancia, independentemente de as supostas condutas criminosas que motivaram o pedido terem ocorrido enquanto o autor e a v\u00edtima encontravam-se em viagem fora do domic\u00edlio desta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-11-im-possibilidade-da-antecipacao-de-provas-para-a-oitiva-de-testemunhas-policiais\"><a>11.&nbsp; (Im)Possibilidade da antecipa\u00e7\u00e3o de provas para a oitiva de testemunhas policiais<\/a><\/h2>\n\n\n\n<p><strong>AGRAVO REGIMENTAL NO AGRAVO EM RECURSO ESPECIAL<\/strong><strong><\/strong><\/p>\n\n\n\n<p>\u00c9 poss\u00edvel a antecipa\u00e7\u00e3o de provas para a oitiva de testemunhas policiais, dado que, pela natureza dessa atividade profissional, diariamente em contato com fatos delituosos semelhantes, o decurso do tempo traz efetivo risco de perecimento da prova testemunhal por esquecimento.<\/p>\n\n\n\n<p>AgRg no AREsp 1.995.527-SE, Rel. Ministro Antonio Saldanha Palheiro, Sexta Turma, por unanimidade, julgado em 19\/12\/2022, DJe 21\/12\/2022. (Info 764)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-1-situacao-fatica\"><a>11.1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Situa\u00e7\u00e3o F\u00c1TICA.<\/a><\/h3>\n\n\n\n<p>O MP requereu a produ\u00e7\u00e3o antecipada de provas consistente na oitiva de testemunhas policiais. Fundamentou o pedido no fato de que, em virtude do lapso temporal de cerca de quatro anos decorridos desde os fatos, de as \u00fanicas testemunhas serem policiais militares, bem como o efetivo risco de fuga do acusado e de esquecimento dos fatos pelas testemunhas.<\/p>\n\n\n\n<p>O requerimento foi deferido, o que levou a defesa do acusado a interpor sucessivos recursos nos quais alega que os fundamentos elencados pelo MP n\u00e3o seriam suficientes para proceder a produ\u00e7\u00e3o antecipada de provas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-11-2-analise-estrategica\"><a>11.2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An\u00e1lise ESTRAT\u00c9GICA.<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-1-questao-juridica\"><a>11.2.1. Quest\u00e3o JUR\u00cdDICA.<\/a><\/h4>\n\n\n\n<p>C\u00f3digo de Processo Penal:<\/p>\n\n\n\n<p>Art. 312. A pris\u00e3o preventiva poder\u00e1 ser decretada como garantia da ordem p\u00fablica, da ordem econ\u00f4mica, por conveni\u00eancia da instru\u00e7\u00e3o criminal ou para assegurar a aplica\u00e7\u00e3o da lei penal, quando houver prova da exist\u00eancia do crime e ind\u00edcio suficiente de autoria e de perigo gerado pelo estado de liberdade do imputado.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7 1\u00ba&nbsp; A pris\u00e3o preventiva tamb\u00e9m poder\u00e1 ser decretada em caso de descumprimento de qualquer das obriga\u00e7\u00f5es impostas por for\u00e7a de outras medidas cautelares (<\/p>\n\n\n\n<p>\u00a7 2\u00ba A decis\u00e3o que decretar a pris\u00e3o preventiva deve ser motivada e fundamentada em receio de perigo e exist\u00eancia concreta de fatos novos ou contempor\u00e2neos que justifiquem a aplica\u00e7\u00e3o da medida adotada<\/p>\n\n\n\n<p>Art. 366. Se o acusado, citado por edital, n\u00e3o comparecer, nem constituir advogado, ficar\u00e3o suspensos o processo e o curso do prazo prescricional, podendo o juiz determinar a produ\u00e7\u00e3o antecipada das provas consideradas urgentes e, se for o caso, decretar pris\u00e3o preventiva, nos termos do disposto no art. 312.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-2-possivel-a-antecipacao-da-prova\"><a>11.2.2. Poss\u00edvel a antecipa\u00e7\u00e3o da prova?<\/a><\/h4>\n\n\n\n<p><strong><em><u>R:<\/u><\/em><\/strong> <strong>Yeaph!!!<\/strong><\/p>\n\n\n\n<p>No que concerne ao tema, preconiza o art. 366 do C\u00f3digo de Processo Penal que, &#8220;se o acusado, citado por edital, n\u00e3o comparecer, nem constituir advogado, ficar\u00e3o suspensos o processo e o curso do prazo prescricional, podendo o juiz determinar a produ\u00e7\u00e3o antecipada das provas consideradas urgentes e, se for o caso, decretar pris\u00e3o preventiva, nos termos do disposto no art. 312&#8221;.<\/p>\n\n\n\n<p>Cumpre ressaltar que, nos termos do Enunciado n. 455 da S\u00famula do Superior Tribunal de Justi\u00e7a, &#8220;A decis\u00e3o que determina a produ\u00e7\u00e3o antecipada de provas com base no art. 366 do CPP deve ser concretamente fundamentada, n\u00e3o a justificando unicamente o mero decurso do tempo&#8221;.<\/p>\n\n\n\n<p>No caso, os fundamentos do ac\u00f3rd\u00e3o que determinou a produ\u00e7\u00e3o antecipada de provas s\u00e3o ID\u00d4NEOS, tendo em vista a urg\u00eancia da medida, consubstanciada na possibilidade do perecimento ou da fragilidade dos elementos de convic\u00e7\u00e3o, salientando a inst\u00e2ncia ordin\u00e1ria a necessidade da oitiva antecipada das testemunhas, seja em virtude do lapso temporal de cerca de quatro anos decorridos desde os fatos, seja em raz\u00e3o de as \u00fanicas testemunhas serem policiais militares, estando presente o efetivo risco de fuga do acusado do distrito da culpa e de esquecimento dos fatos pelas testemunhas, pela pr\u00f3pria natureza do of\u00edcio de quem atua diariamente no combate \u00e0 criminalidade, circunst\u00e2ncias essas concretas que justificam a antecipa\u00e7\u00e3o da prova, nos termos do art. 366 do CPP e do entendimento do Superior Tribunal de Justi\u00e7a.<\/p>\n\n\n\n<p>Nessa esteira, compreendeu a Terceira Se\u00e7\u00e3o do STJ, no julgamento do RHC 64.086\/DF, que \u00e9 justific\u00e1vel a antecipa\u00e7\u00e3o de provas para a oitiva de testemunhas policiais, j\u00e1 que, nesse caso, o simples decurso do tempo traz efetivo <strong>risco de perecimento da prova testemunhal<\/strong>, por <em>esquecimento, dada a natureza dessa atividade profissional, diariamente em contato com fatos delituosos semelhantes<\/em>, devendo ser ouvidas com a m\u00e1xima urg\u00eancia poss\u00edvel (RHC 64.086\/DF).<\/p>\n\n\n\n<p>Ademais, conforme assentado pelo Superior Tribunal de Justi\u00e7a, &#8220;<strong>a realiza\u00e7\u00e3o antecipada de provas n\u00e3o traz preju\u00edzo \u00ednsito \u00e0 defesa, visto que, a par de o ato ser realizado na presen\u00e7a de defensor nomeado, nada impede que, retomado eventualmente o curso do processo com o comparecimento do r\u00e9u, sejam produzidas provas que se julgarem \u00fateis \u00e0 defesa, n\u00e3o sendo vedada a repeti\u00e7\u00e3o, se indispens\u00e1vel, da prova produzida antecipadamente<\/strong>&#8221; (RHC 64.086\/DF, relator Ministro Nefi Cordeiro, relator p\/ Ac\u00f3rd\u00e3o Ministro Rogerio Schietti Cruz, Terceira Se\u00e7\u00e3o, DJe 9\/12\/2016).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-11-2-3-resultado-final\"><a>11.2.3. Resultado final.<\/a><\/h4>\n\n\n\n<p>\u00c9 poss\u00edvel a antecipa\u00e7\u00e3o de provas para a oitiva de testemunhas policiais, dado que, pela natureza dessa atividade profissional, diariamente em contato com fatos delituosos semelhantes, o decurso do tempo traz efetivo risco de perecimento da prova testemunhal por esquecimento.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"Incorporar PDF\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-4eccb982-c40a-4273-b3f5-b1e6f8bae75e\" href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/21013614\/stj-764-parte-2.pdf\">stj-764-parte-2<\/a><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/21013614\/stj-764-parte-2.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-4eccb982-c40a-4273-b3f5-b1e6f8bae75e\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informativo n\u00ba 764 (Parte 2) do STJ\u00a0COMENTADO\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! DIREITO EMPRESARIAL 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Responsabilidade do importador nacional pelos valores pagos pelo banco confirmador ao exportador estrangeiro, na hip\u00f3tese de insolv\u00eancia do banco emissor de carta de cr\u00e9dito internacional RECURSO ESPECIAL O [&hellip;]<\/p>\n","protected":false},"author":833,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1189546","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativo STJ 764 (Parte 2) Comentado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativo STJ 764 (Parte 2) Comentado\" \/>\n<meta property=\"og:description\" content=\"Informativo n\u00ba 764 (Parte 2) do STJ\u00a0COMENTADO\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! DIREITO EMPRESARIAL 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Responsabilidade do importador nacional pelos valores pagos pelo banco confirmador ao exportador estrangeiro, na hip\u00f3tese de insolv\u00eancia do banco emissor de carta de cr\u00e9dito internacional RECURSO ESPECIAL O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-21T04:36:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T04:36:39+00:00\" \/>\n<meta name=\"author\" content=\"Jean Vilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Vilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"38 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/\"},\"author\":{\"name\":\"Jean Vilbert\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\"},\"headline\":\"Informativo STJ 764 (Parte 2) Comentado\",\"datePublished\":\"2023-03-21T04:36:37+00:00\",\"dateModified\":\"2023-03-21T04:36:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/\"},\"wordCount\":7638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/\",\"name\":\"Informativo STJ 764 (Parte 2) Comentado\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2023-03-21T04:36:37+00:00\",\"dateModified\":\"2023-03-21T04:36:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativo STJ 764 (Parte 2) Comentado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999\",\"name\":\"Jean Vilbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g\",\"caption\":\"Jean Vilbert\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativo STJ 764 (Parte 2) Comentado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/","og_locale":"pt_BR","og_type":"article","og_title":"Informativo STJ 764 (Parte 2) Comentado","og_description":"Informativo n\u00ba 764 (Parte 2) do STJ\u00a0COMENTADO\u00a0saindo do forno (quentinho) para quem est\u00e1 ligado aqui conosco no Estrat\u00e9gia Carreiras Jur\u00eddicas! DOWNLOAD do PDF AQUI! DIREITO EMPRESARIAL 1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Responsabilidade do importador nacional pelos valores pagos pelo banco confirmador ao exportador estrangeiro, na hip\u00f3tese de insolv\u00eancia do banco emissor de carta de cr\u00e9dito internacional RECURSO ESPECIAL O [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-03-21T04:36:37+00:00","article_modified_time":"2023-03-21T04:36:39+00:00","author":"Jean Vilbert","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Jean Vilbert","Est. tempo de leitura":"38 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/"},"author":{"name":"Jean Vilbert","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999"},"headline":"Informativo STJ 764 (Parte 2) Comentado","datePublished":"2023-03-21T04:36:37+00:00","dateModified":"2023-03-21T04:36:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/"},"wordCount":7638,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/","name":"Informativo STJ 764 (Parte 2) Comentado","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2023-03-21T04:36:37+00:00","dateModified":"2023-03-21T04:36:39+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/informativo-stj-764-parte-2-comentado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Informativo STJ 764 (Parte 2) Comentado"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/475a0922f10cff0d1bc8bfecde05f999","name":"Jean Vilbert","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1667694e4ebdd32feeac9ea2794de3f0470b5c55c6198181ab0b0c333b121921?s=96&d=mm&r=g","caption":"Jean Vilbert"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jeanvilbertgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1189546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1189546"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1189546\/revisions"}],"predecessor-version":[{"id":1189548,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1189546\/revisions\/1189548"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1189546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1189546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1189546"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1189546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}