{"id":1184505,"date":"2023-04-02T08:00:00","date_gmt":"2023-04-02T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1184505"},"modified":"2023-03-13T13:06:57","modified_gmt":"2023-03-13T16:06:57","slug":"teoria-crime","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/","title":{"rendered":"Teoria do Crime"},"content":{"rendered":"\n<p>Teoria do Crime<\/p>\n\n\n\n<p>Ol\u00e1, amigos. Tudo bom? Espero que sim.<\/p>\n\n\n\n<p>Hoje nosso artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Teoria do Crime<\/mark><\/strong>. Tendo em vista que este tema \u00e9 bastante abrangente e complexo, \u00e9 de suma import\u00e2ncia que haja o conhecimento de suas subdivis\u00f5es, para que possamos organizar nossos estudos da melhor maneira e compreender a mat\u00e9ria como um todo.&nbsp;<\/p>\n\n\n\n<p>Primeiramente, vejamos os t\u00f3picos que ser\u00e3o abordados:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conceito de crime;<\/li>\n\n\n\n<li>Estrutura da teoria do crime;<\/li>\n\n\n\n<li>An\u00e1lise estat\u00edstica da teoria do crime;<\/li>\n\n\n\n<li>Voc\u00ea n\u00e3o pode deixar de saber;<\/li>\n\n\n\n<li>Videoaula: Temas especiais de Direito Penal.<\/li>\n<\/ul>\n\n\n\n<p>Animados? Vamos l\u00e1.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-1024x768.jpg\" alt=\"Teoria do Crime\" class=\"wp-image-1184918\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-1024x768.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-300x225.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-768x576.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-1536x1152.jpg 1536w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-2048x1536.jpg 2048w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-610x458.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-150x113.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Teoria do Crime<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Conceito de crime<\/h2>\n\n\n\n<p>Existem diversos conceitos acerca do que \u00e9 o crime e quais s\u00e3o os elementos que o comp\u00f5e. Portanto, como a doutrina costuma conceituar o crime de <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">forma anal\u00edtica<\/mark><\/strong>, ser\u00e1 esse o conceito tratado neste artigo, ok?!<\/p>\n\n\n\n<p>Para a corrente dominante que adota o conceito anal\u00edtico de crime, este consubstancia-se em fato t\u00edpico, il\u00edcito e culp\u00e1vel (<strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">teoria tripartite<\/mark><\/strong>).<\/p>\n\n\n\n<p>Para esta conceitua\u00e7\u00e3o, levamos em considera\u00e7\u00e3o os substratos do crime, quais sejam:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Fato t\u00edpico<\/mark><\/strong>: considera-se um fato como t\u00edpico quando ele se amolda \u00e0 hip\u00f3tese prevista em lei. Ou seja, a a\u00e7\u00e3o ou omiss\u00e3o do agente se encaixa perfeitamente naquilo que disp\u00f5e a norma penal;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Ilicitude<\/mark><\/strong>: a ilicitude consiste na contrariedade da conduta do agente em rela\u00e7\u00e3o ao ordenamento jur\u00eddico;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Culpabilidade<\/mark><\/strong>: trata-se da an\u00e1lise da conduta sob o ponto de vista da reprova\u00e7\u00e3o. \u00c9 a possibilidade de se atribuir a conduta praticada e o resultado ao seu respectivo autor, com um ju\u00edzo de censura;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Punibilidade<\/mark><\/strong>: consiste na possibilidade de o Estado aplicar ao sujeito ativo a san\u00e7\u00e3o penal legalmente prevista para a conduta t\u00edpica que por ele foi praticada. Alguns fatores como a morte do agente ou a prescri\u00e7\u00e3o, por exemplo, extinguem a punibilidade.<\/li>\n<\/ol>\n\n\n\n<p>Pois bem. Agora que temos uma no\u00e7\u00e3o geral do que se entende por crime, vamos ampliar nosso olhar para a teoria geral do crime.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estrutura da teoria do crime<\/h2>\n\n\n\n<p>A teoria do crime abrange os seguintes aspectos:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Conceito de crime (apresentado no t\u00f3pico anterior);<\/li>\n\n\n\n<li>Fato t\u00edpico (conduta, tipicidade, resultado e nexo de causalidade);<\/li>\n\n\n\n<li>Iter criminis (caminho do crime);<\/li>\n\n\n\n<li>Ilicitude e suas excludentes;<\/li>\n\n\n\n<li>Culpabilidade;<\/li>\n\n\n\n<li>Sujeitos do crime; e<\/li>\n\n\n\n<li>Classifica\u00e7\u00f5es dos crimes.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise estat\u00edstica da teoria do crime<\/h2>\n\n\n\n<p>Pessoal, abaixo temos uma an\u00e1lise estat\u00edstica realizada dentro da tem\u00e1tica de Teoria do Crime, para que possamos entender quais s\u00e3o os dispositivos legais mais queridinhos pelas bancas examinadoras.<\/p>\n\n\n\n<p>Tal an\u00e1lise foi realizada com quest\u00f5es objetivas das seguintes bancas: <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Bancas CEBRASPE (CESPE), FGV, FCC, Instituto AOCP, Vunesp, IBFC<\/mark><\/strong>, entre os anos de <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">2018 a 2023<\/mark><\/strong>, todas as \u00e1reas:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Teoria Geral do Crime (Foram encontradas 493 quest\u00f5es)<\/strong><\/td><\/tr><tr><td><strong>Assunto<\/strong><\/td><td><strong>Quantidade de quest\u00f5es<\/strong><\/td><td><strong>%<\/strong><\/td><\/tr><tr><td>Conceito de crime<\/td><td>2<\/td><td>0,41%<\/td><\/tr><tr><td>Fato t\u00edpico<\/td><td>130<\/td><td>26,37%<\/td><\/tr><tr><td>Iter criminis<\/td><td>87<\/td><td>17,65%<\/td><\/tr><tr><td>Ilicitude e suas excludentes<\/td><td>84<\/td><td>17,04%<\/td><\/tr><tr><td>Culpabilidade<\/td><td>104<\/td><td>21,10%<\/td><\/tr><tr><td>Sujeitos do crime<\/td><td>65<\/td><td>13,18%<\/td><\/tr><tr><td>Classifica\u00e7\u00f5es do crime<\/td><td>21<\/td><td>4,26%<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">An\u00e1lise estat\u00edstica- Teoria do Crime<\/figcaption><\/figure>\n\n\n\n<p>Observando a tabela acima, podemos perceber que <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">fato t\u00edpico e culpabilidade<\/mark><\/strong> s\u00e3o os camp\u00f5es de cobran\u00e7as. Desse modo, apesar de ser importante estudar a teoria geral do crime como um todo, afinal, os institutos se complementam, os t\u00f3picos relacionados ao fato t\u00edpico e a culpabilidade merecem aten\u00e7\u00e3o redobrada (ou triplicada!).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Voc\u00ea n\u00e3o pode deixar de saber: Teoria Geral do Crime<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No \u00e2mbito do fato t\u00edpico, estude com aten\u00e7\u00e3o os diferentes <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">conceitos de conduta<\/mark><\/strong> para as v\u00e1rias teorias, dando especial aten\u00e7\u00e3o \u00e0 teoria finalista;<\/li>\n\n\n\n<li>Saiba tudo sobre <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">omiss\u00e3o<\/mark><\/strong>: crimes omissivos pr\u00f3prios e impr\u00f3prios;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Rela\u00e7\u00e3o de causalidade<\/mark><\/strong> (nexo causal) \u00e9 tema certo nas provas;<\/li>\n\n\n\n<li>Saiba diferenciar dolo, culpa e preterdolo;<\/li>\n\n\n\n<li>Atente-se para a <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">consuma\u00e7\u00e3o e tentativa<\/mark><\/strong>;<\/li>\n\n\n\n<li>N\u00e3o deixe de estudar as <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">excludentes de ilicitude<\/mark><\/strong>, especialmente a leg\u00edtima defesa e o estado de necessidade;<\/li>\n\n\n\n<li>Conhe\u00e7a muito bem as <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">teorias da culpabilidade<\/mark><\/strong>;<\/li>\n\n\n\n<li>Saiba diferenciar imputabilidade, inimputabilidade e semi-ininputabilidade;<\/li>\n\n\n\n<li><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Teoria do erro<\/mark><\/strong> n\u00e3o pode ficar de fora da sua revis\u00e3o. Certifique-se de que n\u00e3o est\u00e1 confundindo as diversas modalidades de erro;<\/li>\n<\/ul>\n\n\n\n<p>Ufa! Quantos detalhes, n\u00e3o \u00e9 mesmo? O lado bom \u00e9 que esse tema costuma despencar em concursos e com certeza ir\u00e3o te render bons pontos na prova.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Temas especiais de Direito Penal<\/h2>\n\n\n\n<p>Amigos, no v\u00eddeo abaixo o Professor Renan Ara\u00fajo trouxe, de forma bastante did\u00e1tica, alguns temas especiais de Direito Penal:<\/p>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" style=\"width:853px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_Kf1-EEcznNI\"><div id=\"lyte_Kf1-EEcznNI\" data-src=\"\/\/i.ytimg.com\/vi\/Kf1-EEcznNI\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/Kf1-EEcznNI\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/Kf1-EEcznNI\/0.jpg\" alt=\"YouTube video thumbnail\" width=\"853\" height=\"460\" \/><br \/>Assista a este v\u00eddeo no YouTube<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px;\"><\/div><figcaption><\/figcaption><\/figure>\n\n\n<p class=\"wp-embed-aspect-16-9 wp-has-aspect-ratio\"><a href=\"https:\/\/www.youtube.com\/watch?v=Kf1-EEcznNI&amp;ab_channel=Estrat%C3%A9giaConcursos\">https:\/\/www.youtube.com\/watch?v=Kf1-EEcznNI&amp;ab_channel=Estrat%C3%A9giaConcursos<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consideracoes-finais\">Considera\u00e7\u00f5es Finais<\/h2>\n\n\n\n<p>Finalizamos mais um artigo, galera. Desejamos que as informa\u00e7\u00f5es aqui apresentadas possam ajud\u00e1-los na jornada di\u00e1ria de estudos e, dessa forma, contribuir para sua aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para uma prepara\u00e7\u00e3o completa, invista nos <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursos\/concurso\/\">cursos do Estrat\u00e9gia Concursos.<\/a> <\/strong>L\u00e1 voc\u00ea encontrar\u00e1 aulas completas e detalhadas, com os melhores professores do mercado, de todos os t\u00f3picos exigidos no edital do seu concurso.<\/p>\n\n\n\n<p>Conhe\u00e7a tamb\u00e9m o <strong><a href=\"https:\/\/concursos.estrategia.com\/\">Sistema de Quest\u00f5es do Estrat\u00e9gia.<\/a><\/strong> Afinal, a \u00fanica maneira de consolidar o conte\u00fado de maneira satisfat\u00f3ria \u00e9 atrav\u00e9s da resolu\u00e7\u00e3o de quest\u00f5es.<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima, pessoal!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Refer\u00eancias Bibliogr\u00e1ficas<\/h2>\n\n\n\n<p>CUNHA. Rog\u00e9rio Sanches. Manual de Direito Penal: Parte Geral (arts. 1 ao 120). 8\u00aa ed. Ver., ampl. E atual. \u2013 Salvador: JusPODIVM, 2020.<\/p>\n\n\n\n<p>MASSON, Cleber. Direito penal: parte geral (arts. 1\u00ba a 120) &#8211; volume 1.<\/p>\n\n\n\n<p>PROC\u00d3PIO. Michael. Curso de Direito Penal. Estrat\u00e9gia Concursos- Carreiras Jur\u00eddicas. 2022.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\">Concursos abertos<\/a><\/mark><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-background\" style=\"background-color:#0078bd\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-white-color\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\">Concursos 2023<\/a><\/mark><\/strong><\/p>\n\n\n\n<div class=\"container\" id=\"boxes\">\n  <div class=\"row\">\n    <div class=\"col-sm\">\n      <div class=\"estrategia\" id=\"box-assinatura\">\n        <h3 class=\"titulo-assinatura\">Assinatura de Concursos<\/h3>\n        <p class=\"subtitulo-assinatura\">Assinatura de 1 ano ou 2 anos<\/p>\n        <div class=\"box-botao\">\n          <a class=\"btn-assinatura\" target=\"_blank\" href=\"https:\/\/www.estrategiaconcursos.com.br\/assinaturas\/\" role=\"button\" rel=\"noopener noreferrer\">ASSINE AGORA<\/a>\n        <\/div>\n      <\/div>\n      \n    <\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Refer\u00eancias Bibliogr\u00e1ficas<\/h2>\n\n\n\n<p>CUNHA. Rog\u00e9rio Sanches. Manual de Direito Penal: Parte Geral (arts. 1 ao 120). 8\u00aa ed. Ver., ampl. E atual. \u2013 Salvador: JusPODIVM, 2020.<\/p>\n\n\n\n<p>MASSON, Cleber. Direito penal: parte geral (arts. 1\u00ba a 120) &#8211; volume 1.<\/p>\n\n\n\n<p>PROC\u00d3PIO. Michael. Curso de Direito Penal. Estrat\u00e9gia Concursos- Carreiras Jur\u00eddicas. 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teoria do Crime Ol\u00e1, amigos. Tudo bom? Espero que sim. Hoje nosso artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: Teoria do Crime. Tendo em vista que este tema \u00e9 bastante abrangente e complexo, \u00e9 de suma import\u00e2ncia que haja o conhecimento de suas [&hellip;]<\/p>\n","protected":false},"author":1572,"featured_media":1184918,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[219964,219965,219966,219967,219968,219969,219963,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1184505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-concursos-federais","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Teoria do Crime<\/title>\n<meta name=\"description\" content=\"Este artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: Teoria do Crime.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teoria do Crime\" \/>\n<meta property=\"og:description\" content=\"Este artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: Teoria do Crime.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-02T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcela Neves Suonski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcela Neves Suonski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/\"},\"author\":{\"name\":\"Marcela Neves Suonski\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a15c21c2f6fa4756fcdcb8613065671c\"},\"headline\":\"Teoria do Crime\",\"datePublished\":\"2023-04-02T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/\"},\"wordCount\":1025,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/\",\"name\":\"Teoria do Crime\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg\",\"datePublished\":\"2023-04-02T11:00:00+00:00\",\"description\":\"Este artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: Teoria do Crime.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Teoria do Crime\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teoria do Crime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a15c21c2f6fa4756fcdcb8613065671c\",\"name\":\"Marcela Neves Suonski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0d4a2e1e9762c57505715db480ae30bd030689a7d92a8cfab6265cca9baff330?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d4a2e1e9762c57505715db480ae30bd030689a7d92a8cfab6265cca9baff330?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d4a2e1e9762c57505715db480ae30bd030689a7d92a8cfab6265cca9baff330?s=96&d=mm&r=g\",\"caption\":\"Marcela Neves Suonski\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/marcela_nevessuonskihotmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teoria do Crime","description":"Este artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: Teoria do Crime.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/","og_locale":"pt_BR","og_type":"article","og_title":"Teoria do Crime","og_description":"Este artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: Teoria do Crime.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-04-02T11:00:00+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Marcela Neves Suonski","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Marcela Neves Suonski","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/"},"author":{"name":"Marcela Neves Suonski","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a15c21c2f6fa4756fcdcb8613065671c"},"headline":"Teoria do Crime","datePublished":"2023-04-02T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/"},"wordCount":1025,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg","articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/","name":"Teoria do Crime","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg","datePublished":"2023-04-02T11:00:00+00:00","description":"Este artigo trata de uma vis\u00e3o geral acerca do t\u00f3pico mais explorado em Direito Penal nas provas de concursos p\u00fablicos: Teoria do Crime.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/10133400\/phoebe-t-ybq0tlcaa7i-unsplash-scaled.jpg","width":2560,"height":1920,"caption":"Teoria do Crime"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/teoria-crime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Teoria do Crime"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/a15c21c2f6fa4756fcdcb8613065671c","name":"Marcela Neves Suonski","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0d4a2e1e9762c57505715db480ae30bd030689a7d92a8cfab6265cca9baff330?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0d4a2e1e9762c57505715db480ae30bd030689a7d92a8cfab6265cca9baff330?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d4a2e1e9762c57505715db480ae30bd030689a7d92a8cfab6265cca9baff330?s=96&d=mm&r=g","caption":"Marcela Neves Suonski"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/marcela_nevessuonskihotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1184505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1572"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1184505"}],"version-history":[{"count":8,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1184505\/revisions"}],"predecessor-version":[{"id":1185800,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1184505\/revisions\/1185800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1184918"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1184505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1184505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1184505"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1184505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}