{"id":1179894,"date":"2023-03-27T14:00:00","date_gmt":"2023-03-27T17:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1179894"},"modified":"2023-03-20T14:43:19","modified_gmt":"2023-03-20T17:43:19","slug":"ativo-intangivel-rfb","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/","title":{"rendered":"Resumo Ativo Intang\u00edvel para a RFB"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><em>Resumo dos principais aspectos do CPC 04 &#8211; Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil &#8211; RFB.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg\" alt=\"ativo intang\u00edvel rfb\" class=\"wp-image-1179895\" width=\"533\" height=\"400\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a-300x225.jpeg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a-610x458.jpeg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a-150x113.jpeg 150w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><figcaption class=\"wp-element-caption\">Concurso Receita Federal<\/figcaption><\/figure>\n\n\n\n<p>Fala, pessoal!<\/p>\n\n\n\n<p>Tudo bem com voc\u00eas?<\/p>\n\n\n\n<p>Hoje vamos conhecer os principais aspectos do CPC 04 &#8211; Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil &#8211; RFB. \u00c9 um assunto tranquilo e muito importante para a sua prova.<\/p>\n\n\n\n<p>O concurso da <a href=\"https:\/\/conhecimento.fgv.br\/concursos\/rfb22\">Receita Federal<\/a> trouxe uma oportunidade \u00fanica para o concurseiro da \u00e1rea fiscal. <strong>S\u00e3o 699 vagas com remunera\u00e7\u00f5es de at\u00e9 R$21.000.<\/strong><\/p>\n\n\n\n<p>Destas vagas, <strong>469 s\u00e3o para o cargo de&nbsp; Analista Tribut\u00e1rio (ATRFB) e 230 para Auditor Fiscal (AFRFB<\/strong>), ambos com exig\u00eancia em n\u00edvel superior de forma\u00e7\u00e3o.<\/p>\n\n\n\n<p>Contabilidade \u00e9 uma mat\u00e9ria important\u00edssima que vem sendo cobrada em alto n\u00edvel pela Funda\u00e7\u00e3o Get\u00falio Vargas (FGV).<\/p>\n\n\n\n<p>Portanto, \u00e9 fundamental que estejam bem preparados para quest\u00f5es deste tema.<\/p>\n\n\n\n<p>Vamos nessa?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-definicoes-e-alcance-do-cpc-04\">Defini\u00e7\u00f5es e alcance do CPC 04<\/h2>\n\n\n\n<p>Um dos principais pontos acerca dos ativos intang\u00edveis \u00e9 saber como s\u00e3o identificados e quais os crit\u00e9rios para que possam ser reconhecidos.<\/p>\n\n\n\n<p>Dessa forma, as normas definem que devem ser classificados no ativo intang\u00edvel os direitos que tenham por <strong>objeto bens incorp\u00f3reos destinados \u00e0 manuten\u00e7\u00e3o da companhia ou exercidos com essa finalidade<\/strong>, inclusive o fundo de com\u00e9rcio adquirido, e est\u00e3o contidos no grupo ativo n\u00e3o-circulante.<\/p>\n\n\n\n<p>\u00c9 importante ressaltar que o CPC 04 se aplica nos casos em que n\u00e3o haja outro pronunciamento t\u00e9cnico espec\u00edfico. Por exemplo, para os ativos intang\u00edveis mantidos por uma empresa para a venda no curso ordin\u00e1rio dos neg\u00f3cios, aplica-se o CPC 16 &#8211; Estoques. Ainda, no caso de arrendamentos de ativo intang\u00edvel,deve-se seguir o CPC 06 &#8211; Arrendamentos.<\/p>\n\n\n\n<p>Conforme defini\u00e7\u00e3o do CPC 04, <strong><em>ativo intang\u00edvel \u00e9 um ativo n\u00e3o monet\u00e1rio identific\u00e1vel sem subst\u00e2ncia f\u00edsica<\/em><\/strong>. Esta \u00e9 uma defini\u00e7\u00e3o important\u00edssima para a sua prova, vamos entender cada parte.<\/p>\n\n\n\n<p>Ativo<strong> monet\u00e1rio<\/strong> \u00e9 aquele representado <strong>por dinheiro ou por direitos a serem recebidos em dinheiro<\/strong>.<\/p>\n\n\n\n<p>De forma contr\u00e1ria e bem simples, o ativo<strong> n\u00e3o monet\u00e1rio<\/strong> \u00e9 aquele que<strong> n\u00e3o \u00e9 representado por dinheiro ou direito a ser recebido em dinheiro<\/strong>.<\/p>\n\n\n\n<p>Por exemplo, um computador \u00e9 representado por dinheiro ou direito a ser recebido em dinheiro? N\u00e3o! Portanto, \u00e9 considerado um ativo n\u00e3o monet\u00e1rio.<\/p>\n\n\n\n<p>No caso do exemplo de um item que seria classificado como intang\u00edvel temos o software, ele \u00e9 representado por dinheiro ou direito a ser recebido em dinheiro? N\u00e3o! Portanto, \u00e9 um ativo n\u00e3o monet\u00e1rio. Ele possui subst\u00e2ncia f\u00edsica? N\u00e3o! Com isso, vai ser classificado, em regra, como intang\u00edvel.<\/p>\n\n\n\n<p>Mas cuidado aqui! Alguns ativos intang\u00edveis, a exemplo do software, podem estar contidos em elementos que possuem subst\u00e2ncia f\u00edsica.<\/p>\n\n\n\n<p>Nestes casos, a entidade deve avaliar qual elemento \u00e9 mais significativo e se s\u00e3o indispens\u00e1veis de alguma forma para o outro.<\/p>\n\n\n\n<p>Por exemplo, um software de uma m\u00e1quina controlada por computador que n\u00e3o funciona sem esse software espec\u00edfico \u00e9 considerado parte integrante do referido equipamento, devendo, portanto, ser considerado como ativo imobilizado.<\/p>\n\n\n\n<p>Da mesma forma, no caso de um sistema operacional de um computador, a m\u00e1quina n\u00e3o funciona sem esse sistema b\u00e1sico, portanto, o sistema operacional \u00e9 reconhecido junto com a m\u00e1quina no ativo imobilizado. Por\u00e9m, quando o software n\u00e3o \u00e9 parte integrante do respectivo hardware, ele deve ser tratado como ativo intang\u00edvel.<\/p>\n\n\n\n<p>Por exemplo, se a empresa adquire softwares de antiv\u00edrus para melhorar a prote\u00e7\u00e3o dos computadores da empresa, a despeito de ser um item importante para o computador, n\u00e3o \u00e9 essencial para o seu funcionamento e, com isso, ser\u00e1 contabilizado no ativo intang\u00edvel.<\/p>\n\n\n\n<p>&nbsp;Exemplos de itens que se enquadram na categoria de ativo intang\u00edvel s\u00e3o:<\/p>\n\n\n\n<p><strong>&#8211; softwares<\/strong><\/p>\n\n\n\n<p><strong>&#8211; patentes<\/strong><\/p>\n\n\n\n<p><strong>&#8211; direitos autorais<\/strong><\/p>\n\n\n\n<p><strong>&#8211; direitos sobre filmes cinematogr\u00e1ficos<\/strong><\/p>\n\n\n\n<p><strong>&#8211; listas de clientes,<\/strong><\/p>\n\n\n\n<p><strong>&#8211; franquias<\/strong><\/p>\n\n\n\n<p><strong>&#8211; relacionamentos com clientes ou fornecedores<\/strong><\/p>\n\n\n\n<p>Por\u00e9m, aqui vamos para outro ponto muito importante do CPC 04, nem todos os itens descritos acima se enquadram na defini\u00e7\u00e3o de ativo intang\u00edvel. Para que o sejam, devem atender a 3 requisitos:<\/p>\n\n\n\n<p><strong>&#8211; s\u00e3o identific\u00e1veis<\/strong><\/p>\n\n\n\n<p><strong>-s\u00e3o controlados<\/strong><\/p>\n\n\n\n<p><strong>&#8211; s\u00e3o geradores de benef\u00edcios econ\u00f4micos futuros<\/strong><\/p>\n\n\n\n<p>&nbsp;Caso um item abrangido pelo presente CPC <strong>n\u00e3o atenda \u00e0 defini\u00e7\u00e3o de ativo intang\u00edvel<\/strong>, o gasto incorrido na sua aquisi\u00e7\u00e3o ou gera\u00e7\u00e3o interna <strong>deve ser reconhecido como despesa quando incorrido.<\/strong><\/p>\n\n\n\n<p>Mas, caso o item seja adquirido em uma combina\u00e7\u00e3o de neg\u00f3cios, passa a fazer parte do \u00e1gio derivado da expectativa de rentabilidade futura (goodwill) reconhecido na data da aquisi\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>O goodwill, no balan\u00e7o individual, fica no grupo de investimentos e balan\u00e7o consolidado, fica no intang\u00edvel.<\/strong><\/p>\n\n\n\n<p>Vejamos alguns detalhes referentes ao \u00e1gio por expectativa de rentabilidade futura trazidos pelo CPC 04.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ativo Intang\u00edvel: goodwill<\/h2>\n\n\n\n<p>&nbsp;Em suma, o \u00e1gio por expectativa de rentabilidade futura surge em uma combina\u00e7\u00e3o de neg\u00f3cio, onde o controle de uma empresa \u00e9 transferido \u00e0 outra, e corresponde ao <strong>excesso de pre\u00e7o pago pela compra de um empreendimento ou patrim\u00f4nio sobre o valor de mercado de seus ativos l\u00edquidos<\/strong>. Basicamente \u00e9 o valor pago menos o valor justo (n\u00e3o entraremos aqui em detalhes mais espec\u00edficos do c\u00e1lculo do goodwill porque n\u00e3o \u00e9 o foco deste artigo). Vejamos a defini\u00e7\u00e3o trazida pelo CPC 04:<\/p>\n\n\n\n<p><strong><em>O \u00e1gio derivado da expectativa de rentabilidade futura (goodwill) reconhecido em uma combina\u00e7\u00e3o de neg\u00f3cios \u00e9 um ativo que representa benef\u00edcios econ\u00f4micos futuros gerados por outros ativos adquiridos em uma combina\u00e7\u00e3o de neg\u00f3cios, que<\/em><\/strong><strong><em> n\u00e3o s\u00e3o identificados individualmente e reconhecidos separadamente.<\/em><\/strong><\/p>\n\n\n\n<p>Com isso, \u00e9 importante entender as diferen\u00e7as existentes entre o goodwill e o ativo intang\u00edvel \u201ctradicional\u201d.<\/p>\n\n\n\n<p>O primeiro ponto \u00e9 que o<strong> intang\u00edvel pode ser reconhecido individualmente, o \u00e1gio n\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Ademais, a <strong>defini\u00e7\u00e3o de ativo intang\u00edvel requer que ele seja identific\u00e1vel, para diferenci\u00e1-lo do \u00e1gio derivado da expectativa de rentabilidade futura (goodwill).<\/strong><\/p>\n\n\n\n<p>E o que qualifica um ativo como identific\u00e1vel?<\/p>\n\n\n\n<p>S\u00e3o basicamente duas situa\u00e7\u00f5es que levam a reconhecer um ativo intang\u00edvel como identific\u00e1vel, quais sejam:<\/p>\n\n\n\n<p>&#8211; <strong>se for separ\u00e1vel:<\/strong> puder ser<strong> separado <\/strong>da entidade e <strong>vendido, transferido, licenciado, alugado ou trocado<\/strong>, individualmente ou junto com um contrato, ativo ou passivo relacionado, independente da inten\u00e7\u00e3o de uso pela entidade;<\/p>\n\n\n\n<p>&#8211; <strong>se resultar de direitos contratuais ou outros direitos legais<\/strong>,<strong> independentemente de tais direitos serem transfer\u00edveis ou separ\u00e1veis<\/strong> da entidade ou de outros direitos e obriga\u00e7\u00f5es.<\/p>\n\n\n\n<p>Fiquem atentos \u00e0s palavras chaves pois este \u00e9 um t\u00f3pico que despenca em prova. Vejamos alguns pontos importantes acerca do ativo intang\u00edvel gerado internamente para o seu concurso da RFB.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ativo intang\u00edvel gerado internamente<\/h2>\n\n\n\n<p>No geral, \u00e9 dif\u00edcil fazer uma avalia\u00e7\u00e3o se um ativo intang\u00edvel gerado internamente pode ser reconhecido, isso porque pode ser complicado avaliar se haver\u00e1 gera\u00e7\u00e3o de benef\u00edcios econ\u00f4micos futuros, e mensurar o seu custo com efici\u00eancia.<\/p>\n\n\n\n<p>Sabemos que o ativo intang\u00edvel somente ser\u00e1 reconhecido se for prov\u00e1vel que o que os<strong> benef\u00edcios econ\u00f4micos futuros esperados atribu\u00edveis ao ativo ser\u00e3o gerados em favor da entidade e o custo do ativo possa ser mensurado com seguran\u00e7a.<\/strong><\/p>\n\n\n\n<p>No geral, existem duas fases da constru\u00e7\u00e3o de ativos intang\u00edveis gerados internamente: a pesquisa e o desenvolvimento.<\/p>\n\n\n\n<p>O CPC 04 nos diz que nenhum gasto da fase de pesquisa deve ser reconhecido no ativo, devem, portanto, ser reconhecidos como despesa no resultado, quando incorridos.<\/p>\n\n\n\n<p>Aqui vale uma observa\u00e7\u00e3o mais avan\u00e7ada. No caso de uma combina\u00e7\u00e3o de neg\u00f3cios que envolva ativos gerados internamente, estes gastos com pesquisa s\u00e3o considerados para a determina\u00e7\u00e3o do valor justo da empresa.<\/p>\n\n\n\n<p>Alguns <strong>exemplos de atividades de pesquisa<\/strong> s\u00e3o (isso j\u00e1 foi cobrado pela FGV):<\/p>\n\n\n\n<p>&#8211; atividades destinadas \u00e0 obten\u00e7\u00e3o de novo conhecimento;<\/p>\n\n\n\n<p>&#8211; busca de alternativas para materiais, dispositivos, produtos, processos, sistemas ou servi\u00e7os;<\/p>\n\n\n\n<p>&#8211; busca, avalia\u00e7\u00e3o e sele\u00e7\u00e3o final das aplica\u00e7\u00f5es dos resultados de pesquisa ou outros conhecimentos; e<\/p>\n\n\n\n<p>&#8211; formula\u00e7\u00e3o, projeto, avalia\u00e7\u00e3o e sele\u00e7\u00e3o final de alternativas poss\u00edveis para materiais, dispositivos, produtos, processos, sistemas ou servi\u00e7os novos ou aperfei\u00e7oados.<\/p>\n\n\n\n<p>Por outro lado,na fase de desenvolvimento, j\u00e1 \u00e9 poss\u00edvel, atendidos os requisitos da norma, o reconhecimento do ativo intang\u00edvel gerado internamente.<\/p>\n\n\n\n<p>Um ativo em fase de desenvolvimento deve ser reconhecido<strong> somente se a entidade puder demonstrar TODOS os aspectos a seguir enumerados:<\/strong><\/p>\n\n\n\n<p>&#8211; viabilidade t\u00e9cnica para concluir o ativo intang\u00edvel de forma que ele seja disponibilizado para uso ou venda;<\/p>\n\n\n\n<p>&#8211; inten\u00e7\u00e3o de concluir o ativo intang\u00edvel e de us\u00e1-lo ou vend\u00ea-lo;<\/p>\n\n\n\n<p>&#8211; capacidade para usar ou vender o ativo intang\u00edvel;<\/p>\n\n\n\n<p>&#8211; forma como o ativo intang\u00edvel deve gerar benef\u00edcios econ\u00f4micos futuros.<\/p>\n\n\n\n<p>-disponibilidade de recursos t\u00e9cnicos, financeiros e outros recursos adequados para concluir seu desenvolvimento e usar ou vender o ativo intang\u00edvel; e<\/p>\n\n\n\n<p>&#8211; capacidade de mensurar com seguran\u00e7a os gastos atribu\u00edveis ao ativo intang\u00edvel<\/p>\n\n\n\n<p>durante seu desenvolvimento.<\/p>\n\n\n\n<p>Por fim, outra informa\u00e7\u00e3o que n\u00e3o pode ficar de fora \u00e9 que no caso de <strong>marcas, t\u00edtulos de publica\u00e7\u00f5es, listas de clientes e outros itens similares gerados internamente<\/strong> <strong>n\u00e3o podem ser reconhecidos como ativos intang\u00edveis. <\/strong>Isso porque n\u00e3o podem ser separados dos custos do desenvolvimento do neg\u00f3cio como um todo.<\/p>\n\n\n\n<p>Pessoal, n\u00e3o deixem de fazer a leitura completa do CPC 04 &#8211; Ativo Intang\u00edvel para o seu concurso da RFB. Em outros artigos abordaremos outros aspectos desta norma, fiquem ligados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Finalizando<\/h2>\n\n\n\n<p>Pessoal, esse foi o nosso resumo sobre os principais aspectos do CPC 04 &#8211; Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil &#8211; RFB. Busquem compreender como s\u00e3o feitas as contabiliza\u00e7\u00f5es de cada caso e estar\u00e3o preparados para as quest\u00f5es sobre o assunto.<\/p>\n\n\n\n<p>O Estrat\u00e9gia Concursos possui o curso completo de Contabilidade Geral para o concurso da RFB, n\u00e3o deixem de conferir.<\/p>\n\n\n\n<p>Bons estudos!<\/p>\n\n\n\n<p>At\u00e9 a pr\u00f3xima.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-cursos-e-assinaturas\">Cursos e Assinaturas <\/h2>\n\n\n\n<p>Prepare-se com o melhor material e com quem mais aprova em Concursos P\u00fablicos em todo o pa\u00eds!<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-purple-background-color has-text-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos abertos<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-purple-background-color has-background\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Concursos <\/strong>2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo dos principais aspectos do CPC 04 &#8211; Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil &#8211; RFB.<\/p>\n","protected":false},"author":2459,"featured_media":1179895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1,220182],"tags":[40,484],"tax_estado":[219963],"class_list":["post-1179894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-fiscal-federal","tag-concurso","tag-receita-federal","tax_estado-concursos-federais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resumo Ativo Intang\u00edvel para a RFB<\/title>\n<meta name=\"description\" content=\"Resumo dos principais aspectos do CPC 04 - Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil - RFB.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo Ativo Intang\u00edvel para a RFB\" \/>\n<meta property=\"og:description\" content=\"Resumo dos principais aspectos do CPC 04 - Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil - RFB.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-27T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00e9ssica Luciano Barcelos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00e9ssica Luciano Barcelos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/\"},\"author\":{\"name\":\"J\u00e9ssica Luciano Barcelos\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8207b340097a76d57b0d52dd527d7e53\"},\"headline\":\"Resumo Ativo Intang\u00edvel para a RFB\",\"datePublished\":\"2023-03-27T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/\"},\"wordCount\":1732,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg\",\"keywords\":[\"Concurso\",\"Receita Federal\"],\"articleSection\":[\"Concursos P\u00fablicos\",\"Fiscal - Federal (RFB e AFT)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/\",\"name\":\"Resumo Ativo Intang\u00edvel para a RFB\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg\",\"datePublished\":\"2023-03-27T17:00:00+00:00\",\"description\":\"Resumo dos principais aspectos do CPC 04 - Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil - RFB.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg\",\"width\":768,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo Ativo Intang\u00edvel para a RFB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8207b340097a76d57b0d52dd527d7e53\",\"name\":\"J\u00e9ssica Luciano Barcelos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/feaa24cba2d6d73f21c019e05c8bff471043b1db62437f2c2e5112e2f3773495?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/feaa24cba2d6d73f21c019e05c8bff471043b1db62437f2c2e5112e2f3773495?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/feaa24cba2d6d73f21c019e05c8bff471043b1db62437f2c2e5112e2f3773495?s=96&d=mm&r=g\",\"caption\":\"J\u00e9ssica Luciano Barcelos\"},\"description\":\"Formada em Engenharia Civil pela Universidade Federal dos Vales do Jequitinhonha e Mucuri (UFVJM). Aprovada para Auditora Fiscal da SEFAZ AM em 2022.\",\"sameAs\":[\"https:\/\/www.instagram.com\/jessicalbarcelos\/\",\"https:\/\/www.linkedin.com\/in\/jssica-barcelos-580594143\/\"],\"worksFor\":\"J\u00c9SSICA LUCIANO BARCELOS\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jessicalbarcelosgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resumo Ativo Intang\u00edvel para a RFB","description":"Resumo dos principais aspectos do CPC 04 - Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil - RFB.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo Ativo Intang\u00edvel para a RFB","og_description":"Resumo dos principais aspectos do CPC 04 - Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil - RFB.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-03-27T17:00:00+00:00","og_image":[{"width":768,"height":576,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg","type":"image\/jpeg"}],"author":"J\u00e9ssica Luciano Barcelos","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"J\u00e9ssica Luciano Barcelos","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/"},"author":{"name":"J\u00e9ssica Luciano Barcelos","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8207b340097a76d57b0d52dd527d7e53"},"headline":"Resumo Ativo Intang\u00edvel para a RFB","datePublished":"2023-03-27T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/"},"wordCount":1732,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg","keywords":["Concurso","Receita Federal"],"articleSection":["Concursos P\u00fablicos","Fiscal - Federal (RFB e AFT)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/","name":"Resumo Ativo Intang\u00edvel para a RFB","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg","datePublished":"2023-03-27T17:00:00+00:00","description":"Resumo dos principais aspectos do CPC 04 - Ativo Intang\u00edvel para o concurso da Receita Federal do Brasil - RFB.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/03\/01201655\/df91b10a-e7b7-47b9-b3a6-6d0ade57915a.jpeg","width":768,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/ativo-intangivel-rfb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo Ativo Intang\u00edvel para a RFB"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/8207b340097a76d57b0d52dd527d7e53","name":"J\u00e9ssica Luciano Barcelos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/feaa24cba2d6d73f21c019e05c8bff471043b1db62437f2c2e5112e2f3773495?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/feaa24cba2d6d73f21c019e05c8bff471043b1db62437f2c2e5112e2f3773495?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/feaa24cba2d6d73f21c019e05c8bff471043b1db62437f2c2e5112e2f3773495?s=96&d=mm&r=g","caption":"J\u00e9ssica Luciano Barcelos"},"description":"Formada em Engenharia Civil pela Universidade Federal dos Vales do Jequitinhonha e Mucuri (UFVJM). Aprovada para Auditora Fiscal da SEFAZ AM em 2022.","sameAs":["https:\/\/www.instagram.com\/jessicalbarcelos\/","https:\/\/www.linkedin.com\/in\/jssica-barcelos-580594143\/"],"worksFor":"J\u00c9SSICA LUCIANO BARCELOS","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/jessicalbarcelosgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1179894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2459"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1179894"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1179894\/revisions"}],"predecessor-version":[{"id":1179896,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1179894\/revisions\/1179896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1179895"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1179894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1179894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1179894"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1179894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}