{"id":117251,"date":"2018-11-10T00:00:23","date_gmt":"2018-11-10T03:00:23","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=117251"},"modified":"2021-08-10T13:35:50","modified_gmt":"2021-08-10T16:35:50","slug":"edital-dpe-rj-2018","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/","title":{"rendered":"Concurso DPE RJ Defensor: saiu o resultado da 1\u00aa fase; primeira prova escrita ocorre em novembro"},"content":{"rendered":"<p><em><span style=\"font-size: 18pt;\">Provas do concurso DPE RJ se estender\u00e3o at\u00e9 2019<\/span><\/em><\/p>\n<p>A Defensoria P\u00fablica do Estado do Rio de Janeiro divulgou, por meio de publica\u00e7\u00e3o no Di\u00e1rio Oficial do Estado, a rela\u00e7\u00e3o dos candidatos aprovados na primeira etapa do concurso para Defensor.<\/p>\n<p>Os aprovados se submeter\u00e3o agora \u00e0 primeira prova escrita espec\u00edfica, marcada para o dia 25 de novembro de 2018.<\/p>\n<p>O edital, publicado em abril de 2018,&nbsp; informa que existem, atualmente,&nbsp;<strong><em>20 cargos vagos<\/em><\/strong> na carreira, sendo&nbsp;<strong><em>1&nbsp;<\/em><\/strong>da classe inicial. S\u00e3o esperadas mais nomea\u00e7\u00f5es durante o per\u00edodo de validade do certame.<\/p>\n<p>A remunera\u00e7\u00e3o inicial para o cargo de Defensor P\u00fablico do Estado \u00e9 de&nbsp;<span style=\"color: #000000;\"><strong><em>R<\/em><em>$ 19.820,00.<\/em><\/strong><\/span><\/p>\n<p>Confira abaixo o cronograma completo do certame:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-122593\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg\" alt=\"CONCURSO DPE RJ DEFENSOR\" width=\"1264\" height=\"430\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 1264w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 610w\" sizes=\"auto, (max-width: 1264px) 100vw, 1264px\" \/><\/p>\n<h2>Requisitos do cargo<\/h2>\n<p>\u00c9 necess\u00e1rio que o candidato tenha diploma de&nbsp;<strong><em>bacharel em Direito<\/em><\/strong>, devidamente registrado e expedido por institui\u00e7\u00e3o reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC).<\/p>\n<p>Exige-se tamb\u00e9m a comprova\u00e7\u00e3o,&nbsp;<em><strong>na data da posse<\/strong><\/em>, do exerc\u00edcio de&nbsp;<strong><em>atividade jur\u00eddica<\/em><\/strong><strong>&nbsp;<\/strong>pelo tempo m\u00ednimo de&nbsp;<strong><em>dois anos<\/em><\/strong>.<\/p>\n<h2>Etapas do concurso DPE RJ<\/h2>\n<p><span style=\"color: #000000;\"><strong>1)&nbsp;<\/strong><em>Prova Escrita Preliminar;<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>2)<\/strong> <em>Provas Escritas Espec\u00edficas;<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>3)&nbsp;<\/strong><em>Provas de Sustenta\u00e7\u00e3o Oral;<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>4)&nbsp;<\/strong><em>Avalia\u00e7\u00e3o de T\u00edtulos.<\/em><\/span><\/p>\n<h2>Cronograma do certame<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-122593\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg\" alt=\"CONCURSO DPE RJ DEFENSOR\" width=\"827\" height=\"281\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 1264w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2018\/04\/24123700\/concurso-dpe-rj.jpg 610w\" sizes=\"auto, (max-width: 827px) 100vw, 827px\" \/><\/p>\n<h2>Disciplinas cobradas<\/h2>\n<p><span style=\"color: #000000;\">Direito Civil;<\/span><br \/>\n<span style=\"color: #000000;\">Direito Processual Civil;<\/span><br \/>\n<span style=\"color: #000000;\">Princ\u00edpios Institucionais da Defensoria P\u00fablica.<\/span><br \/>\n<span style=\"color: #000000;\">Direito Empresarial;<\/span><br \/>\n<span style=\"color: #000000;\">Direito Penal;<\/span><br \/>\n<span style=\"color: #000000;\">Direito Processual Penal;<\/span><br \/>\n<span style=\"color: #000000;\">Direito de Execu\u00e7\u00e3o Penal;<\/span><br \/>\n<span style=\"color: #000000;\">Criminologia;<\/span><br \/>\n<span style=\"color: #000000;\">Direito Constitucional;<\/span><br \/>\n<span style=\"color: #000000;\">Direito Administrativo;<\/span><br \/>\n<span style=\"color: #000000;\">Direitos Humanos das Pessoas em Situa\u00e7\u00e3o de Vulnerabilidade;<\/span><br \/>\n<span style=\"color: #000000;\">Tutela Coletiva;<\/span><br \/>\n<span style=\"color: #000000;\">Direito da Crian\u00e7a e do Adolescente.<\/span><\/p>\n<h2>Bancas Examinadoras<\/h2>\n<p><span style=\"color: #000000;\"><strong>BANCA I:<\/strong>&nbsp;<\/span><\/p>\n<p><span style=\"color: #000000;\">Direito Civil;<br \/>\n<\/span><span style=\"color: #000000;\">Direito Processual Civil;<br \/>\nDireito Empresarial;<br \/>\nTutela Coletiva;<br \/>\nPrinc\u00edpios Institucionais da Defensoria P\u00fablica.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>BANCA II<\/strong><br \/>\n<\/span><\/p>\n<p><span style=\"color: #000000;\">Direito Penal;<br \/>\nDireito Processual Penal;<br \/>\nDireito de Execu\u00e7\u00e3o Penal;<br \/>\nCriminologia.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>BANCA III:<\/strong><br \/>\n<\/span><\/p>\n<p><span style=\"color: #000000;\">Direitos Humanos das Pessoas em Situa\u00e7\u00e3o de Vulnerabilidade;<br \/>\nDireito Constitucional;<br \/>\nDireito Administrativo;<br \/>\nDireito da Crian\u00e7a e do Adolescente.<\/span><\/p>\n<h2>Provas do concurso DPE RJ 2018<\/h2>\n<p>O<strong>&nbsp;<em>concurso DPE RJ&nbsp;<\/em><\/strong> para o cargo de&nbsp;<strong><em>Defensor P\u00fablico do Estado<\/em><\/strong><strong>&nbsp;<\/strong>n\u00e3o tem&nbsp;<strong><em>prova objetiva<\/em><\/strong>. Todas as provas s\u00e3o&nbsp;<strong><em>escritas<\/em><\/strong>, exceto a de&nbsp;<strong><em>sustenta\u00e7\u00e3o oral<\/em><\/strong>.<\/p>\n<h2>Prova Escrita Preliminar<\/h2>\n<p>Esta prova tem car\u00e1ter&nbsp;<strong><em>eliminat\u00f3rio&nbsp;<\/em><\/strong>e&nbsp;<strong><em>classificat\u00f3rio<\/em><\/strong> e tem valor total de&nbsp;<strong><em>100 pontos<\/em><\/strong>. Os candidatos responder\u00e3o quest\u00f5es discursivas sobre&nbsp;<strong><em>todas as disciplinas do programa<\/em><\/strong>.<\/p>\n<p>A prova ser\u00e1 corrigida por, no m\u00ednimo, dois membros de cada banca examinadora, e a nota final ser\u00e1 a m\u00e9dia das pontua\u00e7\u00f5es atribu\u00eddas por cada um.<\/p>\n<p>\u00c9 necess\u00e1rio atingir as seguintes classifica\u00e7\u00f5es para ser convocado para as Provas Escritas Espec\u00edficas, respeitados os empates, de acordo com cada lista de vagas:<\/p>\n<p><span style=\"color: #000000;\">333\u00aa coloca\u00e7\u00e3o (ampla concorr\u00eancia);<\/span><\/p>\n<p><span style=\"color: #000000;\">26\u00aa coloca\u00e7\u00e3o (PcD);<\/span><\/p>\n<p><span style=\"color: #000000;\">104\u00aa coloca\u00e7\u00e3o (\u00edndios e negros);<\/span><\/p>\n<p><span style=\"color: #000000;\">52\u00aa coloca\u00e7\u00e3o (popula\u00e7\u00e3o com hipossufici\u00eancia econ\u00f4mica).<\/span><\/p>\n<h2>Provas Escritas Espec\u00edficas<\/h2>\n<p>Os candidatos realizar\u00e3o&nbsp;<strong><em>tr\u00eas provas<\/em><\/strong>, uma para cada banca examinadora. Estas provas ser\u00e3o classificat\u00f3rias e eliminat\u00f3rias e ter\u00e3o o valor total de&nbsp;<strong><em>100 pontos<\/em><\/strong><strong>&nbsp;<\/strong>cada.<\/p>\n<p>Sua aplica\u00e7\u00e3o se deu em&nbsp;<strong><em>datas diferentes<\/em><\/strong>: todos os candidatos habilitados prestar\u00e3o a&nbsp;<strong><em>primeira prova espec\u00edfica<\/em><\/strong> e somente os que atingirem as pontua\u00e7\u00f5es m\u00ednimas em cada prova (<strong><em>50 pontos<\/em><\/strong>) se classificar\u00e3o para a seguinte.<\/p>\n<p>Ser\u00e1 divulgada uma&nbsp;<strong><em>lista de 5 pontos por disciplina<\/em>&nbsp;<\/strong>que ser\u00e3o sorteados na data da prova. O candidato dever\u00e1 discorrer sobre o ponto sorteado.<\/p>\n<p>A lista de pontos ainda n\u00e3o foi divulgada. Voc\u00ea pode conferir a do \u00faltimo certame <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/04\/pontos2.pdf\" target=\"_blank\" rel=\"noopener\">clicando aqui<\/a>.<\/p>\n<h2>Prova de Sustenta\u00e7\u00e3o Oral<\/h2>\n<p>Os candidatos habilitados nas Provas Escritas Espec\u00edficas ser\u00e3o convocados para esta etapa do certame, que tem valor total de&nbsp;<strong><em>100 pontos<\/em><\/strong>.<\/p>\n<p>Ser\u00e1 sorteado um ponto sobre o qual o candidato dever\u00e1 sustentar oralmente a manifesta\u00e7\u00e3o ou pe\u00e7a processual relacionada \u00e0 quest\u00e3o pr\u00e1tica no tempo m\u00e1ximo de&nbsp;<strong><em>25 minutos<\/em><\/strong>.<\/p>\n<p>Os candidatos ter\u00e3o&nbsp;<strong><em>10 minutos<\/em><\/strong><strong>&nbsp;<\/strong>para a leitura da quest\u00e3o. A nota final ser\u00e1 calculada pela m\u00e9dia aritm\u00e9tica entre as pontua\u00e7\u00f5es atribu\u00eddas pelos examinadores.<\/p>\n<h2>Avalia\u00e7\u00e3o de T\u00edtulos<\/h2>\n<p>Os candidatos convocados para a Prova de Sustenta\u00e7\u00e3o Oral ser\u00e3o convocados, por meio de edital pr\u00f3prio, para apresentar a documenta\u00e7\u00e3o comprobat\u00f3ria referente aos t\u00edtulos.<\/p>\n<p>Os pontos atribu\u00eddos se distribuir\u00e3o da seguinte maneira:<\/p>\n<p><span style=\"color: #000000;\"><strong>a)<\/strong><em> 5,0 pontos para a aprova\u00e7\u00e3o em concurso p\u00fablico de provas e t\u00edtulos, para o exerc\u00edcio das profiss\u00f5es de Defensoria P\u00fablica, Minist\u00e9rio P\u00fablico, Magistratura, Advocacia Geral da Uni\u00e3o e Procuradoria Geral do Estado<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>b)<\/strong> <em>4,0 pontos para Doutorado na \u00e1rea jur\u00eddica, reconhecido oficialmente pelo \u00f3rg\u00e3o nacional brasileiro competente<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>c)<\/strong> <em>3,0 pontos para o exerc\u00edcio de magist\u00e9rio superior de direito; autoria de livros jur\u00eddicos; Mestrado na \u00e1rea jur\u00eddica, reconhecido oficialmente pelo \u00f3rg\u00e3o nacional brasileiro competente, e aprova\u00e7\u00e3o em concurso p\u00fablico de provas e t\u00edtulos para o Magist\u00e9rio Superior de Direito<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>d)<\/strong> <em>3,00 pontos para a nomea\u00e7\u00e3o e efetivo exerc\u00edcio no cargo de T\u00e9cnico Superior Jur\u00eddico da Defensoria P\u00fablica do Estado do Rio de Janeiro, por pelo menos um ano<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>e)<\/strong> <em>2,0 pontos para aprova\u00e7\u00e3o em concurso p\u00fablico para cargo que exija o requisito de ser bacharel em direito<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>f)<\/strong> <em>1,5 pontos para P\u00f3s-Gradua\u00e7\u00e3o na \u00e1rea jur\u00eddica, reconhecida oficialmente pelo \u00f3rg\u00e3o nacional brasileiro competente<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>g)<\/strong> <em>1,0 ponto para a conclus\u00e3o de cursos regulares ministrados pela Funda\u00e7\u00e3o Escola Superior da Defensoria P\u00fablica<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>h)<\/strong> <em>1,0 ponto para cada publica\u00e7\u00e3o, em autoria individual, e que obrigatoriamente envolva uma das mat\u00e9rias abrangidas pelo Concurso, em peri\u00f3dicos com avalia\u00e7\u00e3o Qualis\/CAPES nos estratos A e B<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>i)<\/strong> <em>1,5 ponto para cada publica\u00e7\u00e3o em autoria individual ou coautoria, por meio de editora com conselho editorial estabelecido, de livro jur\u00eddico devidamente registrado no ISBN\/ISSN<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>j)<\/strong> <em>0,5 ponto para o efetivo exerc\u00edcio de fun\u00e7\u00e3o, cargo, ou emprego p\u00fablico, na forma da Lei n\u00ba 2.646 de 22 de novembro de 1996<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>k)<\/strong><em> 0,5 ponto para estagi\u00e1rio oficial da Defensoria P\u00fablica do Estado do Rio de Janeiro, a cada 6 meses de est\u00e1gio, comprovado por certid\u00e3o do Est\u00e1gio&nbsp; Forense<\/em>;<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>l)<\/strong> <em>0,5 ponto para a participa\u00e7\u00e3o no programa de resid\u00eancia jur\u00eddica da Defensoria P\u00fablica a cada 6 meses de exerc\u00edcio, comprovado por certid\u00e3o da Coordena\u00e7\u00e3o da Resid\u00eancia Jur\u00eddica da Defensoria P\u00fablica<\/em>.<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 14pt;\">Gostou dessa <strong>oportunidade<\/strong>? Deseja se preparar para esta <strong>oportunidade<\/strong>?<\/span><\/em><br \/>\n<em><span style=\"font-size: 14pt;\">O Estrat\u00e9gia Concurso j\u00e1 tem cursos para o certame, <strong>Confira<\/strong>!<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/defensoria-publica-do-rio-de-janeiro-dpe-rj\/\"><span style=\"font-size: 18pt;\">CURSOS PARA CONCURSO DPE RJ DEFENSOR<\/span><\/a><\/p>\n<div id=\"attachment_60957\" style=\"width: 367px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-60957\" class=\"wp-image-60957 \" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2017\/01\/coruja-ficha-tecnica-1024x347.png\" alt=\"Concurso\" width=\"357\" height=\"121\"\/><p id=\"caption-attachment-60957\" class=\"wp-caption-text\"><span style=\"font-size: 14pt;\"><strong>\u2329Informa\u00e7\u00f5es do concurso DPE RJ 2018\u232a<\/strong><\/span><\/p><\/div>\n<p>\u25baData: 2018<br \/>\n\u25baVagas: 20 (cargos vagos)<br \/>\n\u25baCargos: Defensor P\u00fablico do Estado<br \/>\n\u25baLota\u00e7\u00f5es: Rio de Janeiro<br \/>\n\u25baBanca: DPE RJ<br \/>\n\u25baEscolaridade: N\u00edvel Superior em Direito + 2 anos de atividade jur\u00eddica<\/p>\n<p>\u25ba<strong>Cursos Estrat\u00e9gia Concursos<\/strong>: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorConcurso\/defensoria-publica-do-rio-de-janeiro-dpe-rj\/\" target=\"_blank\" rel=\"noopener\">Cursos Concurso DPE RJ Defensor 2018<\/a><br \/>\n\u25ba<strong>Edital<\/strong>: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/04\/Concurso-DPE-RJ-Edital.pdf\">Edital Concurso DPE RJ Defensor 2018<\/a><br \/>\n\u25ba<strong>Regulamento<\/strong>: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/02\/Regulamento-Concurso-DPE-RJ.pdf\" target=\"_blank\" rel=\"noopener\">Regulamento Concurso DPE RJ Defensor 2018<\/a><\/p>\n<p><i>Ricardo Brito<\/i><br \/>\n<em>Ascom Estrat\u00e9gia<\/em><br \/>\nascomestrategia@gmail.com<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><em><strong>Receba not\u00edcias de Concursos no seu WhatsApp e\/ou Telegram!<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><em><strong><span style=\"font-size: 14pt;\">Cadastre-se clicando no \u00edcone abaixo<\/span><br \/>\n<a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/noticias-de-concursos-whatsapp-estrategia-concursos\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-112824 \" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2018\/03\/whatsapptelegram.png\" alt=\"\" width=\"220\" height=\"124\"\/><\/a><br \/>\n<\/strong><\/em><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/noticias-de-concursos-whatsapp-estrategia-concursos\/\" target=\"_blank\" rel=\"noopener\">Not\u00edcias de concursos no seu WhatsApp e\/ou Telegram<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Provas do concurso DPE RJ se estender\u00e3o at\u00e9 2019 A Defensoria P\u00fablica do Estado do Rio de Janeiro divulgou, por meio de publica\u00e7\u00e3o no Di\u00e1rio Oficial do Estado, a rela\u00e7\u00e3o dos candidatos aprovados na primeira etapa do concurso para Defensor. Os aprovados se submeter\u00e3o agora \u00e0 primeira prova escrita espec\u00edfica, marcada para o dia 25 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":96435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"news","footnotes":""},"categories":[2185],"tags":[],"tax_estado":[219982],"class_list":["post-117251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreiras-juridicas","tax_estado-rj"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concurso DPE RJ Defensor: saiu o resultado da prova escrita geral<\/title>\n<meta name=\"description\" content=\"Concurso DPE RJ Defensor: publicada a lista dos aprovados na prova escrita geral do concurso da DPE RJ. Provas escritas espec\u00edficas come\u00e7am em novembro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso DPE RJ Defensor: saiu o resultado da 1\u00aa fase; primeira prova escrita ocorre em novembro\" \/>\n<meta property=\"og:description\" content=\"Concurso DPE RJ Defensor: publicada a lista dos aprovados na prova escrita geral do concurso da DPE RJ. Provas escritas espec\u00edficas come\u00e7am em novembro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/EstrategiaConcursos\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-10T03:00:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-10T16:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"209\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coordena\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coordena\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/\"},\"author\":{\"name\":\"Coordena\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\"},\"headline\":\"Concurso DPE RJ Defensor: saiu o resultado da 1\u00aa fase; primeira prova escrita ocorre em novembro\",\"datePublished\":\"2018-11-10T03:00:23+00:00\",\"dateModified\":\"2021-08-10T16:35:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/\"},\"wordCount\":1215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg\",\"articleSection\":[\"Jur\u00eddico\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/\",\"name\":\"Concurso DPE RJ Defensor: saiu o resultado da prova escrita geral\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg\",\"datePublished\":\"2018-11-10T03:00:23+00:00\",\"dateModified\":\"2021-08-10T16:35:50+00:00\",\"description\":\"Concurso DPE RJ Defensor: publicada a lista dos aprovados na prova escrita geral do concurso da DPE RJ. Provas escritas espec\u00edficas come\u00e7am em novembro.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg\",\"width\":400,\"height\":209,\"caption\":\"Concurso DPE RJ Defensor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso DPE RJ Defensor: saiu o resultado da 1\u00aa fase; primeira prova escrita ocorre em novembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f\",\"name\":\"Coordena\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g\",\"caption\":\"Coordena\u00e7\u00e3o\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EstrategiaConcursos\",\"https:\/\/x.com\/EstratConcursos\"],\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concurso DPE RJ Defensor: saiu o resultado da prova escrita geral","description":"Concurso DPE RJ Defensor: publicada a lista dos aprovados na prova escrita geral do concurso da DPE RJ. Provas escritas espec\u00edficas come\u00e7am em novembro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/","og_locale":"pt_BR","og_type":"article","og_title":"Concurso DPE RJ Defensor: saiu o resultado da 1\u00aa fase; primeira prova escrita ocorre em novembro","og_description":"Concurso DPE RJ Defensor: publicada a lista dos aprovados na prova escrita geral do concurso da DPE RJ. Provas escritas espec\u00edficas come\u00e7am em novembro.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/","og_site_name":"Estrat\u00e9gia Concursos","article_author":"https:\/\/www.facebook.com\/EstrategiaConcursos","article_published_time":"2018-11-10T03:00:23+00:00","article_modified_time":"2021-08-10T16:35:50+00:00","og_image":[{"width":400,"height":209,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg","type":"image\/jpeg"}],"author":"Coordena\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Coordena\u00e7\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/"},"author":{"name":"Coordena\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f"},"headline":"Concurso DPE RJ Defensor: saiu o resultado da 1\u00aa fase; primeira prova escrita ocorre em novembro","datePublished":"2018-11-10T03:00:23+00:00","dateModified":"2021-08-10T16:35:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/"},"wordCount":1215,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg","articleSection":["Jur\u00eddico"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/","name":"Concurso DPE RJ Defensor: saiu o resultado da prova escrita geral","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg","datePublished":"2018-11-10T03:00:23+00:00","dateModified":"2021-08-10T16:35:50+00:00","description":"Concurso DPE RJ Defensor: publicada a lista dos aprovados na prova escrita geral do concurso da DPE RJ. Provas escritas espec\u00edficas come\u00e7am em novembro.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2017\/11\/23081358\/DPE-RJ-DEFENSOR6-e1511435650757.jpg","width":400,"height":209,"caption":"Concurso DPE RJ Defensor"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/edital-dpe-rj-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Concurso DPE RJ Defensor: saiu o resultado da 1\u00aa fase; primeira prova escrita ocorre em novembro"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/b4a388c97673c5f483d72185668afa1f","name":"Coordena\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b720319e4c9a967eb58678d110f4fe35452fc5d5f97b202bac7b8acceb18c6ad?s=96&d=mm&r=g","caption":"Coordena\u00e7\u00e3o"},"sameAs":["https:\/\/www.facebook.com\/EstrategiaConcursos","https:\/\/x.com\/EstratConcursos"],"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/estrategia2013\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/117251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=117251"}],"version-history":[{"count":19,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/117251\/revisions"}],"predecessor-version":[{"id":832407,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/117251\/revisions\/832407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/96435"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=117251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=117251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=117251"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=117251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}