{"id":1171149,"date":"2023-03-13T08:00:00","date_gmt":"2023-03-13T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1171149"},"modified":"2023-02-15T15:27:37","modified_gmt":"2023-02-15T18:27:37","slug":"filtro-portugues-sq","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/","title":{"rendered":"Filtros do Sistema de Quest\u00f5es: Portugu\u00eas"},"content":{"rendered":"\n<p>Ol\u00e1, caro aluno (a)! Na postagem de hoje iremos ver na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas.<\/p>\n\n\n\n<p>O meu nome \u00e9 Carlos Eduardo, sou Consultor do Tesouro da SEFAZ do Esp\u00edrito Santo e coach do Estrat\u00e9gia Concursos. O meu <strong>objetivo nesta postagem \u00e9 ajudar voc\u00eas a utilizarem melhor as ferramentas de filtros do Sistema de quest\u00f5es do Estrat\u00e9gia, com foco na disciplina de Portugu\u00eas. Muitos alunos costumam ter dificuldade na hora de fazer os filtros de quest\u00f5es, ent\u00e3o iremos tentar demonstrar na pr\u00e1tica como otimizar os recursos dispon\u00edveis no Sistema de Quest\u00f5es.<\/strong><\/p>\n\n\n\n<p>Como modelo irei utilizar o edital do Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo para o cargo Escrevente T\u00e9cnico Judici\u00e1rio para a Comarca da Capital, pois sei que \u00e9 um edital que muitos de voc\u00eas t\u00eam interesse. \u00c9 importante ressaltar que o objetivo desse artigo \u00e9 ensinar a montar os filtros mais adequados, ent\u00e3o, ap\u00f3s a leitura, espero que voc\u00eas consigam aplicar os filtros nos concursos que t\u00eam interesse. Para isso, basta adaptar os t\u00f3picos de cobran\u00e7a com os que est\u00e3o previstos no edital de seu interesse na mat\u00e9ria de Portugu\u00eas e a banca examinadora respons\u00e1vel pela sua prova de interesse.<\/p>\n\n\n\n<p>Em primeiro lugar, acho fundamental ver os t\u00f3picos que est\u00e3o sendo cobrados no edital publicado. Vejamos o que disp\u00f5e o edital da Vunesp:<\/p>\n\n\n\n<p><em>\u201c1. An\u00e1lise, compreens\u00e3o e interpreta\u00e7\u00e3o de diversos tipos de textos verbais, n\u00e3o verbais, liter\u00e1rios e n\u00e3o liter\u00e1rios. 2. Informa\u00e7\u00f5es literais e infer\u00eancias poss\u00edveis. 3. Ponto de vista do autor. 4. Estrutura\u00e7\u00e3o do texto: rela\u00e7\u00f5es entre ideias; recursos de coes\u00e3o. 5. Significa\u00e7\u00e3o contextual de palavras e express\u00f5es. 6. Sin\u00f4nimos e ant\u00f4nimos. 7. Sentido pr\u00f3prio e figurado das palavras. 8. Classes de palavras: emprego e sentido que imprimem \u00e0s rela\u00e7\u00f5es que estabelecem: substantivo, adjetivo, artigo, numeral, pronome, verbo, adv\u00e9rbio, preposi\u00e7\u00e3o e conjun\u00e7\u00e3o. 9. Concord\u00e2ncia verbal e nominal. 10. Reg\u00eancia verbal e nominal. 11. Coloca\u00e7\u00e3o pronominal. 12. Crase. 13. Pontua\u00e7\u00e3o.\u201d<\/em><\/p>\n\n\n\n<p>Uma outra possibilidade tamb\u00e9m para preparar o filtro \u00e9 ver os t\u00f3picos cobrados em cada aula do curso TJ-SP (Escrevente Judici\u00e1rio) Portugu\u00eas &#8211; 2023 (P\u00f3s-Edital) no site do Estrat\u00e9gia Concursos nessa disciplina:<\/p>\n\n\n\n<p>Aula 00 \u2013 Classes de palavras: substantivo, adjetivo, adv\u00e9rbios, artigo, numeral, interjei\u00e7\u00e3o.<\/p>\n\n\n\n<p>Aula 01 \u2013 Classes de palavras: Preposi\u00e7\u00e3o e conjun\u00e7\u00e3o<\/p>\n\n\n\n<p>Aula 02 \u2013 Classes de palavras: Pronomes e coloca\u00e7\u00e3o pronominal<\/p>\n\n\n\n<p>Aula 03 \u2013 Classes de palavras: Verbos<\/p>\n\n\n\n<p>Aula 04 \u2013 Correla\u00e7\u00e3o e vozes verbais<\/p>\n\n\n\n<p>Aula 05 \u2013 Pontua\u00e7\u00e3o<\/p>\n\n\n\n<p>Aula 06 \u2013 Concord\u00e2ncia verbal e nominal<\/p>\n\n\n\n<p>Aula 07 \u2013 Reg\u00eancia verbal e nominal. Crase<\/p>\n\n\n\n<p>Aula 08 \u2013 Estrutura\u00e7\u00e3o do texto: rela\u00e7\u00f5es entre ideias, recursos de coes\u00e3o<\/p>\n\n\n\n<p>Aula 09 \u2013 Significa\u00e7\u00e3o contextual de palavras e express\u00f5es. Sin\u00f4nimos e ant\u00f4nimos. Sentido pr\u00f3prio e figurado de palavras.<\/p>\n\n\n\n<p>Aula 10 \u2013 An\u00e1lise, compreens\u00e3o e interpreta\u00e7\u00e3o de diversos tipos de textos verbais, n\u00e3o verbais, liter\u00e1rios e n\u00e3o liter\u00e1rios. Informa\u00e7\u00f5es literais e infer\u00eancias poss\u00edveis. Ponto de vista do autor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fazendo-filtro-no-sistemas-de-questoes-portugues\"><strong>Fazendo filtro no Sistemas de Quest\u00f5es \u2013 Portugu\u00eas<\/strong><\/h2>\n\n\n\n<p>Agora que j\u00e1 sabemos o que ir\u00e1 ser cobrado no concurso, o pr\u00f3ximo passo \u00e9 abrir o sistema de quest\u00f5es do Estrat\u00e9gia atrav\u00e9s do seguinte endere\u00e7o:<a href=\"https:\/\/concursos.estrategia.com\/questoes\/buscar\"> <em>https:\/\/concursos.estrategia.com\/questoes\/buscar<\/em><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"475\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2-1024x475.png\" alt=\"Filtro de Quest\u00f5es SQ\" class=\"wp-image-1170820\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2-1024x475.png 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2-300x139.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2-768x356.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2-610x283.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2-150x70.png 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png 1312w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sistema de Quest\u00f5es<\/figcaption><\/figure>\n\n\n\n<p>Nessa p\u00e1gina j\u00e1 podemos come\u00e7ar a fazer os filtros mais relevantes. Veja que, por defini\u00e7\u00e3o, o site j\u00e1 exclui as quest\u00f5es desatualizadas, anuladas e sem solu\u00e7\u00e3o. Caso voc\u00ea sinta necessidade de incluir essas quest\u00f5es, basta clicar no \u201cx\u201d ao lado do grupo desejado que ele automaticamente ir\u00e1 desaparecer e as quest\u00f5es do grupo ficar\u00e3o dispon\u00edveis. Eu normalmente n\u00e3o utilizo as quest\u00f5es desatualizadas e anuladas na minha prepara\u00e7\u00e3o, pois considero que podem acabar me prejudicando de algum modo.<\/p>\n\n\n\n<p>Para come\u00e7ar a filtrar, escreva na frente da lupa que aparece na imagem anterior o nome da mat\u00e9ria desejada. Nesse caso, podemos colocar no filtro: Portugu\u00eas. Alternativamente, podemos deslizar a barra de rolagem para baixo e clicar na setinha ao lado do nome da mat\u00e9ria desejada. Ao clicar nessa seta ir\u00e1 aparecer uma lista de t\u00f3picos da mat\u00e9ria conforme a imagem a seguir:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"903\" height=\"605\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104054\/imagem-2-5.png\" alt=\"Filtro Portugu\u00eas\" class=\"wp-image-1171153\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104054\/imagem-2-5.png 903w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104054\/imagem-2-5-300x201.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104054\/imagem-2-5-768x515.png 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104054\/imagem-2-5-610x409.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104054\/imagem-2-5-150x100.png 150w\" sizes=\"auto, (max-width: 903px) 100vw, 903px\" \/><figcaption class=\"wp-element-caption\">Filtro Portugu\u00eas<\/figcaption><\/figure>\n\n\n\n<p>Agora basta selecionar os t\u00f3picos que est\u00e3o no edital ou no conte\u00fado das aulas que eu citei acima. Por exemplo, o t\u00f3pico \u201cInterpreta\u00e7\u00e3o de texto\u201d aparece na imagem acima. Basta clicar na caixa ao lado do t\u00f3pico e ele j\u00e1 fica selecionado. Feito isso agora \u00e9 s\u00f3 procurar os diversos outros t\u00f3picos presentes no Edital.<\/p>\n\n\n\n<p>Uma outra forma de filtrar tamb\u00e9m \u00e9 atrav\u00e9s da norma de interesse (Lei, Estatuto, Constitui\u00e7\u00e3o, tratado, &#8230;). Contudo, na disciplina de L\u00edngua Portuguesa n\u00e3o \u00e9 necess\u00e1rio utilizar esse tipo de filtro. Normalmente \u00e9 mais aplicado para mat\u00e9rias de Direito, Contabilidade e legisla\u00e7\u00e3o espec\u00edfica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-filtrando-a-banca-examinadora-e-os-anos\"><strong>Filtrando a banca examinadora e os anos<\/strong><\/h2>\n\n\n\n<p>Agora que voc\u00ea j\u00e1 filtrou os t\u00f3picos que ir\u00e3o ser cobrados na sua prova, a minha dica \u00e9 filtrar a banca examinadora respons\u00e1vel pelo seu concurso. Como estamos nos baseando pelo concurso do Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo, vou fazer a pesquisa da banca respons\u00e1vel pelo concurso: a Funda\u00e7\u00e3o para o Vestibular da UNESP \u2013 VUNESP. O primeiro passo \u00e9 selecionar Banca na parte superior e depois escrever \u201cVunesp\u201d na lupa logo abaixo, conforme imagem a seguir:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"613\" height=\"235\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104127\/imagem-4-6.png\" alt=\"Filtro Portugu\u00eas Banca\" class=\"wp-image-1171156\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104127\/imagem-4-6.png 613w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104127\/imagem-4-6-300x115.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104127\/imagem-4-6-610x234.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/14104127\/imagem-4-6-150x58.png 150w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><figcaption class=\"wp-element-caption\">Filtro Banca<\/figcaption><\/figure>\n\n\n\n<p>O mesmo procedimento pode ser feito para o filtro do ano. A minha dica \u00e9 come\u00e7ar pelas quest\u00f5es mais recentes da banca, os \u00faltimos cinco anos, pois a chance de ter um padr\u00e3o parecido com o da sua prova \u00e9 mais elevado. Selecione \u201cAno\u201d na parte superior (est\u00e1 no final, basta seguir com a seta para a direita para encontrar) e depois selecione os anos desejados. Caso apare\u00e7am poucos resultados pode recorrer aos anos anteriores. Normalmente n\u00e3o temos esse problema quando estamos filtrando mat\u00e9rias com muitas quest\u00f5es (ex: Portugu\u00eas, Constitucional, Administrativo,&#8230;) e bancas com tradi\u00e7\u00e3o em concursos p\u00fablicos, como \u00e9 o caso.<\/p>\n\n\n\n<p>Se achar necess\u00e1rio pode ainda inserir mais filtros como, por exemplo, o cargo, forma\u00e7\u00e3o espec\u00edfica, dificuldade, entre outros. Eu n\u00e3o costumo utilizar esses outros filtros pois pode acabar limitando demais o n\u00famero de quest\u00f5es que ir\u00e3o aparecer como resultado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-finalizando-o-filtro-e-criando-cadernos-de-questoes-de-portugues\"><strong>Finalizando o filtro e criando cadernos de quest\u00f5es<\/strong> <strong>de Portugu\u00eas<\/strong><\/h2>\n\n\n\n<p>Ao aplicar os filtros com os t\u00f3picos da mat\u00e9ria de Portugu\u00eas, da banca (Vunesp), foram encontradas 318 quest\u00f5es. Agora basta clicar em:<\/p>\n\n\n\n<p>Ver quest\u00f5es \u2013 se quiser ver e come\u00e7ar as resolver imediatamente as quest\u00f5es;<\/p>\n\n\n\n<p>Criar simulado \u2013 para fazer um simulado com o tempo e o n\u00famero de quest\u00f5es desejadas;<\/p>\n\n\n\n<p>Criar Caderno \u2013 para criar um caderno e poder resolver as quest\u00f5es mais tarde.<\/p>\n\n\n\n<p>Eu aconselho a cria\u00e7\u00e3o do caderno j\u00e1 com os filtros apresentados. Como nome do caderno, voc\u00eas podem colocar, por exemplo, \u201cPortugu\u00eas Vunesp TJ SP\u201d. As principais vantagens do caderno s\u00e3o que voc\u00ea pode continuar a resolver as quest\u00f5es mais tarde, ele mostra quantas quest\u00f5es voc\u00ea j\u00e1 respondeu e o n\u00famero de acertos e erros. Al\u00e9m disso, voc\u00ea pode partilhar o link do caderno com os seus amigos para poderem responder \u00e0s mesmas quest\u00f5es. Segue o link dos cadernos que eu criei utilizando os filtros acima:<\/p>\n\n\n\n<p><a href=\"https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4254a052-5ebe-4115-8852-cfb0c63cb746\">https:\/\/concursos.estrategia.com\/cadernos-e-simulados\/cadernos\/4254a052-5ebe-4115-8852-cfb0c63cb746<\/a><\/p>\n\n\n\n<p>Ao clicar no link voc\u00ea ser\u00e1 diretamente direcionado para o sistema de quest\u00f5es e poder\u00e1 come\u00e7ar a resolver as quest\u00f5es filtradas.<\/p>\n\n\n\n<p>Para partilhar um caderno que voc\u00ea criou, basta ir ao campo: \u201cCadernos e Simulados\u201d na aba da direita do site. Depois clique nos tr\u00eas pontos ao final da linha em que aparece o seu caderno. Ao fazer isso ir\u00e1 aparecer uma s\u00e9rie de op\u00e7\u00f5es interessantes, como duplicar caderno, editar caderno, excluir caderno e compartilhar caderno.<\/p>\n\n\n\n<p>Nessa p\u00e1gina de \u201cCadernos e Simulados\u201d \u00e9 poss\u00edvel tamb\u00e9m acompanhar o seu desempenho dentro do respectivo caderno de quest\u00f5es, verificando quantas quest\u00f5es est\u00e3o no caderno, o n\u00famero de quest\u00f5es j\u00e1 respondidas e a quantidade de acertos e erros. Essa ferramenta \u00e9 bem interessante para acompanhar em quais mat\u00e9rias o seu desempenho est\u00e1 melhor e utilizar como um indicador em que mat\u00e9rias \u00e9 necess\u00e1rio focar o estudo para melhorar o desempenho.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resolvendo-questoes\"><strong>Resolvendo quest\u00f5es<\/strong><\/h2>\n\n\n\n<p>Uma vez feito os filtros, o pr\u00f3ximo passo \u00e9 passar para a resolu\u00e7\u00e3o de quest\u00f5es, para responder basta clicar na op\u00e7\u00e3o desejada e marcar \u201cResponder\u201d. Ap\u00f3s responder, voc\u00ea pode clicar em \u201cVer solu\u00e7\u00f5es e coment\u00e1rios\u201d para: ver a \u201cSolu\u00e7\u00e3o em Texto\u201d feita por um professor do Estrat\u00e9gia; ver a \u201cSolu\u00e7\u00e3o em V\u00eddeo\u201d feita por um professor do Estrat\u00e9gia (n\u00e3o s\u00e3o todas as quest\u00f5es que t\u00eam essa op\u00e7\u00e3o); ler os coment\u00e1rios de outros alunos sobre a quest\u00e3o; e aproveitar para deixar o seu coment\u00e1rio contribuindo com a comunidade.<\/p>\n\n\n\n<p>Se a sua prova \u00e9 realizada por uma banca nova ou sem muita tradi\u00e7\u00e3o que n\u00e3o tem muitas quest\u00f5es de concurso, aconselho fazer o filtro da mat\u00e9ria de Portugu\u00eas inserindo algumas bancas tradicionais para treinar. Uma boa op\u00e7\u00e3o seria Cespe (Cebraspe), FGV, FCC e VUNESP.<\/p>\n\n\n\n<p><strong>Dica final<\/strong>, agora que voc\u00ea j\u00e1 aprendeu a utilizar os filtros, aproveite e resolva muitas quest\u00f5es da banca do seu concurso de interesse sobre os temas cobrados no edital, pois essa \u00e9 uma \u00f3tima maneira de revisar e saber como a banca costuma cobrar o assunto. Al\u00e9m disso, aproveite para ler os coment\u00e1rios dos professores nas quest\u00f5es (tem algumas quest\u00f5es que eu mesmo comentei como professor), bem como ver as solu\u00e7\u00f5es em v\u00eddeo (existem milhares de quest\u00f5es comentadas por v\u00eddeo pelos professores do Estrat\u00e9gia). Se tiver oportunidade aproveite para comentar tamb\u00e9m adicionando informa\u00e7\u00f5es relevantes nas quest\u00f5es de interesse. \u00c9 fundamental que o candidato resolva muitas quest\u00f5es de modo que na hora da prova esteja acostumado com o tipo de cobran\u00e7a da banca examinadora.<\/p>\n\n\n\n<p>Por fim, vale salientar que se deve utilizar este artigo e as quest\u00f5es do Sistema de Quest\u00f5es como complemento ao estudo, privilegiando, sempre, o material te\u00f3rico e as quest\u00f5es dos PDF\u2019s das aulas. Al\u00e9m disso, caso sinta necessidade, recomendo a visualiza\u00e7\u00e3o de v\u00eddeo aulas sobre os assuntos de maior dificuldade\/complexidade. Na plataforma de assinantes do Estrat\u00e9gia existem diversos v\u00eddeos da disciplina de Portugu\u00eas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Carlos Eduardo Cardoso<\/p>\n\n\n\n<p>Consultor do Tesouro Estadual, Coach do Estudo Acompanhado e Professor do Estrat\u00e9gia quest\u00f5es<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Para mais dicas e materiais sobre concurso, siga-me no Instagram:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.instagram.com\/profcarloseduardocardoso\/?igshid=YmMyMTA2M2Y%3D\">@profcarloseduardocardoso<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"quer-saber-tudo-sobre-concursos-previstos-confira-nossos-artigos\">Quer saber tudo sobre concursos previstos?<br \/>Confira nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, caro aluno (a)! Na postagem de hoje iremos ver na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas. O meu nome \u00e9 Carlos Eduardo, sou Consultor do Tesouro da SEFAZ do Esp\u00edrito Santo e coach do Estrat\u00e9gia Concursos. O meu objetivo nesta postagem [&hellip;]<\/p>\n","protected":false},"author":2472,"featured_media":1170820,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1984],"tags":[834,40,861,48],"tax_estado":[219963,219971],"class_list":["post-1171149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunais","tag-coaching","tag-concurso","tag-dicas-de-estudo","tag-edital","tax_estado-concursos-federais","tax_estado-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Filtro Portugu\u00eas para o Sistema de Quest\u00f5es<\/title>\n<meta name=\"description\" content=\"Aprender na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filtros do Sistema de Quest\u00f5es: Portugu\u00eas\" \/>\n<meta property=\"og:description\" content=\"Aprender na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-13T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1312\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carlos Eduardo Chagas Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Eduardo Chagas Cardoso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/\"},\"author\":{\"name\":\"Carlos Eduardo Chagas Cardoso\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5\"},\"headline\":\"Filtros do Sistema de Quest\u00f5es: Portugu\u00eas\",\"datePublished\":\"2023-03-13T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/\"},\"wordCount\":1870,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png\",\"keywords\":[\"coaching\",\"Concurso\",\"dicas de estudo\",\"edital\"],\"articleSection\":[\"Tribunais\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/\",\"name\":\"Filtro Portugu\u00eas para o Sistema de Quest\u00f5es\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png\",\"datePublished\":\"2023-03-13T11:00:00+00:00\",\"description\":\"Aprender na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png\",\"width\":1312,\"height\":609,\"caption\":\"Filtro de Quest\u00f5es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filtros do Sistema de Quest\u00f5es: Portugu\u00eas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5\",\"name\":\"Carlos Eduardo Chagas Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g\",\"caption\":\"Carlos Eduardo Chagas Cardoso\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carloschagascardosogmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Filtro Portugu\u00eas para o Sistema de Quest\u00f5es","description":"Aprender na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/","og_locale":"pt_BR","og_type":"article","og_title":"Filtros do Sistema de Quest\u00f5es: Portugu\u00eas","og_description":"Aprender na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-03-13T11:00:00+00:00","og_image":[{"width":1312,"height":609,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png","type":"image\/png"}],"author":"Carlos Eduardo Chagas Cardoso","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Carlos Eduardo Chagas Cardoso","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/"},"author":{"name":"Carlos Eduardo Chagas Cardoso","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5"},"headline":"Filtros do Sistema de Quest\u00f5es: Portugu\u00eas","datePublished":"2023-03-13T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/"},"wordCount":1870,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png","keywords":["coaching","Concurso","dicas de estudo","edital"],"articleSection":["Tribunais"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/","name":"Filtro Portugu\u00eas para o Sistema de Quest\u00f5es","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png","datePublished":"2023-03-13T11:00:00+00:00","description":"Aprender na pr\u00e1tica como utilizar os filtros do Sistema de Quest\u00f5es do Estrat\u00e9gia para filtrar as quest\u00f5es da disciplina de Portugu\u00eas.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/13212341\/imagem-1-2.png","width":1312,"height":609,"caption":"Filtro de Quest\u00f5es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/filtro-portugues-sq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Filtros do Sistema de Quest\u00f5es: Portugu\u00eas"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/dd0d60f163b910918686346d6b9b7cd5","name":"Carlos Eduardo Chagas Cardoso","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87e8a3317d2c325a36d045fe2cc05df9d3b54288620d17d0e241ec43377fdc25?s=96&d=mm&r=g","caption":"Carlos Eduardo Chagas Cardoso"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/carloschagascardosogmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1171149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2472"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1171149"}],"version-history":[{"count":1,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1171149\/revisions"}],"predecessor-version":[{"id":1171161,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1171149\/revisions\/1171161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1170820"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1171149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1171149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1171149"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1171149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}