{"id":1170902,"date":"2023-03-15T14:00:00","date_gmt":"2023-03-15T17:00:00","guid":{"rendered":"https:\/\/blog-estrategia.mystagingwebsite.com\/blog\/?p=1170902"},"modified":"2023-03-01T16:16:43","modified_gmt":"2023-03-01T19:16:43","slug":"balanco-financeiro-cgdf","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/","title":{"rendered":"Balan\u00e7o Financeiro: resumo de CASP para a CGDF"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ol\u00e1, pessoal, tudo bem? Neste artigo apresentaremos os principais t\u00f3picos acerca do Balan\u00e7o Financeiro para o novo concurso da <a href=\"https:\/\/www.cg.df.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Controladoria-Geral do Distrito Federal (CGDF)<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/02\/cgdf-2-1024x536.jpg\" alt=\"Balan\u00e7o Financeiro: resumo de CASP para a CGDF\" class=\"wp-image-1173008\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/16144835\/cgdf-2-1024x536.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/16144835\/cgdf-2-300x157.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/16144835\/cgdf-2-768x402.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/16144835\/cgdf-2-610x319.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/16144835\/cgdf-2-150x79.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/16144835\/cgdf-2.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Balan\u00e7o Financeiro: resumo de CASP para a CGDF<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bons estudos!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-demonstracoes-contabeis-aplicadas-ao-setor-publico-introducao\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Demonstra\u00e7\u00f5es cont\u00e1beis aplicadas ao setor p\u00fablico: introdu\u00e7\u00e3o<\/mark><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pessoal, n\u00e3o \u00e9 novidade que a contabilidade p\u00fablica no Brasil passou por grandes mudan\u00e7as ao longo dos \u00faltimos anos, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Principalmente em decorr\u00eancia da converg\u00eancia aos padr\u00f5es cont\u00e1beis internacionais, foram editadas v\u00e1rias normas t\u00e9cnicas para regulamentar e uniformizar os procedimentos nacionais de contabilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, inevitavelmente, as Demonstra\u00e7\u00f5es Cont\u00e1beis Aplicadas ao Setor P\u00fablico (DCASP) passaram a exigir, em v\u00e1rios aspectos, tratamento similar ao ocorrido na iniciativa privada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, obviamente, permaneceram no cen\u00e1rio cont\u00e1bil nacional algumas peculiaridades t\u00edpicas da contabilidade p\u00fablica do Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, vale citar o Balan\u00e7o Financeiro, que apesar de n\u00e3o constar nas normas t\u00e9cnicas de contabilidade (convergidas para o padr\u00e3o internacional), encontra-se previsto na legisla\u00e7\u00e3o nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por isso, neste artigo, trataremos, de forma resumida, acerca do Balan\u00e7o Financeiro, que \u00e9 umas das demonstra\u00e7\u00f5es cont\u00e1beis mais recorrentes em provas de concursos p\u00fablicos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Conjunto completo das demonstra\u00e7\u00f5es cont\u00e1beis<\/mark><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Primeiramente, em \u00e2mbito do estudo do Balan\u00e7o Financeiro para a CGDF, devemos conhecer o conjunto completo das DCASP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A NBC TSP 11 (apresenta\u00e7\u00e3o das demonstra\u00e7\u00f5es cont\u00e1beis), portanto, estabelece o rol de demonstrativos cont\u00e1beis obrigat\u00f3rios no setor p\u00fablico, a saber:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Balan\u00e7o Patrimonial;<\/li>\n\n\n\n<li>Demonstra\u00e7\u00e3o do Resultado;<\/li>\n\n\n\n<li>Demonstra\u00e7\u00e3o das Muta\u00e7\u00f5es do Patrim\u00f4nio L\u00edquido;<\/li>\n\n\n\n<li>Demonstra\u00e7\u00e3o dos Fluxos de Caixa;<\/li>\n\n\n\n<li>Compara\u00e7\u00e3o entre o or\u00e7amento e os valores realizados (quando a entidade divulga publicamente os or\u00e7amentos aprovados);<\/li>\n\n\n\n<li>Notas explicativas;<\/li>\n\n\n\n<li>Informa\u00e7\u00e3o comparativa com o per\u00edodo anterior.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, podemos observar que o Balan\u00e7o Financeiro n\u00e3o foi inclu\u00eddo, pela supracitada norma, como uma demonstra\u00e7\u00e3o cont\u00e1bil obrigat\u00f3ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso decorre, principalmente, devido \u00e0 inexist\u00eancia desse demonstrativo na contabilidade internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme estudaremos a seguir, pode-se observar que o Balan\u00e7o Financeiro possui preponder\u00e2ncia quanto ao aspecto or\u00e7ament\u00e1rio (receitas e despesas or\u00e7ament\u00e1rias e extraor\u00e7ament\u00e1rio).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, diverge dos padr\u00f5es internacionais da contabilidade p\u00fablica que, atualmente, buscam evidenciar, com maior relev\u00e2ncia, os aspectos cont\u00e1beis patrimoniais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o aluno pode se perguntar: <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">ora, ent\u00e3o por que o Balan\u00e7o Financeiro \u00e9 uma das principais demonstra\u00e7\u00f5es cont\u00e1beis no Brasil?<\/mark><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A resposta para esse questionamento \u00e9 bastante objetiva: <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">porque a lei obriga a sua elabora\u00e7\u00e3o!<\/mark><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar de n\u00e3o constar no conjunto completo das demonstra\u00e7\u00f5es cont\u00e1beis da NBC TSP 11, o Balan\u00e7o Financeiro consta expressamente na Lei 4.320\/64.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esse motivo, sua elabora\u00e7\u00e3o e divulga\u00e7\u00e3o \u00e9 obrigat\u00f3ria no contexto dos \u00f3rg\u00e3os e entidades da administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Balan\u00e7o Financeiro para a CGDF: aspectos gerais<\/mark><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pessoal, agora que j\u00e1 entendemos que o Balan\u00e7o Financeiro \u00e9 obrigat\u00f3rio (por for\u00e7a da Lei 4.320\/64), apesar de n\u00e3o constar na NBC TSP 11, vamos tratar especificamente acerca deste demonstrativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme a Lei 4.320\/64, o Balan\u00e7o Financeiro consiste em um demonstrativo cont\u00e1bil destinado a representar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Receitas e despesas or\u00e7ament\u00e1rias;<\/li>\n\n\n\n<li>Recebimentos e pagamentos extraor\u00e7ament\u00e1rios;<\/li>\n\n\n\n<li>Saldos em esp\u00e9cie provenientes de exerc\u00edcios anteriores;<\/li>\n\n\n\n<li>Saldos em esp\u00e9cie que se transferem para o exerc\u00edcio seguinte.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, como indicamos anteriormente, o Balan\u00e7o Financeiro prima pela evidencia\u00e7\u00e3o dos aspectos financeiros (saldos em esp\u00e9cie), todavia, em um contexto de an\u00e1lise or\u00e7ament\u00e1ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Balan\u00e7o Financeiro para a CGDF: estrutura<\/mark><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme disp\u00f5e o Manual de Contabilidade Aplicado ao Setor P\u00fablico (MCASP), o Balan\u00e7o Financeiro \u00e9 composto por um \u00fanico quadro, a exemplo da figura seguinte:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"435\" src=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-content\/uploads\/2023\/02\/balanco-financeiro-exemplo-1-1024x435.jpg\" alt=\"Exemplo de Balan\u00e7o Financeiro para CGDF.\" class=\"wp-image-1174560\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/18203806\/balanco-financeiro-exemplo-1-1024x435.jpg 1024w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/18203806\/balanco-financeiro-exemplo-1-300x128.jpg 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/18203806\/balanco-financeiro-exemplo-1-768x327.jpg 768w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/18203806\/balanco-financeiro-exemplo-1-610x259.jpg 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/18203806\/balanco-financeiro-exemplo-1-150x64.jpg 150w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/18203806\/balanco-financeiro-exemplo-1.jpg 1096w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Exemplo de Balan\u00e7o Financeiro<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse quadro s\u00e3o registradas todas as informa\u00e7\u00f5es relevantes exigidas pela Lei 4.320\/64 e, a partir dele, podem ser realizadas diversas an\u00e1lises relevantes para o concurso da CGDF, conforme aprenderemos a seguir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Resultado financeiro<\/mark><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para o concurso da CGDF, \u00e9 muito importante aprender a calcular o resultado financeiro, a partir da estrutura do Balan\u00e7o Financeiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, em s\u00edntese, basta somar os ingressos e subtrair os disp\u00eandios (sem considerar os saldos em esp\u00e9cie).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, para facilitar a compreens\u00e3o, apresentaremos a seguir os fatores que devem ser somados e os que devem ser subtra\u00eddos para o c\u00e1lculo do resultado. Vejamos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Receitas or\u00e7ament\u00e1rias (+)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Transfer\u00eancias financeiras recebidas (+)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Recebimentos extraor\u00e7ament\u00e1rios (+)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Despesas or\u00e7ament\u00e1rias (-)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Transfer\u00eancias financeiras concedidas (-)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Pagamentos extraor\u00e7ament\u00e1rios (-)<\/mark><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Todavia, existe outro m\u00e9todo para calcular o resultado financeiro a partir do balan\u00e7o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para isso, basta subtrair o saldo em esp\u00e9cie do exerc\u00edcio anterior do valor referente ao saldo em esp\u00e9cie para o exerc\u00edcio seguinte, conforme segue:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Saldo em esp\u00e9cie para o exerc\u00edcio seguinte (+)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Saldo em esp\u00e9cie do exerc\u00edcio anterior (-)<\/mark><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, obviamente, o valor do c\u00e1lculo do resultado financeiro pelos dois m\u00e9todos supracitados deve ser coincidente. Portanto, pode-se proceder ao c\u00e1lculo pelos dois m\u00e9todos para verificar a exist\u00eancia de erros na montagem do balan\u00e7o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, \u00e9 muito importante, para o concurso da CGDF, saber que o super\u00e1vit financeiro n\u00e3o \u00e9 calculado no Balan\u00e7o Financeiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa \u00e9 uma \u201cpegadinha\u201d recorrente em provas de concursos p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, vale lembrar que se calcula o super\u00e1vit financeiro a partir do balan\u00e7o patrimonial, sendo uma das fontes para a abertura de cr\u00e9ditos adicionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme a Lei 4.320\/64, o super\u00e1vit financeiro pode ser calculado da seguinte forma:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Ativo financeiro (+)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Passivo financeiro (-)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Cr\u00e9ditos adicionais transferidos (-)<\/mark><\/li>\n\n\n\n<li><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Opera\u00e7\u00f5es de cr\u00e9dito vinculadas aos cr\u00e9ditos adicionais transferidos (+)<\/mark><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, mesmo que voc\u00ea, caro concurseiro, ainda n\u00e3o tenha estudado o Balan\u00e7o Patrimonial, fica f\u00e1cil perceber que as informa\u00e7\u00f5es utilizadas para c\u00e1lculo do super\u00e1vit financeiro n\u00e3o prov\u00eam do Balan\u00e7o Financeiro, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Resultado financeiro positivo e negativo<\/mark><\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Pessoal, j\u00e1 aprendemos que o super\u00e1vit financeiro n\u00e3o \u00e9 calculado no Balan\u00e7o Financeiro, certo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igualmente, o d\u00e9ficit financeiro tamb\u00e9m n\u00e3o \u00e9 calculado no Balan\u00e7o Financeiro. O c\u00e1lculo de ambos os par\u00e2metros decorre do Balan\u00e7o Patrimonial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o, <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">como devemos classificar o resultado financeiro calculado no Balan\u00e7o Financeiro?<\/mark><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme o MCASP, o resultado financeiro pode ser positivo ou negativo. Al\u00e9m disso, tamb\u00e9m \u00e9 poss\u00edvel dizer que o resultado financeiro foi superavit\u00e1rio ou deficit\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, ratifica-se que o super\u00e1vit e o d\u00e9ficit financeiros decorrem apenas do Balan\u00e7o Patrimonial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o MCASP esclarece que o resultado financeiro positivo consiste em um indicador de equil\u00edbrio financeiro. Por\u00e9m, isso n\u00e3o deve ser entendido como uma verdade absoluta, pois, em \u00faltima an\u00e1lise, pode decorrer de um aumento do endividamento p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, o manual tamb\u00e9m esclarece que o resultado financeiro negativo nem sempre consiste em um mau indicador, j\u00e1 que pode representar redu\u00e7\u00e3o do endividamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Restos a pagar<\/mark><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Outro t\u00f3pico bastante relevante acerca do Balan\u00e7o Financeiro, para o concurso da CGDF, refere-se ao tratamento dos restos a pagar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em resumo, os restos a pagar consistem nas despesas empenhadas, por\u00e9m, n\u00e3o pagas antes do t\u00e9rmino do exerc\u00edcio financeiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, podem ser classificados como restos a pagar processados ou n\u00e3o processados, dependendo de terem ou n\u00e3o (respectivamente) sido liquidadas no curso do exerc\u00edcio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em \u00e2mbito do balan\u00e7o financeiro, devemos saber que o registro dos restos a pagar consiste em um ajuste do saldo financeiro do \u00f3rg\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, percebemos que a despesa que originou os restos a pagar foi realizada sob o aspecto or\u00e7ament\u00e1rio (ocorreu o empenho), todavia, n\u00e3o houve o seu pagamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dessa forma, para compensar a despesa or\u00e7ament\u00e1ria, realiza-se a inscri\u00e7\u00e3o de uma receita extraor\u00e7ament\u00e1ria (de restos a pagar).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pessoal, essa an\u00e1lise pode parecer, a priori, bastante abstrata. Por\u00e9m, fica f\u00e1cil perceber essa compensa\u00e7\u00e3o quando entendemos o c\u00e1lculo do resultado financeiro (estudado anteriormente).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ora, se para o c\u00e1lculo do resultado financeiro devemos somar os ingressos extraor\u00e7ament\u00e1rios e subtrair as despesas or\u00e7ament\u00e1rias, resta claro que, se aumentarmos igualmente esses dois fatores, n\u00e3o haver\u00e1 reflexo no resultado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, por meio desse ajuste cont\u00e1bil (inscri\u00e7\u00e3o dos restos a pagar como ingressos extraor\u00e7ament\u00e1rios) o saldo em esp\u00e9cie para o exerc\u00edcio seguinte n\u00e3o ser\u00e1 reduzido em face das despesas or\u00e7ament\u00e1rias realizadas sob o enfoque or\u00e7ament\u00e1rio, mas que n\u00e3o geraram, ao longo do exerc\u00edcio, redu\u00e7\u00e3o do caixa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, devemos lembrar que os restos a pagar do exerc\u00edcio devem ser inscritos como receitas extraor\u00e7ament\u00e1rias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, os pagamentos de restos a pagar consistem em despesas extraor\u00e7ament\u00e1rias no Balan\u00e7o Financeiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o pagamento dos restos a pagar representa a finaliza\u00e7\u00e3o da obriga\u00e7\u00e3o, dando-se baixa na receita extraor\u00e7ament\u00e1ria (de restos a pagar) por meio de uma despesa extraor\u00e7ament\u00e1ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Balan\u00e7o Financeiro para a CGDF: elabora\u00e7\u00e3o quanto ao PCASP<\/mark><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O Plano de Contas Aplicado ao Setor P\u00fablico (PCASP) consiste na estrutura b\u00e1sica da escritura\u00e7\u00e3o cont\u00e1bil e permite os registros cont\u00e1beis de forma padronizada e sistematizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, utiliza-se um conjunto padronizado de contas cont\u00e1beis, classificadas em um sistema de codifica\u00e7\u00e3o que permite a automatiza\u00e7\u00e3o dos registros e demonstrativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, o Balan\u00e7o Financeiro utiliza algumas classes do PCASP para realizar os registros conforme a estrutura normatizada do demonstrativo, a saber:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Recebimentos e pagamentos extraor\u00e7ament\u00e1rios de dep\u00f3sitos restitu\u00edveis e valores vinculados, saldos em esp\u00e9cie do exerc\u00edcio anterior e para o exerc\u00edcio seguinte: utiliza-se as classes 1 e 2 do PCASP (ativo e passivo, respectivamente);<\/li>\n\n\n\n<li>Transfer\u00eancias financeiras concedidas: utiliza-se a classe 3 do PCASP (varia\u00e7\u00f5es patrimoniais diminutivas \u2013 VPD);<\/li>\n\n\n\n<li>Transfer\u00eancias financeiras recebidas: utiliza-se a classe 4 do PCASP (varia\u00e7\u00f5es patrimoniais aumentativas \u2013 VPA);<\/li>\n\n\n\n<li>Inscri\u00e7\u00e3o de restos a pagar: utiliza-se a classe 5 do PCASP (or\u00e7amento aprovado);<\/li>\n\n\n\n<li>Receita or\u00e7ament\u00e1ria, despesa or\u00e7ament\u00e1ria e pagamento de restos a pagar: utiliza-se a classe 6 do PCASP (execu\u00e7\u00e3o do or\u00e7amento).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Balan\u00e7o Financeiro para a CGDF: conclus\u00e3o<\/mark><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pessoal, sintetizamos neste artigo os principais pontos acerca do Balan\u00e7o Financeiro para o concurso da CGDF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Espero que tenham gostado desse conte\u00fado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o pr\u00f3ximo artigo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grande abra\u00e7o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rafael Chaves<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size wp-block-paragraph\"><strong>Saiba mais: <a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-cgdf\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concurso CGDF<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Quer saber tudo sobre concursos previstos?<br \/>Confira  nossos artigos!<\/h2>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-pale-cyan-blue-background-color has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos 2023<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1, pessoal, tudo bem? Neste artigo apresentaremos os principais t\u00f3picos acerca do Balan\u00e7o Financeiro para o novo concurso da Controladoria-Geral do Distrito Federal (CGDF). Bons estudos! Demonstra\u00e7\u00f5es cont\u00e1beis aplicadas ao setor p\u00fablico: introdu\u00e7\u00e3o Pessoal, n\u00e3o \u00e9 novidade que a contabilidade p\u00fablica no Brasil passou por grandes mudan\u00e7as ao longo dos \u00faltimos anos, n\u00e3o \u00e9 mesmo? [&hellip;]<\/p>\n","protected":false},"author":2261,"featured_media":1149575,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"post_tipo":"article","footnotes":""},"categories":[1,220180],"tags":[],"tax_estado":[219970],"class_list":["post-1170902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","category-controle-gestao","tax_estado-df"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Balan\u00e7o Financeiro: resumo de CASP para a CGDF<\/title>\n<meta name=\"description\" content=\"Estude sobre o balan\u00e7o financeiro, uma das principais demonstra\u00e7\u00f5es cont\u00e1beis aplic\u00e1veis ao setor p\u00fablico, com foco no novo concurso da CGDF.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Balan\u00e7o Financeiro: resumo de CASP para a CGDF\" \/>\n<meta property=\"og:description\" content=\"Estude sobre o balan\u00e7o financeiro, uma das principais demonstra\u00e7\u00f5es cont\u00e1beis aplic\u00e1veis ao setor p\u00fablico, com foco no novo concurso da CGDF.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-15T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/09143420\/cgdf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafael Ferreira Chaves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafael Ferreira Chaves\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/\"},\"author\":{\"name\":\"Rafael Ferreira Chaves\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/545cce8f1c81268ec2ca202a954284e1\"},\"headline\":\"Balan\u00e7o Financeiro: resumo de CASP para a CGDF\",\"datePublished\":\"2023-03-15T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/\"},\"wordCount\":1807,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2023\\\/01\\\/09143420\\\/cgdf.jpg\",\"articleSection\":[\"Concursos P\u00fablicos\",\"Controladorias\\\/Gest\u00e3o (CGU, CGE, STN, EPPGG)\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/\",\"name\":\"Balan\u00e7o Financeiro: resumo de CASP para a CGDF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2023\\\/01\\\/09143420\\\/cgdf.jpg\",\"datePublished\":\"2023-03-15T17:00:00+00:00\",\"description\":\"Estude sobre o balan\u00e7o financeiro, uma das principais demonstra\u00e7\u00f5es cont\u00e1beis aplic\u00e1veis ao setor p\u00fablico, com foco no novo concurso da CGDF.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2023\\\/01\\\/09143420\\\/cgdf.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2023\\\/01\\\/09143420\\\/cgdf.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Concurso CGDF inscritos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/balanco-financeiro-cgdf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Balan\u00e7o Financeiro: resumo de CASP para a CGDF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#website\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dhg1h5j42swfq.cloudfront.net\\\/2025\\\/06\\\/03203428\\\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog-estrategia.mystagingwebsite.com\\\/#\\\/schema\\\/person\\\/545cce8f1c81268ec2ca202a954284e1\",\"name\":\"Rafael Ferreira Chaves\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g\",\"caption\":\"Rafael Ferreira Chaves\"},\"description\":\"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\\\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\\\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\\\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\\\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \\\/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\\\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).\",\"url\":\"https:\\\/\\\/www.estrategiaconcursos.com.br\\\/blog\\\/author\\\/fchaves01gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Balan\u00e7o Financeiro: resumo de CASP para a CGDF","description":"Estude sobre o balan\u00e7o financeiro, uma das principais demonstra\u00e7\u00f5es cont\u00e1beis aplic\u00e1veis ao setor p\u00fablico, com foco no novo concurso da CGDF.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/","og_locale":"pt_BR","og_type":"article","og_title":"Balan\u00e7o Financeiro: resumo de CASP para a CGDF","og_description":"Estude sobre o balan\u00e7o financeiro, uma das principais demonstra\u00e7\u00f5es cont\u00e1beis aplic\u00e1veis ao setor p\u00fablico, com foco no novo concurso da CGDF.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-03-15T17:00:00+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/09143420\/cgdf.jpg","type":"image\/jpeg"}],"author":"Rafael Ferreira Chaves","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Rafael Ferreira Chaves","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/"},"author":{"name":"Rafael Ferreira Chaves","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1"},"headline":"Balan\u00e7o Financeiro: resumo de CASP para a CGDF","datePublished":"2023-03-15T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/"},"wordCount":1807,"commentCount":0,"publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/09143420\/cgdf.jpg","articleSection":["Concursos P\u00fablicos","Controladorias\/Gest\u00e3o (CGU, CGE, STN, EPPGG)"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/","name":"Balan\u00e7o Financeiro: resumo de CASP para a CGDF","isPartOf":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/09143420\/cgdf.jpg","datePublished":"2023-03-15T17:00:00+00:00","description":"Estude sobre o balan\u00e7o financeiro, uma das principais demonstra\u00e7\u00f5es cont\u00e1beis aplic\u00e1veis ao setor p\u00fablico, com foco no novo concurso da CGDF.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/09143420\/cgdf.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/09143420\/cgdf.jpg","width":1200,"height":628,"caption":"Concurso CGDF inscritos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/balanco-financeiro-cgdf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog-estrategia.mystagingwebsite.com\/"},{"@type":"ListItem","position":2,"name":"Balan\u00e7o Financeiro: resumo de CASP para a CGDF"}]},{"@type":"WebSite","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#website","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog-estrategia.mystagingwebsite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/blog-estrategia.mystagingwebsite.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/blog-estrategia.mystagingwebsite.com\/#\/schema\/person\/545cce8f1c81268ec2ca202a954284e1","name":"Rafael Ferreira Chaves","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d43172b7c8451a76fe991e14bf7b661f56fcd3e9d8f44dcd92c997cfaf1286f?s=96&d=mm&r=g","caption":"Rafael Ferreira Chaves"},"description":"Engenheiro Civil formado pela Universidade Federal do Piau\u00ed - UFPI. Especialista em Engenharia Ambiental e Saneamento B\u00e1sico pela Faculdade Est\u00e1cio. Atualmente exerce o cargo de Auditor de Controle Externo do TCE\/AM. Aprovado e nomeado nos seguintes concursos: ARSETE\/PMT (1\u00ba lugar - Analista de Regula\u00e7\u00e3o - Eng. Civil), Prefeitura de Campinas\/SP (Eng. Civil) , CODEVASF (Analista de Desenvolvimento Regional - Eng. Civil), TCE\/AM (2\u00ba lugar - Auditor de Controle Externo - Obras P\u00fablicas \/ 14\u00ba lugar - Auditor de Controle Externo - Auditoria Governamental), TCE\/TO (2\u00ba lugar - Auditor de Controle Externo - Eng. Civil), TCE GO (Analista de Controle Externo - Controle Externo).","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/fchaves01gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1170902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2261"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1170902"}],"version-history":[{"count":0,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1170902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1149575"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1170902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1170902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1170902"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1170902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}