{"id":1160917,"date":"2023-02-20T08:00:00","date_gmt":"2023-02-20T11:00:00","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1160917"},"modified":"2023-02-20T10:52:30","modified_gmt":"2023-02-20T13:52:30","slug":"policia-penal-disciplinas-mais-cobradas","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/","title":{"rendered":"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?"},"content":{"rendered":"\n<p>Concurseira(o) impar\u00e1vel, o primeiro semestre do ano de 2023 est\u00e1 apenas come\u00e7ando e j\u00e1 h\u00e1 previs\u00e3o de alguns editais para Pol\u00edcia Penal pelo pa\u00eds. A hora de se preparar \u00e9 justamente esta: no pr\u00e9-edital. Ent\u00e3o, foque nos concursos de 2023 conciliando as disciplinas mais cobradas. Saia na frente da concorr\u00eancia!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-as-atribuicoes-do-policial-penal\">Quais as atribui\u00e7\u00f5es do Policial Penal?<\/h2>\n\n\n\n<p>A pessoa que trabalha como Policial Penal atua, basicamente, promovendo a seguran\u00e7a e a ordem interna nos estabelecimentos penais. Ou seja, suas atribui\u00e7\u00f5es abrangem a realiza\u00e7\u00e3o de revistas nas celas e nas demais depend\u00eancias, bem como em detentos e detentas e em seus familiares e visitantes; o controle de acesso de tudo que entra e sai; preenchimento de formul\u00e1rios; presta\u00e7\u00e3o de assist\u00eancia em situa\u00e7\u00f5es de emerg\u00eancia como fugas, motins etc. Al\u00e9m disso, h\u00e1 o contato direto com presos e presas, atrav\u00e9s do fornecimento de orienta\u00e7\u00f5es quanto aos seus direitos, procedimentos de rotina, e sua condu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por exemplo, veja algumas atribui\u00e7\u00f5es trazidas no edital para o concurso da SEAP do Estado do Par\u00e1, no ano de 2021:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>executar opera\u00e7\u00f5es de <strong>transporte, escolta e cust\u00f3dia<\/strong> de pessoas presas em movimenta\u00e7\u00f5es internas ou externas aos estabelecimentos penais, inclusive<strong> interna\u00e7\u00f5es hospitalares<\/strong>, bem como opera\u00e7\u00f5es de <strong>transfer\u00eancias<\/strong> interestaduais ou entre estabelecimentos penais no interior do Estado;<\/li>\n\n\n\n<li>exercer atividades de <strong>cust\u00f3dia, fiscaliza\u00e7\u00e3o e controle<\/strong> de pessoas presas, sejam provis\u00f3rios ou condenados em quaisquer dos regimes de cumprimento de pena, submetidas a medida de seguran\u00e7a, monitoramento eletr\u00f4nico ou penas restritivas de direito.<\/li>\n<\/ul>\n\n\n\n<p>Ent\u00e3o, veja que algumas das atividades da carreira incluem a dire\u00e7\u00e3o de autom\u00f3veis. Por isso, h\u00e1 editais que j\u00e1 trazem como requisito que voc\u00ea tenha licen\u00e7a para dirigir, como veremos adiante.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-requisitos-e-salarios\">Requisitos e sal\u00e1rios<\/h3>\n\n\n\n<p>De forma geral, apenas o Ensino M\u00e9dio completo \u00e9 exigido para atuar no cargo de Policial Penal. Alguns Estados, e a depender das especificidades de sua atua\u00e7\u00e3o, o Ensino Superior \u00e9 exigido. Por exemplo, para a carreira de Agente Penitenci\u00e1rio dos Estados de Santa Catarina e do Rio Grande do Sul, \u00e9 preciso ter Ensino Superior completo e ainda Carteira Nacional de Habilita\u00e7\u00e3o (CNH) categoria B.<\/p>\n\n\n\n<p>Ademais, em rela\u00e7\u00e3o aos sal\u00e1rios iniciais, fazendo um apanhado nos editais dos \u00faltimos 5 anos (2018-2022), a m\u00e9dia varia inclusive quanto ao n\u00edvel de escolaridade exigido. Ou seja, para as carreiras que exigem Diploma de Gradua\u00e7\u00e3o, a remunera\u00e7\u00e3o inicial varia de R$ 3.993,82 a R$ 5.500,00. J\u00e1 para aquelas em que o Certificado de Conclus\u00e3o do Ensino M\u00e9dio \u00e9 suficiente, os servidores recebem entre R$ 2.810,00 e R$ 5.097,15, inicialmente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-etapas-de-provas\">Etapas de provas<\/h3>\n\n\n\n<p>Geralmente, as etapas s\u00e3o:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Prova Objetiva<\/li>\n\n\n\n<li>Prova de Capacidade F\u00edsica ou Teste de Aptid\u00e3o F\u00edsica (TAF)<\/li>\n\n\n\n<li>Avalia\u00e7\u00e3o Psicol\u00f3gica<\/li>\n\n\n\n<li>Exame M\u00e9dico e Toxicol\u00f3gico<\/li>\n\n\n\n<li>Investiga\u00e7\u00e3o Social<\/li>\n<\/ol>\n\n\n\n<p>Al\u00e9m dessas fases, alguns certames v\u00eam cobrando a parte discursiva, inclusive como crit\u00e9rio de desempate.<\/p>\n\n\n\n<p>Aten\u00e7\u00e3o! Para algumas carreiras, n\u00e3o \u00e9 qualquer cidad\u00e3o que pode concorrer para tais vagas. \u00c0s vezes, <strong>apenas policiais militares ou civis<\/strong> podem exercer fun\u00e7\u00f5es de policiais penais. Logo, leia com aten\u00e7\u00e3o seu edital, e confira se voc\u00ea se encaixa no que \u00e9 solicitado. Afinal de contas, antes mesmo de sentar para estudar, \u00e9 necess\u00e1rio ler as exig\u00eancias de seu certame.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-concursos-previstos-para-2023\">Concursos previstos para 2023<\/h2>\n\n\n\n<p><em>N\u00e3o t\u00e1 cedo para come\u00e7ar a estudar agora? Nem tem edital publicado!<\/em> Concurseira(o), o estudo de um edital requer tempo, paci\u00eancia e muito foco, principalmente para quem tem uma rotina agitada e poucas horas dispon\u00edveis de estudo. Inclusive, alguns editais trazem conte\u00fados program\u00e1ticos extensos e com n\u00edveis de dificuldade cada vez maiores. Portanto, o quanto antes come\u00e7ar, pelo menos pelas disciplinas-base, maiores s\u00e3o as chances de &#8220;fechar&#8221; o edital, entre sua publica\u00e7\u00e3o e a data da prova.<\/p>\n\n\n\n<p>Tenho certeza que voc\u00ea acompanha as not\u00edcias do Estrat\u00e9gia Concursos e j\u00e1 viu que alguns Estados j\u00e1 contam com comiss\u00f5es formadas para planejar novos certames. A previs\u00e3o \u00e9 que, ainda para esse ano de 2023, aconte\u00e7am as seguintes provas:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-iapen-acre\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Penal do Acre<\/a><\/h3>\n\n\n\n<p>S\u00e3o <strong>260 vagas<\/strong> previstas, para cargos de n\u00edveis m\u00e9dio e superior, e com a banca <strong>IBFC<\/strong> j\u00e1 contratada. O an\u00fancio aconteceu logo no in\u00edcio desse m\u00eas de Janeiro, logo, \u00e9 uma excelente oportunidade para dar in\u00edcio a sua <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/policia-penal-ce-policial-penal-agente-penitenciario-pacotaco-pacote-teorico-passo-estrategico-2022-pre-edital\/\" target=\"_blank\" rel=\"noreferrer noopener\">prepara\u00e7\u00e3o<\/a><\/strong>.<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 importante destacar que a carreira de Policial Penal acriana foi institu\u00edda recentemente. Em dezembro de 2021, a <a href=\"http:\/\/www.legis.ac.gov.br\/detalhar\/5038\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Lei Complementar n\u00b0 392<\/strong><\/a> foi publicada trazendo detalhes sobre os requisitos, as atribui\u00e7\u00f5es, as condi\u00e7\u00f5es para promo\u00e7\u00e3o, veda\u00e7\u00f5es, deveres etc. E ainda, o dispositivo enuncia o valor de R$ 1.800,00 como &#8220;pr\u00eamio anual de valoriza\u00e7\u00e3o da atividade policial penal&#8221;. Ent\u00e3o, por ser uma carreira recentemente regulamentada, pode trazer maiores expectativas de valoriza\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-penal-pb\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Penal da Para\u00edba<\/a><\/h3>\n\n\n\n<p>O cargo de Agente de Seguran\u00e7a Penitenci\u00e1ria, vinculado \u00e0 Secretaria de Estado da Cidadania e Administra\u00e7\u00e3o Penitenci\u00e1ria, teve seu \u00faltimo concurso realizado h\u00e1 mais de 10 anos. A remunera\u00e7\u00e3o prevista no edital da \u00e9poca era de R$ 1.213,93. No ano de 2022, segundo o <strong><a href=\"https:\/\/sagres.tce.pb.gov.br\/estado_pessoal08.php?poder=1&amp;ano=2022&amp;competencia=092022&amp;descricao=Setembro&amp;cargo=000001017&amp;cargonome=AGENTE+DE+SEG+PENITENCIARIO&amp;tipo=EFETIVO+ATIVO&amp;secretaria=SEC.EST.ADM.+PENITENCIARIA\" target=\"_blank\" rel=\"noreferrer noopener\">Portal da Transpar\u00eancia<\/a><\/strong>, os sal\u00e1rios passaram dos R$ 2.000,00.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"282\" height=\"482\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31222818\/transparencia-pb.png\" alt=\"\" class=\"wp-image-1162423\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31222818\/transparencia-pb.png 282w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31222818\/transparencia-pb-176x300.png 176w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31222818\/transparencia-pb-150x256.png 150w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><figcaption class=\"wp-element-caption\">Atuais remunera\u00e7\u00f5es de agentes vinculados penitenci\u00e1rios da Para\u00edba<\/figcaption><\/figure>\n\n\n\n<p>Recentemente, a Emenda Complementar n\u00b0 48 de 2021 criou a Pol\u00edcia Penal da Para\u00edba. Dessa forma, as carreiras dos agentes vinculados a ela dever\u00e3o ainda ser organizadas atrav\u00e9s de lei complementar e ter estatuto pr\u00f3prio. Outrossim, sua principal atribui\u00e7\u00e3o ser\u00e1 promover a&nbsp;seguran\u00e7a dos estabelecimentos penais.<\/p>\n\n\n\n<p>At\u00e9 ent\u00e3o, o <strong><a href=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2021\/06\/10120617\/diario-oficial-19-06-2019.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Plano de Cargos, Carreiras e Remunera\u00e7\u00e3o<\/a><\/strong>, de 2019, prev\u00ea como exig\u00eancia o ensino m\u00e9dio completo &#8211; com possibilidade de progress\u00e3o para Classes subsequentes conforme seu n\u00edvel de forma\u00e7\u00e3o &#8211; e CNH de categoria B.<\/p>\n\n\n\n<p>Por isso, h\u00e1 pouco tempo o secret\u00e1rio de Administra\u00e7\u00e3o Penitenci\u00e1ria da Para\u00edba, Jo\u00e3o Alves, j\u00e1 citou a possibilidade de estudos sobre novo certame em breve. Apesar disso, o <strong><a href=\"http:\/\/sapl.al.pb.leg.br\/sapl\/sapl_documentos\/materia\/95204_texto_integral\" target=\"_blank\" rel=\"noreferrer noopener\">or\u00e7amento do Estado para 2023<\/a><\/strong> n\u00e3o prev\u00ea despesas para realiza\u00e7\u00e3o de certame, especificamente, para suprir a demanda de tais servidores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-penal-go-700-vagas-com-salarios-de-ate-r-5-mil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Penal de Goi\u00e1s<\/a><\/h3>\n\n\n\n<p>Logo depois, aqui h\u00e1 <strong>700 vagas<\/strong> previstas e j\u00e1 com comiss\u00e3o formada para organizar tudo. O \u00faltimo concurso da Pol\u00edcia Penal de Goi\u00e1s ofertou 500 vagas, tendo como requisito o n\u00edvel superior completo, e remunera\u00e7\u00e3o inicial de R$ 4.891,25. Hoje, a remunera\u00e7\u00e3o da classe inicial da carreira passa dos <strong><a href=\"http:\/\/www.transparencia.go.gov.br\/admin\/uploaded\/pessoal\/Anexo_I_Tabelas_das_Estruturas_Remuneratorias_Efetivos.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">R$ 5.300,00<\/a><\/strong>. Ainda com base no concurso anterior, realizado no ano de 2019, al\u00e9m das etapas ditas acima, houve tamb\u00e9m uma prova discursiva relativa aos Conhecimentos Espec\u00edficos previstos no edital. Ademais, a discursiva foi o principal crit\u00e9rio de desempate. Ent\u00e3o, <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/policia-penal-go-agente-penitenciario-pacotaco-pacote-teorico-pacote-passo-estrategico-2023-pre-edital\/\" target=\"_blank\" rel=\"noreferrer noopener\">prepare-se<\/a><\/strong>, candidata(o)!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-penal-ce\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Penal do Cear\u00e1<\/a><\/h3>\n\n\n\n<p>Em seguida, o \u00faltimo certame da Pol\u00edcia Penal cearense aconteceu no ano de 2017, e ofertou 1.000 vagas distribu\u00eddas por macrorregi\u00f5es. A carreira requisitou apenas o ensino m\u00e9dio completo, para um sal\u00e1rio inicial de mais de R$ 3.700,00, al\u00e9m das vantagens pessoais, abonos e adicionais,<strong> <a href=\"https:\/\/belt.al.ce.gov.br\/index.php\/legislacao-do-ceara\/organizacao-tematica\/defesa-social\/item\/3963-lei-n-14-582-de-21-12-09-d-o-28-12-09\" target=\"_blank\" rel=\"noreferrer noopener\">previstos em lei<\/a><\/strong>.<\/p>\n\n\n\n<p>Al\u00e9m das disciplinas mais cobradas nos demais certames, a(o) concurseira(o) precisou estudar a disciplina de Direitos Humanos e Cidadania, que foi um dos crit\u00e9rios de desempate. Com base no \u00faltimo conte\u00fado program\u00e1tico, j\u00e1 \u00e9 poss\u00edvel se <strong><a href=\"https:\/\/www.estrategiaconcursos.com.br\/curso\/policia-penal-ce-policial-penal-agente-penitenciario-pacotaco-pacote-teorico-pacote-passo-estrategico-2023-pre-edital\/\" target=\"_blank\" rel=\"noreferrer noopener\">organizar<\/a><\/strong>.<\/p>\n\n\n\n<p>Ademais, o or\u00e7amento do Cear\u00e1, para esse ano de 2023, j\u00e1 separa parte de sua despesa para a realiza\u00e7\u00e3o de concurso p\u00fablico, conforme imagem abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"382\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31213356\/ploa-2023-ce.png\" alt=\"\" class=\"wp-image-1162417\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31213356\/ploa-2023-ce.png 760w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31213356\/ploa-2023-ce-300x151.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31213356\/ploa-2023-ce-610x307.png 610w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/31213356\/ploa-2023-ce-150x75.png 150w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><figcaption class=\"wp-element-caption\">PLOA 2023 do Estado do Cear\u00e1<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concurso-policia-penal-ba\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edcia Penal da Bahia<\/a><\/h3>\n\n\n\n<p>Logo depois, al\u00e9m dos certames acima mencionados, o Estado da Bahia tamb\u00e9m prev\u00ea a realiza\u00e7\u00e3o de concurso p\u00fablico, em seu or\u00e7amento de 2023, para provimento de 400 vagas. As \u00faltimas provas ocorreram em 2014, e o edital trouxe como requisitos a conclus\u00e3o do ensino m\u00e9dio e tamb\u00e9m a CNH de categoria B.<\/p>\n\n\n\n<p>Ainda nesse contexto, as(os) candidatas(os) precisaram desenvolver uma reda\u00e7\u00e3o (que foi um dos crit\u00e9rios de desempate), e tamb\u00e9m ter conhecimentos sobre Direitos Humanos e No\u00e7\u00f5es de Direito Penal. Vamos ver as disciplinas mais cobradas para concursos de Pol\u00edcia Penal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quais-as-disciplinas-mais-cobradas\">Quais as disciplinas mais cobradas?<\/h2>\n\n\n\n<p>Assim, d\u00e1 para notar que voc\u00ea j\u00e1 pode ir conciliando as disciplinas mais cobradas dos concursos da Pol\u00edcia Penal. Ao observar os \u00faltimos editais, podemos extrair os <strong>conhecimentos b\u00e1sicos<\/strong> que j\u00e1 devem estar afiados desde o pr\u00e9-edital. S\u00e3o eles:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u00edngua Portuguesa<\/li>\n\n\n\n<li>Racioc\u00ednio L\u00f3gico<\/li>\n\n\n\n<li>Direito Constitucional<\/li>\n\n\n\n<li>Direito Administrativo<\/li>\n\n\n\n<li>Direitos Humanos<\/li>\n<\/ul>\n\n\n\n<p>Agora, para <strong>conhecimentos espec\u00edficos<\/strong> podemos citar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direito Penal (ou no\u00e7\u00f5es)<\/li>\n\n\n\n<li>Direito Processual Penal (ou no\u00e7\u00f5es)<\/li>\n\n\n\n<li>Legisla\u00e7\u00f5es Especiais\n<ul class=\"wp-block-list\">\n<li>Estatuto do Desarmamento<\/li>\n\n\n\n<li>Crimes Hediondos<\/li>\n\n\n\n<li>Crimes de Tortura<\/li>\n\n\n\n<li>Tr\u00e1fico il\u00edcito e uso indevido de drogas<\/li>\n\n\n\n<li>\u201cLei Maria da Penha\u201d<\/li>\n\n\n\n<li>Lei de Execu\u00e7\u00e3o Penal<\/li>\n\n\n\n<li>Lei das Contraven\u00e7\u00f5es Penais<\/li>\n\n\n\n<li>Organiza\u00e7\u00e3o Criminosa<\/li>\n\n\n\n<li>Abuso de Autoridade<\/li>\n\n\n\n<li>Crimes resultantes de preconceitos de ra\u00e7a ou de cor<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Para embasar a lista acima, repare o quadro abaixo dos concursos de Minas Gerais e de Santa Catarina de 2022, respectivamente. Temos as disciplinas cobradas e seus respectivos pesos: <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"420\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01085133\/disciplinas-comuns-em-2022.png\" alt=\"Pol\u00edcia Penal: as disciplinas mais cobradas\" class=\"wp-image-1162561\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01085133\/disciplinas-comuns-em-2022.png 516w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01085133\/disciplinas-comuns-em-2022-300x244.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01085133\/disciplinas-comuns-em-2022-150x122.png 150w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><figcaption class=\"wp-element-caption\">Pol\u00edcia Penal: as disciplinas mais cobradas<\/figcaption><\/figure>\n\n\n\n<p>Dessa forma, apesar de serem a base dos estudos, s\u00e3o conhecimentos que possuem um peso importante para a pontua\u00e7\u00e3o final da prova. Eles chegam a representar mais de 50% dos pontos totais. E ainda, para perceber que tais assuntos n\u00e3o variaram tanto com o passar do tempo, olhe esses assuntos do concurso de Santa Catarina, em 2019:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"278\" src=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01090310\/disciplinas-sc-em-2019.png\" alt=\"\" class=\"wp-image-1162574\" srcset=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01090310\/disciplinas-sc-em-2019.png 499w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01090310\/disciplinas-sc-em-2019-300x167.png 300w, https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/02\/01090310\/disciplinas-sc-em-2019-150x84.png 150w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\">Pol\u00edcia Penal: as disciplinas mais cobradas<\/figcaption><\/figure>\n\n\n\n<p>Logo, essas s\u00e3o disciplinas que t\u00eam sido exigidas com certa frequ\u00eancia, e que merecem sua aten\u00e7\u00e3o no pr\u00e9-edital, tanto para garantir pontos na etapa objetiva quanto para desenvolver os textos dissertativos que venham a ser cobrados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-comecar-a-estudar\">Como come\u00e7ar a estudar?<\/h2>\n\n\n\n<p>Por fim, para ir conciliando tudo para os concursos previstos para 2023, re\u00fana os materiais das disciplinas mais cobradas de <strong>conhecimentos b\u00e1sicos<\/strong>. A princ\u00edpio, a ideia \u00e9 obter a base necess\u00e1ria para prosseguir para os conhecimentos espec\u00edficos. Afinal, ainda n\u00e3o h\u00e1 como saber exatamente qual \u00e9 o conhecimento espec\u00edfico que vir\u00e1 em seu edital.<\/p>\n\n\n\n<p>Entretanto, a recomenda\u00e7\u00e3o \u00e9 estudar a teoria de cada disciplina, resolver quest\u00f5es, e tamb\u00e9m j\u00e1 escrever textos. Dessa forma, voc\u00ea estar\u00e1 retendo o conhecimento, fazendo uma esp\u00e9cie de resumo e tamb\u00e9m avaliando em qual parte ainda precisa dar uma revisada, al\u00e9m de fixar o que aprendeu.<\/p>\n\n\n\n<p>Portanto, apesar de haver algumas op\u00e7\u00f5es de estudo a serem seguidas, o caminho \u00e9 apenas um: estudar! As oportunidades est\u00e3o surgindo, e os editais n\u00e3o esperam.<\/p>\n\n\n\n<p>Senta e estuda!<\/p>\n\n\n\n<p>Boa sorte!<\/p>\n\n\n\n<p class=\"has-text-align-center\" id=\"h-quer-saber-tudo-sobre-concursos-previstos\"><strong>Quer saber quais ser\u00e3o os pr\u00f3ximos concursos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Confira nossos artigos!<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-abertos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Concursos abertos<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/concursos-2023\/\">Concursos 2023<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Concurseira(o) impar\u00e1vel, o primeiro semestre do ano de 2023 est\u00e1 apenas come\u00e7ando e j\u00e1 h\u00e1 previs\u00e3o de alguns editais para Pol\u00edcia Penal pelo pa\u00eds. A hora de se preparar \u00e9 justamente esta: no pr\u00e9-edital. Ent\u00e3o, foque nos concursos de 2023 conciliando as disciplinas mais cobradas. Saia na frente da concorr\u00eancia! Quais as atribui\u00e7\u00f5es do Policial [&hellip;]<\/p>\n","protected":false},"author":2569,"featured_media":1151527,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[221305,221304],"tax_estado":[219964,219965,219966,219967,219968,219969,219970,219971,219972,219973,219974,219975,219976,219977,219978,219979,219980,219981,219982,219983,219984,219985,219986,219987,219988,219989,219990],"class_list":["post-1160917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-e-concursos","tag-concurso-policia-penal","tag-policia-penal","tax_estado-ac","tax_estado-al","tax_estado-am","tax_estado-ap","tax_estado-ba","tax_estado-ce","tax_estado-df","tax_estado-es","tax_estado-go","tax_estado-ma","tax_estado-mg","tax_estado-ms","tax_estado-mt","tax_estado-pa","tax_estado-pb","tax_estado-pe","tax_estado-pi","tax_estado-pr","tax_estado-rj","tax_estado-rn","tax_estado-ro","tax_estado-rr","tax_estado-rs","tax_estado-sc","tax_estado-se","tax_estado-sp","tax_estado-to"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pol\u00edcia Penal: Quais as disciplinas mais cobradas?<\/title>\n<meta name=\"description\" content=\"Descubra quais as disciplinas mais cobradas nos Concursos para Pol\u00edcia Penal e as principais oportunidades para 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?\" \/>\n<meta property=\"og:description\" content=\"Descubra quais as disciplinas mais cobradas nos Concursos para Pol\u00edcia Penal e as principais oportunidades para 2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-20T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T13:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Taiane Ferreira Concei\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Taiane Ferreira Concei\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/\"},\"author\":{\"name\":\"Taiane Ferreira Concei\u00e7\u00e3o\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/699843c170e88965fc39f4f55cbc3504\"},\"headline\":\"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?\",\"datePublished\":\"2023-02-20T11:00:00+00:00\",\"dateModified\":\"2023-02-20T13:52:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/\"},\"wordCount\":1834,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg\",\"keywords\":[\"concurso pol\u00edcia penal\",\"pol\u00edcia penal\"],\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/\",\"name\":\"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg\",\"datePublished\":\"2023-02-20T11:00:00+00:00\",\"dateModified\":\"2023-02-20T13:52:30+00:00\",\"description\":\"Descubra quais as disciplinas mais cobradas nos Concursos para Pol\u00edcia Penal e as principais oportunidades para 2023.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg\",\"width\":600,\"height\":400,\"caption\":\"policia penal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/699843c170e88965fc39f4f55cbc3504\",\"name\":\"Taiane Ferreira Concei\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3eeaf722fb4a0f0403ab2fcd989778b82e4ab1df34e59c86868171efee133a4d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3eeaf722fb4a0f0403ab2fcd989778b82e4ab1df34e59c86868171efee133a4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3eeaf722fb4a0f0403ab2fcd989778b82e4ab1df34e59c86868171efee133a4d?s=96&d=mm&r=g\",\"caption\":\"Taiane Ferreira Concei\u00e7\u00e3o\"},\"description\":\"Aprovada nos concursos Marinha do Brasil, Correios, Secretaria de Educa\u00e7\u00e3o do Estado da Bahia, EMBASA e Pol\u00edcia Civil do Estado da Bahia.\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/taianef1yahoo-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?","description":"Descubra quais as disciplinas mais cobradas nos Concursos para Pol\u00edcia Penal e as principais oportunidades para 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/","og_locale":"pt_BR","og_type":"article","og_title":"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?","og_description":"Descubra quais as disciplinas mais cobradas nos Concursos para Pol\u00edcia Penal e as principais oportunidades para 2023.","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-02-20T11:00:00+00:00","article_modified_time":"2023-02-20T13:52:30+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg","type":"image\/jpeg"}],"author":"Taiane Ferreira Concei\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Taiane Ferreira Concei\u00e7\u00e3o","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/"},"author":{"name":"Taiane Ferreira Concei\u00e7\u00e3o","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/699843c170e88965fc39f4f55cbc3504"},"headline":"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?","datePublished":"2023-02-20T11:00:00+00:00","dateModified":"2023-02-20T13:52:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/"},"wordCount":1834,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg","keywords":["concurso pol\u00edcia penal","pol\u00edcia penal"],"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/","name":"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage"},"thumbnailUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg","datePublished":"2023-02-20T11:00:00+00:00","dateModified":"2023-02-20T13:52:30+00:00","description":"Descubra quais as disciplinas mais cobradas nos Concursos para Pol\u00edcia Penal e as principais oportunidades para 2023.","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#primaryimage","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2023\/01\/12111942\/policia-penal-go.jpg","width":600,"height":400,"caption":"policia penal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/policia-penal-disciplinas-mais-cobradas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edcia Penal: Quais as disciplinas mais cobradas?"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/699843c170e88965fc39f4f55cbc3504","name":"Taiane Ferreira Concei\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3eeaf722fb4a0f0403ab2fcd989778b82e4ab1df34e59c86868171efee133a4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3eeaf722fb4a0f0403ab2fcd989778b82e4ab1df34e59c86868171efee133a4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3eeaf722fb4a0f0403ab2fcd989778b82e4ab1df34e59c86868171efee133a4d?s=96&d=mm&r=g","caption":"Taiane Ferreira Concei\u00e7\u00e3o"},"description":"Aprovada nos concursos Marinha do Brasil, Correios, Secretaria de Educa\u00e7\u00e3o do Estado da Bahia, EMBASA e Pol\u00edcia Civil do Estado da Bahia.","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/taianef1yahoo-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1160917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/2569"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1160917"}],"version-history":[{"count":24,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1160917\/revisions"}],"predecessor-version":[{"id":1174872,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1160917\/revisions\/1174872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media\/1151527"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1160917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1160917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1160917"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1160917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}