{"id":1156905,"date":"2023-01-22T10:25:03","date_gmt":"2023-01-22T13:25:03","guid":{"rendered":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?p=1156905"},"modified":"2023-05-17T13:36:24","modified_gmt":"2023-05-17T16:36:24","slug":"recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial","status":"publish","type":"post","link":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/","title":{"rendered":"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial"},"content":{"rendered":"\n<p>Eu, Prof. Paulo Sousa (<a href=\"http:\/\/www.instagram.com.br\/prof.phms\">IG<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UC5BNzTLlcneB_x1aUAhXBAg\">YT<\/a>), vou apresentar o gabarito da prova objetiva de Direito Civil e Legisla\u00e7\u00e3o Civil Especial da DP\/DF \u2013 Defensor P\u00fablico. Vou fazer alguns coment\u00e1rios sobre a prova e analisar a possibilidade de recursos.<\/p>\n\n\n\n<p>Vamos l\u00e1<\/p>\n\n\n\n<p>51. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023)No que se refere aos direitos de personalidade, assinale a op\u00e7\u00e3o correta.<\/p>\n\n\n\n<p>a) O exerc\u00edcio dos direitos da personalidade pode sofrer limita\u00e7\u00e3o volunt\u00e1ria.<\/p>\n\n\n\n<p>b) \u00c9 v\u00e1lida a disposi\u00e7\u00e3o gratuita, ainda em vida, de parte do pr\u00f3prio corpo, com objetivo cient\u00edfico.<\/p>\n\n\n\n<p>c) Sem que haja inten\u00e7\u00e3o difamat\u00f3ria, o nome da pessoa pode ser empregado por outrem em publica\u00e7\u00f5es que a exponham ao desprezo p\u00fablico.<\/p>\n\n\n\n<p>d) A vida privada da pessoa natural \u00e9 inviol\u00e1vel.<\/p>\n\n\n\n<p>e) O pseud\u00f4nimo goza da mesma prote\u00e7\u00e3o conferida ao nome, independentemente da finalidade pretendida.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>A alternativa A est\u00e1 incorreta, j\u00e1 que h\u00e1 possibilidade de limita\u00e7\u00e3o volunt\u00e1ria ao exerc\u00edcio dos direitos de personalidade. No entanto a limita\u00e7\u00e3o n\u00e3o pode ser permanente nem geral, conforme o Enunciado 4 da Jornada de Direito Civil.<\/p>\n\n\n\n<p>A alternativa B est\u00e1 incorreta, conforme o art. 14 do CC: \u201c\u00c9 v\u00e1lida, com objetivo cient\u00edfico, ou altru\u00edstico, a disposi\u00e7\u00e3o gratuita do pr\u00f3prio corpo, no todo ou em parte, <strong>para depois da morte<\/strong>\u201d.<\/p>\n\n\n\n<p>A alternativa C est\u00e1 incorreta, conforme o art. 17 do CC: \u201cO nome da pessoa <strong>n\u00e3o pode ser empregado<\/strong> por outrem em publica\u00e7\u00f5es ou representa\u00e7\u00f5es que a exponham ao desprezo p\u00fablico, <strong>ainda quando n\u00e3o haja inten\u00e7\u00e3o difamat\u00f3ria<\/strong>\u201d.<\/p>\n\n\n\n<p>A alternativa D est\u00e1 correta, conforme o art. 21 do CC: \u201c<strong>A vida privada da pessoa natural \u00e9 inviol\u00e1vel<\/strong>, e o juiz, a requerimento do interessado, adotar\u00e1 as provid\u00eancias necess\u00e1rias para impedir ou fazer cessar ato contr\u00e1rio a esta norma\u201d.<\/p>\n\n\n\n<p>A alternativa E est\u00e1 incorreta, conforme o art. 19 do CC: \u201cO pseud\u00f4nimo adotado <strong>para atividades l\u00edcitas<\/strong> goza da prote\u00e7\u00e3o que se d\u00e1 ao nome\u201d.<\/p>\n\n\n\n<p>52. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023) Acerca dos bens im\u00f3veis e de suas classifica\u00e7\u00f5es, assinale a op\u00e7\u00e3o correta.<\/p>\n\n\n\n<p>a) Direitos reais sobre im\u00f3veis e a\u00e7\u00f5es que os asseguram s\u00e3o considerados bens m\u00f3veis por determina\u00e7\u00e3o legal.<\/p>\n\n\n\n<p>b) Os materiais provisoriamente separados de um pr\u00e9dio, para nele se reempregarem, adquirem o car\u00e1ter de bens m\u00f3veis.<\/p>\n\n\n\n<p>c) Direitos \u00e0 sucess\u00e3o aberta s\u00e3o considerados bens im\u00f3veis para efeitos legais.<\/p>\n\n\n\n<p>d) O solo \u00e9 considerado bem im\u00f3vel por acess\u00e3o natural.<\/p>\n\n\n\n<p>e) As edifica\u00e7\u00f5es que, separadas do solo, mas conservando a sua unidade, forem removidas para outro local perdem o car\u00e1ter de bens im\u00f3veis.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>A alternativa A est\u00e1 incorreta, conforme o art. 83, inc. II do CC: \u201cConsideram-se m\u00f3veis para os efeitos legais: os direitos reais sobre <strong>objetos m\u00f3veis<\/strong> e as a\u00e7\u00f5es correspondentes;\u201d.<\/p>\n\n\n\n<p>A alternativa B est\u00e1 incorreta, conforme o art. 81, inc. II do CC: \u201c<strong>N\u00e3o perdem o car\u00e1ter de im\u00f3veis<\/strong>: os materiais provisoriamente separados de um pr\u00e9dio, para nele se reempregarem\u201d.<\/p>\n\n\n\n<p>A alternativa C est\u00e1 correta, conforme o art. 80, inc. II do CC: \u201cConsideram-se im\u00f3veis para os efeitos legais: o direito \u00e0 sucess\u00e3o aberta\u201d.<\/p>\n\n\n\n<p>A alternativa D est\u00e1 incorreta, j\u00e1 que o solo e suas adjac\u00eancias naturais pertencem \u00e0 categoria dos bens im\u00f3veis por sua natureza, assim como \u00e1rvores e frutos pendentes, o espa\u00e7o a\u00e9reo e o subsolo.<\/p>\n\n\n\n<p>A alternativa E est\u00e1 incorreta, conforme o art. 81, inc. I do CC: \u201c<strong>N\u00e3o perdem o car\u00e1ter de im\u00f3veis<\/strong>: as edifica\u00e7\u00f5es que, separadas do solo, mas conservando a sua unidade, forem removidas para outro local;\u201d.<\/p>\n\n\n\n<p>53. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023) O princ\u00edpio contratual que faculta \u00e0s partes se vincularem a um contrato, adquirindo direitos e obriga\u00e7\u00f5es, \u00e9 denominado<\/p>\n\n\n\n<p>a) princ\u00edpio do equil\u00edbrio contratual.<\/p>\n\n\n\n<p>b) princ\u00edpio da fun\u00e7\u00e3o social do contrato.<\/p>\n\n\n\n<p>c) princ\u00edpio da autonomia da vontade.<\/p>\n\n\n\n<p>d) princ\u00edpio da boa-f\u00e9.<\/p>\n\n\n\n<p>e) princ\u00edpio da onerosidade excessiva.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>A alternativa A est\u00e1 incorreta, j\u00e1 que esse princ\u00edpio trata da justi\u00e7a contratual, ou seja, da <strong>proporcionalidade entre a presta\u00e7\u00e3o e a contrapresta\u00e7\u00e3o<\/strong> dos contratantes. Origina-se, em \u00faltima inst\u00e2ncia, dos postulados constitucionais de redu\u00e7\u00e3o das desigualdades e promo\u00e7\u00e3o do bem-estar coletivo (art. 3\u00ba, incs. III e IV da CF\/1988).<\/p>\n\n\n\n<p>A alternativa B est\u00e1 incorreta, j\u00e1 que a fun\u00e7\u00e3o social do contrato tem um vi\u00e9s axiol\u00f3gico (um valor juridicamente protegido), criada a partir de uma vis\u00e3o integrativa do contrato na sociedade, de modo a <strong>conciliar os interesses individuais com os interesses da sociedade toda, promovendo a dignidade da pessoa humana.<\/strong><\/p>\n\n\n\n<p>A alternativa C est\u00e1 correta, j\u00e1 que, na concep\u00e7\u00e3o tradicional, <strong>a autonomia privada e a liberdade de contratar significam que o sujeito tem o poder de gerir seus neg\u00f3cios, j\u00e1 que ele \u00e9 o melhor juiz de si mesmo<\/strong>. A partir da vetusta \u201cautonomia da vontade\u201d, a vontade dos contratantes \u00e9 suprema e inderrog\u00e1vel sen\u00e3o pelas pr\u00f3prias partes. Ela significa a express\u00e3o m\u00e1xima da igualdade formal (\u201ctodos s\u00e3o iguais perante a lei\u201d), protegida, inclusive, no plano constitucional, a partir da liberdade de iniciativa, prevista no art. 170 da CF\/1988.<\/p>\n\n\n\n<p>A alternativa D est\u00e1 incorreta, conforme o art. 422 do CC\/2002: \u201cos contratantes s\u00e3o obrigados a guardar, assim na conclus\u00e3o do contrato, como em sua execu\u00e7\u00e3o, os princ\u00edpios da probidade e boa-f\u00e9\u201d. Assim, a boa-f\u00e9 objetiva estabelece um <strong>modelo de conduta aos contratantes (primeira fun\u00e7\u00e3o, fun\u00e7\u00e3o modeladora).<\/strong> Ou seja, como eles devem portar-se desde o momento pr\u00e9vio \u00e0 contrata\u00e7\u00e3o, impedindo o apelo a cl\u00e1usulas abusivas n\u00e3o previstas, letras mi\u00fadas, reda\u00e7\u00e3o confusa, erros propositais etc.<\/p>\n\n\n\n<p>A alternativa E est\u00e1 incorreta, j\u00e1 que o princ\u00edpio da onerosidade excessiva significa que a rela\u00e7\u00e3o contratual se torna desequilibrada em raz\u00e3o de acontecimentos extraordin\u00e1rios, imprevis\u00edveis e supervenientes. Assim, o devedor arca com uma presta\u00e7\u00e3o excessivamente onerosa e a outra parte obt\u00e9m benef\u00edcio exagerado.<\/p>\n\n\n\n<p>54. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023) No que concerne ao parcelamento do solo urbano conforme previsto na Lei n.<em>\u00ba<\/em> 6.766\/1979, assinale a op\u00e7\u00e3o correta.<\/p>\n\n\n\n<p>a) O desmembramento \u00e9 uma forma de parcelamento do solo, com abertura de novas vias e logradouros p\u00fablicos, al\u00e9m do prolongamento, da modifica\u00e7\u00e3o ou da amplia\u00e7\u00e3o dos j\u00e1 existentes.<\/p>\n\n\n\n<p>b) O loteamento \u00e9 uma forma de parcelamento do solo, com aproveitamento do sistema vi\u00e1rio existente, sem abertura de novas vias e logradouros p\u00fablicos, nem prolongamento, modifica\u00e7\u00e3o ou amplia\u00e7\u00e3o dos j\u00e1 existentes.<\/p>\n\n\n\n<p>c) O parcelamento do solo somente ser\u00e1 admitido para fins urbanos em zonas urbanas, de expans\u00e3o urbana ou de urbaniza\u00e7\u00e3o espec\u00edfica, assim definidas pelo plano diretor ou aprovadas por lei municipal.<\/p>\n\n\n\n<p>d) Aprovado o projeto de parcelamento, o loteador dever\u00e1 submet\u00ea-lo ao registro imobili\u00e1rio no prazo de 180 dias de sua aprova\u00e7\u00e3o, sob pena de multa de at\u00e9 cinquenta sal\u00e1rios m\u00ednimos.<\/p>\n\n\n\n<p>e) O registro do loteamento somente poder\u00e1 ser cancelado por decis\u00e3o judicial.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>A alternativa A est\u00e1 incorreta, conforme o art. 2<sup>o<\/sup>, \u00a7 2<sup>o<\/sup> da Lei n.<em>\u00ba<\/em> 6.766\/1979: \u201cConsidera-se <strong>desmembramento<\/strong> a subdivis\u00e3o de gleba em lotes destinados a edifica\u00e7\u00e3o, com aproveitamento do sistema vi\u00e1rio existente, desde que n\u00e3o implique na abertura de novas vias e logradouros p\u00fablicos, nem no prolongamento, modifica\u00e7\u00e3o ou amplia\u00e7\u00e3o dos j\u00e1 existentes\u201d.<\/p>\n\n\n\n<p>A alternativa B est\u00e1 incorreta, conforme o art. 2<sup>o<\/sup>, \u00a7 1<sup>o<\/sup> da Lei n.<em>\u00ba<\/em> 6.766\/1979: \u201cConsidera-se <strong>loteamento<\/strong> a subdivis\u00e3o de gleba em lotes destinados a edifica\u00e7\u00e3o, com abertura de novas vias de circula\u00e7\u00e3o, de logradouros p\u00fablicos ou prolongamento, modifica\u00e7\u00e3o ou amplia\u00e7\u00e3o das vias existentes\u201d.<\/p>\n\n\n\n<p>A alternativa C est\u00e1 correta, conforme o art. 3<sup>o<\/sup> da Lei n.<em>\u00ba<\/em> 6.766\/1979: \u201cSomente ser\u00e1 admitido o parcelamento do solo para fins urbanos em zonas urbanas, de expans\u00e3o urbana ou de urbaniza\u00e7\u00e3o espec\u00edfica, assim definidas pelo plano diretor ou aprovadas por lei municipal\u201d.&nbsp;&nbsp;<\/p>\n\n\n\n<p>A alternativa D est\u00e1 incorreta, conforme o art. 18 da Lei n.<em>\u00ba<\/em> 6.766\/1979: \u201cAprovado o <strong>projeto de loteamento ou de desmembramento<\/strong>, o loteador dever\u00e1 submet\u00ea-lo ao registro imobili\u00e1rio dentro de 180 (cento e oitenta) dias, <strong>sob pena de caducidade da aprova\u00e7\u00e3o<\/strong> (&#8230;)\u201d.<\/p>\n\n\n\n<p>A alternativa E est\u00e1 incorreta, conforme o art. 23, incisos I, II e II da Lei n.<em>\u00ba<\/em> 6.766\/1979: \u201cO registro do loteamento s\u00f3 poder\u00e1 ser cancelado:<a><\/a> I &#8211; por decis\u00e3o judicial;<a><\/a> II &#8211; <strong>a requerimento do loteador<\/strong>, com anu\u00eancia da Prefeitura, ou do Distrito Federal quando for o caso, enquanto nenhum lote houver sido objeto de contrato;<a><\/a> III &#8211; <strong>a requerimento conjunto do loteador e de todos os adquirentes de lotes<\/strong>, com anu\u00eancia da Prefeitura, ou do Distrito Federal quando for o caso, e do Estado\u201d.<\/p>\n\n\n\n<p>55. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023) \u00c9 obriga\u00e7\u00e3o do locador de im\u00f3vel urbano arcar com as despesas relativas a<\/p>\n\n\n\n<p>a) sal\u00e1rios, encargos trabalhistas, contribui\u00e7\u00f5es previdenci\u00e1rias e sociais dos empregados do condom\u00ednio.<\/p>\n\n\n\n<p>b) limpeza, conserva\u00e7\u00e3o e pintura das instala\u00e7\u00f5es e depend\u00eancias de uso comum.<\/p>\n\n\n\n<p>c) manuten\u00e7\u00e3o e conserva\u00e7\u00e3o das instala\u00e7\u00f5es e dos equipamentos hidr\u00e1ulicos, el\u00e9tricos, mec\u00e2nicos e de seguran\u00e7a que sejam de uso comum.<\/p>\n\n\n\n<p>d) decora\u00e7\u00e3o e paisagismo nas partes de uso comum.<\/p>\n\n\n\n<p>e) manuten\u00e7\u00e3o e conserva\u00e7\u00e3o das instala\u00e7\u00f5es e dos equipamentos de uso comum destinados \u00e0 pr\u00e1tica de esportes e ao lazer.<\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>A alternativa A est\u00e1 incorreta, conforme o art. 23, inc. XII: \u201cO <strong>locat\u00e1rio <\/strong>\u00e9 obrigado a: XII &#8211; pagar as despesas ordin\u00e1rias de condom\u00ednio\u201d e \u00a7 1\u00ba, al\u00ednea \u201ca\u201d&nbsp; da <a href=\"http:\/\/legislacao.planalto.gov.br\/legisla\/legislacao.nsf\/Viw_Identificacao\/lei%208.245-1991?OpenDocument\">&nbsp;Lei n.<em>\u00ba<\/em>&nbsp; 8.245<\/a>\/1991: \u201cPor despesas ordin\u00e1rias de condom\u00ednio se entendem as necess\u00e1rias \u00e0 administra\u00e7\u00e3o respectiva, especialmente: a) sal\u00e1rios, encargos trabalhistas, contribui\u00e7\u00f5es previdenci\u00e1rias e sociais dos empregados do condom\u00ednio;\u201d.<\/p>\n\n\n\n<p>A alternativa B est\u00e1 incorreta, conforme o art. 23, inc. XII: \u201cO <strong>locat\u00e1rio <\/strong>\u00e9 obrigado a: XII &#8211; pagar as despesas ordin\u00e1rias de condom\u00ednio\u201d e \u00a7 1\u00ba, al\u00ednea \u201cc\u201d&nbsp; da <a href=\"http:\/\/legislacao.planalto.gov.br\/legisla\/legislacao.nsf\/Viw_Identificacao\/lei%208.245-1991?OpenDocument\">&nbsp;Lei n.<em>\u00ba<\/em>&nbsp; 8.245<\/a>\/1991: \u201cPor despesas ordin\u00e1rias de condom\u00ednio se entendem as necess\u00e1rias \u00e0 administra\u00e7\u00e3o respectiva, especialmente: c) limpeza, conserva\u00e7\u00e3o e pintura das instala\u00e7\u00f5es e depend\u00eancias de uso comum;\u201d.<\/p>\n\n\n\n<p>A alternativa C est\u00e1 incorreta, conforme o art. 23, inc. XII: \u201cO <strong>locat\u00e1rio <\/strong>\u00e9 obrigado a: XII &#8211; pagar as despesas ordin\u00e1rias de condom\u00ednio\u201d e \u00a7 1\u00ba, al\u00ednea \u201cd\u201d&nbsp; da <a href=\"http:\/\/legislacao.planalto.gov.br\/legisla\/legislacao.nsf\/Viw_Identificacao\/lei%208.245-1991?OpenDocument\">&nbsp;Lei n.<em>\u00ba<\/em>&nbsp; 8.245<\/a>\/1991: \u201cPor despesas ordin\u00e1rias de condom\u00ednio se entendem as necess\u00e1rias \u00e0 administra\u00e7\u00e3o respectiva, especialmente: d) manuten\u00e7\u00e3o e conserva\u00e7\u00e3o das instala\u00e7\u00f5es e equipamentos hidr\u00e1ulicos, el\u00e9tricos, mec\u00e2nicos e de seguran\u00e7a, de uso comum;\u201d.<\/p>\n\n\n\n<p>A alternativa D est\u00e1 correta, conforme o art. 22, inc. X: \u201cO locador \u00e9 obrigado a: X &#8211; pagar as despesas extraordin\u00e1rias de condom\u00ednio\u201d e par\u00e1grafo \u00fanico, al\u00ednea \u201cf\u201d da <a href=\"http:\/\/legislacao.planalto.gov.br\/legisla\/legislacao.nsf\/Viw_Identificacao\/lei%208.245-1991?OpenDocument\">&nbsp;Lei n.<em>\u00ba<\/em>&nbsp; 8.245<\/a>\/1991: \u201cPor despesas extraordin\u00e1rias de condom\u00ednio se entendem aquelas que n\u00e3o se refiram aos gastos rotineiros de manuten\u00e7\u00e3o do edif\u00edcio, especialmente: despesas de decora\u00e7\u00e3o e paisagismo nas partes de uso comum;\u201d.<\/p>\n\n\n\n<p>A alternativa E est\u00e1 incorreta, conforme o art. 23, inc. XII: \u201cO <strong>locat\u00e1rio <\/strong>\u00e9 obrigado a: XII &#8211; pagar as despesas ordin\u00e1rias de condom\u00ednio\u201d e \u00a7 1\u00ba, al\u00ednea \u201ce\u201d&nbsp; da <a href=\"http:\/\/legislacao.planalto.gov.br\/legisla\/legislacao.nsf\/Viw_Identificacao\/lei%208.245-1991?OpenDocument\">&nbsp;Lei n.<em>\u00ba<\/em>&nbsp; 8.245<\/a>\/1991: \u201cPor despesas ordin\u00e1rias de condom\u00ednio se entendem as necess\u00e1rias \u00e0 administra\u00e7\u00e3o respectiva, especialmente: e) manuten\u00e7\u00e3o e conserva\u00e7\u00e3o das instala\u00e7\u00f5es e equipamentos de uso comum destinados \u00e0 pr\u00e1tica de esportes e lazer;\u201d.<\/p>\n\n\n\n<p>56. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023) Assinale a op\u00e7\u00e3o que indica o contrato banc\u00e1rio por meio do qual o banco empresta certa quantia ao cliente, o qual se obriga a pag\u00e1-la, em determinado prazo, acrescida dos encargos remunerat\u00f3rios contratados.<\/p>\n\n\n\n<p>a) contrato de fomento mercantil<\/p>\n\n\n\n<p>b) contrato de dep\u00f3sito banc\u00e1rio<\/p>\n\n\n\n<p>c) contrato de m\u00fatuo banc\u00e1rio<\/p>\n\n\n\n<p>d) contrato de desconto banc\u00e1rio<\/p>\n\n\n\n<p>e) contrato de fian\u00e7a banc\u00e1ria<\/p>\n\n\n\n<p><strong>Coment\u00e1rios:<\/strong><\/p>\n\n\n\n<p>A alternativa A est\u00e1 incorreta, j\u00e1 que o contrato de fomento mercantil ou Factoring se trata da venda de direitos credit\u00f3rios de determinada empresa a terceiro que os compra \u00e0 vista, mas com desconto.<\/p>\n\n\n\n<p>A alternativa B est\u00e1 incorreta, j\u00e1 que o art. 627 estabelece que o deposit\u00e1rio recebe um bem m\u00f3vel, para guardar, at\u00e9 que o depositante o reclame. Assim, a institui\u00e7\u00e3o financeira guarda um certo valor que poder\u00e1 ser retirado no futuro pelo cliente.<\/p>\n\n\n\n<p>A alternativa C est\u00e1 correta, conforme o art. 586 do CC: \u201cO m\u00fatuo \u00e9 o empr\u00e9stimo de coisas fung\u00edveis. O mutu\u00e1rio \u00e9 obrigado a restituir ao mutuante o que dele recebeu em coisa do mesmo g\u00eanero, qualidade e quantidade\u201d. No m\u00fatuo banc\u00e1rio, as institui\u00e7\u00f5es financeiras aplicam juros sobre o valor emprestado, permitindo-se a capitaliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>A alternativa D est\u00e1 incorreta, j\u00e1 que o contrato de desconto banc\u00e1rio se refere ao adiantamento de cr\u00e9ditos de terceiros para clientes. Assim, o banco deduz do montante juros, despesas e comiss\u00f5es ao realizar o pagamento pelo cr\u00e9dito descontado.<\/p>\n\n\n\n<p>A alternativa E est\u00e1 incorreta, j\u00e1 que no contrato de fian\u00e7a banc\u00e1ria a institui\u00e7\u00e3o financeira garante o cumprimento das obriga\u00e7\u00f5es de seu cliente no caso de inadimpl\u00eancia.<\/p>\n\n\n\n<p>Assim, n\u00e3o visualizei a possibilidade de recurso nas quest\u00f5es de Direito Civil.<\/p>\n\n\n\n<p>Espero que voc\u00ea tenha ido bem na prova!<\/p>\n\n\n\n<p><br \/>Voc\u00ea j\u00e1 est\u00e1 preparado para as pr\u00f3ximas etapas? O Estrat\u00e9gia tem cursos para todas as etapas da DPE RO e eu sou o Professor respons\u00e1vel pelo Direito Civil! Fique ligado!<\/p>\n\n\n\n<p>Abra\u00e7o,<\/p>\n\n\n\n<p><a href=\"https:\/\/www.estrategiaconcursos.com.br\/cursosPorProfessor\/paulo-h-m-sousa-3384\/\">Paulo H M Sousa<\/a><\/p>\n\n\n\n<p><a href=\"http:\/\/www.instagram.com.br\/prof.phms\">Instagram<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.youtube.com\/channel\/UC5BNzTLlcneB_x1aUAhXBAg\">Youtube<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eu, Prof. Paulo Sousa (IG\u00a0e\u00a0YT), vou apresentar o gabarito da prova objetiva de Direito Civil e Legisla\u00e7\u00e3o Civil Especial da DP\/DF \u2013 Defensor P\u00fablico. Vou fazer alguns coment\u00e1rios sobre a prova e analisar a possibilidade de recursos. Vamos l\u00e1 51. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023)No que se refere aos direitos de personalidade, assinale [&hellip;]<\/p>\n","protected":false},"author":1094,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"post_tipo":"article","footnotes":""},"categories":[1],"tags":[],"tax_estado":[],"class_list":["post-1156905","post","type-post","status-publish","format-standard","hentry","category-cursos-e-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial\" \/>\n<meta property=\"og:description\" content=\"Eu, Prof. Paulo Sousa (IG\u00a0e\u00a0YT), vou apresentar o gabarito da prova objetiva de Direito Civil e Legisla\u00e7\u00e3o Civil Especial da DP\/DF \u2013 Defensor P\u00fablico. Vou fazer alguns coment\u00e1rios sobre a prova e analisar a possibilidade de recursos. Vamos l\u00e1 51. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023)No que se refere aos direitos de personalidade, assinale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia Concursos\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-22T13:25:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T16:36:24+00:00\" \/>\n<meta name=\"author\" content=\"Paulo Sousa (Coord.)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:site\" content=\"@EstratConcursos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paulo Sousa (Coord.)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/\"},\"author\":{\"name\":\"Paulo Sousa (Coord.)\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f6cf94f3aa8ed75620a4506ad577b88a\"},\"headline\":\"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial\",\"datePublished\":\"2023-01-22T13:25:03+00:00\",\"dateModified\":\"2023-05-17T16:36:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/\"},\"wordCount\":2299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"articleSection\":[\"Concursos P\u00fablicos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/\",\"name\":\"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial\",\"isPartOf\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\"},\"datePublished\":\"2023-01-22T13:25:03+00:00\",\"dateModified\":\"2023-05-17T16:36:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"name\":\"Estrat\u00e9gia Concursos\",\"description\":\"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.\",\"publisher\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization\",\"name\":\"Estrat\u00e9gia Concursos\",\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"contentUrl\":\"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg\",\"width\":230,\"height\":60,\"caption\":\"Estrat\u00e9gia Concursos\"},\"image\":{\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/EstratConcursos\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f6cf94f3aa8ed75620a4506ad577b88a\",\"name\":\"Paulo Sousa (Coord.)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/29f9e2d4ed868d929b68f3762e3577b9db519beed74b347b76e194f9a3293cf1?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/29f9e2d4ed868d929b68f3762e3577b9db519beed74b347b76e194f9a3293cf1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/29f9e2d4ed868d929b68f3762e3577b9db519beed74b347b76e194f9a3293cf1?s=96&d=mm&r=g\",\"caption\":\"Paulo Sousa (Coord.)\"},\"url\":\"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/prof-phmsestrategiaconcursos-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/","og_locale":"pt_BR","og_type":"article","og_title":"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial","og_description":"Eu, Prof. Paulo Sousa (IG\u00a0e\u00a0YT), vou apresentar o gabarito da prova objetiva de Direito Civil e Legisla\u00e7\u00e3o Civil Especial da DP\/DF \u2013 Defensor P\u00fablico. Vou fazer alguns coment\u00e1rios sobre a prova e analisar a possibilidade de recursos. Vamos l\u00e1 51. (CEBRASPE \u2013 DPE\/RO &#8211; DEFENSOR \u2013 2023)No que se refere aos direitos de personalidade, assinale [&hellip;]","og_url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/","og_site_name":"Estrat\u00e9gia Concursos","article_published_time":"2023-01-22T13:25:03+00:00","article_modified_time":"2023-05-17T16:36:24+00:00","author":"Paulo Sousa (Coord.)","twitter_card":"summary_large_image","twitter_creator":"@EstratConcursos","twitter_site":"@EstratConcursos","twitter_misc":{"Escrito por":"Paulo Sousa (Coord.)","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#article","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/"},"author":{"name":"Paulo Sousa (Coord.)","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f6cf94f3aa8ed75620a4506ad577b88a"},"headline":"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial","datePublished":"2023-01-22T13:25:03+00:00","dateModified":"2023-05-17T16:36:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/"},"wordCount":2299,"commentCount":0,"publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"articleSection":["Concursos P\u00fablicos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/","name":"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial","isPartOf":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website"},"datePublished":"2023-01-22T13:25:03+00:00","dateModified":"2023-05-17T16:36:24+00:00","breadcrumb":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/recurso-e-gabarito-dpe-ro-direito-civil-e-legislacao-civil-especial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.estrategiaconcursos.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"RECURSO e Gabarito: DPE\/RO \u2013 Direito Civil e Legisla\u00e7\u00e3o Civil Especial"}]},{"@type":"WebSite","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#website","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","name":"Estrat\u00e9gia Concursos","description":"O blog da Estrat\u00e9gia Concursos traz not\u00edcias sobre concursos e artigos de professores oferecendo cursos para concursos (pdf + videaulas) no site.","publisher":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estrategiaconcursos.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#organization","name":"Estrat\u00e9gia Concursos","url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","contentUrl":"https:\/\/dhg1h5j42swfq.cloudfront.net\/2025\/06\/03203428\/logo_concursos-1.jpg","width":230,"height":60,"caption":"Estrat\u00e9gia Concursos"},"image":{"@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/EstratConcursos"]},{"@type":"Person","@id":"https:\/\/www.estrategiaconcursos.com.br\/blog\/#\/schema\/person\/f6cf94f3aa8ed75620a4506ad577b88a","name":"Paulo Sousa (Coord.)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/29f9e2d4ed868d929b68f3762e3577b9db519beed74b347b76e194f9a3293cf1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29f9e2d4ed868d929b68f3762e3577b9db519beed74b347b76e194f9a3293cf1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29f9e2d4ed868d929b68f3762e3577b9db519beed74b347b76e194f9a3293cf1?s=96&d=mm&r=g","caption":"Paulo Sousa (Coord.)"},"url":"https:\/\/www.estrategiaconcursos.com.br\/blog\/author\/prof-phmsestrategiaconcursos-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1156905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/users\/1094"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1156905"}],"version-history":[{"count":2,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1156905\/revisions"}],"predecessor-version":[{"id":1217763,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/posts\/1156905\/revisions\/1217763"}],"wp:attachment":[{"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1156905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1156905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1156905"},{"taxonomy":"tax_estado","embeddable":true,"href":"https:\/\/www.estrategiaconcursos.com.br\/blog\/wp-json\/wp\/v2\/tax_estado?post=1156905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}